{"id":1451670,"date":"2024-08-07T22:03:58","date_gmt":"2024-08-08T05:03:58","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/08\/07\/china-necesidad-alto-el-fuego-gaza-trax\/"},"modified":"2024-08-07T22:03:58","modified_gmt":"2024-08-08T05:03:58","slug":"china-necesidad-alto-el-fuego-gaza-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/07\/china-necesidad-alto-el-fuego-gaza-trax\/","title":{"rendered":"China reitera la necesidad de un alto el fuego en Gaza en llamadas con Egipto y Jordania"},"content":{"rendered":"<p>(CNN) &#8212; El ministro chino de Asuntos Exteriores, Wang Yi, reiter\u00f3 la necesidad de un alto el fuego en Gaza durante sus conversaciones telef\u00f3nicas con sus hom\u00f3logos egipcio y jordano, seg\u00fan un comunicado de prensa emitido este mi\u00e9rcoles por el Ministerio de Asuntos Exteriores (MAE).<\/p>\n<p>Este martes, Wang habl\u00f3 con el ministro jordano de Asuntos Exteriores y Expatriados, Ayman Safadi, sobre diversos asuntos relacionados con Medio Oriente.<\/p>\n<p>&#171;La clave para evitar el deterioro y la escalada de la situaci\u00f3n es lograr un alto el fuego completo y permanente en Gaza lo antes posible&#187;, dec\u00eda un comunicado emitido por el MAE, en el que se a\u00f1ad\u00eda que la comunidad internacional &#171;deber\u00eda hacer o\u00edr su voz de forma m\u00e1s consistente y formar una fuerza conjunta en este sentido&#187;.<\/p>\n<p>El hambre y los desplazamientos de los gazat\u00edes contin\u00faan con el nuevo liderazgo de Hamas<\/p>\n<p>El ministro de Asuntos Exteriores chino, Wang Yi, habla durante la Conferencia de Seguridad de M\u00fanich 2024 el 17 de febrero. (Cr\u00e9dito: Johannes Simon\/Getty Images)<\/p>\n<p>En otra conversaci\u00f3n telef\u00f3nica mantenida este martes con su hom\u00f3logo egipcio, Badr Abdelatty, Wang afirm\u00f3 que &#171;la continuaci\u00f3n del conflicto ha provocado un grave desastre humanitario&#187;. Aunque el Consejo de Seguridad de la ONU ha adoptado una resoluci\u00f3n de alto el fuego, la guerra no ha sido sofocada&#187;, rezaba un comunicado del MAE.<\/p>\n<p>Ambas conversaciones tambi\u00e9n incluyeron discusiones sobre el reciente asesinato del l\u00edder pol\u00edtico de Hamas Ismail Haniyeh en Teher\u00e1n, y Wang dijo que el incidente hab\u00eda &#171;empujado la situaci\u00f3n regional a una m\u00e1s peligrosa&#187;, seg\u00fan el MAE.<\/p>\n<p>&#171;Este asesinato viola los principios b\u00e1sicos de la Carta de la ONU, atenta contra la soberan\u00eda y la dignidad de Ir\u00e1n, socava gravemente los esfuerzos de todas las partes por promover la paz y aleja a\u00fan m\u00e1s el alto el fuego en Gaza. Nos oponemos firmemente a ello y lo condenamos en\u00e9rgicamente&#187;, rezaba el comunicado del MAE.<\/p>\n<p>Wang destac\u00f3 que &#171;la venganza conduce a un c\u00edrculo vicioso, y la violencia s\u00f3lo intensificar\u00e1 el conflicto&#187;.<\/p>\n<p>Durante la llamada con Safadi se intercambiaron sentimientos similares.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El ministro chino de Asuntos Exteriores, Wang Yi, reiter\u00f3 la necesidad de un alto el fuego en Gaza durante sus conversaciones telef\u00f3nicas con sus hom\u00f3logos egipcio y jordano, seg\u00fan un comunicado de prensa emitido este mi\u00e9rcoles por el Ministerio de Asuntos Exteriores (MAE). Este martes, Wang habl\u00f3 con el ministro jordano de Asuntos [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1451670","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>China reitera la necesidad de un alto el fuego en Gaza en llamadas con Egipto y Jordania - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/08\/07\/china-necesidad-alto-el-fuego-gaza-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"China reitera la necesidad de un alto el fuego en Gaza en llamadas con Egipto y Jordania - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El ministro chino de Asuntos Exteriores, Wang Yi, reiter\u00f3 la necesidad de un alto el fuego en Gaza durante sus conversaciones telef\u00f3nicas con sus hom\u00f3logos egipcio y jordano, seg\u00fan un comunicado de prensa emitido este mi\u00e9rcoles por el Ministerio de Asuntos Exteriores (MAE). Este martes, Wang habl\u00f3 con el ministro jordano de Asuntos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/08\/07\/china-necesidad-alto-el-fuego-gaza-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-08T05:03:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/07\/china-necesidad-alto-el-fuego-gaza-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/07\/china-necesidad-alto-el-fuego-gaza-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"China reitera la necesidad de un alto el fuego en Gaza en llamadas con Egipto y Jordania\",\"datePublished\":\"2024-08-08T05:03:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/07\/china-necesidad-alto-el-fuego-gaza-trax\/\"},\"wordCount\":406,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/07\/china-necesidad-alto-el-fuego-gaza-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/07\/china-necesidad-alto-el-fuego-gaza-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/08\/07\/china-necesidad-alto-el-fuego-gaza-trax\/\",\"name\":\"China reitera la necesidad de un alto el fuego en Gaza en llamadas con Egipto y Jordania - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-08-08T05:03:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/07\/china-necesidad-alto-el-fuego-gaza-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/07\/china-necesidad-alto-el-fuego-gaza-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/07\/china-necesidad-alto-el-fuego-gaza-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"China reitera la necesidad de un alto el fuego en Gaza en llamadas con Egipto y Jordania\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"China reitera la necesidad de un alto el fuego en Gaza en llamadas con Egipto y Jordania - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/08\/07\/china-necesidad-alto-el-fuego-gaza-trax\/","og_locale":"es_ES","og_type":"article","og_title":"China reitera la necesidad de un alto el fuego en Gaza en llamadas con Egipto y Jordania - Noticias","og_description":"(CNN) &#8212; El ministro chino de Asuntos Exteriores, Wang Yi, reiter\u00f3 la necesidad de un alto el fuego en Gaza durante sus conversaciones telef\u00f3nicas con sus hom\u00f3logos egipcio y jordano, seg\u00fan un comunicado de prensa emitido este mi\u00e9rcoles por el Ministerio de Asuntos Exteriores (MAE). Este martes, Wang habl\u00f3 con el ministro jordano de Asuntos [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/08\/07\/china-necesidad-alto-el-fuego-gaza-trax\/","og_site_name":"Noticias","article_published_time":"2024-08-08T05:03:58+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/08\/07\/china-necesidad-alto-el-fuego-gaza-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/08\/07\/china-necesidad-alto-el-fuego-gaza-trax\/"},"author":{"name":"","@id":""},"headline":"China reitera la necesidad de un alto el fuego en Gaza en llamadas con Egipto y Jordania","datePublished":"2024-08-08T05:03:58+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/08\/07\/china-necesidad-alto-el-fuego-gaza-trax\/"},"wordCount":406,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/08\/07\/china-necesidad-alto-el-fuego-gaza-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/08\/07\/china-necesidad-alto-el-fuego-gaza-trax\/","url":"https:\/\/noticiasya.com\/2024\/08\/07\/china-necesidad-alto-el-fuego-gaza-trax\/","name":"China reitera la necesidad de un alto el fuego en Gaza en llamadas con Egipto y Jordania - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-08-08T05:03:58+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/08\/07\/china-necesidad-alto-el-fuego-gaza-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/08\/07\/china-necesidad-alto-el-fuego-gaza-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/08\/07\/china-necesidad-alto-el-fuego-gaza-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"China reitera la necesidad de un alto el fuego en Gaza en llamadas con Egipto y Jordania"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/07\/china-necesidad-alto-el-fuego-gaza-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"China reitera la necesidad de un alto el fuego en Gaza en llamadas con Egipto y Jordania","url":"http:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/07\/china-necesidad-alto-el-fuego-gaza-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/07\/china-necesidad-alto-el-fuego-gaza-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-08-08T05:03:58Z","datePublished":"2024-08-08T05:03:58Z","dateModified":"2024-08-08T05:03:58Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"China reitera la necesidad de un alto el fuego en Gaza en llamadas con Egipto y Jordania\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2024\\\/08\\\/07\\\/china-necesidad-alto-el-fuego-gaza-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2024\\\/08\\\/07\\\/china-necesidad-alto-el-fuego-gaza-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-08-08T05:03:58Z\",\"datePublished\":\"2024-08-08T05:03:58Z\",\"dateModified\":\"2024-08-08T05:03:58Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1461664,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/04\/26\/dirigentes-hamas-el-cairo-negociar-alto-el-fuego-trax\/","url_meta":{"origin":1451670,"position":0},"title":"Altos dirigentes de Hamas llegan a El Cairo para negociar un alto el fuego. Trump afirma: &#171;Tenemos que ser buenos con Gaza&#187;","author":"","date":"abril 26, 2025","format":false,"excerpt":"Una delegaci\u00f3n de alto rango de Hamas lleg\u00f3 a El Cairo temprano este s\u00e1bado para conversaciones con funcionarios egipcios con el objetivo de negociar un acuerdo de alto el fuego, seg\u00fan un comunicado de Hamas.La delegaci\u00f3n, encabezada por el presidente del Consejo de Liderazgo de Hamas, Muhammad Darwish, incluye a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451957,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/18\/ataque-israel-palestinos-muertos-familia-centro-gaza-trax\/","url_meta":{"origin":1451670,"position":1},"title":"Mueren siete miembros de una misma familia tras ataque de Israel en el centro de Gaza","author":"","date":"agosto 18, 2024","format":false,"excerpt":"(CNN) -- Siete miembros de una misma familia murieron el domingo en un ataque a\u00e9reo israel\u00ed en el centro de Gaza, seg\u00fan informaron fuentes m\u00e9dicas, mientras el secretario de Estado Antony Blinken aterrizaba en Israel para impulsar un cese del fuego y un acuerdo sobre los rehenes.Seis ni\u00f1os y su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472747,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/01\/analisis-china-mediador-paz-estados-unidos-iran-trax\/","url_meta":{"origin":1451670,"position":2},"title":"\u00bfSe est\u00e1 posicionando China para convertirse en un mediador de paz entre Estados Unidos e Ir\u00e1n?","author":"","date":"abril 1, 2026","format":false,"excerpt":"Mientras la guerra en el Golfo se prolonga por segundo mes, lastrando la econom\u00eda mundial sin que se vislumbre una salida, surgen cada vez m\u00e1s preguntas sobre el papel que est\u00e1 dispuesta a desempe\u00f1ar China, una potencia mundial y socio diplom\u00e1tico de Ir\u00e1n.El posible papel de China estuvo en el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457246,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/01\/05\/soldados-israelies-riesgo-detencion-extranjero-gaza-trax\/","url_meta":{"origin":1451670,"position":3},"title":"Soldados israel\u00edes se enfrentan a un creciente riesgo de detenci\u00f3n en el extranjero tras su servicio en Gaza","author":"","date":"enero 5, 2025","format":false,"excerpt":"Un exsoldado israel\u00ed que se encontraba de vacaciones en Brasil huy\u00f3 repentinamente del pa\u00eds despu\u00e9s de que se iniciara all\u00ed un proceso contra \u00e9l por su presunta responsabilidad en cr\u00edmenes de guerra durante su servicio en Gaza.El caso es el m\u00e1s reciente de una serie de demandas interpuestas por la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469680,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/12\/31\/israel-ayuda-gaza-crisis-humanitaria-catastrofica-trax\/","url_meta":{"origin":1451670,"position":4},"title":"Israel suspender\u00e1 operaciones de grupos de ayuda en Gaza mientras pa\u00edses advierten de crisis humanitaria &#171;catastr\u00f3fica&#187;","author":"","date":"diciembre 31, 2025","format":false,"excerpt":"Varias organizaciones humanitarias internacionales, incluida M\u00e9dicos Sin Fronteras (MSF), se enfrentan a la posibilidad de que se les proh\u00edba trabajar en Gaza a partir del jueves por no cumplir con las nuevas restricciones de Israel para los grupos de ayuda que operan en el devastado enclave.Israel dijo este martes que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464730,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/07\/21\/paises-critican-israel-ayuda-gaza-masacre-palestinos-trax\/","url_meta":{"origin":1451670,"position":5},"title":"M\u00e1s de 1.000 palestinos han muerto intentando recibir ayuda en Gaza desde finales de mayo, seg\u00fan el Ministerio de Salud","author":"","date":"julio 21, 2025","format":false,"excerpt":"Los ministros de Asuntos Exteriores de al menos 25 pa\u00edses occidentales han criticado duramente a Israel por el suministro de ayuda a Gaza, al tiempo que el Ministerio de Salud del territorio indic\u00f3 que m\u00e1s de 1.000 personas han muerto buscando ayuda humanitaria all\u00ed desde finales de mayo.El Ministerio de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1451670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1451670"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1451670\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1451670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1451670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1451670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}