{"id":1451703,"date":"2024-08-09T16:03:49","date_gmt":"2024-08-09T23:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/08\/09\/imane-khelif-boxeo-argelina-medalla-oro-juegos-olimpicos-2024-trax\/"},"modified":"2024-08-09T16:03:49","modified_gmt":"2024-08-09T23:03:49","slug":"imane-khelif-boxeo-argelina-medalla-oro-juegos-olimpicos-2024-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/09\/imane-khelif-boxeo-argelina-medalla-oro-juegos-olimpicos-2024-trax\/","title":{"rendered":"La boxeadora argelina Imane Khelif gana la medalla de oro  tras la tormenta de cr\u00edticas en redes sociales"},"content":{"rendered":"<p>(CNN) &#8212; La boxeadora argelina Imane Khelif derrot\u00f3 este viernes a su rival china Yang Liu en el combate por la medalla de oro de los 66 kilos de los Juegos Ol\u00edmpicos de Par\u00eds 2024.<\/p>\n<p>Khelif recibi\u00f3 una calurosa bienvenida del p\u00fablico cuando subi\u00f3 al cuadril\u00e1tero del estadio Roland Garros para disputar su cuarto combate de los juegos. Las banderas argelinas ondeaban por todo el recinto.<\/p>\n<p>La boxeadora italiana Angela Carini pide perd\u00f3n a la argelina Imane Khelif por c\u00f3mo la trat\u00f3<\/p>\n<p>En el primer asalto, ambas luchadoras empezaron t\u00edmidamente, pero Khelif se impuso a su rival zurda por unanimidad.<\/p>\n<p>En el segundo asalto, la argelina propin\u00f3 un fuerte pu\u00f1etazo a Yang, que rebot\u00f3 contra las cuerdas en los primeros segundos. Con el p\u00fablico a favor de Khelif coreando a rabiar, la argelina castig\u00f3 a su rival con un aluvi\u00f3n de pu\u00f1etazos en su camino hacia otro asalto victorioso en todas las tarjetas de puntuaci\u00f3n de los jueces.<\/p>\n<p>Con una enorme ventaja en el marcador, Khelif sigui\u00f3 presionando a Yang en el tercer y \u00faltimo asalto. La china sigui\u00f3 presionando, pero no pudo superar la defensa de Khelif.<\/p>\n<p>Tras sonar la campana final, las p\u00fagiles se abrazaron en se\u00f1al de respeto y deportividad.<\/p>\n<p>Un intercambio de golpes entre boxeadora argelina Imane Khelif y la china Yang Liu en la lucha por la medalla de oro en Par\u00eds 2024 de la categor\u00eda de peso w\u00e9lter femenino de 66 kg. Richard Pelham\/Getty Images<\/p>\n<p>El p\u00fablico aplaudi\u00f3 fervientemente cuando se anunci\u00f3 que Khelif hab\u00eda ganado la medalla de oro a los puntos por decisi\u00f3n un\u00e1nime.<\/p>\n<p>Khelif hizo su caracter\u00edstico baile de la victoria en el cuadril\u00e1tero y pos\u00f3 para los fot\u00f3grafos antes de que uno de sus entrenadores se la llevara a hombros.<\/p>\n<p>Imane Khelif, de Argelia, golpe\u00f3 a Angela Carini, de Italia, durante el combate de la ronda preliminar de los 66 kilos femeninos de los Juegos Ol\u00edmpicos de Par\u00eds, el 2 de agosto.<\/p>\n<p>La boxeadora italiana Angela Carini pide perd\u00f3n a la argelina Imane Khelif por c\u00f3mo la trat\u00f3<\/p>\n<p>Khelif hab\u00eda sido objeto de atenci\u00f3n de todo el mundo despu\u00e9s de derrotar a la boxeadora italiana Angela Carini en solo 46 segundos en un combate preliminar.<\/p>\n<p>El combate desencaden\u00f3 una avalancha de insultos en Internet, con comentaristas transf\u00f3bicos que llamaron err\u00f3neamente &#171;hombre&#187; a Khelif porque no hab\u00eda superado una supuesta &#171;prueba de g\u00e9nero&#187; realizada por una federaci\u00f3n de boxeo ahora desacreditada a la que se hab\u00eda retirado la capacidad de organizar los eventos ol\u00edmpicos. El Comit\u00e9 Ol\u00edmpico Internacional (COI) se hizo cargo de este deporte para los Juegos de 2024 porque decidi\u00f3 que ninguna federaci\u00f3n internacional estaba cualificada para dirigirlo y recalc\u00f3 en repetidas ocasiones que Khelif cumpl\u00eda los criterios para competir.<\/p>\n<p>El presidente del COI, Thomas Bach, fue preguntado el viernes si la organizaci\u00f3n estaba dando prioridad a la inclusi\u00f3n sobre la seguridad al permitir que Khelif y Lin compitieran.<\/p>\n<p>&#171;No es tan f\u00e1cil como algunos en esta guerra cultural quieren pintar&#187;, respondi\u00f3 Bach. &#171;Estas dos son mujeres, y tienen derecho a participar en la competici\u00f3n femenina. Y esto no tiene nada que ver con la inclusi\u00f3n de ninguna manera&#187;.<\/p>\n<p>En declaraciones en \u00e1rabe a SNTV, un socio de videos deportivos de Associated Press, Khelif inst\u00f3 a la gente a \u201cdefender los principios ol\u00edmpicos, seg\u00fan la carta ol\u00edmpica, abstenerse de intimidar a todos los atletas porque esto tiene efectos, efectos masivos\u201d.<\/p>\n<p>\u201cPuede destruir a la gente, puede matar los pensamientos, el esp\u00edritu y la mente de la gente\u201d, dijo, a\u00f1adiendo que no fue f\u00e1cil pasar por lo que sigui\u00f3 a su combate con Carini.<\/p>\n<p>La boxeadora argelina Imane Khelif pide que se ponga fin al &#171;bullying de todos los atletas&#187;<\/p>\n<p>El portavoz del COI, Mark Adams, defendi\u00f3 la participaci\u00f3n de Khelif en los Juegos Ol\u00edmpicos de Par\u00eds 2024 en una rueda de prensa posterior al combate con Carini, afirmando que Khelif &#171;naci\u00f3 mujer, fue registrada como mujer, vive su vida como mujer, boxea como mujer, tiene un pasaporte de mujer&#187;.<\/p>\n<p>El COI confirm\u00f3 entonces que el combate &#171;no era de un hombre contra una mujer&#187; y que &#171;cient\u00edficamente sobre eso, hay consenso&#187;.<\/p>\n<p>Khelif no es la \u00fanica boxeadora que recibe atenci\u00f3n a\u00f1adida por su presencia en Par\u00eds. La boxeadora Lin Yu-ting, de Taiw\u00e1n, tambi\u00e9n est\u00e1 en el punto de mira tras a\u00f1os de competici\u00f3n amateur.<\/p>\n<p>Lin pelear\u00e1 el s\u00e1bado en el combate femenino por la medalla de oro de 57 kg.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; La boxeadora argelina Imane Khelif derrot\u00f3 este viernes a su rival china Yang Liu en el combate por la medalla de oro de los 66 kilos de los Juegos Ol\u00edmpicos de Par\u00eds 2024. Khelif recibi\u00f3 una calurosa bienvenida del p\u00fablico cuando subi\u00f3 al cuadril\u00e1tero del estadio Roland Garros para disputar su cuarto combate [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1451703","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La boxeadora argelina Imane Khelif gana la medalla de oro tras la tormenta de cr\u00edticas en redes sociales - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/08\/09\/imane-khelif-boxeo-argelina-medalla-oro-juegos-olimpicos-2024-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La boxeadora argelina Imane Khelif gana la medalla de oro tras la tormenta de cr\u00edticas en redes sociales - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; La boxeadora argelina Imane Khelif derrot\u00f3 este viernes a su rival china Yang Liu en el combate por la medalla de oro de los 66 kilos de los Juegos Ol\u00edmpicos de Par\u00eds 2024. Khelif recibi\u00f3 una calurosa bienvenida del p\u00fablico cuando subi\u00f3 al cuadril\u00e1tero del estadio Roland Garros para disputar su cuarto combate [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/08\/09\/imane-khelif-boxeo-argelina-medalla-oro-juegos-olimpicos-2024-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-09T23:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/09\/imane-khelif-boxeo-argelina-medalla-oro-juegos-olimpicos-2024-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/09\/imane-khelif-boxeo-argelina-medalla-oro-juegos-olimpicos-2024-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La boxeadora argelina Imane Khelif gana la medalla de oro tras la tormenta de cr\u00edticas en redes sociales\",\"datePublished\":\"2024-08-09T23:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/09\/imane-khelif-boxeo-argelina-medalla-oro-juegos-olimpicos-2024-trax\/\"},\"wordCount\":821,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/09\/imane-khelif-boxeo-argelina-medalla-oro-juegos-olimpicos-2024-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/09\/imane-khelif-boxeo-argelina-medalla-oro-juegos-olimpicos-2024-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/08\/09\/imane-khelif-boxeo-argelina-medalla-oro-juegos-olimpicos-2024-trax\/\",\"name\":\"La boxeadora argelina Imane Khelif gana la medalla de oro tras la tormenta de cr\u00edticas en redes sociales - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-08-09T23:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/09\/imane-khelif-boxeo-argelina-medalla-oro-juegos-olimpicos-2024-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/09\/imane-khelif-boxeo-argelina-medalla-oro-juegos-olimpicos-2024-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/09\/imane-khelif-boxeo-argelina-medalla-oro-juegos-olimpicos-2024-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La boxeadora argelina Imane Khelif gana la medalla de oro tras la tormenta de cr\u00edticas en redes sociales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La boxeadora argelina Imane Khelif gana la medalla de oro tras la tormenta de cr\u00edticas en redes sociales - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/08\/09\/imane-khelif-boxeo-argelina-medalla-oro-juegos-olimpicos-2024-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La boxeadora argelina Imane Khelif gana la medalla de oro tras la tormenta de cr\u00edticas en redes sociales - Noticias","og_description":"(CNN) &#8212; La boxeadora argelina Imane Khelif derrot\u00f3 este viernes a su rival china Yang Liu en el combate por la medalla de oro de los 66 kilos de los Juegos Ol\u00edmpicos de Par\u00eds 2024. Khelif recibi\u00f3 una calurosa bienvenida del p\u00fablico cuando subi\u00f3 al cuadril\u00e1tero del estadio Roland Garros para disputar su cuarto combate [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/08\/09\/imane-khelif-boxeo-argelina-medalla-oro-juegos-olimpicos-2024-trax\/","og_site_name":"Noticias","article_published_time":"2024-08-09T23:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/08\/09\/imane-khelif-boxeo-argelina-medalla-oro-juegos-olimpicos-2024-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/08\/09\/imane-khelif-boxeo-argelina-medalla-oro-juegos-olimpicos-2024-trax\/"},"author":{"name":"","@id":""},"headline":"La boxeadora argelina Imane Khelif gana la medalla de oro tras la tormenta de cr\u00edticas en redes sociales","datePublished":"2024-08-09T23:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/08\/09\/imane-khelif-boxeo-argelina-medalla-oro-juegos-olimpicos-2024-trax\/"},"wordCount":821,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/08\/09\/imane-khelif-boxeo-argelina-medalla-oro-juegos-olimpicos-2024-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/08\/09\/imane-khelif-boxeo-argelina-medalla-oro-juegos-olimpicos-2024-trax\/","url":"https:\/\/noticiasya.com\/2024\/08\/09\/imane-khelif-boxeo-argelina-medalla-oro-juegos-olimpicos-2024-trax\/","name":"La boxeadora argelina Imane Khelif gana la medalla de oro tras la tormenta de cr\u00edticas en redes sociales - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-08-09T23:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/08\/09\/imane-khelif-boxeo-argelina-medalla-oro-juegos-olimpicos-2024-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/08\/09\/imane-khelif-boxeo-argelina-medalla-oro-juegos-olimpicos-2024-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/08\/09\/imane-khelif-boxeo-argelina-medalla-oro-juegos-olimpicos-2024-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La boxeadora argelina Imane Khelif gana la medalla de oro tras la tormenta de cr\u00edticas en redes sociales"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/09\/imane-khelif-boxeo-argelina-medalla-oro-juegos-olimpicos-2024-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La boxeadora argelina Imane Khelif gana la medalla de oro  tras la tormenta de cr\u00edticas en redes sociales","url":"http:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/09\/imane-khelif-boxeo-argelina-medalla-oro-juegos-olimpicos-2024-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/09\/imane-khelif-boxeo-argelina-medalla-oro-juegos-olimpicos-2024-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-08-09T23:03:49Z","datePublished":"2024-08-09T23:03:49Z","dateModified":"2024-08-09T23:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La boxeadora argelina Imane Khelif gana la medalla de oro  tras la tormenta de cr\\u00edticas en redes sociales\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2024\\\/08\\\/09\\\/imane-khelif-boxeo-argelina-medalla-oro-juegos-olimpicos-2024-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2024\\\/08\\\/09\\\/imane-khelif-boxeo-argelina-medalla-oro-juegos-olimpicos-2024-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-08-09T23:03:49Z\",\"datePublished\":\"2024-08-09T23:03:49Z\",\"dateModified\":\"2024-08-09T23:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1451582,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/03\/boxeadora-imane-khelif-gana-cuartos-final-trax\/","url_meta":{"origin":1451703,"position":0},"title":"La boxeadora argelina Imane Khelif gana contra la h\u00fangara Anna Luca Hamori y se asegura una medalla ol\u00edmpica","author":"","date":"agosto 3, 2024","format":false,"excerpt":"(CNN) -- La boxeadora argelina Imane Khelif derrot\u00f3 este s\u00e1bado a su oponente h\u00fangara Anna Luca Hamori en los cuartos de final de la categor\u00eda de 66 kg en los Juegos Ol\u00edmpicos de Par\u00eds,\u00a0 avanzando a las semifinales y asegur\u00e1ndose una medalla.Khelif recibi\u00f3 una c\u00e1lida bienvenida de la multitud parisina\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451610,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/05\/imane-khelif-boxeadora-argelina-mensaje-bullying-trax\/","url_meta":{"origin":1451703,"position":1},"title":"La boxeadora argelina Imane Khelif pide que se ponga fin al &#171;bullying de todos los atletas&#187;","author":"","date":"agosto 5, 2024","format":false,"excerpt":"(CNN) -- La boxeadora argelina Imane Khelif ha pedido que se ponga fin al \"bullying de todos los atletas\", diciendo que \"puede destruir a la gente\".Sus comentarios se producen tras el abuso en l\u00ednea que Khelif recibi\u00f3 despu\u00e9s de su combate de boxeo contra la italiana Angela Carini el jueves,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451945,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/17\/imane-khelif-recibe-desfile-celebracion-regreso-a-casa-tras-juegos-olimpicos-trax\/","url_meta":{"origin":1451703,"position":2},"title":"La boxeadora argelina Imane Khelif recibe un desfile de celebraci\u00f3n a su regreso a casa tras los Juegos Ol\u00edmpicos de Par\u00eds","author":"","date":"agosto 17, 2024","format":false,"excerpt":"(CNN) -- Multitudes entusiastas llenaron las calles de Tiaret, Argelia, este viernes por la noche para dar la bienvenida a la boxeadora Imane Khelif en su regreso a casa tras su paso por los Juegos Ol\u00edmpicos de Par\u00eds , donde gan\u00f3 una medalla de oro.Ella public\u00f3 un video del desfile\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470878,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/04\/imane-khelif-prueba-genetica-boxeo-trax\/","url_meta":{"origin":1451703,"position":3},"title":"La boxeadora ol\u00edmpica Imane Khelif quiere pelear y est\u00e1 dispuesta a pasar una prueba para lograrlo","author":"","date":"febrero 4, 2026","format":false,"excerpt":"Imane Khelif sabe c\u00f3mo aguantar los golpes. Para lo que nunca se entren\u00f3 fue para convertirse en blanco pol\u00edtico.Desde su oro ol\u00edmpico en los Juegos Ol\u00edmpicos de Par\u00eds 2024, la boxeadora argelina ha sido objeto de una campa\u00f1a sostenida de abusos y escrutinio invasivo, impulsada por algunas de las figuras\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458306,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/02\/05\/cnn-verifica-trump-campeonas-olimpicas-boxeo-transicion-trax\/","url_meta":{"origin":1451703,"position":4},"title":"CNN verifica: Trump repite una mentira al decir que las campeonas ol\u00edmpicas de boxeo eran hombres que &#171;transicionaron&#187;","author":"","date":"febrero 5, 2025","format":false,"excerpt":"Antes de firmar un decreto este mi\u00e9rcoles para prohibir que las mujeres transg\u00e9nero compitan en deportes femeninos en escuelas y otros \u00e1mbitos, el presidente de Estados Unidos, Donald Trump, repiti\u00f3 una afirmaci\u00f3n falsa que hizo el a\u00f1o pasado. Se\u00f1al\u00f3 que dos atletas ol\u00edmpicas que ganaron el oro en eventos de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465191,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/08\/06\/trump-atletas-transgenero-femeninos-trax\/","url_meta":{"origin":1451703,"position":5},"title":"Trump quiere pruebas rigurosas para alejar a atletas transg\u00e9nero de los deportes femeninos en los Juegos Ol\u00edmpicos de 2028","author":"","date":"agosto 6, 2025","format":false,"excerpt":"El presidente de EE.UU., Donald Trump, firm\u00f3 el martes un decreto para establecer un grupo de trabajo en la Casa Blanca que coordine la preparaci\u00f3n del Gobierno federal para los Juegos Ol\u00edmpicos de Verano de 2028 en Los \u00c1ngeles, y aprovech\u00f3 la ocasi\u00f3n para criticar duramente la participaci\u00f3n de atletas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1451703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1451703"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1451703\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1451703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1451703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1451703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}