{"id":1451712,"date":"2024-08-10T10:03:59","date_gmt":"2024-08-10T17:03:59","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/08\/10\/tim-walz-china-lazos-harris-trax\/"},"modified":"2024-08-10T10:03:59","modified_gmt":"2024-08-10T17:03:59","slug":"tim-walz-china-lazos-harris-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/10\/tim-walz-china-lazos-harris-trax\/","title":{"rendered":"El elegido por Kamala Harris para vicepresidente tiene una larga historia con China. Pero puede que a Beijing no le haga mucha gracia"},"content":{"rendered":"<p>(CNN) &#8212; El compa\u00f1ero de f\u00f3rmula de la presunta candidata presidencial dem\u00f3crata Kamala Harris tiene una larga relaci\u00f3n con China. Pero a los ojos de Beijing, eso puede no ser necesariamente una buena noticia.<\/p>\n<p>Tim Walz se traslad\u00f3 a China reci\u00e9n salido de la universidad en 1989 para ense\u00f1ar en un instituto durante un a\u00f1o, y despu\u00e9s regres\u00f3 con frecuencia al pa\u00eds durante una d\u00e9cada en la que llev\u00f3 a estudiantes estadounidenses en intercambios culturales de verano.<\/p>\n<p>El gobernador de Minnesota, de 60 a\u00f1os, habl\u00f3 con cari\u00f1o de su estancia en China y de la gente que conoci\u00f3 all\u00ed, su familiaridad con el pa\u00eds y su empat\u00eda con su gente aportan una perspectiva personal y matizada sobre el mayor rival estrat\u00e9gico de Estados Unidos que es poco frecuente entre sus colegas pol\u00edticos.<\/p>\n<p>Algunos opositores republicanos aprovecharon esa experiencia para acusar a Walz de ser &#171;prochino&#187;, pero el candidato dem\u00f3crata a la vicepresidencia tiene un largo historial de cr\u00edticas al autoritario liderazgo chino.<\/p>\n<p>\u00bfQui\u00e9n es Tim Walz, el aspirante dem\u00f3crata a vicepresidente de Kamala Harris?<\/p>\n<p>Walz se traslad\u00f3 a China en un momento tumultuoso y de gran carga pol\u00edtica, poco despu\u00e9s de la masacre de la plaza de Tiananmen, cuando el Partido Comunista en el poder envi\u00f3 tanques para sofocar violentamente las protestas pac\u00edficas de los estudiantes por la democracia en Beijing. Al regresar a Nebraska en 1990, declar\u00f3 a un peri\u00f3dico local que sent\u00eda que el pueblo chino hab\u00eda sido maltratado por su gobierno durante a\u00f1os.<\/p>\n<p>&#171;Si tuvieran el liderazgo adecuado, no habr\u00eda l\u00edmites a lo que podr\u00edan conseguir. Son gente tan amable, generosa y capaz&#187;, declar\u00f3 entonces al Star-Herald.<\/p>\n<p>Durante su mandato en el Congreso, de 2007 a 2019, Walz apoy\u00f3 a los activistas chinos encarcelados. Se reuni\u00f3 con el Dalai Lama, el l\u00edder espiritual tibetano en el exilio aborrecido por Beijing, y con Joshua Wong, el joven activista por la democracia de Hong Kong ahora encarcelado por su activismo contra el creciente control de Beijing.<\/p>\n<p>&#171;Cuanto m\u00e1s entiende China, m\u00e1s compasi\u00f3n siente por el pueblo chino y m\u00e1s cr\u00edtico se muestra con los dirigentes que lo gobiernan&#187;, afirma Shen Dingli, analista de pol\u00edtica exterior en Shanghai.<\/p>\n<p>&#171;Comprende en cierta medida la cultura china y la respeta en el fondo, pero desde luego no acepta el (sistema) pol\u00edtico de China&#187;, a\u00f1adi\u00f3 Shen. &#171;Beijing est\u00e1 probablemente m\u00e1s temeroso e inc\u00f3modo con un extranjero que entiende China&#187;.<\/p>\n<p>Una joven queda atrapada entre civiles y soldados chinos que intentaban sacarla de una reuni\u00f3n cerca del Gran Sal\u00f3n del Pueblo en Pek\u00edn el 3 de junio de 1989. (Cr\u00e9dito Jeff Widener\/Associated Press)<\/p>\n<p>Se trataba m\u00e1s de la gente<\/p>\n<p>Walz form\u00f3 parte de los primeros grupos de j\u00f3venes estadounidenses que ense\u00f1aron en institutos de China en el marco de un programa de voluntariado de la Universidad de Harvard, justo una d\u00e9cada despu\u00e9s de que ambos pa\u00edses establecieran relaciones diplom\u00e1ticas.<\/p>\n<p>Reci\u00e9n licenciado, pas\u00f3 un a\u00f1o ense\u00f1ando ingl\u00e9s e historia de Estados Unidos en el instituto n\u00ba 1 de Foshan, en la provincia meridional de Guangdong.<\/p>\n<p>All\u00ed se encontr\u00f3 con estudiantes aplicados y acogedores que le aplaud\u00edan cada vez que utilizaba correctamente una palabra china, y con amables desconocidos que se ofrec\u00edan a ayudarle cada vez que se deten\u00eda en la calle con cara de desconcierto, seg\u00fan declar\u00f3 al Star-Herald en 1990.<\/p>\n<p>&#171;Me trataron excepcionalmente bien&#187;, declar\u00f3 al peri\u00f3dico. &#171;No hab\u00eda ning\u00fan sentimiento antiamericano. Para los chinos, lo americano es &#8216;eso&#8217;. Muchos de los estudiantes quieren venir a estudiar a Estados Unidos&#187;.<\/p>\n<p>El candidato a vicepresidente Tim Walz enfrent\u00f3 acusaciones en 2006 de exagerar su servicio militar, lo que \u00e9l calific\u00f3 de calumnia<\/p>\n<p>Eran otros tiempos en China. El empobrecido pa\u00eds sent\u00eda curiosidad por el mundo tras salir de d\u00e9cadas de aislamiento autoimpuesto y tumultuoso gobierno de Mao Zedong. El l\u00edder supremo Deng Xiaoping desencaden\u00f3 las reformas de mercado y, junto con la apertura econ\u00f3mica, en la d\u00e9cada de 1980 cobraron impulso las llamadas a la liberalizaci\u00f3n pol\u00edtica.<\/p>\n<p>En la primavera de 1989, estos llamamientos desembocaron en un movimiento estudiantil que fue brutalmente sofocado por el ej\u00e9rcito chino semanas antes del viaje de Walz.<\/p>\n<p>&#171;Recuerdo que el 4 de junio me despert\u00e9 y vi las noticias de que hab\u00eda ocurrido lo impensable&#187;, dijo Walz a Voice of America en una entrevista en 2014.<\/p>\n<p>&#171;Muchos de mis colegas decidieron volver a casa y no seguir [en China]. Pens\u00e9 que era m\u00e1s importante que nunca ir, para asegurarme de que se contaba la historia y para que el pueblo chino supiera que est\u00e1bamos all\u00ed, que est\u00e1bamos con ellos.&#187;<\/p>\n<p>Desde Guangdong, Walz hizo un viaje de 40 horas en tren hasta la capital china para ver la plaza de Tiananmen, el lugar de las protestas por la democracia.<\/p>\n<p>Se asegur\u00f3 de conmemorar siempre la represi\u00f3n de una forma personal: cas\u00e1ndose el 4 de junio de 1994, quinto aniversario de la masacre.<\/p>\n<p>&#171;Quer\u00eda tener una fecha que recordara siempre&#187;, declar\u00f3 su esposa y compa\u00f1era de instituto, Gwen, a un peri\u00f3dico local de Minnesota antes de su boda.<\/p>\n<p>Los reci\u00e9n casados pasaron su luna de miel llevando a sus alumnos de viaje por China durante dos semanas para hacer turismo y dar clases de cultura, educaci\u00f3n e historia. Estos viajes se convirtieron en una tradici\u00f3n veraniega para la pareja hasta 2003.<\/p>\n<p>Tim Walz posa para una foto con Dalai Lama en 2016. (Cr\u00e9dito: Tim Walz\/X (Twitter))<\/p>\n<p>&#171;Volver\u00eda sin dudarlo&#187;, afirma Cara Roemhildt, que particip\u00f3 en uno de estos viajes en 1998. &#171;Fue un viaje educativo con uno de nuestros profesores favoritos. Se trataba m\u00e1s de la gente. No se trataba de pol\u00edtica&#187;.<\/p>\n<p>OPINI\u00d3N | \u00bfEs Tim Walz el compa\u00f1ero ideal para Kamala Harris?<\/p>\n<p>Roemhildt dice que ella y sus compa\u00f1eros de clase siguen hablando del viaje d\u00e9cadas despu\u00e9s.<\/p>\n<p>&#171;Nos sentimos muy, muy c\u00f3modos. Viajamos en tren a un mont\u00f3n de sitios diferentes&#187;, dijo a CNN. &#171;Ver una cultura diferente y respetarla al mismo tiempo. Saber que es diferente, pero saber que tambi\u00e9n est\u00e1 bien&#187;.<\/p>\n<p>Un cr\u00edtico matizado<\/p>\n<p>Tras entrar en pol\u00edtica en 2006, Walz sigui\u00f3 dedicando tiempo y atenci\u00f3n a China en el Congreso.<\/p>\n<p>Form\u00f3 parte durante m\u00e1s de una d\u00e9cada de la Comisi\u00f3n Ejecutiva del Congreso sobre China, que supervisa los derechos humanos y el Estado de derecho en el pa\u00eds, un papel que a Beijing no le har\u00eda ninguna gracia.<\/p>\n<p>&#171;El gobierno chino siempre ha considerado a esa comisi\u00f3n como &#8216;antichina'&#187;, dijo Liu Dongshu, profesor adjunto de asuntos p\u00fablicos e internacionales en la City University de Hong Kong.<\/p>\n<p>En el Congreso, Walz copatrocin\u00f3 una serie de resoluciones en las que se ped\u00eda a China que pusiera en libertad a sus activistas de derechos humanos encarcelados, incluido el premio Nobel de la Paz Liu Xiaobo, que finalmente muri\u00f3 bajo custodia a causa de un c\u00e1ncer de h\u00edgado.<\/p>\n<p>En 2015, Walz se uni\u00f3 a una delegaci\u00f3n del Congreso en un viaje a China, que incluy\u00f3 una parada poco habitual en el T\u00edbet, que tambi\u00e9n hab\u00eda visitado d\u00e9cadas antes durante su \u00e9poca de profesor en el instituto chino.<\/p>\n<p>C\u00f3mo Tim Walz, un discreto gobernador del Medio Oeste, lleg\u00f3 a la cima para ser el vicepresidente de Kamala Harris<\/p>\n<p>Al a\u00f1o siguiente, Walz se reuni\u00f3 con el Dalai Lama en Washington para lo que llam\u00f3 un &#171;almuerzo que cambi\u00f3 su vida.&#187; Tambi\u00e9n recibi\u00f3 en su oficina del Congreso a Lobsang Sangay, entonces l\u00edder del gobierno tibetano en el exilio, para que conociera a un grupo de estudiantes de secundaria de Minnesota.<\/p>\n<p>En una reuni\u00f3n del Congreso ese a\u00f1o, pidi\u00f3 a Beijing que &#171;garantizara la preservaci\u00f3n de la cultura tradicional tibetana&#187; y &#171;proporcionara una libertad religiosa menos regulada a los tibetanos&#187;.<\/p>\n<p>Walz tambi\u00e9n ha sido un firme defensor del movimiento prodemocr\u00e1tico de Hong Kong.<\/p>\n<p>En 2017, cuando Wong, el l\u00edder estudiantil de las protestas, fue encarcelado por su activismo pol\u00edtico, Walz public\u00f3 una foto suya y del joven activista codo con codo para mostrar su solidaridad con &#171;todos los que abogan por la democracia en Hong Kong.&#187;<\/p>\n<p>Walz tambi\u00e9n dio su apoyo a la Ley de Derechos Humanos y Democracia de Hong Kong, que sanciona a los funcionarios responsables de violaciones de los derechos humanos en la ciudad, cuando la legislaci\u00f3n parec\u00eda languidecer en el Congreso.<\/p>\n<p>&#171;Llamamos a todas las puertas cuando la #HKHRDA carec\u00eda de impulso. Solo Walz respondi\u00f3 a la suya&#187;, dijo en X Jeffrey Ngo, un activista por la democracia de Hong Kong que ahora reside en Washington.<\/p>\n<p>&#171;Walz es quiz\u00e1s el candidato m\u00e1s s\u00f3lido en lo que se refiere a derechos humanos y China en una candidatura de un partido mayoritario en la memoria reciente&#187;, dijo Ngo.<\/p>\n<p>En el frente diplom\u00e1tico, Walz ha criticado las pr\u00e1cticas comerciales desleales de China y su creciente asertividad en el Mar de China Meridional.<\/p>\n<p>En los c\u00edrculos nacionalistas chinos, que tienen una voz muy destacada en los debates pol\u00edticos en China, no se hacen ilusiones sobre Walz.<\/p>\n<p>Tim Walz posa para una foto con el activista pro-democracia de Hong Kong, Joshua Wang, que ahora est\u00e1 encarcelado. (Cr\u00e9dito: Tim Walz\/X (Twitter))<\/p>\n<p>&#171;En cuestiones ideol\u00f3gicas y de derechos humanos, b\u00e1sicamente ha cruzado todas las l\u00edneas rojas posibles&#187;, escribi\u00f3 en las redes sociales Shen Yi, un acad\u00e9mico de relaciones internacionales conocido por sus opiniones ferozmente nacionalistas.<\/p>\n<p>Harris y Walz encabezan su primer mitin juntos hacia la Convenci\u00f3n Dem\u00f3crata<\/p>\n<p>Pero a diferencia de otros pol\u00edticos m\u00e1s belicistas, Walz no cree en la desvinculaci\u00f3n, sino que tiene una visi\u00f3n m\u00e1s matizada de la rivalidad geoestrat\u00e9gica entre Estados Unidos y China.<\/p>\n<p>&#171;No creo que China tenga que ser necesariamente una relaci\u00f3n de adversarios. Estoy totalmente en desacuerdo&#187;, dijo en una entrevista en 2016.<\/p>\n<p>&#171;Estamos en la misma partitura, dos de las grandes superpotencias del mundo, hay muchas cosas de colaboraci\u00f3n que podemos hacer juntos&#187;.<\/p>\n<p>Stephen Roach, exjefe de Morgan Stanley Asia, dijo que la candidatura Harris-Walz puede proporcionar &#171;un importante contrapeso al veneno actual de la sinofobia estadounidense.&#187;<\/p>\n<p>La empat\u00eda de Walz hacia el pueblo chino y su apreciaci\u00f3n de los aspectos no pol\u00edticos de China lo convierten en un caso m\u00e1s dif\u00edcil para que Pek\u00edn lo \u201cdemonice como un \u2018anti-China\u2019\u201d en comparaci\u00f3n con los pol\u00edticos que son beligerantes en todos los aspectos, dijo Eric Fish, ex periodista con base en Pek\u00edn y autor de \u201cChina\u2019s Millennials: The Want Generation,\u201d en X.<\/p>\n<p>Un pa\u00eds complejo<\/p>\n<p>La amplia experiencia de Walz con China lo convierte en una figura poco com\u00fan en la carrera hacia la Casa Blanca, al menos desde George H. W. Bush, que fue embajador oficioso de Estados Unidos en Beijing a mediados de los a\u00f1os setenta, antes de presentarse como candidato a la vicepresidencia y m\u00e1s tarde a la presidencia.<\/p>\n<p>La estancia de Bush en Beijing influir\u00eda en su pol\u00edtica exterior y ayudar\u00eda a dirigir las relaciones entre Estados Unidos y China durante las tumultuosas consecuencias de la represi\u00f3n de Tiananmen.<\/p>\n<p>Pero las relaciones entre Estados Unidos y China se encuentran en un momento muy distinto al del periodo de luna de miel. Ser duro con China se ha convertido en un raro punto de consenso bipartidista en Estados Unidos, y es poco probable que Beijing cuente con Walz para mejorar los lazos bilaterales.<\/p>\n<p>&#171;La direcci\u00f3n de la pol\u00edtica estadounidense hacia China est\u00e1 muy clara. Como individuo, independientemente de su actitud hacia China, no hay mucho margen de maniobra&#187;, dijo Liu, experto de la City University de Hong Kong.<\/p>\n<p>AN\u00c1LISIS | \u00bfPodr\u00eda una victoria de Trump y Vance reconfigurar la relaci\u00f3n de Estados Unidos con China y Taiw\u00e1n?<\/p>\n<p>&#171;Y los vicepresidentes pueden tener un nivel de voz variado en pol\u00edtica exterior, dependiendo del presidente al que sirvan&#187;, a\u00f1adi\u00f3.<\/p>\n<p>La experiencia de Walz viviendo y ense\u00f1ando en China podr\u00eda servir para romper el hielo diplom\u00e1tico y caldear el ambiente, si eso es lo que desean ambas partes, dijo Liu. Pero incluso entonces, a\u00f1adi\u00f3, los chinos tendr\u00edan que sortear la incomodidad del momento y evitar toda menci\u00f3n a la represi\u00f3n de Tiananmen, que sigue siendo un tab\u00fa pol\u00edtico en China.<\/p>\n<p>En las redes sociales chinas, fuertemente controladas, los primeros v\u00ednculos de Walz con el pa\u00eds generado revuelo y suscitado un inter\u00e9s considerable. El hashtag &#171;Harris&#8217; VP pick once taught in China&#187; acumul\u00f3 15 millones de visitas en el sitio de microblogging Weibo.<\/p>\n<p>El a\u00f1o de la llegada de Walz a China, 1989, no pas\u00f3 desapercibido entre quienes comprenden la sensibilidad de la fecha, a pesar de los esfuerzos del gobierno chino durante d\u00e9cadas por borrar la brutal represi\u00f3n de la memoria p\u00fablica.<\/p>\n<p>Pero, tal vez como reflejo de la era diferente en la que China se encuentra ahora bajo el liderazgo de Xi Jinping, que ha avivado el sentimiento nacionalista y la sospecha contra los extranjeros por motivos de seguridad nacional, muchos cuestionaron el &#171;motivo real&#187; del primer viaje de Walz a China.<\/p>\n<p>&#171;Heh, 1989-1990, estadounidenses ense\u00f1ando en China durante este periodo&#8230; es algo que merece la pena meditar detenidamente&#187;, dec\u00eda uno de los principales comentarios en Weibo.<\/p>\n<p>&#171;Debe de ser un esp\u00eda&#187;, dec\u00eda otro.<\/p>\n<p>Kamala Harris elige a Tim Walz como aspirante dem\u00f3crata a vicepresidente, seg\u00fan fuentes<\/p>\n<p>Liu dijo que, dado lo dr\u00e1sticamente que ha cambiado China en las \u00faltimas d\u00e9cadas, el conocimiento que Walz ten\u00eda del pa\u00eds en sus a\u00f1os mozos puede ofrecer una ayuda limitada en la pol\u00edtica estadounidense hacia China en la actualidad.<\/p>\n<p>El propio Walz ha reconocido que no es en absoluto un experto en China.<\/p>\n<p>&#171;Viv\u00ed en China y, como he dicho, he estado all\u00ed unas 30 veces&#187;, dijo en la entrevista de 2016. &#171;Pero si alguien te dice que es un experto en China, probablemente no te est\u00e9 diciendo la verdad porque es un pa\u00eds complejo&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El compa\u00f1ero de f\u00f3rmula de la presunta candidata presidencial dem\u00f3crata Kamala Harris tiene una larga relaci\u00f3n con China. Pero a los ojos de Beijing, eso puede no ser necesariamente una buena noticia. Tim Walz se traslad\u00f3 a China reci\u00e9n salido de la universidad en 1989 para ense\u00f1ar en un instituto durante un a\u00f1o, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1451712","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El elegido por Kamala Harris para vicepresidente tiene una larga historia con China. Pero puede que a Beijing no le haga mucha gracia - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/08\/10\/tim-walz-china-lazos-harris-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El elegido por Kamala Harris para vicepresidente tiene una larga historia con China. Pero puede que a Beijing no le haga mucha gracia - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El compa\u00f1ero de f\u00f3rmula de la presunta candidata presidencial dem\u00f3crata Kamala Harris tiene una larga relaci\u00f3n con China. Pero a los ojos de Beijing, eso puede no ser necesariamente una buena noticia. Tim Walz se traslad\u00f3 a China reci\u00e9n salido de la universidad en 1989 para ense\u00f1ar en un instituto durante un a\u00f1o, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/08\/10\/tim-walz-china-lazos-harris-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-10T17:03:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/10\/tim-walz-china-lazos-harris-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/10\/tim-walz-china-lazos-harris-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El elegido por Kamala Harris para vicepresidente tiene una larga historia con China. Pero puede que a Beijing no le haga mucha gracia\",\"datePublished\":\"2024-08-10T17:03:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/10\/tim-walz-china-lazos-harris-trax\/\"},\"wordCount\":2460,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/10\/tim-walz-china-lazos-harris-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/10\/tim-walz-china-lazos-harris-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/08\/10\/tim-walz-china-lazos-harris-trax\/\",\"name\":\"El elegido por Kamala Harris para vicepresidente tiene una larga historia con China. Pero puede que a Beijing no le haga mucha gracia - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-08-10T17:03:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/10\/tim-walz-china-lazos-harris-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/10\/tim-walz-china-lazos-harris-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/10\/tim-walz-china-lazos-harris-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El elegido por Kamala Harris para vicepresidente tiene una larga historia con China. Pero puede que a Beijing no le haga mucha gracia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El elegido por Kamala Harris para vicepresidente tiene una larga historia con China. Pero puede que a Beijing no le haga mucha gracia - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/08\/10\/tim-walz-china-lazos-harris-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El elegido por Kamala Harris para vicepresidente tiene una larga historia con China. Pero puede que a Beijing no le haga mucha gracia - Noticias","og_description":"(CNN) &#8212; El compa\u00f1ero de f\u00f3rmula de la presunta candidata presidencial dem\u00f3crata Kamala Harris tiene una larga relaci\u00f3n con China. Pero a los ojos de Beijing, eso puede no ser necesariamente una buena noticia. Tim Walz se traslad\u00f3 a China reci\u00e9n salido de la universidad en 1989 para ense\u00f1ar en un instituto durante un a\u00f1o, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/08\/10\/tim-walz-china-lazos-harris-trax\/","og_site_name":"Noticias","article_published_time":"2024-08-10T17:03:59+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/08\/10\/tim-walz-china-lazos-harris-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/08\/10\/tim-walz-china-lazos-harris-trax\/"},"author":{"name":"","@id":""},"headline":"El elegido por Kamala Harris para vicepresidente tiene una larga historia con China. Pero puede que a Beijing no le haga mucha gracia","datePublished":"2024-08-10T17:03:59+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/08\/10\/tim-walz-china-lazos-harris-trax\/"},"wordCount":2460,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/08\/10\/tim-walz-china-lazos-harris-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/08\/10\/tim-walz-china-lazos-harris-trax\/","url":"https:\/\/noticiasya.com\/2024\/08\/10\/tim-walz-china-lazos-harris-trax\/","name":"El elegido por Kamala Harris para vicepresidente tiene una larga historia con China. Pero puede que a Beijing no le haga mucha gracia - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-08-10T17:03:59+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/08\/10\/tim-walz-china-lazos-harris-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/08\/10\/tim-walz-china-lazos-harris-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/08\/10\/tim-walz-china-lazos-harris-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El elegido por Kamala Harris para vicepresidente tiene una larga historia con China. Pero puede que a Beijing no le haga mucha gracia"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/10\/tim-walz-china-lazos-harris-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El elegido por Kamala Harris para vicepresidente tiene una larga historia con China. Pero puede que a Beijing no le haga mucha gracia","url":"http:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/10\/tim-walz-china-lazos-harris-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/10\/tim-walz-china-lazos-harris-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-08-10T17:03:59Z","datePublished":"2024-08-10T17:03:59Z","dateModified":"2024-08-10T17:03:59Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El elegido por Kamala Harris para vicepresidente tiene una larga historia con China. Pero puede que a Beijing no le haga mucha gracia\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2024\\\/08\\\/10\\\/tim-walz-china-lazos-harris-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2024\\\/08\\\/10\\\/tim-walz-china-lazos-harris-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-08-10T17:03:59Z\",\"datePublished\":\"2024-08-10T17:03:59Z\",\"dateModified\":\"2024-08-10T17:03:59Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1459685,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/03\/09\/china-mensaje-trump-estados-unidos-trax\/","url_meta":{"origin":1451712,"position":0},"title":"China tiene un mensaje para Trump: Estados Unidos no detendr\u00e1 su ascenso","author":"","date":"marzo 9, 2025","format":false,"excerpt":"Mientras el presidente de Estados Unidos, Donald Trump, incrementaba la presi\u00f3n econ\u00f3mica sobre China durante la \u00faltima semana, Beijing envi\u00f3 su propio mensaje: su ascenso no se ver\u00e1 interrumpido.Una importante reuni\u00f3n pol\u00edtica que se est\u00e1 celebrando en la capital fue el escenario ideal para que Beijing respondiera. La reuni\u00f3n de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464639,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/07\/18\/china-iran-israel-eje-analisis-trax\/","url_meta":{"origin":1451712,"position":1},"title":"China se mantuvo al margen de la guerra entre Ir\u00e1n e Israel. Justo donde quer\u00eda estar","author":"","date":"julio 18, 2025","format":false,"excerpt":"Semanas despu\u00e9s de que su pa\u00eds fuera azotado por oleadas de ataques israel\u00edes y de que Estados Unidos bombardeara tres de sus preciadas instalaciones nucleares, el ministro de Asuntos Exteriores de Ir\u00e1n acudi\u00f3 a una reuni\u00f3n de diplom\u00e1ticos regionales en China esta semana con una petici\u00f3n sencilla.Su grupo, la Organizaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464234,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/07\/04\/china-dice-no-puede-aceptar-rusia-pierda-lguerra-ucrania-trax\/","url_meta":{"origin":1451712,"position":2},"title":"China dice a la Uni\u00f3n Europea que no puede aceptar que Rusia pierda la guerra contra Ucrania, seg\u00fan un funcionario","author":"","date":"julio 4, 2025","format":false,"excerpt":"El ministro de Relaciones Exteriores de China, Wang Yi, le dijo a la principal diplom\u00e1tica de la Uni\u00f3n Europea (UE) que Beijing no puede aceptar que Rusia pierda la guerra contra Ucrania, ya que esto permitir\u00eda a Estados Unidos centrar toda su atenci\u00f3n en China, seg\u00fan un funcionario informado sobre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444106,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/01\/19\/ucrania-esta-presionando-a-china-para-que-ayude-a-poner-fin-a-la-guerra-pero-los-planes-de-paz-de-beijing-estan-enfocados-en-otro-lado\/","url_meta":{"origin":1451712,"position":3},"title":"Ucrania est\u00e1 presionando a China para que ayude a poner fin a la guerra. Pero los planes de paz de Beijing est\u00e1n enfocados en otro lado","author":"","date":"enero 19, 2024","format":false,"excerpt":"(CNN) -- Mientras Ucrania lucha por mantener el apoyo internacional frente a la invasi\u00f3n rusa que llega a su tercer a\u00f1o, su l\u00edder ha dejado claro un pa\u00eds que le gustar\u00eda que se uniera a su impulso por la paz: China.Aumentar la presi\u00f3n sobre Beijing, el aliado pol\u00edtico m\u00e1s poderoso\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444108,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/01\/19\/ucrania-esta-presionando-a-china-para-que-ayude-a-poner-fin-a-la-guerra-pero-los-planes-de-paz-de-beijing-estan-enfocados-en-otro-lado-2\/","url_meta":{"origin":1451712,"position":4},"title":"Ucrania est\u00e1 presionando a China para que ayude a poner fin a la guerra. Pero los planes de paz de Beijing est\u00e1n enfocados en otro lado","author":"","date":"enero 19, 2024","format":false,"excerpt":"(CNN) -- Mientras Ucrania lucha por mantener el apoyo internacional frente a la invasi\u00f3n rusa que llega a su tercer a\u00f1o, su l\u00edder ha dejado claro un pa\u00eds que le gustar\u00eda que se uniera a su impulso por la paz: China.Aumentar la presi\u00f3n sobre Beijing, el aliado pol\u00edtico m\u00e1s poderoso\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457830,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/01\/24\/trump-china-eeuu-relaciones-comerciales-analisis-trax\/","url_meta":{"origin":1451712,"position":5},"title":"AN\u00c1LISIS | Trump 2.0 va bien para China hasta ahora. Pero, \u00bfpuede durar la luna de miel?","author":"","date":"enero 24, 2025","format":false,"excerpt":"El segundo mandato de Donald Trump empieza con buen pie para China.Hasta ahora, el nuevo presidente estadounidense se abstuvo de cumplir su amenaza de imponer fuertes aranceles a China, dijo a l\u00edderes empresariales y pol\u00edticos en un foro econ\u00f3mico en Davos que los dos pa\u00edses podr\u00edan tener una \u201cmuy buena\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1451712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1451712"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1451712\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1451712"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1451712"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1451712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}