{"id":1451810,"date":"2024-08-12T23:03:46","date_gmt":"2024-08-13T06:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/08\/12\/trump-y-musk-mantienen-conversacion-amistosa-en-x-tras-retraso-por-dificultades-tecnicas\/"},"modified":"2024-08-12T23:03:46","modified_gmt":"2024-08-13T06:03:46","slug":"trump-y-musk-mantienen-conversacion-amistosa-en-x-tras-retraso-por-dificultades-tecnicas","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/12\/trump-y-musk-mantienen-conversacion-amistosa-en-x-tras-retraso-por-dificultades-tecnicas\/","title":{"rendered":"Trump y Musk mantienen conversaci\u00f3n amistosa en X tras retraso por dificultades t\u00e9cnicas"},"content":{"rendered":"<p>(CNN) &#8212; El expresidente Donald Trump y el director ejecutivo de Tesla y propietario de X, Elon Musk, mantuvieron una conversaci\u00f3n amistosa este lunes en X despu\u00e9s de que su entrevista se retrasara m\u00e1s de 40 minutos debido a dificultades t\u00e9cnicas.<\/p>\n<p>El retraso de la entrevista de alto perfil fue el \u00faltimo tropiezo de la campa\u00f1a de Trump en su intento de recuperar impulso despu\u00e9s de que el Partido Dem\u00f3crata se uniera en torno a la vicepresidenta Kamala Harris. Tambi\u00e9n marc\u00f3 la segunda vez que Musk sufri\u00f3 un rev\u00e9s al intentar lanzar un X Space muy concurrido con un candidato presidencial.<\/p>\n<p>La discusi\u00f3n entre el expresidente y el hombre m\u00e1s rico del mundo, que ha respaldado a Trump, marc\u00f3 el regreso de Trump a X despu\u00e9s de que su cuenta hab\u00eda permanecido inactiva durante casi un a\u00f1o. La \u00faltima vez que Trump hab\u00eda publicado en el sitio web de redes sociales fue cuando public\u00f3 su foto policial mientras era procesado en una c\u00e1rcel de Atlanta por el caso de subversi\u00f3n electoral de Georgia en agosto del a\u00f1o pasado. Trump hab\u00eda ganado alrededor de 900.000 nuevos seguidores hasta el lunes por la noche desde que comenz\u00f3 a publicar nuevamente en la plataforma.<\/p>\n<p>A lo largo de la conversaci\u00f3n, Musk le hizo preguntas f\u00e1ciles a Trump que le permitieron al expresidente ce\u00f1irse a sus puntos de vista, incluidos los de inmigraci\u00f3n y econom\u00eda. Repiti\u00f3 partes de su discurso de campa\u00f1a y Musk no cuestion\u00f3 ninguna de sus afirmaciones falsas.<\/p>\n<p>Los dos hombres tambi\u00e9n se elogiaron mutuamente, y Musk afirm\u00f3: &#171;Creo que estamos en una encrucijada en el camino del destino de la civilizaci\u00f3n y creo que debemos tomar el camino correcto y creo que t\u00fa est\u00e1s en el camino correcto&#187;.<\/p>\n<p>Trump dijo que el apoyo de Musk \u201csignifica mucho para m\u00ed\u201d y agreg\u00f3: \u201cPara ser honesto, no todos los apoyos significan tanto. Tu apoyo signific\u00f3 mucho\u201d.<\/p>\n<p>En un momento dado, Musk sugiri\u00f3 que Trump deber\u00eda formar una nueva comisi\u00f3n presidencial centrada en la \u201ceficiencia del gobierno\u201d y nombrarlo miembro de ella. Trump respondi\u00f3 de inmediato: \u201cMe encantar\u00eda\u201d.<\/p>\n<p>Trump y Musk comenzaron su conversaci\u00f3n con el expresidente contando en detalle c\u00f3mo hab\u00eda sobrevivido al intento de magnicidio en su mitin en Butler, Pensilvania, el 13 de julio. Trump habl\u00f3 de c\u00f3mo la polic\u00eda local y los asistentes al mitin hab\u00edan visto al tirador, y elogi\u00f3 al Servicio Secreto por su reacci\u00f3n al tiroteo.<\/p>\n<p>Su conversaci\u00f3n cubri\u00f3 una amplia gama de temas, incluyendo largas porciones sobre pol\u00edtica energ\u00e9tica, cambio clim\u00e1tico y la amenaza de una guerra nuclear; inmigraci\u00f3n, con Trump prometiendo la \u201cmayor deportaci\u00f3n en la historia de este pa\u00eds\u201d; gasto del gobierno federal, con Musk proponiendo una comisi\u00f3n para buscar formas de hacer recortes; y m\u00e1s.<\/p>\n<p>Trump acus\u00f3 a los dem\u00f3cratas de un golpe de Estado para sacar al presidente Joe Biden de la papeleta electoral, sin presentar pruebas. Habl\u00f3 de la aparici\u00f3n de Harris en una portada de la revista Time y critic\u00f3 el estado mental de Biden. Dijo que los jud\u00edos que votan por los dem\u00f3cratas deber\u00edan hacerse &#171;examinar la cabeza&#187;.<\/p>\n<p>&#171;Podemos hablar de t\u00faneles, cohetes, coches el\u00e9ctricos y muchas cosas m\u00e1s. Y ahora estamos hablando de inteligencia artificial, y eso ser\u00e1 otra belleza&#187;, le dijo Trump a Musk hacia el final de la conversaci\u00f3n.<\/p>\n<p>En varios momentos de la entrevista, el discurso de Trump son\u00f3 como si ceceara o arrastrara las palabras, lo que atrajo la atenci\u00f3n en Internet.<\/p>\n<p>Cuando se le pregunt\u00f3 si hab\u00eda una explicaci\u00f3n, el portavoz de la campa\u00f1a de Trump, Steven Cheung, dijo: &#171;Debe ser su audici\u00f3n&#187;.<\/p>\n<p>La campa\u00f1a de Harris describi\u00f3 a Trump y Musk como \u201ctipos ricos obsesionados con s\u00ed mismos\u201d en un comunicado.<\/p>\n<p>\u201cToda la campa\u00f1a de Trump est\u00e1 al servicio de gente como Elon Musk y \u00e9l mismo: tipos ricos obsesionados consigo mismos que vender\u00e1n a la clase media y que no pueden realizar una transmisi\u00f3n en vivo en el a\u00f1o 2024\u201d, dijo el portavoz de la campa\u00f1a de Harris, Joseph Costello.<\/p>\n<p>Un comienzo retrasado<\/p>\n<p>Cuando las dificultades t\u00e9cnicas retrasaron el inicio de su conversaci\u00f3n, Musk afirm\u00f3 que un ataque distribuido de denegaci\u00f3n de servicio hab\u00eda abrumado los servidores de la compa\u00f1\u00eda, pero no estaba claro de inmediato si los malos actores estaban detr\u00e1s de lo que Musk llam\u00f3 un &#171;ataque&#187;, o si el problema fue simplemente causado por demasiados usuarios que intentaban escuchar la conversaci\u00f3n.<\/p>\n<p>\u201cParece que hay un ataque DDOS masivo en \ud835\udd4f. Estamos trabajando para desactivarlo\u201d, dijo Musk en una publicaci\u00f3n en X. \u201cEn el peor de los casos, procederemos con un n\u00famero menor de oyentes en vivo y publicaremos la conversaci\u00f3n m\u00e1s tarde\u201d.<\/p>\n<p>\u201cDDOS\u201d, o denegaci\u00f3n de servicio distribuida, es un m\u00e9todo de ataque com\u00fan en el que los piratas inform\u00e1ticos inundan un sitio con tr\u00e1fico falso para saturar sus sistemas e intentar desconectarlo.<\/p>\n<p>Musk dijo en una publicaci\u00f3n separada que X \u201cprob\u00f3 el sistema con 8 millones de oyentes simult\u00e1neos hoy temprano\u201d.<\/p>\n<p>El inicio problem\u00e1tico de la entrevista, que solo se transmiti\u00f3 en audio, record\u00f3 el lanzamiento del a\u00f1o pasado del gobernador de Florida, Ron DeSantis, de su fallida campa\u00f1a para la nominaci\u00f3n presidencial republicana. DeSantis intent\u00f3 iniciar su campa\u00f1a con un evento en Twitter Spaces con Musk, pero el evento se retras\u00f3 25 minutos y se vio empa\u00f1ado por dificultades t\u00e9cnicas que resultaron en una audiencia mucho menor que las 500.000 personas que inicialmente hab\u00edan intentado unirse y escuchar.<\/p>\n<p>En ese momento, Trump se burl\u00f3 del fallido lanzamiento de DeSantis y dijo en su sitio web Truth Social que fue &#171;\u00a1un DESASTRE!&#187;.<\/p>\n<p>\u201cToda su campa\u00f1a ser\u00e1 un desastre\u201d, dijo Trump.<\/p>\n<p>La campa\u00f1a de Harris comparti\u00f3 ese comentario de Trump sobre DeSantis en su propia cuenta Truth Social cuando el evento del expresidente con Musk se retras\u00f3 el lunes por la noche.<\/p>\n<p>Esta historia ha sido actualizada con informaci\u00f3n adicional.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El expresidente Donald Trump y el director ejecutivo de Tesla y propietario de X, Elon Musk, mantuvieron una conversaci\u00f3n amistosa este lunes en X despu\u00e9s de que su entrevista se retrasara m\u00e1s de 40 minutos debido a dificultades t\u00e9cnicas. El retraso de la entrevista de alto perfil fue el \u00faltimo tropiezo de la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1451810","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump y Musk mantienen conversaci\u00f3n amistosa en X tras retraso por dificultades t\u00e9cnicas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/08\/12\/trump-y-musk-mantienen-conversacion-amistosa-en-x-tras-retraso-por-dificultades-tecnicas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump y Musk mantienen conversaci\u00f3n amistosa en X tras retraso por dificultades t\u00e9cnicas - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El expresidente Donald Trump y el director ejecutivo de Tesla y propietario de X, Elon Musk, mantuvieron una conversaci\u00f3n amistosa este lunes en X despu\u00e9s de que su entrevista se retrasara m\u00e1s de 40 minutos debido a dificultades t\u00e9cnicas. El retraso de la entrevista de alto perfil fue el \u00faltimo tropiezo de la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/08\/12\/trump-y-musk-mantienen-conversacion-amistosa-en-x-tras-retraso-por-dificultades-tecnicas\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-13T06:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/12\/trump-y-musk-mantienen-conversacion-amistosa-en-x-tras-retraso-por-dificultades-tecnicas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/12\/trump-y-musk-mantienen-conversacion-amistosa-en-x-tras-retraso-por-dificultades-tecnicas\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump y Musk mantienen conversaci\u00f3n amistosa en X tras retraso por dificultades t\u00e9cnicas\",\"datePublished\":\"2024-08-13T06:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/12\/trump-y-musk-mantienen-conversacion-amistosa-en-x-tras-retraso-por-dificultades-tecnicas\/\"},\"wordCount\":1082,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/12\/trump-y-musk-mantienen-conversacion-amistosa-en-x-tras-retraso-por-dificultades-tecnicas\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/12\/trump-y-musk-mantienen-conversacion-amistosa-en-x-tras-retraso-por-dificultades-tecnicas\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/08\/12\/trump-y-musk-mantienen-conversacion-amistosa-en-x-tras-retraso-por-dificultades-tecnicas\/\",\"name\":\"Trump y Musk mantienen conversaci\u00f3n amistosa en X tras retraso por dificultades t\u00e9cnicas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-08-13T06:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/12\/trump-y-musk-mantienen-conversacion-amistosa-en-x-tras-retraso-por-dificultades-tecnicas\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/12\/trump-y-musk-mantienen-conversacion-amistosa-en-x-tras-retraso-por-dificultades-tecnicas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/12\/trump-y-musk-mantienen-conversacion-amistosa-en-x-tras-retraso-por-dificultades-tecnicas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump y Musk mantienen conversaci\u00f3n amistosa en X tras retraso por dificultades t\u00e9cnicas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump y Musk mantienen conversaci\u00f3n amistosa en X tras retraso por dificultades t\u00e9cnicas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/08\/12\/trump-y-musk-mantienen-conversacion-amistosa-en-x-tras-retraso-por-dificultades-tecnicas\/","og_locale":"es_ES","og_type":"article","og_title":"Trump y Musk mantienen conversaci\u00f3n amistosa en X tras retraso por dificultades t\u00e9cnicas - Noticias","og_description":"(CNN) &#8212; El expresidente Donald Trump y el director ejecutivo de Tesla y propietario de X, Elon Musk, mantuvieron una conversaci\u00f3n amistosa este lunes en X despu\u00e9s de que su entrevista se retrasara m\u00e1s de 40 minutos debido a dificultades t\u00e9cnicas. El retraso de la entrevista de alto perfil fue el \u00faltimo tropiezo de la [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/08\/12\/trump-y-musk-mantienen-conversacion-amistosa-en-x-tras-retraso-por-dificultades-tecnicas\/","og_site_name":"Noticias","article_published_time":"2024-08-13T06:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/08\/12\/trump-y-musk-mantienen-conversacion-amistosa-en-x-tras-retraso-por-dificultades-tecnicas\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/08\/12\/trump-y-musk-mantienen-conversacion-amistosa-en-x-tras-retraso-por-dificultades-tecnicas\/"},"author":{"name":"","@id":""},"headline":"Trump y Musk mantienen conversaci\u00f3n amistosa en X tras retraso por dificultades t\u00e9cnicas","datePublished":"2024-08-13T06:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/08\/12\/trump-y-musk-mantienen-conversacion-amistosa-en-x-tras-retraso-por-dificultades-tecnicas\/"},"wordCount":1082,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/08\/12\/trump-y-musk-mantienen-conversacion-amistosa-en-x-tras-retraso-por-dificultades-tecnicas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/08\/12\/trump-y-musk-mantienen-conversacion-amistosa-en-x-tras-retraso-por-dificultades-tecnicas\/","url":"https:\/\/noticiasya.com\/2024\/08\/12\/trump-y-musk-mantienen-conversacion-amistosa-en-x-tras-retraso-por-dificultades-tecnicas\/","name":"Trump y Musk mantienen conversaci\u00f3n amistosa en X tras retraso por dificultades t\u00e9cnicas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-08-13T06:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/08\/12\/trump-y-musk-mantienen-conversacion-amistosa-en-x-tras-retraso-por-dificultades-tecnicas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/08\/12\/trump-y-musk-mantienen-conversacion-amistosa-en-x-tras-retraso-por-dificultades-tecnicas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/08\/12\/trump-y-musk-mantienen-conversacion-amistosa-en-x-tras-retraso-por-dificultades-tecnicas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump y Musk mantienen conversaci\u00f3n amistosa en X tras retraso por dificultades t\u00e9cnicas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/12\/trump-y-musk-mantienen-conversacion-amistosa-en-x-tras-retraso-por-dificultades-tecnicas\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump y Musk mantienen conversaci\u00f3n amistosa en X tras retraso por dificultades t\u00e9cnicas","url":"http:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/12\/trump-y-musk-mantienen-conversacion-amistosa-en-x-tras-retraso-por-dificultades-tecnicas\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/12\/trump-y-musk-mantienen-conversacion-amistosa-en-x-tras-retraso-por-dificultades-tecnicas\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-08-13T06:03:46Z","datePublished":"2024-08-13T06:03:46Z","dateModified":"2024-08-13T06:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump y Musk mantienen conversaci\\u00f3n amistosa en X tras retraso por dificultades t\\u00e9cnicas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2024\\\/08\\\/12\\\/trump-y-musk-mantienen-conversacion-amistosa-en-x-tras-retraso-por-dificultades-tecnicas\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2024\\\/08\\\/12\\\/trump-y-musk-mantienen-conversacion-amistosa-en-x-tras-retraso-por-dificultades-tecnicas\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-08-13T06:03:46Z\",\"datePublished\":\"2024-08-13T06:03:46Z\",\"dateModified\":\"2024-08-13T06:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1451812,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/13\/musk-ayuda-trump-harris-x-analisis-trax\/","url_meta":{"origin":1451810,"position":0},"title":"AN\u00c1LISIS | Musk intenta ayudar a Trump a frenar la subida de Harris","author":"","date":"agosto 13, 2024","format":false,"excerpt":"(CNN) -- El hombre m\u00e1s rico del mundo y el otrora \u2013y posiblemente futuro\u2013 hombre m\u00e1s poderoso coincidieron en casi todo.El tit\u00e1n de la tecnolog\u00eda Elon Musk abri\u00f3 de par en par su plataforma X este lunes por la noche, y le ofreci\u00f3 a Donald Trump una v\u00eda libre de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451758,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/12\/trump-x-twitter-musk-trax\/","url_meta":{"origin":1451810,"position":1},"title":"Trump publica en X por primera vez en casi un a\u00f1o, poco antes de la conversaci\u00f3n con Elon Musk","author":"","date":"agosto 12, 2024","format":false,"excerpt":"(CNN) -- El expresidente Donald Trump public\u00f3 el lunes en X \u2014antes conocido como Twitter\u2014 por primera vez en casi un a\u00f1o, antes de la conversaci\u00f3n que mantendr\u00e1 m\u00e1s tarde en la plataforma con el propietario de X y CEO de Tesla, Elon Musk.Entre las publicaciones de Trump en X\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463160,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/06\/03\/musk-califica-proyecto-ley-trump-abominacion-repugnante-trax\/","url_meta":{"origin":1451810,"position":2},"title":"Elon Musk califica el proyecto de ley presupuestal de Trump como una &#171;abominaci\u00f3n repugnante&#187;","author":"","date":"junio 3, 2025","format":false,"excerpt":"Elon Musk arremeti\u00f3 el martes contra el proyecto de ley presupuestal del presidente Donald Trump \u2014por el que el mandatario est\u00e1 presionando a los senadores republicanos para que respalden\u2014 y lo calific\u00f3 como una \u201cabominaci\u00f3n repugnante\u201d.\u201cLo siento, pero ya no lo soporto. Este proyecto de ley de gastos del Congreso,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459740,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/03\/10\/elon-musk-interrupciones-x-ciberataque-trax\/","url_meta":{"origin":1451810,"position":3},"title":"Elon Musk afirma que la oleada de interrupciones que afectan a X se deben a &#171;un ciberataque masivo&#187;","author":"","date":"marzo 10, 2025","format":false,"excerpt":"La red social X de Elon Musk se ha visto afectada desde la ma\u00f1ana de este lunes por tres oleadas de interrupciones, las cuales el multimillonario afirma que se deben a un ciberataque.Seg\u00fan el sitio de seguimiento de interrupciones DownDetector, los problemas comenzaron alrededor de las 6 a.m. (hora de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451821,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/13\/trump-elogia-milei-musk-orix\/","url_meta":{"origin":1451810,"position":4},"title":"Trump elogia a Milei en su conversaci\u00f3n con Elon Musk: &#171;Est\u00e1 haciendo un gran trabajo, realmente recort\u00f3&#187;","author":"","date":"agosto 13, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El expresidente Donald Trump elogi\u00f3 al mandatario de Argentina, Javier Milei, durante su conversaci\u00f3n con Elon Mausk en la plataforma X, antes Twitter, haciendo \u00e9nfasis en los recortes del gasto que ha puesto en marcha el l\u00edder sudamericano.Sin mencionar su nombre, Trump habl\u00f3 de Javier Milei como\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461422,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/04\/20\/elon-musk-doge-entrevista-desafiante-trax\/","url_meta":{"origin":1451810,"position":5},"title":"Elon Musk es la cara de DOGE pero no ha enfrentado una entrevista desafiante","author":"","date":"abril 20, 2025","format":false,"excerpt":"En abril de 2023, unos meses despu\u00e9s de que Elon Musk comprara Twitter, ahora llamado X, el franco multimillonario realiz\u00f3 una especie de gira medi\u00e1tica.\u201cEstoy haciendo entrevistas a lo largo del espectro pol\u00edtico. La divisi\u00f3n de SF de la BBC es \u2018de izquierda\u2019, como lo demuestran las preguntas que hizo.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1451810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1451810"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1451810\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1451810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1451810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1451810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}