{"id":1451854,"date":"2024-08-14T14:03:52","date_gmt":"2024-08-14T21:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/08\/14\/corea-norte-turismo-internacional-trax\/"},"modified":"2024-08-14T14:03:52","modified_gmt":"2024-08-14T21:03:52","slug":"corea-norte-turismo-internacional-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/14\/corea-norte-turismo-internacional-trax\/","title":{"rendered":"Corea del Norte reabrir\u00e1 sus puertas al turismo internacional este invierno, afirman operadores tur\u00edsticos"},"content":{"rendered":"<p>(CNN) &#8212; Corea del Norte reabrir\u00e1 el turismo internacional limitado a fines de 2024, casi cinco a\u00f1os despu\u00e9s de cerrar por completo las fronteras del pa\u00eds debido a la pandemia de covid-19, seg\u00fan anunciaron dos compa\u00f1\u00edas de viajes con conexiones con el pa\u00eds aislado.<\/p>\n<p>Koryo Tours, con sede en Beijing, y KTG Tours, con sede en Shenyang, hicieron anuncios online por separado este mi\u00e9rcoles, en los que dijeron a grupos de turistas que se les permitir\u00eda visitar la ciudad monta\u00f1osa de Samjiyon, el supuesto lugar de nacimiento del difunto l\u00edder norcoreano Kim Jong Il.<\/p>\n<p>C\u00f3mo es ir a un campamento de verano en Corea del Norte<\/p>\n<p>\u201cHemos recibido la confirmaci\u00f3n de nuestro socio local de que el turismo en Samjiyon y probablemente en el resto del pa\u00eds se reanudar\u00e1 oficialmente en diciembre de 2024\u201d, dijo Koryo Tours, y agreg\u00f3 que el itinerario y otros detalles se finalizar\u00e1n \u201cen los pr\u00f3ximos d\u00edas y semanas\u201d.<\/p>\n<p>En una publicaci\u00f3n aparte en Facebook , KTG Tours tambi\u00e9n dijo que las fechas exactas de los recorridos a\u00fan no se hab\u00edan confirmado. \u201cHasta ahora solo se ha mencionado Samjiyon, pero creemos que PY (Pyongyang) y otros lugares tambi\u00e9n abrir\u00e1n\u201d.<\/p>\n<p>Samjiyon se encuentra sobre la frontera con China y est\u00e1 cerca del pico m\u00e1s alto de la pen\u00ednsula de Corea, el monte Paektu, un volc\u00e1n activo de suma importancia y significado hist\u00f3rico para los norcoreanos y surcoreanos, ya que se considera la cuna del pueblo coreano.<\/p>\n<p>El linaje &#8216;Paektu&#8217;<\/p>\n<p>Aunque los surcoreanos tienen restringido visitar el Norte, el expresidente de Corea del Sur, Moon Jae-in, y la entonces primera dama Kim Jung-sook, visitaron la cima de la monta\u00f1a con Kim Jong Un y su esposa Ri Sol Ju en 2018, lo que resalta el simbolismo de la monta\u00f1a.<\/p>\n<p>Visitar la cima del monte Paektu es como hacer una peregrinaci\u00f3n religiosa para los norcoreanos. El legendario linaje de los \u201cPaektu\u201d es lo que le da legitimidad a la familia gobernante Kim, dicen los observadores, quienes a su vez remarcan las contradictorias afirmaciones de los historiadores occidentales de que el l\u00edder de segunda generaci\u00f3n naci\u00f3 en Rusia.<\/p>\n<p>Samjiyon era un destino popular para los turistas chinos, que sol\u00edan llegar en autobuses antes de la pandemia de covid-19. El turismo proporcionaba ingresos econ\u00f3micos a Corea del Norte a pesar de las sanciones internacionales por los programas ilegales de misiles bal\u00edsticos y nucleares de Pyongyang.<\/p>\n<p>Corea del Norte dice que el pacto de defensa de Kim y Putin permite todos los medios disponibles para ayudarse si cualquiera de las dos naciones es atacada<\/p>\n<p>El l\u00edder norcoreano Kim Jong Un inspeccion\u00f3 personalmente los sitios de construcci\u00f3n dentro de Samjiyon a principios de julio, informaron los medios estatales.<\/p>\n<p>Los medios estatales de Corea del Norte no informaron hasta el momento cambios relacionados con la reapertura del pa\u00eds a los visitantes extranjeros, pero el l\u00edder norcoreano Kim Jong Un ha indicado previamente que priorizar\u00eda a los visitantes de naciones &#171;amigas&#187;, que incluyen a Rusia y China.<\/p>\n<p>Turistas chinos posan para fotograf\u00edas en la plaza Kim Il Sung en 2019. Cr\u00e9dito: Ed Jones\/AFP\/Getty Images.<\/p>\n<p>El camino hacia la reapertura<\/p>\n<p>La pandemia dej\u00f3 las fronteras de Corea del Norte herm\u00e9ticamente selladas para casi todo el mundo exterior durante varios a\u00f1os, restricciones que contin\u00faan en gran medida, excepto para peque\u00f1os grupos de turistas procedentes de Rusia, a quienes se les permiti\u00f3 ingresar este a\u00f1o en medio de la profundizaci\u00f3n de la asociaci\u00f3n de Kim con el presidente de Rusia, Vladimir Putin.<\/p>\n<p>Unos 100 turistas rusos fueron recibidos en Corea del Norte a principios de este a\u00f1o, y viajaron en un avi\u00f3n Air Koryo, propiedad norcoreana, desde Vladivostok.<\/p>\n<p>Por qu\u00e9 es tan impactante esta selfie en el podio con atletas de Corea del Norte y Corea del Sur en los Juegos Ol\u00edmpicos de Par\u00eds 2024<\/p>\n<p>Pero las restricciones fronterizas por la pandemia obligaron a la mayor\u00eda de las misiones diplom\u00e1ticas y organizaciones internacionales sin fines de lucro a retirarse de Corea del Norte. Esto dej\u00f3 a la empobrecida naci\u00f3n de alrededor de 25 millones de habitantes posiblemente en el lugar m\u00e1s aislado del mundo desde la Guerra Fr\u00eda.<\/p>\n<p>Los pasaportes estadounidenses no son v\u00e1lidos para viajar hacia, dentro o a trav\u00e9s de Corea del Norte, a menos que est\u00e9n especialmente validados por el Departamento de Estado de EE.UU. El departamento clasifica a Corea del Norte como de \u201cNivel 4: no viajar\u201d.<\/p>\n<p>Los anuncios de reabrir el turismo se producen aproximadamente un mes despu\u00e9s de que Kim visitara un nuevo sitio tur\u00edstico junto a la playa, la zona de Wonsan-Kalma, en la costa oriental del pa\u00eds, que est\u00e1 actualmente en desarrollo.<\/p>\n<p>Kim dijo que el complejo se inaugurar\u00eda en mayo de 2025, despu\u00e9s de a\u00f1os de retrasos en la construcci\u00f3n debido a la pandemia de covid-19 y las sanciones de las Naciones Unidas, inform\u00f3 la agencia estatal de noticias KCNA.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Corea del Norte reabrir\u00e1 el turismo internacional limitado a fines de 2024, casi cinco a\u00f1os despu\u00e9s de cerrar por completo las fronteras del pa\u00eds debido a la pandemia de covid-19, seg\u00fan anunciaron dos compa\u00f1\u00edas de viajes con conexiones con el pa\u00eds aislado. Koryo Tours, con sede en Beijing, y KTG Tours, con sede [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1451854","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Corea del Norte reabrir\u00e1 sus puertas al turismo internacional este invierno, afirman operadores tur\u00edsticos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/08\/14\/corea-norte-turismo-internacional-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corea del Norte reabrir\u00e1 sus puertas al turismo internacional este invierno, afirman operadores tur\u00edsticos - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Corea del Norte reabrir\u00e1 el turismo internacional limitado a fines de 2024, casi cinco a\u00f1os despu\u00e9s de cerrar por completo las fronteras del pa\u00eds debido a la pandemia de covid-19, seg\u00fan anunciaron dos compa\u00f1\u00edas de viajes con conexiones con el pa\u00eds aislado. Koryo Tours, con sede en Beijing, y KTG Tours, con sede [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/08\/14\/corea-norte-turismo-internacional-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-14T21:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/14\/corea-norte-turismo-internacional-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/14\/corea-norte-turismo-internacional-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Corea del Norte reabrir\u00e1 sus puertas al turismo internacional este invierno, afirman operadores tur\u00edsticos\",\"datePublished\":\"2024-08-14T21:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/14\/corea-norte-turismo-internacional-trax\/\"},\"wordCount\":892,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/14\/corea-norte-turismo-internacional-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/14\/corea-norte-turismo-internacional-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/08\/14\/corea-norte-turismo-internacional-trax\/\",\"name\":\"Corea del Norte reabrir\u00e1 sus puertas al turismo internacional este invierno, afirman operadores tur\u00edsticos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-08-14T21:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/14\/corea-norte-turismo-internacional-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/14\/corea-norte-turismo-internacional-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/14\/corea-norte-turismo-internacional-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Corea del Norte reabrir\u00e1 sus puertas al turismo internacional este invierno, afirman operadores tur\u00edsticos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Corea del Norte reabrir\u00e1 sus puertas al turismo internacional este invierno, afirman operadores tur\u00edsticos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/08\/14\/corea-norte-turismo-internacional-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Corea del Norte reabrir\u00e1 sus puertas al turismo internacional este invierno, afirman operadores tur\u00edsticos - Noticias","og_description":"(CNN) &#8212; Corea del Norte reabrir\u00e1 el turismo internacional limitado a fines de 2024, casi cinco a\u00f1os despu\u00e9s de cerrar por completo las fronteras del pa\u00eds debido a la pandemia de covid-19, seg\u00fan anunciaron dos compa\u00f1\u00edas de viajes con conexiones con el pa\u00eds aislado. Koryo Tours, con sede en Beijing, y KTG Tours, con sede [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/08\/14\/corea-norte-turismo-internacional-trax\/","og_site_name":"Noticias","article_published_time":"2024-08-14T21:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/08\/14\/corea-norte-turismo-internacional-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/08\/14\/corea-norte-turismo-internacional-trax\/"},"author":{"name":"","@id":""},"headline":"Corea del Norte reabrir\u00e1 sus puertas al turismo internacional este invierno, afirman operadores tur\u00edsticos","datePublished":"2024-08-14T21:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/08\/14\/corea-norte-turismo-internacional-trax\/"},"wordCount":892,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/08\/14\/corea-norte-turismo-internacional-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/08\/14\/corea-norte-turismo-internacional-trax\/","url":"https:\/\/noticiasya.com\/2024\/08\/14\/corea-norte-turismo-internacional-trax\/","name":"Corea del Norte reabrir\u00e1 sus puertas al turismo internacional este invierno, afirman operadores tur\u00edsticos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-08-14T21:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/08\/14\/corea-norte-turismo-internacional-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/08\/14\/corea-norte-turismo-internacional-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/08\/14\/corea-norte-turismo-internacional-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Corea del Norte reabrir\u00e1 sus puertas al turismo internacional este invierno, afirman operadores tur\u00edsticos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/14\/corea-norte-turismo-internacional-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Corea del Norte reabrir\u00e1 sus puertas al turismo internacional este invierno, afirman operadores tur\u00edsticos","url":"http:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/14\/corea-norte-turismo-internacional-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/14\/corea-norte-turismo-internacional-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-08-14T21:03:52Z","datePublished":"2024-08-14T21:03:52Z","dateModified":"2024-08-14T21:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Corea del Norte reabrir\\u00e1 sus puertas al turismo internacional este invierno, afirman operadores tur\\u00edsticos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2024\\\/08\\\/14\\\/corea-norte-turismo-internacional-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2024\\\/08\\\/14\\\/corea-norte-turismo-internacional-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-08-14T21:03:52Z\",\"datePublished\":\"2024-08-14T21:03:52Z\",\"dateModified\":\"2024-08-14T21:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1456160,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/11\/29\/starbucks-nueva-sucursal-corea-norte-trax\/","url_meta":{"origin":1451854,"position":0},"title":"Starbucks abre una sucursal con vistas a Corea del Norte","author":"","date":"noviembre 29, 2024","format":false,"excerpt":"Se\u00fal, Corea del Norte (CNN) -- Los amantes del caf\u00e9 que est\u00e9n interesados en vislumbrar la vida en la naci\u00f3n m\u00e1s reclusa del mundo deber\u00edan prepararse para viajar: Starbucks tiene el lugar perfecto para ellos.El \u00faltimo establecimiento de la cadena estadounidense en Corea del Sur est\u00e1 situado en una torre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446027,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/02\/26\/turistas-rusos-corea-del-norte-trax\/","url_meta":{"origin":1451854,"position":1},"title":"Los turistas regresaron a Corea del Norte por primera vez desde la pandemia. Esto es lo que vieron","author":"","date":"febrero 26, 2024","format":false,"excerpt":"(CNN) -- Lena Bychcova no pod\u00eda creerlo cuando recibi\u00f3 su visa de turista norcoreana.Muchos turistas rusos se han visto excluidos de los destinos tur\u00edsticos. Pero Corea del Norte, como aliado clave de Rusia, ofrec\u00eda una rara oportunidad de viajar.La profesional de mercadeo fue una de los aproximadamente 100 ciudadanos rusos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458876,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/02\/18\/turistas-estadounidenses-corea-del-norte-seis-cifras-segundo-pasaporte-trax\/","url_meta":{"origin":1451854,"position":2},"title":"Los turistas de EE.UU. no pueden visitar Corea del Norte: uno pag\u00f3 una suma de seis cifras por otro pasaporte para poder ir","author":"","date":"febrero 18, 2025","format":false,"excerpt":"Para la mayor parte del mundo, los d\u00edas oscuros del covid-19 parecen un recuerdo lejano, pero no es as\u00ed en Corea del Norte, dijo Justin Martell, quien acaba de convertirse en el primer estadounidense conocido en poner un pie en el misterioso pa\u00eds desde el inicio de la pandemia, hace\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447979,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/04\/11\/china-envia-delegacion-corea-del-norte-trax\/","url_meta":{"origin":1451854,"position":3},"title":"China env\u00eda su delegaci\u00f3n de m\u00e1s alto nivel a Corea del Norte para iniciar un &#171;a\u00f1o de la amistad&#187;","author":"","date":"abril 11, 2024","format":false,"excerpt":"Hong Kong (CNN) -- La visita de m\u00e1s alto nivel de China a Corea del Norte en casi cinco a\u00f1os, desde 2019, comenz\u00f3 este jueves, mientras Pyongyang busca fortalecer las relaciones tanto con Beijing como con Mosc\u00fa en medio de una creciente coordinaci\u00f3n entre sus vecinos y Estados Unidos.Zhao Leji,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443838,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/01\/16\/kim-jong-un-promete-desmantelar-el-arco-de-unificacion-de-su-padre-en-corea-del-norte-y-declara-a-corea-del-sur-su-enemigo-principal\/","url_meta":{"origin":1451854,"position":4},"title":"Kim Jong Un promete desmantelar el arco de unificaci\u00f3n de su padre en Corea del Norte y declara a Corea del Sur su &#171;enemigo principal&#187;","author":"","date":"enero 16, 2024","format":false,"excerpt":"Se\u00fal, Corea del Sur (CNN) -- El l\u00edder norcoreano Kim Jong Un prometi\u00f3 este lunes retirar un enorme monumento a la posible reunificaci\u00f3n de la Pen\u00ednsula de Corea que su padre construy\u00f3 en Pyongyang, calific\u00e1ndolo de \u201cmonstruo a la vista\u201d.La llamada de Kim durante un discurso en una reuni\u00f3n de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443840,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/01\/16\/kim-jong-un-promete-desmantelar-el-arco-de-unificacion-de-su-padre-en-corea-del-norte-y-declara-a-corea-del-sur-su-enemigo-principal-2\/","url_meta":{"origin":1451854,"position":5},"title":"Kim Jong Un promete desmantelar el arco de unificaci\u00f3n de su padre en Corea del Norte y declara a Corea del Sur su &#171;enemigo principal&#187;","author":"","date":"enero 16, 2024","format":false,"excerpt":"Se\u00fal, Corea del Sur (CNN) -- El l\u00edder norcoreano Kim Jong Un prometi\u00f3 este lunes retirar un enorme monumento a la posible reunificaci\u00f3n de la Pen\u00ednsula de Corea que su padre construy\u00f3 en Pyongyang, calific\u00e1ndolo de \u201cmonstruo a la vista\u201d.La llamada de Kim durante un discurso en una reuni\u00f3n de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1451854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1451854"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1451854\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1451854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1451854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1451854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}