{"id":1451953,"date":"2024-08-18T03:03:46","date_gmt":"2024-08-18T10:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/08\/18\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax\/"},"modified":"2024-08-18T03:03:46","modified_gmt":"2024-08-18T10:03:46","slug":"muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/18\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax\/","title":{"rendered":"Alain Delon, leyenda del cine franc\u00e9s, muere a los 88 a\u00f1os"},"content":{"rendered":"<p>(CNN) &#8211;Alain Delon, el actor, productor y escritor franc\u00e9s cuya belleza fresca y enigm\u00e1tica lo convirti\u00f3 en un s\u00edmbolo sexual internacional, muri\u00f3 a la edad de 88 a\u00f1os.<\/p>\n<p>\u201cFalleci\u00f3 en paz en su casa de Douchy, rodeado de sus tres hijos y su familia\u201d, indic\u00f3 un comunicado de la familia difundido a la agencia de noticias AFP. Delon hab\u00eda estado luchando contra su mala salud en los \u00faltimos a\u00f1os.<\/p>\n<p>Nacido en Sceaux, un suburbio al sur de Par\u00eds, Delon tuvo una infancia turbulenta marcada por el divorcio de sus padres y frecuentes expulsiones de la escuela, antes de servir en la Marina francesa en Indochina y luego aceptar trabajos ocasionales en Par\u00eds.<\/p>\n<p>Hizo su primera aparici\u00f3n en el cine en 1957, interpretando a un sicario en el thriller \u201cQuand la femme s&#8217;en m\u00eale\u201d, titulado \u201cEnv\u00eda a una mujer cuando el diablo falla\u201d en ingl\u00e9s.<\/p>\n<p>Este iba a ser el primero de muchos papeles de antih\u00e9roe para Delon, quien luego se convirti\u00f3 en una figura importante del cine europeo en la d\u00e9cada de 1960, trabajando con directores tan elogiados como Ren\u00e9 Cl\u00e9ment (&#171;Plein Soleil&#187;, 1960, titulada &#171;Purple Noon&#187; en los Estados Unidos), Luchino Visconti (&#171;Rocco y sus hermanos&#187;, 1960, y &#171;El gatopardo&#187;, 1963) y Jean-Pierre Melville (&#171;Le Samoura\u00ef&#187;, 1967).<\/p>\n<p>En 1968, Delon se vio envuelto en un esc\u00e1ndalo de sexo, drogas y asesinato que involucraba a la alta sociedad francesa, conocido como el caso Markovic. Fue interrogado, pero nunca acusado.<\/p>\n<p>Tambi\u00e9n apareci\u00f3 en muchas producciones en idioma ingl\u00e9s, incluida la pel\u00edcula antol\u00f3gica \u201cThe Yellow Rolls-Royce\u201d (1964) y los westerns \u201cTexas Across the River\u201d (1966) y \u201cRed Sun\u201d (1971), pero no logr\u00f3 replicar el \u00e9xito que disfrut\u00f3 en el cine europeo.<\/p>\n<p>Delon gan\u00f3 un premio C\u00e9sar, el equivalente franc\u00e9s del Oscar, al mejor actor en 1985 por su papel de alcoh\u00f3lico en \u201cNuestra historia\u201d, de Bertrand Blier. Tambi\u00e9n fue nominado a un Globo de Oro por su interpretaci\u00f3n del apasionado y pobre Tancredi en \u201cEl gatopardo\u201d.<\/p>\n<p>Su estrella se apag\u00f3 en sus \u00faltimos a\u00f1os, pero reapareci\u00f3 en la televisi\u00f3n a principios del siglo, interpretando a detectives veteranos en dos miniseries: \u201cFabio Montale\u201d (2002) y \u201cFrank Riva\u201d (2003-04).<\/p>\n<p>En 2005, Delon fue nombrado Oficial de la Legi\u00f3n de Honor francesa por su contribuci\u00f3n al cine mundial.<\/p>\n<p>Estuvo casado con la actriz y modelo Nathalie Delon de 1964 a 1969 y la pareja tuvo un hijo, Anthony.<\/p>\n<p>Delon tuvo otros tres hijos: un hijo, Christian Boulogne, con la cantante y actriz Nico, y Anouchka Delon y Alain-Fabien Delon con la actriz holandesa Rosalie van Breemen .<\/p>\n<p>El presidente de Francia, Emmanuel Macron, califica al fallecido Alain Delon de &#171;monumento franc\u00e9s&#187;<\/p>\n<p>El presidente de Francia, Emmanuel Macron, rindi\u00f3 homenaje este domingo al fallecido mito del cine Alain Delon, calific\u00e1ndolo de &#171;monumento franc\u00e9s&#187;, mientras llueven los homenajes recordando al actor, productor y guionista franc\u00e9s.<\/p>\n<p>&#171;Se\u00f1or Klein o Rocco, el Leopardo o el Samurai, Alain Delon ha interpretado papeles legendarios y ha hecho so\u00f1ar al mundo. Prestando su rostro inolvidable para sacudir nuestras vidas. Melanc\u00f3lico, popular, reservado, era m\u00e1s que una estrella: un monumento franc\u00e9s&#187;, escribi\u00f3 Macron en X.<\/p>\n<p>M\u00e1s temprano este domingo, la l\u00edder de la extrema derecha francesa Marine Le Pen dijo: &#171;La leyenda se ha ido. Alain Delon nos deja hu\u00e9rfanos de la edad de oro del cine franc\u00e9s que tan bien encarn\u00f3&#187;. Es una peque\u00f1a parte de la Francia que amamos la que se va con \u00e9l\u00bb.<\/p>\n<p>El Ministro de Econom\u00eda, Bruno Le Maire, tambi\u00e9n agradeci\u00f3 a Delon en un comunicado en X&#187;esta inmensa vida de cine&#187;.<\/p>\n<p>Delon falleci\u00f3 a los 88 a\u00f1os, seg\u00fan un comunicado de su familia difundido el domingo a la Agencia France-Presse (AFP).<\/p>\n<p>De\u00a0 y CNN<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8211;Alain Delon, el actor, productor y escritor franc\u00e9s cuya belleza fresca y enigm\u00e1tica lo convirti\u00f3 en un s\u00edmbolo sexual internacional, muri\u00f3 a la edad de 88 a\u00f1os. \u201cFalleci\u00f3 en paz en su casa de Douchy, rodeado de sus tres hijos y su familia\u201d, indic\u00f3 un comunicado de la familia difundido a la agencia de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1451953","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Alain Delon, leyenda del cine franc\u00e9s, muere a los 88 a\u00f1os - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/08\/18\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alain Delon, leyenda del cine franc\u00e9s, muere a los 88 a\u00f1os - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8211;Alain Delon, el actor, productor y escritor franc\u00e9s cuya belleza fresca y enigm\u00e1tica lo convirti\u00f3 en un s\u00edmbolo sexual internacional, muri\u00f3 a la edad de 88 a\u00f1os. \u201cFalleci\u00f3 en paz en su casa de Douchy, rodeado de sus tres hijos y su familia\u201d, indic\u00f3 un comunicado de la familia difundido a la agencia de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/08\/18\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-18T10:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/18\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/18\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Alain Delon, leyenda del cine franc\u00e9s, muere a los 88 a\u00f1os\",\"datePublished\":\"2024-08-18T10:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/18\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax\/\"},\"wordCount\":666,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/18\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/18\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/08\/18\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax\/\",\"name\":\"Alain Delon, leyenda del cine franc\u00e9s, muere a los 88 a\u00f1os - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-08-18T10:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/18\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/18\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/18\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alain Delon, leyenda del cine franc\u00e9s, muere a los 88 a\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alain Delon, leyenda del cine franc\u00e9s, muere a los 88 a\u00f1os - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/08\/18\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Alain Delon, leyenda del cine franc\u00e9s, muere a los 88 a\u00f1os - Noticias","og_description":"(CNN) &#8211;Alain Delon, el actor, productor y escritor franc\u00e9s cuya belleza fresca y enigm\u00e1tica lo convirti\u00f3 en un s\u00edmbolo sexual internacional, muri\u00f3 a la edad de 88 a\u00f1os. \u201cFalleci\u00f3 en paz en su casa de Douchy, rodeado de sus tres hijos y su familia\u201d, indic\u00f3 un comunicado de la familia difundido a la agencia de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/08\/18\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax\/","og_site_name":"Noticias","article_published_time":"2024-08-18T10:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/08\/18\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/08\/18\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax\/"},"author":{"name":"","@id":""},"headline":"Alain Delon, leyenda del cine franc\u00e9s, muere a los 88 a\u00f1os","datePublished":"2024-08-18T10:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/08\/18\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax\/"},"wordCount":666,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/08\/18\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/08\/18\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax\/","url":"https:\/\/noticiasya.com\/2024\/08\/18\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax\/","name":"Alain Delon, leyenda del cine franc\u00e9s, muere a los 88 a\u00f1os - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-08-18T10:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/08\/18\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/08\/18\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/08\/18\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Alain Delon, leyenda del cine franc\u00e9s, muere a los 88 a\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/18\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Alain Delon, leyenda del cine franc\u00e9s, muere a los 88 a\u00f1os","url":"http:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/18\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/18\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-08-18T10:03:46Z","datePublished":"2024-08-18T10:03:46Z","dateModified":"2024-08-18T10:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Alain Delon, leyenda del cine franc\\u00e9s, muere a los 88 a\\u00f1os\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2024\\\/08\\\/18\\\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2024\\\/08\\\/18\\\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-08-18T10:03:46Z\",\"datePublished\":\"2024-08-18T10:03:46Z\",\"dateModified\":\"2024-08-18T10:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1451950,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/18\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-ap\/","url_meta":{"origin":1451953,"position":0},"title":"Alain Delon, leyenda del cine franc\u00e9s, muere a los 88 a\u00f1os","author":"","date":"agosto 18, 2024","format":false,"excerpt":"(CNN) --Alain Delon, el actor, productor y escritor franc\u00e9s cuya belleza fresca y enigm\u00e1tica lo convirti\u00f3 en un s\u00edmbolo sexual internacional, muri\u00f3 a la edad de 88 a\u00f1os.\u201cFalleci\u00f3 en paz en su casa de Douchy, rodeado de sus tres hijos y su familia\u201d, indic\u00f3 un comunicado de la familia difundido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458039,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/01\/30\/muere-78-anios-cantante-britanica-marianne-faithfull-efe\/","url_meta":{"origin":1451953,"position":1},"title":"Muere a los 78 a\u00f1os la cantante brit\u00e1nica Marianne Faithfull","author":"","date":"enero 30, 2025","format":false,"excerpt":"La cantante brit\u00e1nica Marianne Faithfull falleci\u00f3 este jueves a los 78 a\u00f1os, seg\u00fan inform\u00f3 un portavoz de la artista.\u201cCon profunda tristeza anunciamos la muerte de la cantautora y actriz Marianne Faithfull\u201d, anunciaron en un comunicado.Entre los \u00e9xitos de la carrera de Faithfull se encuentra el tema \u201cAs Tears Go By\u201d,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464981,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/07\/30\/la-barredora-grupo-criminal-tabasco-orix\/","url_meta":{"origin":1451953,"position":2},"title":"\u00bfQu\u00e9 es La Barredora, el grupo criminal generador de violencia en Tabasco?","author":"","date":"julio 30, 2025","format":false,"excerpt":"En los \u00faltimos meses, Tabasco \u2015estado del sureste de M\u00e9xico\u2015 ha sido escenario de ataques armados, bloqueos, incendios y otros hechos violentos. Autoridades locales y federales han atribuido esta ola de inseguridad a una organizaci\u00f3n criminal poco conocida hasta hace poco: La Barredora.Este grupo delictivo opera principalmente en esa regi\u00f3n.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466504,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/09\/16\/quien-fue-robert-redford-galan-sundance-trax\/","url_meta":{"origin":1451953,"position":3},"title":"Qui\u00e9n fue Robert Redford, el gal\u00e1n de Hollywood pionero del cine independiente y defensor del medio ambiente","author":"","date":"septiembre 16, 2025","format":false,"excerpt":"Robert Redford, el fallecido actor, director y activista ambiental, protagoniz\u00f3 cl\u00e1sicos de Hollywood, gan\u00f3 un \u00d3scar como director y fund\u00f3 el Festival de Sundance, dejando un legado que transform\u00f3 el cine independiente y la defensa del medio ambiente.Conocido por sus papeles protag\u00f3nicos en \u201cButch Cassidy and the Sundance Kid\u201d y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446013,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/02\/26\/kenneth-mitchell-actor-star-trek-marvel-muere-49-anios-trax\/","url_meta":{"origin":1451953,"position":4},"title":"Kenneth Mitchell, actor de &#171;Star Trek&#187; y &#171;Marvel&#187;, muere a los 49 a\u00f1os","author":"","date":"febrero 26, 2024","format":false,"excerpt":"(CNN) -- Kenneth Mitchell, actor que apareci\u00f3 en las series \"Star Trek: Discovery\" y \"Captain Marvel\" de Marvel, muri\u00f3, anunci\u00f3 su familia en un comunicado compartido en sus redes sociales verificadas este domingo.Ten\u00eda 49 a\u00f1os.\"Con gran pesar anunciamos el fallecimiento de Kenneth Alexander Mitchell, amado padre, esposo, hermano, t\u00edo, hijo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456182,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/11\/30\/silvia-pinal-homenaje-palacio-bellas-artes-mexico-orix\/","url_meta":{"origin":1451953,"position":5},"title":"\u201c\u00a1Adi\u00f3s a la diva!\u201d, M\u00e9xico rinde emotivo homenaje p\u00f3stumo a la actriz Silvia Pinal en el Palacio de Bellas Artes","author":"","date":"noviembre 30, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Tras fallecer el jueves a los 93 a\u00f1os, M\u00e9xico despidi\u00f3 este s\u00e1bado a la actriz Silvia Pinal, considerada la \u00faltima leyenda de la \u00c9poca de Oro del cine mexicano, con un sentido homenaje p\u00f3stumo en el Palacio de Bellas Artes en el centro de la capital mexicana, el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1451953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1451953"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1451953\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1451953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1451953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1451953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}