{"id":1451971,"date":"2024-08-19T03:03:38","date_gmt":"2024-08-19T10:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/08\/19\/un-muerto-y-seis-desaparecidos-tras-hundirse-tornado-yate-de-lujo-frente-a-sicilia-trax\/"},"modified":"2024-08-19T03:03:38","modified_gmt":"2024-08-19T10:03:38","slug":"un-muerto-y-seis-desaparecidos-tras-hundirse-tornado-yate-de-lujo-frente-a-sicilia-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/19\/un-muerto-y-seis-desaparecidos-tras-hundirse-tornado-yate-de-lujo-frente-a-sicilia-trax\/","title":{"rendered":"Un muerto y seis desaparecidos tras hundirse un tornado en un yate de lujo frente a Sicilia"},"content":{"rendered":"<p>(CNN) &#8212; Un cuerpo fue recuperado del casco de un yate de lujo que se hundi\u00f3 frente a las costas de Sicilia, seg\u00fan las autoridades italianas.<\/p>\n<p>Seis personas siguen desaparecidas despu\u00e9s de que un tornado impactara el barco alrededor de las 5 de la ma\u00f1ana del lunes, seg\u00fan un portavoz de la Guardia Costera italiana. El yate estaba anclado a media milla del puerto de Porticello, en la isla mediterr\u00e1nea.<\/p>\n<p>Quince personas fueron rescatadas del lugar del accidente y un ni\u00f1o fue trasladado en helic\u00f3ptero al hospital infantil de Palermo. El capit\u00e1n se encuentra entre los supervivientes, seg\u00fan el portavoz de la Guardia Costera italiana.<\/p>\n<p>El yate de 56 metros llamado \u201cBayesian\u201d, que navega bajo bandera brit\u00e1nica, ten\u00eda en su mayor\u00eda pasajeros y tripulaci\u00f3n brit\u00e1nicos, adem\u00e1s de dos anglo-franceses, un neozeland\u00e9s, un irland\u00e9s y un esrilanqu\u00e9s, dijo el portavoz a CNN.<\/p>\n<p>Los bomberos italianos informaron de que sus buzos hab\u00edan llegado al casco del yate, que se encontraba a 49 metros por debajo del nivel del mar, seg\u00fan un comunicado de prensa. La brigada tambi\u00e9n envi\u00f3 helic\u00f3pteros para reforzar la operaci\u00f3n de b\u00fasqueda.<\/p>\n<p>Esta es una historia en desarrollo y se actualizar\u00e1.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Un cuerpo fue recuperado del casco de un yate de lujo que se hundi\u00f3 frente a las costas de Sicilia, seg\u00fan las autoridades italianas. Seis personas siguen desaparecidas despu\u00e9s de que un tornado impactara el barco alrededor de las 5 de la ma\u00f1ana del lunes, seg\u00fan un portavoz de la Guardia Costera italiana. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1451971","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un muerto y seis desaparecidos tras hundirse un tornado en un yate de lujo frente a Sicilia - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/08\/19\/un-muerto-y-seis-desaparecidos-tras-hundirse-tornado-yate-de-lujo-frente-a-sicilia-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un muerto y seis desaparecidos tras hundirse un tornado en un yate de lujo frente a Sicilia - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Un cuerpo fue recuperado del casco de un yate de lujo que se hundi\u00f3 frente a las costas de Sicilia, seg\u00fan las autoridades italianas. Seis personas siguen desaparecidas despu\u00e9s de que un tornado impactara el barco alrededor de las 5 de la ma\u00f1ana del lunes, seg\u00fan un portavoz de la Guardia Costera italiana. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/08\/19\/un-muerto-y-seis-desaparecidos-tras-hundirse-tornado-yate-de-lujo-frente-a-sicilia-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-19T10:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/19\/un-muerto-y-seis-desaparecidos-tras-hundirse-tornado-yate-de-lujo-frente-a-sicilia-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/19\/un-muerto-y-seis-desaparecidos-tras-hundirse-tornado-yate-de-lujo-frente-a-sicilia-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un muerto y seis desaparecidos tras hundirse un tornado en un yate de lujo frente a Sicilia\",\"datePublished\":\"2024-08-19T10:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/19\/un-muerto-y-seis-desaparecidos-tras-hundirse-tornado-yate-de-lujo-frente-a-sicilia-trax\/\"},\"wordCount\":246,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/19\/un-muerto-y-seis-desaparecidos-tras-hundirse-tornado-yate-de-lujo-frente-a-sicilia-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/19\/un-muerto-y-seis-desaparecidos-tras-hundirse-tornado-yate-de-lujo-frente-a-sicilia-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/08\/19\/un-muerto-y-seis-desaparecidos-tras-hundirse-tornado-yate-de-lujo-frente-a-sicilia-trax\/\",\"name\":\"Un muerto y seis desaparecidos tras hundirse un tornado en un yate de lujo frente a Sicilia - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-08-19T10:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/19\/un-muerto-y-seis-desaparecidos-tras-hundirse-tornado-yate-de-lujo-frente-a-sicilia-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/19\/un-muerto-y-seis-desaparecidos-tras-hundirse-tornado-yate-de-lujo-frente-a-sicilia-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/19\/un-muerto-y-seis-desaparecidos-tras-hundirse-tornado-yate-de-lujo-frente-a-sicilia-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un muerto y seis desaparecidos tras hundirse un tornado en un yate de lujo frente a Sicilia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un muerto y seis desaparecidos tras hundirse un tornado en un yate de lujo frente a Sicilia - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/08\/19\/un-muerto-y-seis-desaparecidos-tras-hundirse-tornado-yate-de-lujo-frente-a-sicilia-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Un muerto y seis desaparecidos tras hundirse un tornado en un yate de lujo frente a Sicilia - Noticias","og_description":"(CNN) &#8212; Un cuerpo fue recuperado del casco de un yate de lujo que se hundi\u00f3 frente a las costas de Sicilia, seg\u00fan las autoridades italianas. Seis personas siguen desaparecidas despu\u00e9s de que un tornado impactara el barco alrededor de las 5 de la ma\u00f1ana del lunes, seg\u00fan un portavoz de la Guardia Costera italiana. [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/08\/19\/un-muerto-y-seis-desaparecidos-tras-hundirse-tornado-yate-de-lujo-frente-a-sicilia-trax\/","og_site_name":"Noticias","article_published_time":"2024-08-19T10:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/08\/19\/un-muerto-y-seis-desaparecidos-tras-hundirse-tornado-yate-de-lujo-frente-a-sicilia-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/08\/19\/un-muerto-y-seis-desaparecidos-tras-hundirse-tornado-yate-de-lujo-frente-a-sicilia-trax\/"},"author":{"name":"","@id":""},"headline":"Un muerto y seis desaparecidos tras hundirse un tornado en un yate de lujo frente a Sicilia","datePublished":"2024-08-19T10:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/08\/19\/un-muerto-y-seis-desaparecidos-tras-hundirse-tornado-yate-de-lujo-frente-a-sicilia-trax\/"},"wordCount":246,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/08\/19\/un-muerto-y-seis-desaparecidos-tras-hundirse-tornado-yate-de-lujo-frente-a-sicilia-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/08\/19\/un-muerto-y-seis-desaparecidos-tras-hundirse-tornado-yate-de-lujo-frente-a-sicilia-trax\/","url":"https:\/\/noticiasya.com\/2024\/08\/19\/un-muerto-y-seis-desaparecidos-tras-hundirse-tornado-yate-de-lujo-frente-a-sicilia-trax\/","name":"Un muerto y seis desaparecidos tras hundirse un tornado en un yate de lujo frente a Sicilia - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-08-19T10:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/08\/19\/un-muerto-y-seis-desaparecidos-tras-hundirse-tornado-yate-de-lujo-frente-a-sicilia-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/08\/19\/un-muerto-y-seis-desaparecidos-tras-hundirse-tornado-yate-de-lujo-frente-a-sicilia-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/08\/19\/un-muerto-y-seis-desaparecidos-tras-hundirse-tornado-yate-de-lujo-frente-a-sicilia-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un muerto y seis desaparecidos tras hundirse un tornado en un yate de lujo frente a Sicilia"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/19\/un-muerto-y-seis-desaparecidos-tras-hundirse-tornado-yate-de-lujo-frente-a-sicilia-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un muerto y seis desaparecidos tras hundirse un tornado en un yate de lujo frente a Sicilia","url":"http:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/19\/un-muerto-y-seis-desaparecidos-tras-hundirse-tornado-yate-de-lujo-frente-a-sicilia-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/19\/un-muerto-y-seis-desaparecidos-tras-hundirse-tornado-yate-de-lujo-frente-a-sicilia-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-08-19T10:03:38Z","datePublished":"2024-08-19T10:03:38Z","dateModified":"2024-08-19T10:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un muerto y seis desaparecidos tras hundirse un tornado en un yate de lujo frente a Sicilia\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2024\\\/08\\\/19\\\/un-muerto-y-seis-desaparecidos-tras-hundirse-tornado-yate-de-lujo-frente-a-sicilia-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2024\\\/08\\\/19\\\/un-muerto-y-seis-desaparecidos-tras-hundirse-tornado-yate-de-lujo-frente-a-sicilia-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-08-19T10:03:38Z\",\"datePublished\":\"2024-08-19T10:03:38Z\",\"dateModified\":\"2024-08-19T10:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1452000,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/20\/que-paso-yate-lujo-naufrago-sicilia-tornado-trax\/","url_meta":{"origin":1451971,"position":0},"title":"\u00bfQu\u00e9 pas\u00f3 con el yate de lujo que naufrag\u00f3 en Sicilia tras chocar con un tornado? Esto sabemos","author":"","date":"agosto 20, 2024","format":false,"excerpt":"(CNN) --\u00a0Los equipos de emergencia del sur de Italia siguen buscando a seis personas desaparecidas a causa de un tornado que hundi\u00f3 un yate de lujo a primera hora del lunes, lo que provoc\u00f3 una operaci\u00f3n a\u00e9rea y naval frente a la costa de Sicilia.Quince personas fueron rescatadas de entre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451978,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/19\/quien-es-mike-lynch-empresario-tecnologico-naufragio-yate-lujo-sicilia-trax\/","url_meta":{"origin":1451971,"position":1},"title":"\u00bfQui\u00e9n es Mike Lynch, el empresario tecnol\u00f3gico que desapareci\u00f3 tras naufragio de yate de lujo frente a Sicilia?","author":"","date":"agosto 19, 2024","format":false,"excerpt":"(CNN) -- Mike Lynch, inversor brit\u00e1nico del sector tecnol\u00f3gico de 59 a\u00f1os de edad, se encuentra entre las personas desaparecidas despu\u00e9s de que un tornado golpeara el yate de lujo en el que viajaba y lo hundiera frente a la costa de Sicilia, Italia, a primera hora de este lunes,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452037,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/21\/localizan-cuatro-cuerpos-busqueda-desaparecidos-superyate-bayesian-hundido-trax\/","url_meta":{"origin":1451971,"position":2},"title":"Localizan cuatro cuerpos en la b\u00fasqueda de los desaparecidos del superyate Bayesian hundido en Sicilia","author":"","date":"agosto 21, 2024","format":false,"excerpt":"Porticello, Italia (CNN) -- Cuatro cuerpos fueron encontrados por buzos el mi\u00e9rcoles mientras los rescatistas buscan a los desaparecidos del superyate \"Bayesian\", que se hundi\u00f3 frente a la costa de Sicilia a principios de esta semana.Un equipo de CNN sobre el terreno vio el mi\u00e9rcoles a las autoridades italianas trasladar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452119,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/24\/italia-investigacion-homicidio-involuntario-hundimiento-superyate-trax\/","url_meta":{"origin":1451971,"position":3},"title":"Las autoridades italianas abren una investigaci\u00f3n por homicidio involuntario en el caso del hundimiento del superyate","author":"","date":"agosto 24, 2024","format":false,"excerpt":"(CNN) -- Las autoridades italianas han abierto una investigaci\u00f3n por homicidio involuntario en el hundimiento de un superyate, en el que murieron el magnate tecnol\u00f3gico brit\u00e1nico Mike Lynch y otras seis personas en la costa de Sicilia a principios de esta semana.Al anunciar la investigaci\u00f3n, el fiscal Ambrogio Cartosio dijo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452910,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/09\/21\/superyate-hundido-cajas-fuertes-hermeticas-inteligencia-sensibles-trax\/","url_meta":{"origin":1451971,"position":4},"title":"Sospechan que el superyate hundido en agosto conten\u00eda cajas fuertes herm\u00e9ticas con datos de inteligencia sensibles","author":"","date":"septiembre 21, 2024","format":false,"excerpt":"(CNN) -- Buzos especializados que inspeccionan los restos del superyate de US$ 40 millones que se hundi\u00f3 frente a Sicilia en agosto y en el que murieron ahogadas ocho personas \u2014incluido el magnate tecnol\u00f3gico brit\u00e1nico Mike Lynch\u2014 han solicitado mayor seguridad en el barco, debido a que les preocupa que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452070,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/22\/recuperan-quinto-cuerpo-superyate-hundido-mientras-investigadores-causa-del-naufragio-trax\/","url_meta":{"origin":1451971,"position":5},"title":"Recuperan quinto cuerpo de superyate hundido mientras autoridades investigan causa del naufragio","author":"","date":"agosto 22, 2024","format":false,"excerpt":"(CNN) --\u00a0 Un quinto cuerpo ha sido llevado a la costa mientras las autoridades italianas buscan a la \u00faltima persona desaparecida del superyate \u201cBayesian\u201d que se hundi\u00f3 frente a la costa de Sicilia a principios de semana.Un equipo de CNN en el terreno vio a las autoridades italianas trasladar el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1451971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1451971"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1451971\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1451971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1451971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1451971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}