{"id":1451998,"date":"2024-08-20T09:03:57","date_gmt":"2024-08-20T16:03:57","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/08\/20\/muere-117-anos-persona-mas-anciana-maria-branyas-morera-trax\/"},"modified":"2024-08-20T09:03:57","modified_gmt":"2024-08-20T16:03:57","slug":"muere-117-anos-persona-mas-anciana-maria-branyas-morera-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/20\/muere-117-anos-persona-mas-anciana-maria-branyas-morera-trax\/","title":{"rendered":"Muere a los 117 a\u00f1os Mar\u00eda Branyas Morera, la persona m\u00e1s longeva del mundo"},"content":{"rendered":"<p>(CNN) &#8212; La persona m\u00e1s longeva del mundo, Mar\u00eda Branyas Morera, muri\u00f3 a los 117 a\u00f1os, seg\u00fan anunci\u00f3 su familia en redes sociales.<\/p>\n<p>Guinness World Records tambi\u00e9n emiti\u00f3 un comunicado confirmando su muerte a la edad de 117 a\u00f1os y 168 d\u00edas, lo que la convierte en la octava persona que alcanz\u00f3 la mayor edad verificada de la historia.<\/p>\n<p>&#171;Mar\u00eda falleci\u00f3 en paz en la residencia de ancianos de Catalu\u00f1a, Espa\u00f1a, donde resid\u00eda desde hace dos d\u00e9cadas&#187;, rezaba el comunicado de Guinness World Records, que a\u00f1ad\u00eda que muri\u00f3 el lunes.<\/p>\n<p>El martes, la familia de Morera public\u00f3 un post en su cuenta X anunciando su muerte.<\/p>\n<p>&#171;Se ha ido como ella quer\u00eda: durmiendo, en paz y sin dolor&#187;, rezaba el post.<\/p>\n<p>Su familia a\u00f1adi\u00f3 que Morera les dijo poco antes de su muerte: &#171;No s\u00e9 cu\u00e1ndo, pero muy pronto este largo viaje llegar\u00e1 a su fin. La muerte me encontrar\u00e1 agotada de haber vivido tanto, pero quiero que me encuentre sonriente, libre y satisfecha&#187;.<\/p>\n<p>Morera fue nombrada la persona viva m\u00e1s longeva del mundo por el libro de los r\u00e9cords en enero de 2023, tras la muerte de la monja francesa Andr\u00e9 a los 118 a\u00f1os.<\/p>\n<p>Ella declar\u00f3 a Guinness World Records que hab\u00eda vivido una vida tan larga gracias al &#171;orden, la tranquilidad, la buena conexi\u00f3n con la familia y los amigos, el contacto con la naturaleza, la estabilidad emocional, sin preocupaciones, sin remordimientos, con mucha positividad y alej\u00e1ndose de la gente t\u00f3xica&#187;.<\/p>\n<p>Una foto de Maria Branyas Morera de joven. (Cr\u00e9dito: Supercentenaria\/Twitter)<\/p>\n<p>&#171;Creo que la longevidad tambi\u00e9n tiene que ver con la suerte. Suerte y buena gen\u00e9tica&#187;, a\u00f1adi\u00f3.<\/p>\n<p>Naci\u00f3 el 4 de marzo de 1907, menos de cuatro a\u00f1os despu\u00e9s de que los hermanos Wright lanzaran el primer vuelo propulsado y dos a\u00f1os antes de que comenzara la construcci\u00f3n del malogrado Titanic.<\/p>\n<p>Morera naci\u00f3 un a\u00f1o despu\u00e9s de que sus padres emigraran de Espa\u00f1a a Estados Unidos. Ocho a\u00f1os m\u00e1s tarde, la familia se traslad\u00f3 de nuevo, llegando a Barcelona durante la Primera Guerra Mundial. La vida de Morera tambi\u00e9n atraves\u00f3 la Guerra Civil espa\u00f1ola y la Segunda Guerra Mundial.<\/p>\n<p>Pas\u00f3 las \u00faltimas d\u00e9cadas de su vida en una residencia de ancianos en Catalu\u00f1a, donde, a pesar de su avanzada edad, Morera utiliz\u00f3 X -con un poco de ayuda de su hija- para comunicarse con sus miles de seguidores.<\/p>\n<p>&#171;Soy vieja, muy vieja, pero no idiota&#187;, dice su biograf\u00eda en la red social.<\/p>\n<p>Se cree que Morera es una de las personas de mayor edad que se han recuperado del covid-19, luego de dar positivo en la prueba del virus en mayo de 2020.<\/p>\n<p>Seg\u00fan el Grupo de Investigaci\u00f3n Gerontol\u00f3gica, una organizaci\u00f3n cient\u00edfica sin \u00e1nimo de lucro que valida las edades de las personas de al menos 110 a\u00f1os, la persona viva de m\u00e1s edad es actualmente una japonesa de 116 a\u00f1os llamada Tomiko Itooka.<\/p>\n<p>El t\u00edtulo de la persona m\u00e1s longeva jam\u00e1s registrada pertenece a Jeanne Louise Calment. Nacida el 21 de febrero de 1875, vivi\u00f3 122 a\u00f1os y 164 d\u00edas, seg\u00fan Guinness World Records.<\/p>\n<p>John Murphy, Lianne Kolirin y Arnaud Siad, de CNN, han contribuido a este art\u00edculo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; La persona m\u00e1s longeva del mundo, Mar\u00eda Branyas Morera, muri\u00f3 a los 117 a\u00f1os, seg\u00fan anunci\u00f3 su familia en redes sociales. Guinness World Records tambi\u00e9n emiti\u00f3 un comunicado confirmando su muerte a la edad de 117 a\u00f1os y 168 d\u00edas, lo que la convierte en la octava persona que alcanz\u00f3 la mayor edad [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1451998","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Muere a los 117 a\u00f1os Mar\u00eda Branyas Morera, la persona m\u00e1s longeva del mundo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/08\/20\/muere-117-anos-persona-mas-anciana-maria-branyas-morera-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Muere a los 117 a\u00f1os Mar\u00eda Branyas Morera, la persona m\u00e1s longeva del mundo - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; La persona m\u00e1s longeva del mundo, Mar\u00eda Branyas Morera, muri\u00f3 a los 117 a\u00f1os, seg\u00fan anunci\u00f3 su familia en redes sociales. Guinness World Records tambi\u00e9n emiti\u00f3 un comunicado confirmando su muerte a la edad de 117 a\u00f1os y 168 d\u00edas, lo que la convierte en la octava persona que alcanz\u00f3 la mayor edad [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/08\/20\/muere-117-anos-persona-mas-anciana-maria-branyas-morera-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-20T16:03:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/20\/muere-117-anos-persona-mas-anciana-maria-branyas-morera-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/20\/muere-117-anos-persona-mas-anciana-maria-branyas-morera-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Muere a los 117 a\u00f1os Mar\u00eda Branyas Morera, la persona m\u00e1s longeva del mundo\",\"datePublished\":\"2024-08-20T16:03:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/20\/muere-117-anos-persona-mas-anciana-maria-branyas-morera-trax\/\"},\"wordCount\":598,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/20\/muere-117-anos-persona-mas-anciana-maria-branyas-morera-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/20\/muere-117-anos-persona-mas-anciana-maria-branyas-morera-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/08\/20\/muere-117-anos-persona-mas-anciana-maria-branyas-morera-trax\/\",\"name\":\"Muere a los 117 a\u00f1os Mar\u00eda Branyas Morera, la persona m\u00e1s longeva del mundo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-08-20T16:03:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/20\/muere-117-anos-persona-mas-anciana-maria-branyas-morera-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/20\/muere-117-anos-persona-mas-anciana-maria-branyas-morera-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/20\/muere-117-anos-persona-mas-anciana-maria-branyas-morera-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Muere a los 117 a\u00f1os Mar\u00eda Branyas Morera, la persona m\u00e1s longeva del mundo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Muere a los 117 a\u00f1os Mar\u00eda Branyas Morera, la persona m\u00e1s longeva del mundo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/08\/20\/muere-117-anos-persona-mas-anciana-maria-branyas-morera-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Muere a los 117 a\u00f1os Mar\u00eda Branyas Morera, la persona m\u00e1s longeva del mundo - Noticias","og_description":"(CNN) &#8212; La persona m\u00e1s longeva del mundo, Mar\u00eda Branyas Morera, muri\u00f3 a los 117 a\u00f1os, seg\u00fan anunci\u00f3 su familia en redes sociales. Guinness World Records tambi\u00e9n emiti\u00f3 un comunicado confirmando su muerte a la edad de 117 a\u00f1os y 168 d\u00edas, lo que la convierte en la octava persona que alcanz\u00f3 la mayor edad [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/08\/20\/muere-117-anos-persona-mas-anciana-maria-branyas-morera-trax\/","og_site_name":"Noticias","article_published_time":"2024-08-20T16:03:57+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/08\/20\/muere-117-anos-persona-mas-anciana-maria-branyas-morera-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/08\/20\/muere-117-anos-persona-mas-anciana-maria-branyas-morera-trax\/"},"author":{"name":"","@id":""},"headline":"Muere a los 117 a\u00f1os Mar\u00eda Branyas Morera, la persona m\u00e1s longeva del mundo","datePublished":"2024-08-20T16:03:57+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/08\/20\/muere-117-anos-persona-mas-anciana-maria-branyas-morera-trax\/"},"wordCount":598,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/08\/20\/muere-117-anos-persona-mas-anciana-maria-branyas-morera-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/08\/20\/muere-117-anos-persona-mas-anciana-maria-branyas-morera-trax\/","url":"https:\/\/noticiasya.com\/2024\/08\/20\/muere-117-anos-persona-mas-anciana-maria-branyas-morera-trax\/","name":"Muere a los 117 a\u00f1os Mar\u00eda Branyas Morera, la persona m\u00e1s longeva del mundo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-08-20T16:03:57+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/08\/20\/muere-117-anos-persona-mas-anciana-maria-branyas-morera-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/08\/20\/muere-117-anos-persona-mas-anciana-maria-branyas-morera-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/08\/20\/muere-117-anos-persona-mas-anciana-maria-branyas-morera-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Muere a los 117 a\u00f1os Mar\u00eda Branyas Morera, la persona m\u00e1s longeva del mundo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/20\/muere-117-anos-persona-mas-anciana-maria-branyas-morera-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Muere a los 117 a\u00f1os Mar\u00eda Branyas Morera, la persona m\u00e1s longeva del mundo","url":"http:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/20\/muere-117-anos-persona-mas-anciana-maria-branyas-morera-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/20\/muere-117-anos-persona-mas-anciana-maria-branyas-morera-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-08-20T16:03:57Z","datePublished":"2024-08-20T16:03:57Z","dateModified":"2024-08-20T16:03:57Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Muere a los 117 a\\u00f1os Mar\\u00eda Branyas Morera, la persona m\\u00e1s longeva del mundo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2024\\\/08\\\/20\\\/muere-117-anos-persona-mas-anciana-maria-branyas-morera-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2024\\\/08\\\/20\\\/muere-117-anos-persona-mas-anciana-maria-branyas-morera-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-08-20T16:03:57Z\",\"datePublished\":\"2024-08-20T16:03:57Z\",\"dateModified\":\"2024-08-20T16:03:57Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1452189,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/26\/hombre-mas-longevo-mundo-titanic-cumple-112-anos-trax\/","url_meta":{"origin":1451998,"position":0},"title":"El hombre m\u00e1s longevo del mundo, nacido el mismo a\u00f1o del hundimiento del Titanic, cumple 112 a\u00f1os","author":"","date":"agosto 26, 2024","format":false,"excerpt":"(CNN) -- John Alfred Tinniswood naci\u00f3 el mismo a\u00f1o en que se hundi\u00f3 el Titanic y en que Nuevo M\u00e9xico y Arizona se convirtieron en estados de Estados Unidos.Ahora, el hombre vivo m\u00e1s longevo del mundo, nacido el 26 de agosto de 1912, celebra su 112 cumplea\u00f1os.Tinniswood celebra con amigos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469039,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/12\/06\/opositor-venezolano-alfredo-diaz-muere-prision-orix\/","url_meta":{"origin":1451998,"position":1},"title":"El exgobernador y opositor venezolano Alfredo D\u00edaz muere en prisi\u00f3n tras estar detenido durante un a\u00f1o","author":"","date":"diciembre 6, 2025","format":false,"excerpt":"Alfredo D\u00edaz, dirigente pol\u00edtico opositor de Venezuela, muri\u00f3 en prisi\u00f3n tras estar detenido durante un a\u00f1o, dijo a CNN este s\u00e1bado Alejandra Mar\u00eda D\u00edaz, su hija.El exgobernador del estado Nueva Esparta, de 56 a\u00f1os, estaba privado de su libertad desde noviembre de 2024. Se encontraba en la sede del Servicio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465014,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/07\/31\/revelan-causa-muerte-hulk-hogan-trax\/","url_meta":{"origin":1451998,"position":2},"title":"Revelan la causa de muerte de Hulk Hogan","author":"","date":"julio 31, 2025","format":false,"excerpt":"El luchador profesional Hulk Hogan muri\u00f3 de un ataque al coraz\u00f3n, seg\u00fan las autoridades.La causa oficial de muerte de Hogan se cita como \u201cinfarto agudo de miocardio\u201d, que en t\u00e9rminos sencillos significa un ataque al coraz\u00f3n, de acuerdo con un informe de aprobaci\u00f3n de cremaci\u00f3n de la oficina del m\u00e9dico\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458324,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/02\/06\/irv-gotti-def-jam-muerte-trax\/","url_meta":{"origin":1451998,"position":3},"title":"Muere a los 54 a\u00f1os el productor y ejecutivo musical Irv Gotti, que ayud\u00f3 a lanzar las carreras de estrellas del rap","author":"","date":"febrero 6, 2025","format":false,"excerpt":"El famoso ejecutivo musical Irv Gotti, fundador del sello de hip-hop Murder Inc., del que salieron superestrellas como Ashanti y Ja Rule, falleci\u00f3 a los 54 a\u00f1os, seg\u00fan inform\u00f3 la distribuidora Def Jam.\u201cDef Jam Recordings y la extensa familia Def Jam de artistas, ejecutivos y empleados est\u00e1n profundamente entristecidos por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1411514,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2022\/07\/07\/shuan-shuan-fallece-a-los-35-anos-la-panda-mas-longeva-de-mexico\/","url_meta":{"origin":1451998,"position":4},"title":"Shuan Shuan fallece a los 35 a\u00f1os, la panda m\u00e1s longeva de M\u00e9xico","author":"agomez","date":"julio 7, 2022","format":false,"excerpt":"Shuan super\u00f3 la expectativa de vida de su especie cuando est\u00e1n en su h\u00e1bitat natural, que es de 15 a\u00f1os.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455790,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/11\/13\/muere-futbolista-ecuatoriano-marco-angulo-accidente-automovilistico-trax\/","url_meta":{"origin":1451998,"position":5},"title":"Muere el futbolista ecuatoriano Marco Angulo a los 22 a\u00f1os tras un accidente automovil\u00edstico","author":"agomez","date":"noviembre 13, 2024","format":false,"excerpt":"(CNN) -- El futbolista ecuatoriano Marco Angulo muri\u00f3 a los 22 a\u00f1os, inform\u00f3 la Federaci\u00f3n Ecuatoriana de F\u00fatbol en un comunicado.\u201cLa Federaci\u00f3n Ecuatoriana de F\u00fatbol expresa su m\u00e1s sentido p\u00e9same por el fallecimiento de Marco Angulo, quien con su talento y dedicaci\u00f3n defendi\u00f3 los colores de nuestro pa\u00eds en cada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1451998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1451998"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1451998\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1451998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1451998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1451998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}