{"id":1452052,"date":"2024-08-21T16:03:39","date_gmt":"2024-08-21T23:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/08\/21\/flamencos-mismo-sexo-empollan-huevo-reino-unido-animales-trax\/"},"modified":"2024-08-21T16:03:39","modified_gmt":"2024-08-21T23:03:39","slug":"flamencos-mismo-sexo-empollan-huevo-reino-unido-animales-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/21\/flamencos-mismo-sexo-empollan-huevo-reino-unido-animales-trax\/","title":{"rendered":"Una pareja de flamencos del mismo sexo logra empollar un huevo en un zool\u00f3gico del Reino Unido"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Siete polluelos de flamencos chilenos blancos est\u00e1n en exhibici\u00f3n en un zool\u00f3gico en el suroeste de Inglaterra por primera vez desde 2018, y uno es particularmente notable por la forma en que naci\u00f3. Dos flamencos machos llamados Arthur y Curtis lograron empollar un huevo juntos, una novedad para el zool\u00f3gico de Paignton.<\/p>\n<p>El zool\u00f3gico ha tenido varias parejas de machos durante las temporadas de cr\u00eda anteriores, por lo que la pareja del mismo sexo no es un giro inesperado de los acontecimientos, dijo Pete Smallbones, el curador de aves del zool\u00f3gico. Pero el zool\u00f3gico no est\u00e1 seguro exactamente de c\u00f3mo la pareja adquiri\u00f3 el huevo.<\/p>\n<p>&#171;Es probable que este huevo estuviera disponible, sin protecci\u00f3n, como si lo hubieran dejado (en un nido) y luego aprovecharon la oportunidad&#187;, dijo Smallbones. &#171;Como departamento de aves, somos conscientes de que es conocido que los flamencos, ping\u00fcinos y otras especies tienen parejas del mismo sexo. Por lo tanto, no fue una sorpresa. Supongo que fue una ligera sorpresa, simplemente porque no era exactamente lo esperado (la pareja de macho y hembra)&#187;.<\/p>\n<p>Los flamencos rosados son m\u00e1s agresivos que sus contrapartes m\u00e1s p\u00e1lidos, seg\u00fan un nuevo estudio<\/p>\n<p>Durante la temporada de cr\u00eda, las parejas suelen pasar m\u00e1s tiempo juntas y se siguen unas a otras por el recinto, pero el emparejamiento se confirma cuando dos p\u00e1jaros eligen un nido para compartir, donde se turnan para sentarse en el mont\u00edculo de barro con o sin un huevo. Sin embargo, este a\u00f1o una pareja del mismo sexo tuvo un huevo para sentarse. Aunque es notablemente raro que dos p\u00e1jaros machos empollen un huevo juntos, ha sucedido m\u00faltiples veces en otros zool\u00f3gicos.<\/p>\n<p>La exitosa eclosi\u00f3n entre dos machos resalta los instintos parentales innatos y la flexibilidad de las aves sociales, dicen los expertos. Tambi\u00e9n subraya la necesidad de hablar sobre los flamencos chilenos, casi amenazados, cuyas poblaciones disminuyen en la naturaleza y en su hogar nativo de Sudam\u00e9rica, de acuerdo con el comunicado de prensa del zool\u00f3gico. Y los expertos tienen algunas teor\u00edas sobre c\u00f3mo y por qu\u00e9 se produjo este emparejamiento.<\/p>\n<p>El zool\u00f3gico ha tenido varias parejas formadas exclusivamente por machos durante las pasadas temporadas de cr\u00eda. Sin embargo, este a\u00f1o una pareja del mismo sexo ten\u00eda un huevo para empollar. Wild Planet Trust<\/p>\n<p>P\u00e1jaros del mismo plumaje<\/p>\n<p>Los flamencos chilenos pueden ser muy quisquillosos a la hora de reproducirse. En la naturaleza, las observaciones han demostrado que la especie evita reproducirse hasta nueve a\u00f1os, ya que las aves esperan que el clima y las condiciones ambientales sean las adecuadas, dijo Smallbones. Pero incluso en el zool\u00f3gico, que les proporciona sus nidos de barro preferidos, a menudo no se reproducen todos los a\u00f1os.<\/p>\n<p>Un a\u00f1o en el zool\u00f3gico de Paignton, los huevos de flamencos puestos varias semanas demasiado tarde tuvieron que ser retirados, ya que los polluelos probablemente no habr\u00edan prosperado en las condiciones clim\u00e1ticas m\u00e1s fr\u00edas, dijo Smallbones. Las preocupaciones por la influenza aviar interrumpieron otra temporada de reproducci\u00f3n previa, ya que las aves fueron retiradas de su recinto como medida de seguridad, agreg\u00f3.<\/p>\n<p>El polluelo de Curtis y Arthur, que a\u00fan no tiene nombre, tiene casi un mes y parece estar prosperando, dijo Smallbones. &#171;Obviamente, los padres est\u00e1n haciendo un gran trabajo&#187;. Se ha observado al polluelo explorando la exhibici\u00f3n con otros de aproximadamente la misma edad. Sin embargo, de todos modos regresar\u00e1 con Curtis y Arthur para alimentarse.<\/p>\n<p>Aunque los dos machos son la \u00fanica pareja del mismo sexo de la que el zool\u00f3gico tiene conocimiento en esta temporada de reproducci\u00f3n, podr\u00eda potencialmente dar la bienvenida a m\u00e1s polluelos este a\u00f1o, ya que varios huevos a\u00fan est\u00e1n incubando, seg\u00fan el comunicado de prensa.<\/p>\n<p>El polluelo de Curtis y Arthur, que a\u00fan no tiene nombre, tiene casi un mes y parece estar prosperando, seg\u00fan el zool\u00f3gico de Paignton. Wild Planet Trust<\/p>\n<p>Necesidad de anidar<\/p>\n<p>En otros zool\u00f3gicos se han observado parejas del mismo sexo entre ciertas especies de aves. Incluso hay varias historias de \u00e9xito al empollar huevos, como en 2007, cuando el Wildfowl &#038; Wetlands Trust de Gloucestershire confi\u00f3 un huevo abandonado a dos flamencos machos; y en 2018, cuando dos ping\u00fcinos machos del Acuario Sea Life de Sydney tambi\u00e9n se convirtieron en padres adoptivos de un polluelo.<\/p>\n<p>\u201cEstar en una pareja del mismo sexo es algo relativamente com\u00fan en los flamencos cautivos, debido al peque\u00f1o tama\u00f1o de las bandadas\u201d, dijo Paul Rose, bi\u00f3logo y profesor titular de comportamiento animal en la Universidad de Exeter. \u201cEn realidad, empollar un huevo es m\u00e1s inusual. Estos dos flamencos machos probablemente estaban muy interesados \u200b\u200ben anidar, pero no pod\u00edan atraer a una pareja hembra, por lo que el mismo impulso de anidar los uni\u00f3\u201d.<\/p>\n<p>A veces, se ha observado que parejas de flamencos del mismo sexo perturban otros nidos (como los flamencos chilenos anidan en bandada) en un intento de obtener sus propios huevos, dijo Rose.<\/p>\n<p>En la naturaleza, las bandadas de flamencos chilenos pueden llegar a cientos de ejemplares durante la temporada de cr\u00eda, de acuerdo con Rose. El zool\u00f3gico de Paignton tiene actualmente 26 flamencos hembras y 25 machos en la exhibici\u00f3n, lo que sugiere que hay suficientes hembras para que los machos se apareen, dijo Smallbones. Aunque se necesita m\u00e1s investigaci\u00f3n para determinar por qu\u00e9 ocurren los emparejamientos de aves del mismo sexo, es posible que Arthur y Curtis encontraran un huevo de una pareja de macho y hembra que no era cuidado y aprovecharan la oportunidad de cuidarlo; o se apoderaran del nido de otra pareja, dijo Smallbones.<\/p>\n<p>Se necesitan dos<\/p>\n<p>Los flamencos a menudo tienen asociaciones no reproductivas que consisten en asociaciones del mismo sexo, seg\u00fan un estudio de junio de 2020 dirigido por Rose. Las aves tienden a ser &#171;muy particulares en cuanto a con qui\u00e9n les gusta pasar el tiempo, y buscar\u00e1n activamente algunas aves en una bandada y evitar\u00e1n otras&#187;, agreg\u00f3 Rose en un correo electr\u00f3nico. \u201cNo me sorprende que dos flamencos machos logren criar un polluelo por su flexibilidad social, pero no creo que hubiera sido su primera opci\u00f3n de pareja reproductiva\u201d.<\/p>\n<p>Si bien se registran m\u00e1s parejas de aves del mismo sexo en cautiverio que en la naturaleza, de acuerdo con Rose, varias especies de albatros (tipos de aves marinas) tienen m\u00e1s hembras que machos en la poblaci\u00f3n y, ocasionalmente, las hembras se emparejan para criar un huevo; o ambas ponen huevos y los cuidan juntas, dijo Kevin McGowan, ornit\u00f3logo del Laboratorio de Ornitolog\u00eda de Cornell.<\/p>\n<p>Al igual que en el caso de los flamencos, para que un huevo eclosione y cuide de un polluelo de albatros se necesitan dos padres dedicados, ya que empollar el huevo puede durar hasta 60 d\u00edas (unos 28 d\u00edas en el caso de los flamencos) y ambos padres deben proporcionar alimento al polluelo.<\/p>\n<p>\u201cNo se puede hacer solo. Por eso, estas aves han descubierto c\u00f3mo hacerlo funcionar. Tienen el instinto de querer cuidar de un huevo, sean cuales sean las circunstancias\u201d, afirm\u00f3 McGowan. En el caso de Arthur y Curtis, el fuerte instinto natural de procreaci\u00f3n fue probablemente el motivo de la uni\u00f3n de parejas del mismo sexo. \u201cHay un gran deseo de tener hijos, y estos dos machos (Arthur y Curtis) descubrieron c\u00f3mo hacerlo\u201d, a\u00f1adi\u00f3 McGowan.<\/p>\n<p>La investigaci\u00f3n sobre la aparici\u00f3n de parejas del mismo sexo en la naturaleza podr\u00eda proporcionar m\u00e1s informaci\u00f3n sobre los posibles beneficios adaptativos de la conducta. Por ejemplo, si un flamenco salvaje perdiera a su pareja, pero tuviera un huevo que cuidar, afirm\u00f3 Rose. \u201cEsto demuestra lo ingeniosos que pueden ser los animales cuando se les obliga a hacer algo en un momento o una estaci\u00f3n espec\u00edfica del a\u00f1o\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Siete polluelos de flamencos chilenos blancos est\u00e1n en exhibici\u00f3n en un zool\u00f3gico en el suroeste de Inglaterra por primera vez desde 2018, y uno es particularmente notable por la forma en que naci\u00f3. Dos flamencos machos llamados Arthur y Curtis lograron empollar un huevo juntos, una novedad para el zool\u00f3gico de Paignton. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1452052","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Una pareja de flamencos del mismo sexo logra empollar un huevo en un zool\u00f3gico del Reino Unido - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/08\/21\/flamencos-mismo-sexo-empollan-huevo-reino-unido-animales-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una pareja de flamencos del mismo sexo logra empollar un huevo en un zool\u00f3gico del Reino Unido - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; Siete polluelos de flamencos chilenos blancos est\u00e1n en exhibici\u00f3n en un zool\u00f3gico en el suroeste de Inglaterra por primera vez desde 2018, y uno es particularmente notable por la forma en que naci\u00f3. Dos flamencos machos llamados Arthur y Curtis lograron empollar un huevo juntos, una novedad para el zool\u00f3gico de Paignton. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/08\/21\/flamencos-mismo-sexo-empollan-huevo-reino-unido-animales-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-21T23:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/21\/flamencos-mismo-sexo-empollan-huevo-reino-unido-animales-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/21\/flamencos-mismo-sexo-empollan-huevo-reino-unido-animales-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Una pareja de flamencos del mismo sexo logra empollar un huevo en un zool\u00f3gico del Reino Unido\",\"datePublished\":\"2024-08-21T23:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/21\/flamencos-mismo-sexo-empollan-huevo-reino-unido-animales-trax\/\"},\"wordCount\":1391,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/21\/flamencos-mismo-sexo-empollan-huevo-reino-unido-animales-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/21\/flamencos-mismo-sexo-empollan-huevo-reino-unido-animales-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/08\/21\/flamencos-mismo-sexo-empollan-huevo-reino-unido-animales-trax\/\",\"name\":\"Una pareja de flamencos del mismo sexo logra empollar un huevo en un zool\u00f3gico del Reino Unido - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-08-21T23:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/21\/flamencos-mismo-sexo-empollan-huevo-reino-unido-animales-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/21\/flamencos-mismo-sexo-empollan-huevo-reino-unido-animales-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/21\/flamencos-mismo-sexo-empollan-huevo-reino-unido-animales-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una pareja de flamencos del mismo sexo logra empollar un huevo en un zool\u00f3gico del Reino Unido\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una pareja de flamencos del mismo sexo logra empollar un huevo en un zool\u00f3gico del Reino Unido - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/08\/21\/flamencos-mismo-sexo-empollan-huevo-reino-unido-animales-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Una pareja de flamencos del mismo sexo logra empollar un huevo en un zool\u00f3gico del Reino Unido - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; Siete polluelos de flamencos chilenos blancos est\u00e1n en exhibici\u00f3n en un zool\u00f3gico en el suroeste de Inglaterra por primera vez desde 2018, y uno es particularmente notable por la forma en que naci\u00f3. Dos flamencos machos llamados Arthur y Curtis lograron empollar un huevo juntos, una novedad para el zool\u00f3gico de Paignton. [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/08\/21\/flamencos-mismo-sexo-empollan-huevo-reino-unido-animales-trax\/","og_site_name":"Noticias","article_published_time":"2024-08-21T23:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/08\/21\/flamencos-mismo-sexo-empollan-huevo-reino-unido-animales-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/08\/21\/flamencos-mismo-sexo-empollan-huevo-reino-unido-animales-trax\/"},"author":{"name":"","@id":""},"headline":"Una pareja de flamencos del mismo sexo logra empollar un huevo en un zool\u00f3gico del Reino Unido","datePublished":"2024-08-21T23:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/08\/21\/flamencos-mismo-sexo-empollan-huevo-reino-unido-animales-trax\/"},"wordCount":1391,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/08\/21\/flamencos-mismo-sexo-empollan-huevo-reino-unido-animales-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/08\/21\/flamencos-mismo-sexo-empollan-huevo-reino-unido-animales-trax\/","url":"https:\/\/noticiasya.com\/2024\/08\/21\/flamencos-mismo-sexo-empollan-huevo-reino-unido-animales-trax\/","name":"Una pareja de flamencos del mismo sexo logra empollar un huevo en un zool\u00f3gico del Reino Unido - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-08-21T23:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/08\/21\/flamencos-mismo-sexo-empollan-huevo-reino-unido-animales-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/08\/21\/flamencos-mismo-sexo-empollan-huevo-reino-unido-animales-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/08\/21\/flamencos-mismo-sexo-empollan-huevo-reino-unido-animales-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Una pareja de flamencos del mismo sexo logra empollar un huevo en un zool\u00f3gico del Reino Unido"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/21\/flamencos-mismo-sexo-empollan-huevo-reino-unido-animales-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Una pareja de flamencos del mismo sexo logra empollar un huevo en un zool\u00f3gico del Reino Unido","url":"http:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/21\/flamencos-mismo-sexo-empollan-huevo-reino-unido-animales-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/21\/flamencos-mismo-sexo-empollan-huevo-reino-unido-animales-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-08-21T23:03:39Z","datePublished":"2024-08-21T23:03:39Z","dateModified":"2024-08-21T23:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Una pareja de flamencos del mismo sexo logra empollar un huevo en un zool\\u00f3gico del Reino Unido\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2024\\\/08\\\/21\\\/flamencos-mismo-sexo-empollan-huevo-reino-unido-animales-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2024\\\/08\\\/21\\\/flamencos-mismo-sexo-empollan-huevo-reino-unido-animales-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-08-21T23:03:39Z\",\"datePublished\":\"2024-08-21T23:03:39Z\",\"dateModified\":\"2024-08-21T23:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1465142,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/08\/05\/zoologico-dinamarca-donar-mascotas-depredadores-cadena-alimenticia-trax\/","url_meta":{"origin":1452052,"position":0},"title":"Zool\u00f3gico de Dinamarca pide donar mascotas no deseadas para alimentar depredadores e imitar la &#171;cadena alimenticia natural&#187;","author":"","date":"agosto 5, 2025","format":false,"excerpt":"Un zool\u00f3gico en el norte de Dinamarca est\u00e1 pidiendo a los due\u00f1os de mascotas que donen sus cobayas, conejos, gallinas e incluso caballos peque\u00f1os no deseados para alimentar a los depredadores del zool\u00f3gico.El Zool\u00f3gico de Aalborg escribi\u00f3 en una publicaci\u00f3n de Facebook que intenta \u201cimitar la cadena alimenticia natural de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1406713,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2022\/06\/16\/instalan-mas-camaras-en-zoologico-de-amarillo-tras-aparicion-de-criatura\/","url_meta":{"origin":1452052,"position":1},"title":"Instalan m\u00e1s c\u00e1maras en Zool\u00f3gico de Amarillo tras aparicion de criatura","author":"agomez","date":"junio 16, 2022","format":false,"excerpt":"Los funcionarios del zool\u00f3gico emitieron un comunicado agradeciendo a Wyze por su generosa donaci\u00f3n.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1434003,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2022\/10\/24\/aves-que-murieron-en-zoologico-de-denver-tenian-gripe-aviar\/","url_meta":{"origin":1452052,"position":2},"title":"Aves que murieron en zool\u00f3gico de Denver ten\u00edan gripe aviar","author":"agomez","date":"octubre 24, 2022","format":false,"excerpt":"El zool\u00f3gico anunci\u00f3 que varias actividades que involucran el contacto con las aves han quedado suspendidas.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448433,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/04\/23\/murio-karen-avestruz-zoologico-llaves-trax\/","url_meta":{"origin":1452052,"position":3},"title":"Karen, la &#171;vibrante y querida&#187; avestruz del zool\u00f3gico de Topeka, muri\u00f3 despu\u00e9s de tragarse un juego de llaves","author":"agomez","date":"abril 23, 2024","format":false,"excerpt":"(CNN) -- Karen, una avestruz de cinco a\u00f1os que viv\u00eda en el zool\u00f3gico de Topeka en Kansas, muri\u00f3 despu\u00e9s de tragarse un juego de llaves que le arrebat\u00f3 a un miembro del personal, seg\u00fan funcionarios del zool\u00f3gico.La simp\u00e1tica ave \u201csucumbi\u00f3 tr\u00e1gicamente a las complicaciones derivadas del consumo de un objeto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1428067,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2022\/09\/22\/zoologico-de-el-paso-celebro-la-llegada-de-un-nuevo-caballo-de-przewalski\/","url_meta":{"origin":1452052,"position":4},"title":"Zool\u00f3gico de El Paso celebr\u00f3 la llegada de un nuevo caballo de Przewalski","author":"agomez","date":"septiembre 22, 2022","format":false,"excerpt":"Con este nuevo nacimiento de la potra, es la tercera cr\u00eda de los caballos adultos de Przewalski.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1408342,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2022\/06\/23\/zoologico-de-san-diego-da-la-bienvenida-a-lemur-especie-en-peligro-de-extincion\/","url_meta":{"origin":1452052,"position":5},"title":"Zool\u00f3gico de San Diego da la bienvenida a l\u00e9mur, especie en peligro de extinci\u00f3n","author":"agomez","date":"junio 23, 2022","format":false,"excerpt":"La beb\u00e9 naci\u00f3 el 22 de mayo de una madre l\u00e9mur primeriza","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1452052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1452052"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1452052\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1452052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1452052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1452052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}