{"id":1467793,"date":"2025-10-27T19:03:45","date_gmt":"2025-10-28T02:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/10\/27\/vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix\/"},"modified":"2025-10-27T19:03:45","modified_gmt":"2025-10-28T02:03:45","slug":"vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/27\/vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix\/","title":{"rendered":"Los pormenores del enojo de Vin\u00edcius Jr. con Xabi Alonso en la victoria del Real Madrid sobre el Barcelona"},"content":{"rendered":"<p>El cl\u00e1sico entre el Real Madrid y el FC Barcelona tuvo tres grandes protagonistas. El primero fue el club merengue, que se sacudi\u00f3 una racha de cuatro derrotas seguidas en cl\u00e1sicos contra el cuadro cul\u00e9 y se afianz\u00f3 en el liderato de LaLiga.<\/p>\n<p>En segundo lugar, Kylian Mbapp\u00e9, quien ratific\u00f3 su condici\u00f3n de m\u00e1ximo goleador de la liga de Espa\u00f1a con 10 anotaciones.<\/p>\n<p>El tercer lugar se lo lleva un Vin\u00edcius Junior que, si bien fue del agrado de la tribuna por lo hecho en el campo contra el FC Barcelona, decepcion\u00f3 a muchos por su enojo cuando fue sustituido por el director t\u00e9cnico del cuadro blanco, Xabi Alonso.<\/p>\n<p>El brasile\u00f1o sali\u00f3 del terreno de juego al minuto 73 y no ocult\u00f3 su enfado, dejando un repertorio de gestos y dirigi\u00e9ndose directamente al vestuario sin pasar por el banco de suplentes. Una actitud que no se espera en un equipo que est\u00e1 ganando un partido tan trascendental como el cl\u00e1sico y donde los blancos llevaban una ventaja de solo un gol. Los gestos, incluso, pueden hasta afectar al jugador que debe entrar al campo en su reemplazo.<\/p>\n<p>Est\u00e1 claro que ning\u00fan jugador quiere salir de un partido de semejante envergadura, menos si, como el brasile\u00f1o, has sido determinante para que tu equipo gane, pero siempre hay momentos y formas.<\/p>\n<p>El delantero se mostr\u00f3 en la banca y m\u00e1s calmado unos minutos despu\u00e9s, aunque al t\u00e9rmino del partido protagoniz\u00f3 un tumulto al recriminarle a la joven estrella Lamine Yamal por sus declaraciones de la \u00faltima semana, cuando intent\u00f3 minimizar la dificultad de visitar el Santiago Bernab\u00e9u. \u201cHablas demasiado\u201d, le dijo el brasile\u00f1o.<\/p>\n<p>Ya con la cabeza fr\u00eda y luego de varios minutos de haber concluido el encuentro, Vini asegur\u00f3 que no era su intenci\u00f3n ofender a los jugadores del club rival ni a la afici\u00f3n.<\/p>\n<p>En tanto, el entrenador del equipo, Xabi Alonso, asegur\u00f3 en la conferencia post partido que un entrenador \u201cconoce las personalidades de los jugadores\u201d y que llegar\u00e1 el momento de hablar con el brasile\u00f1o en el vestuario.<\/p>\n<p>Seg\u00fan medios como Marca, el club no tiene pensado meterse en este asunto que opac\u00f3 el triunfo Merengue en algunas portadas deportivas.<\/p>\n<p>Como dice una vieja frase: \u201cLa ropa sucia se lava en casa\u201d. Eso fue precisamente lo que Alonso prefiri\u00f3 hacer con el atacante de 25 a\u00f1os cuando fue cuestionado sobre la rabieta del brasile\u00f1o. De forma muy ecu\u00e1nime, el estratega espa\u00f1ol prefiri\u00f3 zanjar cualquier tipo de pol\u00e9mica y aclarar\u00e1 la situaci\u00f3n con Vini en privado.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cl\u00e1sico entre el Real Madrid y el FC Barcelona tuvo tres grandes protagonistas. El primero fue el club merengue, que se sacudi\u00f3 una racha de cuatro derrotas seguidas en cl\u00e1sicos contra el cuadro cul\u00e9 y se afianz\u00f3 en el liderato de LaLiga. En segundo lugar, Kylian Mbapp\u00e9, quien ratific\u00f3 su condici\u00f3n de m\u00e1ximo goleador [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467793","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los pormenores del enojo de Vin\u00edcius Jr. con Xabi Alonso en la victoria del Real Madrid sobre el Barcelona - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/10\/27\/vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los pormenores del enojo de Vin\u00edcius Jr. con Xabi Alonso en la victoria del Real Madrid sobre el Barcelona - Noticias\" \/>\n<meta property=\"og:description\" content=\"El cl\u00e1sico entre el Real Madrid y el FC Barcelona tuvo tres grandes protagonistas. El primero fue el club merengue, que se sacudi\u00f3 una racha de cuatro derrotas seguidas en cl\u00e1sicos contra el cuadro cul\u00e9 y se afianz\u00f3 en el liderato de LaLiga. En segundo lugar, Kylian Mbapp\u00e9, quien ratific\u00f3 su condici\u00f3n de m\u00e1ximo goleador [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/10\/27\/vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-28T02:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/27\/vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/27\/vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Los pormenores del enojo de Vin\u00edcius Jr. con Xabi Alonso en la victoria del Real Madrid sobre el Barcelona\",\"datePublished\":\"2025-10-28T02:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/27\/vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix\/\"},\"wordCount\":478,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/27\/vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/27\/vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/10\/27\/vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix\/\",\"name\":\"Los pormenores del enojo de Vin\u00edcius Jr. con Xabi Alonso en la victoria del Real Madrid sobre el Barcelona - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-10-28T02:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/27\/vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/27\/vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/27\/vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los pormenores del enojo de Vin\u00edcius Jr. con Xabi Alonso en la victoria del Real Madrid sobre el Barcelona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los pormenores del enojo de Vin\u00edcius Jr. con Xabi Alonso en la victoria del Real Madrid sobre el Barcelona - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/10\/27\/vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Los pormenores del enojo de Vin\u00edcius Jr. con Xabi Alonso en la victoria del Real Madrid sobre el Barcelona - Noticias","og_description":"El cl\u00e1sico entre el Real Madrid y el FC Barcelona tuvo tres grandes protagonistas. El primero fue el club merengue, que se sacudi\u00f3 una racha de cuatro derrotas seguidas en cl\u00e1sicos contra el cuadro cul\u00e9 y se afianz\u00f3 en el liderato de LaLiga. En segundo lugar, Kylian Mbapp\u00e9, quien ratific\u00f3 su condici\u00f3n de m\u00e1ximo goleador [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/10\/27\/vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix\/","og_site_name":"Noticias","article_published_time":"2025-10-28T02:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/10\/27\/vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/10\/27\/vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix\/"},"author":{"name":"","@id":""},"headline":"Los pormenores del enojo de Vin\u00edcius Jr. con Xabi Alonso en la victoria del Real Madrid sobre el Barcelona","datePublished":"2025-10-28T02:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/10\/27\/vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix\/"},"wordCount":478,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/10\/27\/vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/10\/27\/vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix\/","url":"https:\/\/noticiasya.com\/2025\/10\/27\/vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix\/","name":"Los pormenores del enojo de Vin\u00edcius Jr. con Xabi Alonso en la victoria del Real Madrid sobre el Barcelona - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-10-28T02:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/10\/27\/vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/10\/27\/vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/10\/27\/vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Los pormenores del enojo de Vin\u00edcius Jr. con Xabi Alonso en la victoria del Real Madrid sobre el Barcelona"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/27\/vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Los pormenores del enojo de Vin\u00edcius Jr. con Xabi Alonso en la victoria del Real Madrid sobre el Barcelona","url":"http:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/27\/vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/27\/vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-10-28T02:03:45Z","datePublished":"2025-10-28T02:03:45Z","dateModified":"2025-10-28T02:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Los pormenores del enojo de Vin\\u00edcius Jr. con Xabi Alonso en la victoria del Real Madrid sobre el Barcelona\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2025\\\/10\\\/27\\\/vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2025\\\/10\\\/27\\\/vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-10-28T02:03:45Z\",\"datePublished\":\"2025-10-28T02:03:45Z\",\"dateModified\":\"2025-10-28T02:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1469094,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/12\/08\/real-madrid-crisis-xabi-alonso-orix\/","url_meta":{"origin":1467793,"position":0},"title":"El Real Madrid, del cielo al infierno en 40 d\u00edas: \u00bfle encontrar\u00e1 la vuelta un Xabi Alonso en la cornisa?","author":"","date":"diciembre 8, 2025","format":false,"excerpt":"Cuando el Real Madrid venci\u00f3 al Barcelona el 26 de octubre, no eran pocos los que aventuraban que el Merengue estaba listo para una temporada de ensue\u00f1o, tanto en Espa\u00f1a como en Europa. Sin embargo, poco m\u00e1s de 40 d\u00edas despu\u00e9s, los madridistas parecen a la deriva, indefensos ante un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468631,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/11\/23\/resultado-real-madrid-elche-laliga-efe\/","url_meta":{"origin":1467793,"position":1},"title":"El Real Madrid jug\u00f3 mal y perdi\u00f3 puntos ante Elche, pero sigue arriba del FC Barcelona en LaLiga","author":"","date":"noviembre 23, 2025","format":false,"excerpt":"El Real Madrid confirm\u00f3 su mal momento y cuaj\u00f3 de nuevo un p\u00e9simo encuentro en el Mart\u00ednez Valero ante un animoso y atrevido Elche, que estuvo a punto de endosarle la segunda derrota del curso liguero pero que le ara\u00f1\u00f3 un empate (2-2) de gran m\u00e9rito, resultado que ratifica los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465665,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/08\/19\/penal-mbappe-debut-real-madrid-laliga-orix\/","url_meta":{"origin":1467793,"position":2},"title":"Un gol de penal de Mbapp\u00e9 salv\u00f3 el debut del Real Madrid en LaLiga: as\u00ed quedaron las posiciones","author":"","date":"agosto 19, 2025","format":false,"excerpt":"No le sobr\u00f3 nada. As\u00ed podr\u00eda resumirse el debut del Real Madrid en la temporada 2025\/2026 de LaLiga. Frente a m\u00e1s de 80.000 personas que llenaron el Santiago Bernab\u00e9u, el equipo dirigido por Xabi Alonso tuvo que trabajar de m\u00e1s para vencer 1-0 al Osasuna y as\u00ed comenzar con el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465816,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/08\/24\/real-madrid-ovideo-laliga-mbappe-analisis-orix\/","url_meta":{"origin":1467793,"position":3},"title":"El Real Madrid gana con presi\u00f3n alta y los goles de Mbapp\u00e9: \u00bfle alcanza para ganar LaLiga?","author":"","date":"agosto 24, 2025","format":false,"excerpt":"Los grandes equipos parecieran no terminar de engranar en el comienzo de LaLiga. Le pasa al Atl\u00e9tico de Madrid, que empat\u00f3 sus dos partidos. Casi le pasa al FC Barcelona, que el s\u00e1bado salv\u00f3 con lo justo los tres puntos ante Levante, tras ir perdiendo 0-2. Y le pasa al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470011,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/01\/12\/real-madrid-despide-xabi-alonso-orix\/","url_meta":{"origin":1467793,"position":4},"title":"El Real Madrid se despide de Xabi Alonso","author":"","date":"enero 12, 2026","format":false,"excerpt":"La relaci\u00f3n entre el Real Madrid y Xabi Alonso no aguanto m\u00e1s. Despu\u00e9s del fracaso en la Supercopa de Espa\u00f1a, en la que su eterno rival el Barcelona se coron\u00f3 campe\u00f3n, el club blanco anunci\u00f3 la salida del director t\u00e9cnico por mutuo acuerdo.\u201cEl Real Madrid C. F. comunica que, de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462781,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/05\/25\/xabi-alonso-posibles-cambios-real-madrid-orix\/","url_meta":{"origin":1467793,"position":5},"title":"\u00bfQu\u00e9 tendr\u00e1 que cambiar y que necesitar\u00e1 Xabi Alonso en el Real Madrid?","author":"","date":"mayo 25, 2025","format":false,"excerpt":"La salida de Carlo Ancelotti y la llegada de Xabi Alonso al banquillo del Real Madrid, implican el final de una era y el comienzo de una nueva.En el Santiago Bernab\u00e9u est\u00e1n conscientes que la plantilla requerir\u00e1 varios refuerzos en zonas clave del campo.\u00bfQu\u00e9 refuerzos necesitar\u00e1 Xabi Alonso, ahora como\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1467793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1467793"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1467793\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1467793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1467793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1467793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}