{"id":1467800,"date":"2025-10-28T03:03:38","date_gmt":"2025-10-28T10:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/10\/28\/katy-perry-justin-trudeau-saliendo-segun-mundo-trax\/"},"modified":"2025-10-28T03:03:38","modified_gmt":"2025-10-28T10:03:38","slug":"katy-perry-justin-trudeau-saliendo-segun-mundo-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/28\/katy-perry-justin-trudeau-saliendo-segun-mundo-trax\/","title":{"rendered":"Katy Perry y Justin Trudeau est\u00e1n &#171;oficialmente saliendo&#187;, todo el mundo lo ha decidido"},"content":{"rendered":"<p>Durante meses, los avistamientos han sido confusos y a larga distancia, m\u00e1s dignos de la fotograf\u00eda de naturaleza \u00e1rtica que de las p\u00e1ginas de chismes. En julio, <a href=\"https:\/\/www.tmz.com\/2025\/07\/29\/katy-perry-justin-trudeau-dinner-walk-park-dog\/\">se les vio<\/a> paseando un perro y luego cenando en un restaurante en Montreal. Y despu\u00e9s, un silencio confuso, ya que la \u2014\u00bferan siquiera?\u2014 nueva pareja se hab\u00eda retirado a una hibernaci\u00f3n veraniega.<\/p>\n<p>No fue hasta septiembre que en un viaje de avistamiento de ballenas en California se logr\u00f3 la mayor observaci\u00f3n n\u00e1utica de todas, cuando un pasajero tom\u00f3 una foto a distancia de una pareja rom\u00e1ntica entrelazada en la cima de un yate.<\/p>\n<p>Al ampliar la imagen, <a href=\"https:\/\/people.com\/katy-perry-justin-trudeau-kiss-cuddle-pda-yacht-santa-barbara-california-11828747\">el fot\u00f3grafo<\/a> reconoci\u00f3 al ex primer ministro de Canad\u00e1 Justin Trudeau por su <a href=\"https:\/\/macleans.ca\/politics\/skin-deep-the-awkwardness-of-justin-trudeaus-haida-tattoo\/\">espinoso tatuaje ind\u00edgena<\/a>, aunque aparentemente no reconoci\u00f3 a la incre\u00edblemente famosa estrella pop Katy Perry por el hecho de que estaban acurrucados en su <a href=\"https:\/\/www.superyachttimes.com\/yachts\/caravelle\/overview\">elegante yate a motor<\/a>, el Caravelle de 23 metros.<\/p>\n<p>Eran, al parecer, <em>algo<\/em>.<\/p>\n<p>Ha sido un a\u00f1o muy extra\u00f1o para ambos. <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/06\/mundo\/canada-justin-trudeau-renunciar-partido-trax\">Trudeau anunci\u00f3 que renunciar\u00eda en enero<\/a>, dejando a Canad\u00e1 para continuar su conflicto con Estados Unidos sin \u00e9l. Fue reemplazado en abril.<\/p>\n<p>Ese fue el mismo mes en que Perry \u201crenunci\u00f3 al planeta\u201d, haciendo un viaje de celebridad extra\u00f1amente desastroso a la termosfera terrestre. Ella, Gayle King y la entonces prometida de Bezos, Lauren S\u00e1nchez, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/04\/13\/entretenimiento\/katy-perry-gayle-king-otras-cuatro-mujeres-espacio-trax\">tomaron el cohete Blue Origin<\/a> de Bezos hasta el mism\u00edsimo borde del espacio.<\/p>\n<p>Por alguna raz\u00f3n dif\u00edcil de definir, este viaje convirti\u00f3 a Perry en el hazmerre\u00edr. \u00bf<a href=\"https:\/\/www.cnn.com\/science\/live-news\/blue-origin-space-flight-katy-perry-04-14-25\">Fue el momento inc\u00f3modo de besar el suelo al regresar<\/a>? \u00bfFue la vibra anticuada de \u201cequipo femenino\u201d del viaje? \u00bfFue que b\u00e1sicamente quemaron una fortuna sin ning\u00fan prop\u00f3sito, mientras el mundo ya parec\u00eda estar ardiendo?<\/p>\n<p>\u00bfO fue que estas malas vibras eran personales para Perry; alguna campa\u00f1a de relaciones p\u00fablicas negativa liderada por Orlando Bloom? Porque, pronto sabr\u00edamos, Perry se estaba separando de su prometido, el viejo Legolas en persona.<\/p>\n<p>Cualquiera que sea la raz\u00f3n, de la noche a la ma\u00f1ana pas\u00f3 de ser \u201c<a href=\"https:\/\/slate.com\/culture\/2025\/06\/katy-perry-tour-concert-2025-space-blue-origin.html\">realeza del pop a la broma favorita de Estados Unidos<\/a>\u201d.<\/p>\n<p>Solo su lenta migraci\u00f3n rom\u00e1ntica hacia el norte ha evitado que su marca caiga en una crisis profunda. Trudeau la ha convertido en el blanco de un tipo de broma m\u00e1s amable: \u201cKaty Perry lanza nuevo sencillo sobre la superioridad de la manufactura canadiense\u201d, <a href=\"https:\/\/theonion.com\/katy-perry-releases-new-single-about-superiority-of-canadian-manufacturing\/\">brome\u00f3 The Onion<\/a>. Esta <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/10\/24\/eeuu\/trump-fin-negociaciones-comerciales-canada-ap\">guerra comercial<\/a> del coraz\u00f3n est\u00e1 dando frutos.<\/p>\n<p>Ahora est\u00e1n, oficialmente, fuera del armario, y lo sabemos porque lo dice Pop Crave: \u201cKaty Perry y Justin Trudeau est\u00e1n oficialmente saliendo\u201d, public\u00f3 la cuenta de chismes de referencia el fin de semana.<\/p>\n<p>Y aqu\u00ed est\u00e1 ella, <a href=\"https:\/\/www.bbc.com\/news\/articles\/ce3x70g9wq4o\">triunfante en la portada de todos los mejores tabloides ingleses<\/a>. El s\u00e1bado fue su cumplea\u00f1os. Hizo una gran fiesta en el cabaret Crazy Horse de Par\u00eds. Ella y Trudeau no solo se tomaron de la mano, sino que aparentemente tambi\u00e9n se fueron juntos de la fiesta. Honestamente, se ve\u00edan muy bien.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante meses, los avistamientos han sido confusos y a larga distancia, m\u00e1s dignos de la fotograf\u00eda de naturaleza \u00e1rtica que de las p\u00e1ginas de chismes. En julio, se les vio paseando un perro y luego cenando en un restaurante en Montreal. Y despu\u00e9s, un silencio confuso, ya que la \u2014\u00bferan siquiera?\u2014 nueva pareja se hab\u00eda [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467800","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Katy Perry y Justin Trudeau est\u00e1n &quot;oficialmente saliendo&quot;, todo el mundo lo ha decidido - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/10\/28\/katy-perry-justin-trudeau-saliendo-segun-mundo-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Katy Perry y Justin Trudeau est\u00e1n &quot;oficialmente saliendo&quot;, todo el mundo lo ha decidido - Noticias\" \/>\n<meta property=\"og:description\" content=\"Durante meses, los avistamientos han sido confusos y a larga distancia, m\u00e1s dignos de la fotograf\u00eda de naturaleza \u00e1rtica que de las p\u00e1ginas de chismes. En julio, se les vio paseando un perro y luego cenando en un restaurante en Montreal. Y despu\u00e9s, un silencio confuso, ya que la \u2014\u00bferan siquiera?\u2014 nueva pareja se hab\u00eda [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/10\/28\/katy-perry-justin-trudeau-saliendo-segun-mundo-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-28T10:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/28\/katy-perry-justin-trudeau-saliendo-segun-mundo-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/28\/katy-perry-justin-trudeau-saliendo-segun-mundo-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Katy Perry y Justin Trudeau est\u00e1n &#171;oficialmente saliendo&#187;, todo el mundo lo ha decidido\",\"datePublished\":\"2025-10-28T10:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/28\/katy-perry-justin-trudeau-saliendo-segun-mundo-trax\/\"},\"wordCount\":554,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/28\/katy-perry-justin-trudeau-saliendo-segun-mundo-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/28\/katy-perry-justin-trudeau-saliendo-segun-mundo-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/10\/28\/katy-perry-justin-trudeau-saliendo-segun-mundo-trax\/\",\"name\":\"Katy Perry y Justin Trudeau est\u00e1n \\\"oficialmente saliendo\\\", todo el mundo lo ha decidido - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-10-28T10:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/28\/katy-perry-justin-trudeau-saliendo-segun-mundo-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/28\/katy-perry-justin-trudeau-saliendo-segun-mundo-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/28\/katy-perry-justin-trudeau-saliendo-segun-mundo-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Katy Perry y Justin Trudeau est\u00e1n &#171;oficialmente saliendo&#187;, todo el mundo lo ha decidido\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Katy Perry y Justin Trudeau est\u00e1n \"oficialmente saliendo\", todo el mundo lo ha decidido - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/10\/28\/katy-perry-justin-trudeau-saliendo-segun-mundo-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Katy Perry y Justin Trudeau est\u00e1n \"oficialmente saliendo\", todo el mundo lo ha decidido - Noticias","og_description":"Durante meses, los avistamientos han sido confusos y a larga distancia, m\u00e1s dignos de la fotograf\u00eda de naturaleza \u00e1rtica que de las p\u00e1ginas de chismes. En julio, se les vio paseando un perro y luego cenando en un restaurante en Montreal. Y despu\u00e9s, un silencio confuso, ya que la \u2014\u00bferan siquiera?\u2014 nueva pareja se hab\u00eda [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/10\/28\/katy-perry-justin-trudeau-saliendo-segun-mundo-trax\/","og_site_name":"Noticias","article_published_time":"2025-10-28T10:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/10\/28\/katy-perry-justin-trudeau-saliendo-segun-mundo-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/10\/28\/katy-perry-justin-trudeau-saliendo-segun-mundo-trax\/"},"author":{"name":"","@id":""},"headline":"Katy Perry y Justin Trudeau est\u00e1n &#171;oficialmente saliendo&#187;, todo el mundo lo ha decidido","datePublished":"2025-10-28T10:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/10\/28\/katy-perry-justin-trudeau-saliendo-segun-mundo-trax\/"},"wordCount":554,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/10\/28\/katy-perry-justin-trudeau-saliendo-segun-mundo-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/10\/28\/katy-perry-justin-trudeau-saliendo-segun-mundo-trax\/","url":"https:\/\/noticiasya.com\/2025\/10\/28\/katy-perry-justin-trudeau-saliendo-segun-mundo-trax\/","name":"Katy Perry y Justin Trudeau est\u00e1n \"oficialmente saliendo\", todo el mundo lo ha decidido - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-10-28T10:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/10\/28\/katy-perry-justin-trudeau-saliendo-segun-mundo-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/10\/28\/katy-perry-justin-trudeau-saliendo-segun-mundo-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/10\/28\/katy-perry-justin-trudeau-saliendo-segun-mundo-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Katy Perry y Justin Trudeau est\u00e1n &#171;oficialmente saliendo&#187;, todo el mundo lo ha decidido"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/28\/katy-perry-justin-trudeau-saliendo-segun-mundo-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Katy Perry y Justin Trudeau est\u00e1n &#171;oficialmente saliendo&#187;, todo el mundo lo ha decidido","url":"http:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/28\/katy-perry-justin-trudeau-saliendo-segun-mundo-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/28\/katy-perry-justin-trudeau-saliendo-segun-mundo-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-10-28T10:03:38Z","datePublished":"2025-10-28T10:03:38Z","dateModified":"2025-10-28T10:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Katy Perry y Justin Trudeau est\\u00e1n &#171;oficialmente saliendo&#187;, todo el mundo lo ha decidido\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2025\\\/10\\\/28\\\/katy-perry-justin-trudeau-saliendo-segun-mundo-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2025\\\/10\\\/28\\\/katy-perry-justin-trudeau-saliendo-segun-mundo-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-10-28T10:03:38Z\",\"datePublished\":\"2025-10-28T10:03:38Z\",\"dateModified\":\"2025-10-28T10:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1473119,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/13\/katy-perry-justin-trudeau-coachella-orix\/","url_meta":{"origin":1467800,"position":0},"title":"Katy Perry y Justin Trudeau disfrutan de Coachella en pareja","author":"","date":"abril 13, 2026","format":false,"excerpt":"La cantante Katy Perry y el ex primer ministro canadiense Justin Trudeau asistieron como p\u00fablico al primer fin de semana del Coachella 2026. La pareja se dej\u00f3 ver entre los asistentes y no perdi\u00f3 oportunidad de demostrar su cari\u00f1o en varias ocasiones.Incluso, la propia Perry comparti\u00f3 una publicaci\u00f3n en su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469078,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/12\/08\/katy-perry-justin-trudeau-instagram-trax\/","url_meta":{"origin":1467800,"position":1},"title":"Justin Trudeau y Katy Perry hacen oficial su relaci\u00f3n a trav\u00e9s de Instagram","author":"","date":"diciembre 8, 2025","format":false,"excerpt":"El ex primer ministro canadiense Justin Trudeau y la estrella del pop Katy Perry parecen haber confirmado su relaci\u00f3n de la \u00fanica manera que importa: haci\u00e9ndola oficial en Instagram.Perry public\u00f3 el s\u00e1bado una serie de fotos en las que aparece junto a Trudeau, posando mejilla con mejilla y comiendo sushi\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457270,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/01\/06\/canada-justin-trudeau-renunciar-partido-trax\/","url_meta":{"origin":1467800,"position":2},"title":"El primer ministro de Canad\u00e1, Justin Trudeau, se dispone a renunciar como l\u00edder del partido mientras cae su popularidad","author":"","date":"enero 6, 2025","format":false,"excerpt":"Se espera que el primer ministro de Canad\u00e1, Justin Trudeau, anuncie su renuncia como l\u00edder del gobernante Partido Liberal en los pr\u00f3ximos d\u00edas, seg\u00fan han informado los medios canadienses, antes de las elecciones generales que se celebrar\u00e1n a finales de este a\u00f1o y que se espera que pierda.Trudeau probablemente anunciar\u00e1\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456673,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/12\/17\/justin-trudeau-donald-trump-canada-trax\/","url_meta":{"origin":1467800,"position":3},"title":"Justin Trudeau se enfrenta a una crisis pol\u00edtica agravada por Donald Trump. \u00bfPodr\u00e1 sobrevivir como l\u00edder de Canad\u00e1?","author":"","date":"diciembre 17, 2024","format":false,"excerpt":"El primer ministro de Canad\u00e1, Justin Trudeau, se alz\u00f3 con la victoria en 2015 gracias a su promesa de cambio y \u201ccaminos soleados\u201d para el pa\u00eds.Casi una d\u00e9cada despu\u00e9s, un oscuro nubarr\u00f3n ha descendido sobre su Gobierno, cada vez m\u00e1s impopular, con la renuncia de una importante ministra del Gabinete\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468452,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/11\/18\/sophie-gregoire-habla-romance-trudeau-perry-trax\/","url_meta":{"origin":1467800,"position":4},"title":"Sophie Gr\u00e9goire rompe el silencio sobre el romance de su exposo, Justin Trudeau, con Katy Perry","author":"","date":"noviembre 18, 2025","format":false,"excerpt":"Sophie Gr\u00e9goire ha hablado sobre su vida en p\u00fablico como exesposa del ex primer ministro de Canad\u00e1 Justin Trudeau.Durante una reciente aparici\u00f3n en el podcast \u201cArlene is Alone\u201d, surgi\u00f3 el tema de la atenci\u00f3n medi\u00e1tica que est\u00e1 recibiendo Trudeau por salir con la cantante Katy Perry, mientras la presentadora Arlene\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459702,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/03\/09\/mark-carney-sucesor-justin-trudeau-partido-liberal-canada-trax\/","url_meta":{"origin":1467800,"position":5},"title":"El Partido Liberal de Canad\u00e1 elige a Mark Carney para suceder a Justin Trudeau","author":"","date":"marzo 9, 2025","format":false,"excerpt":"Mark Carney fue elegido l\u00edder del Partido Liberal de Canad\u00e1 tras una carrera de alto perfil que dur\u00f3 meses para reemplazar a Justin Trudeau.Se espera entonces que lidere al partido en las pr\u00f3ximas elecciones federales, que deben celebrarse antes de octubre, donde es probable que se enfrenten a una dura\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1467800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1467800"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1467800\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1467800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1467800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1467800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}