{"id":1467804,"date":"2025-10-28T05:03:49","date_gmt":"2025-10-28T12:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/10\/28\/periodista-estadounidense-desaparecido-siria-13-anos-busqueda-madre-trax\/"},"modified":"2025-10-28T05:03:49","modified_gmt":"2025-10-28T12:03:49","slug":"periodista-estadounidense-desaparecido-siria-13-anos-busqueda-madre-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/28\/periodista-estadounidense-desaparecido-siria-13-anos-busqueda-madre-trax\/","title":{"rendered":"Un periodista estadounidense desapareci\u00f3 en Siria hace 13 a\u00f1os. Su madre nunca dej\u00f3 de buscarlo"},"content":{"rendered":"<p>\u201cEsto ser\u00e1 un \u00e9xito rotundo o un completo desastre\u201d, escribi\u00f3 <a href=\"https:\/\/www.cnn.com\/2024\/12\/10\/politics\/austin-tice-search-syria\">Austin Tice<\/a> en mayo de 2012, en v\u00edsperas de un peligroso viaje para dar testimonio de la historia. \u201cAqu\u00ed va la cosa\u201d.<\/p>\n<p>Tice, un exinfante de Marina de EE.UU., de complexi\u00f3n imponente y periodista novato, se lanz\u00f3 con coraje y determinaci\u00f3n a zonas de guerra, amistades y las injusticias que le preocupaban profundamente.<\/p>\n<p>Pero a\u00fan no ha regresado de ese viaje. Tice desapareci\u00f3 en Siria dos meses despu\u00e9s de partir para cubrir la devastadora guerra civil del pa\u00eds, desatando un misterio de 13 a\u00f1os que ha torturado a su familia texana y ha afectado la relaci\u00f3n de Washington con el brutal exdictador sirio, Bashar al-Assad.<\/p>\n<p>Durante m\u00e1s de una d\u00e9cada, nadie ha visto ni o\u00eddo hablar de Tice. Su familia nunca ha perdido la esperanza de que est\u00e9 vivo, incluso cuando sucesivos gobiernos, desde el presidente Obama hasta el presidente Trump, no lograron traerlo a casa.<\/p>\n<p>Pero en diciembre, el r\u00e9gimen represivo de al-Assad, que siempre hab\u00eda negado haber capturado o asesinado a Tice, se derrumb\u00f3 en un instante. Y en los ca\u00f3ticos meses transcurridos desde entonces, pistas sobre el destino de Tice han comenzado a filtrarse a trav\u00e9s de los muros de las otrora impenetrables prisiones y palacios de Siria.<\/p>\n<p>Ahora, una <a href=\"https:\/\/www.cnn.com\/videos\/title-2573152\">investigaci\u00f3n de CNN<\/a> ha revelado un avance notable. Bassam al Hassan, un general de cuatro estrellas cercano a al-Assad, declar\u00f3 a la corresponsal internacional jefe de CNN, Clarissa Ward, que Tice fue asesinado en 2013, un a\u00f1o despu\u00e9s de su captura. La <a href=\"https:\/\/www.cnn.com\/2025\/10\/28\/politics\/al-hassan-austin-tice-update\">orden provino de al-Assad<\/a>, dijo. Sin embargo, Hassan no pas\u00f3 la prueba del pol\u00edgrafo del FBI, seg\u00fan confirm\u00f3 CNN, y no est\u00e1 claro qu\u00e9 partes de su historia siguen siendo falsas.<\/p>\n<p>\u201cAustin es como un puente entre Estados Unidos y Siria\u201d, declar\u00f3 a CNN Waseem Enawi, activista sirio que acogi\u00f3 a Tice en su casa de Yabrud durante tres semanas. \u201cA trav\u00e9s de lo que le ocurri\u00f3 con Austin, la gente puede comprender lo que les ocurri\u00f3 a cientos de miles de sirios\u201d, a\u00f1adi\u00f3.<\/p>\n<p>\u201cEs lo \u00fanico bueno que se me ocurre que pueda salir de todo esto\u201d.<\/p>\n<p>Mucho antes de su viaje a Siria, Tice sab\u00eda que quer\u00eda dejar un impacto.<\/p>\n<p>El mayor de siete hermanos, Tice recibi\u00f3 su educaci\u00f3n en casa en Houston con sus devotos padres cat\u00f3licos, Debra y Mark Tice. A la familia le encantaba viajar; visitaban M\u00e9xico al menos una vez al a\u00f1o, hicieron varios viajes por carretera a trav\u00e9s del pa\u00eds y pasaron tres meses en Europa durante la adolescencia de Austin.<\/p>\n<p>\u201cPara mis padres era muy importante que supi\u00e9ramos que hab\u00eda todo un mundo ah\u00ed fuera\u201d, dijo a CNN Abigail Tice, la hermana menor de Austin.<\/p>\n<p>Tice era un protector feroz, record\u00f3 Abigail. \u201cSiempre que me gustaba alguien de la escuela secundaria, \u00e9l les hablaba y les dec\u00eda: \u2018Esa es mi hermanita, m\u00e1s vale que la trates con respeto\u2019\u201d.<\/p>\n<p>Cuando naci\u00f3 la hija de Abigail, Austin se convirti\u00f3 en un \u201coso de peluche enorme y cari\u00f1oso\u201d, dijo Abigail a CNN. \u201cCada momento que pod\u00eda, jugaba con ella\u201d.<\/p>\n<p>A los 23 a\u00f1os, Tice se uni\u00f3 a la Infanter\u00eda de Marina. \u201cCreo que ve\u00eda a la Infanter\u00eda de Marina como el mayor desaf\u00edo\u201d, dijo Brian Bruggeman, comandante del batall\u00f3n de Austin durante su despliegue en Afganist\u00e1n en 2011. \u201cA Austin le atrajo la forma de liderazgo de la Infanter\u00eda de Marina\u201d.<\/p>\n<p>Tice destacaba, dijo Bruggeman a CNN. \u201cEra sociable y extremadamente curioso\u201d.<\/p>\n<p>Se esforz\u00f3 por integrar a su int\u00e9rprete afgano en el batall\u00f3n, record\u00f3 Bruggeman, dici\u00e9ndole al traductor local: \u201cAhora eres parte de nuestra unidad. Un a\u00f1o despu\u00e9s, Tice se alegr\u00f3 mucho cuando el int\u00e9rprete fue aceptado en una universidad estadounidense, y el hombre se qued\u00f3 con su familia en Texas despu\u00e9s de mudarse a Estados Unidos\u201d.<\/p>\n<p>En Afganist\u00e1n, Tice se abri\u00f3 a sus compa\u00f1eros. \u201cMe dej\u00f3 entrar\u201d, dijo Bruggeman. \u201cLe encantaba hablar de su familia\u201d, record\u00f3 su comandante. \u201cSent\u00ed que conoc\u00eda bien a su madre antes de conocerla o hablar con ella\u201d.<\/p>\n<p>Tice tuvo una revelaci\u00f3n mientras estaba en Afganist\u00e1n, a\u00f1adi\u00f3 Bruggeman: quer\u00eda dedicarse al fotoperiodismo. Celebr\u00f3 su 30\u00ba cumplea\u00f1os compr\u00e1ndose una c\u00e1mara y comenz\u00f3 a documentar su despliegue, compartiendo sus reflexiones en blogs y Twitter.<\/p>\n<p>Pero el tiempo que pas\u00f3 Tice en Afganist\u00e1n tambi\u00e9n lo cambi\u00f3 de forma m\u00e1s oscura. Vio a varios compa\u00f1eros de la Infanter\u00eda de Marina muertos o heridos: uno perdi\u00f3 la pierna izquierda al detonar un artefacto explosivo improvisado (IED), y otro muri\u00f3 electrocutado cuando su antena de radio toc\u00f3 un cable el\u00e9ctrico. Desarroll\u00f3 un morboso sentido del humor sobre su propia vulnerabilidad.<\/p>\n<p>\u201cPronto me embarcar\u00e9 en una misi\u00f3n horriblemente concebida\u201d, escribi\u00f3 en un tuit. \u201cOjal\u00e1 quede en el olvido, como ocurre con la mayor\u00eda de las misiones absurdas; si no, nos vemos en CNN\u201d.<\/p>\n<p>\u201cHe servido en el frente de ambas guerras\u201d, escribi\u00f3 en otro momento, refiri\u00e9ndose tambi\u00e9n a su servicio en Iraq. \u201cAparte de mis hombres, a\u00fan no he visto nada por lo que valga la pena morir\u201d.<\/p>\n<p>Tice regres\u00f3 a Estados Unidos para graduarse en Derecho en la Universidad de Georgetown mientras la Primavera \u00c1rabe derrocaba a los aut\u00f3cratas y pon\u00eda fin a d\u00e9cadas de dominio severo en Medio Oriente. \u201cEs hora de trabajar duro, aburrirse y prepararse para la pr\u00f3xima gran aventura\u201d, escribi\u00f3.<\/p>\n<p>Pero convertirse en abogado no era su vocaci\u00f3n, y ser aburrido no era su naturaleza.<\/p>\n<p>\u201cNo es el camino que yo ve\u00eda para \u00e9l\u201d, dijo a CNN un amigo de la familia Tice. \u201cEra una persona demasiado activa como para sentarse detr\u00e1s de un escritorio\u201d.<\/p>\n<p>As\u00ed que, despu\u00e9s de su segundo a\u00f1o en la Facultad de Ferecho, Tice se propuso una nueva misi\u00f3n. Y quer\u00eda que su hermano se uniera a \u00e9l.<\/p>\n<p>\u201cMe col\u00e9 en una habitaci\u00f3n vac\u00eda de la casita que alquil\u00e1bamos y escuch\u00e9, asombrado, c\u00f3mo me contaba que estaba planeando un viaje a Siria ese verano de 2012\u201d, escribi\u00f3 Jacob Tice en <a href=\"https:\/\/www.cnn.com\/2020\/09\/25\/opinions\/my-brother-austin-asked-me-to-go-to-syria-with-him-jacob-tice\">un art\u00edculo de opini\u00f3n de 2020<\/a> para CNN.<\/p>\n<p>Jacob lo rechaz\u00f3 porque no se imaginaba viajar a una zona de guerra activa. Pero escribi\u00f3: \u201cLo anim\u00e9 a seguir su coraz\u00f3n y a dar testimonio de la escalada del conflicto en Siria. Cre\u00ed en su visi\u00f3n, admir\u00e9 su determinaci\u00f3n y lo apoy\u00e9 por completo\u201d.<\/p>\n<p>Tice comprend\u00eda los riesgos. Llevaba mucho tiempo en la misma situaci\u00f3n con un colega cercano en el juego en l\u00ednea \u201cWords With Friends\u201d, e hizo un trato: si no jugaba mi turno durante m\u00e1s de una semana, avisar\u00eda a la gente que estaba en problemas.<\/p>\n<p>La noche antes de partir hacia Siria, Tice se encontr\u00f3 con un amigo de la familia en un bar de Washington. \u201cNo hubo manera de disuadirlo\u201d, declar\u00f3 el amigo a CNN. \u201cQuer\u00eda contar su historia. Porque sent\u00eda que no hab\u00eda nadie m\u00e1s all\u00ed\u201d.<\/p>\n<p>\u201cPienso en esa noche todo el tiempo\u201d, a\u00f1adi\u00f3 el amigo de Tice, que pidi\u00f3 no ser identificado. \u201cSi hubiera podido, si hubiera podido detenerlo\u201d.<\/p>\n<p>\u201cMaldita sea, ojal\u00e1 hubiera dicho lo correcto\u201d, dijo.<\/p>\n<p>Cuando Tice viaj\u00f3 a Siria, el pa\u00eds se encontraba sumido en una violenta guerra civil. El Ej\u00e9rcito Libre Sirio (ELS), una coalici\u00f3n de combatientes rebeldes, avanzaba hacia la capital, Damasco, en el suroeste del pa\u00eds, y <a href=\"https:\/\/cnnespanol.cnn.com\/video\/rebeldes-siria-aleppo-idlib-bombardeos-rusia-orix\">hacia Aleppo<\/a>, en el noroeste. Ambas ciudades se hab\u00edan convertido en frentes clave del conflicto despu\u00e9s de que las fuerzas de al-Assad comenzaran a reprimir a los manifestantes pac\u00edficos el a\u00f1o anterior.<\/p>\n<p>Tice se qued\u00f3 con Enawi cerca de la frontera norte del pa\u00eds durante casi tres semanas, entrevistando a lugare\u00f1os sobre la guerra. \u201cTodos lo saludaban; era un poco famoso\u201d, declar\u00f3 Enawi a CNN.<\/p>\n<p>Tice a\u00fan no era reportero, pero no quer\u00eda perder el tiempo. \u201cDeseaba desesperadamente ser periodista. Quer\u00eda triunfar\u201d, declar\u00f3 a CNN Liz Sly, editora de la oficina de Beirut del Washington Post, quien trabaj\u00f3 con Tice y public\u00f3 tres de sus art\u00edculos. Quer\u00eda aprender con la pr\u00e1ctica, y se le daba bien.<\/p>\n<p>\u201cA mucha gente le cuesta escribir una noticia. No lo entienden\u201d, dijo Sly. \u201cA \u00e9l no parec\u00eda costarle nada. Parec\u00eda tener un don natural\u201d.<\/p>\n<p>Pero Tice era un caso incipiente, y un creciente grupo de periodistas experimentados se esforzaba por pulir su energ\u00eda inagotable. David Enders, quien viaj\u00f3 con Tice por Siria durante varias semanas y colabor\u00f3 \u200b\u200bcon \u00e9l en una serie de reportajes para McClatchy, declar\u00f3 a CNN: \u201cUna de las primeras cosas que le dije fue: \u2018Si tuiteas nuestra ubicaci\u00f3n en tiempo real, no me volver\u00e1s a ver\u2019\u201d.<\/p>\n<p>Tice y Enders se integraron en una unidad rebelde y corrieron hacia Damasco, durmiendo en refugios con las botas puestas y cargando solo con lo que pod\u00edan llevar. Subieron a autobuses improvisados \u200b\u200by a la parte trasera de motocicletas, y a veces caminaron, evadiendo los bombardeos y helic\u00f3pteros del Gobierno.<\/p>\n<p>\u201cEstoy integrado con <a href=\"https:\/\/x.com\/hashtag\/FSA?src=hashtag_click\">#FSA<\/a> . Noticias de inter\u00e9s a diario\u201d, tuite\u00f3 Tice a finales de mayo. \u201cSi alguien quisiera contratarme, ser\u00eda genial. Los pr\u00e9stamos estudiantiles no se pagan solos\u201d.<\/p>\n<p>En una ocasi\u00f3n, un proyectil de tanque impact\u00f3 la fachada de una casa tras la que se refugiaban, dijo Enders. \u201cNo recuerdo el sonido\u201d, dijo. \u201cRecuerdo el impacto y el golpe contra el suelo\u201d.<\/p>\n<p>Seg\u00fan Enders, fue una acci\u00f3n m\u00e1s violenta de la que Tice hab\u00eda visto en las fuerzas armadas. Pero el par trab\u00f3 amistad por su profesi\u00f3n y sus recientes divorcios, y Tice sol\u00eda compartir historias sobre su familia. En una ocasi\u00f3n, interrumpi\u00f3 una conversaci\u00f3n entre combatientes rebeldes para decirles que su plan de emboscar un convoy gubernamental no estaba lo suficientemente bien planificado.<\/p>\n<p>Tice ganar\u00eda posteriormente el Premio George Polk de Reportaje de Guerra, junto con Enders. Pero finalmente se separaron. Las fuerzas rebeldes estaban tomando el control de los suburbios que rodean Damasco, escenario de violentos combates, y Tice quer\u00eda llegar a tiempo para presenciar el colapso del r\u00e9gimen de al-Assad.<\/p>\n<p>\u201cFue extremadamente dif\u00edcil y peligroso: el Gobierno estaba cortando las l\u00edneas de suministro y las rutas de tr\u00e1nsito\u201d, dijo Enders. En un momento dado, se escap\u00f3 de un refugio rebelde y comenz\u00f3 a caminar hacia la ciudad, hasta que los combatientes rebeldes lo rescataron y lo encerraron en una habitaci\u00f3n por su propia seguridad.<\/p>\n<p>Tice llam\u00f3 a Sly para desahogar su frustraci\u00f3n. \u201cEstaba tan convencido de que al-Assad iba a caer\u201d, dijo. \u201cY ten\u00eda que estar presente\u201d.<\/p>\n<p>Ese agosto, Tice cumpli\u00f3 31 a\u00f1os. \u201cEscuchar las bombas anuncia mi cumplea\u00f1os\u201d, escribi\u00f3 en Twitter. Estaba en un estado de reflexi\u00f3n. \u201cAfganist\u00e1n, California, Washington, Egipto, Turqu\u00eda, Siria. \u00a1Qu\u00e9 a\u00f1o tan loco!\u201d.<\/p>\n<p>El a\u00f1o termin\u00f3 con Tice relaj\u00e1ndose en una fiesta en la piscina con rebeldes de la FSA, seg\u00fan <a href=\"https:\/\/x.com\/Austin_Tice\/status\/101410823758544896\">una publicaci\u00f3n<\/a> suya de la madrugada del 12 de agosto. La m\u00fasica de Taylor Swift sonaba a todo volumen de fondo; Tice era un fan incondicional de Swift. \u201cSin duda, el mejor cumplea\u00f1os de mi vida\u201d, escribi\u00f3.<\/p>\n<p>Ese fue el \u00faltimo tuit que envi\u00f3. En Beirut, Sly recibi\u00f3 noticias de un editor del Washington Post, donde Tice hab\u00eda enviado un cuarto despacho. \u201cAustin no ha respondido a sus preguntas\u201d, le dijo el editor a Sly. \u201cSiempre lo hace. \u00bfHas tenido noticias suyas?\u201d<\/p>\n<p>Pasaron algunos d\u00edas hasta que empez\u00f3 a preocuparse. Tice hab\u00eda estado planeando descansar y tal vez estaba en camino al L\u00edbano o Turqu\u00eda para tomarse un descanso.<\/p>\n<p>Pero con el paso de los d\u00edas, se hizo evidente que Tice hab\u00eda sido capturado. Sly, Enders y los dem\u00e1s periodistas con los que Tice hab\u00eda trabado amistad durante su r\u00e1pido ascenso profesional contactaron desesperadamente a sus contactos, pero nadie sab\u00eda qu\u00e9 le hab\u00eda sucedido.<\/p>\n<p>En casa, los Tice estaban de vacaciones familiares en Gulf Shores, Alabama. Austin hab\u00eda estado en contacto durante toda su estancia en Siria \u2014sab\u00eda que sus hermanos y padres estaban preocupados por \u00e9l\u2014, as\u00ed que no tard\u00f3 mucho en notar algo extra\u00f1o.<\/p>\n<p>\u201cEs uno de esos momentos en la historia de nuestra familia donde hay un antes y un despu\u00e9s\u201d, dijo Abigail a CNN.<\/p>\n<p>Acortaron el viaje y, durante las semanas siguientes, el tel\u00e9fono de su pared en Houston no dej\u00f3 de sonar. Los periodistas se reunieron r\u00e1pidamente frente a su casa. Fue abrumador, dijo Abigail.<\/p>\n<p>Tanto Sly como Enders tuvieron pesadillas con su colega. \u201cHab\u00eda una en la que estaba en un bosque y le disparaban, y tuve que advertirle\u201d, record\u00f3 Sly.<\/p>\n<p>Luego, en septiembre, apareci\u00f3 un video en YouTube. Las <a href=\"https:\/\/www.cnn.com\/2012\/10\/01\/world\/meast\/syria-missing-journalist\">im\u00e1genes borrosas<\/a> mostraban a Tice, con los ojos vendados, semanas despu\u00e9s de su desaparici\u00f3n. Recit\u00f3 una oraci\u00f3n incoherente en \u00e1rabe y luego a\u00f1adi\u00f3, en ingl\u00e9s: \u201cOh Jes\u00fas, oh Jes\u00fas\u201d. El video aparentemente lo mostraba rodeado de militantes yihadistas, pero Estados Unidos r\u00e1pidamente concluy\u00f3 que hab\u00eda sido orquestado por fuerzas leales a alAssad.<\/p>\n<p>Marc Tice, el padre de Austin, dijo en una declaraci\u00f3n en ese momento que ver el video fue \u201cdif\u00edcil\u201d, pero \u201csaber que Austin est\u00e1 vivo y bien es reconfortante para nuestra familia\u201d.<\/p>\n<p>Desde entonces no se ha vuelto a ver ninguna imagen de Tice, pero la familia nunca perdi\u00f3 la esperanza.<\/p>\n<p>\u201cSabemos que est\u00e1 vivo y que alg\u00fan d\u00eda volver\u00e1 a casa y nuestra familia volver\u00e1 a estar junta\u201d, dijo Abigail. \u201cNunca lo hemos dudado\u201d.<\/p>\n<p>La desaparici\u00f3n de Austin transform\u00f3 a su madre, Debra, en una cruzada geopol\u00edtica de la noche a la ma\u00f1ana. Se ha reunido con sucesivos presidentes de Estados Unidos y declar\u00f3 a CNN a principios de este a\u00f1o que el equipo del presidente Trump comenz\u00f3 a contactarla poco despu\u00e9s de su victoria electoral en noviembre pasado, describiendo su trabajo en el caso como \u201cfant\u00e1stico\u201d.<\/p>\n<p>Con el paso del tiempo, la determinaci\u00f3n de su madre no ha hecho m\u00e1s que crecer. \u201cDebra Tice es una fuerza de la naturaleza\u201d, declar\u00f3 a CNN la vieja amiga de la familia. \u201cLa singular determinaci\u00f3n de esta mujer en la vida es asombrosa e inspiradora\u201d.<\/p>\n<p>Luego, en diciembre, se renov\u00f3 la esperanza. El r\u00e9gimen de al-Assad cay\u00f3 de forma dram\u00e1tica y decisiva ante los combatientes rebeldes, doce a\u00f1os despu\u00e9s de lo que Austin Tice cre\u00eda. En los d\u00edas siguientes, Debra escribi\u00f3 una carta a varios l\u00edderes, incluido el presidente de Rusia, Vladimir Putin, quienes dieron refugio al d\u00e9spota ca\u00eddo tras su huida de Siria.<\/p>\n<p>Su carta provoc\u00f3 una respuesta p\u00fablica de Putin, quien <a href=\"https:\/\/www.cnn.com\/2024\/12\/19\/europe\/russia-putin-austin-tice-comments-conference-intl\">dijo en su conferencia de prensa de fin de a\u00f1o<\/a> que hablar\u00eda con al-Assad sobre el paradero de Tice.<\/p>\n<p>\u201cNunca he visto a alguien con las agallas de enfrentarse a ning\u00fan l\u00edder mundial, a nadie, de decir las cosas que ella le ha dicho a la gente para intentar sacar a su hijo\u201d, dijo un amigo de la familia Tice.<\/p>\n<p>Trece a\u00f1os despu\u00e9s de su desaparici\u00f3n, es posible que nunca se sepa con certeza el destino de Austin Tice. Su desaparici\u00f3n a\u00fan atormenta a quienes lo conocieron. Cambi\u00f3 la forma en que Sly contrataba a trabajadores independientes: \u201cNo se puede simplemente aceptar a personas que llegan al pa\u00eds sin antecedentes ni experiencia\u201d, declar\u00f3 a CNN. Tambi\u00e9n se pregunta: \u201c\u00bfPodr\u00edamos haber hecho m\u00e1s?\u201d.<\/p>\n<p>Pero Tice sab\u00eda que estaba bailando con el peligro, y todos los que lo conoc\u00edan reconoc\u00edan una cosa: una vez que se decid\u00eda por algo, intentar hacerle cambiar de opini\u00f3n era imposible.<\/p>\n<p>\u201cTodas las personas de este pa\u00eds que luchan por su libertad se despiertan cada d\u00eda y se acuestan cada noche con la certeza de que la muerte podr\u00eda visitarlas en cualquier momento. Aceptan esa realidad como el precio de la libertad\u201d, <a href=\"https:\/\/www.mcclatchydc.com\/news\/special-reports\/article245984170.html#storylink=cpy\">escribi\u00f3 Tice<\/a> en Facebook menos de tres semanas antes de su desaparici\u00f3n.<\/p>\n<p>\u201cNo, no deseo morir, deseo vivir\u201d, continu\u00f3. \u201cVenir a Siria es lo mejor que he hecho, y es la sensaci\u00f3n m\u00e1s grande de mi vida\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cEsto ser\u00e1 un \u00e9xito rotundo o un completo desastre\u201d, escribi\u00f3 Austin Tice en mayo de 2012, en v\u00edsperas de un peligroso viaje para dar testimonio de la historia. \u201cAqu\u00ed va la cosa\u201d. Tice, un exinfante de Marina de EE.UU., de complexi\u00f3n imponente y periodista novato, se lanz\u00f3 con coraje y determinaci\u00f3n a zonas de guerra, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467804","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un periodista estadounidense desapareci\u00f3 en Siria hace 13 a\u00f1os. Su madre nunca dej\u00f3 de buscarlo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/10\/28\/periodista-estadounidense-desaparecido-siria-13-anos-busqueda-madre-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un periodista estadounidense desapareci\u00f3 en Siria hace 13 a\u00f1os. Su madre nunca dej\u00f3 de buscarlo - Noticias\" \/>\n<meta property=\"og:description\" content=\"\u201cEsto ser\u00e1 un \u00e9xito rotundo o un completo desastre\u201d, escribi\u00f3 Austin Tice en mayo de 2012, en v\u00edsperas de un peligroso viaje para dar testimonio de la historia. \u201cAqu\u00ed va la cosa\u201d. Tice, un exinfante de Marina de EE.UU., de complexi\u00f3n imponente y periodista novato, se lanz\u00f3 con coraje y determinaci\u00f3n a zonas de guerra, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/10\/28\/periodista-estadounidense-desaparecido-siria-13-anos-busqueda-madre-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-28T12:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/28\/periodista-estadounidense-desaparecido-siria-13-anos-busqueda-madre-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/28\/periodista-estadounidense-desaparecido-siria-13-anos-busqueda-madre-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un periodista estadounidense desapareci\u00f3 en Siria hace 13 a\u00f1os. Su madre nunca dej\u00f3 de buscarlo\",\"datePublished\":\"2025-10-28T12:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/28\/periodista-estadounidense-desaparecido-siria-13-anos-busqueda-madre-trax\/\"},\"wordCount\":2819,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/28\/periodista-estadounidense-desaparecido-siria-13-anos-busqueda-madre-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/28\/periodista-estadounidense-desaparecido-siria-13-anos-busqueda-madre-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/10\/28\/periodista-estadounidense-desaparecido-siria-13-anos-busqueda-madre-trax\/\",\"name\":\"Un periodista estadounidense desapareci\u00f3 en Siria hace 13 a\u00f1os. Su madre nunca dej\u00f3 de buscarlo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-10-28T12:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/28\/periodista-estadounidense-desaparecido-siria-13-anos-busqueda-madre-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/28\/periodista-estadounidense-desaparecido-siria-13-anos-busqueda-madre-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/28\/periodista-estadounidense-desaparecido-siria-13-anos-busqueda-madre-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un periodista estadounidense desapareci\u00f3 en Siria hace 13 a\u00f1os. Su madre nunca dej\u00f3 de buscarlo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un periodista estadounidense desapareci\u00f3 en Siria hace 13 a\u00f1os. Su madre nunca dej\u00f3 de buscarlo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/10\/28\/periodista-estadounidense-desaparecido-siria-13-anos-busqueda-madre-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Un periodista estadounidense desapareci\u00f3 en Siria hace 13 a\u00f1os. Su madre nunca dej\u00f3 de buscarlo - Noticias","og_description":"\u201cEsto ser\u00e1 un \u00e9xito rotundo o un completo desastre\u201d, escribi\u00f3 Austin Tice en mayo de 2012, en v\u00edsperas de un peligroso viaje para dar testimonio de la historia. \u201cAqu\u00ed va la cosa\u201d. Tice, un exinfante de Marina de EE.UU., de complexi\u00f3n imponente y periodista novato, se lanz\u00f3 con coraje y determinaci\u00f3n a zonas de guerra, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/10\/28\/periodista-estadounidense-desaparecido-siria-13-anos-busqueda-madre-trax\/","og_site_name":"Noticias","article_published_time":"2025-10-28T12:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"14 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/10\/28\/periodista-estadounidense-desaparecido-siria-13-anos-busqueda-madre-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/10\/28\/periodista-estadounidense-desaparecido-siria-13-anos-busqueda-madre-trax\/"},"author":{"name":"","@id":""},"headline":"Un periodista estadounidense desapareci\u00f3 en Siria hace 13 a\u00f1os. Su madre nunca dej\u00f3 de buscarlo","datePublished":"2025-10-28T12:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/10\/28\/periodista-estadounidense-desaparecido-siria-13-anos-busqueda-madre-trax\/"},"wordCount":2819,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/10\/28\/periodista-estadounidense-desaparecido-siria-13-anos-busqueda-madre-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/10\/28\/periodista-estadounidense-desaparecido-siria-13-anos-busqueda-madre-trax\/","url":"https:\/\/noticiasya.com\/2025\/10\/28\/periodista-estadounidense-desaparecido-siria-13-anos-busqueda-madre-trax\/","name":"Un periodista estadounidense desapareci\u00f3 en Siria hace 13 a\u00f1os. Su madre nunca dej\u00f3 de buscarlo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-10-28T12:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/10\/28\/periodista-estadounidense-desaparecido-siria-13-anos-busqueda-madre-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/10\/28\/periodista-estadounidense-desaparecido-siria-13-anos-busqueda-madre-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/10\/28\/periodista-estadounidense-desaparecido-siria-13-anos-busqueda-madre-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un periodista estadounidense desapareci\u00f3 en Siria hace 13 a\u00f1os. Su madre nunca dej\u00f3 de buscarlo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/28\/periodista-estadounidense-desaparecido-siria-13-anos-busqueda-madre-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un periodista estadounidense desapareci\u00f3 en Siria hace 13 a\u00f1os. Su madre nunca dej\u00f3 de buscarlo","url":"http:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/28\/periodista-estadounidense-desaparecido-siria-13-anos-busqueda-madre-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/28\/periodista-estadounidense-desaparecido-siria-13-anos-busqueda-madre-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-10-28T12:03:49Z","datePublished":"2025-10-28T12:03:49Z","dateModified":"2025-10-28T12:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un periodista estadounidense desapareci\\u00f3 en Siria hace 13 a\\u00f1os. Su madre nunca dej\\u00f3 de buscarlo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2025\\\/10\\\/28\\\/periodista-estadounidense-desaparecido-siria-13-anos-busqueda-madre-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2025\\\/10\\\/28\\\/periodista-estadounidense-desaparecido-siria-13-anos-busqueda-madre-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-10-28T12:03:49Z\",\"datePublished\":\"2025-10-28T12:03:49Z\",\"dateModified\":\"2025-10-28T12:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1456520,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/12\/12\/estadounidense-desaparecido-siria-peregrino-trax\/","url_meta":{"origin":1467804,"position":0},"title":"Estadounidense desaparecido que fue hallado en Siria dice que estuvo en prisi\u00f3n tras llegar al pa\u00eds como peregrino","author":"","date":"diciembre 12, 2024","format":false,"excerpt":"Un hombre estadounidense que estaba desaparecido ha sido encontrado en Siria, donde dice que estuvo en prisi\u00f3n durante meses despu\u00e9s de entrar al pa\u00eds como peregrino.Travis Timmerman habl\u00f3 con varios medios este jueves, despu\u00e9s de que un grupo de lugare\u00f1os lo vieran caminando descalzo por las calles del sur de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456811,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/12\/20\/eeuu-elimina-recompensa-lider-rebelde-sirio-trax\/","url_meta":{"origin":1467804,"position":1},"title":"EE.UU. retira una antigua recompensa de US$ 10 millones a cambio del l\u00edder rebelde sirio","author":"","date":"diciembre 20, 2024","format":false,"excerpt":"Estados Unidos elimin\u00f3 la antigua recompensa de US$ 10 millones por el l\u00edder de facto de Siria tras una reuni\u00f3n de alto nivel de una delegaci\u00f3n estadounidense con el exyihadista este viernes.La subsecretaria de Estado para Asuntos del Cercano Oriente (NEA, por sus siglas en ingl\u00e9s), Barbara Leaf, una de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456597,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/12\/14\/ee-uu-contacto-grupo-rebelde-sirio-blinken-trax\/","url_meta":{"origin":1467804,"position":2},"title":"EE.UU. ha tenido contacto con el grupo rebelde sirio detr\u00e1s de la ca\u00edda del r\u00e9gimen de Assad, dice Blinken","author":"","date":"diciembre 14, 2024","format":false,"excerpt":"Estados Unidos ha tenido contacto directo con Hayat Tahrir al-Sham, el grupo rebelde sirio que ahora tiene el control de facto del pa\u00eds, dijo este s\u00e1bado el secretario de Estado, Antony Blinken.La primera confirmaci\u00f3n p\u00fablica de la interacci\u00f3n directa con el grupo designado como terrorista por EE.UU., conocido como HTS\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456787,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/12\/20\/soldados-estados-unidos-siria-damasco-trax\/","url_meta":{"origin":1467804,"position":3},"title":"EE.UU. admite que tiene el doble de soldados en Siria mientras Biden env\u00eda funcionarios a Damasco","author":"","date":"diciembre 20, 2024","format":false,"excerpt":"El Pent\u00e1gono anunci\u00f3 que EE.UU. tiene actualmente \u201caproximadamente 2.000\u201d soldados en Siria, m\u00e1s del doble del n\u00famero previamente revelado de 900, dijo un portavoz del Departamento de Defensa en una rueda de prensa de este jueves.\u201cHay consideraciones de seguridad diplom\u00e1ticas y operativas a menudo con nuestros despliegues y algunos de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456405,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/12\/09\/analisis-abu-mohammad-al-jolani-lider-siria-trax\/","url_meta":{"origin":1467804,"position":4},"title":"AN\u00c1LISIS | Qui\u00e9n es y qu\u00e9 busca Abu Mohammad al-Jolani, l\u00edder de los rebeldes sirios","author":"","date":"diciembre 9, 2024","format":false,"excerpt":"El Departamento de Estado de Estados Unidos anunci\u00f3 una recompensa de hasta US$ 10 millones por informaci\u00f3n que conduzca a la captura de Abu Mohammad al-Jolani, a quien la agencia design\u00f3 por primera vez como terrorista hace m\u00e1s de una d\u00e9cada, diciendo que su grupo hab\u00eda llevado a cabo \u201cm\u00faltiples\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455078,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/10\/14\/periodista-ucraniana-victoria-roshchyna-muere-detencion-rusa-kyiv-trax\/","url_meta":{"origin":1467804,"position":5},"title":"La periodista ucraniana Victoria Roshchyna muri\u00f3 bajo detenci\u00f3n rusa, seg\u00fan Kyiv","author":"","date":"octubre 14, 2024","format":false,"excerpt":"(CNN) -- La periodista ucraniana Victoria Roshchyna, quien desapareci\u00f3 en una zona ocupada de su pa\u00eds, muri\u00f3 bajo detenci\u00f3n rusa el mes pasado, informaron autoridades de Ucrania esta semana.Ahora puedes seguirnos en\u00a0WhatsApp ChannelRoshchyna, de 27 a\u00f1os, desapareci\u00f3 en agosto del a\u00f1o pasado durante un viaje informativo a una zona de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1467804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1467804"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1467804\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1467804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1467804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1467804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}