{"id":1467858,"date":"2025-10-29T19:03:51","date_gmt":"2025-10-30T02:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/10\/29\/ejecutivos-aviacion-sorpresa-incertidumbre-eeuu-suspender-rutas-aereas-orix\/"},"modified":"2025-10-29T19:03:51","modified_gmt":"2025-10-30T02:03:51","slug":"ejecutivos-aviacion-sorpresa-incertidumbre-eeuu-suspender-rutas-aereas-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/29\/ejecutivos-aviacion-sorpresa-incertidumbre-eeuu-suspender-rutas-aereas-orix\/","title":{"rendered":"Ejecutivos de aerol\u00edneas de M\u00e9xico muestran sorpresa e incertidumbre ante la decisi\u00f3n de EE.UU. de suspender rutas a\u00e9reas"},"content":{"rendered":"<p>Ejecutivos de la aviaci\u00f3n de M\u00e9xico consultados por CNN recibieron este mi\u00e9rcoles con sorpresa y frustraci\u00f3n el anuncio del Departamento de Transporte de EE.UU. sobre<a href=\"https:\/\/cnnespanol.cnn.com\/2025\/10\/29\/mexico\/sheinbaum-en-desacuerdo-con-la-decision-de-ee-uu-de-cancelar-13-rutas-aereas-y-los-vuelos-desde-el-aeropuerto-construido-por-lopez-obrador\"> la revocaci\u00f3n de 13 rutas existentes y planeadas de aerol\u00edneas mexicanas<\/a> desde los aeropuertos Internacional de la Ciudad de M\u00e9xico (AICM) y el Felipe \u00c1ngeles (AIFA).<\/p>\n<p>Una acci\u00f3n sin precedentes, dijeron fuentes del sector que pidieron no ser identificadas sobre esta medida que, seg\u00fan el Departamento del Transporte estadounidense, se debe al incumplimiento de las obligaciones de M\u00e9xico en el Acuerdo de Transporte A\u00e9reo firmado con Estados Unidos en 2015.<\/p>\n<p>Quedaron desaprobadas la ruta programada de Aerom\u00e9xico, que iniciar\u00eda este 29 de octubre hacia Puerto Rico, y las que present\u00f3 para operar desde el Aeropuerto Internacional Felipe \u00c1ngeles (AIFA) hacia Houston y hacia McAllen.<\/p>\n<p>El Departamento del Transporte rechaz\u00f3 tambi\u00e9n, hasta nuevo aviso, la ruta de la aerol\u00ednea Volaris entre Ciudad de M\u00e9xico y la terminal de Newark programada para iniciar el pr\u00f3ximo 2 de noviembre.<\/p>\n<p>En el caso de Viva Aerobus, el Departamento de Transporte desaprob\u00f3 las rutas programadas para comenzar en noviembre y diciembre entre el AIFA y Austin, Nueva York (JFK), Chicago, Dallas\/Ft. Worth, Denver, Houston, Los Angeles, Miami y Orlando.<\/p>\n<p>La desaprobaci\u00f3n de estos vuelos, dice, \u201ces la respuesta apropiada a la prolongada y generalizada falta de cumplimiento del Gobierno de M\u00e9xico con el acuerdo y el da\u00f1o colectivo resultante sobre las operadoras estadounidense\u201d, seg\u00fan el documento de notificaci\u00f3n que fue entregado a las aerol\u00edneas y del cual CNN tiene copia.<\/p>\n<p>En otra notificaci\u00f3n por separado, el Departamento de Transporte de EE.UU. tambi\u00e9n cancel\u00f3 los servicios combinados \u2014en los que las aerol\u00edneas transportan pasajeros y carga\u2014 entre Estados Unidos y el AIFA, al tiempo que suspendi\u00f3 la expansi\u00f3n de estos servicios para las aerol\u00edneas mexicanas entre Estados Unidos y el AICM.<\/p>\n<p>Enrique Beltranena, CEO de Volaris, dijo a CNN que se estudian a detalle estas \u00f3rdenes. \u201cEstamos en comunicaci\u00f3n con las autoridades mexicanas esperando su reacci\u00f3n. Volaris en el corto plazo solo tiene en riesgo una ruta comercial de pasajeros y no tenemos mayor impacto en carga\u201d, dijo.<\/p>\n<p>Por su lado, la Asociaci\u00f3n Internacional de Transporte A\u00e9reo (IATA) y la Asociaci\u00f3n Latinoamericana y del Caribe de Transporte A\u00e9reo (ALTA) dijeron que est\u00e1n \u201cmonitoreado la situaci\u00f3n, analizando el impacto al sector. A ra\u00edz de las conversaciones que los ejecutivos de aviaci\u00f3n sostengan con la presidenta de M\u00e9xico, se decidir\u00e1 el siguiente paso. El di\u00e1logo entre los dos pa\u00edses es cr\u00edtico para encontrar una soluci\u00f3n que beneficie a ambas partes y al sector\u201d.<\/p>\n<p>En tanto, Viva Aerobus dijo: \u201cEstamos evaluando cuidadosamente el impacto de esta orden en nuestras operaciones y en los servicios de transporte para todos nuestros usuarios con el fin de informarles oportunamente y de minimizar afectaciones a los mismos. La decisi\u00f3n unilateral anunciada por el gobierno de Estados Unidos, y la poca antelaci\u00f3n con la que emiten esta orden, tendr\u00e1 un impacto en miles de pasajeros norte americanos y mexicanos en plena temporada vacacional. Confiamos en el dialogo entre las autoridades de nuestro Gobierno con su contraparte en Estados Unidos para buscar una soluci\u00f3n razonable a este conflicto, y minimizar las afectaciones a los pasajeros\u201d.<\/p>\n<p>Seg\u00fan marcan los documentos del Departamento de Transporte estadounidense, las decisiones tomadas durante el gobierno de Andr\u00e9s Manuel L\u00f3pez Obrador son la causa de este desencuentro. Una de ellas, relacionada con el Aeropuerto Internacional Felipe \u00c1ngeles, el pol\u00e9mico desarrollo que quiso construir para sustituir el Nuevo Aeropuerto Internacional de M\u00e9xico, en Texcoco, y al que Lopez Obrador calificaba como una \u201cobra fara\u00f3nica\u201d.<\/p>\n<p>Como candidato a la presidencia, L\u00f3pez Obrador hab\u00eda criticado el proyecto y, en su lugar, propuso adaptar la Base Militar de Santa Luc\u00eda para vuelos civiles. Como candidato, anunci\u00f3 que cancelar\u00eda el proyecto en Texcoco el 29 de octubre de 2018, despu\u00e9s de una controvertida consulta organizada por su equipo.<\/p>\n<p>Las obras del AIFA comenzaron el 17 de octubre de 2019, a cargo de la Secretar\u00eda de la Defensa Nacional. El proyecto quedo inaugurado el 21 de marzo de 2022. Pero llevar pasajeros y carga demostr\u00f3 ser un importante desaf\u00edo inicial.<\/p>\n<p>El Gobierno de Trump insiste que los principales asuntos de preocupaci\u00f3n se relacionan con el decreto presidencial que el gobierno mexicano emiti\u00f3 el 2 de febrero de 2023, prohibiendo todas las operaciones de carga en el AICM. Eso oblig\u00f3 a los operadores a cesar sus operaciones en esa terminal y transferirlas al AIFA. El 1\u00b0 de septiembre de 2023, dice, las tres operadoras de Estados Unidos que ofrec\u00edan servicios de carga finalizaron sus operaciones en el AICM y las trasladaron al AIFA.<\/p>\n<p>El Departamento de Transporte asegur\u00f3 que, antes de entrar en vigor, comunic\u00f3 a las autoridades de M\u00e9xico que la prohibici\u00f3n ser\u00e1 inconsistente con las obligaciones del pa\u00eds bajo el Acuerdo de 2015 y que expres\u00f3 repetidamente su oposici\u00f3n al decreto mediante cartas a la Secretaria de Comunicaciones y Transportes, consultas t\u00e9cnicas y hasta una reuni\u00f3n con L\u00f3pez Obrador, pidiendo rescindir el texto y restablecer la capacidad de todos los operadores de carga estadounidenses para funcionar en el AICM.<\/p>\n<p>En el documento enviado a las aerol\u00edneas dice: \u201cEl Departamento a\u00fan est\u00e1 alarmado por el rechazo de la SCT y el gobierno mexicano a rescindir el decreto para corregir el efecto negativo que ha tenido sobre los servicios de carga de Estados Unidos. Parece haber cero potencial en el horizonte para un cumplimiento completo del acuerdo de 2015 del gobierno de M\u00e9xico\u201d.<\/p>\n<p>Una segunda molestia de Estados Unidos tiene que ver con los slots en el AICM.<\/p>\n<p>Record\u00f3 que en agosto de 2022, mediante una resoluci\u00f3n y argumentando saturaci\u00f3n de la terminal, se confiscaron los slots de American Airlines, Delta y United,Aeromexico, Viva Aerob\u00fas y Volaris, para reducir operaciones desde 61 a 52 por hora para labores de construcci\u00f3n temporales, \u201csin que hasta ahora haya sucedido nada\u201d.<\/p>\n<p>Un a\u00f1o despu\u00e9s, el gobierno mexicano activ\u00f3 una nueva reducci\u00f3n de 52 a 43 operaciones por hora para la temporada de invierno 2023\/2024.<\/p>\n<p>Al respecto, el Departamento de Transporte explic\u00f3 que, desde el inicio el gobierno de Trump, expres\u00f3 sus preocupaciones al gobierno de M\u00e9xico por las medidas y se pidi\u00f3 una copia del an\u00e1lisis t\u00e9cnico para explicar qu\u00e9 fue lo que llevo a declarar al AICM como una terminal saturada.<\/p>\n<p>Al respecto dijo: \u201cEn este sentido, es notable que esas reducciones s\u00fabitas de capacidad en el AICM fueron implementadas cuando el gobierno activamente buscaba aumentar el tr\u00e1fico en Santa Luc\u00eda que, pese a los esfuerzos de la administraci\u00f3n de L\u00f3pez Obrador, ten\u00eda problemas para atraer servicios\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ejecutivos de la aviaci\u00f3n de M\u00e9xico consultados por CNN recibieron este mi\u00e9rcoles con sorpresa y frustraci\u00f3n el anuncio del Departamento de Transporte de EE.UU. sobre la revocaci\u00f3n de 13 rutas existentes y planeadas de aerol\u00edneas mexicanas desde los aeropuertos Internacional de la Ciudad de M\u00e9xico (AICM) y el Felipe \u00c1ngeles (AIFA). Una acci\u00f3n sin precedentes, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467858","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ejecutivos de aerol\u00edneas de M\u00e9xico muestran sorpresa e incertidumbre ante la decisi\u00f3n de EE.UU. de suspender rutas a\u00e9reas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/10\/29\/ejecutivos-aviacion-sorpresa-incertidumbre-eeuu-suspender-rutas-aereas-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ejecutivos de aerol\u00edneas de M\u00e9xico muestran sorpresa e incertidumbre ante la decisi\u00f3n de EE.UU. de suspender rutas a\u00e9reas - Noticias\" \/>\n<meta property=\"og:description\" content=\"Ejecutivos de la aviaci\u00f3n de M\u00e9xico consultados por CNN recibieron este mi\u00e9rcoles con sorpresa y frustraci\u00f3n el anuncio del Departamento de Transporte de EE.UU. sobre la revocaci\u00f3n de 13 rutas existentes y planeadas de aerol\u00edneas mexicanas desde los aeropuertos Internacional de la Ciudad de M\u00e9xico (AICM) y el Felipe \u00c1ngeles (AIFA). Una acci\u00f3n sin precedentes, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/10\/29\/ejecutivos-aviacion-sorpresa-incertidumbre-eeuu-suspender-rutas-aereas-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-30T02:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/29\/ejecutivos-aviacion-sorpresa-incertidumbre-eeuu-suspender-rutas-aereas-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/29\/ejecutivos-aviacion-sorpresa-incertidumbre-eeuu-suspender-rutas-aereas-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Ejecutivos de aerol\u00edneas de M\u00e9xico muestran sorpresa e incertidumbre ante la decisi\u00f3n de EE.UU. de suspender rutas a\u00e9reas\",\"datePublished\":\"2025-10-30T02:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/29\/ejecutivos-aviacion-sorpresa-incertidumbre-eeuu-suspender-rutas-aereas-orix\/\"},\"wordCount\":1190,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/29\/ejecutivos-aviacion-sorpresa-incertidumbre-eeuu-suspender-rutas-aereas-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/29\/ejecutivos-aviacion-sorpresa-incertidumbre-eeuu-suspender-rutas-aereas-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/10\/29\/ejecutivos-aviacion-sorpresa-incertidumbre-eeuu-suspender-rutas-aereas-orix\/\",\"name\":\"Ejecutivos de aerol\u00edneas de M\u00e9xico muestran sorpresa e incertidumbre ante la decisi\u00f3n de EE.UU. de suspender rutas a\u00e9reas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-10-30T02:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/29\/ejecutivos-aviacion-sorpresa-incertidumbre-eeuu-suspender-rutas-aereas-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/29\/ejecutivos-aviacion-sorpresa-incertidumbre-eeuu-suspender-rutas-aereas-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/29\/ejecutivos-aviacion-sorpresa-incertidumbre-eeuu-suspender-rutas-aereas-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ejecutivos de aerol\u00edneas de M\u00e9xico muestran sorpresa e incertidumbre ante la decisi\u00f3n de EE.UU. de suspender rutas a\u00e9reas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ejecutivos de aerol\u00edneas de M\u00e9xico muestran sorpresa e incertidumbre ante la decisi\u00f3n de EE.UU. de suspender rutas a\u00e9reas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/10\/29\/ejecutivos-aviacion-sorpresa-incertidumbre-eeuu-suspender-rutas-aereas-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Ejecutivos de aerol\u00edneas de M\u00e9xico muestran sorpresa e incertidumbre ante la decisi\u00f3n de EE.UU. de suspender rutas a\u00e9reas - Noticias","og_description":"Ejecutivos de la aviaci\u00f3n de M\u00e9xico consultados por CNN recibieron este mi\u00e9rcoles con sorpresa y frustraci\u00f3n el anuncio del Departamento de Transporte de EE.UU. sobre la revocaci\u00f3n de 13 rutas existentes y planeadas de aerol\u00edneas mexicanas desde los aeropuertos Internacional de la Ciudad de M\u00e9xico (AICM) y el Felipe \u00c1ngeles (AIFA). Una acci\u00f3n sin precedentes, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/10\/29\/ejecutivos-aviacion-sorpresa-incertidumbre-eeuu-suspender-rutas-aereas-orix\/","og_site_name":"Noticias","article_published_time":"2025-10-30T02:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/10\/29\/ejecutivos-aviacion-sorpresa-incertidumbre-eeuu-suspender-rutas-aereas-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/10\/29\/ejecutivos-aviacion-sorpresa-incertidumbre-eeuu-suspender-rutas-aereas-orix\/"},"author":{"name":"","@id":""},"headline":"Ejecutivos de aerol\u00edneas de M\u00e9xico muestran sorpresa e incertidumbre ante la decisi\u00f3n de EE.UU. de suspender rutas a\u00e9reas","datePublished":"2025-10-30T02:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/10\/29\/ejecutivos-aviacion-sorpresa-incertidumbre-eeuu-suspender-rutas-aereas-orix\/"},"wordCount":1190,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/10\/29\/ejecutivos-aviacion-sorpresa-incertidumbre-eeuu-suspender-rutas-aereas-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/10\/29\/ejecutivos-aviacion-sorpresa-incertidumbre-eeuu-suspender-rutas-aereas-orix\/","url":"https:\/\/noticiasya.com\/2025\/10\/29\/ejecutivos-aviacion-sorpresa-incertidumbre-eeuu-suspender-rutas-aereas-orix\/","name":"Ejecutivos de aerol\u00edneas de M\u00e9xico muestran sorpresa e incertidumbre ante la decisi\u00f3n de EE.UU. de suspender rutas a\u00e9reas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-10-30T02:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/10\/29\/ejecutivos-aviacion-sorpresa-incertidumbre-eeuu-suspender-rutas-aereas-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/10\/29\/ejecutivos-aviacion-sorpresa-incertidumbre-eeuu-suspender-rutas-aereas-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/10\/29\/ejecutivos-aviacion-sorpresa-incertidumbre-eeuu-suspender-rutas-aereas-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Ejecutivos de aerol\u00edneas de M\u00e9xico muestran sorpresa e incertidumbre ante la decisi\u00f3n de EE.UU. de suspender rutas a\u00e9reas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/29\/ejecutivos-aviacion-sorpresa-incertidumbre-eeuu-suspender-rutas-aereas-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Ejecutivos de aerol\u00edneas de M\u00e9xico muestran sorpresa e incertidumbre ante la decisi\u00f3n de EE.UU. de suspender rutas a\u00e9reas","url":"http:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/29\/ejecutivos-aviacion-sorpresa-incertidumbre-eeuu-suspender-rutas-aereas-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/29\/ejecutivos-aviacion-sorpresa-incertidumbre-eeuu-suspender-rutas-aereas-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-10-30T02:03:51Z","datePublished":"2025-10-30T02:03:51Z","dateModified":"2025-10-30T02:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Ejecutivos de aerol\\u00edneas de M\\u00e9xico muestran sorpresa e incertidumbre ante la decisi\\u00f3n de EE.UU. de suspender rutas a\\u00e9reas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2025\\\/10\\\/29\\\/ejecutivos-aviacion-sorpresa-incertidumbre-eeuu-suspender-rutas-aereas-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2025\\\/10\\\/29\\\/ejecutivos-aviacion-sorpresa-incertidumbre-eeuu-suspender-rutas-aereas-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-10-30T02:03:51Z\",\"datePublished\":\"2025-10-30T02:03:51Z\",\"dateModified\":\"2025-10-30T02:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1467842,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/29\/sheinbaum-en-desacuerdo-con-la-decision-de-ee-uu-de-cancelar-13-rutas-aereas-y-los-vuelos-desde-el-aeropuerto-construido-por-lopez-obrador\/","url_meta":{"origin":1467858,"position":0},"title":"Sheinbaum cuestiona la decisi\u00f3n de EE.UU. de cancelar 13 rutas a\u00e9reas y los vuelos desde el aeropuerto construido por AMLO","author":"","date":"octubre 29, 2025","format":false,"excerpt":"La presidenta de M\u00e9xico, Claudia Sheinbaum, expres\u00f3 su desacuerdo con la decisi\u00f3n del Departamento de Transporte de Estados Unidos de revocar la aprobaci\u00f3n de 13 rutas que hab\u00eda otorgado a aerol\u00edneas mexicanas hacia ese pa\u00eds, as\u00ed como la cancelaci\u00f3n de los vuelos de pasajeros y de carga de estas empresas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464676,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/07\/19\/ee-uu-rechazar-vuelos-acuerdo-de-aviacion-orix\/","url_meta":{"origin":1467858,"position":1},"title":"EE.UU. dice que podr\u00eda rechazar vuelos desde M\u00e9xico si el pa\u00eds incumple acuerdo de aviaci\u00f3n","author":"","date":"julio 19, 2025","format":false,"excerpt":"El Departamento de Transporte de Estados Unidos dijo este s\u00e1bado que podr\u00eda rechazar vuelos procedentes de M\u00e9xico si el pa\u00eds incumple con un acuerdo bilateral de aviaci\u00f3n establecido en 2015.Mediante un comunicado, el Departamento acus\u00f3 a M\u00e9xico de no cumplir con el acuerdo desde 2022 cuando, afirma, el pa\u00eds rescindi\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466510,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/09\/16\/aeromexico-lamenta-eeyy-retiro-inmunidad-antimonopolio-delta-efe\/","url_meta":{"origin":1467858,"position":2},"title":"Aerom\u00e9xico lamenta el retiro de EE.UU. de la inmunidad antimonopolio de su alianza con Delta","author":"","date":"septiembre 16, 2025","format":false,"excerpt":"La aerol\u00ednea Aerom\u00e9xico manifest\u00f3 este lunes su inconformidad ante el anuncio de Estados Unidos de poner fin a la inmunidad antimonopolio de su alianza con la estadounidense Delta Air Lines, a partir del 1 de enero de 2026.\u201cAerom\u00e9xico lamenta esta decisi\u00f3n, la cual pasa por alto los beneficios que la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448944,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/05\/06\/estados-unidos-sanciones-ejecutivos-empresas-colombianas-transporte-migrantes-orix\/","url_meta":{"origin":1467858,"position":3},"title":"EE.UU. anuncia sanciones a ejecutivos de empresas mar\u00edtimas colombianas por presunto transporte de migrantes","author":"","date":"mayo 6, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El Departamento de Estado de Estados Unidos anunci\u00f3 este lunes que ha impuesto restricciones de visa a ejecutivos de varias empresas mar\u00edtimas colombianas a las que se\u00f1al\u00f3 de estar utilizando sus compa\u00f1\u00edas para transportar a inmigrantes a ese pa\u00eds.En un comunicado que no identifica a las empresas ni\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468823,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/11\/29\/eeuu-venezuela-crisis-aerea-tension-mas-aislada-orix\/","url_meta":{"origin":1467858,"position":4},"title":"Por la tensi\u00f3n con EE.UU., Venezuela enfrenta una crisis a\u00e9rea y queda a\u00fan m\u00e1s aislada","author":"","date":"noviembre 29, 2025","format":false,"excerpt":"Mientras recrudece la tensi\u00f3n por el despliegue militar de Estados Unidos en el Caribe, se complica cada vez m\u00e1s la situaci\u00f3n relacionada con el espacio a\u00e9reo de Venezuela.Este s\u00e1bado, el presidente de Estados Unidos, Donald Trump, pidi\u00f3 a aerol\u00edneas, pilotos y redes criminales que consideraran el \u201cespacio a\u00e9reo sobre y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445856,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/02\/21\/american-airlines-sube-precios-equipaje-registrado-trax\/","url_meta":{"origin":1467858,"position":5},"title":"American Airlines sube los precios para el equipaje registrado","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN) -- Registrar el equipaje en American Airlines ahora te costar\u00e1 m\u00e1s que en cualquier otra aerol\u00ednea principal de Estados Unidos.La compa\u00f1\u00eda anunci\u00f3 este martes que el precio de la primera maleta registrada o facturada en la mayor\u00eda de los vuelos aumentar\u00e1 a US$ 40 para los clientes que no\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1467858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1467858"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1467858\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1467858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1467858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1467858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}