{"id":1467861,"date":"2025-10-30T00:03:57","date_gmt":"2025-10-30T07:03:57","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/10\/30\/trump-reduccion-aranceles-productos-chinos-trax\/"},"modified":"2025-10-30T00:03:57","modified_gmt":"2025-10-30T07:03:57","slug":"trump-reduccion-aranceles-productos-chinos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/30\/trump-reduccion-aranceles-productos-chinos-trax\/","title":{"rendered":"Trump reduce los aranceles para los productos chinos al 47 %"},"content":{"rendered":"<p>Estados Unidos rebaj\u00f3 el arancel general sobre los productos chinos al 47 %, seg\u00fan anunci\u00f3 el presidente Trump el jueves, tras los avances logrados con China en materia de <a href=\"https:\/\/www.cnn.com\/politics\/live-news\/trump-south-korea-china-xi-government-shutdown-10-29-25?post-id=cmhcwxh7l001v3b6nzcpc3hev\">importaciones de soja<\/a>, <a href=\"https:\/\/www.cnn.com\/politics\/live-news\/trump-south-korea-china-xi-government-shutdown-10-29-25?post-id=cmhcxel1a000l3b6n3uwx91xt\">tierras raras<\/a> y fentanilo.<\/p>\n<p>\u201cLo hemos reducido\u2026 Ya hemos visto las medidas tomadas contra <a href=\"https:\/\/www.cnn.com\/politics\/live-news\/trump-south-korea-china-xi-government-shutdown-10-29-25?post-id=cmhcxn16n00253b6nfgj3tzvn\">el fentanilo<\/a>, y est\u00e1n tomando medidas muy en\u00e9rgicas. As\u00ed que lo hemos reducido al 10 %\u201d, dijo Trump a bordo del Air Force One tras reunirse con el l\u00edder de China, Xi Jinping, en Corea del Sur.<\/p>\n<p>Trump a\u00f1adi\u00f3 que la reducci\u00f3n entrar\u00eda en vigor de inmediato, lo que significa que el arancel general para las exportaciones chinas a Estados Unidos bajar\u00eda del 57 % al 47 %.<\/p>\n<p>El representante comercial de Estados Unidos, Jamieson Greer, quien acompa\u00f1aba a Trump durante su rueda de prensa, afirm\u00f3 que algunos productos espec\u00edficos seguir\u00edan sujetos a aranceles m\u00e1s elevados. \u201cPara algunos productos concretos, el arancel podr\u00eda llegar al 100 %. Pero, en general, se sit\u00faa en torno al 45 o 47 %\u201d, declar\u00f3 Greer.<\/p>\n<p>Durante meses, la econom\u00eda mundial se ha visto sacudida por una escalada rec\u00edproca de aranceles, controles a las exportaciones y otras sanciones, mientras Estados Unidos y China han oscilado entre la escalada y la negociaci\u00f3n en su guerra comercial.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estados Unidos rebaj\u00f3 el arancel general sobre los productos chinos al 47 %, seg\u00fan anunci\u00f3 el presidente Trump el jueves, tras los avances logrados con China en materia de importaciones de soja, tierras raras y fentanilo. \u201cLo hemos reducido\u2026 Ya hemos visto las medidas tomadas contra el fentanilo, y est\u00e1n tomando medidas muy en\u00e9rgicas. As\u00ed [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467861","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump reduce los aranceles para los productos chinos al 47 % - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/10\/30\/trump-reduccion-aranceles-productos-chinos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump reduce los aranceles para los productos chinos al 47 % - Noticias\" \/>\n<meta property=\"og:description\" content=\"Estados Unidos rebaj\u00f3 el arancel general sobre los productos chinos al 47 %, seg\u00fan anunci\u00f3 el presidente Trump el jueves, tras los avances logrados con China en materia de importaciones de soja, tierras raras y fentanilo. \u201cLo hemos reducido\u2026 Ya hemos visto las medidas tomadas contra el fentanilo, y est\u00e1n tomando medidas muy en\u00e9rgicas. As\u00ed [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/10\/30\/trump-reduccion-aranceles-productos-chinos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-30T07:03:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/30\/trump-reduccion-aranceles-productos-chinos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/30\/trump-reduccion-aranceles-productos-chinos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump reduce los aranceles para los productos chinos al 47 %\",\"datePublished\":\"2025-10-30T07:03:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/30\/trump-reduccion-aranceles-productos-chinos-trax\/\"},\"wordCount\":235,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/30\/trump-reduccion-aranceles-productos-chinos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/30\/trump-reduccion-aranceles-productos-chinos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/10\/30\/trump-reduccion-aranceles-productos-chinos-trax\/\",\"name\":\"Trump reduce los aranceles para los productos chinos al 47 % - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-10-30T07:03:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/30\/trump-reduccion-aranceles-productos-chinos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/30\/trump-reduccion-aranceles-productos-chinos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/30\/trump-reduccion-aranceles-productos-chinos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump reduce los aranceles para los productos chinos al 47 %\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump reduce los aranceles para los productos chinos al 47 % - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/10\/30\/trump-reduccion-aranceles-productos-chinos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trump reduce los aranceles para los productos chinos al 47 % - Noticias","og_description":"Estados Unidos rebaj\u00f3 el arancel general sobre los productos chinos al 47 %, seg\u00fan anunci\u00f3 el presidente Trump el jueves, tras los avances logrados con China en materia de importaciones de soja, tierras raras y fentanilo. \u201cLo hemos reducido\u2026 Ya hemos visto las medidas tomadas contra el fentanilo, y est\u00e1n tomando medidas muy en\u00e9rgicas. As\u00ed [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/10\/30\/trump-reduccion-aranceles-productos-chinos-trax\/","og_site_name":"Noticias","article_published_time":"2025-10-30T07:03:57+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/10\/30\/trump-reduccion-aranceles-productos-chinos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/10\/30\/trump-reduccion-aranceles-productos-chinos-trax\/"},"author":{"name":"","@id":""},"headline":"Trump reduce los aranceles para los productos chinos al 47 %","datePublished":"2025-10-30T07:03:57+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/10\/30\/trump-reduccion-aranceles-productos-chinos-trax\/"},"wordCount":235,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/10\/30\/trump-reduccion-aranceles-productos-chinos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/10\/30\/trump-reduccion-aranceles-productos-chinos-trax\/","url":"https:\/\/noticiasya.com\/2025\/10\/30\/trump-reduccion-aranceles-productos-chinos-trax\/","name":"Trump reduce los aranceles para los productos chinos al 47 % - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-10-30T07:03:57+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/10\/30\/trump-reduccion-aranceles-productos-chinos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/10\/30\/trump-reduccion-aranceles-productos-chinos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/10\/30\/trump-reduccion-aranceles-productos-chinos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump reduce los aranceles para los productos chinos al 47 %"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/30\/trump-reduccion-aranceles-productos-chinos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump reduce los aranceles para los productos chinos al 47 %","url":"http:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/30\/trump-reduccion-aranceles-productos-chinos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/30\/trump-reduccion-aranceles-productos-chinos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-10-30T07:03:57Z","datePublished":"2025-10-30T07:03:57Z","dateModified":"2025-10-30T07:03:57Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump reduce los aranceles para los productos chinos al 47 %\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2025\\\/10\\\/30\\\/trump-reduccion-aranceles-productos-chinos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2025\\\/10\\\/30\\\/trump-reduccion-aranceles-productos-chinos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-10-30T07:03:57Z\",\"datePublished\":\"2025-10-30T07:03:57Z\",\"dateModified\":\"2025-10-30T07:03:57Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1458151,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/02\/03\/trump-aranceles-china-guerra-comercial-trax\/","url_meta":{"origin":1467861,"position":0},"title":"AN\u00c1LISIS | Trump lanz\u00f3 un golpe arancelario contra China. \u00bfEst\u00e1 Beijing dispuesto a convertirlo en una guerra comercial?","author":"","date":"febrero 3, 2025","format":false,"excerpt":"El presidente Donald Trump finalmente cumpli\u00f3 su promesa de campa\u00f1a de aumentar los aranceles a las importaciones chinas: el s\u00e1bado anunci\u00f3 aranceles del 10% sobre todos los productos chinos que ingresen al pa\u00eds como parte de amplias medidas comerciales que tambi\u00e9n apuntaron a M\u00e9xico y Canad\u00e1.Ahora la pregunta para los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456083,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/11\/25\/trump-arancel-productos-canadienses-mexicanos-trax\/","url_meta":{"origin":1467861,"position":1},"title":"Trump dice que impondr\u00e1 un arancel del 25% a todos los productos que ingresen a EE.UU. desde M\u00e9xico y Canad\u00e1","author":"","date":"noviembre 25, 2024","format":false,"excerpt":"(CNN) \u2013\u2013\u00a0El presidente electo de EE.UU. Donald Trump prometi\u00f3 el lunes aranceles a los productos provenientes de M\u00e9xico, Canad\u00e1 y China desde el primer d\u00eda de su Gobierno.La medida, dijo Trump, ser\u00e1 en represalia por la inmigraci\u00f3n ilegal y el \u201ccrimen y las drogas\u201d que cruzan la frontera.\u201cEl 20 de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464477,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/07\/13\/fentanilo-comercio-china-estados-unidos-trax\/","url_meta":{"origin":1467861,"position":2},"title":"La droga mortal que complica el comercio entre Estados Unidos y China","author":"","date":"julio 13, 2025","format":false,"excerpt":"Desde que el presidente de Estados Unidos, Donald Trump, \u2013apenas unos d\u00edas despu\u00e9s de iniciar su segundo mandato\u2013 comenz\u00f3 a imponer aranceles a China por su papel en el flujo de opioides mortales como el fentanilo a Estados Unidos, el mensaje de Beijing ha sido claro.La crisis del fentanilo es\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459438,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/03\/03\/secretario-comercio-trump-esquema-arancelario-mexico-canada-trax\/","url_meta":{"origin":1467861,"position":3},"title":"Trump podr\u00eda considerar un esquema arancelario diferente para M\u00e9xico y Canad\u00e1, dice secretario de Comercio a CNN","author":"","date":"marzo 3, 2025","format":false,"excerpt":"Horas antes de la fecha l\u00edmite de las 12:01 a.m. ET para la entrada en vigor de los aranceles del 25% a las importaciones de M\u00e9xico y Canad\u00e1, as\u00ed como un arancel adicional del 10% a las importaciones chinas, el secretario de Comercio Howard Lutnick dijo este lunes que el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458264,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/02\/05\/guerra-comercial-con-china-trax\/","url_meta":{"origin":1467861,"position":4},"title":"\u00bfQu\u00e9 tan grave ser\u00e1 la guerra comercial con China?","author":"","date":"febrero 5, 2025","format":false,"excerpt":"Se lanzaron los primeros golpes entre Estados Unidos y China en lo que podr\u00eda constituir una disputa comercial de corta duraci\u00f3n con consecuencias econ\u00f3micas limitadas o el inicio de otra guerra comercial larga y dolorosa que recuerde al primer mandato del presidente Donald Trump.Inmediatamente despu\u00e9s de que el martes a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457760,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/01\/22\/productos-caros-trump-arancel-productos-chinos-trax\/","url_meta":{"origin":1467861,"position":5},"title":"\u00bfQu\u00e9 productos ser\u00e1n m\u00e1s caros si Trump impone un arancel del 10% a los art\u00edculos fabricados en China?","author":"","date":"enero 22, 2025","format":false,"excerpt":"\u00bfNecesitas una computadora, un televisor o un tel\u00e9fono nuevo? Tal vez te convenga comprar uno ahora.Esto se debe a que el presidente Donald Trump dijo este martes que podr\u00eda empezar a regir un nuevo arancel general del 10% sobre los productos chinos tan pronto como el 1 de febrero.A diferencia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1467861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1467861"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1467861\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1467861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1467861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1467861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}