{"id":1467874,"date":"2025-10-30T11:03:47","date_gmt":"2025-10-30T18:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/10\/30\/sancion-organizacion-criminal-bhardwaj-cancun-trafico-migrantes-orix\/"},"modified":"2025-10-30T11:03:47","modified_gmt":"2025-10-30T18:03:47","slug":"sancion-organizacion-criminal-bhardwaj-cancun-trafico-migrantes-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/30\/sancion-organizacion-criminal-bhardwaj-cancun-trafico-migrantes-orix\/","title":{"rendered":"EE.UU. sanciona a una organizaci\u00f3n criminal con sede en Canc\u00fan presuntamente dedicada a traficar migrantes al pa\u00eds"},"content":{"rendered":"<p>El Departamento del Tesoro de Estados Unidos sancion\u00f3 este jueves a un grupo delictivo con sede en Canc\u00fan, uno de los principales centros tur\u00edsticos de M\u00e9xico, desde donde presuntamente se dedica a traficar migrantes indocumentados desde varias partes del mundo hacia territorio estadounidense.<\/p>\n<p>Mediante <a href=\"https:\/\/home.treasury.gov\/news\/press-releases\/sb0296\">un comunicado<\/a>, el Departamento identific\u00f3 a la agrupaci\u00f3n como Bhardwaj, a la que design\u00f3 como organizaci\u00f3n criminal transnacional.<\/p>\n<p>El Departamento tambi\u00e9n sancion\u00f3 a cuatro personas \u2014el presunto l\u00edder de Bhardwaj y tres supuestos socios\u2014 y a 16 empresas situadas en M\u00e9xico, India y Emiratos \u00c1rabes Unidos. Estas compa\u00f1\u00edas pertenecen a sectores como la construcci\u00f3n, los bienes ra\u00edces y el alojamiento y, seg\u00fan Estados Unidos, brindan apoyo a las actividades delictivas de Bhardwaj.<\/p>\n<p>Las sanciones dadas a conocer este jueves implican que se congelen todos los bienes de las personas y empresas sancionadas que se encuentren en Estados Unidos, as\u00ed como la prohibici\u00f3n de que ciudadanos estadounidenses realicen negocios con ellas.<\/p>\n<p>El Departamento atribuy\u00f3 a Bhardwaj haber traficado a \u201cmiles\u201d de migrantes indocumentados desde Europa, Medio Oriente, Asia y Sudam\u00e9rica hacia Estados Unidos, as\u00ed como participar en narcotr\u00e1fico, sobornos y lavado de dinero.<\/p>\n<p>\u201cBhardwaj es una organizaci\u00f3n sofisticada que ha combinado varios m\u00e9todos de transporte para facilitar el traslado \u2014por aire y por mar\u2014 de migrantes indocumentados de pa\u00edses que representan preocupaciones de seguridad para Estados Unidos\u201d, dijo el Departamento.<\/p>\n<p>Esos m\u00e9todos, seg\u00fan el Departamento, incluyen el uso de embarcaciones e instalaciones propias para transportar a los migrantes hasta M\u00e9xico.<\/p>\n<p>Ah\u00ed, presuntamente se les da alojamiento en hoteles y hostales hasta que son llevados a la frontera con Estados Unidos, principalmente a trav\u00e9s de un corredor entre las ciudades mexicanas de Canc\u00fan, en el estado de Quintana Roo, en el Caribe mexicano; Tapachula, en el estado de Chiapas, en la frontera sur, y Mexicali, en el estado de Baja California, en la frontera norte.<\/p>\n<p>CNN contact\u00f3 a la Fiscal\u00eda de Justicia de Quintana Roo para pedir informaci\u00f3n sobre este grupo criminal y est\u00e1 en espera de respuesta.<\/p>\n<p>Las sanciones del Departamento se suman a otras acciones del Gobierno de Estados Unidos para frenar lo que describe como un constante flujo de migrantes indocumentados hacia su pa\u00eds.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Departamento del Tesoro de Estados Unidos sancion\u00f3 este jueves a un grupo delictivo con sede en Canc\u00fan, uno de los principales centros tur\u00edsticos de M\u00e9xico, desde donde presuntamente se dedica a traficar migrantes indocumentados desde varias partes del mundo hacia territorio estadounidense. Mediante un comunicado, el Departamento identific\u00f3 a la agrupaci\u00f3n como Bhardwaj, a [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467874","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EE.UU. sanciona a una organizaci\u00f3n criminal con sede en Canc\u00fan presuntamente dedicada a traficar migrantes al pa\u00eds - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/10\/30\/sancion-organizacion-criminal-bhardwaj-cancun-trafico-migrantes-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EE.UU. sanciona a una organizaci\u00f3n criminal con sede en Canc\u00fan presuntamente dedicada a traficar migrantes al pa\u00eds - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Departamento del Tesoro de Estados Unidos sancion\u00f3 este jueves a un grupo delictivo con sede en Canc\u00fan, uno de los principales centros tur\u00edsticos de M\u00e9xico, desde donde presuntamente se dedica a traficar migrantes indocumentados desde varias partes del mundo hacia territorio estadounidense. Mediante un comunicado, el Departamento identific\u00f3 a la agrupaci\u00f3n como Bhardwaj, a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/10\/30\/sancion-organizacion-criminal-bhardwaj-cancun-trafico-migrantes-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-30T18:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/30\/sancion-organizacion-criminal-bhardwaj-cancun-trafico-migrantes-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/30\/sancion-organizacion-criminal-bhardwaj-cancun-trafico-migrantes-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"EE.UU. sanciona a una organizaci\u00f3n criminal con sede en Canc\u00fan presuntamente dedicada a traficar migrantes al pa\u00eds\",\"datePublished\":\"2025-10-30T18:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/30\/sancion-organizacion-criminal-bhardwaj-cancun-trafico-migrantes-orix\/\"},\"wordCount\":421,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/30\/sancion-organizacion-criminal-bhardwaj-cancun-trafico-migrantes-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/30\/sancion-organizacion-criminal-bhardwaj-cancun-trafico-migrantes-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/10\/30\/sancion-organizacion-criminal-bhardwaj-cancun-trafico-migrantes-orix\/\",\"name\":\"EE.UU. sanciona a una organizaci\u00f3n criminal con sede en Canc\u00fan presuntamente dedicada a traficar migrantes al pa\u00eds - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-10-30T18:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/30\/sancion-organizacion-criminal-bhardwaj-cancun-trafico-migrantes-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/30\/sancion-organizacion-criminal-bhardwaj-cancun-trafico-migrantes-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/30\/sancion-organizacion-criminal-bhardwaj-cancun-trafico-migrantes-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EE.UU. sanciona a una organizaci\u00f3n criminal con sede en Canc\u00fan presuntamente dedicada a traficar migrantes al pa\u00eds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EE.UU. sanciona a una organizaci\u00f3n criminal con sede en Canc\u00fan presuntamente dedicada a traficar migrantes al pa\u00eds - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/10\/30\/sancion-organizacion-criminal-bhardwaj-cancun-trafico-migrantes-orix\/","og_locale":"es_ES","og_type":"article","og_title":"EE.UU. sanciona a una organizaci\u00f3n criminal con sede en Canc\u00fan presuntamente dedicada a traficar migrantes al pa\u00eds - Noticias","og_description":"El Departamento del Tesoro de Estados Unidos sancion\u00f3 este jueves a un grupo delictivo con sede en Canc\u00fan, uno de los principales centros tur\u00edsticos de M\u00e9xico, desde donde presuntamente se dedica a traficar migrantes indocumentados desde varias partes del mundo hacia territorio estadounidense. Mediante un comunicado, el Departamento identific\u00f3 a la agrupaci\u00f3n como Bhardwaj, a [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/10\/30\/sancion-organizacion-criminal-bhardwaj-cancun-trafico-migrantes-orix\/","og_site_name":"Noticias","article_published_time":"2025-10-30T18:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/10\/30\/sancion-organizacion-criminal-bhardwaj-cancun-trafico-migrantes-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/10\/30\/sancion-organizacion-criminal-bhardwaj-cancun-trafico-migrantes-orix\/"},"author":{"name":"","@id":""},"headline":"EE.UU. sanciona a una organizaci\u00f3n criminal con sede en Canc\u00fan presuntamente dedicada a traficar migrantes al pa\u00eds","datePublished":"2025-10-30T18:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/10\/30\/sancion-organizacion-criminal-bhardwaj-cancun-trafico-migrantes-orix\/"},"wordCount":421,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/10\/30\/sancion-organizacion-criminal-bhardwaj-cancun-trafico-migrantes-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/10\/30\/sancion-organizacion-criminal-bhardwaj-cancun-trafico-migrantes-orix\/","url":"https:\/\/noticiasya.com\/2025\/10\/30\/sancion-organizacion-criminal-bhardwaj-cancun-trafico-migrantes-orix\/","name":"EE.UU. sanciona a una organizaci\u00f3n criminal con sede en Canc\u00fan presuntamente dedicada a traficar migrantes al pa\u00eds - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-10-30T18:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/10\/30\/sancion-organizacion-criminal-bhardwaj-cancun-trafico-migrantes-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/10\/30\/sancion-organizacion-criminal-bhardwaj-cancun-trafico-migrantes-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/10\/30\/sancion-organizacion-criminal-bhardwaj-cancun-trafico-migrantes-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"EE.UU. sanciona a una organizaci\u00f3n criminal con sede en Canc\u00fan presuntamente dedicada a traficar migrantes al pa\u00eds"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/30\/sancion-organizacion-criminal-bhardwaj-cancun-trafico-migrantes-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"EE.UU. sanciona a una organizaci\u00f3n criminal con sede en Canc\u00fan presuntamente dedicada a traficar migrantes al pa\u00eds","url":"http:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/30\/sancion-organizacion-criminal-bhardwaj-cancun-trafico-migrantes-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/30\/sancion-organizacion-criminal-bhardwaj-cancun-trafico-migrantes-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-10-30T18:03:47Z","datePublished":"2025-10-30T18:03:47Z","dateModified":"2025-10-30T18:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"EE.UU. sanciona a una organizaci\\u00f3n criminal con sede en Canc\\u00fan presuntamente dedicada a traficar migrantes al pa\\u00eds\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2025\\\/10\\\/30\\\/sancion-organizacion-criminal-bhardwaj-cancun-trafico-migrantes-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2025\\\/10\\\/30\\\/sancion-organizacion-criminal-bhardwaj-cancun-trafico-migrantes-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-10-30T18:03:47Z\",\"datePublished\":\"2025-10-30T18:03:47Z\",\"dateModified\":\"2025-10-30T18:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1470403,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/01\/22\/tesoro-sanciones-ciudadanos-costa-rica-trafico-cocaina-orix\/","url_meta":{"origin":1467874,"position":0},"title":"EE.UU. sanciona a cinco ciudadanos y empresas de Costa Rica por presuntamente formar una red para traficar coca\u00edna","author":"","date":"enero 22, 2026","format":false,"excerpt":"El Departamento del Tesoro de Estados Unidos sancion\u00f3 este jueves a cinco ciudadanos y cinco empresas de Costa Rica por presuntamente formar parte de una red dedicada a traficar grandes cantidades de coca\u00edna y lavar dinero.Las sanciones implican que los bienes de los involucrados que se encuentren en Estados Unidos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466595,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/09\/18\/eeuu-mexico-bloquean-bienes-personas-empresas-cartel-sinaloa-orix\/","url_meta":{"origin":1467874,"position":1},"title":"EE.UU. y M\u00e9xico bloquean bienes de 7 personas y 15 empresas presuntamente ligadas al C\u00e1rtel de Sinaloa","author":"","date":"septiembre 18, 2025","format":false,"excerpt":"Los gobiernos de Estados Unidos y M\u00e9xico anunciaron este jueves que bloquearon los bienes de siete personas y 15 empresas presuntamente ligadas al C\u00e1rtel de Sinaloa, una medida que describieron como una acci\u00f3n m\u00e1s de su pol\u00edtica de combate al narcotr\u00e1fico y una muestra de su cooperaci\u00f3n en la materia.El\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469718,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/01\/01\/detienen-culiacan-pedro-insunza-noriega-sagitario-orix\/","url_meta":{"origin":1467874,"position":2},"title":"Detienen en Culiac\u00e1n a Pedro Insunza Noriega, alias &#171;Sagitario&#187;, acusado de narcoterrorismo en EE.UU.","author":"","date":"enero 1, 2026","format":false,"excerpt":"Pedro Insunza Noriega, alias \u201cSagitario\u201d o \u201cEl Se\u00f1or de la Silla\u201d, presunto operador del c\u00e1rtel de los Beltr\u00e1n Leyva, una facci\u00f3n del C\u00e1rtel de Sinaloa, se\u00f1alada por las autoridades estadounidenses como la mayor red conocida de producci\u00f3n de fentanilo en el mundo, fue detenido el mi\u00e9rcoles en Culiac\u00e1n, Sinaloa, de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445492,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/02\/16\/corte-de-nueva-york-acusa-al-mayo-zambada-por-fabricar-y-traficar-fentanilo\/","url_meta":{"origin":1467874,"position":3},"title":"Corte de Nueva York acusa al Mayo Zambada por fabricar y traficar fentanilo","author":"","date":"febrero 16, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Un tribunal federal de Brooklyn, Nueva York, acus\u00f3 este jueves a Ismael \u201cel Mayo\u201d Zambada, l\u00edder fundador del C\u00e1rtel de Sinaloa, por conspirar para fabricar y distribuir fentanilo en Estados Unidos, inform\u00f3 el Departamento de Justicia de Estados Unidos.\u00bfQui\u00e9n es Ismael \u2018El Mayo\u2019 Zambada?Se trata de la quinta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470378,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/01\/22\/quienes-son-37-presuntos-delincuentes-enviados-eeuu-orix\/","url_meta":{"origin":1467874,"position":4},"title":"\u00bfQui\u00e9nes son los 37 presuntos delincuentes que M\u00e9xico envi\u00f3 a Estados Unidos?","author":"","date":"enero 22, 2026","format":false,"excerpt":"M\u00e9xico envi\u00f3 este martes a Estados Unidos a 37 presuntos delincuentes peligrosos, una medida que forma parte de los mecanismos de cooperaci\u00f3n entre ambos pa\u00edses en materia de seguridad, seg\u00fan indicaron desde el Gobierno. Este traslado se suma a otros dos que M\u00e9xico realiz\u00f3 en 2025, uno de 29 personas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457387,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/01\/09\/yakuza-japon-materiales-nucleares-myanmar-trax\/","url_meta":{"origin":1467874,"position":5},"title":"Presunto l\u00edder de la mafia japonesa Yakuza admite traficar materiales nucleares desde Myanmar","author":"","date":"enero 9, 2025","format":false,"excerpt":"Un supuesto l\u00edder de la organizaci\u00f3n criminal japonesa Yakuza se declar\u00f3 culpable de traficar materiales nucleares desde Myanmar como parte de una red mundial de tr\u00e1fico de drogas, armas y dinero lavado, seg\u00fan el Departamento de Justicia de Estados Unidos.Durante una investigaci\u00f3n encubierta de la Administraci\u00f3n de Control de Drogas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1467874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1467874"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1467874\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1467874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1467874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1467874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}