{"id":1467908,"date":"2025-10-31T12:03:53","date_gmt":"2025-10-31T19:03:53","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/10\/31\/muerte-musicos-colombianos-mexico-drogas-extorsion-secuestro-orix\/"},"modified":"2025-10-31T12:03:53","modified_gmt":"2025-10-31T19:03:53","slug":"muerte-musicos-colombianos-mexico-drogas-extorsion-secuestro-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/31\/muerte-musicos-colombianos-mexico-drogas-extorsion-secuestro-orix\/","title":{"rendered":"Drogas, extorsi\u00f3n y 16 detenidos: las claves del crimen de B King y Regio Clown, los m\u00fasicos colombianos asesinados en M\u00e9xico"},"content":{"rendered":"<p>Las muertes de los m\u00fasicos colombianos Bayron S\u00e1nchez, conocido art\u00edsticamente como \u201cB King\u201d, y Jorge Luis Herrera, conocido como \u201cDJ Regio Clown\u201d, han sido vinculados con una compleja red de delitos, entre los que destacan venta de drogas, extorsi\u00f3n y secuestro, seg\u00fan las investigaciones de las autoridades mexicanas.<\/p>\n<p>Al menos 16 personas han sido detenidas por sus presuntas vinculaciones con el hecho, dijo este jueves la Fiscal\u00eda del Estado de M\u00e9xico.<\/p>\n<p>Ambos m\u00fasicos desaparecieron en el centro de M\u00e9xico a mediados de septiembre luego de llegar al pa\u00eds para una <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/09\/22\/colombia\/petro-desaparicion-bking-estados-unidos-mafias-orix\">gira<\/a>. Dos cuerpos que coincid\u00edan con las caracter\u00edsticas de los m\u00fasicos <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/09\/24\/mexico\/lo-que-sabemos-caso-musicos-colombianos-hallados-muertos-orix\">fueron hallados<\/a> el 17 de septiembre en el Estado de M\u00e9xico. Unos d\u00edas despu\u00e9s, sus familiares confirmaron que se trataba de sus seres queridos.<\/p>\n<p>La Fiscal\u00eda inform\u00f3 el jueves que las investigaciones realizadas hasta el momento sobre las dos muertes muestran que los hechos est\u00e1n relacionados con actividades il\u00edcitas.<\/p>\n<p>Las investigaciones \u201cvinculan la muerte de ambos sujetos con un entorno delictivo de distribuci\u00f3n y comercializaci\u00f3n de narc\u00f3ticos, en particular los conocidos como \u20182-CB (Tusi)\u2019 y \u2018Coco Channel\u2019. Las investigaciones permiten relacionar esta actividad con otros delitos como extorsi\u00f3n \u2018gota a gota\u2019, privaci\u00f3n de la libertad y secuestro\u201d, menciona la Fiscal\u00eda en un comunicado.<\/p>\n<p>Seg\u00fan las indagaciones, los m\u00fasicos habr\u00edan sido contratados para participar en eventos llamados \u201cSin Censura\u201d, espect\u00e1culos donde se presentan cantantes, DJ, shows de contenido er\u00f3tico, gente de alto poder adquisitivo, y donde se planeaban vender las drogas \u201cTusi\u201d y \u201cCoco Channel\u201d, dicen las autoridades.<\/p>\n<p>La droga \u201cTusi\u201d tambi\u00e9n es conocida como \u201ccoca\u00edna rosa\u201d. Su nombre proviene del ingl\u00e9s \u201c2-CB\u201d, la sustancia qu\u00edmica base para crear esta droga, <a href=\"https:\/\/www.dea.gov\/pink-cocaine\">seg\u00fan<\/a> la Administraci\u00f3n para el Control de Drogas (DEA, por sus siglas en ingl\u00e9s) de Estados Unidos. La DEA a\u00f1ade que actualmente se ha vuelto complicado hallar 2-CB, por lo que la droga Tusi es ahora una mezcla de sustancias, entre ellas fentanilo.<\/p>\n<p>Sobre la droga \u201cCoco Channel\u201d no hay informaci\u00f3n p\u00fablica que la identifique plenamente. La Fiscal\u00eda del Estado de M\u00e9xico dice que es una droga de origen colombiano y que su venta en los eventos \u201cSin Censura\u201d generar\u00eda \u201cmayores ganancias\u201d a las que se obtienen con otras drogas en M\u00e9xico.<\/p>\n<p>Las autoridades del Estado de M\u00e9xico identificaron al promotor de B-King entre los organizadores de los eventos \u201cSin Censura\u201d, que se llevaban a cabo en el rancho \u201cLos Leones\u201d, ubicado en Ixtapan de la Sal, municipio del Estado de M\u00e9xico.<\/p>\n<p>El 14 de septiembre, dicen las autoridades, los dos m\u00fasicos colombianos viajaron de un hotel en Polanco, en la Ciudad de M\u00e9xico, a un evento \u201cSin Censura\u201d.<\/p>\n<p>El 17 de septiembre, mismo d\u00eda en que encontraron los cuerpos de B-King y DJ Regio Clown, la Secretar\u00eda de Seguridad del Estado de M\u00e9xico rescat\u00f3 a una mujer espa\u00f1ola que se encontraba privada de su libertad en un evento \u201cSin Censura\u201d.<\/p>\n<p>La Fiscal\u00eda del Estado de M\u00e9xico dice que un auto Mercedes Benz color plata ha sido clave en la indagatoria.<\/p>\n<p>Seg\u00fan las investigaciones, B-King y DJ Regio Clown abordaron este veh\u00edculo en plaza Miyana, en las inmediaciones de Polanco, en la tarde del 16 de septiembre. Ese fue el \u00faltimo d\u00eda en que las familias tuvieron <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/09\/24\/mexico\/lo-que-sabemos-caso-musicos-colombianos-hallados-muertos-orix\">contacto<\/a> con los m\u00fasicos.<\/p>\n<p>Las autoridades se\u00f1alan que, tras abordar el veh\u00edculo, fueron llevados a la colonia Renovaci\u00f3n, ubicada en la alcald\u00eda Iztapalapa, en el oriente de la Ciudad de M\u00e9xico, donde habr\u00edan sido asesinados.<\/p>\n<p>\u201cUn testigo se\u00f1al\u00f3 que las v\u00edctimas fueron privadas de la vida en domicilio de alias \u2018El Ap\u00e1\u2019 ubicado en la Ciudad de M\u00e9xico y que este sujeto es propietario de un taller de reciclado ubicado en la colonia Renovaci\u00f3n en la alcald\u00eda Iztapalapa, donde se usan bolsas de pl\u00e1stico y de rafia similares a las que conten\u00edan los restos humanos en el lugar del hallazgo\u201d original el pasado 17 de septiembre en el municipio de Cocotitl\u00e1n, Estado de M\u00e9xico.<\/p>\n<p>La autoridades del Estado de M\u00e9xico identificaron que se trat\u00f3 de modificar la pintura de los rines del auto en un taller de hojalater\u00eda cercano a la colonia Renovaci\u00f3n, con el fin de que el veh\u00edculo pasara desapercibido<\/p>\n<p>El veh\u00edculo fue localizado por la Fiscal\u00eda en un domicilio ubicado en el municipio de Tepetlaoxtoc, Estado de M\u00e9xico, en donde las autoridades hallaron tambi\u00e9n a una mujer privada de su libertad.<\/p>\n<p>El hallazgo de esta mujer, que se dio por otra investigaci\u00f3n que hac\u00eda la Fiscal\u00eda, llev\u00f3 al descubrimiento del auto Mercedes involucrado en el homicidio de los m\u00fasicos colombianos. El veh\u00edculo estaba oculto en un estacionamiento subterr\u00e1neo en el mismo inmueble donde encontraron a la mujer.<\/p>\n<p>La Fiscal\u00eda del Estado de M\u00e9xico agrega que en este inmueble detuvieron a cuatro personas, todas de origen colombiano y que \u201cpresuntamente forman parte de un esquema extorsivo conocido como \u2018gota a gota\u2019 a trav\u00e9s de una empresa denominada \u2018Emprende Coin\u2019 con domicilio fiscal en la Ciudad de M\u00e9xico y que, adem\u00e1s, podr\u00edan estar relacionados con actividades delictivas de despojo y contra la salud\u201d.<\/p>\n<p>Esta empresa supuestamente ofrece \u201cpr\u00e9stamos que van desde 500 hasta un mill\u00f3n de pesos con tasas de inter\u00e9s y condiciones que llevan a los deudores al incumplimiento\u201d, quienes son amenazados y violentados verbal y f\u00edsicamente para obligarlos a pagar, se\u00f1ala la Fiscal\u00eda. Los integrantes de la empresa son se\u00f1alados de instalar una aplicaci\u00f3n en el celular de cada solicitante de pr\u00e9stamo para hacer m\u00e1s sencillo el siguiente en tiempo real de las v\u00edctimas y el robo de su informaci\u00f3n.<\/p>\n<p>Entre las cuatro personas colombianas detenidas, se encuentra Yonier Alexander \u201cN\u201d, quien fue identificado por testigos como la \u201c\u00fanica persona autorizada por la Uni\u00f3n Tepito para cocinar Tusi en la Ciudad de M\u00e9xico\u201d, indic\u00f3 la Fiscal\u00eda del Estado de M\u00e9xico. La Uni\u00f3n Tepito es un cartel del narcotr\u00e1fico que se origin\u00f3 en la Ciudad de M\u00e9xico.<\/p>\n<p>La Fiscal\u00eda dice que las investigaciones se\u00f1alan que el m\u00f3vil del homicidio ser\u00eda el adeudo de uno de los m\u00fasicos con un grupo criminal, adem\u00e1s de la relaci\u00f3n de los colombianos con un sujeto identificado como alias \u201cEl Pantera\u201d.<\/p>\n<p>Seg\u00fan la autoridad, hab\u00eda un acuerdo previo entre El Pantera y otros involucrados \u2014entre ellos Cristopher \u201cN\u201d, alias \u201cEl Comandante\u201d, detenido el jueves por ser presunto coautor material de los homicidios\u2014 \u201cpara privar de la vida a las v\u00edctimas, principalmente por el inter\u00e9s de alias \u2018El Pantera\u2019 de \u2018matar\u2019 a alias DJ Regio Clown, debido a que este habr\u00eda divulgado datos sobre su identidad y porque distribu\u00eda droga en los eventos \u2018Sin Censura\u2019 sin su autorizaci\u00f3n\u201d.<\/p>\n<p>\u201cEl an\u00e1lisis conjunto de los indicios permite inferir que Cristopher \u2018N\u2019, alias \u2018El Comandante\u2019 tuvo control sobre aspectos esenciales de la ejecuci\u00f3n, al coordinar y dirigir la fase de atracci\u00f3n de las v\u00edctimas mediante el enga\u00f1o y la manipulaci\u00f3n de su confianza para asegurar el resultado planificado por el grupo\u201d, dice la Fiscal\u00eda del Estado de M\u00e9xico.<\/p>\n<p>Sobre El Pantera, la Fiscal\u00eda no a\u00f1ade m\u00e1s informaci\u00f3n, salvo que B-King y DJ Regio Clown ten\u00edan una \u201crelaci\u00f3n personal\u201d con \u00e9l.<\/p>\n<p>Entre los 16 detenidos hay desde implicados directos, como el Comandante, hasta personas que habr\u00edan participado en la alteraci\u00f3n del veh\u00edculo Mercedes o los sujetos colombianos que estaban relacionados con extorsi\u00f3n en la empresa Emprende Coin.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las muertes de los m\u00fasicos colombianos Bayron S\u00e1nchez, conocido art\u00edsticamente como \u201cB King\u201d, y Jorge Luis Herrera, conocido como \u201cDJ Regio Clown\u201d, han sido vinculados con una compleja red de delitos, entre los que destacan venta de drogas, extorsi\u00f3n y secuestro, seg\u00fan las investigaciones de las autoridades mexicanas. Al menos 16 personas han sido detenidas [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467908","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Drogas, extorsi\u00f3n y 16 detenidos: las claves del crimen de B King y Regio Clown, los m\u00fasicos colombianos asesinados en M\u00e9xico - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/10\/31\/muerte-musicos-colombianos-mexico-drogas-extorsion-secuestro-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Drogas, extorsi\u00f3n y 16 detenidos: las claves del crimen de B King y Regio Clown, los m\u00fasicos colombianos asesinados en M\u00e9xico - Noticias\" \/>\n<meta property=\"og:description\" content=\"Las muertes de los m\u00fasicos colombianos Bayron S\u00e1nchez, conocido art\u00edsticamente como \u201cB King\u201d, y Jorge Luis Herrera, conocido como \u201cDJ Regio Clown\u201d, han sido vinculados con una compleja red de delitos, entre los que destacan venta de drogas, extorsi\u00f3n y secuestro, seg\u00fan las investigaciones de las autoridades mexicanas. Al menos 16 personas han sido detenidas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/10\/31\/muerte-musicos-colombianos-mexico-drogas-extorsion-secuestro-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-31T19:03:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/31\/muerte-musicos-colombianos-mexico-drogas-extorsion-secuestro-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/31\/muerte-musicos-colombianos-mexico-drogas-extorsion-secuestro-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Drogas, extorsi\u00f3n y 16 detenidos: las claves del crimen de B King y Regio Clown, los m\u00fasicos colombianos asesinados en M\u00e9xico\",\"datePublished\":\"2025-10-31T19:03:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/31\/muerte-musicos-colombianos-mexico-drogas-extorsion-secuestro-orix\/\"},\"wordCount\":1362,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/31\/muerte-musicos-colombianos-mexico-drogas-extorsion-secuestro-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/31\/muerte-musicos-colombianos-mexico-drogas-extorsion-secuestro-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/10\/31\/muerte-musicos-colombianos-mexico-drogas-extorsion-secuestro-orix\/\",\"name\":\"Drogas, extorsi\u00f3n y 16 detenidos: las claves del crimen de B King y Regio Clown, los m\u00fasicos colombianos asesinados en M\u00e9xico - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-10-31T19:03:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/31\/muerte-musicos-colombianos-mexico-drogas-extorsion-secuestro-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/31\/muerte-musicos-colombianos-mexico-drogas-extorsion-secuestro-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/31\/muerte-musicos-colombianos-mexico-drogas-extorsion-secuestro-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Drogas, extorsi\u00f3n y 16 detenidos: las claves del crimen de B King y Regio Clown, los m\u00fasicos colombianos asesinados en M\u00e9xico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Drogas, extorsi\u00f3n y 16 detenidos: las claves del crimen de B King y Regio Clown, los m\u00fasicos colombianos asesinados en M\u00e9xico - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/10\/31\/muerte-musicos-colombianos-mexico-drogas-extorsion-secuestro-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Drogas, extorsi\u00f3n y 16 detenidos: las claves del crimen de B King y Regio Clown, los m\u00fasicos colombianos asesinados en M\u00e9xico - Noticias","og_description":"Las muertes de los m\u00fasicos colombianos Bayron S\u00e1nchez, conocido art\u00edsticamente como \u201cB King\u201d, y Jorge Luis Herrera, conocido como \u201cDJ Regio Clown\u201d, han sido vinculados con una compleja red de delitos, entre los que destacan venta de drogas, extorsi\u00f3n y secuestro, seg\u00fan las investigaciones de las autoridades mexicanas. Al menos 16 personas han sido detenidas [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/10\/31\/muerte-musicos-colombianos-mexico-drogas-extorsion-secuestro-orix\/","og_site_name":"Noticias","article_published_time":"2025-10-31T19:03:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/10\/31\/muerte-musicos-colombianos-mexico-drogas-extorsion-secuestro-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/10\/31\/muerte-musicos-colombianos-mexico-drogas-extorsion-secuestro-orix\/"},"author":{"name":"","@id":""},"headline":"Drogas, extorsi\u00f3n y 16 detenidos: las claves del crimen de B King y Regio Clown, los m\u00fasicos colombianos asesinados en M\u00e9xico","datePublished":"2025-10-31T19:03:53+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/10\/31\/muerte-musicos-colombianos-mexico-drogas-extorsion-secuestro-orix\/"},"wordCount":1362,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/10\/31\/muerte-musicos-colombianos-mexico-drogas-extorsion-secuestro-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/10\/31\/muerte-musicos-colombianos-mexico-drogas-extorsion-secuestro-orix\/","url":"https:\/\/noticiasya.com\/2025\/10\/31\/muerte-musicos-colombianos-mexico-drogas-extorsion-secuestro-orix\/","name":"Drogas, extorsi\u00f3n y 16 detenidos: las claves del crimen de B King y Regio Clown, los m\u00fasicos colombianos asesinados en M\u00e9xico - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-10-31T19:03:53+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/10\/31\/muerte-musicos-colombianos-mexico-drogas-extorsion-secuestro-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/10\/31\/muerte-musicos-colombianos-mexico-drogas-extorsion-secuestro-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/10\/31\/muerte-musicos-colombianos-mexico-drogas-extorsion-secuestro-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Drogas, extorsi\u00f3n y 16 detenidos: las claves del crimen de B King y Regio Clown, los m\u00fasicos colombianos asesinados en M\u00e9xico"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/31\/muerte-musicos-colombianos-mexico-drogas-extorsion-secuestro-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Drogas, extorsi\u00f3n y 16 detenidos: las claves del crimen de B King y Regio Clown, los m\u00fasicos colombianos asesinados en M\u00e9xico","url":"http:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/31\/muerte-musicos-colombianos-mexico-drogas-extorsion-secuestro-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/31\/muerte-musicos-colombianos-mexico-drogas-extorsion-secuestro-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-10-31T19:03:53Z","datePublished":"2025-10-31T19:03:53Z","dateModified":"2025-10-31T19:03:53Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Drogas, extorsi\\u00f3n y 16 detenidos: las claves del crimen de B King y Regio Clown, los m\\u00fasicos colombianos asesinados en M\\u00e9xico\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2025\\\/10\\\/31\\\/muerte-musicos-colombianos-mexico-drogas-extorsion-secuestro-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2025\\\/10\\\/31\\\/muerte-musicos-colombianos-mexico-drogas-extorsion-secuestro-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-10-31T19:03:53Z\",\"datePublished\":\"2025-10-31T19:03:53Z\",\"dateModified\":\"2025-10-31T19:03:53Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1466886,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/09\/26\/detienen-actriz-venezolana-muerte-musicos-colombianos-orix\/","url_meta":{"origin":1467908,"position":0},"title":"Detienen a actriz venezolana por su presunta relaci\u00f3n con la muerte de los m\u00fasicos colombianos B King y Regio Clown","author":"","date":"septiembre 26, 2025","format":false,"excerpt":"La actriz y creadora de contenido venezolana Ang\u00e9lica Yetsey Torrini Le\u00f3n, tambi\u00e9n conocida como Angie Miller, fue detenida en M\u00e9xico por su presunta relaci\u00f3n con la muerte de dos m\u00fasicos colombianos cuyos cuerpos fueron hallados el 17 de septiembre, de acuerdo con informaci\u00f3n de la Fiscal\u00eda de la Ciudad de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467219,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/08\/familia-b-king-fiscalia-colombia-dj-regio-clown-mexico-orix\/","url_meta":{"origin":1467908,"position":1},"title":"Familia del m\u00fasico colombiano B King pide a Fiscal\u00eda de Colombia ayudar a esclarecer su homicidio y el del DJ Regio Clown","author":"","date":"octubre 8, 2025","format":false,"excerpt":"A dos semanas de que autoridades de M\u00e9xico informaron sobre el homicidio de los m\u00fasicos colombianos Bayron S\u00e1nchez Salazar, conocido como B King, y Jorge Luis Herrera Lemos, conocido como Regio Clown, la familia de S\u00e1nchez Salazar pidi\u00f3 a la Fiscal\u00eda de Colombia que ayude a esclarecer el caso.La petici\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466769,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/09\/24\/lo-que-sabemos-caso-musicos-colombianos-hallados-muertos-orix\/","url_meta":{"origin":1467908,"position":2},"title":"\u00bfQui\u00e9nes eran B King y Jorge Luis Herrera, m\u00fasicos colombianos hallados muertos en M\u00e9xico, y qu\u00e9 se sabe del doble crimen?","author":"","date":"septiembre 24, 2025","format":false,"excerpt":"Autoridades de M\u00e9xico informaron este lunes que el cantante Bayron S\u00e1nchez Salazar, conocido como B King, y el DJ Jorge Luis Herrera Lemos, conocido como Regio Clown, fueron encontrados muertos en el centro del pa\u00eds.Los dos m\u00fasicos colombianos ten\u00edan casi una semana desaparecidos, una situaci\u00f3n por la que tanto sus\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466689,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/09\/22\/petro-desaparicion-bking-estados-unidos-mafias-orix\/","url_meta":{"origin":1467908,"position":3},"title":"Petro pide ayuda a M\u00e9xico por desaparici\u00f3n de B King y se cruza en una pelea con EE.UU. por &#171;mafias multinacionales&#187;","author":"","date":"septiembre 22, 2025","format":false,"excerpt":"El presidente de Colombia, Gustavo Petro, pidi\u00f3 este domingo apoyo a su hom\u00f3loga de M\u00e9xico, Claudia Sheinbaum, para localizar al cantante colombiano Bayron S\u00e1nchez Salazar, conocido art\u00edsticamente como B King y reportado como desaparecido junto con el DJ Jorge Luis Herrera durante una gira en M\u00e9xico.\u201cLe solicito a la presidenta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467280,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/10\/matan-actor-cantante-argentino-fede-dorcaz-orix\/","url_meta":{"origin":1467908,"position":4},"title":"Matan al actor y cantante argentino Fede Dorcaz en la Ciudad de M\u00e9xico","author":"","date":"octubre 10, 2025","format":false,"excerpt":"El actor y cantante argentino Fede Dorcaz muri\u00f3 el jueves en la Ciudad de M\u00e9xico tras ser blanco de lo que la Polic\u00eda local describe como un posible \u201cataque directo\u201d en la alcald\u00eda Miguel Hidalgo, al oeste de la capital, inform\u00f3 la Secretar\u00eda de Seguridad Ciudadana en un comunicado.Dorcaz recibi\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466800,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/09\/25\/5-cosas-25-septiembre-orix\/","url_meta":{"origin":1467908,"position":5},"title":"Las 5 cosas que debes saber este 25 de septiembre: ataque en centro del ICE, Noboa y &#171;rapto&#187; viral en TikTok","author":"","date":"septiembre 25, 2025","format":false,"excerpt":"Marina de EE.UU. prueba misiles bal\u00edsticos cerca de Florida en plena tensi\u00f3n con Venezuela. Decisiva victoria dem\u00f3crata para desclasificar los archivos de Epstein. \u00bfQu\u00e9 es el \u201crapto\u201d viral en TikTok? Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1467908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1467908"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1467908\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1467908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1467908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1467908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}