{"id":1467919,"date":"2025-10-31T16:03:44","date_gmt":"2025-10-31T23:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/10\/31\/trump-no-especifica-nuevas-pruebas-nucleares-trax\/"},"modified":"2025-10-31T16:03:44","modified_gmt":"2025-10-31T23:03:44","slug":"trump-no-especifica-nuevas-pruebas-nucleares-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/31\/trump-no-especifica-nuevas-pruebas-nucleares-trax\/","title":{"rendered":"Trump se niega a especificar qu\u00e9 quiso decir exactamente al pedir que se realicen nuevas pruebas nucleares"},"content":{"rendered":"<p>El presidente de Estados Unidos, Donald Trump, mantuvo este viernes un velo de ambig\u00fcedad sobre su directiva de reanudar las pruebas nucleares, diciendo a los periodistas que \u201csabr\u00e1n muy pronto\u201d si decide avanzar con las primeras pruebas explosivas estadounidenses en d\u00e9cadas.<\/p>\n<p>\u201cVamos a hacer algunas pruebas\u201d, dijo a bordo del Air Force One. \u201cOtros pa\u00edses lo hacen. Si ellos lo van a hacer, nosotros lo vamos a hacer\u201d.<\/p>\n<p>A Trump se le pregunt\u00f3 si estaba pidiendo nuevas pruebas subterr\u00e1neas con su instrucci\u00f3n p\u00fablica de esta semana al Pent\u00e1gono de comenzar a probar armas nucleares nuevamente.<\/p>\n<p>Estados Unidos realiz\u00f3 su \u00faltima prueba nuclear en 1992; desde entonces, se han utilizado simulaciones por computadora para evaluar el arsenal estadounidense.<\/p>\n<p>En su mensaje, Trump afirm\u00f3 que los adversarios Rusia y China estaban realizando sus propias pruebas, y que Estados Unidos simplemente necesitaba mantenerse al d\u00eda. De hecho, Rusia y China han respetado una moratoria sobre las pruebas durante d\u00e9cadas. Algunos funcionarios dijeron que Trump pudo haber sido motivado por los vuelos de prueba de Mosc\u00fa en los \u00faltimos d\u00edas de misiles de crucero y torpedos con capacidad nuclear, aunque ya se conoc\u00eda su existencia y las pruebas no involucraron una detonaci\u00f3n nuclear.<\/p>\n<p>Trump, presionado sobre qu\u00e9 ped\u00eda exactamente, se neg\u00f3 a responder el viernes.<\/p>\n<p>\u201cNo lo voy a decir. S\u00e9 exactamente lo que estamos haciendo, d\u00f3nde lo estamos haciendo\u201d, dijo. \u201cSi otros pa\u00edses lo hacen, nosotros lo hacemos\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de Estados Unidos, Donald Trump, mantuvo este viernes un velo de ambig\u00fcedad sobre su directiva de reanudar las pruebas nucleares, diciendo a los periodistas que \u201csabr\u00e1n muy pronto\u201d si decide avanzar con las primeras pruebas explosivas estadounidenses en d\u00e9cadas. \u201cVamos a hacer algunas pruebas\u201d, dijo a bordo del Air Force One. \u201cOtros pa\u00edses [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467919","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump se niega a especificar qu\u00e9 quiso decir exactamente al pedir que se realicen nuevas pruebas nucleares - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/10\/31\/trump-no-especifica-nuevas-pruebas-nucleares-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump se niega a especificar qu\u00e9 quiso decir exactamente al pedir que se realicen nuevas pruebas nucleares - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente de Estados Unidos, Donald Trump, mantuvo este viernes un velo de ambig\u00fcedad sobre su directiva de reanudar las pruebas nucleares, diciendo a los periodistas que \u201csabr\u00e1n muy pronto\u201d si decide avanzar con las primeras pruebas explosivas estadounidenses en d\u00e9cadas. \u201cVamos a hacer algunas pruebas\u201d, dijo a bordo del Air Force One. \u201cOtros pa\u00edses [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/10\/31\/trump-no-especifica-nuevas-pruebas-nucleares-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-31T23:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/31\/trump-no-especifica-nuevas-pruebas-nucleares-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/31\/trump-no-especifica-nuevas-pruebas-nucleares-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump se niega a especificar qu\u00e9 quiso decir exactamente al pedir que se realicen nuevas pruebas nucleares\",\"datePublished\":\"2025-10-31T23:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/31\/trump-no-especifica-nuevas-pruebas-nucleares-trax\/\"},\"wordCount\":283,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/31\/trump-no-especifica-nuevas-pruebas-nucleares-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/31\/trump-no-especifica-nuevas-pruebas-nucleares-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/10\/31\/trump-no-especifica-nuevas-pruebas-nucleares-trax\/\",\"name\":\"Trump se niega a especificar qu\u00e9 quiso decir exactamente al pedir que se realicen nuevas pruebas nucleares - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-10-31T23:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/31\/trump-no-especifica-nuevas-pruebas-nucleares-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/31\/trump-no-especifica-nuevas-pruebas-nucleares-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/31\/trump-no-especifica-nuevas-pruebas-nucleares-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump se niega a especificar qu\u00e9 quiso decir exactamente al pedir que se realicen nuevas pruebas nucleares\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump se niega a especificar qu\u00e9 quiso decir exactamente al pedir que se realicen nuevas pruebas nucleares - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/10\/31\/trump-no-especifica-nuevas-pruebas-nucleares-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trump se niega a especificar qu\u00e9 quiso decir exactamente al pedir que se realicen nuevas pruebas nucleares - Noticias","og_description":"El presidente de Estados Unidos, Donald Trump, mantuvo este viernes un velo de ambig\u00fcedad sobre su directiva de reanudar las pruebas nucleares, diciendo a los periodistas que \u201csabr\u00e1n muy pronto\u201d si decide avanzar con las primeras pruebas explosivas estadounidenses en d\u00e9cadas. \u201cVamos a hacer algunas pruebas\u201d, dijo a bordo del Air Force One. \u201cOtros pa\u00edses [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/10\/31\/trump-no-especifica-nuevas-pruebas-nucleares-trax\/","og_site_name":"Noticias","article_published_time":"2025-10-31T23:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/10\/31\/trump-no-especifica-nuevas-pruebas-nucleares-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/10\/31\/trump-no-especifica-nuevas-pruebas-nucleares-trax\/"},"author":{"name":"","@id":""},"headline":"Trump se niega a especificar qu\u00e9 quiso decir exactamente al pedir que se realicen nuevas pruebas nucleares","datePublished":"2025-10-31T23:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/10\/31\/trump-no-especifica-nuevas-pruebas-nucleares-trax\/"},"wordCount":283,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/10\/31\/trump-no-especifica-nuevas-pruebas-nucleares-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/10\/31\/trump-no-especifica-nuevas-pruebas-nucleares-trax\/","url":"https:\/\/noticiasya.com\/2025\/10\/31\/trump-no-especifica-nuevas-pruebas-nucleares-trax\/","name":"Trump se niega a especificar qu\u00e9 quiso decir exactamente al pedir que se realicen nuevas pruebas nucleares - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-10-31T23:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/10\/31\/trump-no-especifica-nuevas-pruebas-nucleares-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/10\/31\/trump-no-especifica-nuevas-pruebas-nucleares-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/10\/31\/trump-no-especifica-nuevas-pruebas-nucleares-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump se niega a especificar qu\u00e9 quiso decir exactamente al pedir que se realicen nuevas pruebas nucleares"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/31\/trump-no-especifica-nuevas-pruebas-nucleares-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump se niega a especificar qu\u00e9 quiso decir exactamente al pedir que se realicen nuevas pruebas nucleares","url":"http:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/31\/trump-no-especifica-nuevas-pruebas-nucleares-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/31\/trump-no-especifica-nuevas-pruebas-nucleares-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-10-31T23:03:44Z","datePublished":"2025-10-31T23:03:44Z","dateModified":"2025-10-31T23:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump se niega a especificar qu\\u00e9 quiso decir exactamente al pedir que se realicen nuevas pruebas nucleares\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2025\\\/10\\\/31\\\/trump-no-especifica-nuevas-pruebas-nucleares-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2025\\\/10\\\/31\\\/trump-no-especifica-nuevas-pruebas-nucleares-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-10-31T23:03:44Z\",\"datePublished\":\"2025-10-31T23:03:44Z\",\"dateModified\":\"2025-10-31T23:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1468346,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/11\/14\/reunion-casa-blanca-pruebas-nucleares-trump-trax\/","url_meta":{"origin":1467919,"position":0},"title":"Funcionarios de Energ\u00eda intentar\u00e1n persuadir a Trump de no realizar pruebas nucleares que incluyan detonaciones","author":"","date":"noviembre 14, 2025","format":false,"excerpt":"Funcionarios de alto rango de las \u00e1reas de energ\u00eda y energ\u00eda nuclear de la administraci\u00f3n Trump tienen previsto reunirse con la Casa Blanca y el Consejo de Seguridad Nacional en los pr\u00f3ximos d\u00edas para disuadir al presidente Donald Trump de reanudar las pruebas con armas nucleares del pa\u00eds, seg\u00fan informaron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467968,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/11\/02\/trump-pruebas-armas-nucleares-trax\/","url_meta":{"origin":1467919,"position":1},"title":"Trump afirma que Rusia y China prueban armas nucleares en secreto y justifica su llamado a reanudar las detonaciones","author":"","date":"noviembre 2, 2025","format":false,"excerpt":"El presidente de EE.UU. Donald Trump sugiri\u00f3 el domingo que Rusia y China estaban realizando pruebas secretas de armas nucleares, lo que, seg\u00fan \u00e9l, justifica que Estados Unidos reanude sus propias pruebas explosivas despu\u00e9s de m\u00e1s de tres d\u00e9cadas.\u201cNo quiero ser el \u00fanico pa\u00eds que no prueba\u201d, dijo Trump en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468053,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/11\/05\/putin-insinua-posibilidad-pruebas-nucleares-trax\/","url_meta":{"origin":1467919,"position":2},"title":"Putin insin\u00faa la posibilidad de nuevas pruebas nucleares tras los comentarios de Trump","author":"","date":"noviembre 5, 2025","format":false,"excerpt":"El presidente de Rusia, Vladimir Putin, afirm\u00f3 que su pa\u00eds explorar\u00e1 la posibilidad de realizar nuevas pruebas nucleares despu\u00e9s de que su par estadounidense, Donald Trump, anunciara la semana pasada que Washington comenzar\u00eda programas de ensayos nucleares.\u201cRusia siempre ha cumplido y sigue cumpliendo estrictamente sus obligaciones en virtud del Tratado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467887,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/30\/trump-armas-nucleares-sorpresa-asesores-trax\/","url_meta":{"origin":1467919,"position":3},"title":"Trump dijo que Estados Unidos comenzar\u00eda a probar armas nucleares, tomando por sorpresa incluso a algunos de sus asesores","author":"","date":"octubre 30, 2025","format":false,"excerpt":"Cuando el l\u00edder chino Xi Jinping incluy\u00f3 una referencia a los \u201caltibajos\u201d en su relaci\u00f3n con el presidente Donald Trump en las declaraciones de apertura de su cumbre esta semana, dif\u00edcilmente podr\u00eda haber imaginado el giro que ocurri\u00f3 minutos antes de que comenzaran las conversaciones.Escribiendo desde el Marine One, que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470959,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/06\/china-prueba-nuclear-secreta-acuerdo-trax\/","url_meta":{"origin":1467919,"position":4},"title":"EE.UU. acusa a China de realizar una prueba nuclear secreta mientras el Gobierno de Trump pide un acuerdo nuclear m\u00e1s amplio","author":"","date":"febrero 6, 2026","format":false,"excerpt":"Estados Unidos acus\u00f3 este viernes a China de llevar a cabo una prueba nuclear secreta en 2020, mientras el Gobierno de Trump solicita un acuerdo de armas nucleares m\u00e1s amplio que incluya tanto a China como a Rusia.La acusaci\u00f3n se produce un d\u00eda despu\u00e9s de que el \u00faltimo tratado de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470135,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/01\/15\/record-mundial-pausa-pruebas-nucleares-trax\/","url_meta":{"origin":1467919,"position":5},"title":"R\u00e9cord mundial de paz nuclear: por qu\u00e9 la mayor pausa en ensayos est\u00e1 en grave riesgo","author":"","date":"enero 15, 2026","format":false,"excerpt":"El mundo acaba de alcanzar un hito nuclear hist\u00f3rico. A pesar de la creciente tensi\u00f3n y las amenazas de guerra entre potencias como Rusia y Estados Unidos, el planeta ha logrado su periodo m\u00e1s largo sin detonaciones at\u00f3micas desde el inicio de la era nuclear en 1945. Este r\u00e9cord, marcado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1467919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1467919"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1467919\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1467919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1467919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1467919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}