{"id":1467930,"date":"2025-11-01T03:03:52","date_gmt":"2025-11-01T10:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/01\/madre-indocumentada-redadas-ice-cornhusker-clink-nebraska-trax\/"},"modified":"2025-11-01T03:03:52","modified_gmt":"2025-11-01T10:03:52","slug":"madre-indocumentada-redadas-ice-cornhusker-clink-nebraska-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/11\/01\/madre-indocumentada-redadas-ice-cornhusker-clink-nebraska-trax\/","title":{"rendered":"Madre indocumentada afirma que las redadas de ICE y el &#171;Cornhusker Clink&#187; representan el fin de la Nebraska que fue su hogar"},"content":{"rendered":"<p>Alejandra no sale de casa a menos que sea estrictamente necesario. Falta a sus citas m\u00e9dicas y a la iglesia para no ser detectada. Y si la detienen los agentes de inmigraci\u00f3n, su hijo de 13 a\u00f1os est\u00e1 preparado con una lista de personas a las que llamar y su n\u00famero de seguro social memorizado.<\/p>\n<p>\u201cNo puedo separarme de mis hijos\u201d, dijo la madre indocumentada de 30 a\u00f1os, con cuatro hijos nacidos en Estados Unidos. \u201cSimplemente no puedo arriesgarme\u201d. CNN acord\u00f3 usar solo el nombre de pila de Alejandra para proteger su identidad por respeto a su seguridad, debido a su estatus migratorio.<\/p>\n<p>Seg\u00fan dijo, la idea de que su familia pudiera ser destrozada solo se le pas\u00f3 por la cabeza recientemente, cuando <a href=\"https:\/\/www.cnn.com\/2025\/10\/27\/politics\/trump-ice-shakeup-border-patrol-immigration\">la represi\u00f3n migratoria<\/a> a nivel nacional del presidente Donald Trump penetr\u00f3 en la humilde y tranquila comunidad de Nebraska a la que llama hogar.<\/p>\n<p>En junio, agentes del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE) allanaron una <a href=\"https:\/\/www.cnn.com\/2025\/06\/17\/us\/omaha-ice-raid-meatpacking-plant\">planta empacadora de carne en Omaha, en lo que la agencia describi\u00f3 como el <\/a><a href=\"https:\/\/www.ice.gov\/news\/releases\/ice-federal-partners-assaulted-during-largest-worksite-enforcement-operation-nebraska\">mayor operativo en un centro de trabajo<\/a> en el estado desde el inicio de la administraci\u00f3n Trump.<\/p>\n<p>Alejandra afirma que varios amigos de la familia y conocidos de la iglesia se encontraban entre las decenas de personas detenidas.<\/p>\n<p>Mientras ese evento contin\u00faa generando r\u00e9plicas, un nuevo centro de detenci\u00f3n del ICE, apodado <a href=\"https:\/\/www.cnn.com\/2025\/08\/19\/us\/nebraska-immigration-detention-center\">\u201cCornhusker Clink\u201d,<\/a> abrir\u00e1 pronto sus puertas en el oeste de Nebraska y se espera que albergue hasta 300 adultos, seg\u00fan inform\u00f3 el jueves a CNN un portavoz del gobernador republicano de Nebraska, Jim Pillen.<\/p>\n<p>La instalaci\u00f3n se unir\u00e1 a otros nuevos centros de detenci\u00f3n de ICE en estados liderados por republicanos, incluyendo \u201c<a href=\"https:\/\/www.cnn.com\/2025\/09\/04\/us\/alligator-alcatraz-appeals-court-stay\">Alligator Alcatraz<\/a>\u201d en Florida, \u201cLouisiana Lockup\u201d o <a href=\"https:\/\/www.cnn.com\/2025\/09\/03\/politics\/new-ice-facility-angola-louisiana-prison\">\u201cCamp 57\u201d<\/a> en Louisiana y \u201cSpeedway Slammer\u201d en Indiana.<\/p>\n<p>Estas nuevas instalaciones de ICE \u201cest\u00e1n ampliando significativamente el espacio de detenci\u00f3n para albergar a los inmigrantes indocumentados m\u00e1s peligrosos\u201d, declar\u00f3 el mi\u00e9rcoles un portavoz del Departamento de Seguridad Nacional a CNN. \u201cEsperamos que esta nueva colaboraci\u00f3n con Nebraska se inaugure muy pronto\u201d.<\/p>\n<p>La oficina de Pillen estima que el contrato con el DHS aportar\u00e1 al estado unos US$ 14 millones anuales. Laura Strimple, portavoz de la oficina del gobernador, lo describi\u00f3 como \u201cla \u00faltima medida emprendida por el gobernador Pillen para apoyar al presidente Trump y proteger a los estadounidenses de los inmigrantes ilegales con antecedentes penales. El centro no solo dar\u00e1 servicio a Nebraska, sino tambi\u00e9n a otros estados de la regi\u00f3n\u201d.<\/p>\n<p>Situada a cientos de kil\u00f3metros de la frontera, la apertura de la prisi\u00f3n de Cornhusker Clink podr\u00eda consolidar la posici\u00f3n de Nebraska en el debate nacional sobre inmigraci\u00f3n.<\/p>\n<p>A diferencia de muchos estados que son epicentro de las operaciones de control migratorio, Nebraska est\u00e1 bajo control republicano total y su gobernador no ha eludido el tema.<\/p>\n<p>Pillen firm\u00f3 una <a href=\"https:\/\/governor.nebraska.gov\/gov-pillen-releases-executive-order-establishing-support-federal-immigration-policy-implementation\">orden ejecutiva en enero<\/a> expresando su apoyo a la pol\u00edtica federal de inmigraci\u00f3n, orden\u00f3 el despliegue de la Guardia Nacional de Nebraska en Texas y facilit\u00f3 la <a href=\"https:\/\/governor.nebraska.gov\/gov-pillen-issues-emergency-proclamation-facilitate-activation-national-guard\">activaci\u00f3n de las tropas<\/a> antes de las recientes protestas contra el ICE en su estado.<\/p>\n<p>Tambi\u00e9n destac\u00f3 la supuesta <a href=\"https:\/\/governor.nebraska.gov\/gov-pillen-partners-president-trump-dhs-ice-national-security-efforts\">detenci\u00f3n de un cabecilla de la MS-13<\/a> en Omaha este verano.<\/p>\n<p>Sin embargo, los defensores de los inmigrantes, algunos legisladores estatales y l\u00edderes empresariales afirmaron que esto contrasta con el ambiente acogedor que hab\u00edan construido en el estado con tanto trabajado, especialmente para fortalecer su econom\u00eda.<\/p>\n<p>A diferencia de otros estados, Nebraska no suele considerarse un refugio para inmigrantes, pero algunas zonas del estado son un enclave para los latinos, que han vivido y trabajado en el estado de Cornhuskers durante muchos a\u00f1os, en parte debido a la industria c\u00e1rnica, seg\u00fan afirman defensores de los inmigrantes y l\u00edderes empresariales del estado.<\/p>\n<p>Hoy en d\u00eda, gran parte de la poblaci\u00f3n latina de Nebraska pertenece a la segunda, tercera o incluso cuarta generaci\u00f3n.<\/p>\n<p>En pueblos rurales como Schuyler, Lexington y Madison, conocidos por algunos como \u201cpueblos latinos\u201d, algunos empresarios y l\u00edderes comunitarios se sintieron atra\u00eddos inicialmente por los empleos en las plantas empacadoras de carne y permanecieron all\u00ed durante d\u00e9cadas.<\/p>\n<p>Ahora, las operaciones de inmigraci\u00f3n est\u00e1n amenazando la estabilidad de estas peque\u00f1as comunidades y las actividades industriales en Nebraska, dijo John Hansen, presidente de la <a href=\"https:\/\/nebraskafarmersunion.org\/\">Uni\u00f3n de Agricultores de Nebraska<\/a>.<\/p>\n<p>\u201cHay much\u00edsima gente que simplemente tiene miedo de ir a trabajar, miedo de ser vista en p\u00fablico\u201d, dijo Hansen, se\u00f1alando que muchas granjas y plantas empacadoras de carne est\u00e1n luchando para mantener a su personal.<\/p>\n<p>La industria c\u00e1rnica de Nebraska, que incluye importantes plantas procesadoras de JBS, Tyson Foods, Cargill y Smithfield, depende de la mano de obra inmigrante.<\/p>\n<p>Los inmigrantes, muchos de ellos indocumentados, representan aproximadamente el 53 % de la fuerza laboral del estado, seg\u00fan el <a href=\"https:\/\/www.migrationpolicy.org\/content\/essential-role-immigrants-us-food-supply-chain\">Instituto de Pol\u00edtica Migratoria<\/a>.<\/p>\n<p>Las redadas migratorias, el creciente temor a las deportaciones y los cambios pol\u00edticos han creado \u201cun clima de miedo e intimidaci\u00f3n\u201d entre los trabajadores, dijo Hansen, y algunos miembros del sindicato han expresado en privado su arrepentimiento por haber votado por Trump, quien gan\u00f3 la mayor\u00eda de los votos del estado en las elecciones de 2024, citando la deportaci\u00f3n masiva y los aranceles.<\/p>\n<p>El estado est\u00e1 experimentando una grave escasez de mano de obra, con solo 70 trabajadores disponibles por cada 100 puestos de trabajo vacantes en agosto, seg\u00fan datos de la <a href=\"https:\/\/www.uschamber.com\/workforce\/the-states-suffering-most-from-the-labor-shortage\">C\u00e1mara de Comercio de Estados Unidos<\/a>.<\/p>\n<p>Durante su campa\u00f1a, Trump afirm\u00f3 repetidamente que <a href=\"https:\/\/www.cnn.com\/2024\/06\/17\/politics\/fact-check-donald-trump-jobs-biden-immigration\">los inmigrantes les estaban quitando el trabajo a los estadounidenses.<\/a> Pero en realidad, los economistas afirman que los inmigrantes estaban <a href=\"https:\/\/www.epi.org\/blog\/immigrants-are-not-hurting-u-s-born-workers-six-facts-to-set-the-record-straight\/\">cubriendo importantes carencias laborales.<\/a><\/p>\n<p>Aunque los empleos en la industria c\u00e1rnica inicialmente proporcionaron vidas estables de clase media, seg\u00fan Hansen, lesiones como el s\u00edndrome del t\u00fanel carpiano aumentaron dr\u00e1sticamente a medida que las l\u00edneas de montaje se volvieron m\u00e1s r\u00e1pidas y repetitivas en las d\u00e9cadas de 1960 y 1970, lo que provoc\u00f3 un \u00e9xodo de trabajadores estadounidenses.<\/p>\n<p>Posteriormente, los inmigrantes ocuparon su lugar, dando forma a las granjas, f\u00e1bricas y pueblos de Nebraska durante d\u00e9cadas, afirm\u00f3.<\/p>\n<p>Los inmigrantes, como la familia de Alejandra que emigr\u00f3 primero de M\u00e9xico a Iowa, as\u00ed como los latinos nacidos en Estados Unidos, han pasado d\u00e9cadas dentro de esas plantas, cortando, recortando, empacando y procesando la carne que termina en las mesas de todo Estados Unidos.<\/p>\n<p>Ness Sandoval, profesor de la Universidad de Saint Louis que estudia la desigualdad y la demograf\u00eda latina e inmigrante, recuerda su infancia en Nebraska y el duro trabajo de su padre en una planta empacadora de carne.<\/p>\n<p>\u201cNo ten\u00eda tiempo ni energ\u00eda para asistir a ninguno de mis eventos o partidos. Hac\u00eda un esfuerzo cuando era algo importante, pero ten\u00eda que estar en la cama a las ocho de la noche\u201d, coment\u00f3 Sandoval. \u201cEs un trabajo muy exigente f\u00edsicamente\u201d.<\/p>\n<p>Las lesiones eran tan frecuentes que el padre de Sandoval recibi\u00f3 un premio por pasar un a\u00f1o sin lesionarse.<\/p>\n<p>Con el paso de los a\u00f1os, el trabajo repetitivo le provoc\u00f3 lesiones en el hombro, artritis y, finalmente, se jubil\u00f3 tras fracturarse el hombro en una ca\u00edda, seg\u00fan cont\u00f3 Sandoval.<\/p>\n<p>Aunque su padre se enorgullec\u00eda de su trabajo, nunca quiso que su hijo siguiera el mismo camino \u201cporque entend\u00eda lo duro que era ese trabajo para el cuerpo\u201d, dijo Sandoval.<\/p>\n<p>El edificio de color terracota en McCook, Nebraska, que pronto se conocer\u00e1 como \u201cCornhusker Clink\u201d, era anteriormente una prisi\u00f3n estatal conocida como el Campamento de \u00c9tica Laboral del Departamento de Servicios Correccionales de Nebraska.<\/p>\n<p>Con el objetivo de reintegrar a la comunidad a delincuentes de bajo riesgo, el campamento alberg\u00f3 a m\u00e1s de 180 internos que a menudo trabajaban en la cocina o el almac\u00e9n del centro, seg\u00fan un <a href=\"https:\/\/www.nebraskalegislature.gov\/FloorDocs\/108\/PDF\/Agencies\/Correctional_Services__Department_of\/239_20241230-092524.pdf\">informe<\/a> de 2024.<\/p>\n<p>Otros ocuparon puestos de trabajo en cuadrillas de mantenimiento de carreteras del Departamento de Transporte de Nebraska.<\/p>\n<p>La instalaci\u00f3n, inaugurada en 2001, ten\u00eda como objetivo aliviar el hacinamiento carcelario y \u201cponer plazas en prisi\u00f3n a disposici\u00f3n de delincuentes violentos\u201d.<\/p>\n<p>D\u00e9cadas despu\u00e9s, el sistema penitenciario de Nebraska sigue teniendo dificultades para gestionar su poblaci\u00f3n actual, que supera el 140 % de su capacidad de dise\u00f1o, seg\u00fan un <a href=\"https:\/\/nebraskalegislature.gov\/FloorDocs\/108\/PDF\/Agencies\/Inspector_General_of_the_Nebraska_Correctional_System\/600_20240912-130303.pdf?utm\">informe de 2024<\/a> del inspector general del sistema penitenciario del estado.<\/p>\n<p>Se prev\u00e9 que la reconversi\u00f3n de las instalaciones en McCook desestabilice a\u00fan m\u00e1s el sistema penitenciario, dijo Mindy Chipman, directora ejecutiva de la Uni\u00f3n Estadounidense por las Libertades Civiles de Nebraska.<\/p>\n<p>\u201cTransformar un centro de m\u00ednima seguridad que ofrece servicios de reinserci\u00f3n \u2014servicios que, seg\u00fan el Departamento de Correcciones, son m\u00e1s necesarios que nunca\u2014 en un centro de detenci\u00f3n de inmigrantes elimina el apoyo de los habitantes de Nebraska y confina a personas, la mayor\u00eda de las cuales no tienen antecedentes penales\u201d, dijo Chipman a CNN.<\/p>\n<p>Los presos actuales ser\u00e1n liberados, puestos en libertad condicional o trasladados a otros centros penitenciarios \u201cpara cuando el centro est\u00e9 listo para albergar a los detenidos de ICE\u201d, dijo la oficina del gobernador en un <a href=\"https:\/\/governor.nebraska.gov\/executive-members-gov-pillens-team-meet-judiciary-committee-today\">comunicado de prensa de septiembre<\/a>.<\/p>\n<p>Seg\u00fan informaron funcionarios estatales, cuando se inaugure el centro de detenci\u00f3n de ICE reconvertido, las personas con antecedentes penales menores y delitos graves no violentos podr\u00e1n ser alojadas all\u00ed, pero no aquellas con condenas por delitos graves vinculados a actos de violencia.<\/p>\n<p>CNN se ha puesto en contacto con la oficina del gobernador, el departamento de correcciones y el Departamento de Seguridad Nacional para obtener comentarios.<\/p>\n<p>Seg\u00fan Chipman, el motivo de Pillen no es la seguridad, sino mostrar su apoyo a la agenda antinmigrante de Trump.<\/p>\n<p>El centro de detenci\u00f3n conocido como \u201cCornhusker Clink\u201d es uno de varios proyectos nuevos de detenci\u00f3n respaldados por el proyecto de ley \u201c<a href=\"https:\/\/www.cnn.com\/2025\/07\/03\/business\/trump-big-beautiful-bill-business-economy\">One Big Beautiful Bill<\/a>\u201d de la administraci\u00f3n Trump, valorado en US$ 45.000 millones, que a\u00f1adir\u00eda 80.000 plazas de detenci\u00f3n para ICE en todo el pa\u00eds.<\/p>\n<p>Adem\u00e1s del hacinamiento, los defensores legales de Nebraska dijeron que les preocupa que la ubicaci\u00f3n remota de las instalaciones pueda aumentar la probabilidad de que los detenidos sufran violaciones de derechos civiles, ya que muchos est\u00e1n lejos de sus familias y abogados.<\/p>\n<p>McCook es una de varias peque\u00f1as comunidades en el suroeste de Nebraska y se encuentra relativamente cerca de la Interestatal 80, una importante carretera que viaja hacia el este a Omaha, a unas cuatro horas de distancia, y hacia el oeste a Denver, a tres horas de distancia.<\/p>\n<p>No hay autob\u00fas p\u00fablico desde Omaha, la ciudad m\u00e1s poblada del estado, hasta McCook ni hasta North Platte, un pueblo rural situado a una hora al norte, adonde fueron llevados la mayor\u00eda de los inmigrantes detenidos tras la redada en la planta empacadora de carne en junio.<\/p>\n<p>Todo el transporte debe hacerse en autom\u00f3vil, lo que puede resultar complicado durante los duros inviernos de Nebraska.<\/p>\n<p>\u201cEs m\u00e1s f\u00e1cil llegar a North Platte porque est\u00e1 en la I-80. A McCook hay que ir m\u00e1s lejos y est\u00e1 m\u00e1s en medio de la nada\u201d, dijo Lina Traslavi\u00f1a Stover, directora ejecutiva de Heartland Workers Group, una organizaci\u00f3n sin fines de lucro con sede en Omaha, cuyo trabajo consiste en abogar por los migrantes detenidos en centros de detenci\u00f3n de inmigrantes en el estado.<\/p>\n<p>\u201cEl aislamiento forma parte de la estrategia\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Anne Wruth, abogada del Centro para el Avance de los Inmigrantes y Refugiados, que viaj\u00f3 al oeste para reunirse con un cliente detenido en North Platte, calific\u00f3 el proceso de \u201cpesadilla log\u00edstica\u201d.<\/p>\n<p>Para los legisladores y activistas, que dijeron haberse sorprendido cuando se anunciaron los planes para el centro de detenci\u00f3n de ICE, existen otras necesidades apremiantes como los impuestos sobre la propiedad, la escasez de mano de obra y la vivienda asequible en el estado.<\/p>\n<p>\u201cEsto no fue algo que pasara por nosotros\u201d, dijo la senadora estatal de Nebraska, Dunixi Guereca, dem\u00f3crata en la legislatura oficialmente no partidista cuyo distrito incluye parte de Omaha, refiri\u00e9ndose a los legisladores estatales y los planes para la instalaci\u00f3n, y se\u00f1al\u00f3 que el cronograma era \u201cextremadamente truncado\u201d.<\/p>\n<p>Alejandra se est\u00e1 dando cuenta de que el estado que ella y sus padres han llamado hogar y donde instant\u00e1neamente los hicieron sentir bienvenidos \u2014donde muchos todav\u00eda dicen \u201cpor favor\u201d y \u201cgracias\u201d\u2014 ha comenzado a volverse en su contra, o al menos contra algunas personas.<\/p>\n<p>Cuando la familia lleg\u00f3 por primera vez a Nebraska, Alejandra destac\u00f3 en la escuela, donde estaba rodeada de compa\u00f1eros de clase de Tailandia, Hait\u00ed y El Salvador.<\/p>\n<p>Una diversidad impulsada en parte por el programa de reasentamiento de refugiados del estado, que acoge a la mayor cantidad de refugiados per c\u00e1pita en comparaci\u00f3n con otros de EE.UU., a pesar de la poblaci\u00f3n relativamente peque\u00f1a de Nebraska, de poco m\u00e1s de 2 millones de personas, seg\u00fan un <a href=\"https:\/\/immresearch.org\/publications\/refugee-resettlement-per-capita-which-states-do-the-most\/\">an\u00e1lisis de datos<\/a> de la Immigration Research Initiative, un grupo de expertos sin fines de lucro y no partidista que realiza un seguimiento de los datos de los inmigrantes.<\/p>\n<p>\u201cFue incre\u00edble. Vi much\u00edsimas razas y nacionalidades diferentes; no era la \u00fanica\u201d, cont\u00f3 Alejandra. \u201cA diferencia de Iowa, no me se\u00f1alaron diciendo \u2018ella no es de aqu\u00ed\u2019\u201d.<\/p>\n<p>Sus padres, tambi\u00e9n indocumentados, tienen una casa y pagan impuestos. Han visto crecer a sus hijos y nietos y han disfrutado llev\u00e1ndolos al parque o a los partidos de b\u00e9isbol.<\/p>\n<p>Ante el creciente resentimiento hacia los inmigrantes en Estados Unidos y Nebraska, Alejandra afirma que sus padres pronto abandonar\u00e1n el pa\u00eds, pues planean regresar voluntariamente a M\u00e9xico en seis meses.<\/p>\n<p>Temen ser detenidos y les preocupa que las condiciones en los centros de detenci\u00f3n de ICE puedan poner en riesgo la delicada salud de su madre.<\/p>\n<p>\u201cNo les gusta vivir con miedo\u201d, dijo Alejandra.<\/p>\n<p>Ni ella ni sus hijos son inmunes a ese sentimiento. En las \u00faltimas semanas, Alejandra le dio instrucciones a su hijo de 13 a\u00f1os sobre qu\u00e9 hacer si algo le sucediera mientras iban en coche al supermercado.<\/p>\n<p>\u201cMam\u00e1, qu\u00e9date en el coche y yo entrar\u00e9. Buscar\u00e9 todo lo que necesitamos. Y si pasa algo, te marcahas, pero vete conduciendo\u201d, record\u00f3 Alejandra que le dijo su hijo. \u201cS\u00e9 a qui\u00e9n llamar\u201d.<\/p>\n<p>Mientras mira hacia el futuro, Alejandra se pregunta qu\u00e9 tipo de porvenir les espera a sus hijos peque\u00f1os, sobre todo si la Nebraska que conoce contin\u00faa transform\u00e1ndose y aline\u00e1ndose con la ret\u00f3rica antinmigraci\u00f3n de Trump.<\/p>\n<p>Al igual que sus padres, Alejandra dice que podr\u00eda verse obligada a abandonar el estado y todo lo que conoce a cambio de una vida estable y feliz.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alejandra no sale de casa a menos que sea estrictamente necesario. Falta a sus citas m\u00e9dicas y a la iglesia para no ser detectada. Y si la detienen los agentes de inmigraci\u00f3n, su hijo de 13 a\u00f1os est\u00e1 preparado con una lista de personas a las que llamar y su n\u00famero de seguro social memorizado. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467930","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Madre indocumentada afirma que las redadas de ICE y el &quot;Cornhusker Clink&quot; representan el fin de la Nebraska que fue su hogar - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/01\/madre-indocumentada-redadas-ice-cornhusker-clink-nebraska-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Madre indocumentada afirma que las redadas de ICE y el &quot;Cornhusker Clink&quot; representan el fin de la Nebraska que fue su hogar - Noticias\" \/>\n<meta property=\"og:description\" content=\"Alejandra no sale de casa a menos que sea estrictamente necesario. Falta a sus citas m\u00e9dicas y a la iglesia para no ser detectada. Y si la detienen los agentes de inmigraci\u00f3n, su hijo de 13 a\u00f1os est\u00e1 preparado con una lista de personas a las que llamar y su n\u00famero de seguro social memorizado. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/01\/madre-indocumentada-redadas-ice-cornhusker-clink-nebraska-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-01T10:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/01\/madre-indocumentada-redadas-ice-cornhusker-clink-nebraska-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/01\/madre-indocumentada-redadas-ice-cornhusker-clink-nebraska-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Madre indocumentada afirma que las redadas de ICE y el &#171;Cornhusker Clink&#187; representan el fin de la Nebraska que fue su hogar\",\"datePublished\":\"2025-11-01T10:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/01\/madre-indocumentada-redadas-ice-cornhusker-clink-nebraska-trax\/\"},\"wordCount\":2544,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/01\/madre-indocumentada-redadas-ice-cornhusker-clink-nebraska-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/01\/madre-indocumentada-redadas-ice-cornhusker-clink-nebraska-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/01\/madre-indocumentada-redadas-ice-cornhusker-clink-nebraska-trax\/\",\"name\":\"Madre indocumentada afirma que las redadas de ICE y el \\\"Cornhusker Clink\\\" representan el fin de la Nebraska que fue su hogar - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-01T10:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/01\/madre-indocumentada-redadas-ice-cornhusker-clink-nebraska-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/01\/madre-indocumentada-redadas-ice-cornhusker-clink-nebraska-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/01\/madre-indocumentada-redadas-ice-cornhusker-clink-nebraska-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Madre indocumentada afirma que las redadas de ICE y el &#171;Cornhusker Clink&#187; representan el fin de la Nebraska que fue su hogar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Madre indocumentada afirma que las redadas de ICE y el \"Cornhusker Clink\" representan el fin de la Nebraska que fue su hogar - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/01\/madre-indocumentada-redadas-ice-cornhusker-clink-nebraska-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Madre indocumentada afirma que las redadas de ICE y el \"Cornhusker Clink\" representan el fin de la Nebraska que fue su hogar - Noticias","og_description":"Alejandra no sale de casa a menos que sea estrictamente necesario. Falta a sus citas m\u00e9dicas y a la iglesia para no ser detectada. Y si la detienen los agentes de inmigraci\u00f3n, su hijo de 13 a\u00f1os est\u00e1 preparado con una lista de personas a las que llamar y su n\u00famero de seguro social memorizado. [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/01\/madre-indocumentada-redadas-ice-cornhusker-clink-nebraska-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-01T10:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/01\/madre-indocumentada-redadas-ice-cornhusker-clink-nebraska-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/01\/madre-indocumentada-redadas-ice-cornhusker-clink-nebraska-trax\/"},"author":{"name":"","@id":""},"headline":"Madre indocumentada afirma que las redadas de ICE y el &#171;Cornhusker Clink&#187; representan el fin de la Nebraska que fue su hogar","datePublished":"2025-11-01T10:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/01\/madre-indocumentada-redadas-ice-cornhusker-clink-nebraska-trax\/"},"wordCount":2544,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/01\/madre-indocumentada-redadas-ice-cornhusker-clink-nebraska-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/01\/madre-indocumentada-redadas-ice-cornhusker-clink-nebraska-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/01\/madre-indocumentada-redadas-ice-cornhusker-clink-nebraska-trax\/","name":"Madre indocumentada afirma que las redadas de ICE y el \"Cornhusker Clink\" representan el fin de la Nebraska que fue su hogar - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-01T10:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/01\/madre-indocumentada-redadas-ice-cornhusker-clink-nebraska-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/01\/madre-indocumentada-redadas-ice-cornhusker-clink-nebraska-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/01\/madre-indocumentada-redadas-ice-cornhusker-clink-nebraska-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Madre indocumentada afirma que las redadas de ICE y el &#171;Cornhusker Clink&#187; representan el fin de la Nebraska que fue su hogar"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/11\/01\/madre-indocumentada-redadas-ice-cornhusker-clink-nebraska-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Madre indocumentada afirma que las redadas de ICE y el &#171;Cornhusker Clink&#187; representan el fin de la Nebraska que fue su hogar","url":"http:\/\/noticiasya.com\/monterey-salinas\/2025\/11\/01\/madre-indocumentada-redadas-ice-cornhusker-clink-nebraska-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2025\/11\/01\/madre-indocumentada-redadas-ice-cornhusker-clink-nebraska-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-01T10:03:52Z","datePublished":"2025-11-01T10:03:52Z","dateModified":"2025-11-01T10:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Madre indocumentada afirma que las redadas de ICE y el &#171;Cornhusker Clink&#187; representan el fin de la Nebraska que fue su hogar\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2025\\\/11\\\/01\\\/madre-indocumentada-redadas-ice-cornhusker-clink-nebraska-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2025\\\/11\\\/01\\\/madre-indocumentada-redadas-ice-cornhusker-clink-nebraska-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-01T10:03:52Z\",\"datePublished\":\"2025-11-01T10:03:52Z\",\"dateModified\":\"2025-11-01T10:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1450075,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/06\/05\/miss-universo-ecuador-46-anos-hijos-orix\/","url_meta":{"origin":1467930,"position":0},"title":"Miss Universo Ecuador tiene su primera candidata de 46 a\u00f1os y siete concursantes son madres","author":"","date":"junio 5, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El certamen de Miss Universo Ecuador est\u00e1 atravesando por un momento distinto desde que la organizaci\u00f3n internacional del Miss Universo modific\u00f3 ciertas reglas con la finalidad de promover un concurso m\u00e1s inclusivo y diverso.En 2024 ya no existe un l\u00edmite de edad para participar y, por esa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461790,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/04\/30\/que-paso-madres-deportadas-honduras-hijos-orix\/","url_meta":{"origin":1467930,"position":1},"title":"\u00bfQu\u00e9 pas\u00f3 en el caso de las madres deportadas a Honduras junto a sus hijos menores de edad que son ciudadanos de EE.UU.?","author":"","date":"abril 30, 2025","format":false,"excerpt":"La pol\u00e9mica campa\u00f1a contra la inmigraci\u00f3n del Gobierno de Estados Unidos sigue su curso y casos recientes han hecho sonar las alarmas porque involucran a ni\u00f1os que son ciudadanos estadounidenses.En los primeros tres meses de su segundo mandato, la administraci\u00f3n del presidente Donald Trump ha deportado a 139.000 inmigrantes. Entre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471312,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/17\/ninos-estados-unidos-esconderse-ice-escuela-trax\/","url_meta":{"origin":1467930,"position":2},"title":"Naci\u00f3 en EE.UU., pero esta ni\u00f1a de 10 a\u00f1os sabe d\u00f3nde esconderse en la escuela si ICE aparece","author":"","date":"febrero 17, 2026","format":false,"excerpt":"Madeleine, como la mayor\u00eda de los ni\u00f1os de primaria, disfruta del recreo en el patio de juegos, un refugio donde se forman amistades, se construye la independencia y la imaginaci\u00f3n vuela libremente.Pero \u00faltimamente, se r\u00ede y se juega menos all\u00ed. Las conversaciones habituales de los ni\u00f1os sobre programas de televisi\u00f3n,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460126,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/03\/19\/jeanette-vizguerra-activista-deportacion-trump-trax\/","url_meta":{"origin":1467930,"position":3},"title":"Tras su detenci\u00f3n, la activista Jeanette Vizguerra se convierte en s\u00edmbolo del miedo en la escalada migratoria de Trump","author":"","date":"marzo 19, 2025","format":false,"excerpt":"Una madre de cuatro hijos, indocumentada, que trabaja en Target y que fue homenajeada por la revista Time en el pasado, se ha convertido en el \u00faltimo s\u00edmbolo del miedo y la agitaci\u00f3n que se extienden bajo la nueva ofensiva migratoria de la administraci\u00f3n Trump, tras ser detenida este lunes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460086,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/03\/18\/ice-detiene-jeanette-vizguerra-activista-time-trax\/","url_meta":{"origin":1467930,"position":4},"title":"ICE detiene a Jeanette Vizguerra, activista por los derechos de los migrantes, reconocida por la revista Time","author":"","date":"marzo 18, 2025","format":false,"excerpt":"Una madre indocumentada y activista de alto perfil fue detenida por el Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s), dijo su abogado a CNN.Jeanette Vizguerra fue noticia nacional en los \u00faltimos a\u00f1os como defensora de la reforma migratoria que se refugi\u00f3 en una iglesia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465555,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/08\/16\/pediatras-familias-inmigrantes-separar-hijos-trax\/","url_meta":{"origin":1467930,"position":5},"title":"Los pediatras preparan silenciosamente a las familias inmigrantes para lo impensable: separarse de sus hijos","author":"","date":"agosto 16, 2025","format":false,"excerpt":"En un c\u00e1lido d\u00eda de junio en Nashville, Briana acunaba a su hijo de un a\u00f1o en la sala de espera del pediatra. Estaba all\u00ed para su chequeo de rutina, esperando hablar sobre vacunas y tablas de crecimiento.Sin embargo, mientras Briana hac\u00eda rebotar a su beb\u00e9 sobre su regazo en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1467930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1467930"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1467930\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1467930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1467930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1467930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}