{"id":1467939,"date":"2025-11-01T10:03:47","date_gmt":"2025-11-01T17:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/01\/prokrovsk-ucrania-combates-rusia-trax\/"},"modified":"2025-11-01T10:03:47","modified_gmt":"2025-11-01T17:03:47","slug":"prokrovsk-ucrania-combates-rusia-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/11\/01\/prokrovsk-ucrania-combates-rusia-trax\/","title":{"rendered":"Se intensifican los combates en torno a ciudad clave de Ucrania en medio de nuevos ataques contra industria energ\u00e9tica rusa"},"content":{"rendered":"<p>Los combates por el control del centro estrat\u00e9gico de Pokrovsk, en el este de Ucrania, se intensificaron en las \u00faltimas horas, mientras el Ministerio de Defensa ruso afirma haber eliminado a un grupo de fuerzas especiales ucranianas enviado para ayudar a defender la zona.<\/p>\n<p>En las \u00faltimas semanas, unidades rusas han comenzado a penetrar en Pokrovsk y se han acercado a las \u00faltimas rutas de reabastecimiento que mantienen a las fuerzas ucranianas en la ciudad.<\/p>\n<p>Seg\u00fan el Ministerio de Defensa ruso, las fuerzas especiales ucranianas aterrizaron en helic\u00f3ptero en las afueras noroccidentales de Pokrovsk. Im\u00e1genes grabadas con drones y difundidas por un canal no oficial ruso de Telegram mostraron a soldados ucranianos despleg\u00e1ndose desde un helic\u00f3ptero Blackhawk. El Ministerio de Defensa afirm\u00f3 que once de los soldados que aterrizaron murieron. Se desconoce la fecha de la misi\u00f3n.<\/p>\n<p>Una fuente de la inteligencia ucraniana declar\u00f3 a CNN que la afirmaci\u00f3n era falsa. A\u00f1adi\u00f3 que contin\u00faan las labores de estabilizaci\u00f3n en Pokrovsk, dirigidas por el jefe de la Inteligencia de Defensa de Ucrania, Kyrylo Budanov.<\/p>\n<p>El 7\u00ba Cuerpo de Asalto A\u00e9reo de Ucrania tambi\u00e9n confirm\u00f3 un aterrizaje exitoso en la zona de Pokrovsk. \u201cFue una operaci\u00f3n compleja que requiri\u00f3 la acci\u00f3n coordinada de varias unidades\u201d, afirm\u00f3.<\/p>\n<p>Seg\u00fan el Cuerpo, las unidades ucranianas han logrado mejorar su posici\u00f3n t\u00e1ctica en varios distritos de la ciudad. \u201cEstamos aumentando el n\u00famero de grupos de asalto en Pokrovsk\u201d, indic\u00f3, y a\u00f1adi\u00f3 que 85 soldados rusos murieron en Pokrovsk durante la \u00faltima semana.<\/p>\n<p>El comandante militar ucraniano, el general Oleksandr Syrskyi, declar\u00f3 este s\u00e1bado que Pokrovsk y la vecina ciudad de Myrnohrad \u201cno est\u00e1n rodeadas ni bloqueadas, y estamos haciendo todo lo posible para mantener el suministro log\u00edstico\u201d.<\/p>\n<p>\u201cSe est\u00e1 llevando a cabo una operaci\u00f3n integral para destruir y expulsar a las fuerzas enemigas de Pokrovsk\u201d, afirm\u00f3 Syrskyi, a\u00f1adiendo que hab\u00eda visitado la zona para coordinar su defensa.<\/p>\n<p>Las unidades enemigas contin\u00faan \u201cintentando infiltrarse en zonas residenciales y cortar nuestras rutas de suministro\u201d, agreg\u00f3.<\/p>\n<p>Por su parte, el Ministerio de Defensa ruso afirm\u00f3 \u2014tambi\u00e9n este s\u00e1bado\u2014 que sus unidades \u201ccontin\u00faan destruyendo formaciones de las Fuerzas Armadas ucranianas rodeadas en la zona de la estaci\u00f3n de tren\u201d de Pokrovsk, y que han repelido varios intentos de las fuerzas ucranianas de escapar de la ciudad. A\u00f1adi\u00f3 que el cerco a Pokrovsk y Myrnohrad se est\u00e1 estrechando.<\/p>\n<p>El presidente Volodymyr Zelensky declar\u00f3 el martes que unos 200 soldados rusos se hab\u00edan infiltrado en Pokrovsk. Un video geolocalizado ha mostrado a soldados rusos en la zona sur de la ciudad, movi\u00e9ndose en peque\u00f1os grupos.<\/p>\n<p>Seg\u00fan el Instituto para el Estudio de la Guerra, con sede en Washington, las fuerzas ucranianas han intentado un contraataque y han avanzado ligeramente al norte de la ciudad.<\/p>\n<p>Si Pokrovsk cayera, ser\u00eda la mayor \u00e1rea urbana tomada por las fuerzas rusas desde la captura de Bakhmut en mayo de 2023. La ciudad es un nudo de comunicaciones por carretera y ferrocarril, y su ocupaci\u00f3n acercar\u00eda a las fuerzas rusas a las ciudades m\u00e1s grandes de Kramatorsk y Kostiantynivka, en el cintur\u00f3n industrial de Donetsk.<\/p>\n<p>Seg\u00fan el sitio web no oficial ucraniano DeepState, que analiza el campo de batalla, las fuerzas rusas ganaron 267 kil\u00f3metros cuadrados de territorio ucraniano en octubre, la misma superficie que en septiembre.<\/p>\n<p><a href=\"https:\/\/cnnespanol.cnn.com\/2025\/10\/24\/mundo\/rusia-ee-uu-conversciones-sanciones-trax\">Los esfuerzos del presidente estadounidense Donald Trump por lograr un alto el fuego en Ucrania no han dado resultado<\/a>. El Kremlin insiste en que las causas profundas del conflicto \u2014incluida la expansi\u00f3n de la OTAN hacia el este y lo que ha denominado la \u201cnazificaci\u00f3n\u201d de Ucrania\u2014 deben abordarse antes de que pueda haber una tregua.<\/p>\n<p>Mosc\u00fa ha declarado que los objetivos originales de lo que denomina su Operaci\u00f3n Militar Especial son innegociables: la soberan\u00eda sobre cuatro regiones orientales de Ucrania, incluida Donetsk.<\/p>\n<p>Mientras las fuerzas rusas avanzan en varios puntos del frente, Ucrania contin\u00faa sus objetivos de largo plazo para destruir e interrumpir la infraestructura energ\u00e9tica y militar de Rusia.<\/p>\n<p>El viernes, saboteadores ucranianos volaron tres oleoductos que transportaban combustible en la regi\u00f3n de Mosc\u00fa, seg\u00fan informaron funcionarios de defensa del pa\u00eds. Este es el \u00faltimo ataque de Kyiv contra refiner\u00edas, estaciones de bombeo y oleoductos.<\/p>\n<p>\u201cEl oleoducto \u2018Koltsevoy\u2019, que abastec\u00eda al ej\u00e9rcito de ocupaci\u00f3n ruso\u201d, fue desactivado el viernes en una operaci\u00f3n especial, seg\u00fan un comunicado de la Inteligencia de Defensa de Ucrania (DI).<\/p>\n<p>La ID public\u00f3 una imagen que muestra lo que parecen ser artefactos explosivos colocados en tres oleoductos distintos cerca de Ramenskoye, al sur de Mosc\u00fa, que estaban protegidos por redes antidrones. Un video publicado por la ID muestra una explosi\u00f3n que lanz\u00f3 llamas a cientos de metros de altura.<\/p>\n<p>\u201cLos tres oleoductos utilizados por el agresor para transportar gasolina, di\u00e9sel y combustible de aviaci\u00f3n fueron dinamitados con \u00e9xito y simult\u00e1neamente\u201d, declar\u00f3 la ID.<\/p>\n<p>A diferencia de muchos ataques recientes con drones y misiles, los ucranianos utilizaron un equipo de sabotaje para colocar los artefactos explosivos en el lugar, seg\u00fan el video de la ID.<\/p>\n<p>Las autoridades rusas no se han pronunciado sobre la explosi\u00f3n ni sobre posibles interrupciones en el suministro de combustible. Sin embargo, las autoridades locales del distrito vecino de Zhukovsky informaron de cortes de luz para algunos consumidores el viernes, sin especificar la causa.<\/p>\n<p>El oleoducto que rodea Mosc\u00fa se abastece de varias refiner\u00edas. Tiene una capacidad de bombeo de hasta 3 millones de toneladas de combustible para aviaci\u00f3n, hasta 2,8 millones de toneladas de di\u00e9sel y hasta 1,6 millones de toneladas de gasolina al a\u00f1o, seg\u00fan DI.<\/p>\n<p>Ucrania comenz\u00f3 a atacar la infraestructura energ\u00e9tica rusa de forma persistente durante el verano, utilizando drones y misiles de largo alcance para atacar instalaciones en territorio ruso.<\/p>\n<p>\u201cNuestros ataques han tenido mayor impacto que las sanciones [contra Rusia]\u201d, declar\u00f3 Budanov. \u201cHemos causado mucho m\u00e1s da\u00f1o a la Federaci\u00f3n Rusa mediante acciones directas que con cualquier medida de influencia econ\u00f3mica que se haya implementado hasta ahora\u201d.<\/p>\n<p>El presidente de Ucrania, Zelensky, afirm\u00f3 a principios de este mes que hasta un 20 % de la capacidad de refinaci\u00f3n rusa hab\u00eda quedado fuera de servicio, y varias regiones rusas han reportado escasez de gasolina.<\/p>\n<p>Rusia ha importado m\u00e1s combustible de Belar\u00fas para compensar la escasez.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los combates por el control del centro estrat\u00e9gico de Pokrovsk, en el este de Ucrania, se intensificaron en las \u00faltimas horas, mientras el Ministerio de Defensa ruso afirma haber eliminado a un grupo de fuerzas especiales ucranianas enviado para ayudar a defender la zona. En las \u00faltimas semanas, unidades rusas han comenzado a penetrar en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467939","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Se intensifican los combates en torno a ciudad clave de Ucrania en medio de nuevos ataques contra industria energ\u00e9tica rusa - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/01\/prokrovsk-ucrania-combates-rusia-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se intensifican los combates en torno a ciudad clave de Ucrania en medio de nuevos ataques contra industria energ\u00e9tica rusa - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los combates por el control del centro estrat\u00e9gico de Pokrovsk, en el este de Ucrania, se intensificaron en las \u00faltimas horas, mientras el Ministerio de Defensa ruso afirma haber eliminado a un grupo de fuerzas especiales ucranianas enviado para ayudar a defender la zona. En las \u00faltimas semanas, unidades rusas han comenzado a penetrar en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/01\/prokrovsk-ucrania-combates-rusia-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-01T17:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/01\/prokrovsk-ucrania-combates-rusia-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/01\/prokrovsk-ucrania-combates-rusia-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Se intensifican los combates en torno a ciudad clave de Ucrania en medio de nuevos ataques contra industria energ\u00e9tica rusa\",\"datePublished\":\"2025-11-01T17:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/01\/prokrovsk-ucrania-combates-rusia-trax\/\"},\"wordCount\":1124,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/01\/prokrovsk-ucrania-combates-rusia-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/01\/prokrovsk-ucrania-combates-rusia-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/01\/prokrovsk-ucrania-combates-rusia-trax\/\",\"name\":\"Se intensifican los combates en torno a ciudad clave de Ucrania en medio de nuevos ataques contra industria energ\u00e9tica rusa - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-01T17:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/01\/prokrovsk-ucrania-combates-rusia-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/01\/prokrovsk-ucrania-combates-rusia-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/01\/prokrovsk-ucrania-combates-rusia-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se intensifican los combates en torno a ciudad clave de Ucrania en medio de nuevos ataques contra industria energ\u00e9tica rusa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se intensifican los combates en torno a ciudad clave de Ucrania en medio de nuevos ataques contra industria energ\u00e9tica rusa - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/01\/prokrovsk-ucrania-combates-rusia-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Se intensifican los combates en torno a ciudad clave de Ucrania en medio de nuevos ataques contra industria energ\u00e9tica rusa - Noticias","og_description":"Los combates por el control del centro estrat\u00e9gico de Pokrovsk, en el este de Ucrania, se intensificaron en las \u00faltimas horas, mientras el Ministerio de Defensa ruso afirma haber eliminado a un grupo de fuerzas especiales ucranianas enviado para ayudar a defender la zona. En las \u00faltimas semanas, unidades rusas han comenzado a penetrar en [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/01\/prokrovsk-ucrania-combates-rusia-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-01T17:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/01\/prokrovsk-ucrania-combates-rusia-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/01\/prokrovsk-ucrania-combates-rusia-trax\/"},"author":{"name":"","@id":""},"headline":"Se intensifican los combates en torno a ciudad clave de Ucrania en medio de nuevos ataques contra industria energ\u00e9tica rusa","datePublished":"2025-11-01T17:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/01\/prokrovsk-ucrania-combates-rusia-trax\/"},"wordCount":1124,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/01\/prokrovsk-ucrania-combates-rusia-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/01\/prokrovsk-ucrania-combates-rusia-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/01\/prokrovsk-ucrania-combates-rusia-trax\/","name":"Se intensifican los combates en torno a ciudad clave de Ucrania en medio de nuevos ataques contra industria energ\u00e9tica rusa - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-01T17:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/01\/prokrovsk-ucrania-combates-rusia-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/01\/prokrovsk-ucrania-combates-rusia-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/01\/prokrovsk-ucrania-combates-rusia-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Se intensifican los combates en torno a ciudad clave de Ucrania en medio de nuevos ataques contra industria energ\u00e9tica rusa"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/11\/01\/prokrovsk-ucrania-combates-rusia-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Se intensifican los combates en torno a ciudad clave de Ucrania en medio de nuevos ataques contra industria energ\u00e9tica rusa","url":"http:\/\/noticiasya.com\/monterey-salinas\/2025\/11\/01\/prokrovsk-ucrania-combates-rusia-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2025\/11\/01\/prokrovsk-ucrania-combates-rusia-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-01T17:03:47Z","datePublished":"2025-11-01T17:03:47Z","dateModified":"2025-11-01T17:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Se intensifican los combates en torno a ciudad clave de Ucrania en medio de nuevos ataques contra industria energ\\u00e9tica rusa\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2025\\\/11\\\/01\\\/prokrovsk-ucrania-combates-rusia-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2025\\\/11\\\/01\\\/prokrovsk-ucrania-combates-rusia-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-01T17:03:47Z\",\"datePublished\":\"2025-11-01T17:03:47Z\",\"dateModified\":\"2025-11-01T17:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1452299,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/30\/ataque-ruso-mata-menor-parque-infantil-jarkiv-trax\/","url_meta":{"origin":1467939,"position":0},"title":"Ataque ruso mata a un menor en un parque infantil de J\u00e1rkiv, seg\u00fan autoridades ucranianas","author":"","date":"agosto 30, 2024","format":false,"excerpt":"(CNN) --\u00a0Un ataque mortal en la ciudad ucraniana de J\u00e1rkiv este viernes mat\u00f3 a una ni\u00f1a en un parque infantil y dej\u00f3 a otros muertos en un edificio residencial, dijeron las autoridades ucranianas. Al menos cinco personas murieron y 28 resultaron heridas en el ataque.El ataque del viernes \"no habr\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457306,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/01\/07\/rusia-ciudad-este-ucrania-combates-kursk-trax\/","url_meta":{"origin":1467939,"position":1},"title":"Rusia afirma haber capturado una ciudad del este de Ucrania mientras contin\u00faan los combates en Kursk","author":"","date":"enero 7, 2025","format":false,"excerpt":"Rusia afirm\u00f3 que sus fuerzas capturaron una ciudad maltrecha pero estrat\u00e9gica en la regi\u00f3n oriental ucraniana de Donetsk, mientras que el ej\u00e9rcito ucraniano dijo que golpe\u00f3 un puesto de mando durante su contraataque en la regi\u00f3n rusa de Kursk.Tras meses de intensos combates, el Ministerio de Defensa de Rusia afirm\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468144,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/11\/08\/fuerzas-rusas-captura-pokrovsk-victoria-gran-importancia-trax\/","url_meta":{"origin":1467939,"position":2},"title":"Las fuerzas rusas est\u00e1n a punto de capturar finalmente Pokrovsk, una victoria de gran importancia simb\u00f3lica con un alto coste","author":"","date":"noviembre 8, 2025","format":false,"excerpt":"Las fuerzas rusas parecen estar a punto de tomar finalmente la ciudad ucraniana oriental de Pokrovsk, una victoria simb\u00f3lica que el presidente Vladimir Putin ha estado persiguiendo durante 21 meses a un costo cada vez mayor.Los combates dentro de la ciudad se han intensificado en los \u00faltimos d\u00edas, tras la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456497,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/12\/11\/fuerzas-rusas-ciudad-clave-pokrovsk-ucrania-trax\/","url_meta":{"origin":1467939,"position":3},"title":"Las fuerzas rusas se encuentran a unos 3 kil\u00f3metros de la ciudad clave de Pokrovsk en Ucrania","author":"","date":"diciembre 11, 2024","format":false,"excerpt":"Las fuerzas rusas se encuentran ahora a s\u00f3lo tres kil\u00f3metros de las afueras de la ciudad clave de Pokrovsk, en el este de Ucrania, tras haber avanzado este mi\u00e9rcoles, seg\u00fan el servicio de mapas ucraniano DeepState. Tambi\u00e9n destruyeron y capturaron posiciones ucranianas cerca de la ciudad, dijo un portavoz del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463336,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/06\/08\/rusia-avanzado-region-central-ucrania-trax\/","url_meta":{"origin":1467939,"position":4},"title":"Rusia afirma haber avanzado por primera vez hacia regi\u00f3n central de Ucrania","author":"","date":"junio 8, 2025","format":false,"excerpt":"Rusia afirm\u00f3 este domingo que sus fuerzas est\u00e1n avanzando por primera vez en la regi\u00f3n de Dnipropetrovsk, en el centro de Ucrania, una zona a la que ha estado intentando llegar durante meses, en una maniobra que podr\u00eda crear nuevos problemas para las muy limitadas fuerzas de Kyiv.Subunidades de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468389,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/11\/16\/rusia-replantea-forma-guerra-ucrania-trax\/","url_meta":{"origin":1467939,"position":5},"title":"De la picadora de carne a los ciclomotores: c\u00f3mo Rusia replante\u00f3 su forma de hacer la guerra en Ucrania","author":"","date":"noviembre 16, 2025","format":false,"excerpt":"La escena parece casi postapocal\u00edptica. Un convoy de soldados rusos emerge de una densa niebla y avanza hacia la ciudad ucraniana de Pokrovsk, en el este. Algunos de los soldados van en motocicletas y ciclomotores; otros aparecen de pie en la parte trasera de una camioneta destartalada. Un grupo viaja\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1467939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1467939"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1467939\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1467939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1467939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1467939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}