{"id":1470657,"date":"2026-01-30T07:03:40","date_gmt":"2026-01-30T15:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/30\/playoffs-champions-league-partidos-cruces-fechas-orix\/"},"modified":"2026-01-30T07:03:40","modified_gmt":"2026-01-30T15:03:40","slug":"playoffs-champions-league-partidos-cruces-fechas-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/01\/30\/playoffs-champions-league-partidos-cruces-fechas-orix\/","title":{"rendered":"As\u00ed quedaron las eliminatorias de los playoffs de la Champions League: partidos, cruces, fechas y m\u00e1s"},"content":{"rendered":"<p>El sorteo de los <em>playoffs<\/em> de la Champions League 2025\/26 dej\u00f3 un nuevo cruce entre el Benfica y el Real Madrid, que intentar\u00e1 tomarse revancha de la dolorosa derrota sufrida en la \u00faltima jornada de la fase de liga, y un duelo franc\u00e9s entre el vigente campe\u00f3n, el Par\u00eds Saint-Germain, y el M\u00f3naco.<\/p>\n<p>Los equipos clasificados entre el noveno y el vig\u00e9simo cuarto puesto disputar\u00e1n eliminatorias de ida y vuelta entre el 17 y el 25 de febrero, cuyos ganadores avanzar\u00e1n a los octavos de final, donde ya esperan los ocho mejores de la fase inicial.<\/p>\n<p>Benfica y Real Madrid volver\u00e1n a verse las caras tras el 4-2 en Lisboa, sellado con el hist\u00f3rico gol del portero ucraniano Anatoliy Trubin en el minuto 98, que dej\u00f3 al equipo espa\u00f1ol noveno, a un punto del Manchester City. La ida se jugar\u00e1 de nuevo en el estadio Da Luz y la vuelta en el Santiago Bernab\u00e9u, en una eliminatoria sin margen de error para el conjunto dirigido por \u00c1lvaro Arbeloa. El reencuentro tendr\u00e1 adem\u00e1s el regreso de Jose Mourinho al Bernab\u00e9u, ahora al frente del Benfica.<\/p>\n<p>El PSG, und\u00e9cimo tras cerrar la fase de liga sin victorias en sus tres \u00faltimos partidos, se medir\u00e1 con el M\u00f3naco, vig\u00e9simo primero. El equipo de Luis Enrique Mart\u00ednez afronta de nuevo esta ronda, como la pasada temporada, cuando super\u00f3 con contundencia a otro rival franc\u00e9s antes de encaminarse hacia su primer t\u00edtulo continental.<\/p>\n<p>El Atl\u00e9tico de Madrid, que se qued\u00f3 a tres puntos del top 8 tras caer en la \u00faltima jornada ante el Bodo\/Glimt, se enfrentar\u00e1 al Club Brujas. Sobre el papel, el equipo de Diego Pablo Simeone parte como favorito, aunque el conjunto belga ha demostrado ser competitivo, especialmente en casa, y capaz de plantar cara a rivales de mayor entidad.<\/p>\n<p>Entre los otros emparejamientos destacados figuran el Borussia Dortmund ante el Atalanta, ambos fuera de los ocho primeros tras dos derrotas consecutivas; el Inter de Mil\u00e1n, l\u00edder de la Serie A, frente al Bodo\/Glimt, reforzado por sus recientes victorias ante el Manchester City y el Atl\u00e9tico; y la Juventus contra el Galatasaray, un rival siempre peligroso en su estadio. El Newcastle United se medir\u00e1 al Qarabag azer\u00ed, una de las revelaciones del torneo, mientras que el Bayer Leverkusen volver\u00e1 a cruzarse con el Olympiacos, campe\u00f3n griego dirigido por el espa\u00f1ol Jos\u00e9 Luis Mendil\u00edbar, en una eliminatoria marcada por la irregularidad del conjunto alem\u00e1n.<\/p>\n<ul>\n<li><strong>Playoffs: <\/strong>17 y 18 de febrero (ida), 24 y 25 de febrero (vuelta).<\/li>\n<li><strong>Octavos de final: <\/strong>10 y 11 de marzo (ida), 17 y 18 de marzo (vuelta).<\/li>\n<li><strong>Cuartos de final: <\/strong>7 y 8 de abril (ida), 14 y 15 de abril (vuelta).<\/li>\n<li><strong>Semifinales:<\/strong> 28 y 29 de abril (ida), 5 y 6 de mayo (vuelta).<\/li>\n<li><strong>Final:<\/strong> 30 de mayo.<\/li>\n<\/ul>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El sorteo de los playoffs de la Champions League 2025\/26 dej\u00f3 un nuevo cruce entre el Benfica y el Real Madrid, que intentar\u00e1 tomarse revancha de la dolorosa derrota sufrida en la \u00faltima jornada de la fase de liga, y un duelo franc\u00e9s entre el vigente campe\u00f3n, el Par\u00eds Saint-Germain, y el M\u00f3naco. Los equipos [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1470657","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>As\u00ed quedaron las eliminatorias de los playoffs de la Champions League: partidos, cruces, fechas y m\u00e1s - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/30\/playoffs-champions-league-partidos-cruces-fechas-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"As\u00ed quedaron las eliminatorias de los playoffs de la Champions League: partidos, cruces, fechas y m\u00e1s - Noticias\" \/>\n<meta property=\"og:description\" content=\"El sorteo de los playoffs de la Champions League 2025\/26 dej\u00f3 un nuevo cruce entre el Benfica y el Real Madrid, que intentar\u00e1 tomarse revancha de la dolorosa derrota sufrida en la \u00faltima jornada de la fase de liga, y un duelo franc\u00e9s entre el vigente campe\u00f3n, el Par\u00eds Saint-Germain, y el M\u00f3naco. Los equipos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/30\/playoffs-champions-league-partidos-cruces-fechas-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-30T15:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/30\/playoffs-champions-league-partidos-cruces-fechas-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/30\/playoffs-champions-league-partidos-cruces-fechas-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"As\u00ed quedaron las eliminatorias de los playoffs de la Champions League: partidos, cruces, fechas y m\u00e1s\",\"datePublished\":\"2026-01-30T15:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/30\/playoffs-champions-league-partidos-cruces-fechas-orix\/\"},\"wordCount\":501,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/30\/playoffs-champions-league-partidos-cruces-fechas-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/30\/playoffs-champions-league-partidos-cruces-fechas-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/30\/playoffs-champions-league-partidos-cruces-fechas-orix\/\",\"name\":\"As\u00ed quedaron las eliminatorias de los playoffs de la Champions League: partidos, cruces, fechas y m\u00e1s - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-30T15:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/30\/playoffs-champions-league-partidos-cruces-fechas-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/30\/playoffs-champions-league-partidos-cruces-fechas-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/30\/playoffs-champions-league-partidos-cruces-fechas-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"As\u00ed quedaron las eliminatorias de los playoffs de la Champions League: partidos, cruces, fechas y m\u00e1s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"As\u00ed quedaron las eliminatorias de los playoffs de la Champions League: partidos, cruces, fechas y m\u00e1s - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/30\/playoffs-champions-league-partidos-cruces-fechas-orix\/","og_locale":"es_ES","og_type":"article","og_title":"As\u00ed quedaron las eliminatorias de los playoffs de la Champions League: partidos, cruces, fechas y m\u00e1s - Noticias","og_description":"El sorteo de los playoffs de la Champions League 2025\/26 dej\u00f3 un nuevo cruce entre el Benfica y el Real Madrid, que intentar\u00e1 tomarse revancha de la dolorosa derrota sufrida en la \u00faltima jornada de la fase de liga, y un duelo franc\u00e9s entre el vigente campe\u00f3n, el Par\u00eds Saint-Germain, y el M\u00f3naco. Los equipos [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/30\/playoffs-champions-league-partidos-cruces-fechas-orix\/","og_site_name":"Noticias","article_published_time":"2026-01-30T15:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/30\/playoffs-champions-league-partidos-cruces-fechas-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/30\/playoffs-champions-league-partidos-cruces-fechas-orix\/"},"author":{"name":"","@id":""},"headline":"As\u00ed quedaron las eliminatorias de los playoffs de la Champions League: partidos, cruces, fechas y m\u00e1s","datePublished":"2026-01-30T15:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/30\/playoffs-champions-league-partidos-cruces-fechas-orix\/"},"wordCount":501,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/30\/playoffs-champions-league-partidos-cruces-fechas-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/30\/playoffs-champions-league-partidos-cruces-fechas-orix\/","url":"https:\/\/noticiasya.com\/2026\/01\/30\/playoffs-champions-league-partidos-cruces-fechas-orix\/","name":"As\u00ed quedaron las eliminatorias de los playoffs de la Champions League: partidos, cruces, fechas y m\u00e1s - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-30T15:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/30\/playoffs-champions-league-partidos-cruces-fechas-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/30\/playoffs-champions-league-partidos-cruces-fechas-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/30\/playoffs-champions-league-partidos-cruces-fechas-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"As\u00ed quedaron las eliminatorias de los playoffs de la Champions League: partidos, cruces, fechas y m\u00e1s"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/01\/30\/playoffs-champions-league-partidos-cruces-fechas-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"As\u00ed quedaron las eliminatorias de los playoffs de la Champions League: partidos, cruces, fechas y m\u00e1s","url":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/01\/30\/playoffs-champions-league-partidos-cruces-fechas-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/01\/30\/playoffs-champions-league-partidos-cruces-fechas-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-30T15:03:40Z","datePublished":"2026-01-30T15:03:40Z","dateModified":"2026-01-30T15:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"As\\u00ed quedaron las eliminatorias de los playoffs de la Champions League: partidos, cruces, fechas y m\\u00e1s\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/01\\\/30\\\/playoffs-champions-league-partidos-cruces-fechas-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/01\\\/30\\\/playoffs-champions-league-partidos-cruces-fechas-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-30T15:03:40Z\",\"datePublished\":\"2026-01-30T15:03:40Z\",\"dateModified\":\"2026-01-30T15:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1470606,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/01\/29\/champions-eliminatorias-playoffs-partidos-cruces-fechas-orix\/","url_meta":{"origin":1470657,"position":0},"title":"As\u00ed se definir\u00e1n las eliminatorias de los playoffs de la Champions League: equipos clasificados, posibles cruces y fechas","author":"","date":"enero 29, 2026","format":false,"excerpt":"Los playoffs de la Champions tendr\u00e1n a varios equipos grandes obligados a jugarse la continuidad antes de los octavos de final. Real Madrid, Atl\u00e9tico de Madrid, Juventus, Inter y Paris Saint-Germain quedaron fuera del grupo de los ocho mejores y deber\u00e1n superar una eliminatoria previa, a ida y vuelta, para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470621,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/01\/29\/sorteo-playoffs-champions-league-2025-2026-orix\/","url_meta":{"origin":1470657,"position":1},"title":"Sorteo de playoffs de la Champions League 2025\/2026: equipos, emparejamientos, formato, hora y c\u00f3mo ver por TV e internet","author":"","date":"enero 29, 2026","format":false,"excerpt":"La UEFA Champions League se prepara para entrar en etapa de definiciones. Con la emoci\u00f3n estirada hasta el \u00faltimo cabezazo de la Fase de Liga, la m\u00e1xima competencia de Europa a nivel clubes conocer\u00e1 este viernes el camino a recorrer hasta la gran final del 30 de mayo en el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458042,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/01\/30\/sorteo-playoffs-eliminatorios-champions-league-2024-2025-formato-como-funciona-hora-donde-ver-orix\/","url_meta":{"origin":1470657,"position":2},"title":"Sorteo de playoffs eliminatorios de la Champions League 2024\/2025: formato, c\u00f3mo funciona, a qu\u00e9 hora y d\u00f3nde ver","author":"","date":"enero 30, 2025","format":false,"excerpt":"Tras m\u00e1s de cuatro meses de competencia en la etapa inicial de liga, la Champions League 2024\/2025 ya tiene a los equipos clasificados para las fases eliminatorias.Ocho clubes clasificaron directamente a octavos de final luego de las ocho jornadas que se disputaron en la fase de liga desde septiembre hasta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458065,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/01\/31\/sorteo-champions-league-partidos-cruces-fechas-orix\/","url_meta":{"origin":1470657,"position":3},"title":"Sorteo de eliminatorias y playoffs de la Champions League 24\/25: partidos, cruces y fechas","author":"","date":"enero 31, 2025","format":false,"excerpt":"El Real Madrid, vigente campe\u00f3n de Europa, y el Manchester City, ganador de la edici\u00f3n 2023, se enfrentar\u00e1n nuevamente en una electrizante eliminatoria de la Champions League. El sorteo celebrado este viernes en Nyon, Suiza, determin\u00f3 que ambos clubes medir\u00e1n fuerzas en los playoffs de la fase eliminatoria.Ni el conjunto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470574,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/01\/28\/real-madrid-playoff-champions-league-orix\/","url_meta":{"origin":1470657,"position":4},"title":"Los dos rivales que podr\u00edan tocarle al Real Madrid en los playoff de la Champions League","author":"","date":"enero 28, 2026","format":false,"excerpt":"El Real Madrid pas\u00f3 una noche de terror en Portugal, y a pesar de que parec\u00eda que ten\u00eda servida la clasificaci\u00f3n a octavos de final al comienzo del d\u00eda, acab\u00f3 goleado por el Benfica de Jos\u00e9 Mourinho. Lo peor es que, a la derrota propia se le sumaron los triunfos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459457,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/03\/03\/real-madrid-atletico-de-madrid-champions-league-hora-cuando-como-ver-orix\/","url_meta":{"origin":1470657,"position":5},"title":"Real Madrid \u2013 Atl\u00e9tico de Madrid en la Champions League 24\/25: previa, hora, cu\u00e1ndo y c\u00f3mo ver por TV e internet","author":"","date":"marzo 3, 2025","format":false,"excerpt":"Al Real Madrid le tom\u00f3 diez partidos llegar a octavos de final de la Champions League. Suena irreal si se tiene en cuenta la plantilla que posee, pero son las cosas que genera el nuevo formato de este torneo.En todo caso, los dirigidos por Carlo Ancelotti se enfrentar\u00e1n al Atl\u00e9tico\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1470657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1470657"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1470657\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1470657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1470657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1470657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}