{"id":1470896,"date":"2026-02-05T08:03:42","date_gmt":"2026-02-05T16:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/05\/que-esta-pasando-bitcoin-trax\/"},"modified":"2026-02-05T08:03:42","modified_gmt":"2026-02-05T16:03:42","slug":"que-esta-pasando-bitcoin-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/05\/que-esta-pasando-bitcoin-trax\/","title":{"rendered":"No, pero en serio: \u00bfqu\u00e9 est\u00e1 pasando con el bitcoin?"},"content":{"rendered":"<p>El bitcoin est\u00e1 actuando de forma extra\u00f1a.<\/p>\n<p>La criptomoneda m\u00e1s famosa del mundo ha ca\u00eddo un 44 % desde su pico de octubre, al bajar el jueves de los US$ 70.000 por primera vez en 15 meses.<\/p>\n<p>Ese descenso en realidad no es inusual. Las criptomonedas son notoriamente vol\u00e1tiles y han atravesado numerosas ca\u00eddas mayores que esta.<\/p>\n<p>Lo extra\u00f1o es esto: la racha bajista de cuatro meses del bitcoin ha ocurrido en un momento en el que, en teor\u00eda, lo ten\u00eda todo a su favor.<\/p>\n<p>Durante a\u00f1os, los alcistas de las criptomonedas han defendido que los inversionistas traten al bitcoin como \u201coro digital\u201d, un nuevo activo refugio donde los operadores pueden resguardar fondos cuando los tiempos son dif\u00edciles.<\/p>\n<p>Por eso, este ser\u00eda un momento l\u00f3gico para que un activo refugio se disparara.<\/p>\n<p>La geopol\u00edtica se ha tensado este a\u00f1o: el presidente Donald Trump amenaza con atacar Ir\u00e1n tras la salida del l\u00edder de Venezuela. El presidente de EE.UU. tambi\u00e9n ha confrontado recientemente a aliados en Europa y Canad\u00e1 por Groenlandia, y amenaza con aranceles m\u00e1s altos a Corea del Sur.<\/p>\n<p>Mientras tanto, avances significativos en inteligencia artificial est\u00e1n poniendo nerviosos a los inversionistas del mercado burs\u00e1til. Claude, de Anthropic, ya puede realizar tareas para bufetes de abogados, lo que ha hecho caer acciones de software.<\/p>\n<p>Los indicadores de miedo est\u00e1n enviando se\u00f1ales de alerta. El \u00edndice Fear and Greed de CNN est\u00e1 firmemente en zona de \u201cmiedo\u201d, y el \u00edndice de volatilidad VIX estuvo brevemente en su nivel m\u00e1s alto desde noviembre, cuando el mercado tuvo una minicrisis por datos econ\u00f3micos confusos tras el cierre del gobierno y resultados de Nvidia. (Eran tiempos m\u00e1s simples).<\/p>\n<p>Ese miedo ha impulsado un rally r\u00e9cord en el precio del oro, que recientemente super\u00f3 los US$ 5.500 por onza troy.<\/p>\n<p>El oro es el activo refugio por excelencia: un activo relativamente escaso y tangible que preserva valor \u2014y que incluso puede esconderse literalmente bajo un colch\u00f3n si la situaci\u00f3n empeora.<\/p>\n<p>Pero el bitcoin no acompa\u00f1a. Ha perdido 20 % este a\u00f1o pese a toda la incertidumbre. De hecho, Michael Burry (el de \u201cThe Big Short\u201d) escribi\u00f3 recientemente en su Substack que cree que la volatilidad extrema reciente del oro y la plata se debe a que los alcistas del bitcoin est\u00e1n vendiendo sus posiciones en metales para compensar las p\u00e9rdidas de las criptomonedas.<\/p>\n<p>El desplome del bitcoin significa que perdi\u00f3 por completo el \u201cimpulso Trump\u201d. Los inversionistas en criptomonedas celebraron la victoria de Trump en noviembre de 2024, lo que dispar\u00f3 el bitcoin y otros criptoactivos, despu\u00e9s de que Trump adoptara los activos digitales que antes rechazaba y prometiera eliminar regulaciones que, seg\u00fan \u00e9l, frenaban al sector.<\/p>\n<p>Entonces, \u00bfqu\u00e9 hay detr\u00e1s de este nuevo invierno cripto? Principalmente dudas de que el bitcoin sea realmente \u201coro digital\u201d.<\/p>\n<p>El bitcoin ha quedado atrapado en todo el sentimiento de aversi\u00f3n al riesgo que recorre el mercado. En lugar de dar razones para comprar, los operadores ven ese miedo como motivo para vender. La divergencia persistente entre el oro (sube 24 % desde octubre) y el bitcoin (cae 44 %) solo ha reforzado esa percepci\u00f3n.<\/p>\n<p>El secretario del Tesoro, Scott Bessent, no ayud\u00f3 a mejorar el panorama el mi\u00e9rcoles, cuando declar\u00f3 ante el Comit\u00e9 de Servicios Financieros de la C\u00e1mara de Representantes que el Tesoro no tiene autoridad para estabilizar los mercados de criptomonedas.<\/p>\n<p>Pero podr\u00eda haber luz al final del t\u00fanel cripto para los inversionistas en bitcoin. Este desplome no es una tendencia nueva: ya ha ocurrido antes.<\/p>\n<p>En 2014, los precios de las criptomonedas se desplomaron tras el hackeo de la casa de cambio Mt. Gox. La mayor ca\u00edda ocurri\u00f3 en 2018, cuando el bitcoin se hundi\u00f3 un 74 %, impulsado por temores de que la explosi\u00f3n de las ofertas iniciales de monedas hab\u00eda sido excesiva. Y el mercado cripto tuvo ca\u00eddas consecutivas en 2021 y 2022, despu\u00e9s de que la presi\u00f3n regulatoria y el esc\u00e1ndalo de FTX sacudieran la confianza.<\/p>\n<p>Cada vez, el bitcoin se ha recuperado por completo en el plazo de un a\u00f1o y medio.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El bitcoin est\u00e1 actuando de forma extra\u00f1a. La criptomoneda m\u00e1s famosa del mundo ha ca\u00eddo un 44 % desde su pico de octubre, al bajar el jueves de los US$ 70.000 por primera vez en 15 meses. Ese descenso en realidad no es inusual. Las criptomonedas son notoriamente vol\u00e1tiles y han atravesado numerosas ca\u00eddas mayores [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470896","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>No, pero en serio: \u00bfqu\u00e9 est\u00e1 pasando con el bitcoin? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/05\/que-esta-pasando-bitcoin-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"No, pero en serio: \u00bfqu\u00e9 est\u00e1 pasando con el bitcoin? - Noticias\" \/>\n<meta property=\"og:description\" content=\"El bitcoin est\u00e1 actuando de forma extra\u00f1a. La criptomoneda m\u00e1s famosa del mundo ha ca\u00eddo un 44 % desde su pico de octubre, al bajar el jueves de los US$ 70.000 por primera vez en 15 meses. Ese descenso en realidad no es inusual. Las criptomonedas son notoriamente vol\u00e1tiles y han atravesado numerosas ca\u00eddas mayores [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/05\/que-esta-pasando-bitcoin-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-05T16:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/05\/que-esta-pasando-bitcoin-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/05\/que-esta-pasando-bitcoin-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"No, pero en serio: \u00bfqu\u00e9 est\u00e1 pasando con el bitcoin?\",\"datePublished\":\"2026-02-05T16:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/05\/que-esta-pasando-bitcoin-trax\/\"},\"wordCount\":730,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/05\/que-esta-pasando-bitcoin-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/05\/que-esta-pasando-bitcoin-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/05\/que-esta-pasando-bitcoin-trax\/\",\"name\":\"No, pero en serio: \u00bfqu\u00e9 est\u00e1 pasando con el bitcoin? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-05T16:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/05\/que-esta-pasando-bitcoin-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/05\/que-esta-pasando-bitcoin-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/05\/que-esta-pasando-bitcoin-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"No, pero en serio: \u00bfqu\u00e9 est\u00e1 pasando con el bitcoin?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"No, pero en serio: \u00bfqu\u00e9 est\u00e1 pasando con el bitcoin? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/05\/que-esta-pasando-bitcoin-trax\/","og_locale":"es_ES","og_type":"article","og_title":"No, pero en serio: \u00bfqu\u00e9 est\u00e1 pasando con el bitcoin? - Noticias","og_description":"El bitcoin est\u00e1 actuando de forma extra\u00f1a. La criptomoneda m\u00e1s famosa del mundo ha ca\u00eddo un 44 % desde su pico de octubre, al bajar el jueves de los US$ 70.000 por primera vez en 15 meses. Ese descenso en realidad no es inusual. Las criptomonedas son notoriamente vol\u00e1tiles y han atravesado numerosas ca\u00eddas mayores [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/05\/que-esta-pasando-bitcoin-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-05T16:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/05\/que-esta-pasando-bitcoin-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/05\/que-esta-pasando-bitcoin-trax\/"},"author":{"name":"","@id":""},"headline":"No, pero en serio: \u00bfqu\u00e9 est\u00e1 pasando con el bitcoin?","datePublished":"2026-02-05T16:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/05\/que-esta-pasando-bitcoin-trax\/"},"wordCount":730,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/05\/que-esta-pasando-bitcoin-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/05\/que-esta-pasando-bitcoin-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/05\/que-esta-pasando-bitcoin-trax\/","name":"No, pero en serio: \u00bfqu\u00e9 est\u00e1 pasando con el bitcoin? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-05T16:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/05\/que-esta-pasando-bitcoin-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/05\/que-esta-pasando-bitcoin-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/05\/que-esta-pasando-bitcoin-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"No, pero en serio: \u00bfqu\u00e9 est\u00e1 pasando con el bitcoin?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/05\/que-esta-pasando-bitcoin-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"No, pero en serio: \u00bfqu\u00e9 est\u00e1 pasando con el bitcoin?","url":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/05\/que-esta-pasando-bitcoin-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/05\/que-esta-pasando-bitcoin-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-05T16:03:42Z","datePublished":"2026-02-05T16:03:42Z","dateModified":"2026-02-05T16:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"No, pero en serio: \\u00bfqu\\u00e9 est\\u00e1 pasando con el bitcoin?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/05\\\/que-esta-pasando-bitcoin-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/05\\\/que-esta-pasando-bitcoin-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-05T16:03:42Z\",\"datePublished\":\"2026-02-05T16:03:42Z\",\"dateModified\":\"2026-02-05T16:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1455950,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/11\/20\/bitcoin-rompiendo-records-invertir-trax\/","url_meta":{"origin":1470896,"position":0},"title":"El bitcoin rompe r\u00e9cords, \u00bfes buen momento para invertir?","author":"","date":"noviembre 20, 2024","format":false,"excerpt":"(CNN) -- En el primer trimestre de este a\u00f1o, el precio del bitcoin bati\u00f3 r\u00e9cords tras la aprobaci\u00f3n por parte de la Comisi\u00f3n del Mercado de Valores de los primeros fondos de bitcoin al contado cotizados en bolsa. La criptomoneda super\u00f3 los US$ 70.000 en marzo, seg\u00fan coinmarketcap.com.Despu\u00e9s, con los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459602,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/03\/06\/trump-crea-reserva-estrategica-bitcoin-cumbre-criptomonedas-trax\/","url_meta":{"origin":1470896,"position":1},"title":"Trump crea una Reserva Estrat\u00e9gica de Bitcoin un d\u00eda antes de la cumbre de criptomonedas de la Casa Blanca","author":"","date":"marzo 6, 2025","format":false,"excerpt":"El presidente Donald Trump estableci\u00f3 una Reserva Estrat\u00e9gica de Bitcoin a trav\u00e9s de un decreto, seg\u00fan una publicaci\u00f3n en X de David Sacks, el zar de la Casa Blanca para inteligencia artificial y criptomonedas.Trump hab\u00eda publicado en redes sociales el domingo que ordenar\u00eda al Gobierno acumular bitcoin, ethereum y otros\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468471,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/11\/18\/desplome-criptomonedas-acciones-mercado-trax\/","url_meta":{"origin":1470896,"position":2},"title":"Por qu\u00e9 las criptomonedas se est\u00e1n desplomando y las acciones siguen cayendo","author":"","date":"noviembre 18, 2025","format":false,"excerpt":"El bitcoin y las acciones est\u00e1n en ca\u00edda y los inversionistas dicen que podr\u00eda haber m\u00e1s turbulencia en el futuro.Las acciones en EE.UU. bajaron el martes, extendiendo una reciente racha de ca\u00eddas.El Dow cay\u00f3 413 puntos, o 0,89 %. El S&P 500 baj\u00f3 0,6 %. El Nasdaq Composite, de fuerte\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462636,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/05\/21\/bitcoin-maximo-historico-trax\/","url_meta":{"origin":1470896,"position":3},"title":"Bitcoin alcanza un nuevo m\u00e1ximo hist\u00f3rico","author":"","date":"mayo 21, 2025","format":false,"excerpt":"Bitcoin alcanz\u00f3 este mi\u00e9rcoles un m\u00e1ximo hist\u00f3rico de m\u00e1s de US$ 109.400, en un momento en el que los inversores se abalanzan sobre la criptomoneda.Bitcoin, la criptomoneda m\u00e1s grande del mundo por valor de mercado, ha subido m\u00e1s de un 23 % en los \u00faltimos 30 d\u00edas y alcanz\u00f3 un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459023,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/02\/21\/como-funcionan-las-criptomonedas-el-bitcoin-la-infinita-variedad-de-proyectos-y-los-riesgos-de-las-memecoins\/","url_meta":{"origin":1470896,"position":4},"title":"\u00bfC\u00f3mo funcionan las criptomonedas? El Bitcoin, la infinita variedad de proyectos y los riesgos de las \u2018memecoins\u2019","author":"","date":"febrero 21, 2025","format":false,"excerpt":"Daiana G\u00f3mez Benegas, directora fundadora de Mujeres en Bitcoin, habl\u00f3 este viernes en CNN Radio sobre la diferencia entre las diferentes criptomonedas, el esc\u00e1ndalo $Libra y las denominadas \u2018memecoins\u2019, entre otros temas.En La Ma\u00f1ana de CNN, Benegas dijo que \u201cel Bitcoin es un activo con un tratamiento diferente a todas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443509,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/01\/11\/la-comision-de-bolsa-y-valores-da-luz-verde-a-los-fondos-cotizados-de-bitcoin\/","url_meta":{"origin":1470896,"position":5},"title":"La Comisi\u00f3n de Bolsa y Valores da luz verde a los fondos cotizados de bitcoin","author":"","date":"enero 11, 2024","format":false,"excerpt":"Nueva York (CNN) -- Despu\u00e9s de una salida en falso el martes, la Comisi\u00f3n de Bolsa y Valores (SEC, por sus siglas en ingl\u00e9s) dio su aprobaci\u00f3n este mi\u00e9rcoles para que algunas empresas de inversi\u00f3n ofrezcan fondos cotizados (ETF) en bolsa de \"bitcoin al contado\".Con esta medida tan esperada, se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1470896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1470896"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1470896\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1470896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1470896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1470896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}