{"id":1470969,"date":"2026-02-06T21:03:46","date_gmt":"2026-02-07T05:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/06\/tribunal-apelaciones-politica-detener-inmigrantes-sin-libertad-trax\/"},"modified":"2026-02-06T21:03:46","modified_gmt":"2026-02-07T05:03:46","slug":"tribunal-apelaciones-politica-detener-inmigrantes-sin-libertad-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/06\/tribunal-apelaciones-politica-detener-inmigrantes-sin-libertad-trax\/","title":{"rendered":"Tribunal de apelaciones avala pol\u00edtica del Gobierno de Trump para detener a inmigrantes indocumentados sin opci\u00f3n de libertad"},"content":{"rendered":"<p>Un tribunal federal de apelaciones dividido fall\u00f3 este viernes a favor de la pol\u00edtica del Gobierno de Trump de detener a millones de inmigrantes indocumentados, incluso a aquellos que han vivido en Estados Unidos durante d\u00e9cadas, sin oportunidad de impugnar su detenci\u00f3n, otorgando al presidente Donald Trump una importante victoria mientras busca llevar a cabo una campa\u00f1a en\u00e9rgica de deportaciones.<\/p>\n<p>El fallo de <a href=\"https:\/\/storage.courtlistener.com\/recap\/gov.uscourts.ca5.227192\/gov.uscourts.ca5.227192.507860231.1.pdf\">2-1 <\/a>del conservador Quinto Tribunal de Apelaciones de Estados Unidos significa que, en varios estados del sur, numerosos inmigrantes que hab\u00edan estado viviendo en EE.UU. sin documentos, incluidos aquellos que anteriormente pod\u00edan permanecer en libertad bajo fianza mientras su caso avanzaba en el sistema de inmigraci\u00f3n, ahora pueden ser detenidos y se les puede negar la oportunidad de solicitar su liberaci\u00f3n a trav\u00e9s de audiencias de fianza ante jueces de inmigraci\u00f3n.<\/p>\n<p>En miles de casos en todo el pa\u00eds, jueces federales hab\u00edan dictaminado de manera consistente que la pol\u00edtica implementada por Trump el a\u00f1o pasado era ilegal, pero la decisi\u00f3n de este viernes marca la primera vez que una corte de apelaciones la respalda. El fallo solo aplica a inmigrantes en Texas, Louisiana y Mississippi.<\/p>\n<p>\u201cHay una raz\u00f3n por la cual, en m\u00e1s de 3.000 casos en decenas de tribunales federales de distrito, el Gobierno de Trump decidi\u00f3 que su primera apelaci\u00f3n sobre esta cuesti\u00f3n fuera ante el Quinto Circuito\u201d, dijo Steve Vladeck, analista de la Corte Suprema de CNN y profesor en la Facultad de Derecho de la Universidad de Georgetown, quien <a href=\"https:\/\/www.stevevladeck.com\/p\/195-the-immigration-detention-flood?r=1uo2gq&#038;utm_campaign=post&#038;utm_medium=web\">previamente ha escrito<\/a> sobre la disputa legal en estos casos.<\/p>\n<p>\u201cEl Quinto Circuito no solo es el tribunal de apelaciones m\u00e1s conservador del pa\u00eds; en este panel, el Gobierno seleccion\u00f3 a dos de los jueces m\u00e1s conservadores de ese mismo tribunal. Es dif\u00edcil imaginar que vayan a pronunciar la \u00faltima palabra\u201d, dijo.<\/p>\n<p>Aunque otros tribunales de apelaciones en EE.UU. siguen examinando la pol\u00edtica, el fallo del Quinto Circuito anticipa un probable enfrentamiento sobre este tema en la Corte Suprema.<\/p>\n<p>La decisi\u00f3n mayoritaria de este viernes fue redactada por la jueza Edith Jones, nombrada por el expresidente Ronald Reagan, y a la que se sum\u00f3 el juez Kyle Duncan, nombrado por Trump.<\/p>\n<p>Los dos jueces republicanos dijeron que, aunque el Gobierno de Trump hab\u00eda revertido d\u00e9cadas de pol\u00edticas de la rama ejecutiva que permit\u00edan a los inmigrantes indocumentados permanecer en libertad bajo fianza mientras se resolv\u00edan sus casos de inmigraci\u00f3n, las autoridades actuales estaban plenamente dentro de su autoridad para hacer el cambio.<\/p>\n<p>\u201cEl que gobiernos anteriores decidieran usar menos que toda su autoridad de aplicaci\u00f3n\u2026 no significa que carecieran de la autoridad para hacer m\u00e1s\u201d, escribi\u00f3 Jones.<\/p>\n<p>Bajo gobiernos previos, los no ciudadanos que ingresaron a Estados Unidos sin una visa v\u00e1lida, fueron detenidos lejos de la frontera y no ten\u00edan antecedentes penales, pod\u00edan ser liberados bajo fianza mientras se desarrollaban sus casos de inmigraci\u00f3n. Esa pol\u00edtica de larga data contrastaba con el trato recibido por los inmigrantes detenidos en la frontera. Esos individuos pod\u00edan ser sometidos a procedimientos de expulsi\u00f3n acelerada sin la posibilidad de buscar su liberaci\u00f3n bajo fianza.<\/p>\n<p>La jueza Dana Douglas, nombrada por el expresidente Joe Biden, advirti\u00f3 en una opini\u00f3n disidente que el fallo mayoritario podr\u00eda dar lugar a la detenci\u00f3n sin fianza de 2 millones de no ciudadanos en Estados Unidos.<\/p>\n<p>\u201cEl Gobierno hoy invoca la autoridad y el mandato para detener a millones de no ciudadanos en el interior, algunos de ellos presentes aqu\u00ed durante d\u00e9cadas, en las mismas condiciones que si hubieran sido detenidos en la frontera\u201d, escribi\u00f3. \u201cNo importa que este nuevo mandato descubierto llegue sin precedente hist\u00f3rico, y en contra de una de las distinciones fundamentales del derecho de inmigraci\u00f3n\u201d.<\/p>\n<p>Continu\u00f3: \u201cParece que la mayor\u00eda es incapaz de imaginar lo que significar\u00eda estar detenido dentro de Estados Unidos sin la prueba adecuada de admisibilidad y, sin una audiencia de fianza, tener que recurrir a los servicios de un abogado federal de habeas corpus para demostrar que uno tiene derecho a la liberaci\u00f3n y merece volver a ver el exterior de un centro de detenci\u00f3n otra vez\u201d.<\/p>\n<p>\u201cEsto no es, o no solo es, una cuesti\u00f3n de simpat\u00eda humana, sino m\u00e1s bien una cuesti\u00f3n de comprender una de las distinciones fundamentales en la ley de inmigraci\u00f3n, y las muy buenas razones para ello\u201d, escribi\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un tribunal federal de apelaciones dividido fall\u00f3 este viernes a favor de la pol\u00edtica del Gobierno de Trump de detener a millones de inmigrantes indocumentados, incluso a aquellos que han vivido en Estados Unidos durante d\u00e9cadas, sin oportunidad de impugnar su detenci\u00f3n, otorgando al presidente Donald Trump una importante victoria mientras busca llevar a cabo [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470969","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tribunal de apelaciones avala pol\u00edtica del Gobierno de Trump para detener a inmigrantes indocumentados sin opci\u00f3n de libertad - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/06\/tribunal-apelaciones-politica-detener-inmigrantes-sin-libertad-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tribunal de apelaciones avala pol\u00edtica del Gobierno de Trump para detener a inmigrantes indocumentados sin opci\u00f3n de libertad - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un tribunal federal de apelaciones dividido fall\u00f3 este viernes a favor de la pol\u00edtica del Gobierno de Trump de detener a millones de inmigrantes indocumentados, incluso a aquellos que han vivido en Estados Unidos durante d\u00e9cadas, sin oportunidad de impugnar su detenci\u00f3n, otorgando al presidente Donald Trump una importante victoria mientras busca llevar a cabo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/06\/tribunal-apelaciones-politica-detener-inmigrantes-sin-libertad-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-07T05:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/06\/tribunal-apelaciones-politica-detener-inmigrantes-sin-libertad-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/06\/tribunal-apelaciones-politica-detener-inmigrantes-sin-libertad-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Tribunal de apelaciones avala pol\u00edtica del Gobierno de Trump para detener a inmigrantes indocumentados sin opci\u00f3n de libertad\",\"datePublished\":\"2026-02-07T05:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/06\/tribunal-apelaciones-politica-detener-inmigrantes-sin-libertad-trax\/\"},\"wordCount\":802,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/06\/tribunal-apelaciones-politica-detener-inmigrantes-sin-libertad-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/06\/tribunal-apelaciones-politica-detener-inmigrantes-sin-libertad-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/06\/tribunal-apelaciones-politica-detener-inmigrantes-sin-libertad-trax\/\",\"name\":\"Tribunal de apelaciones avala pol\u00edtica del Gobierno de Trump para detener a inmigrantes indocumentados sin opci\u00f3n de libertad - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-07T05:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/06\/tribunal-apelaciones-politica-detener-inmigrantes-sin-libertad-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/06\/tribunal-apelaciones-politica-detener-inmigrantes-sin-libertad-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/06\/tribunal-apelaciones-politica-detener-inmigrantes-sin-libertad-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tribunal de apelaciones avala pol\u00edtica del Gobierno de Trump para detener a inmigrantes indocumentados sin opci\u00f3n de libertad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tribunal de apelaciones avala pol\u00edtica del Gobierno de Trump para detener a inmigrantes indocumentados sin opci\u00f3n de libertad - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/06\/tribunal-apelaciones-politica-detener-inmigrantes-sin-libertad-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Tribunal de apelaciones avala pol\u00edtica del Gobierno de Trump para detener a inmigrantes indocumentados sin opci\u00f3n de libertad - Noticias","og_description":"Un tribunal federal de apelaciones dividido fall\u00f3 este viernes a favor de la pol\u00edtica del Gobierno de Trump de detener a millones de inmigrantes indocumentados, incluso a aquellos que han vivido en Estados Unidos durante d\u00e9cadas, sin oportunidad de impugnar su detenci\u00f3n, otorgando al presidente Donald Trump una importante victoria mientras busca llevar a cabo [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/06\/tribunal-apelaciones-politica-detener-inmigrantes-sin-libertad-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-07T05:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/06\/tribunal-apelaciones-politica-detener-inmigrantes-sin-libertad-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/06\/tribunal-apelaciones-politica-detener-inmigrantes-sin-libertad-trax\/"},"author":{"name":"","@id":""},"headline":"Tribunal de apelaciones avala pol\u00edtica del Gobierno de Trump para detener a inmigrantes indocumentados sin opci\u00f3n de libertad","datePublished":"2026-02-07T05:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/06\/tribunal-apelaciones-politica-detener-inmigrantes-sin-libertad-trax\/"},"wordCount":802,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/06\/tribunal-apelaciones-politica-detener-inmigrantes-sin-libertad-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/06\/tribunal-apelaciones-politica-detener-inmigrantes-sin-libertad-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/06\/tribunal-apelaciones-politica-detener-inmigrantes-sin-libertad-trax\/","name":"Tribunal de apelaciones avala pol\u00edtica del Gobierno de Trump para detener a inmigrantes indocumentados sin opci\u00f3n de libertad - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-07T05:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/06\/tribunal-apelaciones-politica-detener-inmigrantes-sin-libertad-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/06\/tribunal-apelaciones-politica-detener-inmigrantes-sin-libertad-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/06\/tribunal-apelaciones-politica-detener-inmigrantes-sin-libertad-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Tribunal de apelaciones avala pol\u00edtica del Gobierno de Trump para detener a inmigrantes indocumentados sin opci\u00f3n de libertad"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/06\/tribunal-apelaciones-politica-detener-inmigrantes-sin-libertad-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Tribunal de apelaciones avala pol\u00edtica del Gobierno de Trump para detener a inmigrantes indocumentados sin opci\u00f3n de libertad","url":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/06\/tribunal-apelaciones-politica-detener-inmigrantes-sin-libertad-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/06\/tribunal-apelaciones-politica-detener-inmigrantes-sin-libertad-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-07T05:03:46Z","datePublished":"2026-02-07T05:03:46Z","dateModified":"2026-02-07T05:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Tribunal de apelaciones avala pol\\u00edtica del Gobierno de Trump para detener a inmigrantes indocumentados sin opci\\u00f3n de libertad\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/06\\\/tribunal-apelaciones-politica-detener-inmigrantes-sin-libertad-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/06\\\/tribunal-apelaciones-politica-detener-inmigrantes-sin-libertad-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-07T05:03:46Z\",\"datePublished\":\"2026-02-07T05:03:46Z\",\"dateModified\":\"2026-02-07T05:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1462455,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/05\/16\/tribunal-rechaza-reanudar-deportaciones-terceros-paises-trax\/","url_meta":{"origin":1470969,"position":0},"title":"Tribunal de apelaciones rechaza solicitud del Gobierno de EE.UU. para reanudar las deportaciones a terceros pa\u00edses","author":"","date":"mayo 16, 2025","format":false,"excerpt":"Un tribunal federal de apelaciones de Estados Unidos se neg\u00f3 este viernes a permitir que la administraci\u00f3n Trump reanude la deportaci\u00f3n de inmigrantes a pa\u00edses distintos al suyo sin previo aviso ni la oportunidad de buscar protecci\u00f3n contra la persecuci\u00f3n o la tortura.El Tribunal de Apelaciones del Primer Circuito de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460464,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/03\/26\/corte-mantiene-bloqueo-temporal-uso-ley-enemigos-extranjeros-deportaciones-trax\/","url_meta":{"origin":1470969,"position":1},"title":"Corte de apelaciones mantiene bloqueo temporal al uso de la Ley de Enemigos Extranjeros para deportaciones","author":"","date":"marzo 26, 2025","format":false,"excerpt":"Una corte federal de apelaciones mantiene, tras una decisi\u00f3n dividida, un bloqueo temporal a la facultad del presidente Donald Trump de usar la Ley de Enemigos Extranjeros para deportar r\u00e1pidamente a presuntos miembros de una pandilla venezolana.El Tribunal de Apelaciones del Circuito de Washington fall\u00f3 por 2 votos a 1\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465708,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/08\/20\/tribunal-permite-poner-fin-tps-honduras-nicaragua-nepal-trax\/","url_meta":{"origin":1470969,"position":2},"title":"Tribunal de apelaciones avala que el Gobierno de Trump ponga fin temporal al TPS para personas de Honduras, Nicaragua y Nepal","author":"","date":"agosto 20, 2025","format":false,"excerpt":"Un tribunal federal de apelaciones permiti\u00f3 que el Gobierno de Trump ponga fin temporal al Estatus de Protecci\u00f3n Temporal (TPS) para miles de inmigrantes indocumentados de Honduras, Nicaragua y Nepal.En una breve orden, un panel un\u00e1nime de tres jueces del 9\u00ba Circuito de Apelaciones de EE.UU. acord\u00f3 suspender el fallo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464513,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/07\/14\/gobierno-trump-pide-pausa-orden-detiene-arrestos-inmigrantes-trax\/","url_meta":{"origin":1470969,"position":3},"title":"El Gobierno de Trump pide a corte de apelaciones que pause la orden que detiene arrestos a inmigrantes sin causa probable","author":"","date":"julio 14, 2025","format":false,"excerpt":"El Gobierno de Trump solicit\u00f3 este lunes a una corte federal de apelaciones que pausara una amplia orden de una jueza de California que requer\u00eda a los funcionarios dejar de realizar arrestos de inmigraci\u00f3n sin causa probable en la parte sur del estado.El fallo, emitido el viernes por la jueza\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462007,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/05\/05\/tribunal-apelaciones-preserva-parole-humanitario-chnv-trax\/","url_meta":{"origin":1470969,"position":4},"title":"Tribunal de apelaciones desaf\u00eda a Trump y preserva &#8216;parole&#8217; humanitario para venezolanos, cubanos, haitianos y nicarag\u00fcenses","author":"","date":"mayo 5, 2025","format":false,"excerpt":"Un tribunal federal de apelaciones paus\u00f3 el intento del Gobierno de Trump de terminar el parole humanitario para migrantes de Cuba, Hait\u00ed, Nicaragua y Venezuela (programa CHNV, por las siglas de los pa\u00edses), manteniendo por ahora las protecciones contra la deportaci\u00f3n para m\u00e1s de 500.000 personas.La decisi\u00f3n del lunes del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465992,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/08\/29\/jueza-trump-deportaciones-debido-proceso-trax\/","url_meta":{"origin":1470969,"position":5},"title":"Jueza dice que esfuerzo de Trump para expandir pr\u00e1ctica de deportaciones r\u00e1pidas de inmigrantes viola el debido proceso","author":"","date":"agosto 29, 2025","format":false,"excerpt":"Una jueza federal bloque\u00f3 este viernes un esfuerzo de la administraci\u00f3n Trump que pretende acelerar las deportaciones de inmigrantes detenidos en las calles de Estados Unidos, calific\u00e1ndolo de violaci\u00f3n del debido proceso.A diferencia de los indocumentados interceptados en la frontera o cerca de ella, que anteriormente hab\u00edan sido objeto de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1470969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1470969"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1470969\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1470969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1470969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1470969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}