{"id":1470972,"date":"2026-02-07T02:03:57","date_gmt":"2026-02-07T10:03:57","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/07\/archivos-epstein-amenazan-dividir-familia-real-noruega-trax\/"},"modified":"2026-02-07T02:03:57","modified_gmt":"2026-02-07T10:03:57","slug":"archivos-epstein-amenazan-dividir-familia-real-noruega-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/07\/archivos-epstein-amenazan-dividir-familia-real-noruega-trax\/","title":{"rendered":"Los archivos de Epstein amenazan con dividir en dos a la familia real de Noruega"},"content":{"rendered":"<p>La familia real de Noruega ha estado luchando contra esc\u00e1ndalos en <a href=\"https:\/\/www.cnn.com\/2026\/02\/03\/europe\/norway-crown-princess-epstein-hoiby-intl\">m\u00faltiples frentes<\/a> esta semana, que han motivado a organizaciones ben\u00e9ficas a tomar ciertos pasos para cortar o revisar lazos con la princesa heredera por sus pasados v\u00ednculos con el fallecido delincuente sexual Jeffrey Epstein, mientras que otros cr\u00edticos cuestionan su idoneidad para el papel de futura reina.<\/p>\n<p>La primera pol\u00e9mica es la del hijo de 29 a\u00f1os de la princesa heredera Mette-Marit, <a href=\"https:\/\/www.cnn.com\/2026\/02\/04\/europe\/stepson-norway-crown-prince-rape-trial-intl\">Marius Borg H\u00f8iby<\/a>, quien a principios de esta semana rompi\u00f3 a llorar durante su primer d\u00eda de testimonios en un tribunal de Oslo por cuatro cargos de violaci\u00f3n, que neg\u00f3 .<\/p>\n<p>H\u00f8iby se encuentra fuera de la l\u00ednea de sucesi\u00f3n, ya que naci\u00f3 antes de que su madre se casara con el pr\u00edncipe heredero Haakon en 2001.<\/p>\n<p>Haakon reafirm\u00f3 el estatus de H\u00f8iby como plebeyo en una declaraci\u00f3n poco com\u00fan antes del juicio por violaci\u00f3n que comienza el martes, en la que afirma que su hijastro \u201cno es miembro de la Casa Real de Noruega y, por lo tanto, es aut\u00f3nomo\u201d.<\/p>\n<p>Pero sus esfuerzos por salvaguardar la reputaci\u00f3n de la Corona se vieron ensombrecidos cuando estall\u00f3 una segunda controversia, esta vez involucrando a su esposa y madre de H\u00f8iby, la futura reina del pa\u00eds.<\/p>\n<p>Nuevos <a href=\"https:\/\/www.cnn.com\/2026\/02\/02\/uk\/epstein-files-britain-mandelson-andrew-ferguson-intl\">archivos de Epstein<\/a> publicados por el Departamento de Justicia de Estados Unidos muestran una extensa correspondencia entre Mette-Marit y el fallecido delincuente sexual (algo que la princesa ha lamentado desde entonces) a\u00f1os despu\u00e9s de que Epstein se declarara culpable de solicitar relaciones sexuales a una menor.<\/p>\n<p>El viernes, la casa real de Noruega manifest\u00f3 que Mette-Marit \u201crechaza firmemente los abusos y actos criminales de Epstein\u201d y lamenta \u201cno haber comprendido lo suficientemente temprano qu\u00e9 tipo de persona era\u201d.<\/p>\n<p>\u201cParte del contenido de los mensajes entre Epstein y yo no representa la persona que quiero ser. Tambi\u00e9n me disculpo por la situaci\u00f3n en la que he puesto a la familia real, especialmente al rey y a la reina\u201d, declar\u00f3 Mette-Marit en un comunicado.<\/p>\n<p>Esto ha provocado un debate p\u00fablico abierto en Noruega sobre si Mette-Marit deber\u00eda convertirse en reina, dicen los expertos.<\/p>\n<p>\u201cLa confianza en la princesa heredera ha ca\u00eddo dr\u00e1sticamente\u201d, declar\u00f3 Tove Taalesen, corresponsal real del medio de comunicaci\u00f3n Nettavisen. \u201cLa mayor\u00eda a\u00fan respalda a la instituci\u00f3n, pero ese apoyo es menor y la incertidumbre crece\u201d.<\/p>\n<p>La controversia plantea preguntas inc\u00f3modas sobre la posici\u00f3n de Mette-Marit dentro del clan, sobre todo dada la avanzada edad del rey Harald V, quien, a sus 88 a\u00f1os, es el monarca m\u00e1s longevo de Europa.<\/p>\n<p>La salud f\u00edsica de Harald se ha <a href=\"https:\/\/www.cnn.com\/2024\/03\/02\/europe\/norway-king-harald-pacemaker-intl\">deteriorado en los \u00faltimos a\u00f1os<\/a>, lo que ha obligado a Haakon a ejercer de regente en ocasiones.<\/p>\n<p>Taalesen advirti\u00f3 que Mette-Marit a\u00fan no enfrenta un final inmediato de su per\u00edodo como miembro activo de la realeza, pero indic\u00f3 que una opci\u00f3n ser\u00eda retirarse de sus deberes reales alegando razones de salud y dejar que el pr\u00edncipe heredero gobierne alg\u00fan d\u00eda por su cuenta.<\/p>\n<p>A Mette-Marit le diagnosticaron en 2018 fibrosis pulmonar, una enfermedad pulmonar cr\u00f3nica y progresiva con un mal pron\u00f3stico, y probablemente necesitar\u00e1 un trasplante de pulm\u00f3n, seg\u00fan el palacio real.<\/p>\n<p>Otros comentaristas reales coinciden. Kjetil Alstadheim, editor pol\u00edtico del influyente peri\u00f3dico noruego Aftenposten, afirm\u00f3 que muchos noruegos est\u00e1n decepcionados por las revelaciones y, como resultado, tienen menos confianza en la princesa.<\/p>\n<p>\u201cSe preguntan c\u00f3mo ser\u00e1 su juicio en el futuro\u201d, se\u00f1al\u00f3 Alstadheim a CNN.<\/p>\n<p>Ole-J\u00f8rgen Schulsrud-Hansen, comentarista real de la cadena noruega TV2, a\u00f1adi\u00f3: \u201cTenemos que esperar a que pase la tormenta para ver cu\u00e1nto ha afectado realmente a la monarqu\u00eda\u201d.<\/p>\n<p>Mette-Marit se convirti\u00f3 en Princesa Heredera en 2001 tras casarse con Haakon en la catedral de Oslo ante 800 invitados y millones de televidentes.<\/p>\n<p>En aquel entonces, la franqueza de Mette-Marit sobre lo que ella describi\u00f3 como una \u201cvida salvaje\u201d en su juventud tuvo una gran aceptaci\u00f3n, sobre todo entre las generaciones m\u00e1s j\u00f3venes.<\/p>\n<p>\u201cMoviliz\u00f3 a las generaciones m\u00e1s j\u00f3venes, que percib\u00edan esta como una monarqu\u00eda moderna y se identificaban con ella\u201d, apunt\u00f3 Alstadheim. \u201cLogr\u00f3 generar confianza y ser respetada\u201d.<\/p>\n<p>En medio del reciente furor, esa confianza y ese respeto parecen estar desapareciendo.<\/p>\n<p>Esta semana, el centro de salud sexual m\u00e1s grande de Noruega, \u201cSex and Society\u201d, con sede en Oslo, anunci\u00f3 que cortar\u00eda v\u00ednculos con Mette-Marit porque manifest\u00f3 que las \u00faltimas revelaciones eran incompatibles con el esp\u00edritu del grupo.<\/p>\n<p>\u201cLo importante para la fundaci\u00f3n ha sido la consideraci\u00f3n de nuestros pacientes, de todas las v\u00edctimas de abuso y de todos aquellos que luchan por prevenir el abuso sexual\u201d, afirm\u00f3 el centro en un comunicado.<\/p>\n<p>Tres organizaciones culturales de Noruega, todas bajo el patrocinio de la princesa heredera, tambi\u00e9n han escrito a la casa real con respecto a la asociaci\u00f3n pasada de Mette-Marit con Epstein, alegando que el contacto entre ambos parece ser \u201cserio y preocupante\u201d.<\/p>\n<p>\u201cEs importante para nuestra futura cooperaci\u00f3n que la Casa Real proporcione una buena explicaci\u00f3n del asunto\u201d, escribieron el Centro Hamsun de Noruega, el Festival F\u00f8rde y el Centro Cultural Nynorsk en una carta a la que accedi\u00f3 CNN.<\/p>\n<p>Los pol\u00e9micos intercambios de correos electr\u00f3nicos, que demostraron una relaci\u00f3n m\u00e1s profunda entre Epstein y la princesa heredera de lo que se conoc\u00eda anteriormente, han provocado una rara intervenci\u00f3n pol\u00edtica.<\/p>\n<p>El primer ministro de Noruega, Jonas Gahr St\u00f8re, declar\u00f3 el lunes que Mette-Marit demostr\u00f3 un juicio deficiente.<\/p>\n<p>\u201cDice que ha demostrado falta de criterio. Estoy de acuerdo\u201d, declar\u00f3 St\u00f8re a la prensa.<\/p>\n<p>Aunque remite a las propias palabras de Mette-Marit, los comentarios del primer ministro reflejan la considerable presi\u00f3n p\u00fablica que enfrenta la familia, seg\u00fan expertos de la realeza.<\/p>\n<p>\u201cNo he encontrado ning\u00fan ejemplo anterior en la historia moderna noruega en el que un primer ministro haya criticado a un miembro de la familia real en p\u00fablico de esa manera\u201d, declar\u00f3 Alstadheim, el editor pol\u00edtico.<\/p>\n<p>En correos electr\u00f3nicos enviados desde \u201cHKH Kronprinsessen\u201d \u2013que se traduce del noruego como \u201cSu Alteza Real la Princesa Heredera\u201d\u2013 a Epstein en 2012, Mette-Marit llama al difunto delincuente sexual \u201ccari\u00f1o\u201d y \u201cde buen coraz\u00f3n\u201d.<\/p>\n<p>En otro intercambio de correos electr\u00f3nicos de 2012, Mette-Marit se refiere a Epstein como \u201cmuy encantador\u201d, y agrega: \u201c\u00bfEs inapropiado que una madre sugiera dos mujeres desnudas llevando una tabla de surf para el fondo de pantalla de mi hijo de 15 a\u00f1os?\u201d<\/p>\n<p>En otra conversaci\u00f3n de 2012, Epstein le dice a Mette-Marit que est\u00e1 buscando esposa, antes de a\u00f1adir: \u201cPar\u00eds me est\u00e1 resultando interesante, pero prefiero a las escandinavas\u201d. En respuesta, Mette-Marit dice que Par\u00eds es \u201cbuena para el adulterio\u201d y que \u201cEscandinavia es mejor candidata a esposa\u201d.<\/p>\n<p>Mette-Marit acept\u00f3 que mostr\u00f3 \u201cpoco juicio\u201d sobre su relaci\u00f3n con Epstein, pero afirm\u00f3 que el exfinanciero era \u201cel \u00fanico responsable de sus acciones\u201d.<\/p>\n<p>\u201cDebo asumir la responsabilidad por no haber investigado m\u00e1s a fondo los antecedentes de Epstein y por no haberme dado cuenta antes de qu\u00e9 tipo de persona era. Lo lamento profundamente y es una responsabilidad que debo asumir\u201d, declar\u00f3 a CNN en un comunicado.<\/p>\n<p>Mientras aumenta la presi\u00f3n sobre Mette-Marit, el ex primer ministro de Noruega Thorbj\u00f8rn Jagland est\u00e1 bajo investigaci\u00f3n \u201cbajo sospecha de corrupci\u00f3n agravada\u201d relacionada con sus v\u00ednculos con Epstein, informaron funcionarios policiales del pa\u00eds en un comunicado el jueves.<\/p>\n<p>Noruega est\u00e1 investigando \u201csi recibi\u00f3 regalos, viajes y pr\u00e9stamos en relaci\u00f3n con su cargo\u201d, seg\u00fan \u00d8kokrim, el servicio nacional de fiscal\u00eda y agencia policial del pa\u00eds.<\/p>\n<p>Los archivos del Departamento de Justicia muestran que Jagland intercambi\u00f3 correos electr\u00f3nicos amistosos con Epstein y plane\u00f3 unas vacaciones en su isla.<\/p>\n<p>El abogado de Jagland declar\u00f3 a CNN que el exl\u00edder contribuir\u00eda plenamente a la investigaci\u00f3n, y a\u00f1adi\u00f3: \u201cCon base en lo que hemos descubierto hasta ahora, seguimos confiando en el resultado\u201d.<\/p>\n<p>Otras personalidades europeas tambi\u00e9n est\u00e1n se\u00f1aladas en los documentos de la \u00faltima divulgaci\u00f3n, incluidos miembros de la realeza, aunque su nombre en los archivos no indica ninguna irregularidad.<\/p>\n<p>En un correo electr\u00f3nico enviado a Epstein en 2010, una persona cuyo nombre est\u00e1 censurado incluy\u00f3 una foto que parec\u00eda mostrar a la Princesa Sof\u00eda de Suecia, entonces Sof\u00eda Kristina Hellqvist, en un viaje a \u00c1frica.<\/p>\n<p>El correo electr\u00f3nico dice: \u201cAqu\u00ed hay una foto de nuestra Sof\u00eda &#8211; \u00bfrecuerdas? &#8211; es decir, pronto la Princesa Sof\u00eda\u2026 toda la prensa sueca la est\u00e1 buscando\u2026 \u00a1mientras est\u00e1 en \u00c1frica\u2026!\u201d Se desconoce el contexto que rodea el intercambio de correos electr\u00f3nicos.<\/p>\n<p>El nombre \u201cSophia Hellqvist\u201d tambi\u00e9n aparece junto a Epstein en una lista de invitados de 2012, que fue enviada por correo electr\u00f3nico al difunto delincuente sexual, para lo que parece ser una representaci\u00f3n de Los Miserables.<\/p>\n<p>La princesa Sof\u00eda se reuni\u00f3 con Epstein en varias ocasiones hace unos 20 a\u00f1os antes de convertirse en miembro de la familia real, declar\u00f3 la corte real de Suecia a CNN el viernes.<\/p>\n<p>Pero negaron que la princesa hubiera asistido a tal evento en 2012.<\/p>\n<p>\u201cTenemos conocimiento de que, seg\u00fan informes, el nombre de la Princesa (mal escrito) fue encontrado en un documento de un estreno en 2012\u201d.<\/p>\n<p>\u201cSin embargo, la Princesa no sabe c\u00f3mo lleg\u00f3 su nombre a esta lista\u201d, afirman y a\u00f1aden que ella estaba en Suecia en ese momento y no hab\u00eda coincidido con Epstein durante \u201cvarios a\u00f1os\u201d.<\/p>\n<p>Mientras tanto, en 2012, el entonces pr\u00edncipe heredero de Dinamarca, ahora rey Federico X, figuraba en un correo electr\u00f3nico enviado a Epstein como \u201cinvitado confirmado\u201d a una cena.<\/p>\n<p>No est\u00e1 claro si Epstein o el pr\u00edncipe heredero asistieron al evento. CNN se ha puesto en contacto con la familia real danesa para solicitar comentarios.<\/p>\n<p>Como <a href=\"https:\/\/www.cnn.com\/2026\/02\/02\/uk\/epstein-files-britain-mandelson-andrew-ferguson-intl\">inform\u00f3<\/a> CNN, el expr\u00edncipe Andr\u00e9s de Gran Breta\u00f1a tambi\u00e9n est\u00e1 incluido varias veces en los archivos, al igual que su exesposa Sarah Ferguson, quien anteriormente expres\u00f3 su arrepentimiento por su asociaci\u00f3n con Epstein.<\/p>\n<p>De regreso en Noruega, y con el juicio por violaci\u00f3n de H\u00f8iby previsiblemente en el ojo p\u00fablico durante varias semanas, Taalesen cree que las dos controversias reales en curso se est\u00e1n \u201creforzando mutuamente\u201d.<\/p>\n<p>La cobertura diaria del tribunal mantendr\u00e1 a la familia real en el primer plano de la atenci\u00f3n p\u00fablica a medida que crece la presi\u00f3n sobre Mette-Marit, opina.<\/p>\n<p>Pero, reflejando las consecuencias en Gran Breta\u00f1a, son los correos electr\u00f3nicos de Epstein los que presentan el desaf\u00edo m\u00e1s serio al apellido familiar en d\u00e9cadas, un desaf\u00edo que, seg\u00fan ella, la casa real no puede darse el lujo de ignorar.<\/p>\n<p><em>Max Saltman, Nathan Hodge, Hira Humayun y James Frater de CNN contribuyeron con este informe.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La familia real de Noruega ha estado luchando contra esc\u00e1ndalos en m\u00faltiples frentes esta semana, que han motivado a organizaciones ben\u00e9ficas a tomar ciertos pasos para cortar o revisar lazos con la princesa heredera por sus pasados v\u00ednculos con el fallecido delincuente sexual Jeffrey Epstein, mientras que otros cr\u00edticos cuestionan su idoneidad para el papel [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470972","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los archivos de Epstein amenazan con dividir en dos a la familia real de Noruega - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/07\/archivos-epstein-amenazan-dividir-familia-real-noruega-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los archivos de Epstein amenazan con dividir en dos a la familia real de Noruega - Noticias\" \/>\n<meta property=\"og:description\" content=\"La familia real de Noruega ha estado luchando contra esc\u00e1ndalos en m\u00faltiples frentes esta semana, que han motivado a organizaciones ben\u00e9ficas a tomar ciertos pasos para cortar o revisar lazos con la princesa heredera por sus pasados v\u00ednculos con el fallecido delincuente sexual Jeffrey Epstein, mientras que otros cr\u00edticos cuestionan su idoneidad para el papel [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/07\/archivos-epstein-amenazan-dividir-familia-real-noruega-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-07T10:03:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/07\/archivos-epstein-amenazan-dividir-familia-real-noruega-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/07\/archivos-epstein-amenazan-dividir-familia-real-noruega-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Los archivos de Epstein amenazan con dividir en dos a la familia real de Noruega\",\"datePublished\":\"2026-02-07T10:03:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/07\/archivos-epstein-amenazan-dividir-familia-real-noruega-trax\/\"},\"wordCount\":1890,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/07\/archivos-epstein-amenazan-dividir-familia-real-noruega-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/07\/archivos-epstein-amenazan-dividir-familia-real-noruega-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/07\/archivos-epstein-amenazan-dividir-familia-real-noruega-trax\/\",\"name\":\"Los archivos de Epstein amenazan con dividir en dos a la familia real de Noruega - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-07T10:03:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/07\/archivos-epstein-amenazan-dividir-familia-real-noruega-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/07\/archivos-epstein-amenazan-dividir-familia-real-noruega-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/07\/archivos-epstein-amenazan-dividir-familia-real-noruega-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los archivos de Epstein amenazan con dividir en dos a la familia real de Noruega\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los archivos de Epstein amenazan con dividir en dos a la familia real de Noruega - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/07\/archivos-epstein-amenazan-dividir-familia-real-noruega-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Los archivos de Epstein amenazan con dividir en dos a la familia real de Noruega - Noticias","og_description":"La familia real de Noruega ha estado luchando contra esc\u00e1ndalos en m\u00faltiples frentes esta semana, que han motivado a organizaciones ben\u00e9ficas a tomar ciertos pasos para cortar o revisar lazos con la princesa heredera por sus pasados v\u00ednculos con el fallecido delincuente sexual Jeffrey Epstein, mientras que otros cr\u00edticos cuestionan su idoneidad para el papel [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/07\/archivos-epstein-amenazan-dividir-familia-real-noruega-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-07T10:03:57+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/07\/archivos-epstein-amenazan-dividir-familia-real-noruega-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/07\/archivos-epstein-amenazan-dividir-familia-real-noruega-trax\/"},"author":{"name":"","@id":""},"headline":"Los archivos de Epstein amenazan con dividir en dos a la familia real de Noruega","datePublished":"2026-02-07T10:03:57+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/07\/archivos-epstein-amenazan-dividir-familia-real-noruega-trax\/"},"wordCount":1890,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/07\/archivos-epstein-amenazan-dividir-familia-real-noruega-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/07\/archivos-epstein-amenazan-dividir-familia-real-noruega-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/07\/archivos-epstein-amenazan-dividir-familia-real-noruega-trax\/","name":"Los archivos de Epstein amenazan con dividir en dos a la familia real de Noruega - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-07T10:03:57+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/07\/archivos-epstein-amenazan-dividir-familia-real-noruega-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/07\/archivos-epstein-amenazan-dividir-familia-real-noruega-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/07\/archivos-epstein-amenazan-dividir-familia-real-noruega-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Los archivos de Epstein amenazan con dividir en dos a la familia real de Noruega"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/07\/archivos-epstein-amenazan-dividir-familia-real-noruega-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Los archivos de Epstein amenazan con dividir en dos a la familia real de Noruega","url":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/07\/archivos-epstein-amenazan-dividir-familia-real-noruega-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/07\/archivos-epstein-amenazan-dividir-familia-real-noruega-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-07T10:03:57Z","datePublished":"2026-02-07T10:03:57Z","dateModified":"2026-02-07T10:03:57Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Los archivos de Epstein amenazan con dividir en dos a la familia real de Noruega\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/07\\\/archivos-epstein-amenazan-dividir-familia-real-noruega-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/07\\\/archivos-epstein-amenazan-dividir-familia-real-noruega-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-07T10:03:57Z\",\"datePublished\":\"2026-02-07T10:03:57Z\",\"dateModified\":\"2026-02-07T10:03:57Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1473773,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/05\/04\/princesa-eugenia-embarazada-tercer-hijo-trax\/","url_meta":{"origin":1470972,"position":0},"title":"La princesa Eugenia est\u00e1 embarazada de su tercer hijo, seg\u00fan anunci\u00f3 el Palacio de Buckingham","author":"","date":"mayo 4, 2026","format":false,"excerpt":"La princesa Eugenia del Reino Unido espera su tercer hijo con su esposo Jack Brooksbank, seg\u00fan anunci\u00f3 el Palacio de Buckingham este lunes.La pareja, que dar\u00e1 la bienvenida a su nuevo miembro este verano, ya tiene dos ni\u00f1os: August Philip Hawke Brooksbank, quien naci\u00f3 en febrero de 2021, y Ernest\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470836,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/04\/analisis-archivos-epstein-trump-clinton-musk-trax\/","url_meta":{"origin":1470972,"position":1},"title":"Nuevos archivos profundizan un misterio cr\u00edtico sobre quienes se juntaron con Jeffrey Epstein","author":"","date":"febrero 4, 2026","format":false,"excerpt":"\u201cEl pueblo estadounidense debe comprender que no es un delito festejar con el se\u00f1or Epstein\u201d.Tal vez el vicesecretario de Justicia Todd Blanche tenga raz\u00f3n, dado el alto nivel de pruebas requerido para un procesamiento.Pero su comentario del lunes en Fox News ignor\u00f3 cruelmente a las v\u00edctimas de Jeffrey Epstein, que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470807,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/03\/famosos-archivos-epstein-musk-gates-allen-trax\/","url_meta":{"origin":1470972,"position":2},"title":"\u00bfQui\u00e9nes son los famosos que aparecen en los archivos de Epstein? Musk, Gates, Allen y la lista sigue","author":"","date":"febrero 3, 2026","format":false,"excerpt":"Los principales titulares de la \u00faltima filtraci\u00f3n de archivos relacionados con el delincuente sexual convicto Jeffrey Epstein se centran en el presidente Donald Trump, el expresidente Bill Clinton, Bill Gates, Elon Musk y el expr\u00edncipe Andr\u00e9s, entre otros. Y con raz\u00f3n. Esos nombres aparecen dispersos por todos los documentos.Mientras tanto,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449546,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/05\/17\/coleccion-fotos-familia-real-reino-unido-como-nunca-trax\/","url_meta":{"origin":1470972,"position":3},"title":"Esta exhibici\u00f3n de fotos muestra a la familia real del Reino Unido como nunca antes","author":"","date":"mayo 17, 2024","format":false,"excerpt":"(CNN) -- Como reina durante 70 a\u00f1os, Isabel II fue probablemente una de las mujeres m\u00e1s fotografiadas de la historia.Sin embargo, casi dos a\u00f1os despu\u00e9s de su muerte, han aparecido nuevas im\u00e1genes de la monarca que m\u00e1s tiempo ha reinado en Gran Breta\u00f1a con motivo de una exposici\u00f3n que se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447036,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/03\/16\/linea-sucesion-familia-real-quien-rey-despues-carlos-iii-reino-unido-windsor-trax\/","url_meta":{"origin":1470972,"position":4},"title":"As\u00ed es el \u00e1rbol geneal\u00f3gico de la realeza de Reino Unido: qui\u00e9n es qui\u00e9n en la Casa de Windsor","author":"","date":"marzo 16, 2024","format":false,"excerpt":"(CNN) -- La familia real brit\u00e1nica tiene una compleja estructura de pr\u00edncipes, duques y condes que establece claramente qui\u00e9nes pueden ascender al trono y en qu\u00e9 orden.Carlos se convirti\u00f3 en el nuevo rey del Reino Unido de Gran Breta\u00f1a e Irlanda del Norte tras la muerte de su madre, la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447254,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/03\/22\/quienes-arbol-miembros-familia-real-reino-unido-casa-windsor-trax\/","url_meta":{"origin":1470972,"position":5},"title":"As\u00ed es el \u00e1rbol geneal\u00f3gico de la realeza de Reino Unido: qui\u00e9n es qui\u00e9n en la Casa de Windsor","author":"","date":"marzo 22, 2024","format":false,"excerpt":"(CNN) -- La familia real brit\u00e1nica tiene una compleja estructura de pr\u00edncipes, duques y condes.Aqu\u00ed te dejamos una gu\u00eda pr\u00e1ctica de qui\u00e9n es qui\u00e9n en la Casa de Windsor, que encabez\u00f3 Isabel II hasta su muerte a los 96 a\u00f1os, y qu\u00e9 lugar ocupan en la l\u00ednea al trono.Los hijos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1470972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1470972"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1470972\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1470972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1470972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1470972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}