{"id":1470990,"date":"2026-02-07T21:03:40","date_gmt":"2026-02-08T05:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/07\/trump-presume-reunion-presidente-honduras-trax\/"},"modified":"2026-02-07T21:03:40","modified_gmt":"2026-02-08T05:03:40","slug":"trump-presume-reunion-presidente-honduras-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/07\/trump-presume-reunion-presidente-honduras-trax\/","title":{"rendered":"Trump presume una &#171;reuni\u00f3n muy importante&#187; con el presidente de Honduras"},"content":{"rendered":"<p>El presidente de Estados Unidos, Donald Trump, elogi\u00f3 a su hom\u00f3logo hondure\u00f1o, Nasry \u201cTito\u201d Asfura, diciendo que ambos mantuvieron una \u201creuni\u00f3n muy importante\u201d en Florida el s\u00e1bado.<\/p>\n<p>\u201cHoy tuve una reuni\u00f3n muy importante con mi amigo y presidente de Honduras, Nasry \u2018Tito\u2019 Asfura, en Mar-a-Lago en Palm Beach, Florida. Fue un gran honor para m\u00ed apoyar la campa\u00f1a de Tito. Una vez que le di mi fuerte respaldo, \u00a1gan\u00f3 su elecci\u00f3n! Tito y yo compartimos muchos de los mismos valores de \u2018Estados Unidos Primero\u2019\u201d, public\u00f3 Trump en Truth Social.<\/p>\n<p>Asfura, un conservador, super\u00f3 por poco al centrista de derecha Salvador Nasralla a finales del a\u00f1o pasado en una contienda marcada por denuncias de intervenci\u00f3n extranjera e irregularidades en la votaci\u00f3n. Trump respald\u00f3 a Asfura d\u00edas antes de las elecciones, advirtiendo de que si no ganaba, \u201cEstados Unidos no seguir\u00e1 tirando dinero bueno tras malo, porque un l\u00edder equivocado solo puede traer resultados catastr\u00f3ficos a un pa\u00eds, sin importar de cu\u00e1l se trate\u201d.<\/p>\n<p>El presidente estadounidense destac\u00f3 el s\u00e1bado la \u201cestrecha asociaci\u00f3n\u201d entre ambos pa\u00edses en temas de seguridad, lucha contra el narcotr\u00e1fico e inmigraci\u00f3n. Dijo que los dos l\u00edderes \u201cdiscutieron muchos otros temas\u201d, incluido el comercio.<\/p>\n<p>\u201c\u00c9l ama al pueblo de Honduras y est\u00e1 enfocado en su salud, bienestar, educaci\u00f3n y prosperidad econ\u00f3mica\u201d, dijo Trump.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de Estados Unidos, Donald Trump, elogi\u00f3 a su hom\u00f3logo hondure\u00f1o, Nasry \u201cTito\u201d Asfura, diciendo que ambos mantuvieron una \u201creuni\u00f3n muy importante\u201d en Florida el s\u00e1bado. \u201cHoy tuve una reuni\u00f3n muy importante con mi amigo y presidente de Honduras, Nasry \u2018Tito\u2019 Asfura, en Mar-a-Lago en Palm Beach, Florida. Fue un gran honor para m\u00ed [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470990","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump presume una &quot;reuni\u00f3n muy importante&quot; con el presidente de Honduras - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/07\/trump-presume-reunion-presidente-honduras-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump presume una &quot;reuni\u00f3n muy importante&quot; con el presidente de Honduras - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente de Estados Unidos, Donald Trump, elogi\u00f3 a su hom\u00f3logo hondure\u00f1o, Nasry \u201cTito\u201d Asfura, diciendo que ambos mantuvieron una \u201creuni\u00f3n muy importante\u201d en Florida el s\u00e1bado. \u201cHoy tuve una reuni\u00f3n muy importante con mi amigo y presidente de Honduras, Nasry \u2018Tito\u2019 Asfura, en Mar-a-Lago en Palm Beach, Florida. Fue un gran honor para m\u00ed [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/07\/trump-presume-reunion-presidente-honduras-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-08T05:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/07\/trump-presume-reunion-presidente-honduras-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/07\/trump-presume-reunion-presidente-honduras-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump presume una &#171;reuni\u00f3n muy importante&#187; con el presidente de Honduras\",\"datePublished\":\"2026-02-08T05:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/07\/trump-presume-reunion-presidente-honduras-trax\/\"},\"wordCount\":266,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/07\/trump-presume-reunion-presidente-honduras-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/07\/trump-presume-reunion-presidente-honduras-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/07\/trump-presume-reunion-presidente-honduras-trax\/\",\"name\":\"Trump presume una \\\"reuni\u00f3n muy importante\\\" con el presidente de Honduras - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-08T05:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/07\/trump-presume-reunion-presidente-honduras-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/07\/trump-presume-reunion-presidente-honduras-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/07\/trump-presume-reunion-presidente-honduras-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump presume una &#171;reuni\u00f3n muy importante&#187; con el presidente de Honduras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump presume una \"reuni\u00f3n muy importante\" con el presidente de Honduras - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/07\/trump-presume-reunion-presidente-honduras-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trump presume una \"reuni\u00f3n muy importante\" con el presidente de Honduras - Noticias","og_description":"El presidente de Estados Unidos, Donald Trump, elogi\u00f3 a su hom\u00f3logo hondure\u00f1o, Nasry \u201cTito\u201d Asfura, diciendo que ambos mantuvieron una \u201creuni\u00f3n muy importante\u201d en Florida el s\u00e1bado. \u201cHoy tuve una reuni\u00f3n muy importante con mi amigo y presidente de Honduras, Nasry \u2018Tito\u2019 Asfura, en Mar-a-Lago en Palm Beach, Florida. Fue un gran honor para m\u00ed [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/07\/trump-presume-reunion-presidente-honduras-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-08T05:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/07\/trump-presume-reunion-presidente-honduras-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/07\/trump-presume-reunion-presidente-honduras-trax\/"},"author":{"name":"","@id":""},"headline":"Trump presume una &#171;reuni\u00f3n muy importante&#187; con el presidente de Honduras","datePublished":"2026-02-08T05:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/07\/trump-presume-reunion-presidente-honduras-trax\/"},"wordCount":266,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/07\/trump-presume-reunion-presidente-honduras-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/07\/trump-presume-reunion-presidente-honduras-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/07\/trump-presume-reunion-presidente-honduras-trax\/","name":"Trump presume una \"reuni\u00f3n muy importante\" con el presidente de Honduras - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-08T05:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/07\/trump-presume-reunion-presidente-honduras-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/07\/trump-presume-reunion-presidente-honduras-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/07\/trump-presume-reunion-presidente-honduras-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump presume una &#171;reuni\u00f3n muy importante&#187; con el presidente de Honduras"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/07\/trump-presume-reunion-presidente-honduras-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump presume una &#171;reuni\u00f3n muy importante&#187; con el presidente de Honduras","url":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/07\/trump-presume-reunion-presidente-honduras-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/07\/trump-presume-reunion-presidente-honduras-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-08T05:03:40Z","datePublished":"2026-02-08T05:03:40Z","dateModified":"2026-02-08T05:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump presume una &#171;reuni\\u00f3n muy importante&#187; con el presidente de Honduras\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/07\\\/trump-presume-reunion-presidente-honduras-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/07\\\/trump-presume-reunion-presidente-honduras-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-08T05:03:40Z\",\"datePublished\":\"2026-02-08T05:03:40Z\",\"dateModified\":\"2026-02-08T05:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1469598,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/12\/26\/exclusivo-entrevista-nasry-asfura-honduras-ganador-orix\/","url_meta":{"origin":1470990,"position":0},"title":"Exclusivo CNN: Asfura dice que apoyo de Trump fue &#171;espont\u00e1neo&#187; y lo &#171;impresion\u00f3&#187; pero no fue decisivo en elecci\u00f3n de Honduras","author":"","date":"diciembre 26, 2025","format":false,"excerpt":"Nasry \u201cTito\u201d Asfura, el candidato declarado ganador de la elecci\u00f3n presidencial del 30 de noviembre en Honduras, asegura que el apoyo rotundo que obtuvo del presidente de Estados Unidos, Donald Trump, d\u00edas antes de los comicios fue \u201cespont\u00e1neo\u201d y lo \u201csorprendi\u00f3\u201d, pero \u2014desde su perspectiva\u2014 no fue definitivo en el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469547,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/12\/24\/cne-honduras-declara-nasry-asfura-ganador-presidencial-orix\/","url_meta":{"origin":1470990,"position":1},"title":"El Consejo Electoral de Honduras declara a Nasry Asfura ganador de la elecci\u00f3n presidencial; sus rivales dicen que impugnar\u00e1n","author":"","date":"diciembre 24, 2025","format":false,"excerpt":"El Consejo Nacional Electoral de Honduras (CNE) declar\u00f3 este mi\u00e9rcoles a Nasy \u201cTito\u201d Asfura, candidato del conservador Partido Nacional, ganador de la elecci\u00f3n presidencial del 30 de noviembre.D\u00edas antes de las elecciones, Asfura fue respaldado por el presidente de Estados Unidos, Donald Trump.En un mensaje en video, las consejeras Ana\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468797,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/11\/28\/trump-perdon-expresidente-honduras-juan-orlando-hernandez-trax\/","url_meta":{"origin":1470990,"position":2},"title":"Trump dice que conceder\u00e1 un &#171;perd\u00f3n total y completo&#187; al expresidente de Honduras Juan Orlando Hern\u00e1ndez","author":"","date":"noviembre 28, 2025","format":false,"excerpt":"El presidente Donald Trump dijo este viernes que tiene la intenci\u00f3n de conceder un \u201cperd\u00f3n total y completo\u201d al expresidente de Honduras Juan Orlando Hern\u00e1ndez, una medida que borrar\u00eda una importante condena en Estados Unidos por narcotr\u00e1fico para un antiguo aliado estadounidense que actualmente cumple una condena federal de 45\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468753,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/11\/27\/trump-elecciones-honduras-pide-luchar-contra-maduro-orix\/","url_meta":{"origin":1470990,"position":3},"title":"Trump habla sobre las elecciones en Honduras y pide &#171;luchar contra Maduro&#187; y los &#171;narcocomunistas&#187;","author":"","date":"noviembre 27, 2025","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, habl\u00f3 sobre las elecciones en Honduras de este domingo y dio su apoyo a Nasry \u201cTito\u201d Asfura, el candidato del Partido Nacional de Honduras, para \u201ccombatir a los narcocomunistas\u201d y que el presidente de Venezuela, Nicol\u00e1s Maduro, no \u201ctome el control\u201d del pa\u00eds.\u201cTito\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469561,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/12\/25\/paises-organismos-reconocieron-declaratoria-presidencial-asfura-honduras-orix\/","url_meta":{"origin":1470990,"position":4},"title":"Qu\u00e9 pa\u00edses y organismos reconocieron ya la declaratoria presidencial de Asfura en Honduras","author":"","date":"diciembre 25, 2025","format":false,"excerpt":"En medio de la controversia electoral y de advertencias de impugnaciones a los resultados de votaci\u00f3n de Honduras, Nasry \u201cTito\u201d Asfura ya suma varios apoyos internacionales luego de que el Consejo Nacional Electoral (CNE) lo declarara el mi\u00e9rcoles como ganador de los comicios presidenciales.Varios pa\u00edses han felicitado ya a Asfura\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472454,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/03\/22\/asfura-noem-honduras-inversion-migracion-seguridad-efe\/","url_meta":{"origin":1470990,"position":5},"title":"Asfura y Noem hablaron en Honduras de inversi\u00f3n, migraci\u00f3n y seguridad","author":"","date":"marzo 22, 2026","format":false,"excerpt":"El presidente de Honduras, Nasry \u2018Tito\u2019 Asfura, y la exsecretaria de Seguridad Nacional de Estados Unidos, Kristi Noem, hablaron este domingo en Tegucigalpa de inversiones, migraci\u00f3n y seguridad, inform\u00f3 el mandatario del pa\u00eds centroamericano.Asfura dijo escuetamente a periodistas, tras el encuentro de una hora con Noem en la Casa Presidencial,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1470990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1470990"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1470990\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1470990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1470990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1470990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}