{"id":1471044,"date":"2026-02-09T15:03:37","date_gmt":"2026-02-09T23:03:37","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/09\/rey-carlos-apoya-investigacion-principe-andres-epstein-informacion-confidencial-trax\/"},"modified":"2026-02-09T15:03:37","modified_gmt":"2026-02-09T23:03:37","slug":"rey-carlos-apoya-investigacion-principe-andres-epstein-informacion-confidencial-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/09\/rey-carlos-apoya-investigacion-principe-andres-epstein-informacion-confidencial-trax\/","title":{"rendered":"El rey Carlos III apoyar\u00e1 en la investigaci\u00f3n sobre si el expr\u00edncipe Andr\u00e9s comparti\u00f3 informaci\u00f3n confidencial con Epstein"},"content":{"rendered":"<p>El rey Carlos III de Inglaterra ha manifestado su disposici\u00f3n para colaborar con la polic\u00eda brit\u00e1nica en una investigaci\u00f3n que pone nuevamente a Andr\u00e9s Mountbatten-Windsor en el ojo del hurac\u00e1n. Las autoridades eval\u00faan actualmente una denuncia que vincula al expr\u00edncipe con el intercambio de informaci\u00f3n confidencial con el fallecido delincuente sexual Jeffrey Epstein, durante el tiempo en que el ejerc\u00eda como enviado comercial del Reino Unido.<\/p>\n<p>El reciente lote de documentos de Epstein<a href=\"https:\/\/www.cnn.com\/2026\/02\/05\/world\/andrew-virginia-giuffre-photo-intl\"> publicados por el Departamento de Justicia de Estados Unidos<\/a>, que ha generado un renovado escrutinio sobre el desacreditado miembro de la realeza, parece mostrar que Mountbatten-Windsor envi\u00f3 material confidencial a Epstein en 2010.<\/p>\n<p>Graham Smith, director ejecutivo del grupo brit\u00e1nico antimon\u00e1rquico Republic, dijo el lunes que denunci\u00f3 a Mountbatten-Windsor a la polic\u00eda por \u201cpresunta mala conducta en el ejercicio de funciones p\u00fablicas y violaci\u00f3n de secretos oficiales\u201d.<\/p>\n<p>El lunes, la Polic\u00eda del Valle del T\u00e1mesis dijo a CNN: \u201cPodemos confirmar la recepci\u00f3n de este informe y estamos evaluando la informaci\u00f3n seg\u00fan nuestros procedimientos establecidos\u201d, dijo un portavoz de la fuerza policial.<\/p>\n<p>M\u00e1s tarde ese mismo lunes, un portavoz del Palacio de Buckingham dijo que el rey Carlos hab\u00eda \u201cdejado claro, en palabras y <a href=\"https:\/\/www.cnn.com\/2025\/10\/17\/uk\/prince-andrew-gives-up-royal-titles-latam-intl\">mediante acciones sin precedentes<\/a>, su profunda preocupaci\u00f3n ante las acusaciones que siguen saliendo a la luz respecto a la conducta del se\u00f1or Mountbatten-Windsor\u201d.<\/p>\n<p>\u201cAunque las acusaciones espec\u00edficas deber\u00e1n ser abordadas por el se\u00f1or Mountbatten-Windsor, si somos contactados por la Polic\u00eda del Valle del T\u00e1mesis estamos dispuestos a apoyarlos, como cabr\u00eda esperar\u201d, dijo el portavoz.<\/p>\n<p>Mountbatten-Windsor ha negado anteriormente cualquier conducta indebida respecto a sus v\u00ednculos con Epstein. No ha respondido p\u00fablicamente a las \u00faltimas acusaciones. CNN ha intentado contactarlo para obtener comentarios.<\/p>\n<p>El expr\u00edncipe es una de varias figuras destacadas <a href=\"https:\/\/www.cnn.com\/2026\/02\/02\/uk\/epstein-files-britain-mandelson-andrew-ferguson-intl\">de la vida p\u00fablica brit\u00e1nica<\/a> que han enfrentado cr\u00edticas en los \u00faltimos d\u00edas por sus v\u00ednculos con Epstein. <a href=\"https:\/\/www.cnn.com\/2026\/02\/03\/europe\/peter-mandelson-epstein-ties-britain-intl-latam\">Peter Mandelson<\/a>, el exembajador brit\u00e1nico en EE.UU., renunci\u00f3 a la C\u00e1mara de los Lores la semana pasada despu\u00e9s de que los \u00faltimos documentos parecieran mostrar que filtr\u00f3 informaci\u00f3n gubernamental sensible al mercado a Epstein tras la crisis financiera de 2008.<\/p>\n<p><a href=\"https:\/\/www.cnn.com\/2026\/02\/06\/uk\/uk-police-searching-peter-mandelson-linked-properties-intl\">La polic\u00eda brit\u00e1nica registr\u00f3 dos propiedades vinculadas a Mandelson<\/a> el viernes como parte de una investigaci\u00f3n sobre mala conducta en la funci\u00f3n p\u00fablica. CNN no ha podido contactar al representante de Mandelson. Mandelson ha dicho anteriormente que fue \u201cun error creer a (Epstein) tras su condena y continuar mi relaci\u00f3n con \u00e9l despu\u00e9s\u201d.<\/p>\n<p>Mountbatten-Windsor se convirti\u00f3 en enviado comercial en 2001, pero renunci\u00f3 una d\u00e9cada despu\u00e9s tras ser criticado por su relaci\u00f3n con Epstein. El expr\u00edncipe dijo en ese momento que su cargo \u201cya no es necesario para el trabajo que realizo hoy y, m\u00e1s importante aun, en el futuro\u201d.<\/p>\n<p>En octubre de 2010, Epstein envi\u00f3 un correo electr\u00f3nico al miembro de la realeza solicitando detalles sobre un pr\u00f3ximo viaje a Asia, seg\u00fan los archivos del Departamento de Justicia. En respuesta, Mountbatten-Windsor le envi\u00f3 a Epstein un breve itinerario detallando sus planes de viaje a varios destinos, incluidos Vietnam, Singapur y Hong Kong.<\/p>\n<p>Luego, tras concluir el viaje, Mountbatten-Windsor reenvi\u00f3 \u201cinformes de visitas\u201d a Epstein, inicialmente enviados al expr\u00edncipe por su entonces asesor especial Amit Patel. La visita al extranjero aparece en un informe financiero publicado por la familia real.<\/p>\n<p>Los enviados comerciales no son funcionarios p\u00fablicos en el Reino Unido, pero el cargo conlleva un \u201cdeber de confidencialidad respecto a la informaci\u00f3n recibida\u201d, seg\u00fan un documento de condiciones de nombramiento publicado por el Parlamento brit\u00e1nico en 2023.<\/p>\n<p>Esta informaci\u00f3n \u201cpuede incluir datos sensibles, comerciales o pol\u00edticos compartidos sobre mercados\/visitas relevantes\u201d, dec\u00eda el documento. \u201cEste deber de confidencialidad continuar\u00e1 aplic\u00e1ndose despu\u00e9s de la expiraci\u00f3n de su mandato\u201d.<\/p>\n<p>\u201cAdem\u00e1s, ser\u00e1n aplicables las Leyes de Secretos Oficiales de 1911 y 1989\u201d, a\u00f1ad\u00eda el documento. Se desconoce si la informaci\u00f3n que Mountbatten-Windsor comparti\u00f3 era de car\u00e1cter comercial o pol\u00edtico sensible.<\/p>\n<p>Durante a\u00f1os, el expr\u00edncipe ha intentado evitar preguntas sobre sus v\u00ednculos con Epstein. Le dijo al programa <a href=\"https:\/\/www.cnn.com\/2019\/11\/16\/uk\/prince-andrew-jeffrey-epstein-bbc-interview\">Newsnight de la BBC<\/a> en 2019 que hab\u00eda ido a Nueva York en 2010, despu\u00e9s de que Epstein fuera condenado como delincuente sexual, para romper contacto con \u00e9l.<\/p>\n<p>\u201cFui all\u00ed con el \u00fanico prop\u00f3sito de decirle que, debido a que hab\u00eda sido condenado, no era apropiado que nos vieran juntos\u201d, dijo.<\/p>\n<p>En diciembre de 2010, parece que Mountbatten-Windsor envi\u00f3 a Epstein lo que \u00e9l llam\u00f3 un \u201cinforme confidencial\u201d sobre oportunidades de inversi\u00f3n relacionadas con la reconstrucci\u00f3n de la provincia de Helmand en Afganist\u00e1n, donde operaban soldados brit\u00e1nicos en ese momento, seg\u00fan muestran documentos del Departamento de Justicia.<\/p>\n<p>El expr\u00edncipe dijo en el correo electr\u00f3nico dirigido a Epstein que estar\u00eda \u201cmuy interesado en tus comentarios, opiniones o ideas sobre a qui\u00e9n m\u00e1s podr\u00eda mostrar esto de manera \u00fatil para atraer inter\u00e9s\u201d.<\/p>\n<p>En otro correo electr\u00f3nico de diciembre de 2009, Mountbatten-Windsor le dijo a Epstein que pas\u00f3 un fin de semana en Par\u00eds con una \u201cinteresante familia estadounidense de banqueros que busca ayuda en Medio Oriente; una brecha en su cobertura geogr\u00e1fica\u201d.<\/p>\n<p>M\u00e1s tarde esa noche, Epstein respondi\u00f3 preguntando \u201c\u00bfen qu\u00e9 pa\u00eds de Medio Oriente eres m\u00e1s fuerte?\u201d.<\/p>\n<p>Las recientes revelaciones llegan poco despu\u00e9s de que Mountbatten-Windsor se mudara de su residencia de toda la vida en <a href=\"https:\/\/www.cnn.com\/2026\/02\/04\/europe\/andrew-mountbatten-windsor-moves-royals-epstein-intl-hnk\">Windsor<\/a>, a las afueras de Londres, en medio del esc\u00e1ndalo en torno a Epstein.<\/p>\n<p>El lunes, un portavoz del Palacio de Kensington dijo que el pr\u00edncipe y la princesa de Gales han estado \u201cmuy preocupados\u201d por el aluvi\u00f3n de<a href=\"https:\/\/www.cnn.com\/2026\/02\/03\/politics\/epstein-files-musk-lutnick-branson-emails\"> nuevos documentos<\/a>, sin mencionar directamente a Mountbatten-Windsor.<\/p>\n<p>\u201cSus pensamientos siguen enfocados en las v\u00edctimas\u201d, dijo el portavoz.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El rey Carlos III de Inglaterra ha manifestado su disposici\u00f3n para colaborar con la polic\u00eda brit\u00e1nica en una investigaci\u00f3n que pone nuevamente a Andr\u00e9s Mountbatten-Windsor en el ojo del hurac\u00e1n. Las autoridades eval\u00faan actualmente una denuncia que vincula al expr\u00edncipe con el intercambio de informaci\u00f3n confidencial con el fallecido delincuente sexual Jeffrey Epstein, durante el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1471044","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El rey Carlos III apoyar\u00e1 en la investigaci\u00f3n sobre si el expr\u00edncipe Andr\u00e9s comparti\u00f3 informaci\u00f3n confidencial con Epstein - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/09\/rey-carlos-apoya-investigacion-principe-andres-epstein-informacion-confidencial-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El rey Carlos III apoyar\u00e1 en la investigaci\u00f3n sobre si el expr\u00edncipe Andr\u00e9s comparti\u00f3 informaci\u00f3n confidencial con Epstein - Noticias\" \/>\n<meta property=\"og:description\" content=\"El rey Carlos III de Inglaterra ha manifestado su disposici\u00f3n para colaborar con la polic\u00eda brit\u00e1nica en una investigaci\u00f3n que pone nuevamente a Andr\u00e9s Mountbatten-Windsor en el ojo del hurac\u00e1n. Las autoridades eval\u00faan actualmente una denuncia que vincula al expr\u00edncipe con el intercambio de informaci\u00f3n confidencial con el fallecido delincuente sexual Jeffrey Epstein, durante el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/09\/rey-carlos-apoya-investigacion-principe-andres-epstein-informacion-confidencial-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-09T23:03:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/09\/rey-carlos-apoya-investigacion-principe-andres-epstein-informacion-confidencial-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/09\/rey-carlos-apoya-investigacion-principe-andres-epstein-informacion-confidencial-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El rey Carlos III apoyar\u00e1 en la investigaci\u00f3n sobre si el expr\u00edncipe Andr\u00e9s comparti\u00f3 informaci\u00f3n confidencial con Epstein\",\"datePublished\":\"2026-02-09T23:03:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/09\/rey-carlos-apoya-investigacion-principe-andres-epstein-informacion-confidencial-trax\/\"},\"wordCount\":1043,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/09\/rey-carlos-apoya-investigacion-principe-andres-epstein-informacion-confidencial-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/09\/rey-carlos-apoya-investigacion-principe-andres-epstein-informacion-confidencial-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/09\/rey-carlos-apoya-investigacion-principe-andres-epstein-informacion-confidencial-trax\/\",\"name\":\"El rey Carlos III apoyar\u00e1 en la investigaci\u00f3n sobre si el expr\u00edncipe Andr\u00e9s comparti\u00f3 informaci\u00f3n confidencial con Epstein - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-09T23:03:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/09\/rey-carlos-apoya-investigacion-principe-andres-epstein-informacion-confidencial-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/09\/rey-carlos-apoya-investigacion-principe-andres-epstein-informacion-confidencial-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/09\/rey-carlos-apoya-investigacion-principe-andres-epstein-informacion-confidencial-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El rey Carlos III apoyar\u00e1 en la investigaci\u00f3n sobre si el expr\u00edncipe Andr\u00e9s comparti\u00f3 informaci\u00f3n confidencial con Epstein\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El rey Carlos III apoyar\u00e1 en la investigaci\u00f3n sobre si el expr\u00edncipe Andr\u00e9s comparti\u00f3 informaci\u00f3n confidencial con Epstein - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/09\/rey-carlos-apoya-investigacion-principe-andres-epstein-informacion-confidencial-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El rey Carlos III apoyar\u00e1 en la investigaci\u00f3n sobre si el expr\u00edncipe Andr\u00e9s comparti\u00f3 informaci\u00f3n confidencial con Epstein - Noticias","og_description":"El rey Carlos III de Inglaterra ha manifestado su disposici\u00f3n para colaborar con la polic\u00eda brit\u00e1nica en una investigaci\u00f3n que pone nuevamente a Andr\u00e9s Mountbatten-Windsor en el ojo del hurac\u00e1n. Las autoridades eval\u00faan actualmente una denuncia que vincula al expr\u00edncipe con el intercambio de informaci\u00f3n confidencial con el fallecido delincuente sexual Jeffrey Epstein, durante el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/09\/rey-carlos-apoya-investigacion-principe-andres-epstein-informacion-confidencial-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-09T23:03:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/09\/rey-carlos-apoya-investigacion-principe-andres-epstein-informacion-confidencial-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/09\/rey-carlos-apoya-investigacion-principe-andres-epstein-informacion-confidencial-trax\/"},"author":{"name":"","@id":""},"headline":"El rey Carlos III apoyar\u00e1 en la investigaci\u00f3n sobre si el expr\u00edncipe Andr\u00e9s comparti\u00f3 informaci\u00f3n confidencial con Epstein","datePublished":"2026-02-09T23:03:37+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/09\/rey-carlos-apoya-investigacion-principe-andres-epstein-informacion-confidencial-trax\/"},"wordCount":1043,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/09\/rey-carlos-apoya-investigacion-principe-andres-epstein-informacion-confidencial-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/09\/rey-carlos-apoya-investigacion-principe-andres-epstein-informacion-confidencial-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/09\/rey-carlos-apoya-investigacion-principe-andres-epstein-informacion-confidencial-trax\/","name":"El rey Carlos III apoyar\u00e1 en la investigaci\u00f3n sobre si el expr\u00edncipe Andr\u00e9s comparti\u00f3 informaci\u00f3n confidencial con Epstein - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-09T23:03:37+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/09\/rey-carlos-apoya-investigacion-principe-andres-epstein-informacion-confidencial-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/09\/rey-carlos-apoya-investigacion-principe-andres-epstein-informacion-confidencial-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/09\/rey-carlos-apoya-investigacion-principe-andres-epstein-informacion-confidencial-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El rey Carlos III apoyar\u00e1 en la investigaci\u00f3n sobre si el expr\u00edncipe Andr\u00e9s comparti\u00f3 informaci\u00f3n confidencial con Epstein"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/09\/rey-carlos-apoya-investigacion-principe-andres-epstein-informacion-confidencial-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El rey Carlos III apoyar\u00e1 en la investigaci\u00f3n sobre si el expr\u00edncipe Andr\u00e9s comparti\u00f3 informaci\u00f3n confidencial con Epstein","url":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/09\/rey-carlos-apoya-investigacion-principe-andres-epstein-informacion-confidencial-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/09\/rey-carlos-apoya-investigacion-principe-andres-epstein-informacion-confidencial-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-09T23:03:37Z","datePublished":"2026-02-09T23:03:37Z","dateModified":"2026-02-09T23:03:37Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El rey Carlos III apoyar\\u00e1 en la investigaci\\u00f3n sobre si el expr\\u00edncipe Andr\\u00e9s comparti\\u00f3 informaci\\u00f3n confidencial con Epstein\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/09\\\/rey-carlos-apoya-investigacion-principe-andres-epstein-informacion-confidencial-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/09\\\/rey-carlos-apoya-investigacion-principe-andres-epstein-informacion-confidencial-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-09T23:03:37Z\",\"datePublished\":\"2026-02-09T23:03:37Z\",\"dateModified\":\"2026-02-09T23:03:37Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1470706,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/01\/31\/fotos-exprincipe-andres-mujer-epstein-trax\/","url_meta":{"origin":1471044,"position":0},"title":"Una serie de fotos de los archivos Epstein parecen mostrar al expr\u00edncipe Andr\u00e9s en el suelo con una mujer","author":"","date":"enero 31, 2026","format":false,"excerpt":"Una serie de fotograf\u00edas parece mostrar al expr\u00edncipe Andr\u00e9s en cuatro patas, inclinado sobre una mujer o ni\u00f1a que yace en el suelo, seg\u00fan la \u00faltima tanda de archivos de Epstein publicados por parte del Departamento de Justicia de Estados Unidos el viernes.En una imagen sin fecha, Andrew Mountbatten-Windsor mira\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473773,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/05\/04\/princesa-eugenia-embarazada-tercer-hijo-trax\/","url_meta":{"origin":1471044,"position":1},"title":"La princesa Eugenia est\u00e1 embarazada de su tercer hijo, seg\u00fan anunci\u00f3 el Palacio de Buckingham","author":"","date":"mayo 4, 2026","format":false,"excerpt":"La princesa Eugenia del Reino Unido espera su tercer hijo con su esposo Jack Brooksbank, seg\u00fan anunci\u00f3 el Palacio de Buckingham este lunes.La pareja, que dar\u00e1 la bienvenida a su nuevo miembro este verano, ya tiene dos ni\u00f1os: August Philip Hawke Brooksbank, quien naci\u00f3 en febrero de 2021, y Ernest\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471434,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/19\/quien-es-exprincipe-andres-andrew-mountbatten-windsor-orix\/","url_meta":{"origin":1471044,"position":2},"title":"\u00bfQui\u00e9n es Andrew Mountbatten-Windsor, el expr\u00edncipe Andr\u00e9s?","author":"","date":"febrero 19, 2026","format":false,"excerpt":"Andrew Mountbatten-Windsor, anteriormente conocido como el pr\u00edncipe Andr\u00e9s, duque de York, es el tercer hijo \u2014el segundo var\u00f3n\u2014 de la reina Isabel II y el pr\u00edncipe Felipe, duque de Edimburgo. Este jueves, fue detenido en su residencia de Sandringham bajo sospecha de conducta inapropiada en un cargo p\u00fablico, tras nuevas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471429,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/19\/por-que-arresto-andres-mountbatten-windsor-trax\/","url_meta":{"origin":1471044,"position":3},"title":"\u00bfPor qu\u00e9 arrestaron al expr\u00edncipe Andr\u00e9s y cu\u00e1l era su v\u00ednculo con Epstein?","author":"","date":"febrero 19, 2026","format":false,"excerpt":"El arresto de Andrew Mountbatten-Windsor el jueves, d\u00eda de su cumplea\u00f1os n\u00famero 66, es el \u00faltimo acontecimiento en una controversia de a\u00f1os de duraci\u00f3n sobre sus v\u00ednculos con el delincuente sexual convicto Jeffrey Epstein. As\u00ed se desarroll\u00f3:\u2022 2011: Tras una d\u00e9cada como enviado comercial, encargado de promover los intereses comerciales\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467967,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/11\/02\/trump-habla-exprincipe-andres-trax\/","url_meta":{"origin":1471044,"position":4},"title":"Trump sobre el expr\u00edncipe Andr\u00e9s: &#171;Me siento mal por la familia&#187;","author":"","date":"noviembre 2, 2025","format":false,"excerpt":"El presidente de EE.UU. Donald Trump expres\u00f3 consternaci\u00f3n por la situaci\u00f3n de la familia real brit\u00e1nica d\u00edas despu\u00e9s de que Andr\u00e9s fuera despojado de sus t\u00edtulos, diciendo el domingo que los Windsor hab\u00edan sufrido \u201calgo terrible\u201d.\u201cMe siento muy mal\u201d, dijo Trump en el Air Force One mientras regresaba a Washington\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471468,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/19\/exprincipe-arrestado-estados-unidos-entredicho-rendicion-cuentas-trax\/","url_meta":{"origin":1471044,"position":5},"title":"Un expr\u00edncipe es arrestado en el Reino Unido mientras en Estados Unidos sigue en entredicho la rendici\u00f3n de cuentas","author":"","date":"febrero 19, 2026","format":false,"excerpt":"Los agentes de polic\u00eda que acudieron a buscar al pr\u00edncipe ca\u00eddo del Reino Unido en su cumplea\u00f1os n\u00famero 66 desmintieron la percepci\u00f3n definitoria del esc\u00e1ndalo de Jeffrey Epstein: que las \u00e9lites ricas est\u00e1n protegidas del escrutinio debido a qui\u00e9nes son.En Estados Unidos, la rendici\u00f3n de cuentas todav\u00eda parece dif\u00edcil de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1471044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1471044"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1471044\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1471044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1471044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1471044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}