{"id":1471047,"date":"2026-02-09T17:03:52","date_gmt":"2026-02-10T01:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/09\/operaciones-bursatiles-senadores-corrupcion-trax\/"},"modified":"2026-02-09T17:03:52","modified_gmt":"2026-02-10T01:03:52","slug":"operaciones-bursatiles-senadores-corrupcion-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/09\/operaciones-bursatiles-senadores-corrupcion-trax\/","title":{"rendered":"Las operaciones burs\u00e1tiles de los senadores coincidieron directamente con su trabajo en las comisiones, seg\u00fan an\u00e1lisis de CNN"},"content":{"rendered":"<p>Al menos 10 senadores informaron compras o ventas de acciones en 2025 que involucraban a empresas en industrias supervisadas por las comisiones en las que sirven. Estas transacciones preocupan a los grupos de vigilancia del Gobierno, ya que una iniciativa bipartidista para prohibir la pr\u00e1ctica se estanc\u00f3 en el Capitolio.<\/p>\n<p>La mayor\u00eda de esos senadores que invirtieron en acciones que se superponen con sus asignaciones en comisiones durante el \u00faltimo a\u00f1o tienen carteras financieras integrales, no todas las cuales plantean posibles problemas de conflicto de intereses, seg\u00fan una base de datos de declaraciones financieras del Congreso compilada por Capitol Trades y revisada por CNN. Pero las m\u00e1s de una docena de operaciones de este peque\u00f1o grupo de senadores bien conectados ofrecen una ventana para entender por qu\u00e9 el fen\u00f3meno de las operaciones burs\u00e1tiles de legisladores ha generado indignaci\u00f3n p\u00fablica y un gran impulso para prohibir la pr\u00e1ctica.<\/p>\n<p>Al revelar operaciones burs\u00e1tiles, los legisladores deben incluir al propietario de las acciones. Entre los senadores que se incluyeron a s\u00ed mismos como propietarios de acciones en industrias que regulan sus comisiones est\u00e1n los republicanos Bill Hagerty, John Kennedy, Ashley Moody, Jerry Moran, Bernie Moreno, Markwayne Mullin y Tommy Tuberville y los dem\u00f3cratas John Hickenlooper, Gary Peters y Sheldon Whitehouse. En la C\u00e1mara de Representantes, los legisladores tienen la opci\u00f3n de no revelar al propietario de las acciones.<\/p>\n<p>\u201cTodo esto es sumamente preocupante\u201d, dijo Dylan Hedtler-Gaudette, vicepresidente interino del Proyecto de Supervisi\u00f3n Gubernamental, un grupo de vigilancia no partidista. \u201cEs un problema bipartidista. Republicanos y dem\u00f3cratas son culpables de esto, bastante parejo en todos los \u00e1mbitos. Hay una podredumbre institucional en el n\u00facleo de esto\u201d.<\/p>\n<p>Las operaciones realizadas por los senadores son legales, y los legisladores que revelaron estas operaciones han negado tener control personal sobre c\u00f3mo se invierten sus carteras de acciones.<\/p>\n<p>Pero las encuestas han encontrado de manera consistente un amplio apoyo para prohibir que los miembros del Congreso posean acciones. El tema ha recibido atenci\u00f3n nacional \u2014y ha alarmado a expertos en \u00e9tica no partidistas\u2014 gracias a <a href=\"https:\/\/www.cnn.com\/2020\/05\/26\/politics\/doj-closes-investigation-senate-stocks-coronavirus\">ventas sospechosamente oportunas<\/a> al inicio de la pandemia de covid-19, y por operaciones activas de miembros de alto perfil como la expresidenta de la C\u00e1mara de Representantes, Nancy Pelosi. Y a lo largo de los a\u00f1os, <a href=\"https:\/\/www.nytimes.com\/interactive\/2022\/09\/13\/us\/politics\/congress-members-stock-trading-list.html\">docenas<\/a> de legisladores han revelado operaciones burs\u00e1tiles en empresas que son influenciadas por su trabajo en comisiones.<\/p>\n<p>Al menos un dem\u00f3crata y un republicano que han apoyado prohibiciones a las operaciones burs\u00e1tiles del Congreso est\u00e1n entre los senadores que revelaron operaciones en los \u00faltimos meses que involucran empresas relacionadas con su trabajo en las comisiones.<\/p>\n<p>Ese republicano, la senadora Moody, <a href=\"https:\/\/www.moody.senate.gov\/press-releases\/news-release-senators-moody-gillibrand-lead-bipartisan-bill-to-ban-stock-trading-by-members-of-congress\/\">present\u00f3<\/a> en las \u00faltimas semanas un proyecto de ley bipartidista para prohibir las operaciones burs\u00e1tiles de los legisladores.<\/p>\n<p>Sin embargo, la republicana de Florida, que forma parte de la comisi\u00f3n de salud del Senado, invirti\u00f3 en cinco empresas de atenci\u00f3n m\u00e9dica, seg\u00fan <a href=\"https:\/\/efdsearch.senate.gov\/search\/home\/\">los registros federales<\/a>. Eso incluye la compra de entre US$ 100.000 y US$ 250.000 en el gigante farmac\u00e9utico Eli Lilly el pasado marzo.<\/p>\n<p>Eli Lilly gast\u00f3 millones de d\u00f3lares <a href=\"https:\/\/lda.senate.gov\/filings\/public\/filing\/7efc13b2-dca2-4676-975a-bfeb0075f1b2\/print\/\">en cabildeo<\/a> ante el Congreso en 2025. El presidente republicano del panel public\u00f3 <a href=\"https:\/\/chrome-extension:\/\/efaidnbmnnnibpcajpcglclefindmkaj\/https:\/\/www.help.senate.gov\/imo\/media\/doc\/final_340b_majority_staff_reportpdf.pdf\">un informe<\/a> sobre la fijaci\u00f3n de precios de medicamentos federales que se bas\u00f3 en el testimonio de Eli Lilly, y los dem\u00f3cratas del Senado <a href=\"https:\/\/www.durbin.senate.gov\/newsroom\/press-releases\/durbin-warren-welch-sanders-demand-answers-from-telehealth-companies-regarding-their-financial-relationship-with-pfizer-eli-lilly-amid-concerns-of-inappropriate-prescribing\">est\u00e1n examinando<\/a> la relaci\u00f3n de la compa\u00f1\u00eda con empresas de telemedicina.<\/p>\n<p>La oficina de Moody dijo en un comunicado a CNN que la republicana de Florida nunca ha aprobado ni comenzado una operaci\u00f3n burs\u00e1til.<\/p>\n<p>\u201cCuando fue nombrada al Senado a finales de enero de 2025, formaba parte de una sociedad de inversi\u00f3n familiar ampliada donde un socio tomaba decisiones de inversi\u00f3n de manera independiente en consulta con un asesor financiero externo, y sin ninguna aportaci\u00f3n de la senadora\u201d, dijo su oficina en el comunicado.<\/p>\n<p>Desde entonces, la oficina de Moody dice que la senadora \u201cinmediatamente\u201d tom\u00f3 medidas para retirarse de la sociedad y no ha realizado operaciones burs\u00e1tiles desde abril de 2025. \u201cComo muestra de este compromiso, la senadora Moody present\u00f3 una legislaci\u00f3n para restaurar la confianza en el Congreso y garantizar que no haya apariencia de algo no apropiado en lo que respecta a que los miembros realicen operaciones con acciones individuales\u201d, dice el comunicado. Hickenlooper, un dem\u00f3crata, tambi\u00e9n invirti\u00f3 en una empresa que se superpone con sus asignaciones en comisiones, a pesar de haberse convertido recientemente en copatrocinador de una legislaci\u00f3n que impondr\u00eda restricciones a la actividad de compraventa de acciones por parte de legisladores.<\/p>\n<p>En septiembre de 2025, Hickenlooper<a href=\"https:\/\/efdsearch.senate.gov\/search\/home\/\"> invirti\u00f3<\/a> entre US$ 100.000 y US$ 250.000 en una empresa de ciberseguridad llamada Palo Alto Networks mientras formaba parte de la Comisi\u00f3n de Comercio del Senado, seg\u00fan muestran los registros.<\/p>\n<p>La Administraci\u00f3n de Servicios Generales <a href=\"https:\/\/www.gsa.gov\/about-us\/newsroom\/news-releases\/gsa-fortifies-federal-cybersecurity-with-palo-alto-networks-onegov-12042025?utm_source=copilot.com\">anunci\u00f3<\/a> una nueva asociaci\u00f3n en diciembre que permite a las agencias federales comprar productos de Palo Alto Networks con descuentos de hasta el 60 %. Expertos dijeron a CNN que esto levant\u00f3 se\u00f1ales de alarma porque los contratos podr\u00edan beneficiar a Hickenlooper, cuya comisi\u00f3n supervisa los contratos federales.<\/p>\n<p>En respuesta, un portavoz de Hickenlooper dijo a CNN que el senador \u201cno realiza operaciones burs\u00e1tiles personalmente. Sus acciones ya est\u00e1n en un fideicomiso ciego y lo han estado desde que fue alcalde de Denver en 2003. Todas las decisiones las toma un administrador sin conocimiento previo ni participaci\u00f3n del senador\u201d. El portavoz tambi\u00e9n se\u00f1al\u00f3 que Hickenlooper es copatrocinador de una legislaci\u00f3n que obligar\u00eda a todos los miembros del Congreso a colocar sus acciones en un fideicomiso ciego calificado para que no puedan usar informaci\u00f3n privilegiada para tomar decisiones sobre su portafolio y obtener ganancias.<\/p>\n<p>Mullin, un republicano que tambi\u00e9n forma parte del panel de salud del Senado, <a href=\"https:\/\/efdsearch.senate.gov\/search\/home\/\">vendi\u00f3 <\/a>acciones en enero de 2025 a trav\u00e9s de una cuenta conjunta con su esposa en Abbott Laboratories, una empresa de dispositivos m\u00e9dicos y atenci\u00f3n m\u00e9dica. Abbott <a href=\"https:\/\/chrome-extension:\/\/efaidnbmnnnibpcajpcglclefindmkaj\/https:\/\/www.abbott.com\/content\/dam\/corp\/abbott\/en-us\/documents\/pdfs\/investors\/Q4-2024-LD2-Lobbying-Disclosure-Amendment-Signed-Submitted.pdf\">incluy\u00f3 al Senado<\/a> como parte de sus gestiones de cabildeo un mes antes de la transacci\u00f3n de Mullin.<\/p>\n<p>En ese momento, Abbott estaba en medio de una serie de demandas de varios a\u00f1os por <a href=\"https:\/\/www.cnn.com\/2022\/03\/23\/health\/abbott-baby-formula-fda-inspection-results\">f\u00f3rmula infantil contaminada<\/a>, incluyendo un caso que result\u00f3 en una indemnizaci\u00f3n por da\u00f1os de US$ 495 millones.<\/p>\n<p>Pero la oficina de Mullin sostiene que el senador no realiza las transacciones directamente. \u201cEl senador Mullin utiliza una firma operadora independiente y de terceros que gestiona todas las inversiones de su portafolio de acciones en su nombre\u201d, dijo un portavoz. \u201c\u00c9l no realiza ni informa las transacciones. Esta firma independiente reporta cada dos semanas a la Comisi\u00f3n de \u00c9tica del Senado para garantizar el cumplimiento de la ley federal\u201d.<\/p>\n<p>Y Whitehouse, dem\u00f3crata que forma parte de la Comisi\u00f3n de Finanzas del Senado, <a href=\"https:\/\/efdsearch.senate.gov\/search\/home\/\">declar\u00f3<\/a> entre US$ 1.000 y US$ 15.000 en acciones de UnitedHealth Company en noviembre de 2025 en una cuenta de su propiedad.<\/p>\n<p>Aun as\u00ed, una portavoz de Whitehouse, Meaghan McCabe, distanci\u00f3 al dem\u00f3crata de Rhode Island de la transacci\u00f3n. \u201cEl senador no realiza operaciones burs\u00e1tiles, y el administrador de su cuenta est\u00e1 contractualmente obligado a actuar de manera independiente sin ninguna participaci\u00f3n del senador. \u00c9l apoya una prohibici\u00f3n para que los miembros realicen operaciones burs\u00e1tiles y est\u00e1 revisando las distintas propuestas\u201d, dijo la portavoz Meaghan McCabe a CNN.<\/p>\n<p>Los registros muestran que Moran compr\u00f3 acciones en Alphabet Inc, la empresa matriz de Google, <a href=\"https:\/\/www.commerce.senate.gov\/2025\/5\/winning-the-ai-race-strengthening-u-s-capabilities-in-computing-and-innovation_2\">el mismo d\u00eda<\/a> que particip\u00f3 en la audiencia de la Comisi\u00f3n de Comercio del Senado para discutir el futuro de la inteligencia artificial.<\/p>\n<p>Ejecutivos de grandes empresas tecnol\u00f3gicas como OpenAI y Microsoft testificaron como testigos en la audiencia, aunque no hubo nadie de Alphabet o Google.<\/p>\n<p>Cuando el republicano compr\u00f3 las acciones en mayo, el Senado estaba considerando activamente la desregulaci\u00f3n de la IA, lo que beneficiar\u00eda a empresas como Alphabet. Tras una gran reacci\u00f3n p\u00fablica, la disposici\u00f3n que creaba una moratoria sobre regulaciones de IA <a href=\"https:\/\/www.cnn.com\/2025\/07\/18\/politics\/business-lobbyists-trump-agenda-bill#:~:text=Nixed%20AI%20regulation%20moratorium\">fue eliminada<\/a> de la versi\u00f3n final del llamado \u201cgran, hermoso proyecto de ley\u201d de Trump.<\/p>\n<p>\u201cLas inversiones financieras del senador Moran son gestionadas de manera independiente por un corredor, quien tiene plena discreci\u00f3n sobre las cuentas de inversi\u00f3n del senador Moran\u201d, dijo un portavoz de Moran a CNN.<\/p>\n<p>CNN se ha puesto en contacto con Hagerty, Kennedy, Moreno, Peters y Tuberville para obtener comentarios.<\/p>\n<p>Expertos en la compraventa de acciones en el Congreso dijeron a CNN que no est\u00e1n satisfechos con las explicaciones de los senadores.<\/p>\n<p>Emma Lydon, directora general del grupo de cabildeo progresista P Street, dijo que \u201csimplemente la percepci\u00f3n\u201d de un posible uso de informaci\u00f3n privilegiada \u201cerosiona la confianza en nuestra democracia\u201d. Se\u00f1al\u00f3 que <a href=\"https:\/\/unusualwhales.com\/congress-trading-report-2024\">varios estudios<\/a> han <a href=\"https:\/\/unusualwhales.com\/politics\/article\/congress-trading-report-2023#pelosi-trading-again\">encontrado<\/a> que, en promedio, los legisladores que comercian acciones suelen superar el rendimiento del S&#038;P. \u201cCuando se descubre que realizan transacciones burs\u00e1tiles que levantan sospechas, los miembros del Congreso suelen alegar ignorancia, diciendo que las operaciones fueron realizadas sin su conocimiento por corredores financieros independientes\u201d, dijo Lydon. \u201cDesafortunadamente para el pueblo estadounidense, es imposible saber si est\u00e1n diciendo la verdad\u201d.<\/p>\n<p>Kedric Payne, quien dirige el programa de \u00e9tica en el Campaign Legal Center, un grupo de defensa progresista, dijo que las preocupaciones sobre conflictos de inter\u00e9s persisten debido a la opacidad del sistema actual, donde los legisladores pueden legalmente negociar acciones de empresas mientras deciden c\u00f3mo se regulan esas industrias.<\/p>\n<p>\u201cEl p\u00fablico siempre cuestionar\u00e1 si alguna decisi\u00f3n tomada por ese miembro en esa comisi\u00f3n realmente se enfoc\u00f3 en lo que es mejor para los electores, o en lo que es mejor para su propio beneficio financiero personal\u201d, dijo Payne.<\/p>\n<p>Payne, quien trabaj\u00f3 en la Oficina de \u00c9tica del Congreso cuando<a href=\"https:\/\/www.cnn.com\/2012\/04\/04\/politics\/stock-act-signing\"> se aprob\u00f3 la ley<\/a> de divulgaci\u00f3n de transacciones burs\u00e1tiles en 2012, agreg\u00f3 que, \u201ces casi imposible probar que utilizan informaci\u00f3n privilegiada, pero transacciones como estas parecen un conflicto de inter\u00e9s, y por lo tanto el da\u00f1o al inter\u00e9s p\u00fablico permanece\u201d.<\/p>\n<p>Mientras que algunos proyectos de ley est\u00e1n activos en el Senado, un compromiso negociado en la C\u00e1mara para <a href=\"https:\/\/www.cnn.com\/2025\/09\/03\/politics\/stock-trade-ban-congress\">prohibir futuras transacciones burs\u00e1tiles<\/a> por parte de los miembros del Congreso y obligarlos a deshacerse de todas sus participaciones existentes parec\u00eda haber cobrado m\u00e1s fuerza entre las propuestas en el Capitolio el a\u00f1o pasado.<\/p>\n<p>En un momento, un peque\u00f1o grupo de republicanos de la C\u00e1mara intentaba eludir el liderazgo de su partido para llevar ese proyecto de ley bipartidista al pleno. Pero esa maniobra a\u00fan <a href=\"https:\/\/clerk.house.gov\/DischargePetition\/2025120211?Page=2\">est\u00e1 lejos<\/a> de conseguir las firmas necesarias, y l\u00edderes de ambos partidos han tomado medidas recientemente para socavar esa propuesta bipartidista, seg\u00fan los involucrados.<\/p>\n<p>Ese proyecto de ley, la Ley para Restaurar la Confianza en el Congreso, fue \u201cel producto de arduas negociaciones\u201d, dijo Hedtler-Gaudette. Sus 127 copatrocinadores incluyen a republicanos conservadores como el representante Chip Roy y la representante Nancy Mace, y a dem\u00f3cratas progresistas como la representante Alexandria Ocasio-Cortez y la representante Ilhan Omar.<\/p>\n<p>En diciembre, el l\u00edder de la minor\u00eda dem\u00f3crata en la C\u00e1mara, Hakeem Jeffries, present\u00f3 una propuesta separada de prohibici\u00f3n de transacciones burs\u00e1tiles en el Congreso que tambi\u00e9n se aplicar\u00eda a Trump y al vicepresidente J. D. Vance, algo inaceptable para la mayor\u00eda de los legisladores republicanos. Este movimiento<a href=\"https:\/\/prospect.org\/2025\/12\/19\/jeffries-undercuts-congressional-stock-trading-ban\/\"> alarm\u00f3<\/a> a expertos en \u00e9tica y activistas liberales que apoyaban esa pol\u00edtica en principio, pero vieron el nuevo proyecto como un intento de hundir el proyecto bipartidista m\u00e1s viable.<\/p>\n<p>\u201cEl proyecto de Jeffries fue un problema porque se interpuso en el camino del proyecto de consenso bipartidista que realmente resolver\u00eda el problema\u201d, dijo Payne. \u201cAs\u00ed que, de la nada, surgi\u00f3 este obst\u00e1culo, que no era necesario, proveniente de Jeffries\u201d.<\/p>\n<p>El presidente de la C\u00e1mara, Mike Johnson, quien ha sido presionado por sus compa\u00f1eros republicanos para permitir una votaci\u00f3n sobre el proyecto bipartidista, hizo su jugada el mes pasado. Respald\u00f3 una propuesta republicana suavizada que permitir\u00eda a los miembros conservar sus actuales carteras de acciones, pero requerir\u00eda un aviso de siete d\u00edas antes de una venta y evitar\u00eda que los legisladores y sus familias realicen nuevas compras. Dem\u00f3cratas y algunos expertos en \u00e9tica no partidistas dicen que eso podr\u00eda empeorar el problema.<\/p>\n<p>\u201cTiene tantos vac\u00edos legales que es un tigre de papel\u201d, dijo Hedtler-Gaudette. \u201cAhora pueden unirse en torno a esto y afirmar que hicieron algo. Pero es una gran nada, en t\u00e9rminos de resolver el problema\u201d.<\/p>\n<p>La Comisi\u00f3n de Administraci\u00f3n de la C\u00e1mara avanz\u00f3 ese proyecto de ley a principios de este mes solo con apoyo republicano, preparando el escenario para una probable votaci\u00f3n en el pleno.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al menos 10 senadores informaron compras o ventas de acciones en 2025 que involucraban a empresas en industrias supervisadas por las comisiones en las que sirven. Estas transacciones preocupan a los grupos de vigilancia del Gobierno, ya que una iniciativa bipartidista para prohibir la pr\u00e1ctica se estanc\u00f3 en el Capitolio. La mayor\u00eda de esos senadores [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1471047","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las operaciones burs\u00e1tiles de los senadores coincidieron directamente con su trabajo en las comisiones, seg\u00fan an\u00e1lisis de CNN - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/09\/operaciones-bursatiles-senadores-corrupcion-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las operaciones burs\u00e1tiles de los senadores coincidieron directamente con su trabajo en las comisiones, seg\u00fan an\u00e1lisis de CNN - Noticias\" \/>\n<meta property=\"og:description\" content=\"Al menos 10 senadores informaron compras o ventas de acciones en 2025 que involucraban a empresas en industrias supervisadas por las comisiones en las que sirven. Estas transacciones preocupan a los grupos de vigilancia del Gobierno, ya que una iniciativa bipartidista para prohibir la pr\u00e1ctica se estanc\u00f3 en el Capitolio. La mayor\u00eda de esos senadores [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/09\/operaciones-bursatiles-senadores-corrupcion-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-10T01:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/09\/operaciones-bursatiles-senadores-corrupcion-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/09\/operaciones-bursatiles-senadores-corrupcion-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Las operaciones burs\u00e1tiles de los senadores coincidieron directamente con su trabajo en las comisiones, seg\u00fan an\u00e1lisis de CNN\",\"datePublished\":\"2026-02-10T01:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/09\/operaciones-bursatiles-senadores-corrupcion-trax\/\"},\"wordCount\":2199,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/09\/operaciones-bursatiles-senadores-corrupcion-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/09\/operaciones-bursatiles-senadores-corrupcion-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/09\/operaciones-bursatiles-senadores-corrupcion-trax\/\",\"name\":\"Las operaciones burs\u00e1tiles de los senadores coincidieron directamente con su trabajo en las comisiones, seg\u00fan an\u00e1lisis de CNN - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-10T01:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/09\/operaciones-bursatiles-senadores-corrupcion-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/09\/operaciones-bursatiles-senadores-corrupcion-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/09\/operaciones-bursatiles-senadores-corrupcion-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las operaciones burs\u00e1tiles de los senadores coincidieron directamente con su trabajo en las comisiones, seg\u00fan an\u00e1lisis de CNN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las operaciones burs\u00e1tiles de los senadores coincidieron directamente con su trabajo en las comisiones, seg\u00fan an\u00e1lisis de CNN - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/09\/operaciones-bursatiles-senadores-corrupcion-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Las operaciones burs\u00e1tiles de los senadores coincidieron directamente con su trabajo en las comisiones, seg\u00fan an\u00e1lisis de CNN - Noticias","og_description":"Al menos 10 senadores informaron compras o ventas de acciones en 2025 que involucraban a empresas en industrias supervisadas por las comisiones en las que sirven. Estas transacciones preocupan a los grupos de vigilancia del Gobierno, ya que una iniciativa bipartidista para prohibir la pr\u00e1ctica se estanc\u00f3 en el Capitolio. La mayor\u00eda de esos senadores [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/09\/operaciones-bursatiles-senadores-corrupcion-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-10T01:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/09\/operaciones-bursatiles-senadores-corrupcion-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/09\/operaciones-bursatiles-senadores-corrupcion-trax\/"},"author":{"name":"","@id":""},"headline":"Las operaciones burs\u00e1tiles de los senadores coincidieron directamente con su trabajo en las comisiones, seg\u00fan an\u00e1lisis de CNN","datePublished":"2026-02-10T01:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/09\/operaciones-bursatiles-senadores-corrupcion-trax\/"},"wordCount":2199,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/09\/operaciones-bursatiles-senadores-corrupcion-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/09\/operaciones-bursatiles-senadores-corrupcion-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/09\/operaciones-bursatiles-senadores-corrupcion-trax\/","name":"Las operaciones burs\u00e1tiles de los senadores coincidieron directamente con su trabajo en las comisiones, seg\u00fan an\u00e1lisis de CNN - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-10T01:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/09\/operaciones-bursatiles-senadores-corrupcion-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/09\/operaciones-bursatiles-senadores-corrupcion-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/09\/operaciones-bursatiles-senadores-corrupcion-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Las operaciones burs\u00e1tiles de los senadores coincidieron directamente con su trabajo en las comisiones, seg\u00fan an\u00e1lisis de CNN"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/09\/operaciones-bursatiles-senadores-corrupcion-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Las operaciones burs\u00e1tiles de los senadores coincidieron directamente con su trabajo en las comisiones, seg\u00fan an\u00e1lisis de CNN","url":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/09\/operaciones-bursatiles-senadores-corrupcion-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/09\/operaciones-bursatiles-senadores-corrupcion-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-10T01:03:52Z","datePublished":"2026-02-10T01:03:52Z","dateModified":"2026-02-10T01:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Las operaciones burs\\u00e1tiles de los senadores coincidieron directamente con su trabajo en las comisiones, seg\\u00fan an\\u00e1lisis de CNN\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/09\\\/operaciones-bursatiles-senadores-corrupcion-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/09\\\/operaciones-bursatiles-senadores-corrupcion-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-10T01:03:52Z\",\"datePublished\":\"2026-02-10T01:03:52Z\",\"dateModified\":\"2026-02-10T01:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1458109,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/02\/01\/trump-despide-director-proteccion-financiera-consumidor-trax\/","url_meta":{"origin":1471047,"position":0},"title":"Trump despide al director de la Oficina de Protecci\u00f3n Financiera del Consumidor","author":"","date":"febrero 1, 2025","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, despidi\u00f3 a Rohit Chopra, el director de la Oficina de Protecci\u00f3n Financiera del Consumidor (CFPB, por sus siglas en ingl\u00e9s).Chopra recibi\u00f3 un correo electr\u00f3nico de la Casa Blanca el s\u00e1bado por la ma\u00f1ana en el que se le informaba del despido, seg\u00fan dijo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467781,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/27\/gobierno-trump-informes-clasificados-congreso-ataques-caribe-trax\/","url_meta":{"origin":1471047,"position":1},"title":"El Gobierno de Trump dice que entreg\u00f3 al Congreso 7 informes clasificados sobre ataques contra embarcaciones en el Caribe","author":"","date":"octubre 27, 2025","format":false,"excerpt":"El Gobierno de Trump indic\u00f3 este lunes que proporcion\u00f3 siete sesiones informativas clasificadas separadas sobre ataques militares estadounidenses contra supuestas embarcaciones de drogas, incluso cuando legisladores han dicho a CNN que no han recibido informaci\u00f3n.\u201cEl Gobierno proporcion\u00f3 al Congreso siete sesiones informativas clasificadas separadas desde principios de septiembre, reportando a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445836,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/02\/21\/capital-one-compra-discover-millones-operacion-2024-trax\/","url_meta":{"origin":1471047,"position":2},"title":"Capital One compra Discover por US$ 35.000 millones en la mayor operaci\u00f3n en lo que va de 2024","author":"","date":"febrero 21, 2024","format":false,"excerpt":"Nueva York (CNN) -- Capital One adquiri\u00f3 Discover Financial Services por US$ 35.300 millones en una operaci\u00f3n completamente en acciones, lo que dar\u00e1 al banco una ventaja en el competitivo mercado de las tarjetas de cr\u00e9dito.Seg\u00fan los t\u00e9rminos del acuerdo anunciado la noche de este lunes, los accionistas de Discover\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473807,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/05\/05\/ice-senado-trump-salon-baile-trax\/","url_meta":{"origin":1471047,"position":3},"title":"Republicanos del Senado contemplan destinar US$ 1.000 millones para la seguridad del sal\u00f3n de baile de Trump","author":"","date":"mayo 5, 2026","format":false,"excerpt":"Los republicanos del Senado buscan otorgar al Servicio Secreto de EE.UU. US$ 1.000 millones para reforzar la seguridad del futuro sal\u00f3n de baile de la Casa Blanca del presidente Donald Trump, como parte de un paquete m\u00e1s amplio de aplicaci\u00f3n de leyes migratorias.Dos comisiones del Senado lideradas por republicanos presentaron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470373,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/01\/22\/democratas-exigen-saber-beneficios-trump-petroleo-venezuela-trax\/","url_meta":{"origin":1471047,"position":4},"title":"Dem\u00f3cratas exigen saber si el c\u00edrculo \u00edntimo de Trump se beneficiar\u00e1 de las ventas de petr\u00f3leo venezolano","author":"","date":"enero 22, 2026","format":false,"excerpt":"Un grupo de senadores dem\u00f3cratas exige saber si el c\u00edrculo \u00edntimo del presidente Donald Trump se beneficiar\u00e1 de las ventas de petr\u00f3leo venezolano, luego de que CNN informara recientemente detalles de las conversaciones privadas del Gobierno con las mayores compa\u00f1\u00edas petroleras del pa\u00eds.En una carta enviada el mi\u00e9rcoles por la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445771,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/02\/21\/capital-one-compra-discover-por-us-35-000-millones-en-la-mayor-operacion-en-lo-que-va-de-2024\/","url_meta":{"origin":1471047,"position":5},"title":"Capital One compra Discover por US$ 35.000 millones en la mayor operaci\u00f3n en lo que va de 2024","author":"","date":"febrero 21, 2024","format":false,"excerpt":"Nueva York (CNN) -- Capital One adquiri\u00f3 Discover Financial Services por US$ 35.300 millones en una operaci\u00f3n completamente en acciones, lo que dar\u00e1 al banco una ventaja en el competitivo mercado de las tarjetas de cr\u00e9dito.Seg\u00fan los t\u00e9rminos del acuerdo anunciado la noche de este lunes, los accionistas de Discover\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1471047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1471047"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1471047\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1471047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1471047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1471047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}