{"id":1471118,"date":"2026-02-11T12:03:49","date_gmt":"2026-02-11T20:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/11\/muere-james-van-der-beek-dawsons-creek-trax\/"},"modified":"2026-02-11T12:03:49","modified_gmt":"2026-02-11T20:03:49","slug":"muere-james-van-der-beek-dawsons-creek-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/11\/muere-james-van-der-beek-dawsons-creek-trax\/","title":{"rendered":"Muere el actor James Van Der Beek, protagonista de &#171;Dawson&#8217;s Creek&#187;"},"content":{"rendered":"<p>James Van Der Beek, quien salt\u00f3 a la fama interpretando a Dawson Leery en el exitoso drama adolescente de los a\u00f1os 90 \u201cDawson\u2019s Creek\u201d, ha muerto.<\/p>\n<p>Seg\u00fan informes, ten\u00eda 48 a\u00f1os.<\/p>\n<p>La noticia fue confirmada a trav\u00e9s del Instagram verificado del actor el mi\u00e9rcoles, donde se public\u00f3: \u201cNuestro amado James David Van Der Beek falleci\u00f3 pac\u00edficamente esta ma\u00f1ana. Enfrent\u00f3 sus \u00faltimos d\u00edas con valent\u00eda, fe y gracia. Hay mucho que compartir sobre sus deseos, amor por la humanidad y la sacralidad del tiempo. Esos d\u00edas llegar\u00e1n. Por ahora pedimos privacidad y tranquilidad mientras lamentamos la p\u00e9rdida de nuestro amado esposo, padre, hijo, hermano y amigo\u201d.<\/p>\n<p>Su representante Stuart Manashil escribi\u00f3 a CNN en un correo electr\u00f3nico solicitando privacidad para la familia.<\/p>\n<p>Van Der Beek anunci\u00f3 en noviembre de 2024 que viv\u00eda con c\u00e1ncer colorrectal en etapa 3.<\/p>\n<p><em>Esta es una noticia en desarrollo.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>James Van Der Beek, quien salt\u00f3 a la fama interpretando a Dawson Leery en el exitoso drama adolescente de los a\u00f1os 90 \u201cDawson\u2019s Creek\u201d, ha muerto. Seg\u00fan informes, ten\u00eda 48 a\u00f1os. La noticia fue confirmada a trav\u00e9s del Instagram verificado del actor el mi\u00e9rcoles, donde se public\u00f3: \u201cNuestro amado James David Van Der Beek falleci\u00f3 [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1471118","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Muere el actor James Van Der Beek, protagonista de &quot;Dawson&#039;s Creek&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/11\/muere-james-van-der-beek-dawsons-creek-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Muere el actor James Van Der Beek, protagonista de &quot;Dawson&#039;s Creek&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"James Van Der Beek, quien salt\u00f3 a la fama interpretando a Dawson Leery en el exitoso drama adolescente de los a\u00f1os 90 \u201cDawson\u2019s Creek\u201d, ha muerto. Seg\u00fan informes, ten\u00eda 48 a\u00f1os. La noticia fue confirmada a trav\u00e9s del Instagram verificado del actor el mi\u00e9rcoles, donde se public\u00f3: \u201cNuestro amado James David Van Der Beek falleci\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/11\/muere-james-van-der-beek-dawsons-creek-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-11T20:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/11\/muere-james-van-der-beek-dawsons-creek-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/11\/muere-james-van-der-beek-dawsons-creek-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Muere el actor James Van Der Beek, protagonista de &#171;Dawson&#8217;s Creek&#187;\",\"datePublished\":\"2026-02-11T20:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/11\/muere-james-van-der-beek-dawsons-creek-trax\/\"},\"wordCount\":184,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/11\/muere-james-van-der-beek-dawsons-creek-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/11\/muere-james-van-der-beek-dawsons-creek-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/11\/muere-james-van-der-beek-dawsons-creek-trax\/\",\"name\":\"Muere el actor James Van Der Beek, protagonista de \\\"Dawson's Creek\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-11T20:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/11\/muere-james-van-der-beek-dawsons-creek-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/11\/muere-james-van-der-beek-dawsons-creek-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/11\/muere-james-van-der-beek-dawsons-creek-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Muere el actor James Van Der Beek, protagonista de &#171;Dawson&#8217;s Creek&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Muere el actor James Van Der Beek, protagonista de \"Dawson's Creek\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/11\/muere-james-van-der-beek-dawsons-creek-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Muere el actor James Van Der Beek, protagonista de \"Dawson's Creek\" - Noticias","og_description":"James Van Der Beek, quien salt\u00f3 a la fama interpretando a Dawson Leery en el exitoso drama adolescente de los a\u00f1os 90 \u201cDawson\u2019s Creek\u201d, ha muerto. Seg\u00fan informes, ten\u00eda 48 a\u00f1os. La noticia fue confirmada a trav\u00e9s del Instagram verificado del actor el mi\u00e9rcoles, donde se public\u00f3: \u201cNuestro amado James David Van Der Beek falleci\u00f3 [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/11\/muere-james-van-der-beek-dawsons-creek-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-11T20:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/11\/muere-james-van-der-beek-dawsons-creek-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/11\/muere-james-van-der-beek-dawsons-creek-trax\/"},"author":{"name":"","@id":""},"headline":"Muere el actor James Van Der Beek, protagonista de &#171;Dawson&#8217;s Creek&#187;","datePublished":"2026-02-11T20:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/11\/muere-james-van-der-beek-dawsons-creek-trax\/"},"wordCount":184,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/11\/muere-james-van-der-beek-dawsons-creek-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/11\/muere-james-van-der-beek-dawsons-creek-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/11\/muere-james-van-der-beek-dawsons-creek-trax\/","name":"Muere el actor James Van Der Beek, protagonista de \"Dawson's Creek\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-11T20:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/11\/muere-james-van-der-beek-dawsons-creek-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/11\/muere-james-van-der-beek-dawsons-creek-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/11\/muere-james-van-der-beek-dawsons-creek-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Muere el actor James Van Der Beek, protagonista de &#171;Dawson&#8217;s Creek&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/11\/muere-james-van-der-beek-dawsons-creek-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Muere el actor James Van Der Beek, protagonista de &#171;Dawson&#8217;s Creek&#187;","url":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/11\/muere-james-van-der-beek-dawsons-creek-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/11\/muere-james-van-der-beek-dawsons-creek-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-11T20:03:49Z","datePublished":"2026-02-11T20:03:49Z","dateModified":"2026-02-11T20:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Muere el actor James Van Der Beek, protagonista de &#171;Dawson&#8217;s Creek&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/11\\\/muere-james-van-der-beek-dawsons-creek-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/11\\\/muere-james-van-der-beek-dawsons-creek-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-11T20:03:49Z\",\"datePublished\":\"2026-02-11T20:03:49Z\",\"dateModified\":\"2026-02-11T20:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1465721,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/08\/21\/katie-holmes-james-van-der-beek-reunion-dawsons-creek-trax\/","url_meta":{"origin":1471118,"position":0},"title":"Katie Holmes, James Van Der Beek y el elenco de &#171;Dawson\u2019s Creek&#187; se reunir\u00e1n para una lectura de guion ben\u00e9fica","author":"","date":"agosto 21, 2025","format":false,"excerpt":"No quer\u00edas esperar, y ahora ya no tendr\u00e1s que hacerlo.El elenco de \u201cDawson\u2019s Creek\u201d \u2013James Van Der Beek, Katie Holmes, Michelle Williams y Joshua Jackson\u2013 se reunir\u00e1 para una lectura en vivo del guion del episodio piloto el pr\u00f3ximo mes en Broadway, en la ciudad de Nueva York, en apoyo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471157,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/12\/gofundme-james-van-der-beek-millon-orix\/","url_meta":{"origin":1471118,"position":1},"title":"Tras la muerte de James Van Der Beek, la campa\u00f1a de GoFundMe para su familia ya  supera US$ 1,4 millones","author":"","date":"febrero 12, 2026","format":false,"excerpt":"Las amistades del actor James Van Der Beek, fallecido el mi\u00e9rcoles a los 48 a\u00f1os de un c\u00e1ncer colorrectal en etapa 3, crearon una campa\u00f1a de GoFundMe para recaudar dinero para la familia. Seg\u00fan el sitio web de la campa\u00f1a, en las 24 horas transcurridas desde la muerte del actor,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466777,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/09\/24\/james-van-der-beek-virtual-reunion-dawsons-creek-trax\/","url_meta":{"origin":1471118,"position":2},"title":"James Van Der Beek hace una aparici\u00f3n virtual en la reuni\u00f3n de &#171;Dawson\u2019s Creek&#187;","author":"","date":"septiembre 24, 2025","format":false,"excerpt":"James Van Der Beek no pudo presentarse en persona el lunes para la lectura del episodio piloto de \u201cDawson\u2019s Creek\u201d en el teatro Richard Rodgers de Nueva York, pero aun as\u00ed sorprendi\u00f3 al p\u00fablico con una aparici\u00f3n virtual.El evento fue una recaudaci\u00f3n de fondos para la organizaci\u00f3n sin fines de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471138,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/12\/5-cosas-12-de-febrero-orix\/","url_meta":{"origin":1471118,"position":3},"title":"Las 5 cosas que debes saber este 12 de febrero","author":"","date":"febrero 12, 2026","format":false,"excerpt":"El l\u00edo de la presunta incursi\u00f3n de drones mexicanos en EE.UU. Nuevos documentos de Epstein ponen bajo presi\u00f3n al equipo de Trump. Descalifican de los Ol\u00edmpicos de Invierno a atleta ucraniano que quer\u00eda usar casco en honor a compatriotas muertos. Esto es lo que debes saber para comenzar el d\u00eda.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467000,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/09\/30\/hollywood-aparicion-actriz-inteligencia-artificial-trax\/","url_meta":{"origin":1471118,"position":4},"title":"Hollywood est\u00e1 furioso por la aparici\u00f3n de una nueva &#171;actriz de inteligencia artificial&#187;","author":"","date":"septiembre 30, 2025","format":false,"excerpt":"Tras la intensa reacci\u00f3n de los actores humanos ante una \u201cactriz\u201d generada por inteligencia artificial, la creadora del personaje declar\u00f3 que no pretende reemplazar a las personas. Sin embargo, muchos en Hollywood todav\u00eda no lo creen.Esta es la disputa m\u00e1s reciente en la industria cinematogr\u00e1fica, que se gener\u00f3 por una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446080,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/02\/28\/richard-lewis-muerte-comediante-actor-trax\/","url_meta":{"origin":1471118,"position":5},"title":"Muere Richard Lewis, actor recordado por \u201cCurb Your Enthusiasm\u201d, a los 76 a\u00f1os","author":"","date":"febrero 28, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 El comediante y actor Richard Lewis, cuyo humor e ingenio mordaz en programas como \u201cCurb Your Enthusiasm\u201d y \u201cAnything but Love\u201d entretuvieron al p\u00fablico durante d\u00e9cadas, falleci\u00f3, dijo su publicista Jeff Abraham. Ten\u00eda 76 a\u00f1os.Abraham dijo en un correo electr\u00f3nico a CNN que el artista falleci\u00f3 \u201cen paz\u201d\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1471118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1471118"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1471118\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1471118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1471118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1471118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}