{"id":1471121,"date":"2026-02-11T13:03:46","date_gmt":"2026-02-11T21:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/11\/ecuador-fuerzas-armadas-prensa-censura-orix\/"},"modified":"2026-02-11T13:03:46","modified_gmt":"2026-02-11T21:03:46","slug":"ecuador-fuerzas-armadas-prensa-censura-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/11\/ecuador-fuerzas-armadas-prensa-censura-orix\/","title":{"rendered":"Como en EE.UU., las Fuerzas Armadas de Ecuador fijan reglas para la cobertura de prensa. Medios se\u00f1alan censura"},"content":{"rendered":"<p>El Comando Conjunto de las Fuerzas Armadas de Ecuador fij\u00f3 lineamientos para la forma en la que considera deben realizarse las coberturas de prensa sobre la instituci\u00f3n, una acci\u00f3n similar a la que el Departamento de Defensa de Estados Unidos llev\u00f3 a cabo a finales del a\u00f1o pasado y que ha generado molestia entre medios, periodistas y organizaciones civiles ecuatorianas, que acusan un acto de censura por parte de la milicia.<\/p>\n<p>La difusi\u00f3n de los lineamientos se dio a conocer este martes en el noticiero de la cadena Ecuavisa, afiliada de CNN. Durante la emisi\u00f3n, Ecuavisa report\u00f3 la existencia de dos documentos militares con nuevas disposiciones para las coberturas que, dice el medio, podr\u00edan afectar el trabajo period\u00edstico. \u201cDesde este 28 de enero quienes, a su juicio, afecten su imagen p\u00fablica y la confianza ciudadana quedan excluidos de toda cobertura\u201d, <a href=\"https:\/\/x.com\/ecuavisainforma\/status\/2021296123302809691?s=46&#038;t=vWSsaMsKttiCRFRT9JR29g\">se\u00f1al\u00f3<\/a>.<\/p>\n<p>CNN accedi\u00f3 a los documentos citados por Ecuavisa. Uno de ellos se titula \u201cInforme para la coordinaci\u00f3n, acreditaci\u00f3n y gesti\u00f3n estrat\u00e9gica de medios de comunicaci\u00f3n en eventos institucionales de las Fuerzas Armadas\u201d. El otro, \u201cLineamientos para la coordinaci\u00f3n, acreditaci\u00f3n y gesti\u00f3n estrat\u00e9gica de medios de comunicaci\u00f3n en eventos institucionales de las Fuerzas Armadas\u201d.<\/p>\n<p>Entre otras medidas, los documentos establecen que la invitaci\u00f3n y acreditaci\u00f3n de medios de comunicaci\u00f3n para actividades de las Fuerzas Armadas se realizar\u00e1 \u201cexclusivamente bajo criterios t\u00e9cnicos previamente definidos\u201d, que consideren aspectos como l\u00ednea editorial del medio, tratamiento informativo hist\u00f3rico respecto a las Fuerzas Armadas, rigor informativo, conducta profesional y postura frente al rol de las Fuerzas Armadas. Tambi\u00e9n dicen que la acreditaci\u00f3n de medios \u201cno afines\u201d se dar\u00e1 solo de forma excepcional.<\/p>\n<p>Por la noche, el Comando Conjunto de las Fuerzas Armadas confirm\u00f3 la existencia de estos documentos. En <a href=\"https:\/\/x.com\/ffaaecuador\/status\/2021410190621540761?s=46&#038;t=vWSsaMsKttiCRFRT9JR29g\">un comunicado<\/a>, critic\u00f3 \u201cla reciente difusi\u00f3n de documentaci\u00f3n oficial por parte de un medio de comunicaci\u00f3n\u201d y dijo que los lineamientos \u201cno tienen como prop\u00f3sito restringir, limitar ni impedir el ejercicio del trabajo period\u00edstico ni afectar el derecho a la informaci\u00f3n\u201d, sino \u201cordenar, planificar y garantizar que la labor informativa se desarrolle de manera adecuada, oportuna y segura durante los eventos oficiales organizados por las Fuerzas Armadas\u201d.<\/p>\n<p>CNN contact\u00f3 al Ministerio de Defensa y al jefe del Comando Conjunto de las Fuerzas Armadas, Henry Delgado, para pedir comentarios sobre los documentos y los se\u00f1alamientos de censura y est\u00e1 en espera de respuesta.<\/p>\n<p>En un mensaje enviado a periodistas, el Ministerio dijo que las Fuerzas Armadas son una \u201cinstituci\u00f3n apol\u00edtica\u201d y que, en el marco de la declaraci\u00f3n de conflicto interno armado que se mantiene desde enero de 2024 en el pa\u00eds, \u201ctiene la facultad para emitir sus propios lineamientos de comunicaci\u00f3n\u201d. La instituci\u00f3n agreg\u00f3 que ese criterio \u201cno les exime de informar de manera transparente y oportuna las acciones en defensa del pa\u00eds\u201d y dijo estar comprometida con la libertad de prensa.<\/p>\n<p>En sus lineamientos, el Comando Conjunto de las Fuerzas Armadas ordena que \u201cse evite la acreditaci\u00f3n de medios, comunicadores o personal de manera reiterada y debidamente documentada\u201d si, a su criterio, \u201cmantienen una posici\u00f3n contraria, desinformativa o perjudicial para la imagen, visi\u00f3n y valores institucionales\u201d. El documento no especifica cu\u00e1les son los criterios para considerar que un periodista o una informaci\u00f3n tienen esas caracter\u00edsticas.<\/p>\n<p>Por otra parte, solicita que se autorice \u201cde manera excepcional y estrat\u00e9gica\u201d la inclusi\u00f3n selectiva de medios de comunicaci\u00f3n \u201cno afines\u201d, solamente cuando existan eventos considerados por las Fuerzas Armadas \u201cde alto valor simb\u00f3lico, hist\u00f3rico o patri\u00f3tico\u201d y que la participaci\u00f3n de los periodistas de esos medios sea una oportunidad \u201cpara fortalecer la imagen institucional\u201d.<\/p>\n<p>En otra parte de los lineamientos se establecen matrices de calificaci\u00f3n a los medios de comunicaci\u00f3n y periodistas a trav\u00e9s de un \u201cprocedimiento interno de evaluaci\u00f3n y registro\u201d e, incluso, se agregan categor\u00edas de clasificaci\u00f3n que determinan los medios que pueden cubrir actividades de las Fuerzas Armadas. Las calificaciones se establecen de 80 a 100 puntos como \u201cmedio apto o af\u00edn\u201d, de 60 a 79 como \u201cmedio apto condicionado\u201d y menor a 60 como \u201cmedio no apto para acreditaci\u00f3n\u201d.<\/p>\n<p>La cadena Ecuavisa consider\u00f3 que una investigaci\u00f3n suya publicada a inicios de a\u00f1o sobre presuntas irregularidades en la ejecuci\u00f3n de la instalaci\u00f3n de un radar a cargo de Fuerzas Armadas para la lucha contra el crimen organizado <a href=\"https:\/\/www.ecuavisa.com\/amp\/ecuador\/ministerio-defensa-suspendio-contrato-comprar-radar-largo-alcance-manabi-20260112-0063.html\">habr\u00eda empujado la decisi\u00f3n de establecer nuevos lineamientos<\/a> para la cobertura de prensa.<\/p>\n<p>\u201cEstas limitaciones fueron emitidas despu\u00e9s de una serie de reportajes de Televistazo sobre irregularidades en la ejecuci\u00f3n de un millonario contrato de un radar de \u00faltima generaci\u00f3n para la lucha contra el narcotr\u00e1fico que permanece embodegado desde hace seis meses en Espa\u00f1a\u201d, se\u00f1al\u00f3 Ecuavisa.<\/p>\n<p>El ministro de Defensa, Gian Carlo Loffredo, dijo a mediados de enero que la ejecuci\u00f3n del contrato para la instalaci\u00f3n de un nuevo radar no se suspendi\u00f3 sino que \u201cestaba en espera\u201d porque la Fuerza A\u00e9rea hizo un concurso para contratar las obras civiles como carreteras y bases para el asentamiento del radar y que el Cuerpo de Ingenieros del Ej\u00e9rcito, al que se concedi\u00f3 el contrato, se encontr\u00f3 con problemas geol\u00f3gicos y clim\u00e1ticos que impidieron por \u201cfuerza mayor\u201d que las obras de instalaci\u00f3n del nuevo radar empiecen.<\/p>\n<p>\u201cNosotros somos los m\u00e1s interesados en que se concluya esta obra porque toda ayuda que tengamos para el combate al narcotr\u00e1fico es importante\u201d, <a href=\"https:\/\/www.facebook.com\/share\/v\/1CtNBExcdN\/?mibextid=wwXIfr\">dijo Loffredo<\/a>. Cuestion\u00f3 que se intente poner en duda la \u201clucha frontal\u201d contra el narcotr\u00e1fico de las fuerzas militares.<\/p>\n<p>La semana pasada, el periodista de Ecuavisa Pa\u00fal Romero, que ha cubierto por varios a\u00f1os temas de seguridad e investig\u00f3 el caso de la compra de un nuevo radar de vigilancia a\u00e9rea, denunci\u00f3, a trav\u00e9s de la organizaci\u00f3n de defensa de la libertad de expresi\u00f3n <a href=\"https:\/\/fundamedios.org.ec\/alertas\/ministerio-de-defensa-excluye-a-periodista-de-ecuavisa-de-coberturas-oficiales\/\">Fundamedios<\/a>, que estar\u00eda siendo excluido de coberturas por parte del Ministerio de Defensa y que, desde el inicio del gobierno de Daniel Noboa, la instituci\u00f3n dej\u00f3 de responderle a sus requerimientos y solicitudes de informaci\u00f3n.<\/p>\n<p>Este martes, Romero <a href=\"https:\/\/x.com\/mromerorivera\/status\/2021317393457316056?s=46&#038;t=vWSsaMsKttiCRFRT9JR29g\">public\u00f3 en X<\/a> im\u00e1genes de los lineamientos de las Fuerzas Armadas y dijo: \u201cNunca he sido ni ser\u00e9 instrumento de propaganda oficial\u201d.<\/p>\n<p>Los lineamientos del Comando Conjunto de las Fuerzas Armadas de Ecuador tienen parecido con las reglas que el Departamento de Defensa de EE.UU. difundi\u00f3 en 2025 para la cobertura de sus actividades. Entre otras cosas, el Pent\u00e1gono estableci\u00f3 que los periodistas no podr\u00e1n publicar informaci\u00f3n que previamente no haya sido autorizada por la propia instituci\u00f3n, una medida que gener\u00f3 molestia entre reporteros e hizo que algunos entregaran sus acreditaciones.<\/p>\n<p>Sobre las nuevas disposiciones del Comando Conjunto de las Fuerzas Armadas, Fundamedios se pronunci\u00f3 este martes, al calificar el hecho como un \u201cinaceptable estado de censura previa incompatible con una sociedad democr\u00e1tica y violatorio de los principios constitucionales e interamericanos\u201d.<\/p>\n<p>\u201cAlertamos a la sociedad ecuatoriana y a la comunidad internacional: este es un ataque grave, estructural y deliberado contra la libertad de expresi\u00f3n y de prensa en Ecuador\u201d, <a href=\"https:\/\/x.com\/fundamedios\/status\/2021346008933060825?s=46&#038;t=vWSsaMsKttiCRFRT9JR29g\">cuestion\u00f3<\/a> la organizaci\u00f3n no gubernamental.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Comando Conjunto de las Fuerzas Armadas de Ecuador fij\u00f3 lineamientos para la forma en la que considera deben realizarse las coberturas de prensa sobre la instituci\u00f3n, una acci\u00f3n similar a la que el Departamento de Defensa de Estados Unidos llev\u00f3 a cabo a finales del a\u00f1o pasado y que ha generado molestia entre medios, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1471121","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Como en EE.UU., las Fuerzas Armadas de Ecuador fijan reglas para la cobertura de prensa. Medios se\u00f1alan censura - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/11\/ecuador-fuerzas-armadas-prensa-censura-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como en EE.UU., las Fuerzas Armadas de Ecuador fijan reglas para la cobertura de prensa. Medios se\u00f1alan censura - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Comando Conjunto de las Fuerzas Armadas de Ecuador fij\u00f3 lineamientos para la forma en la que considera deben realizarse las coberturas de prensa sobre la instituci\u00f3n, una acci\u00f3n similar a la que el Departamento de Defensa de Estados Unidos llev\u00f3 a cabo a finales del a\u00f1o pasado y que ha generado molestia entre medios, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/11\/ecuador-fuerzas-armadas-prensa-censura-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-11T21:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/11\/ecuador-fuerzas-armadas-prensa-censura-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/11\/ecuador-fuerzas-armadas-prensa-censura-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Como en EE.UU., las Fuerzas Armadas de Ecuador fijan reglas para la cobertura de prensa. Medios se\u00f1alan censura\",\"datePublished\":\"2026-02-11T21:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/11\/ecuador-fuerzas-armadas-prensa-censura-orix\/\"},\"wordCount\":1265,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/11\/ecuador-fuerzas-armadas-prensa-censura-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/11\/ecuador-fuerzas-armadas-prensa-censura-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/11\/ecuador-fuerzas-armadas-prensa-censura-orix\/\",\"name\":\"Como en EE.UU., las Fuerzas Armadas de Ecuador fijan reglas para la cobertura de prensa. Medios se\u00f1alan censura - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-11T21:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/11\/ecuador-fuerzas-armadas-prensa-censura-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/11\/ecuador-fuerzas-armadas-prensa-censura-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/11\/ecuador-fuerzas-armadas-prensa-censura-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como en EE.UU., las Fuerzas Armadas de Ecuador fijan reglas para la cobertura de prensa. Medios se\u00f1alan censura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como en EE.UU., las Fuerzas Armadas de Ecuador fijan reglas para la cobertura de prensa. Medios se\u00f1alan censura - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/11\/ecuador-fuerzas-armadas-prensa-censura-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Como en EE.UU., las Fuerzas Armadas de Ecuador fijan reglas para la cobertura de prensa. Medios se\u00f1alan censura - Noticias","og_description":"El Comando Conjunto de las Fuerzas Armadas de Ecuador fij\u00f3 lineamientos para la forma en la que considera deben realizarse las coberturas de prensa sobre la instituci\u00f3n, una acci\u00f3n similar a la que el Departamento de Defensa de Estados Unidos llev\u00f3 a cabo a finales del a\u00f1o pasado y que ha generado molestia entre medios, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/11\/ecuador-fuerzas-armadas-prensa-censura-orix\/","og_site_name":"Noticias","article_published_time":"2026-02-11T21:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/11\/ecuador-fuerzas-armadas-prensa-censura-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/11\/ecuador-fuerzas-armadas-prensa-censura-orix\/"},"author":{"name":"","@id":""},"headline":"Como en EE.UU., las Fuerzas Armadas de Ecuador fijan reglas para la cobertura de prensa. Medios se\u00f1alan censura","datePublished":"2026-02-11T21:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/11\/ecuador-fuerzas-armadas-prensa-censura-orix\/"},"wordCount":1265,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/11\/ecuador-fuerzas-armadas-prensa-censura-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/11\/ecuador-fuerzas-armadas-prensa-censura-orix\/","url":"https:\/\/noticiasya.com\/2026\/02\/11\/ecuador-fuerzas-armadas-prensa-censura-orix\/","name":"Como en EE.UU., las Fuerzas Armadas de Ecuador fijan reglas para la cobertura de prensa. Medios se\u00f1alan censura - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-11T21:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/11\/ecuador-fuerzas-armadas-prensa-censura-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/11\/ecuador-fuerzas-armadas-prensa-censura-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/11\/ecuador-fuerzas-armadas-prensa-censura-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Como en EE.UU., las Fuerzas Armadas de Ecuador fijan reglas para la cobertura de prensa. Medios se\u00f1alan censura"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/11\/ecuador-fuerzas-armadas-prensa-censura-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Como en EE.UU., las Fuerzas Armadas de Ecuador fijan reglas para la cobertura de prensa. Medios se\u00f1alan censura","url":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/11\/ecuador-fuerzas-armadas-prensa-censura-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/11\/ecuador-fuerzas-armadas-prensa-censura-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-11T21:03:46Z","datePublished":"2026-02-11T21:03:46Z","dateModified":"2026-02-11T21:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Como en EE.UU., las Fuerzas Armadas de Ecuador fijan reglas para la cobertura de prensa. Medios se\\u00f1alan censura\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/11\\\/ecuador-fuerzas-armadas-prensa-censura-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/11\\\/ecuador-fuerzas-armadas-prensa-censura-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-11T21:03:46Z\",\"datePublished\":\"2026-02-11T21:03:46Z\",\"dateModified\":\"2026-02-11T21:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1456265,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/12\/04\/ecuador-investigan-presunta-desaparicion-futbolista-pedro-pablo-perlaza-orix\/","url_meta":{"origin":1471121,"position":0},"title":"Autoridades de Ecuador investigan la presunta desaparici\u00f3n del futbolista Pedro Pablo Perlaza","author":"","date":"diciembre 4, 2024","format":false,"excerpt":"La Polic\u00eda de Esmeraldas, Ecuador, investiga una denuncia por desaparici\u00f3n interpuesta por familiares del futbolista Pedro Pablo Perlaza, confirm\u00f3 el jefe de distrito del cuerpo policial, Diego Velastegu\u00ed, al canal Ecuavisa, afiliado de CNN.La estaci\u00f3n report\u00f3 que la \u00faltima vez que se supo del jugador, que pertenece al club Delf\u00edn,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449734,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/05\/24\/noboa-fuerzas-armadas-control-armas-de-fuego-carceles-ecuador-orix\/","url_meta":{"origin":1471121,"position":1},"title":"Noboa ordena que las Fuerzas Armadas asuman el control de las armas de fuego en las cercan\u00edas de las c\u00e1rceles de Ecuador","author":"","date":"mayo 24, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de Ecuador, Daniel Noboa, public\u00f3 este jueves un nuevo decreto en el que ordena que las Fuerzas Armadas asuman el control de las armas de fuego, las municiones, los explosivos y los accesorios en todas las vialidades autorizadas para el ingreso a las c\u00e1rceles del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450568,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/06\/20\/muere-padre-primera-dama-ecuador-orix\/","url_meta":{"origin":1471121,"position":2},"title":"Muere el padre de la primera dama de Ecuador","author":"","date":"junio 20, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El empresario Furio Valbonesi, padre de Lavinia Valbonesi, esposa del presidente Daniel Noboa, muri\u00f3 este jueves, inform\u00f3 la Presidencia de Ecuador.La instituci\u00f3n public\u00f3 la noticia en X junto con su p\u00e9same a la primera dama y al presidente Daniel Noboa. En sus respectivas cuentas de la misma red\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445848,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/02\/21\/ecuador-carceles-fuerzas-armadas-orix\/","url_meta":{"origin":1471121,"position":3},"title":"Las Fuerzas Armadas seguir\u00e1n en las c\u00e1rceles de Ecuador \u201chasta que sea necesario\u201d, dice jefe militar","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Las Fuerzas Armadas de Ecuador mantendr\u00e1n el control de las c\u00e1rceles del pa\u00eds \u201chasta que sea necesario\u201d, dijo este martes el almirante Jaime Vela, jefe del Comando Conjunto, de acuerdo con un comunicado de la Presidencia.El jefe militar hizo esta declaraci\u00f3n despu\u00e9s de una reuni\u00f3n con el presidente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445963,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/02\/23\/reos-fugan-carcel-ecuador-orix\/","url_meta":{"origin":1471121,"position":4},"title":"Tres reos se fugan de la c\u00e1rcel de Cotopaxi en Ecuador","author":"","date":"febrero 23, 2024","format":false,"excerpt":"(CNN) -- Tres reos se fugaron de la c\u00e1rcel de Cotopaxi durante la madrugada de este jueves, informaron el viernes las Fuerzas Armadas de Ecuador, que mantienen el control de las prisiones del pa\u00eds como parte del plan del Gobierno del presidente Daniel Noboa para frenar la violencia que se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472432,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/03\/21\/pentagono-prensa-fuerte-resistencia-analisis-trax\/","url_meta":{"origin":1471121,"position":5},"title":"La ofensiva del Pent\u00e1gono contra la prensa encuentra una fuerte resistencia","author":"","date":"marzo 21, 2026","format":false,"excerpt":"El secretario de Defensa, Pete Hegseth, ha tomado medidas para obstaculizar la cobertura informativa del Pent\u00e1gono durante m\u00e1s de un a\u00f1o. Ahora, por fin, ha encontrado cierta resistencia.El fallo del viernes de un juez federal que anul\u00f3 las restricciones de prensa del Pent\u00e1gono fue celebrado por la organizaci\u00f3n de noticias\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1471121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1471121"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1471121\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1471121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1471121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1471121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}