{"id":1471128,"date":"2026-02-11T16:03:46","date_gmt":"2026-02-12T00:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/11\/conclusiones-testimonio-combativo-pam-bondi-trax\/"},"modified":"2026-02-11T16:03:46","modified_gmt":"2026-02-12T00:03:46","slug":"conclusiones-testimonio-combativo-pam-bondi-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/11\/conclusiones-testimonio-combativo-pam-bondi-trax\/","title":{"rendered":"5 conclusiones del testimonio combativo de Pam Bondi en la Comisi\u00f3n Judicial de la C\u00e1mara de Representantes"},"content":{"rendered":"<p>El testimonio de <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/11\/eeuu\/bondi-audiencia-jamie-raskin-comite-judicial-trax\">Pam Bondi<\/a>, secretaria de Justicia de Estados Unidos, ante la Comisi\u00f3n Judicial de la C\u00e1mara de Representantes este mi\u00e9rcoles fue uno de los m\u00e1s tensos y confrontativos hasta ahora por parte de un integrante del gabinete del presidente Donald Trump.<\/p>\n<p>Bondi compareci\u00f3 en un momento en que el Gobierno de Estados Unidos y el Departamento de Justicia enfrentan una serie de controversias, incluida la gesti\u00f3n de los <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/21\/eeuu\/que-contienen-archivos-epstein-publicados-trax\">archivos de Jeffrey Epstein<\/a>, los recientes reportes sobre intentos fallidos de acusar formalmente a seis legisladores dem\u00f3cratas y la muerte de dos manifestantes por agentes federales en Minneapolis el mes pasado.<\/p>\n<p>A continuaci\u00f3n, las conclusiones de la audiencia:<\/p>\n<p>Al inicio de la audiencia, la representante dem\u00f3crata Pramila Jayapal, de Washington, pidi\u00f3 a sobrevivientes de Epstein presentes en la sala que se pusieran de pie. Y desafi\u00f3 a Bondi con una cuesti\u00f3n dif\u00edcil.<\/p>\n<p>Le pidi\u00f3 a Bondi, que acababa de disculparse con las v\u00edctimas por los abusos que hab\u00edan sufrido, que tambi\u00e9n se disculpara con ellas por los fallos del Departamento de Justicia a la hora de ocultar la informaci\u00f3n personal sensible de las v\u00edctimas.<\/p>\n<p>Bondi hizo una pausa, como si estuviera pensando en su siguiente movimiento. Entonces, en lugar de disculparse, desvi\u00f3 la respuesta hacia su predecesor, el exsecretario de Justicia Merrick Garland. El intercambio se convirti\u00f3 r\u00e1pidamente en discusiones y ataques personales.<\/p>\n<p>Fue un momento revelador. El Departamento de Justicia ha reconocido estos fallos en edici\u00f3n por protecci\u00f3n. Y las sobrevivientes son algunas de las figuras m\u00e1s emp\u00e1ticas imaginables. Pero Bondi decidi\u00f3 que el momento exig\u00eda combatividad, no contrici\u00f3n.<\/p>\n<p>El resto de la audiencia sigui\u00f3 su curso a partir de ah\u00ed. Bondi se mostr\u00f3 extremadamente combativa en todo momento, haciendo todo lo posible por evitar las preguntas de los dem\u00f3cratas y del representante republicano Thomas Massie sobre Epstein, de una forma que podr\u00eda parecer pol\u00edticamente poco acertada.<\/p>\n<p>Tambi\u00e9n rechaz\u00f3 las repetidas peticiones de los dem\u00f3cratas de que se dirigiera a las v\u00edctimas sentadas detr\u00e1s de ella, sobrevivientes que afirmaban que el Departamento de Justicia las hab\u00eda ignorado, lo que dio lugar a unas im\u00e1genes impactantes.<\/p>\n<p><a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/11\/eeuu\/bondi-audiencia-jamie-raskin-comite-judicial-trax\">Llam\u00f3 a un dem\u00f3crata \u201cabogado fracasado\u201d<\/a>. Reprendi\u00f3 a otro por criticar \u201cal mejor presidente en la historia de Estados Unidos\u201d, Trump. Cuando otro dem\u00f3crata la presion\u00f3 para que le dijera si se hab\u00edan investigado las acusaciones de una denunciante contra Trump, ella sugiri\u00f3 que el legislador se centrara en los \u201chorribles cr\u00edmenes que se cometen en California\u201d, su estado de origen.<\/p>\n<p>Cuando otro legislador le pidi\u00f3 nuevamente que considerara a las v\u00edctimas presentes, en lugar de responder, se\u00f1al\u00f3 el reloj y dijo: \u201cSe acab\u00f3 su tiempo\u201d.<\/p>\n<p>Habl\u00f3 tanto por encima de sus interrogadores que el presidente republicano de la Comisi\u00f3n Judicial, Jim Jordan, tuvo que recordarle repetidas veces que el tiempo pertenec\u00eda a los miembros, no a ella.<\/p>\n<p>Parec\u00eda que Bondi estaba dirigi\u00e9ndose a un \u201cp\u00fablico \u00fanico\u201d: Trump. Pero eso pod\u00eda suponer un perjuicio a la hora de atraer a un p\u00fablico estadounidense que realmente quiere respuestas.<\/p>\n<p>Despu\u00e9s de todo, una encuesta reciente revel\u00f3 que los estadounidenses <a href=\"https:\/\/www.ipsos.com\/sites\/default\/files\/ct\/news\/documents\/2026-01\/Reuters%20Ipsos%20Greenland%20Survey%20Topline%20January%202026%201.14%20Release_0.pdf\">desaprueban por 3 a 1<\/a> la gesti\u00f3n del Gobierno en el caso Epstein.<\/p>\n<p>La combatividad era normal en Bondi, pero corr\u00eda el riesgo de parecer fuera de lugar y como si no se estuviera tomando en serio un tema importante.<\/p>\n<p>En estos momentos, muchos funcionarios de Trump parecen estar eligiendo entre cumplir sus \u00f3rdenes y hacer lo que, de otro modo, podr\u00eda parecer sensato. Y la actuaci\u00f3n de Bondi este mi\u00e9rcoles fue un buen ejemplo de ello.<\/p>\n<p>Pero Bondi no pod\u00eda limitarse a perseguir a los dem\u00f3cratas. Al fin y al cabo, algunos republicanos la han presionado a ella y al Departamento de Justicia sobre este tema.<\/p>\n<p>Y un intercambio con Massie, el principal republicano detr\u00e1s del esfuerzo sobre los archivos de Epstein, destac\u00f3 cuando se trat\u00f3 de poner realmente contra las cuerdas al Gobierno.<\/p>\n<p>El representante de Kentucky se\u00f1al\u00f3 otro gran problema relacionado con las ediciones por protecci\u00f3n: c\u00f3mo el Gobierno pareci\u00f3 editar err\u00f3neamente a algunos hombres que, en un momento dado, las fuerzas del orden sospechaban que estaban involucrados en <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/11\/eeuu\/analisis-afirmo-equipo-trump-frente-archivos-epstein-trax\">actividades delictivas con Epstein<\/a>. Massie y el representante dem\u00f3crata Ro Khanna, de California, han citado a seis de ellos, entre los que se encuentra el magnate multimillonario Les Wexner.<\/p>\n<p>(Wexner no ha sido acusado de delito alguno, y <a href=\"https:\/\/www.nbc4i.com\/news\/local-news\/new-albany\/wexner-named-as-possible-co-conspirator-in-epstein-files-lawyer-offers-context\/\">un representante afirm\u00f3<\/a> que cooper\u00f3 con las autoridades y que se le inform\u00f3 que \u201cno era co-conspirador ni objetivo de investigaci\u00f3n en ning\u00fan sentido\u201d).<\/p>\n<p>Bondi se\u00f1al\u00f3, al igual que el Gobierno, que el nombre de Wexner aparec\u00eda en otras partes de los documentos. Pero Massie se refiri\u00f3 a eso como una cortina de humo, ya que el Departamento de Justicia hab\u00eda ocultado su nombre espec\u00edficamente en los casos en que estaba relacionado con posibles delitos.<\/p>\n<p>Bondi afirm\u00f3 entonces que el Gobierno hab\u00eda eliminado el nombre de Wexner \u201cen 40 minutos\u201d. Pero Massie se\u00f1al\u00f3 acertadamente que eso solo ocurri\u00f3 despu\u00e9s de que \u00e9l y Khanna lo hubieran denunciado.<\/p>\n<p>\u201cEn 40 minutos despu\u00e9s de que los sorprend\u00ed en el acto\u201d, replic\u00f3 Massie.<\/p>\n<p>Bondi continu\u00f3 llamando a Massie \u201cpol\u00edtico fracasado\u201d e \u201chip\u00f3crita\u201d.<\/p>\n<p>Mientras los dem\u00f3cratas intentaban destacar los errores del Gobierno en esta cuesti\u00f3n, Bondi sol\u00eda enturbiar las aguas evitando responder a las preguntas y entrando en discusiones acaloradas.<\/p>\n<p>El intercambio de Massie realmente surti\u00f3 efecto.<\/p>\n<p>Por un breve instante, los legisladores recordaron un problema que cada vez les afecta m\u00e1s a todos. Y eso provoc\u00f3 un momento excepcional de verdadera cordialidad.<\/p>\n<p>El representante dem\u00f3crata Eric Swalwell, de California, que a menudo se ha enfrentado a testigos aliados de Trump, se centr\u00f3 en cambio en las amenazas a las que \u00e9l y su familia se han enfrentado. Tras detallarlas, pregunt\u00f3 a Bondi si a\u00fan se estaban investigando.<\/p>\n<p>\u201cSolo pido su ayuda para proteger la vida, porque la vida est\u00e1 en peligro con el entorno en el que nos encontramos ahora mismo\u201d, dijo Swalwell.<\/p>\n<p>Bondi respondi\u00f3: \u201cSe est\u00e1n investigando, y puedo darles m\u00e1s detalles al respecto. Ninguno de ustedes deber\u00eda ser amenazado jam\u00e1s. Ninguno de sus hijos deber\u00eda ser amenazado. Ninguna de sus familias deber\u00eda ser amenazada, y yo trabajar\u00e9 con ustedes\u201d.<\/p>\n<p>El intercambio puso de relieve un tema que era un gigante dormido, y del que los legisladores suelen ser reacios a hablar. Pero es un tema que claramente afecta a ambos lados del espectro pol\u00edtico. Y, por una vez, hubo cierta unidad en cuanto al objetivo.<\/p>\n<p>Por supuesto, ambas partes tambi\u00e9n han discrepado vehementemente sobre qui\u00e9n tiene m\u00e1s culpa de la violencia pol\u00edtica, un tema que tambi\u00e9n se plante\u00f3 en otro momento de la audiencia.<\/p>\n<p>Por lo general, estas audiencias funcionan de tal manera que los aliados de los testigos en la comisi\u00f3n tratan de orientar las cosas en una direcci\u00f3n m\u00e1s favorable. Por lo tanto, se centran en cuestiones que juegan a su favor.<\/p>\n<p>No obstante, esos temas eran dif\u00edciles de abordar.<\/p>\n<p>Algunos republicanos intentaron centrarse en el hecho de que el Departamento de Justicia de Biden hab\u00eda solicitado los registros de llamadas de los republicanos del Congreso, lo que el Partido Republicano ha comparado con \u201cespiarlos\u201d.<\/p>\n<p>Sin embargo, la audiencia se celebr\u00f3 literalmente un d\u00eda despu\u00e9s de que se informara que el Departamento de Justicia bajo Trump intent\u00f3 sin \u00e9xito acusar formalmente a seis legisladores dem\u00f3cratas. Se trataba, una vez m\u00e1s, de personas que Trump suger\u00eda que merec\u00edan ser procesadas.<\/p>\n<p>Bondi se centr\u00f3 en sus comentarios iniciales en la idea de mantener la seguridad de las personas, citando descensos significativos en las cifras de delincuencia. Y Jordan, en su declaraci\u00f3n inicial, se centr\u00f3 en las deportaciones.<\/p>\n<p>Pero esos tambi\u00e9n son temas que parecen haberse escapado de las manos del Gobierno. <a href=\"https:\/\/www.nbcnews.com\/politics\/trump-administration\/poll-americans-support-ice-overhaul-federal-funding-fight-rcna258241\">Una encuesta de NBC News<\/a> publicada esa misma ma\u00f1ana revelaba que el rechazo a Trump en materia de inmigraci\u00f3n hab\u00eda alcanzado el 60 %. Y el Gobierno sigue lidiando con <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/02\/eeuu\/narrativa-gobierno-trump-muerte-alex-pretti-desmoronada-analisis-trax\">las consecuencias del tiroteo mortal de Alex Pretti<\/a> y <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/16\/eeuu\/renee-good-911-detalles-muerte-trax\">Renee Good<\/a> en Minneapolis a manos de sus agentes, situaciones que tambi\u00e9n se han convertido en importantes responsabilidades para el Gobierno.<\/p>\n<p>Era el tipo de audiencia en la que aparentemente se necesitaba una actuaci\u00f3n contundente, en la que Bondi abordara directamente los temas en cuesti\u00f3n e intentara enderezar el rumbo.<\/p>\n<p>Pero Bondi no acudi\u00f3 para responder a preguntas dif\u00edciles. Acudi\u00f3 para sobrevivir a la audiencia.<\/p>\n<p>Bondi, como se dijo anteriormente, lleg\u00f3 dispuesta a todo para contraatacar a los legisladores.<\/p>\n<p>Sin embargo, la desventaja de ese enfoque es que a veces se puede fallar.<\/p>\n<p>Al principio de la audiencia, Bondi sugiri\u00f3, de forma bastante desconcertante, que los dem\u00f3cratas de la comisi\u00f3n deber\u00edan centrarse en la subida del mercado burs\u00e1til bajo el mandato de Trump.<\/p>\n<p>\u201cEl Dow est\u00e1 por encima de 50.000 puntos, el S&#038;P casi en 7.000 y el NASDAQ rompiendo r\u00e9cords; las cuentas 401(k) y los ahorros para la jubilaci\u00f3n de los estadounidenses est\u00e1n creciendo. De eso deber\u00edamos estar hablando\u201d, afirm\u00f3 Bondi. \u201cEso es de lo que deber\u00edamos estar hablando\u201d.<\/p>\n<p>El mercado burs\u00e1til no suele ser competencia de la Comisi\u00f3n Judicial, como r\u00e1pidamente se\u00f1al\u00f3 un dem\u00f3crata.<\/p>\n<p>M\u00e1s adelante en la audiencia, atac\u00f3 a la representante dem\u00f3crata Becca Balint, de Vermont, por haber votado en contra de una resoluci\u00f3n relacionada con el antisemitismo.<\/p>\n<p>Pero Balint es en realidad la nieta de alguien que muri\u00f3 en el Holocausto.<\/p>\n<p>Balint lo se\u00f1al\u00f3 mientras gritaba a Bondi y le imploraba: \u201c\u00bfHablas en serio?\u201d, antes de abandonar la audiencia.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El testimonio de Pam Bondi, secretaria de Justicia de Estados Unidos, ante la Comisi\u00f3n Judicial de la C\u00e1mara de Representantes este mi\u00e9rcoles fue uno de los m\u00e1s tensos y confrontativos hasta ahora por parte de un integrante del gabinete del presidente Donald Trump. Bondi compareci\u00f3 en un momento en que el Gobierno de Estados Unidos [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1471128","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>5 conclusiones del testimonio combativo de Pam Bondi en la Comisi\u00f3n Judicial de la C\u00e1mara de Representantes - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/11\/conclusiones-testimonio-combativo-pam-bondi-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 conclusiones del testimonio combativo de Pam Bondi en la Comisi\u00f3n Judicial de la C\u00e1mara de Representantes - Noticias\" \/>\n<meta property=\"og:description\" content=\"El testimonio de Pam Bondi, secretaria de Justicia de Estados Unidos, ante la Comisi\u00f3n Judicial de la C\u00e1mara de Representantes este mi\u00e9rcoles fue uno de los m\u00e1s tensos y confrontativos hasta ahora por parte de un integrante del gabinete del presidente Donald Trump. Bondi compareci\u00f3 en un momento en que el Gobierno de Estados Unidos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/11\/conclusiones-testimonio-combativo-pam-bondi-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-12T00:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/11\/conclusiones-testimonio-combativo-pam-bondi-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/11\/conclusiones-testimonio-combativo-pam-bondi-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"5 conclusiones del testimonio combativo de Pam Bondi en la Comisi\u00f3n Judicial de la C\u00e1mara de Representantes\",\"datePublished\":\"2026-02-12T00:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/11\/conclusiones-testimonio-combativo-pam-bondi-trax\/\"},\"wordCount\":1699,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/11\/conclusiones-testimonio-combativo-pam-bondi-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/11\/conclusiones-testimonio-combativo-pam-bondi-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/11\/conclusiones-testimonio-combativo-pam-bondi-trax\/\",\"name\":\"5 conclusiones del testimonio combativo de Pam Bondi en la Comisi\u00f3n Judicial de la C\u00e1mara de Representantes - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-12T00:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/11\/conclusiones-testimonio-combativo-pam-bondi-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/11\/conclusiones-testimonio-combativo-pam-bondi-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/11\/conclusiones-testimonio-combativo-pam-bondi-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5 conclusiones del testimonio combativo de Pam Bondi en la Comisi\u00f3n Judicial de la C\u00e1mara de Representantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5 conclusiones del testimonio combativo de Pam Bondi en la Comisi\u00f3n Judicial de la C\u00e1mara de Representantes - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/11\/conclusiones-testimonio-combativo-pam-bondi-trax\/","og_locale":"es_ES","og_type":"article","og_title":"5 conclusiones del testimonio combativo de Pam Bondi en la Comisi\u00f3n Judicial de la C\u00e1mara de Representantes - Noticias","og_description":"El testimonio de Pam Bondi, secretaria de Justicia de Estados Unidos, ante la Comisi\u00f3n Judicial de la C\u00e1mara de Representantes este mi\u00e9rcoles fue uno de los m\u00e1s tensos y confrontativos hasta ahora por parte de un integrante del gabinete del presidente Donald Trump. Bondi compareci\u00f3 en un momento en que el Gobierno de Estados Unidos [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/11\/conclusiones-testimonio-combativo-pam-bondi-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-12T00:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/11\/conclusiones-testimonio-combativo-pam-bondi-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/11\/conclusiones-testimonio-combativo-pam-bondi-trax\/"},"author":{"name":"","@id":""},"headline":"5 conclusiones del testimonio combativo de Pam Bondi en la Comisi\u00f3n Judicial de la C\u00e1mara de Representantes","datePublished":"2026-02-12T00:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/11\/conclusiones-testimonio-combativo-pam-bondi-trax\/"},"wordCount":1699,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/11\/conclusiones-testimonio-combativo-pam-bondi-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/11\/conclusiones-testimonio-combativo-pam-bondi-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/11\/conclusiones-testimonio-combativo-pam-bondi-trax\/","name":"5 conclusiones del testimonio combativo de Pam Bondi en la Comisi\u00f3n Judicial de la C\u00e1mara de Representantes - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-12T00:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/11\/conclusiones-testimonio-combativo-pam-bondi-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/11\/conclusiones-testimonio-combativo-pam-bondi-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/11\/conclusiones-testimonio-combativo-pam-bondi-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"5 conclusiones del testimonio combativo de Pam Bondi en la Comisi\u00f3n Judicial de la C\u00e1mara de Representantes"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/11\/conclusiones-testimonio-combativo-pam-bondi-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"5 conclusiones del testimonio combativo de Pam Bondi en la Comisi\u00f3n Judicial de la C\u00e1mara de Representantes","url":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/11\/conclusiones-testimonio-combativo-pam-bondi-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/11\/conclusiones-testimonio-combativo-pam-bondi-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-12T00:03:46Z","datePublished":"2026-02-12T00:03:46Z","dateModified":"2026-02-12T00:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"5 conclusiones del testimonio combativo de Pam Bondi en la Comisi\\u00f3n Judicial de la C\\u00e1mara de Representantes\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/11\\\/conclusiones-testimonio-combativo-pam-bondi-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/11\\\/conclusiones-testimonio-combativo-pam-bondi-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-12T00:03:46Z\",\"datePublished\":\"2026-02-12T00:03:46Z\",\"dateModified\":\"2026-02-12T00:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1471885,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/03\/04\/congreso-cita-pam-bondi-investigacion-epstein-trax\/","url_meta":{"origin":1471128,"position":0},"title":"El Congreso cita a la secretaria de Justicia Pam Bondi por la investigaci\u00f3n sobre Epstein","author":"","date":"marzo 4, 2026","format":false,"excerpt":"La Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes, liderada por los republicanos, vot\u00f3 para citar a la secretaria de Justicia de Estados Unidos, Pam Bondi, para que declare sobre su papel en la divulgaci\u00f3n de los archivos de Jeffrey Epstein como parte de la investigaci\u00f3n de la comisi\u00f3n sobre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471119,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/11\/bondi-audiencia-jamie-raskin-comite-judicial-trax\/","url_meta":{"origin":1471128,"position":1},"title":"Pam Bondi llama al principal dem\u00f3crata del Comit\u00e9 Judicial de la C\u00e1mara un &#171;abogado fracasado&#187;","author":"","date":"febrero 11, 2026","format":false,"excerpt":"La secretaria de Justicia Pam Bondi llam\u00f3 al representante Jamie Raskin \u2014exprofesor de derecho constitucional y principal dem\u00f3crata del Comit\u00e9 Judicial de la C\u00e1mara de Representantes\u2014 un \u201cabogado fracasado\u201d, en medio de un enfrentamiento que se intensific\u00f3 entre ella y los dem\u00f3cratas del comit\u00e9 por su forma de responder a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472286,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/03\/17\/presidente-comision-camara-cita-pam-bondi-declarar-epstein-trax\/","url_meta":{"origin":1471128,"position":2},"title":"Presidente de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara cita a Pam Bondi a declarar en la investigaci\u00f3n sobre Epstein","author":"","date":"marzo 17, 2026","format":false,"excerpt":"El presidente de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes, James Comer, emiti\u00f3 este martes una citaci\u00f3n a la secretaria de Justicia de Estados Unidos, Pam Bondi, para que comparezca a una declaraci\u00f3n el 14 de abril como parte de la investigaci\u00f3n sobre Jeffrey Epstein.Comer escribi\u00f3 en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473647,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/29\/bondi-testificara-investigacion-camara-jeffrey-epstein-trax\/","url_meta":{"origin":1471128,"position":3},"title":"Bondi testificar\u00e1 en la investigaci\u00f3n de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes sobre Jeffrey Epstein","author":"","date":"abril 29, 2026","format":false,"excerpt":"La exsecretaria de Justicia Pam Bondi tiene previsto testificar el pr\u00f3ximo mes en la investigaci\u00f3n de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes sobre Jeffrey Epstein.La comparecencia de Bondi \u2014ahora fijada para el 29 de mayo, seg\u00fan una portavoz de la comisi\u00f3n\u2014 se produce mientras el panel ha\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472972,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/08\/departamento-justicia-bondi-comparencia-caso-epstein-trax\/","url_meta":{"origin":1471128,"position":4},"title":"Bondi ya no est\u00e1 obligada a declarar sobre el caso Epstein, dice el Departamento de Justicia","author":"","date":"abril 8, 2026","format":false,"excerpt":"El Departamento de Justicia dijo el mi\u00e9rcoles que Pam Bondi no comparecer\u00e1 en su pr\u00f3xima declaraci\u00f3n en la investigaci\u00f3n de Jeffrey Epstein de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara, dado que ya no se desempe\u00f1a como secretaria de Justicia de Estados Unidos.Esto marca el m\u00e1s reciente obst\u00e1culo en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471308,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/17\/hillary-clinton-acusa-trump-encubrimiento-epstein-trax\/","url_meta":{"origin":1471128,"position":5},"title":"Hillary Clinton acusa a la administraci\u00f3n Trump de &#171;encubrimiento&#187; por el manejo de los documentos de Epstein","author":"","date":"febrero 17, 2026","format":false,"excerpt":"La exsecretaria de Estado de Estados Unidos Hillary Clinton ha acusado a la administraci\u00f3n Trump de un \u201cencubrimiento continuo\u201d por la forma en que el Gobierno ha manejado la publicaci\u00f3n de millones de documentos relacionados con Jeffrey Epstein.\u201cEst\u00e1n actuando con lentitud, est\u00e1n ocultando los nombres de los hombres que participan,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1471128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1471128"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1471128\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1471128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1471128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1471128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}