{"id":1471166,"date":"2026-02-12T15:03:48","date_gmt":"2026-02-12T23:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/12\/trump-deroga-poder-epa-contaminacion-efecto-invernadero-trax\/"},"modified":"2026-02-12T15:03:48","modified_gmt":"2026-02-12T23:03:48","slug":"trump-deroga-poder-epa-contaminacion-efecto-invernadero-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/12\/trump-deroga-poder-epa-contaminacion-efecto-invernadero-trax\/","title":{"rendered":"Trump revoca la capacidad de la EPA para regular los gases de efecto invernadero"},"content":{"rendered":"<p>El Gobierno del presidente Donald Trump ha desmantelado uno de los pilares fundamentales de la estrategia ecol\u00f3gica de EE.UU. al finalizar, este jueves, las normativas que revocan de forma definitiva la facultad de la Agencia de Protecci\u00f3n Ambiental (EPA, por sus siglas en ingl\u00e9s) para regular la contaminaci\u00f3n clim\u00e1tica.<\/p>\n<p>Emitida por primera vez en 2009, la determinaci\u00f3n de peligro concluy\u00f3 que seis gases de efecto invernadero pod\u00edan ser categorizados como peligrosos para la salud humana bajo la Ley de Aire Limpio. La normativa respaldaba la autoridad de la EPA para limitar la contaminaci\u00f3n causante del calentamiento global proveniente de la industria del petr\u00f3leo y el gas, las plantas de energ\u00eda y los veh\u00edculos desde el Gobierno de Obama. Tambi\u00e9n es considerada la herramienta m\u00e1s poderosa del Gobierno federal para abordar la contaminaci\u00f3n clim\u00e1tica y la contribuci\u00f3n de EE.UU. a la crisis global.<\/p>\n<p>\u201cEstamos terminando oficialmente con el llamado dictamen de peligro\u201d, declar\u00f3 el presidente Donald Trump este jueves, calificando la pol\u00edtica de \u201cdesastrosa\u201d.<\/p>\n<p>Trump dijo que derogar las regulaciones \u201cno tiene nada que ver con la salud p\u00fablica\u201d.<\/p>\n<p>\u201cTodo esto fue una estafa, una gran estafa\u201d, dijo Trump el jueves. \u201cEsto fue un robo al pa\u00eds por parte de Obama y Biden\u201d.<\/p>\n<p>Adem\u00e1s, el Gobierno de Trump finalizar\u00e1 la derogaci\u00f3n de las reglas que regulan las emisiones de gases de efecto invernadero de los veh\u00edculos, ya que se derivan del dictamen. Durante el Gobierno de Biden, la EPA busc\u00f3 endurecer esos est\u00e1ndares para impulsar a la industria automotriz a fabricar m\u00e1s h\u00edbridos y veh\u00edculos el\u00e9ctricos eficientes, un esfuerzo que la industria revirti\u00f3 posteriormente.<\/p>\n<p>Al eliminar el dictamen de peligro, el Gobierno puede revocar m\u00e1s f\u00e1cilmente otras reglas que reducen la contaminaci\u00f3n clim\u00e1tica emitida por plantas de energ\u00eda y operaciones de petr\u00f3leo y gas, aunque eso requerir\u00e1 procesos regulatorios separados para ser anulado.<\/p>\n<p>El texto completo de la derogaci\u00f3n del dictamen de peligro por parte de la EPA no estuvo disponible antes del anuncio del Gobierno de Trump, pero la justificaci\u00f3n para la derogaci\u00f3n expuesta en un comunicado de prensa de la EPA se basa mucho m\u00e1s en argumentos legales que en un rechazo contundente de la ciencia clim\u00e1tica.<\/p>\n<p>La agencia argumenta que los Gobiernos de Obama y Biden excedieron su autoridad legal cuando usaron la Ley de Aire Limpio para regular la contaminaci\u00f3n clim\u00e1tica. Esto contrasta con el verano pasado, cuando la agencia propuso por primera vez la derogaci\u00f3n. En ese entonces, la propuesta de la EPA se bas\u00f3 en parte en un informe apresurado elaborado por cinco negacionistas del cambio clim\u00e1tico que cuestionaban la gravedad de los impactos clim\u00e1ticos como incendios forestales, calor extremo y tormentas m\u00e1s fuertes.<\/p>\n<p>En esta ocasi\u00f3n, en lugar de basarse en ello, la EPA de Trump concluy\u00f3 en un comunicado de prensa que la Ley de Aire Limpio \u201cno otorga autoridad estatutaria a la EPA\u201d para presentar est\u00e1ndares de emisiones de veh\u00edculos \u201cincluidos los destinados a abordar el cambio clim\u00e1tico global, y por lo tanto no existe base legal para el dictamen de peligro ni para las regulaciones resultantes\u201d.<\/p>\n<p>Sin embargo, en el mismo comunicado de prensa donde se anunci\u00f3 la derogaci\u00f3n, el administrador de la EPA, Lee Zeldin, aludi\u00f3 a la oposici\u00f3n del Gobierno a la pol\u00edtica clim\u00e1tica.<\/p>\n<p>\u201cLlamado por algunos el \u2018Santo Grial\u2019 de la \u2018religi\u00f3n del cambio clim\u00e1tico\u2019, el dictamen de peligro ahora est\u00e1 eliminado\u201d, dijo Zeldin en el comunicado de la EPA. No obstante, al hablar junto a Trump este jueves, los comentarios de Zeldin fueron ligeramente diferentes.<\/p>\n<p>\u201cHoy, la EPA de Trump ha finalizado el mayor acto \u00fanico de desregulaci\u00f3n en la historia de Estados Unidos de Am\u00e9rica, llamado por algunos el santo grial de la extralimitaci\u00f3n regulatoria federal; el dictamen de peligro de la EPA de Obama de 2009 est\u00e1 ahora eliminado\u201d, dijo Zeldin este jueves.<\/p>\n<p>El precedente legal ha otorgado al Gobierno poderes regulatorios sobre la contaminaci\u00f3n clim\u00e1tica. La Corte Suprema de EE.UU. fall\u00f3 en 2007 que la EPA ten\u00eda la autoridad para regular la contaminaci\u00f3n clim\u00e1tica proveniente de los gases de efecto invernadero. Y en 2022, la Corte Suprema de EE.UU. confirm\u00f3 la autoridad de la EPA para regular los gases de efecto invernadero de las centrales el\u00e9ctricas, pero restringi\u00f3 significativamente el alcance de la agencia, lo que llev\u00f3 al Gobierno de Biden a formular reglas orientadas \u00fanicamente a hacer que las centrales el\u00e9ctricas individuales sean m\u00e1s eficientes.<\/p>\n<p>Pero la derogaci\u00f3n del hallazgo de peligro remitir\u00e1 esa cuesti\u00f3n nuevamente a los tribunales, donde el litigio sobre la derogaci\u00f3n podr\u00eda llevar a\u00f1os y posiblemente llegar hasta el tribunal m\u00e1s alto del pa\u00eds. Un ex alto funcionario de la EPA durante el Gobierno de Biden dijo a CNN que cree que esta medida muestra que el Gobierno de Trump est\u00e1 jugando una estrategia legal a largo plazo.<\/p>\n<p>\u201cSu definici\u00f3n de ganar, creo, ha sido y ser\u00e1 cuando tomen una acci\u00f3n final y defiendan su acci\u00f3n en los tribunales, para eliminar de manera permanente la autoridad de la EPA bajo la Ley de Aire Limpio para regular los gases de efecto invernadero\u201d, dijo Joe Goffman, quien lider\u00f3 la Oficina de Aire y Radiaci\u00f3n de la EPA durante el Gobierno de Biden.<\/p>\n<p>Si la derogaci\u00f3n por parte del Gobierno de Trump \u201cse mantiene en el tribunal, ninguna futura EPA podr\u00e1 regular las emisiones de (di\u00f3xido de carbono)\u201d, dijo Jeff Holmstead, abogado de energ\u00eda en el bufete Bracewell y ex alto funcionario de la EPA durante el Gobierno de George W. Bush. El Congreso podr\u00eda aprobar una nueva ley que instruya espec\u00edficamente a la EPA a regular la contaminaci\u00f3n clim\u00e1tica, pero hay poco consenso bipartidista sobre c\u00f3mo abordar el tema.<\/p>\n<p>Zeldin expuso el argumento de la agencia, diciendo que la EPA no tiene autoridad para regular ciertos tipos de contaminaci\u00f3n a menos que el Congreso apruebe una ley que les otorgue permiso expreso.<\/p>\n<p>\u201cSi el Congreso no lo autoriz\u00f3, la EPA no deber\u00eda hacerlo\u201d, dijo Zeldin este jueves. \u201cSi el Congreso quiere que la EPA regule ampliamente los gases de efecto invernadero emitidos por los veh\u00edculos de motor, entonces el Congreso puede claramente convertir eso en ley\u201d.<\/p>\n<p>Grupos ambientalistas, de salud p\u00fablica y en favor del clima ya est\u00e1n prometiendo desaf\u00edos legales contra la medida de la agencia.<\/p>\n<p>\u201cEarthjustice y nuestros socios ver\u00e1n al Gobierno de Trump en los tribunales\u201d, dijo Abigail Dillen, presidenta del grupo legal ambientalista. \u201cLos tribunales han afirmado repetidamente la obligaci\u00f3n de la EPA de limpiar la contaminaci\u00f3n clim\u00e1tica. No hay forma de reconciliar la decisi\u00f3n de la EPA con la ley, la ciencia y la realidad de los desastres que nos golpean cada vez m\u00e1s fuerte cada a\u00f1o\u201d.<\/p>\n<p>Este jueves, una coalici\u00f3n de grupos de salud p\u00fablica, incluyendo la American Lung Association y la American Public Health Association, anunciaron que demandar\u00edan al Gobierno, calificando el recurso regulatorio como \u201cilegal\u201d.<\/p>\n<p>Abogados del Natural Resources Defense Fund destacaron recientemente que, incluso con una Corte Suprema conservadora, la autoridad de la EPA para regular las emisiones de gases de efecto invernadero ha sido reafirmada en m\u00faltiples ocasiones. Los abogados de NRDC sugirieron que los argumentos legales de la EPA son relativamente novedosos, lo que podr\u00eda hacer que la medida de la EPA sea m\u00e1s vulnerable a ser revocada en los tribunales.<\/p>\n<p>\u201cNo es algo que se haya hecho antes\u201d, dijo Meredith Hankins, directora legal federal para clima en NRDC.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno del presidente Donald Trump ha desmantelado uno de los pilares fundamentales de la estrategia ecol\u00f3gica de EE.UU. al finalizar, este jueves, las normativas que revocan de forma definitiva la facultad de la Agencia de Protecci\u00f3n Ambiental (EPA, por sus siglas en ingl\u00e9s) para regular la contaminaci\u00f3n clim\u00e1tica. Emitida por primera vez en 2009, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1471166","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump revoca la capacidad de la EPA para regular los gases de efecto invernadero - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/12\/trump-deroga-poder-epa-contaminacion-efecto-invernadero-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump revoca la capacidad de la EPA para regular los gases de efecto invernadero - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Gobierno del presidente Donald Trump ha desmantelado uno de los pilares fundamentales de la estrategia ecol\u00f3gica de EE.UU. al finalizar, este jueves, las normativas que revocan de forma definitiva la facultad de la Agencia de Protecci\u00f3n Ambiental (EPA, por sus siglas en ingl\u00e9s) para regular la contaminaci\u00f3n clim\u00e1tica. Emitida por primera vez en 2009, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/12\/trump-deroga-poder-epa-contaminacion-efecto-invernadero-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-12T23:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/12\/trump-deroga-poder-epa-contaminacion-efecto-invernadero-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/12\/trump-deroga-poder-epa-contaminacion-efecto-invernadero-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump revoca la capacidad de la EPA para regular los gases de efecto invernadero\",\"datePublished\":\"2026-02-12T23:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/12\/trump-deroga-poder-epa-contaminacion-efecto-invernadero-trax\/\"},\"wordCount\":1343,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/12\/trump-deroga-poder-epa-contaminacion-efecto-invernadero-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/12\/trump-deroga-poder-epa-contaminacion-efecto-invernadero-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/12\/trump-deroga-poder-epa-contaminacion-efecto-invernadero-trax\/\",\"name\":\"Trump revoca la capacidad de la EPA para regular los gases de efecto invernadero - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-12T23:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/12\/trump-deroga-poder-epa-contaminacion-efecto-invernadero-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/12\/trump-deroga-poder-epa-contaminacion-efecto-invernadero-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/12\/trump-deroga-poder-epa-contaminacion-efecto-invernadero-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump revoca la capacidad de la EPA para regular los gases de efecto invernadero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump revoca la capacidad de la EPA para regular los gases de efecto invernadero - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/12\/trump-deroga-poder-epa-contaminacion-efecto-invernadero-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trump revoca la capacidad de la EPA para regular los gases de efecto invernadero - Noticias","og_description":"El Gobierno del presidente Donald Trump ha desmantelado uno de los pilares fundamentales de la estrategia ecol\u00f3gica de EE.UU. al finalizar, este jueves, las normativas que revocan de forma definitiva la facultad de la Agencia de Protecci\u00f3n Ambiental (EPA, por sus siglas en ingl\u00e9s) para regular la contaminaci\u00f3n clim\u00e1tica. Emitida por primera vez en 2009, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/12\/trump-deroga-poder-epa-contaminacion-efecto-invernadero-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-12T23:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/12\/trump-deroga-poder-epa-contaminacion-efecto-invernadero-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/12\/trump-deroga-poder-epa-contaminacion-efecto-invernadero-trax\/"},"author":{"name":"","@id":""},"headline":"Trump revoca la capacidad de la EPA para regular los gases de efecto invernadero","datePublished":"2026-02-12T23:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/12\/trump-deroga-poder-epa-contaminacion-efecto-invernadero-trax\/"},"wordCount":1343,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/12\/trump-deroga-poder-epa-contaminacion-efecto-invernadero-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/12\/trump-deroga-poder-epa-contaminacion-efecto-invernadero-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/12\/trump-deroga-poder-epa-contaminacion-efecto-invernadero-trax\/","name":"Trump revoca la capacidad de la EPA para regular los gases de efecto invernadero - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-12T23:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/12\/trump-deroga-poder-epa-contaminacion-efecto-invernadero-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/12\/trump-deroga-poder-epa-contaminacion-efecto-invernadero-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/12\/trump-deroga-poder-epa-contaminacion-efecto-invernadero-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump revoca la capacidad de la EPA para regular los gases de efecto invernadero"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/12\/trump-deroga-poder-epa-contaminacion-efecto-invernadero-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump revoca la capacidad de la EPA para regular los gases de efecto invernadero","url":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/12\/trump-deroga-poder-epa-contaminacion-efecto-invernadero-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/12\/trump-deroga-poder-epa-contaminacion-efecto-invernadero-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-12T23:03:48Z","datePublished":"2026-02-12T23:03:48Z","dateModified":"2026-02-12T23:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump revoca la capacidad de la EPA para regular los gases de efecto invernadero\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/12\\\/trump-deroga-poder-epa-contaminacion-efecto-invernadero-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/12\\\/trump-deroga-poder-epa-contaminacion-efecto-invernadero-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-12T23:03:48Z\",\"datePublished\":\"2026-02-12T23:03:48Z\",\"dateModified\":\"2026-02-12T23:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1459842,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/03\/12\/trump-desmantela-politica-climatica-contaminacion-trax\/","url_meta":{"origin":1471166,"position":0},"title":"Trump desmantela de golpe una pol\u00edtica clim\u00e1tica que buscaba reducir la contaminaci\u00f3n","author":"","date":"marzo 12, 2025","format":false,"excerpt":"El Gobierno de Trump anunci\u00f3 su intenci\u00f3n de revertir importantes pol\u00edticas clim\u00e1ticas este mi\u00e9rcoles, incluidas las reglas que buscan reducir la contaminaci\u00f3n de veh\u00edculos y plantas de energ\u00eda, en lo que representa un importante golpe al progreso de Estados Unidos en materia de aire sin poluci\u00f3n, agua limpia y acci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473398,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/22\/contaminacion-bangor-estados-unidos-trax\/","url_meta":{"origin":1471166,"position":1},"title":"En Estados Unidos, donde la gente respira aire cada vez m\u00e1s contaminado, una peque\u00f1a ciudad resiste","author":"","date":"abril 22, 2026","format":false,"excerpt":"La Asociaci\u00f3n Estadounidense del Pulm\u00f3n lo califica como un \u201csombr\u00edo indicio del deterioro de la calidad del aire en todo el pa\u00eds\u201d: Bangor, Maine, es la \u00faltima ciudad que a\u00fan figura en las tres listas de \u201cciudades m\u00e1s limpias\u201d.Seg\u00fan la asociaci\u00f3n, Bangor no registra ning\u00fan d\u00eda con niveles perjudiciales de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450868,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/07\/03\/emisiones-gases-efecto-invernadero-google-inteligencia-artificial-trax\/","url_meta":{"origin":1471166,"position":2},"title":"Las emisiones de gases de efecto invernadero de Google se disparan por la inteligencia artificial","author":"","date":"julio 3, 2024","format":false,"excerpt":"(CNN) -- A medida que Google se ha apresurado a incorporar la inteligencia artificial (IA) a sus productos principales \u2014a veces con resultados menos que estelares\u2014, se ha ido gestando un problema entre bastidores: los sistemas necesarios para alimentar sus herramientas de IA aumentaron enormemente las emisiones de gases de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455766,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/11\/12\/biden-norma-climatica-trump-complicado-desmantelarla-trax\/","url_meta":{"origin":1471166,"position":3},"title":"Biden acaba de ultimar una importante norma clim\u00e1tica. Puede que a Trump le resulte complicado desmantelarla","author":"","date":"noviembre 12, 2024","format":false,"excerpt":"(CNN) -- La Agencia de Protecci\u00f3n Ambiental \u00a0(EPA, por sus siglas en ingl\u00e9s) acaba de finalizar una de las \u00fanicas normas clim\u00e1ticas pendientes de la administraci\u00f3n Biden, destinada a tomar medidas en\u00e9rgicas contra las fugas de metano, un potente gas que calienta el planeta y tiene un impacto descomunal en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448371,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/04\/22\/alimentos-cambio-climatico-huella-de-carbono-carne-consejos-orix\/","url_meta":{"origin":1471166,"position":4},"title":"En el D\u00eda de la Tierra, 5 consejos para reducir la huella de carbono de tu alimentaci\u00f3n (sin tener que dejar los asados)","author":"","date":"abril 22, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0S\u00ed, eres consciente de que la carne de res es el alimento m\u00e1s da\u00f1ino para el clima. Pero no, no est\u00e1 en tus planes abandonar los asados o parrilladas con la familia y los amigos. Eso no significa que no est\u00e9s dispuesto a tomar otras medidas para reducir\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470609,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/01\/29\/crisis-climatica-ramanathan-premio-efecto-invernadero-llamado-tierra-cte\/","url_meta":{"origin":1471166,"position":5},"title":"Este hombre se convirti\u00f3 en cient\u00edfico clim\u00e1tico por accidente al descubrir una fuerza inesperada del calentamiento global","author":"","date":"enero 29, 2026","format":false,"excerpt":"El cient\u00edfico Veerabhadran Ramanathan anhelaba el sue\u00f1o americano cuando crec\u00eda en el sur de la India en la d\u00e9cada de 1960: concretamente, so\u00f1aba con un Chevrolet Impala, un coche deportivo que conoci\u00f3 gracias a su padre, vendedor de neum\u00e1ticos. Ramanathan lleg\u00f3 a Estados Unidos a los veinte a\u00f1os, pero nunca\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1471166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1471166"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1471166\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1471166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1471166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1471166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}