{"id":1471170,"date":"2026-02-12T16:03:39","date_gmt":"2026-02-13T00:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/12\/estadounidenses-pagan-aranceles-inflacion-economia-trax\/"},"modified":"2026-02-12T16:03:39","modified_gmt":"2026-02-13T00:03:39","slug":"estadounidenses-pagan-aranceles-inflacion-economia-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/12\/estadounidenses-pagan-aranceles-inflacion-economia-trax\/","title":{"rendered":"Un a\u00f1o despu\u00e9s, es oficial: los estadounidenses, no los extranjeros, son quienes est\u00e1n pagando los aranceles de Trump"},"content":{"rendered":"<p>Un nuevo informe del Banco de la Reserva Federal de Nueva York confirma lo que los economistas han advertido durante mucho tiempo: la carga de los aranceles recae casi por completo en las personas que viven en el pa\u00eds que los impone.<\/p>\n<p>Ese simple hecho \u2014ahora aprendido por la experiencia en el Estados Unidos del siglo XXI\u2014 es una lecci\u00f3n de econom\u00eda tan b\u00e1sica y fundamental como la oferta y la demanda. \u00a1Siempre ha sido as\u00ed!<\/p>\n<p>Las empresas y consumidores estadounidenses <a href=\"https:\/\/libertystreeteconomics.newyorkfed.org\/2026\/02\/who-is-paying-for-the-2025-u-s-tariffs\/\">pagaron en 2025 casi el 90%<\/a> de los impuestos de importaci\u00f3n de 2025, seg\u00fan descubri\u00f3 la sucursal de la Reserva Federal (Fed). Eso no es sorprendente: la Oficina Nacional de Investigaci\u00f3n Econ\u00f3mica y la Oficina de Presupuesto del Congreso (CBO, por sus siglas en ingl\u00e9s) <a href=\"https:\/\/www.nber.org\/papers\/w34620\">encontraron<\/a> pr\u00e1cticamente<a href=\"https:\/\/www.cbo.gov\/publication\/62052?\"> lo mismo<\/a>.<\/p>\n<p>Y aunque el informe de la Fed de Nueva York no desglos\u00f3 la divisi\u00f3n entre empresas y consumidores, <a href=\"https:\/\/www.cbo.gov\/publication\/62105\">el informe de la CBO<\/a>, publicado el mi\u00e9rcoles, estim\u00f3 que las empresas continuar\u00edan reduciendo ligeramente sus m\u00e1rgenes para compensar los costos adicionales, mientras que trasladar\u00edan la mayor parte de los grav\u00e1menes \u2014un 70 %\u2014 a los consumidores. (\u00bfY los exportadores extranjeros que, seg\u00fan el presidente Donald Trump, pagar\u00edan la factura? Ellos est\u00e1n asumiendo alrededor del 5 %, estima la CBO).<\/p>\n<p>En t\u00e9rminos reales, los aranceles equivalieron a un aumento promedio de impuestos de <a href=\"https:\/\/taxfoundation.org\/research\/all\/federal\/trump-tariffs-trade-war\/\">US$ 1.000 por hogar <\/a>en 2025, de acuerdo con la Fundaci\u00f3n Fiscal no partidista.<\/p>\n<p>Ahora bien, por un lado, estos son solo los t\u00edpicos documentos acad\u00e9micos publicados por un mont\u00f3n de nerds, para un mont\u00f3n de nerds. La sabidur\u00eda colectiva de los economistas nunca le ha importado mucho a Trump cuando se trata de \u201cla palabra m\u00e1s hermosa en el diccionario\u201d, como una vez describi\u00f3 a los aranceles.<\/p>\n<p>Pero los informes de la CBO y de la Fed de Nueva York llegaron justo cuando el cansancio por los aranceles est\u00e1 golpeando fuerte en Washington.<\/p>\n<p><a href=\"https:\/\/www.cnn.com\/2026\/02\/11\/politics\/house-republicans-trump-canada-tariff-vote\">En una rara medida contra <\/a>la agenda econ\u00f3mica emblem\u00e1tica de Trump, seis republicanos de la C\u00e1mara se unieron a los dem\u00f3cratas el mi\u00e9rcoles en una votaci\u00f3n que efectivamente derogar\u00eda sus aranceles a Canad\u00e1. Los aranceles no ser\u00e1n derogados, eso s\u00ed, porque incluso si pasara en el Senado, Trump simplemente lo vetar\u00eda. Pero el rechazo de los propios miembros del partido de Trump no cay\u00f3 bien en la Casa Blanca, como era de esperarse. Poco despu\u00e9s de la votaci\u00f3n, Trump respondi\u00f3 con una amenaza de \u201cconsecuencias\u201d para \u201ccualquier republicano\u201d en el Congreso que vote contra los aranceles.<\/p>\n<p>Mientras tanto, se espera en cualquier momento un fallo de la Corte Suprema sobre la legalidad de los aranceles de Trump, lo que podr\u00eda poner toda su agenda patas arriba.<\/p>\n<p>La Casa Blanca no respondi\u00f3 de inmediato a una solicitud de comentarios.<\/p>\n<p>Y por supuesto, todo eso est\u00e1 ocurriendo mientras los estadounidenses de a pie se enfurecen por el costo de vida y <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/16\/eeuu\/encuesta-cnn-primer-ano-trump-trax\">cada vez m\u00e1s responsabilizan a Trump<\/a> y a los republicanos. El mensaje de campa\u00f1a de Trump de bajar los precios \u201cel primer d\u00eda\u201d simplemente no se ha cumplido. (<a href=\"https:\/\/www.cnn.com\/2025\/11\/17\/business\/trump-prices-affordability\">Excepto en algunos art\u00edculos como los huevos<\/a>. En eso s\u00ed podemos darle el punto, en gran parte porque los agricultores trabajaron muy duro para erradicar la gripe aviar que estaba reduciendo el suministro de huevos y aumentando los precios).<\/p>\n<p>En los papeles, la econom\u00eda estadounidense marcha bien. Eso se debe en gran parte a que la econom\u00eda se mide en promedios y agregados.<\/p>\n<p>Tomemos, por ejemplo,<a href=\"https:\/\/www.cnn.com\/2026\/02\/11\/economy\/us-jobs-report-january-final\"> el informe de empleo de enero<\/a> publicado el mi\u00e9rcoles. En general, se ve sorprendentemente s\u00f3lido, con 130.000 empleos a\u00f1adidos, casi el doble de lo que los economistas esperaban. Pero si se observa m\u00e1s de cerca, casi todas las ganancias surgieron de un solo sector, la atenci\u00f3n m\u00e9dica. Si se examina a\u00fan m\u00e1s, pr\u00e1cticamente todos los dem\u00e1s sectores mostraron ganancias d\u00e9biles o p\u00e9rdidas. De hecho, en todo 2025, la atenci\u00f3n m\u00e9dica y la asistencia social representaron el 97 % de todo el crecimiento del empleo.<\/p>\n<p>Ese es un ejemplo claro de lo que la economista Diane Swonk de KPMG ha llamado los <a href=\"https:\/\/www.cnn.com\/2025\/08\/01\/economy\/us-jobs-report-july\">\u201ctaburetes de una sola pata\u201d<\/a> que sostienen toda la econom\u00eda. Otros dos taburetes de una sola pata: la gente rica haciendo compras desenfrenadas y las grandes empresas tecnol\u00f3gicas gastando cientos de miles de millones en infraestructura de IA.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un nuevo informe del Banco de la Reserva Federal de Nueva York confirma lo que los economistas han advertido durante mucho tiempo: la carga de los aranceles recae casi por completo en las personas que viven en el pa\u00eds que los impone. Ese simple hecho \u2014ahora aprendido por la experiencia en el Estados Unidos del [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1471170","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un a\u00f1o despu\u00e9s, es oficial: los estadounidenses, no los extranjeros, son quienes est\u00e1n pagando los aranceles de Trump - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/12\/estadounidenses-pagan-aranceles-inflacion-economia-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un a\u00f1o despu\u00e9s, es oficial: los estadounidenses, no los extranjeros, son quienes est\u00e1n pagando los aranceles de Trump - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un nuevo informe del Banco de la Reserva Federal de Nueva York confirma lo que los economistas han advertido durante mucho tiempo: la carga de los aranceles recae casi por completo en las personas que viven en el pa\u00eds que los impone. Ese simple hecho \u2014ahora aprendido por la experiencia en el Estados Unidos del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/12\/estadounidenses-pagan-aranceles-inflacion-economia-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-13T00:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/12\/estadounidenses-pagan-aranceles-inflacion-economia-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/12\/estadounidenses-pagan-aranceles-inflacion-economia-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un a\u00f1o despu\u00e9s, es oficial: los estadounidenses, no los extranjeros, son quienes est\u00e1n pagando los aranceles de Trump\",\"datePublished\":\"2026-02-13T00:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/12\/estadounidenses-pagan-aranceles-inflacion-economia-trax\/\"},\"wordCount\":792,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/12\/estadounidenses-pagan-aranceles-inflacion-economia-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/12\/estadounidenses-pagan-aranceles-inflacion-economia-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/12\/estadounidenses-pagan-aranceles-inflacion-economia-trax\/\",\"name\":\"Un a\u00f1o despu\u00e9s, es oficial: los estadounidenses, no los extranjeros, son quienes est\u00e1n pagando los aranceles de Trump - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-13T00:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/12\/estadounidenses-pagan-aranceles-inflacion-economia-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/12\/estadounidenses-pagan-aranceles-inflacion-economia-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/12\/estadounidenses-pagan-aranceles-inflacion-economia-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un a\u00f1o despu\u00e9s, es oficial: los estadounidenses, no los extranjeros, son quienes est\u00e1n pagando los aranceles de Trump\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un a\u00f1o despu\u00e9s, es oficial: los estadounidenses, no los extranjeros, son quienes est\u00e1n pagando los aranceles de Trump - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/12\/estadounidenses-pagan-aranceles-inflacion-economia-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Un a\u00f1o despu\u00e9s, es oficial: los estadounidenses, no los extranjeros, son quienes est\u00e1n pagando los aranceles de Trump - Noticias","og_description":"Un nuevo informe del Banco de la Reserva Federal de Nueva York confirma lo que los economistas han advertido durante mucho tiempo: la carga de los aranceles recae casi por completo en las personas que viven en el pa\u00eds que los impone. Ese simple hecho \u2014ahora aprendido por la experiencia en el Estados Unidos del [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/12\/estadounidenses-pagan-aranceles-inflacion-economia-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-13T00:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/12\/estadounidenses-pagan-aranceles-inflacion-economia-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/12\/estadounidenses-pagan-aranceles-inflacion-economia-trax\/"},"author":{"name":"","@id":""},"headline":"Un a\u00f1o despu\u00e9s, es oficial: los estadounidenses, no los extranjeros, son quienes est\u00e1n pagando los aranceles de Trump","datePublished":"2026-02-13T00:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/12\/estadounidenses-pagan-aranceles-inflacion-economia-trax\/"},"wordCount":792,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/12\/estadounidenses-pagan-aranceles-inflacion-economia-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/12\/estadounidenses-pagan-aranceles-inflacion-economia-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/12\/estadounidenses-pagan-aranceles-inflacion-economia-trax\/","name":"Un a\u00f1o despu\u00e9s, es oficial: los estadounidenses, no los extranjeros, son quienes est\u00e1n pagando los aranceles de Trump - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-13T00:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/12\/estadounidenses-pagan-aranceles-inflacion-economia-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/12\/estadounidenses-pagan-aranceles-inflacion-economia-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/12\/estadounidenses-pagan-aranceles-inflacion-economia-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un a\u00f1o despu\u00e9s, es oficial: los estadounidenses, no los extranjeros, son quienes est\u00e1n pagando los aranceles de Trump"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/12\/estadounidenses-pagan-aranceles-inflacion-economia-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un a\u00f1o despu\u00e9s, es oficial: los estadounidenses, no los extranjeros, son quienes est\u00e1n pagando los aranceles de Trump","url":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/12\/estadounidenses-pagan-aranceles-inflacion-economia-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/12\/estadounidenses-pagan-aranceles-inflacion-economia-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-13T00:03:39Z","datePublished":"2026-02-13T00:03:39Z","dateModified":"2026-02-13T00:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un a\\u00f1o despu\\u00e9s, es oficial: los estadounidenses, no los extranjeros, son quienes est\\u00e1n pagando los aranceles de Trump\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/12\\\/estadounidenses-pagan-aranceles-inflacion-economia-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/12\\\/estadounidenses-pagan-aranceles-inflacion-economia-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-13T00:03:39Z\",\"datePublished\":\"2026-02-13T00:03:39Z\",\"dateModified\":\"2026-02-13T00:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1459033,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/02\/21\/confianza-consumidores-estadounidenses-desploma-aranceles-inflacion-trax\/","url_meta":{"origin":1471170,"position":0},"title":"La confianza de los consumidores estadounidenses se desploma por los temores a los aranceles y la inflaci\u00f3n","author":"","date":"febrero 21, 2025","format":false,"excerpt":"La inflaci\u00f3n est\u00e1 repuntando de nuevo y el presidente Donald Trump dijo esta semana que todo es culpa de su predecesor. Pero no importa a qui\u00e9n culpe Trump, el estado de \u00e1nimo econ\u00f3mico de Estados Unidos se est\u00e1 agriando, y \u00e9l es quien recibe las cr\u00edticas por ello.La encuesta m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458207,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/02\/04\/aranceles-trump-estadounidenses-mas-perjudicados-trax\/","url_meta":{"origin":1471170,"position":1},"title":"Los aranceles de Trump no afectar\u00e1n a todos los estadounidenses por igual. \u00bfQui\u00e9nes ser\u00e1n los m\u00e1s perjudicados?","author":"","date":"febrero 4, 2025","format":false,"excerpt":"Es probable que los estadounidenses de bajos ingresos sean quienes sientan m\u00e1s el peso de los aranceles sin precedentes que ha puesto en marcha el presidente Donald Trump.El costo para las familias de bajos ingresos se magnifica porque, seg\u00fan explican economistas, los productos esenciales como los alimentos, la energ\u00eda y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461457,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/04\/21\/dow-se-desploma-dolar-minimo-trump-powell-fed-trax\/","url_meta":{"origin":1471170,"position":2},"title":"El Dow se desploma y el d\u00f3lar alcanza m\u00ednimo en tres a\u00f1os mientras Trump ataca nuevamente a Powell","author":"","date":"abril 21, 2025","format":false,"excerpt":"Las acciones estadounidenses y el d\u00f3lar cayeron este lunes mientras los inversores evaluaban la continua incertidumbre sobre los aranceles y las implicaciones de la misi\u00f3n en curso del presidente Donald Trump para intentar destituir al presidente de la Reserva Federal, Jerome Powell.El Dow cay\u00f3 972 puntos, o un 2,48 %.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459425,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/03\/03\/economia-estados-unidos-aranceles-trax\/","url_meta":{"origin":1471170,"position":3},"title":"El caos de aranceles de Trump amenaza una econom\u00eda que ya est\u00e1 mostrando luces amarillas","author":"","date":"marzo 3, 2025","format":false,"excerpt":"La salud de la econom\u00eda de EE.UU. parece cada vez menos estable d\u00eda a d\u00eda.Los despidos est\u00e1n aumentando. El gasto del consumidor \u2014la columna vertebral de la econom\u00eda\u2014 cay\u00f3 inesperadamente en enero. La confianza del consumidor ha ca\u00eddo en picada. Una previsi\u00f3n clave del PIB se volvi\u00f3 de repente negativa.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471511,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/21\/analisis-numeros-economicos-anicos-narrativa-trump-trax\/","url_meta":{"origin":1471170,"position":4},"title":"Estos dos nuevos n\u00fameros econ\u00f3micos hicieron a\u00f1icos la narrativa optimista de Trump","author":"","date":"febrero 21, 2026","format":false,"excerpt":"Dos nuevos datos econ\u00f3micos, uno publicado el jueves y otro este viernes, abrieron otro agujero en la narrativa triunfal del presidente Donald Trump sobre los efectos de sus aranceles.Las cifras publicadas la madrugada del jueves muestran que Trump hab\u00eda exagerado considerablemente el impacto de los aranceles en el d\u00e9ficit comercial.Las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460573,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/03\/28\/estadounidenses-preocupados-aumento-desempleo-encuesta-trax\/","url_meta":{"origin":1471170,"position":5},"title":"Los estadounidenses no hab\u00edan estado tan preocupados por el aumento del desempleo desde 2009, seg\u00fan una encuesta","author":"","date":"marzo 28, 2025","format":false,"excerpt":"Los estadounidenses no solo temen cada vez m\u00e1s una mayor inflaci\u00f3n, con el presidente Donald Trump a punto de anunciar una serie de aranceles en pocos d\u00edas, sino que muchos m\u00e1s ahora temen un aumento del desempleo.La confianza del consumidor se desplom\u00f3 un 12% este mes, seg\u00fan inform\u00f3 la Universidad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1471170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1471170"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1471170\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1471170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1471170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1471170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}