{"id":1471205,"date":"2026-02-13T11:04:00","date_gmt":"2026-02-13T19:04:00","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/13\/trump-relacion-venezuela-10-elogia-delcy-trax\/"},"modified":"2026-02-13T11:04:00","modified_gmt":"2026-02-13T19:04:00","slug":"trump-relacion-venezuela-10-elogia-delcy-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/13\/trump-relacion-venezuela-10-elogia-delcy-trax\/","title":{"rendered":"Trump afirma que la relaci\u00f3n con Venezuela &#171;ahora es un 10&#187; y elogia a Delcy Rodr\u00edguez"},"content":{"rendered":"<p>El presidente de EE.UU., Donald Trump, elogi\u00f3 este viernes a la presidenta encargada de Venezuela, Delcy Rodr\u00edguez, mientras se preparaba para reunirse con militares estadounidenses involucrados en la operaci\u00f3n que captur\u00f3 a Nicol\u00e1s Maduro. Trump afirm\u00f3 que la relaci\u00f3n entre ambos pa\u00edses \u201cahora es un 10\u201d.<\/p>\n<p>\u201cTenemos una muy buena relaci\u00f3n con la presidenta de Venezuela, como saben. Estamos trabajando muy estrechamente\u2026 La relaci\u00f3n que tenemos ahora mismo con Venezuela es un 10\u201d, declar\u00f3 Trump a los periodistas mientras se preparaba para partir de la Casa Blanca hacia Fort Bragg, Carolina del Norte.<\/p>\n<p>Y a\u00f1adi\u00f3: \u201cHan hecho un gran trabajo. Ella ha hecho\u2026 Delcy ha hecho un trabajo muy, muy bueno, y la relaci\u00f3n es s\u00f3lida\u201d.<\/p>\n<p>Trump destac\u00f3 la cooperaci\u00f3n con Venezuela en la producci\u00f3n y refinaci\u00f3n de petr\u00f3leo.<\/p>\n<p>\u201cEn este momento, la relaci\u00f3n con Venezuela es la mejor posible\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Dijo que har\u00eda una visita a Venezuela, pero que a\u00fan no ha decidido la fecha.<\/p>\n<p>Esta semana, Delcy Rodr\u00edguez afirm\u00f3 que fue invitada a una visita a Estados Unidos, sin dar una fecha espec\u00edfica, y asegur\u00f3 que el derrocado l\u00edder Nicol\u00e1s Maduro contin\u00faa siendo el mandatario leg\u00edtimo del pa\u00eds sudamericano.<\/p>\n<p>\u201cHe sido invitada a Estados Unidos\u201d, dijo Rodr\u00edguez a <a href=\"https:\/\/www.nbcnews.com\/world\/venezuela\/maduro-legitimate-president-venezuela-delcy-rodriguez-interview-trump-rcna258687\">NBC News<\/a>, en su primera entrevista con un medio internacional desde que asumi\u00f3 como titular encargada del Ejecutivo tras la captura de Maduro.<\/p>\n<p>\u201cEstamos contemplando ir una vez que establezcamos la cooperaci\u00f3n y podamos avanzar con todo\u201d, agreg\u00f3 Rodr\u00edguez, quien el mi\u00e9rcoles recibi\u00f3 en Caracas al secretario de Energ\u00eda de EE.UU., Chris Wright, para trabajar la agenda del sector. El funcionario estadounidense <a href=\"https:\/\/cnnespanol.cnn.com\/venezuela\/live-news\/secretario-energia-eeuu-visita-orix?post-id=cmliultgm0000356rgyrzp724\">declar\u00f3<\/a> a la prensa que habr\u00e1 \u201cun giro absolutamente dr\u00e1stico\u201d en el estado de las relaciones bilaterales.<\/p>\n<p>De confirmarse el viaje de Rodr\u00edguez, ser\u00eda la primera gobernante de Venezuela en ir a Estados Unidos en <a href=\"https:\/\/history.state.gov\/departmenthistory\/visits\/venezuela\">m\u00e1s de 30 a\u00f1os<\/a>, excluyendo las participaciones en la ONU y otros foros internacionales.<\/p>\n<p>Rodr\u00edguez, como en varios de sus pronunciamientos desde el 3 de enero, asegur\u00f3 que Maduro es inocente de los cargos por los que enfrenta un juicio en Nueva York y consider\u00f3 que contin\u00faa siendo el presidente leg\u00edtimo. \u201cPuedo decirte esto como abogada, que lo soy. El presidente Maduro y Cilia Flores, la primera dama, son inocentes\u201d, dijo a NBC.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de EE.UU., Donald Trump, elogi\u00f3 este viernes a la presidenta encargada de Venezuela, Delcy Rodr\u00edguez, mientras se preparaba para reunirse con militares estadounidenses involucrados en la operaci\u00f3n que captur\u00f3 a Nicol\u00e1s Maduro. Trump afirm\u00f3 que la relaci\u00f3n entre ambos pa\u00edses \u201cahora es un 10\u201d. \u201cTenemos una muy buena relaci\u00f3n con la presidenta de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1471205","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump afirma que la relaci\u00f3n con Venezuela &quot;ahora es un 10&quot; y elogia a Delcy Rodr\u00edguez - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/13\/trump-relacion-venezuela-10-elogia-delcy-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump afirma que la relaci\u00f3n con Venezuela &quot;ahora es un 10&quot; y elogia a Delcy Rodr\u00edguez - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente de EE.UU., Donald Trump, elogi\u00f3 este viernes a la presidenta encargada de Venezuela, Delcy Rodr\u00edguez, mientras se preparaba para reunirse con militares estadounidenses involucrados en la operaci\u00f3n que captur\u00f3 a Nicol\u00e1s Maduro. Trump afirm\u00f3 que la relaci\u00f3n entre ambos pa\u00edses \u201cahora es un 10\u201d. \u201cTenemos una muy buena relaci\u00f3n con la presidenta de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/13\/trump-relacion-venezuela-10-elogia-delcy-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-13T19:04:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/13\/trump-relacion-venezuela-10-elogia-delcy-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/13\/trump-relacion-venezuela-10-elogia-delcy-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump afirma que la relaci\u00f3n con Venezuela &#171;ahora es un 10&#187; y elogia a Delcy Rodr\u00edguez\",\"datePublished\":\"2026-02-13T19:04:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/13\/trump-relacion-venezuela-10-elogia-delcy-trax\/\"},\"wordCount\":439,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/13\/trump-relacion-venezuela-10-elogia-delcy-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/13\/trump-relacion-venezuela-10-elogia-delcy-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/13\/trump-relacion-venezuela-10-elogia-delcy-trax\/\",\"name\":\"Trump afirma que la relaci\u00f3n con Venezuela \\\"ahora es un 10\\\" y elogia a Delcy Rodr\u00edguez - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-13T19:04:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/13\/trump-relacion-venezuela-10-elogia-delcy-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/13\/trump-relacion-venezuela-10-elogia-delcy-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/13\/trump-relacion-venezuela-10-elogia-delcy-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump afirma que la relaci\u00f3n con Venezuela &#171;ahora es un 10&#187; y elogia a Delcy Rodr\u00edguez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump afirma que la relaci\u00f3n con Venezuela \"ahora es un 10\" y elogia a Delcy Rodr\u00edguez - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/13\/trump-relacion-venezuela-10-elogia-delcy-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trump afirma que la relaci\u00f3n con Venezuela \"ahora es un 10\" y elogia a Delcy Rodr\u00edguez - Noticias","og_description":"El presidente de EE.UU., Donald Trump, elogi\u00f3 este viernes a la presidenta encargada de Venezuela, Delcy Rodr\u00edguez, mientras se preparaba para reunirse con militares estadounidenses involucrados en la operaci\u00f3n que captur\u00f3 a Nicol\u00e1s Maduro. Trump afirm\u00f3 que la relaci\u00f3n entre ambos pa\u00edses \u201cahora es un 10\u201d. \u201cTenemos una muy buena relaci\u00f3n con la presidenta de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/13\/trump-relacion-venezuela-10-elogia-delcy-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-13T19:04:00+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/13\/trump-relacion-venezuela-10-elogia-delcy-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/13\/trump-relacion-venezuela-10-elogia-delcy-trax\/"},"author":{"name":"","@id":""},"headline":"Trump afirma que la relaci\u00f3n con Venezuela &#171;ahora es un 10&#187; y elogia a Delcy Rodr\u00edguez","datePublished":"2026-02-13T19:04:00+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/13\/trump-relacion-venezuela-10-elogia-delcy-trax\/"},"wordCount":439,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/13\/trump-relacion-venezuela-10-elogia-delcy-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/13\/trump-relacion-venezuela-10-elogia-delcy-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/13\/trump-relacion-venezuela-10-elogia-delcy-trax\/","name":"Trump afirma que la relaci\u00f3n con Venezuela \"ahora es un 10\" y elogia a Delcy Rodr\u00edguez - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-13T19:04:00+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/13\/trump-relacion-venezuela-10-elogia-delcy-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/13\/trump-relacion-venezuela-10-elogia-delcy-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/13\/trump-relacion-venezuela-10-elogia-delcy-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump afirma que la relaci\u00f3n con Venezuela &#171;ahora es un 10&#187; y elogia a Delcy Rodr\u00edguez"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/13\/trump-relacion-venezuela-10-elogia-delcy-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump afirma que la relaci\u00f3n con Venezuela &#171;ahora es un 10&#187; y elogia a Delcy Rodr\u00edguez","url":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/13\/trump-relacion-venezuela-10-elogia-delcy-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/13\/trump-relacion-venezuela-10-elogia-delcy-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-13T19:04:00Z","datePublished":"2026-02-13T19:04:00Z","dateModified":"2026-02-13T19:04:00Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump afirma que la relaci\\u00f3n con Venezuela &#171;ahora es un 10&#187; y elogia a Delcy Rodr\\u00edguez\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/13\\\/trump-relacion-venezuela-10-elogia-delcy-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/13\\\/trump-relacion-venezuela-10-elogia-delcy-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-13T19:04:00Z\",\"datePublished\":\"2026-02-13T19:04:00Z\",\"dateModified\":\"2026-02-13T19:04:00Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1471230,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/14\/maria-corina-machado-eeuu-derrocamiento-maduro-trax\/","url_meta":{"origin":1471205,"position":0},"title":"Mar\u00eda Corina Machado elogia el papel de EE.UU. en el derrocamiento de Maduro","author":"","date":"febrero 14, 2026","format":false,"excerpt":"La l\u00edder opositora venezolana Mar\u00eda Corina Machado dijo que Estados Unidos arriesg\u00f3 la vida de sus ciudadanos para derrocar la dictadura de Nicol\u00e1s Maduro en Venezuela, por lo cual dedic\u00f3 su Premio Nobel de la Paz al presidente de EE.UU., Donald Trump.En su intervenci\u00f3n este s\u00e1bado en la Conferencia de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470536,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/01\/27\/trump-venezuela-delcy-rodriguez-ya-basta-trax\/","url_meta":{"origin":1471205,"position":1},"title":"Trump dice que no hab\u00eda escuchado que la presidenta encargada de Venezuela dijera que &#171;ya basta&#187; de las \u00f3rdenes de EE.UU.","author":"","date":"enero 27, 2026","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, dijo este martes que no estaba al tanto de los comentarios de la presidenta encargada de Venezuela, Delcy Rodr\u00edguez, en los que afirm\u00f3 que \u201cya basta\u201d de recibir \u00f3rdenes de Washington, y rest\u00f3 importancia a cualquier posible tensi\u00f3n entre ambos gobiernos.\u201cBueno, no s\u00e9\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470505,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/01\/26\/delcy-rodriguez-eeuu-no-tenemos-miedo-orix\/","url_meta":{"origin":1471205,"position":2},"title":"Delcy Rodr\u00edguez insiste en que Venezuela no se subordina a EE.UU.: &#171;No tenemos miedo a relaciones de respeto&#187;","author":"","date":"enero 26, 2026","format":false,"excerpt":"La presidenta interina de Venezuela, Delcy Rodr\u00edguez, insisti\u00f3 este lunes en que el pa\u00eds sudamericano no se subordina a Estados Unidos, con el argumento de que no obedece a factores externos y no tiene miedo a \u201crelaciones de respeto\u201d con la naci\u00f3n gobernada por Donald Trump.\u201cNo tenemos otro factor externo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472139,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/03\/12\/trump-reconocimiento-oficial-delcy-rodriguez-venezuela-orix\/","url_meta":{"origin":1471205,"position":3},"title":"El Gobierno de Trump notifica con una carta que reconoce a Delcy Rodr\u00edguez como &#171;la \u00fanica jefa de Estado&#187; en Venezuela","author":"","date":"marzo 12, 2026","format":false,"excerpt":"El Gobierno de Donald Trump notific\u00f3 a la Justicia de Estados Unidos sobre el reconocimiento oficial de Delcy Rodr\u00edguez como gobernante de Venezuela. En una carta enviada por el encargado para Latinoam\u00e9rica del Departamento de Estado, Michael Kozak, al fiscal Jay Clayton, quien lleva el caso contra el derrocado presidente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472936,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/07\/trump-bromea-postularse-presidente-venezuela-orix\/","url_meta":{"origin":1471205,"position":4},"title":"Trump bromea sobre su popularidad en Venezuela: &#171;Me postular\u00e9 a la presidencia&#187;","author":"","date":"abril 7, 2026","format":false,"excerpt":"En medio de la tensi\u00f3n mundial por la guerra en Ir\u00e1n, el presidente de Estados Unidos, Donald Trump, se dio tiempo para bromear sobre su popularidad en Venezuela.\u201cEn las encuestas estoy m\u00e1s alto que nadie\u201d, dijo Trump este lunes en una rueda de prensa sobre la misi\u00f3n de rescate de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471137,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/12\/rodriguez-wright-venezuela-ee-uu-agenda-energetica-bilateral-trax\/","url_meta":{"origin":1471205,"position":5},"title":"Delcy Rodr\u00edguez y Chris Wright afirman que Venezuela y EE.UU. trabajan en una &#171;agenda energ\u00e9tica&#187; bilateral","author":"","date":"febrero 12, 2026","format":false,"excerpt":"La presidenta encargada de Venezuela, Delcy Rodr\u00edguez, y el secretario de Energ\u00eda de Estados Unidos, Chris Wright, emitieron este mi\u00e9rcoles una declaraci\u00f3n conjunta en la que aseguraron que ambos pa\u00edses trabajan en una \u201cagenda energ\u00e9tica\u201d com\u00fan y \u201ca largo tiempo\u201d.Rodr\u00edguez y Wright sostuvieron este mi\u00e9rcoles una reuni\u00f3n en el Palacio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1471205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1471205"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1471205\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1471205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1471205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1471205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}