{"id":1471241,"date":"2026-02-14T19:03:51","date_gmt":"2026-02-15T03:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/14\/inteligencia-artificial-crisis-desaparecidos-mexico-orix\/"},"modified":"2026-02-14T19:03:51","modified_gmt":"2026-02-15T03:03:51","slug":"inteligencia-artificial-crisis-desaparecidos-mexico-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/14\/inteligencia-artificial-crisis-desaparecidos-mexico-orix\/","title":{"rendered":"Del reconocimiento de tatuajes a la progresi\u00f3n de edad: as\u00ed se utiliza la IA en la crisis de desaparecidos en M\u00e9xico"},"content":{"rendered":"<p>H\u00e9ctor Flores recuerda la primera vez\u202fque vio\u202fun video de su hijo\u202fH\u00e9ctor Daniel Flores Hern\u00e1ndez, reportado como desaparecido en 2021 en el que \u2014por medio de inteligencia artificial\u2014 narra la historia de su desaparici\u00f3n y exige a las autoridades ser hallado con vida.<\/p>\n<p>La tecnolog\u00eda de Inteligencia Artificial (IA) utiliza fotograf\u00edas de la persona desparecida para generar un video animado donde parece que la misma persona est\u00e1 hablando, combinando la imagen fija con movimiento digital y voz sintetizada.<\/p>\n<p>\u201cCuando vi a mi hijo, fue el primer video que sali\u00f3, no lo pude terminar de ver la primera vez, tard\u00e9 en asimilarlo.\u202fVerlos con su \u00faltima foto que tienes y contar lo que uno sabe con las investigaciones es desgarrador\u201d,\u202f<a href=\"https:\/\/cnnespanol.cnn.com\/video\/inteligencia-artificial-retorna-personas-desaparecidos-perspectivas-mexico-tv\">dijo previamente<\/a>\u202fa CNN.<\/p>\n<p>El video es parte de una iniciativa lanzada en 2023 por parte de los colectivos Luz de Esperanza y Alas de Libertad \u2014agrupaciones de familiares de personas desaparecidas que se organizan para realizar b\u00fasquedas, visibilizar casos, y exigir justicia\u2014\u202fen el estado occidental de Jalisco, para dar voz a las fichas de b\u00fasqueda de sus familiares.<\/p>\n<p>M\u00e1s de dos a\u00f1os despu\u00e9s, Flores \u2014cofundador de Luz de Esperanza\u2014 dice a CNN que la iniciativa contin\u00faa y que ha tenido un \u201cimpacto muy fuerte tanto para las familias como para la sociedad\u2026 la visibilidad, fue algo que trascendi\u00f3 fronteras y es una herramienta perfecta no solo para la b\u00fasqueda sino tambi\u00e9n para concientizar y tratar de empatizar\u201d.<\/p>\n<p>Como este, otros proyectos que utilizan IA se han puesto en marcha con el objetivo de ayudar a la crisis de desaparecidos en M\u00e9xico, un pa\u00eds que suma m\u00e1s de 132.000 v\u00edctimas, seg\u00fan el Registro Nacional de Personas Desaparecidas y No Localizadas (RNPDNO) de la Secretar\u00eda de Gobernaci\u00f3n\u202fy en el que, de acuerdo con\u202f<a href=\"https:\/\/www.hrw.org\/world-report\/2026\/country-chapters\/mexico#:~:text=trafficking%20of%20diesel.-,Disappearances,had%20been%20killed%20in%202025.\">Human Rights Watch<\/a>, el Gobierno no ha tomado medidas suficientes para prevenirla.<\/p>\n<p>La presidenta Claudia Sheinbaum\u202f<a href=\"https:\/\/www.gob.mx\/presidencia\/prensa\/presidenta-claudia-sheinbaum-anuncia-seis-acciones-inmediatas-contra-el-delito-de-desaparicion\">ha se\u00f1alado<\/a>\u202fque su gobierno trabaja para atender el problema de personas desaparecidas y no localizadas y su compromiso con las familias a esclarecer los hechos y que haya justicia. En marzo de 2025,\u202fel Gobierno mexicano,\u202fanunci\u00f3 seis acciones inmediatas contra el delito de desaparici\u00f3n: fortalecimiento de la Comisi\u00f3n Nacional de B\u00fasqueda, reformas legislativas, nuevos protocolos de b\u00fasqueda inmediata, equiparaci\u00f3n del delito de desaparicion al delito de secuestro, transparencia en cifras con publicaci\u00f3n mensual de carpetas de investigaci\u00f3n, y el fortalecimiento de la Comisi\u00f3n Ejecutiva de Atenci\u00f3n de V\u00edctimas.<\/p>\n<p>No existen datos oficiales completos sobre las causas espec\u00edficas de todas las desapariciones. El registro comenz\u00f3 en la d\u00e9cada de 1960 e incluye datos de desapariciones contra grupos de izquierda y la guerrilla, pero las cifras son mayormente de los \u00faltimos a\u00f1os, cuando se intensific\u00f3 la lucha contra organizaciones criminales. La presidenta Claudia Sheinbaum <a href=\"https:\/\/www.gob.mx\/presidencia\/articulos\/version-estenografica-conferencia-de-prensa-de-la-presidenta-claudia-sheinbaum-pardo-del-27-de-octubre-de-2025?idiom=es\">ha reconocido<\/a> que la mayor\u00eda de las desapariciones est\u00e1n vinculadas a la delincuencia organizada y Amnist\u00eda Internacional se\u00f1ala que la crisis <a href=\"https:\/\/www.es.amnesty.org\/en-que-estamos\/blog\/historia\/articulo\/desapariciones-forzadas-quien-sabe-donde-en-mexico\/\">puede atribuirse<\/a> al contexto de violencia e inseguridad.<\/p>\n<p>En medio de la situaci\u00f3n, universidades, colectivos de b\u00fasqueda, organizaciones y autoridades han desarrollado e implementado la IA para la investigaci\u00f3n y localizaci\u00f3n de desaparecidos con proyectos que incluyen el an\u00e1lisis de bases de datos, identificaci\u00f3n forense o proyecciones de envejecimiento.<\/p>\n<p>\u201cLo que se busca es que estas herramientas sean de utilidad para instancias que conforman el sistema nacional de b\u00fasqueda como son las fiscal\u00edas, las comisiones y los Semefo [Servicios M\u00e9dicos Forenses], que auxilien y hagan m\u00e1s sencillo el trabajo de las personas\u201d, dice a CNN Andrea Horcasitas, encargada del Programa de Derechos Humanos de la Universidad Iberoamericana en Ciudad de M\u00e9xico, que forma parte del Consorcio para el Uso \u00c9tico de la IA en la B\u00fasqueda de Personas Desaparecidas.<\/p>\n<p>El Laboratorio de Soluciones Colaborativas de Pol\u00edticas P\u00fablicas (<a href=\"https:\/\/www.lab-co.org\/\">Lab-Co<\/a>), una\u202forganizaci\u00f3n no gubernamental\u202fen Am\u00e9rica Latina\u202fcon sede en M\u00e9xico, cuyo objetivo es generar innovaciones y soluciones a los problemas en la regi\u00f3n en materia de seguridad, violencia y acceso a la justicia, ha desarrollado tres proyectos que incorporan la inteligencia artificial en la b\u00fasqueda de desaparecidos.<\/p>\n<p>El primero es IdentIA, una herramienta que utiliza IA para identificar y clasificar fotograf\u00edas de tatuajes de personas no identificadas con el fin de facilitar as\u00ed la b\u00fasqueda en los registros de personas sin identificar, explica a CNN Thomas Favennec, director ejecutivo de Lab-Co.<\/p>\n<p>Opera mediante la b\u00fasqueda por texto asociada a la palabra o descripci\u00f3n del tatuaje (una figura, una palabra, etc.) y por b\u00fasqueda por imagen que compara fotograf\u00edas directamente en una base hist\u00f3rica de tatuajes de personas sin identificar.<\/p>\n<p>\u201cNo importa la calidad del tatuaje ni el \u00e1ngulo, este sistema funciona mediante una b\u00fasqueda de vectores y no necesita internet, no se sube nada de contenido sensible a internet, esto permite que no se vulnere la informaci\u00f3n de nadie\u201d, detalla \u00c1ngel Serrano, coordinador de datos y tecnolog\u00eda de Lab-Co.<\/p>\n<p>En una demostraci\u00f3n a CNN, Serrano mostr\u00f3 c\u00f3mo IdentIA realiza la b\u00fasqueda de un tatuaje en cuesti\u00f3n de segundos y permite el cruce de informaci\u00f3n con reportes de personas desaparecidas.<\/p>\n<p>Este sistema se incorpor\u00f3 esta semana a los sistemas institucionales en el estado de Jalisco y est\u00e1 en proceso de implementaci\u00f3n en los servicios periciales de Quintana Roo y Zacatecas.<\/p>\n<p>Favennec agrega que otra de sus herramientas en curso es ContextView, un apoyo para el an\u00e1lisis de contexto que permite procesar m\u00faltiples documentos no estructurados de carpetas de investigaci\u00f3n y extraer datos claros, lo que ayuda a las personas que hacen an\u00e1lisis de b\u00fasqueda en instituciones oficiales.<\/p>\n<p>Es capaz de hacer consultas espec\u00edficas con citas textuales y referencia de p\u00e1ginas, extracci\u00f3n de datos particulares como tel\u00e9fonos, placas vehiculares y coordenadas y, como su nombre lo indica, hacer un an\u00e1lisis contextual.<\/p>\n<p>El tercer esquema permite analizar nombres de forma estructurada y m\u00e1s potente para encontrar las coincidencias en distintas bases de datos que tienen nombres escritos de formas diferentes. Favennec explica que se ha aplicado a la fecha para personas fallecidas identificadas, pero no reclamadas.<\/p>\n<p>\u201cLas familias no saben que esto sucede y es complicado porque hay un tema de bases de datos que no se cruzan. Ah\u00ed hay un desaf\u00edo que es buscar a la familia. Entonces, lo nuevo que hemos desarrollado es algo que permite hacer esos an\u00e1lisis de comparaci\u00f3n entre la situaci\u00f3n de personas desaparecidas y los registros de servicios forenses en distintos estados del pa\u00eds\u201d, detalla.<\/p>\n<p>Las iniciativas son parte del proyecto \u201cConstruyendo Alianzas para la b\u00fasqueda de personas desaparecidas y la identificaci\u00f3n humana\u201d, financiado por la Uni\u00f3n Europea y la Embajada Brit\u00e1nica a trav\u00e9s de la iniciativa Frontier Tech Hub.<\/p>\n<p>Horcasitas, de la Universidad Iberoamericana, se\u00f1ala que hay una herramienta llamada ImageBox que ya se utiliza en algunas fiscal\u00edas que permite limpiar los rostros de las personas que se encuentran en la morgue o el Servicio M\u00e9dico Forense y el Instituto de Servicios Periciales y Ciencias Forenses de Ciudad de M\u00e9xico (Incifo) para auxiliar en el reconocimiento de las personas.<\/p>\n<p>\u201cEsto evita que las personas se enfrenten a ver las fotograf\u00edas desgarradoras, que obviamente tienen impactos psicosociales y cualquier persona que tenga que ver los cat\u00e1logos de las morgues\u201d, detall\u00f3.<\/p>\n<p>La Fiscal\u00eda de Ciudad de M\u00e9xico ha utilizado la t\u00e9cnica de \u201cinpainting\u201d que utiliza la inteligencia artificial para rellenar, restaurar o eliminar partes seleccionadas de una imagen, lo que permite a\u00f1adir o reparar zonas da\u00f1adas con resultados realistas. Con esto, las autoridades realizan b\u00fasquedas inversas, es decir, que, en lugar de buscar a la persona desaparecida, se emite un bolet\u00edn para encontrar a la familia.<\/p>\n<p>CNN contact\u00f3 a la Fiscal\u00eda capitalina para obtener m\u00e1s detalles, pero hasta el momento no ha obtenido respuesta.<\/p>\n<p>El Proyecto Regresa,\u202fdesarrollado por investigadores\u202fde la Universidad Nacional Aut\u00f3noma de M\u00e9xico (UNAM), busca generar una imagen de c\u00f3mo se ver\u00eda en la actualidad un ni\u00f1o que desapareci\u00f3 a\u00f1os atr\u00e1s, para ayudar as\u00ed a sus familiares a encontrarlo.<\/p>\n<p>La premisa de esta iniciativa se basa en que cuando una persona desaparece, el protocolo de b\u00fasqueda se basa en la fotograf\u00eda m\u00e1s reciente que se tiene y en el caso de ni\u00f1os y adolescentes que no son localizados r\u00e1pidamente podr\u00edan no ser reconocidos en el mediano y largo plazo debido a la velocidad con la que cambian y maduran sus rostros y cuerpos.<\/p>\n<p>Encabezado por Ana Itzel Ju\u00e1rez Mart\u00edn, doctora en Antropolog\u00eda de la Universidad Nacional Aut\u00f3noma de M\u00e9xico (UNAM), la iniciativa combina herramientas de IA con conocimientos y t\u00e9cnicas de Antropolog\u00eda F\u00edsica y Social.<\/p>\n<p>La idea del algoritmo \u2013que a\u00fan es un programa piloto\u2013 es realizar la progresi\u00f3n de edad utilizando fotograf\u00edas de ni\u00f1os desaparecidos para determinar c\u00f3mo se ver\u00e1n a los 5 a\u00f1os, a los 15 o a los 30. Tambi\u00e9n ser\u00eda capaz de saber c\u00f3mo se ve\u00eda un adulto en la infancia.<\/p>\n<p>Las cifras oficiales\u202f<a href=\"https:\/\/blog.derechosinfancia.org.mx\/2025\/09\/05\/ninez-y-adolescencia-desaparecida-en-mexico-a-5-de-septiembre-de-2025\/\">contabilizan m\u00e1s de 118.000<\/a>\u202fmenores entre 0 y 17 a\u00f1os reportados como desaparecidos desde 1964 hasta septiembre de 2025.\u202fUn informe de 2022 de la Red por los Derechos de la Infancia en M\u00e9xico se\u00f1ala que en el caso de la desaparici\u00f3n de menores est\u00e1n involucradas redes de reclutamiento para integrarlos al crimen organizado o para trata y explotaci\u00f3n sexual.<\/p>\n<p>Ju\u00e1rez Mart\u00edn\u202f<a href=\"https:\/\/www.politicas.unam.mx\/cea\/?page_id=1796\">explic\u00f3<\/a>\u202fque la intenci\u00f3n del proyecto Regresa es entrenar el algoritmo para que aprenda cu\u00e1l es el crecimiento biol\u00f3gico natural del rostro y que identifique la variabilidad poblacional del mexicano y su crecimiento.<\/p>\n<p>\u201cAunque ya existen algunos bancos de im\u00e1genes para uso de investigaci\u00f3n, no los hay so\u00f3lo de poblaci\u00f3n mexicana, por lo que este algoritmo ser\u00eda el primero de este tipo y se entrenar\u00eda para identificar la variabilidad que existe en el mexicano, por ejemplo, su tipo de nariz, grosor de labios, forma de ojos y cejas\u201d, dijo.<\/p>\n<p>En un pa\u00eds en el que,\u202fseg\u00fan\u202fla organizaci\u00f3n Causa en Com\u00fan, cada d\u00eda\u202fdesaparecen\u202f41 personas\u202fal d\u00eda, es importante contar con herramientas que ayuden y faciliten la b\u00fasqueda de desaparecidos en todo el pa\u00eds.<\/p>\n<p>Lo que sigue es seguir buscando los vac\u00edos o aquellos huecos donde se necesita hacer m\u00e1s eficientes ciertos procesos. \u201cEstamos en el espera de ver c\u00f3mo operan estas herramientas de inteligencia artificial, ver si funcionan, ver las mejoras que se tengan que hacer, y tambi\u00e9n entender cu\u00e1l es el flujo de trabajo dentro de las instancias que conforman al Sistema Nacional de B\u00fasqueda\u201d, dice Horcasitas.<\/p>\n<p>Favennec dice que la implementaci\u00f3n de la IA en los procesos de b\u00fasqueda y localizaci\u00f3n ha sido bien recibido por colectivos y autoridades, pero agrega que es necesario saber que la tecnolog\u00eda \u201cno es magia, ayuda a procesar m\u00e1s r\u00e1pido y mejor la informaci\u00f3n [\u2026] pero en una crisis donde se mezclan tantas cosas de tantas diferentes formas, lo que se necesita es colaboraci\u00f3n\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>H\u00e9ctor Flores recuerda la primera vez\u202fque vio\u202fun video de su hijo\u202fH\u00e9ctor Daniel Flores Hern\u00e1ndez, reportado como desaparecido en 2021 en el que \u2014por medio de inteligencia artificial\u2014 narra la historia de su desaparici\u00f3n y exige a las autoridades ser hallado con vida. La tecnolog\u00eda de Inteligencia Artificial (IA) utiliza fotograf\u00edas de la persona desparecida para [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1471241","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Del reconocimiento de tatuajes a la progresi\u00f3n de edad: as\u00ed se utiliza la IA en la crisis de desaparecidos en M\u00e9xico - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/14\/inteligencia-artificial-crisis-desaparecidos-mexico-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Del reconocimiento de tatuajes a la progresi\u00f3n de edad: as\u00ed se utiliza la IA en la crisis de desaparecidos en M\u00e9xico - Noticias\" \/>\n<meta property=\"og:description\" content=\"H\u00e9ctor Flores recuerda la primera vez\u202fque vio\u202fun video de su hijo\u202fH\u00e9ctor Daniel Flores Hern\u00e1ndez, reportado como desaparecido en 2021 en el que \u2014por medio de inteligencia artificial\u2014 narra la historia de su desaparici\u00f3n y exige a las autoridades ser hallado con vida. La tecnolog\u00eda de Inteligencia Artificial (IA) utiliza fotograf\u00edas de la persona desparecida para [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/14\/inteligencia-artificial-crisis-desaparecidos-mexico-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-15T03:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/14\/inteligencia-artificial-crisis-desaparecidos-mexico-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/14\/inteligencia-artificial-crisis-desaparecidos-mexico-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Del reconocimiento de tatuajes a la progresi\u00f3n de edad: as\u00ed se utiliza la IA en la crisis de desaparecidos en M\u00e9xico\",\"datePublished\":\"2026-02-15T03:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/14\/inteligencia-artificial-crisis-desaparecidos-mexico-orix\/\"},\"wordCount\":1960,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/14\/inteligencia-artificial-crisis-desaparecidos-mexico-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/14\/inteligencia-artificial-crisis-desaparecidos-mexico-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/14\/inteligencia-artificial-crisis-desaparecidos-mexico-orix\/\",\"name\":\"Del reconocimiento de tatuajes a la progresi\u00f3n de edad: as\u00ed se utiliza la IA en la crisis de desaparecidos en M\u00e9xico - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-15T03:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/14\/inteligencia-artificial-crisis-desaparecidos-mexico-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/14\/inteligencia-artificial-crisis-desaparecidos-mexico-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/14\/inteligencia-artificial-crisis-desaparecidos-mexico-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Del reconocimiento de tatuajes a la progresi\u00f3n de edad: as\u00ed se utiliza la IA en la crisis de desaparecidos en M\u00e9xico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Del reconocimiento de tatuajes a la progresi\u00f3n de edad: as\u00ed se utiliza la IA en la crisis de desaparecidos en M\u00e9xico - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/14\/inteligencia-artificial-crisis-desaparecidos-mexico-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Del reconocimiento de tatuajes a la progresi\u00f3n de edad: as\u00ed se utiliza la IA en la crisis de desaparecidos en M\u00e9xico - Noticias","og_description":"H\u00e9ctor Flores recuerda la primera vez\u202fque vio\u202fun video de su hijo\u202fH\u00e9ctor Daniel Flores Hern\u00e1ndez, reportado como desaparecido en 2021 en el que \u2014por medio de inteligencia artificial\u2014 narra la historia de su desaparici\u00f3n y exige a las autoridades ser hallado con vida. La tecnolog\u00eda de Inteligencia Artificial (IA) utiliza fotograf\u00edas de la persona desparecida para [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/14\/inteligencia-artificial-crisis-desaparecidos-mexico-orix\/","og_site_name":"Noticias","article_published_time":"2026-02-15T03:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/14\/inteligencia-artificial-crisis-desaparecidos-mexico-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/14\/inteligencia-artificial-crisis-desaparecidos-mexico-orix\/"},"author":{"name":"","@id":""},"headline":"Del reconocimiento de tatuajes a la progresi\u00f3n de edad: as\u00ed se utiliza la IA en la crisis de desaparecidos en M\u00e9xico","datePublished":"2026-02-15T03:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/14\/inteligencia-artificial-crisis-desaparecidos-mexico-orix\/"},"wordCount":1960,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/14\/inteligencia-artificial-crisis-desaparecidos-mexico-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/14\/inteligencia-artificial-crisis-desaparecidos-mexico-orix\/","url":"https:\/\/noticiasya.com\/2026\/02\/14\/inteligencia-artificial-crisis-desaparecidos-mexico-orix\/","name":"Del reconocimiento de tatuajes a la progresi\u00f3n de edad: as\u00ed se utiliza la IA en la crisis de desaparecidos en M\u00e9xico - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-15T03:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/14\/inteligencia-artificial-crisis-desaparecidos-mexico-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/14\/inteligencia-artificial-crisis-desaparecidos-mexico-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/14\/inteligencia-artificial-crisis-desaparecidos-mexico-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Del reconocimiento de tatuajes a la progresi\u00f3n de edad: as\u00ed se utiliza la IA en la crisis de desaparecidos en M\u00e9xico"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/14\/inteligencia-artificial-crisis-desaparecidos-mexico-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Del reconocimiento de tatuajes a la progresi\u00f3n de edad: as\u00ed se utiliza la IA en la crisis de desaparecidos en M\u00e9xico","url":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/14\/inteligencia-artificial-crisis-desaparecidos-mexico-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/14\/inteligencia-artificial-crisis-desaparecidos-mexico-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-15T03:03:51Z","datePublished":"2026-02-15T03:03:51Z","dateModified":"2026-02-15T03:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Del reconocimiento de tatuajes a la progresi\\u00f3n de edad: as\\u00ed se utiliza la IA en la crisis de desaparecidos en M\\u00e9xico\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/14\\\/inteligencia-artificial-crisis-desaparecidos-mexico-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/14\\\/inteligencia-artificial-crisis-desaparecidos-mexico-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-15T03:03:51Z\",\"datePublished\":\"2026-02-15T03:03:51Z\",\"dateModified\":\"2026-02-15T03:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1456822,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/12\/20\/citas-apps-inteligencia-artificial-trax\/","url_meta":{"origin":1471241,"position":0},"title":"Las citas online est\u00e1n a punto de cambiar radicalmente","author":"","date":"diciembre 20, 2024","format":false,"excerpt":"Chatbots personalizados que tienen citas con otros chatbots en tu lugar. Conserjes de inteligencia artificial que responden a preguntas sobre posibles parejas. Algoritmos avanzados que predicen la compatibilidad mejor que nunca. Las aplicaciones de citas est\u00e1n a punto de experimentar una gran transformaci\u00f3n.Mientras gran parte de la industria tecnol\u00f3gica se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469179,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/12\/11\/portada-time-ia-mercado-caida-trax\/","url_meta":{"origin":1471241,"position":1},"title":"Por qu\u00e9 la portada de TIME con los l\u00edderes de la IA llega en un muy mal d\u00eda para ese sector","author":"","date":"diciembre 11, 2025","format":false,"excerpt":"Time anunci\u00f3 que los \u201carquitectos de la IA\u201d son su Persona del A\u00f1o. Sin duda, la inteligencia artificial cierra un a\u00f1o extraordinario y muchos ejecutivos del sector se han convertido en nombres reconocidos.Pero el gran anuncio anual de Time lleg\u00f3 en un d\u00eda p\u00e9simo para la industria.Las acciones de Oracle\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462796,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/05\/26\/primera-dama-ia-futuro-editorial-trax\/","url_meta":{"origin":1471241,"position":2},"title":"La primera dama afirma que la IA es el futuro del sector editorial. Ya est\u00e1 sucediendo","author":"","date":"mayo 26, 2025","format":false,"excerpt":"La primera dama Melania Trump lanz\u00f3 el jueves una versi\u00f3n en audiolibro de sus memorias en su propia voz, pero no ser\u00e1 ella quien las narre.\u201cEs un honor para m\u00ed presentarles Melania, el audiolibro con IA, narrado \u00edntegramente con inteligencia artificial y con mi propia voz\u201d, escribi\u00f3 en una publicaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467972,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/11\/03\/xania-monet-cantante-inteligencia-artificial-billboard-trax\/","url_meta":{"origin":1471241,"position":3},"title":"Xania Monet es la primera artista creada por IA en debutar en la cartelera Billboard, pero no ser\u00e1 la \u00faltima","author":"","date":"noviembre 3, 2025","format":false,"excerpt":"La Inteligencia Artificial est\u00e1 en todas partes y las listas de \u00e9xitos musicales no son la excepci\u00f3n.Seg\u00fan Billboard, una cantante de IA llamada Xania Monet es \u201cla primera artista de IA conocida en obtener suficiente reproducci\u00f3n en la radio para debutar en una lista de radio de Billboard\u201d.Hasta ahora, Monet\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469177,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/12\/11\/time-persona-del-ano-arquitectos-ia-orix\/","url_meta":{"origin":1471241,"position":4},"title":"La revista TIME nombra &#171;Persona del A\u00f1o&#187; a los &#171;arquitectos&#187; de la inteligencia artificial","author":"","date":"diciembre 11, 2025","format":false,"excerpt":"La revista TIME anunci\u00f3 este jueves su esperada edici\u00f3n de la \u201cPersona del A\u00f1o\u201d en la que design\u00f3 a los \u201carquitectos\u201d de la inteligencia artificial como las figuras m\u00e1s relevantes de 2025 para la publicaci\u00f3n.La designaci\u00f3n reconoce el impacto de la inteligencia artificial en el mundo y refleja c\u00f3mo esta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466121,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/09\/03\/video-ataque-eeuu-caribe-ia-trump-hegseth-orix\/","url_meta":{"origin":1471241,"position":5},"title":"Venezuela afirma que el video del ataque de EE.UU. en el Caribe fue hecho con IA y el Gobierno de Trump lo desmiente","author":"","date":"septiembre 3, 2025","format":false,"excerpt":"Luego del ataque de Estados Unidos contra una presunta embarcacai\u00f3n con drogas en el Caribe, Freddy \u00d1\u00e1\u00f1ez, ministro de Comunicaci\u00f3n e Informaci\u00f3n de Venezuela, asegur\u00f3 el martes en redes sociales que el video del ataque fue realizado con inteligencia artificial (IA) y que el secretario de Estado de EE.UU., Marco\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1471241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1471241"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1471241\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1471241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1471241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1471241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}