{"id":1471269,"date":"2026-02-16T01:03:46","date_gmt":"2026-02-16T09:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/16\/venta-carta-pokemon-logan-paul-record-trax\/"},"modified":"2026-02-16T01:03:46","modified_gmt":"2026-02-16T09:03:46","slug":"venta-carta-pokemon-logan-paul-record-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/16\/venta-carta-pokemon-logan-paul-record-trax\/","title":{"rendered":"Venden la &#171;joya de la corona&#187; de las cartas Pok\u00e9mon de Logan Paul por US$ 16,5 millones, con un collar de diamantes incluido"},"content":{"rendered":"<p>Hace cinco a\u00f1os, <a href=\"https:\/\/cnnespanol.cnn.com\/video\/logan-paul-mayweather-floyd-jr-resumen-video-canelo-jake-paul-exhibicion-boxeo-deportes-cnn-pkg\">Logan Paul<\/a> estableci\u00f3 un r\u00e9cord mundial al comprar una carta Pok\u00e9mon por US$ 5,27 millones. Result\u00f3 ser una inversi\u00f3n acertada: el influencer y luchador vendi\u00f3 esa carta por la asombrosa cifra de US$ 16,49 millones, con un collar incrustado de diamantes incluido.<\/p>\n<p>La rara carta Pikachu Illustrator \u2014una de solo 39 creadas para un concurso de ilustraci\u00f3n de Pok\u00e9mon a finales de los a\u00f1os 90\u2014 fue subastada en Goldin Auctions este lunes.<\/p>\n<p>Se cree que la estrella de la WWE obtuvo m\u00e1s de US$ 8 millones de ganancia despu\u00e9s de las comisiones de la subasta, una venta que calific\u00f3 de \u201cabsolutamente loca\u201d.<\/p>\n<p>La subasta hab\u00eda estado activa durante 42 d\u00edas, pero termin\u00f3 tras horas de pujas extendidas este lunes, con Paul diciendo \u201cpuede que hayamos cansado a alguien\u201d durante una transmisi\u00f3n en vivo en YouTube.<\/p>\n<p>\u201cOh, Dios m\u00edo, esto es una locura\u201d, a\u00f1adi\u00f3 una vez que la subasta cerr\u00f3 y cay\u00f3 confeti.<\/p>\n<p>Momentos despu\u00e9s, un representante de Guinness World Records apareci\u00f3 en pantalla y confirm\u00f3 que Paul hab\u00eda vendido la carta coleccionable m\u00e1s cara de la historia en una subasta.<\/p>\n<p>Esta vez, la carta se vendi\u00f3 dentro de un collar personalizado que Paul us\u00f3 en WrestleMania 38 y con su promesa de entregarla personalmente al comprador ganador.<\/p>\n<p>Pok\u00e9mon es la franquicia medi\u00e1tica m\u00e1s lucrativa del mundo, superando incluso a Disney y Star Wars. Las cartas han disparado su valor, superando a las cartas deportivas y al \u00edndice burs\u00e1til S&#038;P en un 3.000 % en los \u00faltimos 20 a\u00f1os, <a href=\"https:\/\/www.cnn.com\/2025\/12\/24\/entertainment\/video\/pokemon-trading-cards-netflix-series-king-of-collectibles-logan-paul-ken-goldin-tsi\">dijo a CNN<\/a> en diciembre Ken Goldin, fundador y CEO de Goldin, despu\u00e9s de que Logan confirmara que subastar\u00eda la carta.<\/p>\n<p>\u201cEsta es la carta coleccionable m\u00e1s codiciada del mundo\u201d, dijo.<\/p>\n<p>Goldin explic\u00f3 que la carta Illustrator es considerada \u201cla joya de la corona de todas las cartas Pok\u00e9mon\u201d y que la carta de Paul es la que todos quieren porque es pr\u00e1cticamente impecable: la \u00fanica carta Illustrator considerada de grado 10 por la agencia de autenticaci\u00f3n PSA.<\/p>\n<p>Cuando la subasta de este lunes llegaba a su fin, el precio se mantuvo inicialmente en US$ 6,88 millones hasta que una oleada de ofertas de \u00faltimo minuto durante un periodo de puja extendida de varias horas elev\u00f3 el total final a US$ 16,49 millones, con 97 ofertas en total.<\/p>\n<p>Paul tiene fama de llevar las colecciones a niveles extremos y ha gastado millones para conseguir algunos de los objetos m\u00e1s raros jam\u00e1s producidos, incluidos los NFT, activos digitales \u00fanicos y verificables que se negocian en la blockchain.<\/p>\n<p>La estrella de la lucha libre de la WWE se despidi\u00f3 de la carta el s\u00e1bado en una publicaci\u00f3n de Instagram, diciendo: \u201cAdi\u00f3s, amiga. Qu\u00e9 privilegio ha sido ser el due\u00f1o del mayor coleccionable del mundo\u201d.<\/p>\n<p>La carta es solo una de las 20 Illustrator calificadas por PSA.<\/p>\n<p>Paul consigui\u00f3 la ultra rara carta de grado 10 intercambiando una Pikachu Illustrator de grado 9 de PSA que ya pose\u00eda \u2014valorada en US$ 1,27 millones\u2014 y US$ 4 millones en efectivo por ella en julio de 2021.<\/p>\n<p>Solo ocho de las cartas Pikachu Illustrator han recibido un grado 9 de PSA y la venta de Paul es la \u00fanica de grado 10, el nivel m\u00e1s alto y deseado que otorga PSA.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace cinco a\u00f1os, Logan Paul estableci\u00f3 un r\u00e9cord mundial al comprar una carta Pok\u00e9mon por US$ 5,27 millones. Result\u00f3 ser una inversi\u00f3n acertada: el influencer y luchador vendi\u00f3 esa carta por la asombrosa cifra de US$ 16,49 millones, con un collar incrustado de diamantes incluido. La rara carta Pikachu Illustrator \u2014una de solo 39 creadas [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1471269","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Venden la &quot;joya de la corona&quot; de las cartas Pok\u00e9mon de Logan Paul por US$ 16,5 millones, con un collar de diamantes incluido - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/16\/venta-carta-pokemon-logan-paul-record-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Venden la &quot;joya de la corona&quot; de las cartas Pok\u00e9mon de Logan Paul por US$ 16,5 millones, con un collar de diamantes incluido - Noticias\" \/>\n<meta property=\"og:description\" content=\"Hace cinco a\u00f1os, Logan Paul estableci\u00f3 un r\u00e9cord mundial al comprar una carta Pok\u00e9mon por US$ 5,27 millones. Result\u00f3 ser una inversi\u00f3n acertada: el influencer y luchador vendi\u00f3 esa carta por la asombrosa cifra de US$ 16,49 millones, con un collar incrustado de diamantes incluido. La rara carta Pikachu Illustrator \u2014una de solo 39 creadas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/16\/venta-carta-pokemon-logan-paul-record-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-16T09:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/16\/venta-carta-pokemon-logan-paul-record-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/16\/venta-carta-pokemon-logan-paul-record-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Venden la &#171;joya de la corona&#187; de las cartas Pok\u00e9mon de Logan Paul por US$ 16,5 millones, con un collar de diamantes incluido\",\"datePublished\":\"2026-02-16T09:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/16\/venta-carta-pokemon-logan-paul-record-trax\/\"},\"wordCount\":591,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/16\/venta-carta-pokemon-logan-paul-record-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/16\/venta-carta-pokemon-logan-paul-record-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/16\/venta-carta-pokemon-logan-paul-record-trax\/\",\"name\":\"Venden la \\\"joya de la corona\\\" de las cartas Pok\u00e9mon de Logan Paul por US$ 16,5 millones, con un collar de diamantes incluido - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-16T09:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/16\/venta-carta-pokemon-logan-paul-record-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/16\/venta-carta-pokemon-logan-paul-record-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/16\/venta-carta-pokemon-logan-paul-record-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Venden la &#171;joya de la corona&#187; de las cartas Pok\u00e9mon de Logan Paul por US$ 16,5 millones, con un collar de diamantes incluido\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Venden la \"joya de la corona\" de las cartas Pok\u00e9mon de Logan Paul por US$ 16,5 millones, con un collar de diamantes incluido - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/16\/venta-carta-pokemon-logan-paul-record-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Venden la \"joya de la corona\" de las cartas Pok\u00e9mon de Logan Paul por US$ 16,5 millones, con un collar de diamantes incluido - Noticias","og_description":"Hace cinco a\u00f1os, Logan Paul estableci\u00f3 un r\u00e9cord mundial al comprar una carta Pok\u00e9mon por US$ 5,27 millones. Result\u00f3 ser una inversi\u00f3n acertada: el influencer y luchador vendi\u00f3 esa carta por la asombrosa cifra de US$ 16,49 millones, con un collar incrustado de diamantes incluido. La rara carta Pikachu Illustrator \u2014una de solo 39 creadas [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/16\/venta-carta-pokemon-logan-paul-record-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-16T09:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/16\/venta-carta-pokemon-logan-paul-record-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/16\/venta-carta-pokemon-logan-paul-record-trax\/"},"author":{"name":"","@id":""},"headline":"Venden la &#171;joya de la corona&#187; de las cartas Pok\u00e9mon de Logan Paul por US$ 16,5 millones, con un collar de diamantes incluido","datePublished":"2026-02-16T09:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/16\/venta-carta-pokemon-logan-paul-record-trax\/"},"wordCount":591,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/16\/venta-carta-pokemon-logan-paul-record-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/16\/venta-carta-pokemon-logan-paul-record-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/16\/venta-carta-pokemon-logan-paul-record-trax\/","name":"Venden la \"joya de la corona\" de las cartas Pok\u00e9mon de Logan Paul por US$ 16,5 millones, con un collar de diamantes incluido - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-16T09:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/16\/venta-carta-pokemon-logan-paul-record-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/16\/venta-carta-pokemon-logan-paul-record-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/16\/venta-carta-pokemon-logan-paul-record-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Venden la &#171;joya de la corona&#187; de las cartas Pok\u00e9mon de Logan Paul por US$ 16,5 millones, con un collar de diamantes incluido"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/16\/venta-carta-pokemon-logan-paul-record-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Venden la &#171;joya de la corona&#187; de las cartas Pok\u00e9mon de Logan Paul por US$ 16,5 millones, con un collar de diamantes incluido","url":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/16\/venta-carta-pokemon-logan-paul-record-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/16\/venta-carta-pokemon-logan-paul-record-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-16T09:03:46Z","datePublished":"2026-02-16T09:03:46Z","dateModified":"2026-02-16T09:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Venden la &#171;joya de la corona&#187; de las cartas Pok\\u00e9mon de Logan Paul por US$ 16,5 millones, con un collar de diamantes incluido\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/16\\\/venta-carta-pokemon-logan-paul-record-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/16\\\/venta-carta-pokemon-logan-paul-record-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-16T09:03:46Z\",\"datePublished\":\"2026-02-16T09:03:46Z\",\"dateModified\":\"2026-02-16T09:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1467523,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/20\/joyas-historicas-louvre-desastre-nacional-francia-trax\/","url_meta":{"origin":1471269,"position":0},"title":"Joyas hist\u00f3ricas robadas en un &#171;desastre nacional&#187; para Francia: qu\u00e9 pas\u00f3 con los tesoros desaparecidos del Louvre","author":"","date":"octubre 20, 2025","format":false,"excerpt":"Entre los objetos preciosos extra\u00eddos del Museo del Louvre de Par\u00eds el domingo se incluyen un collar de esmeraldas engastado entre m\u00e1s de 1.000 diamantes regalados por Napole\u00f3n a su segunda esposa y otros tesoros de valor \u201cinestimable\u201d.Los ladrones atacaron la Galer\u00eda Apolo del Louvre, en el piso superior, que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468896,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/12\/02\/huevo-faberge-record-millonario-subasta-christies-trax\/","url_meta":{"origin":1471269,"position":1},"title":"Huevo Faberg\u00e9 alcanza r\u00e9cord de US$ 30,2 millones en rara subasta","author":"","date":"diciembre 2, 2025","format":false,"excerpt":"Uno de los \u00faltimos huevos Faberg\u00e9 en manos privadas se vendi\u00f3 por \u00a322,9 millones (US$ 30,2 millones), incluyendo comisiones, el martes, superando su propio r\u00e9cord como la obra m\u00e1s cara del joyero ruso jam\u00e1s subastada.Encargado por el zar Nicol\u00e1s II como regalo para su madre en 1913, el Huevo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452099,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/23\/botswana-enorme-diamante-2492-quilates-trax\/","url_meta":{"origin":1471269,"position":2},"title":"Hallan en Botswana un enorme diamante de 2.492 quilates que se cree es el segundo m\u00e1s grande del mundo","author":"","date":"agosto 23, 2024","format":false,"excerpt":"(CNN) --\u00a0Un enorme diamante en bruto de 2.492 quilates, que se cree es el segundo m\u00e1s grande jam\u00e1s encontrado, fue desenterrado en Botswana, seg\u00fan una empresa minera.Se cree que la enorme piedra es la mayor encontrada desde que en 1905 se descubri\u00f3 en Sud\u00e1frica el diamante Cullinan, de 3.106 quilates.La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472869,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/04\/cartas-pokemon-ola-delitos-nivel-internacional-trax\/","url_meta":{"origin":1471269,"position":3},"title":"Las cartas de Pok\u00e9mon est\u00e1n desencadenando una ola de delitos a nivel internacional","author":"","date":"abril 4, 2026","format":false,"excerpt":"En la madrugada del 7 de marzo, dos ladrones rompieron un escaparate forrado de vinilo en una tienda de Graham, Washington. Las alarmas sonaron mientras llenaban varios contenedores con la mercanc\u00eda robada. En menos de dos minutos, se llevaron casi US$ 10.000 en productos.El objetivo: cartas de Pok\u00e9mon.No era la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448661,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/04\/29\/reloj-titanic-rico-subasta-trax\/","url_meta":{"origin":1471269,"position":4},"title":"El reloj de oro que us\u00f3 el pasajero m\u00e1s rico del Titanic se vendi\u00f3 en subasta por la cifra r\u00e9cord de casi U$S 1,5 millones","author":"","date":"abril 29, 2024","format":false,"excerpt":"(CNN) -- Un reloj de oro usado por John Jacob Astor IV, miembro de la acaudalada familia Astor y el hombre m\u00e1s rico a bordo del Titanic, se vendi\u00f3 el s\u00e1bado en una subasta por la cifra r\u00e9cord de 1,175 millones de libras (US$ 1,485 millones).El reloj se vendi\u00f3 por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464398,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/07\/10\/bolso-hermes-original-jane-birkin-subasta-trax\/","url_meta":{"origin":1471269,"position":5},"title":"El bolso Herm\u00e8s original de Jane Birkin se vende por US$ 10 millones","author":"","date":"julio 10, 2025","format":false,"excerpt":"Desgastado, rayado y manchado, este bolso Birkin de cuero negro se acaba de vender por 8,6 millones de euros (US$ 10 millones), con gastos incluidos, y se convirti\u00f3 en el bolso m\u00e1s caro jam\u00e1s subastado. El precio base de la subasta fue de 7 millones de euros (US$ 8,2 millones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1471269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1471269"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1471269\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1471269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1471269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1471269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}