{"id":1471311,"date":"2026-02-17T05:03:40","date_gmt":"2026-02-17T13:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/17\/warner-bros-discovery-fusion-netflix-paramount-trax\/"},"modified":"2026-02-17T05:03:40","modified_gmt":"2026-02-17T13:03:40","slug":"warner-bros-discovery-fusion-netflix-paramount-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/17\/warner-bros-discovery-fusion-netflix-paramount-trax\/","title":{"rendered":"Warner Bros. Discovery respalda la fusi\u00f3n con Netflix mientras reabre la conversaci\u00f3n con Paramount"},"content":{"rendered":"<p>Warner Bros. Discovery quiere escuchar la \u201cmejor y \u00faltima propuesta\u201d de Paramount para la empresa de medios, y est\u00e1 abriendo una breve ventana para discutir una oferta, al tiempo que avanza con su fusi\u00f3n con Netflix e insta a los accionistas a rechazar la actual oferta hostil de Paramount.<\/p>\n<p>Si esto suena complicado es porque lo es.<\/p>\n<p>Warner Bros. Discovery, o WBD para abreviar, vale decenas de miles de millones de d\u00f3lares, y la junta directiva de la compa\u00f1\u00eda est\u00e1 tratando de asegurarse de exprimir hasta el \u00faltimo mill\u00f3n de sus ofertantes.<\/p>\n<p>As\u00ed que decidi\u00f3 reabrir las conversaciones con Paramount, en busca de un precio m\u00e1s alto, aunque reconoce que Netflix puede y probablemente igualar\u00e1 el precio.<\/p>\n<p>Netflix, por su parte, est\u00e1 criticando agresivamente a Paramount, diciendo que los \u201cdesaf\u00edos financieros de Paramount y sus planes de r\u00e1pido desapalancamiento representan un riesgo tremendo para la industria del entretenimiento\u201d.<\/p>\n<p>En diciembre pasado, WBD acord\u00f3 vender la mayor parte de la compa\u00f1\u00eda, incluyendo el estudio cinematogr\u00e1fico Warner Bros. y HBO, a Netflix. Los canales de cable de WBD, incluyendo CNN, no forman parte de la venta.<\/p>\n<p>El acuerdo con Netflix tambi\u00e9n represent\u00f3 un rechazo a Paramount. Pero el director ejecutivo de Paramount, David Ellison, respondi\u00f3 dirigi\u00e9ndose directamente a los accionistas con una oferta de US$ 30 por acci\u00f3n por la totalidad de WBD, incluyendo CNN.<\/p>\n<p>Esa es la oferta a la que WBD se opone oficialmente. El martes por la ma\u00f1ana, WBD <a href=\"https:\/\/ir.wbd.com\/news-and-events\/financial-news\/financial-news-details\/2026\/Warner-Bros--Discovery-Sets-Special-Meeting-Date-of-March-20-2026-and-Unanimously-Recommends-Shareholders-Vote-FOR-Netflix-Merger-Warner-Bros--Discovery-to-Initiate-Discussions-with-Paramount-Skydance-for-Their-Best-and-Final-Offer\/default.aspx\">anunci\u00f3 que celebrar\u00e1 una junta extraordinaria de accionistas<\/a> el 20 de marzo y recomendar\u00e1 votar para aprobar el acuerdo con Netflix, que valora el estudio y los activos de streaming en US$ 27,75 por acci\u00f3n.<\/p>\n<p>WBD ha argumentado que la venta a Netflix, junto con la creaci\u00f3n de Discovery Global, una nueva compa\u00f1\u00eda que albergar\u00e1 los canales de cable, es la mejor opci\u00f3n disponible para los inversores, aunque ha calificado la propuesta de Paramount <a href=\"https:\/\/www.cnn.com\/2026\/01\/07\/media\/paramount-warner-bros-wbd-offer\">de excesivamente arriesgada<\/a> y la ha comparado con una compra apalancada.<\/p>\n<p>Pero hay una gran inc\u00f3gnita: \u00bfcu\u00e1l es la \u201cmejor y \u00faltima\u201d oferta de Paramount?<\/p>\n<p>En t\u00e9rminos de negociaci\u00f3n, ese es el m\u00e1ximo que un comprador est\u00e1 dispuesto a pagar, y Paramount no ha compartido su respuesta.<\/p>\n<p>Durante la puja inicial por WBD el a\u00f1o pasado, Paramount indic\u00f3 estar dispuesta a pagar m\u00e1s de US$ 30 por acci\u00f3n. La semana pasada, seg\u00fan WBD, una persona que habl\u00f3 en nombre de Paramount le dijo a un miembro de la junta directiva de Warner que Paramount aceptar\u00eda pagar US$ 31 por acci\u00f3n si ambas partes negociaban un acuerdo.<\/p>\n<p>La persona dej\u00f3 un margen de maniobra adicional al indicar que US$ 31 no era la oferta final.<\/p>\n<p>Y as\u00ed, a pesar de tener un acuerdo de fusi\u00f3n firmado, Netflix ha concedido a WBD una exenci\u00f3n limitada para hablar con Paramount durante los pr\u00f3ximos siete d\u00edas.<\/p>\n<p>\u201cBuscamos su mejor y \u00faltima propuesta\u201d, dijo WBD en una carta a la junta directiva de Paramount el martes por la ma\u00f1ana.<\/p>\n<p>El resto de la carta, llena de jerga financiera y legal, se puede traducir as\u00ed: es hora de actuar o callarse.<\/p>\n<p>Paramount hizo algunos movimientos en direcci\u00f3n a WBD la semana pasada con una propuesta modificada que <a href=\"https:\/\/www.cnn.com\/2026\/02\/10\/media\/paramount-sweetens-bid-warner-bros-netflix\">mejor\u00f3 ligeramente<\/a> los t\u00e9rminos de la adquisici\u00f3n.<\/p>\n<p>Mantener conversaciones con Paramount ahora podr\u00eda liberar incluso m\u00e1s efectivo para una compa\u00f1\u00eda que apenas cotizaba a US$ 10 por acci\u00f3n hace un a\u00f1o, antes de que estallaran todos los rumores de venta.<\/p>\n<p>\u201cDurante todo el proceso, nuestro \u00fanico enfoque ha sido maximizar el valor y la certeza para los accionistas de WBD\u201d, dijo el director ejecutivo de WBD, David Zaslav, en un comunicado de prensa del martes.<\/p>\n<p>Refiri\u00e9ndose a Paramount por su s\u00edmbolo burs\u00e1til, afirm\u00f3: \u201cEn cada etapa del proceso, hemos proporcionado a PSKY instrucciones claras sobre las deficiencias en sus ofertas y las oportunidades para abordarlas. Estamos en contacto con PSKY para determinar si pueden presentar una propuesta viable y vinculante que ofrezca mayor valor y certeza a los accionistas de WBD mediante su mejor oferta final\u201d.<\/p>\n<p>Paramount ya present\u00f3 una demanda por la batalla de la fusi\u00f3n, por lo que la \u00faltima medida reglamentaria de WBD tambi\u00e9n podr\u00eda verse como una salvaguardia legal.<\/p>\n<p>Warner enfatiz\u00f3 el martes que su directorio no ha determinado que sea razonablemente probable que la propuesta de Paramount \u201cresulte en una transacci\u00f3n superior a la fusi\u00f3n con Netflix\u201d.<\/p>\n<p>Pero van a hablar, por lo que tampoco es del todo improbable.<\/p>\n<p>\u201cSi bien confiamos en que nuestra transacci\u00f3n ofrece un valor y una seguridad superiores, reconocemos la distracci\u00f3n continua que las maniobras de PSKY han generado para los accionistas de WBD y la industria del entretenimiento en general\u201d, declar\u00f3 Netflix el martes por la ma\u00f1ana. \u201cPor consiguiente, otorgamos a WBD una exenci\u00f3n limitada de siete d\u00edas de ciertas obligaciones bajo nuestro acuerdo de fusi\u00f3n para que puedan colaborar con PSKY y resolver este asunto de forma completa y definitiva\u201d.<\/p>\n<p>Netflix tambi\u00e9n denunci\u00f3 \u201cla financiaci\u00f3n extranjera\u201d que apoya la oferta de Paramount, que proviene en gran parte de las familias reales de Arabia Saudita, Qatar y Abu Dhabi.<\/p>\n<p>La financiaci\u00f3n \u201cya est\u00e1 generando serias preocupaciones en materia de seguridad nacional\u201d, afirm\u00f3 Netflix, prediciendo un escrutinio minucioso por parte de los reguladores en varios pa\u00edses.<\/p>\n<p>Como dijo recientemente Rich Greenfield de Lightshed Partners, \u201cla batalla por Warner Bros. dar\u00e1 lugar a una gran serie derivada de \u2018Succession\u2019 en Netflix alg\u00fan d\u00eda\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Warner Bros. Discovery quiere escuchar la \u201cmejor y \u00faltima propuesta\u201d de Paramount para la empresa de medios, y est\u00e1 abriendo una breve ventana para discutir una oferta, al tiempo que avanza con su fusi\u00f3n con Netflix e insta a los accionistas a rechazar la actual oferta hostil de Paramount. Si esto suena complicado es porque [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1471311","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Warner Bros. Discovery respalda la fusi\u00f3n con Netflix mientras reabre la conversaci\u00f3n con Paramount - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/17\/warner-bros-discovery-fusion-netflix-paramount-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Warner Bros. Discovery respalda la fusi\u00f3n con Netflix mientras reabre la conversaci\u00f3n con Paramount - Noticias\" \/>\n<meta property=\"og:description\" content=\"Warner Bros. Discovery quiere escuchar la \u201cmejor y \u00faltima propuesta\u201d de Paramount para la empresa de medios, y est\u00e1 abriendo una breve ventana para discutir una oferta, al tiempo que avanza con su fusi\u00f3n con Netflix e insta a los accionistas a rechazar la actual oferta hostil de Paramount. Si esto suena complicado es porque [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/17\/warner-bros-discovery-fusion-netflix-paramount-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-17T13:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/17\/warner-bros-discovery-fusion-netflix-paramount-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/17\/warner-bros-discovery-fusion-netflix-paramount-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Warner Bros. Discovery respalda la fusi\u00f3n con Netflix mientras reabre la conversaci\u00f3n con Paramount\",\"datePublished\":\"2026-02-17T13:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/17\/warner-bros-discovery-fusion-netflix-paramount-trax\/\"},\"wordCount\":973,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/17\/warner-bros-discovery-fusion-netflix-paramount-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/17\/warner-bros-discovery-fusion-netflix-paramount-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/17\/warner-bros-discovery-fusion-netflix-paramount-trax\/\",\"name\":\"Warner Bros. Discovery respalda la fusi\u00f3n con Netflix mientras reabre la conversaci\u00f3n con Paramount - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-17T13:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/17\/warner-bros-discovery-fusion-netflix-paramount-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/17\/warner-bros-discovery-fusion-netflix-paramount-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/17\/warner-bros-discovery-fusion-netflix-paramount-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Warner Bros. Discovery respalda la fusi\u00f3n con Netflix mientras reabre la conversaci\u00f3n con Paramount\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Warner Bros. Discovery respalda la fusi\u00f3n con Netflix mientras reabre la conversaci\u00f3n con Paramount - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/17\/warner-bros-discovery-fusion-netflix-paramount-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Warner Bros. Discovery respalda la fusi\u00f3n con Netflix mientras reabre la conversaci\u00f3n con Paramount - Noticias","og_description":"Warner Bros. Discovery quiere escuchar la \u201cmejor y \u00faltima propuesta\u201d de Paramount para la empresa de medios, y est\u00e1 abriendo una breve ventana para discutir una oferta, al tiempo que avanza con su fusi\u00f3n con Netflix e insta a los accionistas a rechazar la actual oferta hostil de Paramount. Si esto suena complicado es porque [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/17\/warner-bros-discovery-fusion-netflix-paramount-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-17T13:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/17\/warner-bros-discovery-fusion-netflix-paramount-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/17\/warner-bros-discovery-fusion-netflix-paramount-trax\/"},"author":{"name":"","@id":""},"headline":"Warner Bros. Discovery respalda la fusi\u00f3n con Netflix mientras reabre la conversaci\u00f3n con Paramount","datePublished":"2026-02-17T13:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/17\/warner-bros-discovery-fusion-netflix-paramount-trax\/"},"wordCount":973,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/17\/warner-bros-discovery-fusion-netflix-paramount-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/17\/warner-bros-discovery-fusion-netflix-paramount-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/17\/warner-bros-discovery-fusion-netflix-paramount-trax\/","name":"Warner Bros. Discovery respalda la fusi\u00f3n con Netflix mientras reabre la conversaci\u00f3n con Paramount - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-17T13:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/17\/warner-bros-discovery-fusion-netflix-paramount-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/17\/warner-bros-discovery-fusion-netflix-paramount-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/17\/warner-bros-discovery-fusion-netflix-paramount-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Warner Bros. Discovery respalda la fusi\u00f3n con Netflix mientras reabre la conversaci\u00f3n con Paramount"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/17\/warner-bros-discovery-fusion-netflix-paramount-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Warner Bros. Discovery respalda la fusi\u00f3n con Netflix mientras reabre la conversaci\u00f3n con Paramount","url":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/17\/warner-bros-discovery-fusion-netflix-paramount-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/17\/warner-bros-discovery-fusion-netflix-paramount-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-17T13:03:40Z","datePublished":"2026-02-17T13:03:40Z","dateModified":"2026-02-17T13:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Warner Bros. Discovery respalda la fusi\\u00f3n con Netflix mientras reabre la conversaci\\u00f3n con Paramount\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/17\\\/warner-bros-discovery-fusion-netflix-paramount-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/17\\\/warner-bros-discovery-fusion-netflix-paramount-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-17T13:03:40Z\",\"datePublished\":\"2026-02-17T13:03:40Z\",\"dateModified\":\"2026-02-17T13:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1469912,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/01\/08\/paramount-respuesta-wbd-oferta-fusion-medios-trax\/","url_meta":{"origin":1471311,"position":0},"title":"Paramount se mantiene firme en su oferta de US$ 30 por acci\u00f3n, mientras que WBD respalda el acuerdo con Netflix","author":"","date":"enero 8, 2026","format":false,"excerpt":"Paramount no est\u00e1 aumentando su oferta por Warner Bros. Discovery por encima de US$ 30 por acci\u00f3n, al menos por ahora.Este jueves, Paramount respondi\u00f3 a la \u00faltima carta de rechazo de WBD reiterando su opini\u00f3n de que los accionistas deber\u00edan apoyar su oferta de toma de control hostil.\u201cLa oferta de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470014,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/01\/12\/paramount-demanda-warner-bros-discovery-netflix-trax\/","url_meta":{"origin":1471311,"position":1},"title":"Paramount presenta una demanda contra Warner Bros. Discovery y amenaza con una batalla por el control de la compa\u00f1\u00eda","author":"","date":"enero 12, 2026","format":false,"excerpt":"Paramount decidi\u00f3 llevar a los tribunales su intento de adquirir Warner Bros. Discovery, la empresa matriz de CNN.El lunes, el CEO de Paramount, David Ellison, anunci\u00f3 una demanda ante el tribunal de equidad de Delaware, donde habitualmente se resuelven las disputas corporativas entre accionistas, en su intento de compra hostil\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469860,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/01\/07\/junta-directiva-warner-bros-discovery-rechaza-paramount-trax\/","url_meta":{"origin":1471311,"position":2},"title":"La junta directiva de Warner Bros. Discovery rechaza la renovada oferta de adquisici\u00f3n hostil de Paramount","author":"","date":"enero 7, 2026","format":false,"excerpt":"Una vez m\u00e1s, Warner Bros. Discovery ha elegido a Netflix como su pretendiente preferido frente a Paramount.La junta directiva de WBD inform\u00f3 este mi\u00e9rcoles a los accionistas que la oferta revisada del mes pasado de Paramount todav\u00eda no es tan atractiva como el acuerdo existente con Netflix, a pesar de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470256,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/01\/20\/netflix-oferta-warner-bros-discovery-efectivo-trax\/","url_meta":{"origin":1471311,"position":3},"title":"Netflix revisa su oferta por Warner Bros. Discovery. Ahora, es todo en efectivo","author":"","date":"enero 20, 2026","format":false,"excerpt":"En la lucha por el futuro de Warner Bros. Discovery, Netflix dice que est\u00e1 dispuesto a pagar todo en efectivo por Warner Bros. y HBO, en lugar de una combinaci\u00f3n de efectivo y acciones.Netflix y Warner Bros. Discovery \u2014WBD para abreviar\u2014 anunciaron el plan modificado este martes por la ma\u00f1ana,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471696,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/26\/netflix-ted-sarandos-casa-blanca-acuerdo-warner-trax\/","url_meta":{"origin":1471311,"position":4},"title":"Netflix se retira de la puja por Warner Bros. despu\u00e9s de que WBD considerara la oferta de Paramount como &#171;superior&#187;","author":"","date":"febrero 26, 2026","format":false,"excerpt":"Netflix dijo en la tarde de este jueves que ha \u201cdecidido no aumentar su oferta por Warner Bros.\u201d despu\u00e9s de que la junta directiva de Warner Bros. Discovery determinara que Paramount ha presentado una oferta \u201csuperior\u201d.El anuncio significa que Paramount se ha acercado repentinamente mucho m\u00e1s a tomar el control\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471723,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/27\/david-ellison-paramount-hollywood-trax\/","url_meta":{"origin":1471311,"position":5},"title":"C\u00f3mo David Ellison, el CEO de Paramount, luch\u00f3 para dominar Hollywood\u2026 y gan\u00f3","author":"","date":"febrero 27, 2026","format":false,"excerpt":"Hace menos de un a\u00f1o, David Ellison dirig\u00eda una peque\u00f1a productora. Ahora, est\u00e1 a punto de convertirse en el rey de Hollywood.El director ejecutivo de Paramount Skydance sali\u00f3 victorioso el jueves por la noche en una puja por Warner Bros. Discovery. Era un premio que Paramount necesitaba desesperadamente para sobrevivir,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1471311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1471311"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1471311\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1471311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1471311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1471311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}