{"id":1471348,"date":"2026-02-17T10:03:58","date_gmt":"2026-02-17T18:03:58","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/17\/tres-ataques-narcotrafico-caribe-pacifico-11-muertos-trax\/"},"modified":"2026-02-17T10:03:58","modified_gmt":"2026-02-17T18:03:58","slug":"tres-ataques-narcotrafico-caribe-pacifico-11-muertos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/17\/tres-ataques-narcotrafico-caribe-pacifico-11-muertos-trax\/","title":{"rendered":"EE.UU. reporta la muerte de 11 personas en ataques contra tres embarcaciones presuntamente del narcotr\u00e1fico"},"content":{"rendered":"<p>Las Fuerzas Armadas de EE.UU. atacaron tres supuestas embarcaciones de narcotr\u00e1fico en el Pac\u00edfico oriental y el Caribe la noche del lunes, matando a las 11 personas a bordo, inform\u00f3 el martes el Comando Sur de EE.UU.<\/p>\n<p>\u201cLa inteligencia confirm\u00f3 que las embarcaciones transitaban por rutas conocidas de narcotr\u00e1fico y estaban involucradas en operaciones de narcotr\u00e1fico\u201d, dijo el Comando Sur en un comunicado. \u201cOnce narco-terroristas masculinos murieron durante estas acciones: 4 en la primera embarcaci\u00f3n en el Pac\u00edfico oriental, 4 en la segunda embarcaci\u00f3n en el Pac\u00edfico oriental y 3 en la tercera embarcaci\u00f3n en el Caribe. Ninguna fuerza militar de EE.UU. result\u00f3 herida\u201d.<\/p>\n<p>Con estos ataques, el n\u00famero de muertos de la campa\u00f1a de EE.UU., que comenz\u00f3 en septiembre, asciende al menos a 135 personas, con varios sobrevivientes de los ataques presuntamente fallecidos. El m\u00e1s reciente ataque de EE.UU. contra una embarcaci\u00f3n sospechosa de narcotr\u00e1fico se hab\u00eda ejecutado el <a href=\"https:\/\/www.cnn.com\/2026\/02\/13\/politics\/us-strikes-alleged-drug-boat\">viernes en el Caribe<\/a> y mat\u00f3 a tres personas, seg\u00fan el Comando Sur.<\/p>\n<p>El oto\u00f1o pasado el Gobierno de Trump elabor\u00f3 una <a href=\"https:\/\/www.cnn.com\/2025\/10\/06\/politics\/classified-justice-department-memo-cartel-strikes\">opini\u00f3n legal<\/a> clasificada que justificaba los ataques letales contra una lista secreta de al menos dos docenas de c\u00e1rteles y supuestos narcotraficantes, clasific\u00e1ndolos como combatientes enemigos, seg\u00fan inform\u00f3 CNN.<\/p>\n<p>Sin embargo, los ataques han sido objeto de un intenso escrutinio por parte de expertos legales y miembros dem\u00f3cratas del Congreso, quienes afirman que equivalen a asesinar civiles, debido a que EE.UU. no est\u00e1 en una guerra declarada y autorizada por el Congreso contra los c\u00e1rteles de la droga.<\/p>\n<p>En al menos un caso, en septiembre pasado, las Fuerzas Armadas de EE.UU. mataron deliberadamente a sobrevivientes despu\u00e9s de un ataque inicial contra una supuesta embarcaci\u00f3n de tr\u00e1fico que no mat\u00f3 a todos los que estaban a bordo, lo que deriv\u00f3 en acusaciones de que EE.UU. hab\u00eda cometido un crimen de guerra y gener\u00f3 investigaciones en el Congreso.<\/p>\n<p>Antes de que los militares estadounidenses comenzaran a bombardear embarcaciones en septiembre, la lucha contra el narcotr\u00e1fico il\u00edcito era manejada por las fuerzas del orden y la Guardia Costera de EE.UU., y los miembros de los c\u00e1rteles y traficantes de drogas eran tratados como criminales con derechos al debido proceso. La Guardia Costera ha continuado <a href=\"https:\/\/www.news.uscg.mil\/Press-Releases\/Article\/4406849\/coast-guard-offloads-over-1335-million-in-illicit-drugs-interdicted-in-eastern\/\">interceptando<\/a> embarcaciones de narcotr\u00e1fico y decomisando narc\u00f3ticos en el Pac\u00edfico oriental sin el uso de fuerza letal.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las Fuerzas Armadas de EE.UU. atacaron tres supuestas embarcaciones de narcotr\u00e1fico en el Pac\u00edfico oriental y el Caribe la noche del lunes, matando a las 11 personas a bordo, inform\u00f3 el martes el Comando Sur de EE.UU. \u201cLa inteligencia confirm\u00f3 que las embarcaciones transitaban por rutas conocidas de narcotr\u00e1fico y estaban involucradas en operaciones de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1471348","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EE.UU. reporta la muerte de 11 personas en ataques contra tres embarcaciones presuntamente del narcotr\u00e1fico - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/17\/tres-ataques-narcotrafico-caribe-pacifico-11-muertos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EE.UU. reporta la muerte de 11 personas en ataques contra tres embarcaciones presuntamente del narcotr\u00e1fico - Noticias\" \/>\n<meta property=\"og:description\" content=\"Las Fuerzas Armadas de EE.UU. atacaron tres supuestas embarcaciones de narcotr\u00e1fico en el Pac\u00edfico oriental y el Caribe la noche del lunes, matando a las 11 personas a bordo, inform\u00f3 el martes el Comando Sur de EE.UU. \u201cLa inteligencia confirm\u00f3 que las embarcaciones transitaban por rutas conocidas de narcotr\u00e1fico y estaban involucradas en operaciones de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/17\/tres-ataques-narcotrafico-caribe-pacifico-11-muertos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-17T18:03:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/17\/tres-ataques-narcotrafico-caribe-pacifico-11-muertos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/17\/tres-ataques-narcotrafico-caribe-pacifico-11-muertos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"EE.UU. reporta la muerte de 11 personas en ataques contra tres embarcaciones presuntamente del narcotr\u00e1fico\",\"datePublished\":\"2026-02-17T18:03:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/17\/tres-ataques-narcotrafico-caribe-pacifico-11-muertos-trax\/\"},\"wordCount\":449,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/17\/tres-ataques-narcotrafico-caribe-pacifico-11-muertos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/17\/tres-ataques-narcotrafico-caribe-pacifico-11-muertos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/17\/tres-ataques-narcotrafico-caribe-pacifico-11-muertos-trax\/\",\"name\":\"EE.UU. reporta la muerte de 11 personas en ataques contra tres embarcaciones presuntamente del narcotr\u00e1fico - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-17T18:03:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/17\/tres-ataques-narcotrafico-caribe-pacifico-11-muertos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/17\/tres-ataques-narcotrafico-caribe-pacifico-11-muertos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/17\/tres-ataques-narcotrafico-caribe-pacifico-11-muertos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EE.UU. reporta la muerte de 11 personas en ataques contra tres embarcaciones presuntamente del narcotr\u00e1fico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EE.UU. reporta la muerte de 11 personas en ataques contra tres embarcaciones presuntamente del narcotr\u00e1fico - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/17\/tres-ataques-narcotrafico-caribe-pacifico-11-muertos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"EE.UU. reporta la muerte de 11 personas en ataques contra tres embarcaciones presuntamente del narcotr\u00e1fico - Noticias","og_description":"Las Fuerzas Armadas de EE.UU. atacaron tres supuestas embarcaciones de narcotr\u00e1fico en el Pac\u00edfico oriental y el Caribe la noche del lunes, matando a las 11 personas a bordo, inform\u00f3 el martes el Comando Sur de EE.UU. \u201cLa inteligencia confirm\u00f3 que las embarcaciones transitaban por rutas conocidas de narcotr\u00e1fico y estaban involucradas en operaciones de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/17\/tres-ataques-narcotrafico-caribe-pacifico-11-muertos-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-17T18:03:58+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/17\/tres-ataques-narcotrafico-caribe-pacifico-11-muertos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/17\/tres-ataques-narcotrafico-caribe-pacifico-11-muertos-trax\/"},"author":{"name":"","@id":""},"headline":"EE.UU. reporta la muerte de 11 personas en ataques contra tres embarcaciones presuntamente del narcotr\u00e1fico","datePublished":"2026-02-17T18:03:58+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/17\/tres-ataques-narcotrafico-caribe-pacifico-11-muertos-trax\/"},"wordCount":449,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/17\/tres-ataques-narcotrafico-caribe-pacifico-11-muertos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/17\/tres-ataques-narcotrafico-caribe-pacifico-11-muertos-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/17\/tres-ataques-narcotrafico-caribe-pacifico-11-muertos-trax\/","name":"EE.UU. reporta la muerte de 11 personas en ataques contra tres embarcaciones presuntamente del narcotr\u00e1fico - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-17T18:03:58+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/17\/tres-ataques-narcotrafico-caribe-pacifico-11-muertos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/17\/tres-ataques-narcotrafico-caribe-pacifico-11-muertos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/17\/tres-ataques-narcotrafico-caribe-pacifico-11-muertos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"EE.UU. reporta la muerte de 11 personas en ataques contra tres embarcaciones presuntamente del narcotr\u00e1fico"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/17\/tres-ataques-narcotrafico-caribe-pacifico-11-muertos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"EE.UU. reporta la muerte de 11 personas en ataques contra tres embarcaciones presuntamente del narcotr\u00e1fico","url":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/17\/tres-ataques-narcotrafico-caribe-pacifico-11-muertos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/17\/tres-ataques-narcotrafico-caribe-pacifico-11-muertos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-17T18:03:58Z","datePublished":"2026-02-17T18:03:58Z","dateModified":"2026-02-17T18:03:58Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"EE.UU. reporta la muerte de 11 personas en ataques contra tres embarcaciones presuntamente del narcotr\\u00e1fico\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/17\\\/tres-ataques-narcotrafico-caribe-pacifico-11-muertos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/17\\\/tres-ataques-narcotrafico-caribe-pacifico-11-muertos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-17T18:03:58Z\",\"datePublished\":\"2026-02-17T18:03:58Z\",\"dateModified\":\"2026-02-17T18:03:58Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1469293,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/12\/15\/ataque-tres-embarcaciones-pacifico-muertos-trax\/","url_meta":{"origin":1471348,"position":0},"title":"Fuerzas militares de EE.UU. atacan tres embarcaciones en el oc\u00e9ano Pac\u00edfico: reportan al menos ocho muertos","author":"","date":"diciembre 15, 2025","format":false,"excerpt":"Las Fuerzas Militares de EE.UU. atacaron tres embarcaciones presuntamente dedicadas al narcotr\u00e1fico en el este del oc\u00e9ano Pac\u00edfico el lunes, y reportaron ocho personas muertas, seg\u00fan el Comando Sur de EE.UU.\u201cEl 15 de diciembre, por orden de @SecWar Pete Hegseth, la Fuerza de Tarea Conjunta Southern Spear llev\u00f3 a cabo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469652,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/12\/29\/cronologia-ataques-eeuu-caribe-pacifico-venezuela-orix\/","url_meta":{"origin":1471348,"position":1},"title":"31 botes destruidos, m\u00e1s de 100 muertos y una crisis que crece en Caribe y Pac\u00edfico: cronolog\u00eda de los ataques de EE.UU.","author":"","date":"diciembre 29, 2025","format":false,"excerpt":"Este lunes, a pocos d\u00edas de cerrar el 2025, las Fuerzas Militares de EE.UU. ejecutaron otro ataque contra una presunta embarcaci\u00f3n de narcotr\u00e1fico en el oc\u00e9ano Pac\u00edfico oriental en el que murieron dos personas, seg\u00fan el Comando Sur de EE.UU.Con ello, desde el 2 de septiembre suman 31 botes destruidos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469512,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/12\/23\/cronologia-ataques-eeuu-caribe-pacifico-venezuela-narcotrafico-orix\/","url_meta":{"origin":1471348,"position":2},"title":"30 botes destruidos, m\u00e1s de 100 muertos y una crisis que crece en Caribe y Pac\u00edfico: cronolog\u00eda de los ataques de EE.UU.","author":"","date":"diciembre 23, 2025","format":false,"excerpt":"Este lunes, las Fuerzas Armadas de Estados Unidos realizaron un ataque contra una \u201cembarcaci\u00f3n de bajo perfil\u201d que presuntamente traficaba drogas en el oc\u00e9ano Pac\u00edfico oriental. Seg\u00fan el Comando Sur de EE.UU., en el ataque muri\u00f3 una persona.Con ello, desde el 2 de septiembre suman 30 botes destruidos en 26\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469299,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/12\/16\/ataques-botes-eeuu-caribe-pacifico-narco-venezuela-cronologia-orix\/","url_meta":{"origin":1471348,"position":3},"title":"25 botes destruidos, 95 muertos y una crisis que crece en el Caribe y el Pac\u00edfico: cronolog\u00eda de los ataques de EE.UU.","author":"","date":"diciembre 16, 2025","format":false,"excerpt":"Las Fuerzas Militares de EE.UU. atacaron tres embarcaciones presuntamente dedicadas al narcotr\u00e1fico en el este del oc\u00e9ano Pac\u00edfico el lunes. Seg\u00fan el Comando Sur de EE.UU., al menos ocho personas murieron como resultado del operativo.Con ello, desde el 2 de septiembre suman 25 botes destruidos en 23 ataques efectuados en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472006,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/03\/08\/ataque-presunta-embarcacion-drogas-pacifico-oriental-muertos-trax\/","url_meta":{"origin":1471348,"position":4},"title":"EE.UU. ataca presunta embarcaci\u00f3n con drogas en el Pac\u00edfico oriental; reportan 6 personas muertas","author":"","date":"marzo 8, 2026","format":false,"excerpt":"Las Fuerzas Armadas de EE.UU. ejecutaron el domingo un ataque contra otra presunta embarcaci\u00f3n de narcotr\u00e1fico en el oc\u00e9ano Pac\u00edfico oriental, que dej\u00f3 seis muertos, seg\u00fan el Comando Sur de EE.UU.\u201cEl 8 de marzo, por instrucci\u00f3n del comandante de #SOUTHCOM, el general Francis L.Donovan, la Fuerza de Tarea Conjunta Southern\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469651,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/12\/29\/ataque-embarcacion-narcotrafico-pacifico-trax\/","url_meta":{"origin":1471348,"position":5},"title":"EE.UU. ataca embarcaci\u00f3n en el Pac\u00edfico oriental; reportan dos personas muertas","author":"","date":"diciembre 29, 2025","format":false,"excerpt":"Las Fuerzas Militares de EE.UU. ejecutaron un ataque contra una presunta embarcaci\u00f3n de narcotr\u00e1fico en el oc\u00e9ano Pac\u00edfico oriental el lunes, matando a dos personas, seg\u00fan el Comando Sur de EE.UU.\u201cEl 29 de diciembre, bajo la direcci\u00f3n de @SecWar Pete Hegseth, la Fuerza de Tarea Conjunta Southern Spear ejecut\u00f3 un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1471348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1471348"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1471348\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1471348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1471348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1471348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}