{"id":1471354,"date":"2026-02-17T13:03:43","date_gmt":"2026-02-17T21:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/17\/elana-meyers-taylor-oro-maternidad-clave-trax\/"},"modified":"2026-02-17T13:03:43","modified_gmt":"2026-02-17T21:03:43","slug":"elana-meyers-taylor-oro-maternidad-clave-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/17\/elana-meyers-taylor-oro-maternidad-clave-trax\/","title":{"rendered":"La maternidad, el arma secreta de Elana Meyers Taylor para conseguir esa esquiva medalla de oro"},"content":{"rendered":"<p>Con la medalla de oro que tanto se le hab\u00eda escapado finalmente colgando de su cuello, Elana Meyers Taylor descart\u00f3 de inmediato la idea de estar en medio de un momento que le cambiar\u00eda la vida.<\/p>\n<p>\u201cEn seis d\u00edas, tendr\u00e9 que recoger y dejar a los ni\u00f1os de la escuela en pleno Texas\u201d, dijo, vestida con su parka y pantalones de nieve del equipo estadounidense. \u201cComo nada de todo esto, no puedo usarlo cuando vuelva a casa\u201d.<\/p>\n<p>Gran parte de estos Juegos Ol\u00edmpicos se han sentido como una lecci\u00f3n en perspectiva. Ganada y perdida. Apreciada con el tiempo y, a veces, entregada con brusquedad. Conseguida con esfuerzo en algunos casos. Conseguida con la vida en todos.<\/p>\n<p>El enfoque singular que requiere ser un atleta ol\u00edmpico no se ha abandonado, pero sus matices se han suavizado para los medallistas que han pasado por muchas cosas: fracasos, lesiones, decepciones y, en el caso de dos mujeres que se encontraban en una zona improvisada para entrevistas con los medios en la azotea del Cortina Curling Center, la maternidad.<\/p>\n<p>Segundos despu\u00e9s de ver a la alemana Laura Nolte cruzar la meta a tan solo 0,04 segundos de ella para asegurar el esquivo oro, Meyers Taylor se desplom\u00f3 en el suelo, con la bandera estadounidense envolvi\u00e9ndola.<\/p>\n<p>Pronto, sus dos hijos, Noah y Nico, la encontraron, desconcertados por el alboroto y claramente desinteresados \u200b\u200ben la magnitud del momento. Ahora, con su sexta medalla ol\u00edmpica en cinco Juegos, su madre est\u00e1 oficialmente empatada con Bonnie Blair como la atleta ol\u00edmpica de invierno estadounidense m\u00e1s condecorada de la historia. Noah y Nico solo quer\u00edan acurrucarse.<\/p>\n<p>Mientras tanto, su compa\u00f1era de equipo Kaillie Armbrusrer Humphries, quien se llev\u00f3 el bronce, ha ganado medallas en cinco Juegos Ol\u00edmpicos consecutivos. Su hijo de 15 meses, Aulden, de quien est\u00e1 bastante segura que durmi\u00f3 la siesta durante la prueba, estaba m\u00e1s interesado en correr por la nieve que en posar con su madre para una foto en el podio.<\/p>\n<p>\u201cLo agarr\u00e9 y sus ojos estaban as\u00ed\u201d, dijo Humphries, cerrando los suyos a media asta. Y yo le dije: \u2018Lo siento, hijo, pero voy a tener este momento contigo\u2019. Pero, sinceramente, le daba igual\u201d.<\/p>\n<p>As\u00ed es la vida de cualquier madre, incluso de aquellas con collares nuevos y relucientes.<\/p>\n<p>Para que nadie se enga\u00f1e, la suya no es una versi\u00f3n de maternidad t\u00edpica de Hallmark. Es real y es complicada. Necesitando prepararse para su carrera, Humphries pas\u00f3 su primera noche fuera de Aulden esta semana. Fue necesario y horrible a la vez.<\/p>\n<p>\u201cLa culpa de madre existe\u201d, dijo.<\/p>\n<p>\u201cPero necesitaba hacerlo para dar lo mejor de m\u00ed\u201d.<\/p>\n<p>Hay una hermosa casualidad en el hecho de que Meyers Taylor finalmente consiguiera el oro con el que hab\u00eda so\u00f1ado desde la universidad en un momento de su vida en el que menos importaba.<\/p>\n<p>\u201cSignifica todo y nada\u201d ha sido su mantra a medida que se acercaban estos Juegos, un cambio radical desde sus a\u00f1os universitarios, cuando la exestrella estadounidense de s\u00f3ftbol de George Washington solo quer\u00eda jugar para el equipo estadounidense.<\/p>\n<p>Quiz\u00e1s incluso lo deseaba demasiado; una prueba sali\u00f3 mal, y el deseo de Meyers Taylor la convirti\u00f3 en un manojo de nervios propenso a errores. Se pas\u00f3 al bobsleigh despu\u00e9s de que sus padres lo vieran por televisi\u00f3n y, afront\u00e1ndolo con la naturalidad de una novata, encontr\u00f3 la meta ol\u00edmpica que tanto anhelaba. Para 2010, gan\u00f3 la plata en el doble femenino, el comienzo de una racha de cinco medallas en los Juegos.<\/p>\n<p>Pero la medalla de oro no ca\u00eda y, aunque no la defin\u00eda, la deseaba con raz\u00f3n. Y entonces llegaron Nico en 2020 y Noah en 2023.<\/p>\n<p>Ambos ni\u00f1os son sordos y Noah tambi\u00e9n tiene s\u00edndrome de Down. Requieren terapia y cuidados especiales, y Meyers Taylor no delega nada de eso. Con el apoyo de su esposo Nic, un bobsledder retirado, sigui\u00f3 adelante con su carrera, pero hubo muchos d\u00edas en los que el bobsleigh parec\u00eda m\u00e1s bien una idea de \u00faltimo momento.<\/p>\n<p>Curiosamente, no le import\u00f3. En cambio, encontr\u00f3 paz en el caos, reconociendo que ninguna medalla \u2014oro, plata o bronce\u2014 la definir\u00eda.<\/p>\n<p>\u201cUna de las cosas que mi esposo me dijo antes de esta carrera fue: \u2018No vamos a dejar que dos curvas nos detengan\u2019\u201d, dijo. \u201cHemos pasado por demasiado como familia\u201d.<\/p>\n<p>A los 41 a\u00f1os, tambi\u00e9n sab\u00eda que el final estaba cerca y cuando sufri\u00f3 un terrible accidente en enero, solo tres semanas antes de los Juegos, pens\u00f3 que definitivamente no era su momento. En cambio, Meyers Taylor y Humphries bajaron sus tiempos r\u00e9cord en la tercera manga, presionando a Nolte, quien lideraba por 0,15 despu\u00e9s de la tercera manga.<\/p>\n<p>Como los l\u00edderes iban en orden inverso, Humphries se adelant\u00f3 a Meyers Taylor, quien luego cedi\u00f3 el paso a Nolte. La diferencia entre los tres es casi tan peque\u00f1a como una astilla de nieve: un tiempo combinado de 3:57.93 para Meyers Taylor, 3:57.97 para Nolte y 3:58.05 para Humphries.<\/p>\n<p>Mientras sus chicos la rodeaban, Meyers Taylor les hizo se\u00f1as. Les hab\u00eda ense\u00f1ado antes la \u201ccarrera de bobsleigh\u201d.<\/p>\n<p>\u201cTambi\u00e9n les ense\u00f1\u00e9 la medalla de oro\u201d, dijo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la medalla de oro que tanto se le hab\u00eda escapado finalmente colgando de su cuello, Elana Meyers Taylor descart\u00f3 de inmediato la idea de estar en medio de un momento que le cambiar\u00eda la vida. \u201cEn seis d\u00edas, tendr\u00e9 que recoger y dejar a los ni\u00f1os de la escuela en pleno Texas\u201d, dijo, vestida [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1471354","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La maternidad, el arma secreta de Elana Meyers Taylor para conseguir esa esquiva medalla de oro - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/17\/elana-meyers-taylor-oro-maternidad-clave-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La maternidad, el arma secreta de Elana Meyers Taylor para conseguir esa esquiva medalla de oro - Noticias\" \/>\n<meta property=\"og:description\" content=\"Con la medalla de oro que tanto se le hab\u00eda escapado finalmente colgando de su cuello, Elana Meyers Taylor descart\u00f3 de inmediato la idea de estar en medio de un momento que le cambiar\u00eda la vida. \u201cEn seis d\u00edas, tendr\u00e9 que recoger y dejar a los ni\u00f1os de la escuela en pleno Texas\u201d, dijo, vestida [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/17\/elana-meyers-taylor-oro-maternidad-clave-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-17T21:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/17\/elana-meyers-taylor-oro-maternidad-clave-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/17\/elana-meyers-taylor-oro-maternidad-clave-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La maternidad, el arma secreta de Elana Meyers Taylor para conseguir esa esquiva medalla de oro\",\"datePublished\":\"2026-02-17T21:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/17\/elana-meyers-taylor-oro-maternidad-clave-trax\/\"},\"wordCount\":918,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/17\/elana-meyers-taylor-oro-maternidad-clave-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/17\/elana-meyers-taylor-oro-maternidad-clave-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/17\/elana-meyers-taylor-oro-maternidad-clave-trax\/\",\"name\":\"La maternidad, el arma secreta de Elana Meyers Taylor para conseguir esa esquiva medalla de oro - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-17T21:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/17\/elana-meyers-taylor-oro-maternidad-clave-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/17\/elana-meyers-taylor-oro-maternidad-clave-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/17\/elana-meyers-taylor-oro-maternidad-clave-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La maternidad, el arma secreta de Elana Meyers Taylor para conseguir esa esquiva medalla de oro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La maternidad, el arma secreta de Elana Meyers Taylor para conseguir esa esquiva medalla de oro - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/17\/elana-meyers-taylor-oro-maternidad-clave-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La maternidad, el arma secreta de Elana Meyers Taylor para conseguir esa esquiva medalla de oro - Noticias","og_description":"Con la medalla de oro que tanto se le hab\u00eda escapado finalmente colgando de su cuello, Elana Meyers Taylor descart\u00f3 de inmediato la idea de estar en medio de un momento que le cambiar\u00eda la vida. \u201cEn seis d\u00edas, tendr\u00e9 que recoger y dejar a los ni\u00f1os de la escuela en pleno Texas\u201d, dijo, vestida [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/17\/elana-meyers-taylor-oro-maternidad-clave-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-17T21:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/17\/elana-meyers-taylor-oro-maternidad-clave-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/17\/elana-meyers-taylor-oro-maternidad-clave-trax\/"},"author":{"name":"","@id":""},"headline":"La maternidad, el arma secreta de Elana Meyers Taylor para conseguir esa esquiva medalla de oro","datePublished":"2026-02-17T21:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/17\/elana-meyers-taylor-oro-maternidad-clave-trax\/"},"wordCount":918,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/17\/elana-meyers-taylor-oro-maternidad-clave-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/17\/elana-meyers-taylor-oro-maternidad-clave-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/17\/elana-meyers-taylor-oro-maternidad-clave-trax\/","name":"La maternidad, el arma secreta de Elana Meyers Taylor para conseguir esa esquiva medalla de oro - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-17T21:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/17\/elana-meyers-taylor-oro-maternidad-clave-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/17\/elana-meyers-taylor-oro-maternidad-clave-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/17\/elana-meyers-taylor-oro-maternidad-clave-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La maternidad, el arma secreta de Elana Meyers Taylor para conseguir esa esquiva medalla de oro"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/17\/elana-meyers-taylor-oro-maternidad-clave-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La maternidad, el arma secreta de Elana Meyers Taylor para conseguir esa esquiva medalla de oro","url":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/17\/elana-meyers-taylor-oro-maternidad-clave-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/17\/elana-meyers-taylor-oro-maternidad-clave-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-17T21:03:43Z","datePublished":"2026-02-17T21:03:43Z","dateModified":"2026-02-17T21:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La maternidad, el arma secreta de Elana Meyers Taylor para conseguir esa esquiva medalla de oro\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/17\\\/elana-meyers-taylor-oro-maternidad-clave-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/17\\\/elana-meyers-taylor-oro-maternidad-clave-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-17T21:03:43Z\",\"datePublished\":\"2026-02-17T21:03:43Z\",\"dateModified\":\"2026-02-17T21:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1470986,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/07\/mujeres-olimpicas-maternidad-sueno-oro-trax\/","url_meta":{"origin":1471354,"position":0},"title":"C\u00f3mo esta generaci\u00f3n de mujeres ol\u00edmpicas borr\u00f3 la idea de que la maternidad es el final del sue\u00f1o de una medalla de oro","author":"","date":"febrero 7, 2026","format":false,"excerpt":"El mensaje que Kendall Coyne Schofield public\u00f3 en sus redes sociales no fue dif\u00edcil de descifrar.Una pizarra enmarcada, colocada frente a los dos perros de Schofield, Penny y Blue, mostraba el mensaje: \u201cBeb\u00e9 Schofield llega en verano de 2023\u201d. Los perros llevaban pa\u00f1uelos iguales que dec\u00edan \u201chermana mayor\u201d, por si\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471541,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/22\/eileen-gu-china-medalla-oro-olimpicos-trax\/","url_meta":{"origin":1471354,"position":1},"title":"Eileen Gu responde a la pol\u00e9mica sobre representar a China ganando una medalla de oro","author":"","date":"febrero 22, 2026","format":false,"excerpt":"Eileen Gu gan\u00f3 su primera medalla de oro en los Juegos de Mil\u00e1n Cortina, defendiendo as\u00ed su t\u00edtulo ol\u00edmpico de esqu\u00ed acrob\u00e1tico halfpipe femenino de 2022.La joven de 22 a\u00f1os se alz\u00f3 con la medalla de oro en la segunda manga de la final, antes de ampliar su ventaja sobre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471082,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/10\/medalla-olimpica-bronce-confiesa-infidelidad-trax\/","url_meta":{"origin":1471354,"position":2},"title":"Ins\u00f3lito momento en los Juegos Ol\u00edmpicos de Invierno: gan\u00f3 una medalla y confes\u00f3 una infidelidad en vivo","author":"","date":"febrero 10, 2026","format":false,"excerpt":"Bueno, no estoy seguro de si es la primera vez que se celebra en los Juegos Ol\u00edmpicos, pero sin duda ha dado que hablar.El biatleta noruego Sturla Holm Laegreid, tras conseguir el bronce en la prueba individual masculina de 20 km, admiti\u00f3 en la televisi\u00f3n noruega que le hab\u00eda sido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452516,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/09\/07\/campeon-paralimpico-hunter-woodhall-esposa-confianza-trax\/","url_meta":{"origin":1471354,"position":3},"title":"El campe\u00f3n paral\u00edmpico de EE.UU., Hunter Woodhall, dijo que el oro ol\u00edmpico de su esposa le dio la confianza necesaria","author":"","date":"septiembre 7, 2024","format":false,"excerpt":"(CNN) --\u00a0 Cuando Hunter Woodhall cruz\u00f3 la l\u00ednea logrando una medalla de oro paral\u00edmpica en la final masculina de 400 m T62, solt\u00f3 un rugido y sigui\u00f3 corriendo para encontrarse con su esposa, Tara Davis-Woodhall.El festejo \u2014con ella abraz\u00e1ndolo desde las gradas entre l\u00e1grimas\u2014 revivi\u00f3 una celebraci\u00f3n que hab\u00eda cautivado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451945,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/17\/imane-khelif-recibe-desfile-celebracion-regreso-a-casa-tras-juegos-olimpicos-trax\/","url_meta":{"origin":1471354,"position":4},"title":"La boxeadora argelina Imane Khelif recibe un desfile de celebraci\u00f3n a su regreso a casa tras los Juegos Ol\u00edmpicos de Par\u00eds","author":"","date":"agosto 17, 2024","format":false,"excerpt":"(CNN) -- Multitudes entusiastas llenaron las calles de Tiaret, Argelia, este viernes por la noche para dar la bienvenida a la boxeadora Imane Khelif en su regreso a casa tras su paso por los Juegos Ol\u00edmpicos de Par\u00eds , donde gan\u00f3 una medalla de oro.Ella public\u00f3 un video del desfile\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451608,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/08\/05\/rebeca-andrade-gimnasta-brasilena-derroto-simone-biles-trax\/","url_meta":{"origin":1471354,"position":5},"title":"Qui\u00e9n es Rebeca Andrade, la gimnasta brasile\u00f1a que derrot\u00f3 a Simone Biles","author":"","date":"agosto 5, 2024","format":false,"excerpt":"(CNN) -- Simone Biles, once veces medallista ol\u00edmpica, es dif\u00edcil de batir, pero no imposible.La gimnasta brasile\u00f1a Rebeca Andrade lo demostr\u00f3 al superar a su rival estadounidense en la final de suelo de los Juegos Ol\u00edmpicos de Par\u00eds. Biles se llev\u00f3 la medalla de plata.Fue un momento de catarsis para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1471354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1471354"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1471354\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1471354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1471354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1471354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}