{"id":1471366,"date":"2026-02-17T19:03:46","date_gmt":"2026-02-18T03:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/17\/afirmaciones-dhs-trump-desmoronado-trax\/"},"modified":"2026-02-17T19:03:46","modified_gmt":"2026-02-18T03:03:46","slug":"afirmaciones-dhs-trump-desmoronado-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/17\/afirmaciones-dhs-trump-desmoronado-trax\/","title":{"rendered":"Todas las afirmaciones del DHS de Trump que se han desmoronado"},"content":{"rendered":"<p>La inminente salida de la portavoz del Departamento de Seguridad Nacional, <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/17\/eeuu\/renuncia-tricia-mclaughlin-portavoz-departamento-seguridad-nacional-trax\">Tricia McLaughlin<\/a>, de la agencia es la \u00faltima se\u00f1al de un reinicio en la agresiva estrategia de deportaci\u00f3n del Gobierno de Trump, <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/04\/eeuu\/que-tan-grave-muerte-alex-pretti-gobierno-trump-trax\">que ha perdido un fuerte respaldo<\/a> entre los estadounidenses.<\/p>\n<p>Y es dif\u00edcil exagerar el gran papel que jug\u00f3 en eso la comunicaci\u00f3n excesivamente agresiva, deficiente y a menudo extra\u00f1a del departamento.<\/p>\n<p>El Gobierno y McLaughlin, quien se ir\u00eda la pr\u00f3xima semana, parec\u00edan pensar que pod\u00edan decir lo que quisieran sobre episodios como los tiroteos de Renee Good y Alex Pretti por parte de agentes federales de inmigraci\u00f3n, sin importar la evidencia. Pero result\u00f3 que ese enfoque tuvo consecuencias pol\u00edticas.<\/p>\n<p>Una encuesta de la Universidad Quinnipiac a principios de este mes mostr\u00f3 que los votantes registrados dijeron por <a href=\"https:\/\/poll.qu.edu\/poll-release?releaseid=3947\">un margen de m\u00e1s de dos a uno (61%-25%)<\/a> que no cre\u00edan que la administraci\u00f3n haya dado una \u201cversi\u00f3n honesta\u201d del tiroteo de Pretti en Minneapolis a finales de enero.<\/p>\n<p>Incluso entre los republicanos, cuatro de cada 10 se negaron a respaldar al Gobierno (Aproximadamente la mitad de ese grupo se mostr\u00f3 neutral, mientras que la otra mitad expres\u00f3 desconfianza).<\/p>\n<p>Y esa reputaci\u00f3n la tiene m\u00e1s que merecida \u2014y no solo por el manejo fallido del Gobierno del tiroteo de Pretti, sino tambi\u00e9n por su manejo de muchos otros incidentes de alto perfil.<\/p>\n<p>Una y otra vez en los \u00faltimos meses, el DHS ha hecho afirmaciones que luego fueron refutadas por video, otras pruebas, la polic\u00eda local y\/o jueces. Sus casos legales contra personas a las que acus\u00f3 de atacar a agentes federales se desmoronaron repetidamente.<\/p>\n<p>Y aunque el asesinato de Pretti fue quiz\u00e1s el ejemplo m\u00e1s impactante de la fallida comunicaci\u00f3n del departamento, fue similar a muchos otros casos, incluidos algunos de los que supimos m\u00e1s en los \u00faltimos d\u00edas, poco antes de que se informara la salida de McLaughlin. (CNN informa que ella comenz\u00f3 a planear su salida en diciembre, pero permaneci\u00f3 despu\u00e9s de esos tiroteos en Minneapolis.)<\/p>\n<p>Repasemos algunos ejemplos de grandes afirmaciones del DHS que se desmoronaron.<\/p>\n<p><strong>Las afirmaciones<\/strong>: McLaughlin dijo que Good hab\u00eda \u201cutilizado su veh\u00edculo como arma en un intento de matar o causar da\u00f1o corporal a agentes federales de la ley\u201d. La secretaria de Seguridad Nacional, Kristi Noem, lo calific\u00f3 de \u201cun acto de terrorismo interno\u201d. Y el presidente Donald Trump dijo que Good <a href=\"https:\/\/truthsocial.com\/@realDonaldTrump\/posts\/115855701696773990\">\u201cvoluntaria y brutalmente atropell\u00f3\u201d<\/a> al agente.<\/p>\n<p><strong>La evidencia<\/strong>: El agente de Inmigraci\u00f3n y Control de Aduanas Jonathan Ross no fue atropellado. Hay cierta duda sobre si el veh\u00edculo hizo contacto con \u00e9l. Pero no hay pruebas de que Good intentara atropellar al agente; de hecho, Good estaba girando en direcci\u00f3n opuesta al agente mientras se alejaba cuando fue baleada. Y <a href=\"https:\/\/www.cnn.com\/2026\/01\/23\/us\/video\/3d-imaging-examines-renee-good-shooting-john-miller-digvid-vrtc\">la evidencia en video<\/a> muestra a Ross que contin\u00faa dispar\u00e1ndole incluso desde el lateral del veh\u00edculo.<\/p>\n<p><strong>Las afirmaciones<\/strong>: McLaughlin dijo que parec\u00eda que Pretti hab\u00eda intentado \u201cmasacrar a las fuerzas del orden\u201d. Noem nuevamente invoc\u00f3 \u201cterrorismo interno\u201d. El asesor de la Casa Blanca, Stephen Miller, llam\u00f3 a Pretti <a href=\"https:\/\/x.com\/StephenM\/status\/2015133481261474030\">un \u201casesino\u201d que \u201ctrat\u00f3 de asesinar a agentes federales\u201d<\/a>.<\/p>\n<p><strong>La evidencia<\/strong>: El video contradijo estas afirmaciones a\u00fan m\u00e1s que en el caso de Good. No hay pruebas de que Pretti haya apuntado a los agentes. Estaba armado legalmente pero no sac\u00f3 su arma, y fue desarmado antes de ser baleado y asesinado. El Gobierno desde entonces <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/28\/eeuu\/trump-retractarse-declaraciones-otan-pretti-analisis-trax\">ha retirado sus afirmaciones<\/a>.<\/p>\n<p><strong>Las afirmaciones<\/strong>: Good y Pretti no fueron los primeros ciudadanos estadounidenses en ser acusados de terrorismo. Despu\u00e9s de que un agente de la Patrulla Fronteriza disparara varias veces contra Marimar Mart\u00ednez en Chicago, un comunicado del DHS dijo que los agentes involucrados fueron \u201c<a href=\"https:\/\/www.dhs.gov\/news\/2025\/10\/04\/update-dhs-deploys-special-operations-after-multiple-violent-attacks-federal-law\">emboscados por terroristas internos<\/a> que embistieron a los agentes federales con sus veh\u00edculos\u201d. Dijo que los disparos fueron \u201cdefensivos\u201d. McLaughlin a\u00f1adi\u00f3: \u201cno permitiremos que terroristas internos ataquen a nuestras fuerzas del orden\u201d.<\/p>\n<p><strong>La evidencia<\/strong>: <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/11\/eeuu\/patrulla-fronteriza-elogio-agente-disparar-mujer-trax\">Evidencia en video<\/a> publicada la semana pasada refuerza la afirmaci\u00f3n de Mart\u00ednez de que fue su veh\u00edculo el que fue embestido, no el del agente. Y el caso contra Mart\u00ednez ya <a href=\"https:\/\/www.cnn.com\/2025\/11\/21\/us\/marimar-martinez-shooting-case-what-we-know\">se hab\u00eda desmoronado anteriormente<\/a> debido a numerosos problemas, incluido el hecho de que el veh\u00edculo del agente \u2014que deb\u00eda ser evidencia\u2014 fue conducido a m\u00e1s de 1.600 kil\u00f3metros del lugar despu\u00e9s del incidente.<\/p>\n<p><strong>Las afirmaciones<\/strong>: El DHS afirm\u00f3 en un comunicado que tres migrantes, incluido uno que fue herido de bala en la pierna en Minneapolis, Julio C\u00e9sar Sosa-Celis, \u201c<a href=\"https:\/\/www.dhs.gov\/news\/2026\/01\/15\/dhs-releases-more-details-about-three-violent-criminal-illegal-aliens-who-violently\">agredieron violentamente a las fuerzas del orden con una pala y una escoba<\/a>\u201d. Noem describi\u00f3 un \u201cintento de asesinato de agentes federales\u201d.<\/p>\n<p><strong>La evidencia<\/strong>: ICE <a href=\"https:\/\/www.cnn.com\/2026\/02\/15\/us\/ice-shooting-dhs-doj-false-statements\">admiti\u00f3<\/a> la semana pasada que sus agentes hicieron \u201cdeclaraciones falsas\u201d bajo juramento, y los fiscales del Departamento de Justicia solicitaron retirar los cargos penales contra dos de los hombres. El director interino de ICE, Todd Lyons, dijo que las afirmaciones fueron contradichas por evidencia en video.<\/p>\n<p><strong>Las afirmaciones<\/strong>: El DHS acus\u00f3 al residente de Milwaukee, Ram\u00f3n Morales Reyes, de escribir una carta en la que \u201c<a href=\"https:\/\/www.dhs.gov\/news\/2025\/05\/28\/secretary-noem-releases-statement-after-ice-arrests-illegal-alien-who-threatened\">amenaz\u00f3 con asesinar al presidente Trump<\/a>\u201d. Noem inst\u00f3 a los cr\u00edticos de Trump a moderar su ret\u00f3rica.<\/p>\n<p><strong>La evidencia<\/strong>: El mes pasado, otro hombre admiti\u00f3 en la corte que <a href=\"https:\/\/www.jsonline.com\/story\/news\/crime\/2026\/01\/27\/trial-begins-for-man-accused-of-framing-crime-victim-for-threat-to-trump\/88361647007\/\">la carta era una artima\u00f1a<\/a> y que en realidad la hab\u00eda escrito \u00e9l. Supuestamente, este hombre hab\u00eda apu\u00f1alado a Morales Reyes y quer\u00eda que lo deportaran antes de que pudiera testificar. La afirmaci\u00f3n del DHS sigue en l\u00ednea, sin indicar que acus\u00f3 falsamente a Morales Reyes. (En su lugar dice que \u201cya no est\u00e1 bajo investigaci\u00f3n\u201d.)<\/p>\n<p><strong>Las afirmaciones<\/strong>: Greg Bovino, el funcionario de la Patrulla Fronteriza que previamente hab\u00eda liderado la operaci\u00f3n en Minneapolis, afirm\u00f3 que us\u00f3 gas lacrim\u00f3geno despu\u00e9s de ser golpeado en el casco por una piedra en Chicago. El DHS tambi\u00e9n dijo que una piedra \u201c<a href=\"https:\/\/x.com\/dhsgov\/status\/1983186057798545573\">golpe\u00f3 al jefe Greg Bovino en la cabeza<\/a>\u201d.<\/p>\n<p><strong>La evidencia<\/strong>: En un caso que involucraba los l\u00edmites en el uso de la fuerza por parte de agentes federales, un juez dijo que Bovino \u201cadmiti\u00f3 en su declaraci\u00f3n\u202fque minti\u00f3 varias veces\u201d sobre el incidente. El juez dijo que las afirmaciones de Bovino cambiaron repetidamente, y que al final <a href=\"https:\/\/chrome-extension:\/\/efaidnbmnnnibpcajpcglclefindmkaj\/https:\/\/cases.justia.com\/federal\/district-courts\/illinois\/ilndce\/1:2025cv12173\/487571\/281\/0.pdf?ts=1763733493\">admiti\u00f3 que no le hab\u00edan arrojado ninguna piedra<\/a> antes de usar el gas lacrim\u00f3geno.<\/p>\n<p><strong>Las afirmaciones<\/strong>: Tras la aparici\u00f3n de un video de una detenci\u00f3n agresiva de un adolescente en Hoffman Estates, Illinois, McLaughlin afirm\u00f3 que era un video antiguo y que no involucraba a ICE. Lo calific\u00f3 como \u201c<a href=\"https:\/\/x.com\/TriciaOhio\/status\/1977378998071038129\">un video de un arresto por robo que la Polic\u00eda de Chicago realiz\u00f3 hace m\u00e1s de un a\u00f1o<\/a>\u201d.<\/p>\n<p><strong>La evidencia<\/strong>: PolitiFact determin\u00f3 que las afirmaciones de McLaughlin eran <a href=\"https:\/\/www.politifact.com\/factchecks\/2025\/oct\/15\/tricia-mclaughlin\/viral-video-shows-ice-activity-in-hoffman-estates\/\">falsas<\/a>. La escena involucraba a agentes con uniformes que los identificaban como vinculados a ICE, y no tendr\u00eda sentido que el arresto involucrara a la polic\u00eda de Chicago, dado que fue en un suburbio a casi 50 kil\u00f3metros de distancia. La familia del adolescente <a href=\"https:\/\/www.cbsnews.com\/chicago\/news\/teen-tossed-to-ground-by-ice\/\">tambi\u00e9n se pronunci\u00f3<\/a>.<\/p>\n<p><strong>Las afirmaciones<\/strong>: El DHS afirm\u00f3 que <a href=\"https:\/\/x.com\/DHSgov\/status\/2003931344553095309\">dos hombres estaban en una camioneta<\/a> que uno de ellos condujo \u201cdirectamente hacia los oficiales de ICE\u201d, en Glen Burnie, Maryland. Uno de ellos fue baleado por un agente.<\/p>\n<p><strong>La evidencia<\/strong>: La polic\u00eda del condado de Anne Arundel dijo despu\u00e9s que uno de los dos hombres estaba \u201c<a href=\"https:\/\/wtop.com\/maryland\/2026\/01\/department-of-homeland-security-changes-its-account-of-christmas-eve-shooting-by-ice-officers\/\">ya bajo custodia<\/a>\u201d en ese momento. El DHS luego modific\u00f3 sus afirmaciones para reflejar que s\u00f3lo una persona estaba en la camioneta.<\/p>\n<p><strong>Las afirmaciones<\/strong>: McLaughlin dijo que un ni\u00f1o de 13 a\u00f1os que fue arrestado y detenido por ICE en Massachusetts \u201c<a href=\"https:\/\/cnnespanol.cnn.com\/2025\/10\/15\/eeuu\/menor-13-anios-arrestado-ice-centro-detencion-trax\">estaba en posesi\u00f3n de un arma de fuego<\/a> y un cuchillo de 5-7 pulgadas cuando fue arrestado\u201d.<\/p>\n<p><strong>La evidencia<\/strong>: El alcalde de Everett, Massachusetts, Carlo DeMaria, neg\u00f3 rotundamente que el adolescente tuviera un arma, diciendo: \u201c<a href=\"https:\/\/cnnespanol.cnn.com\/2025\/10\/15\/eeuu\/menor-13-anios-arrestado-ice-centro-detencion-trax\">no se encontraron armas<\/a>\u201d. (DeMaria confirm\u00f3 lo del cuchillo.) Consultado por CNN para m\u00e1s comentarios, el DHS no respondi\u00f3.<\/p>\n<p><strong>Las afirmaciones<\/strong>: Tras la hospitalizaci\u00f3n de d<a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/18\/eeuu\/familia-minneapolis-gas-lacrimogeno-ice-trax\">os ni\u00f1os despu\u00e9s de ser expuestos a gas lacrim\u00f3geno<\/a> mientras su familia conduc\u00eda cerca de una protesta en Minneapolis, el DHS sugiri\u00f3 que sus padres eran \u201cagitadores\u201d. El DHS escribi\u00f3 en una publicaci\u00f3n: \u201ces horrible ver a agitadores radicales llevar ni\u00f1os a sus disturbios violentos\u201d.<\/p>\n<p><strong>La evidencia<\/strong>: DHS pronto elimin\u00f3 la publicaci\u00f3n, y McLaughlin <a href=\"https:\/\/www.cnn.com\/politics\/live-news\/trump-administration-news-01-16-26?post-id=cmkhhqzc700003b6qmyr3huy0\">reconoci\u00f3<\/a> que las personas no eran agitadores sino \u201cv\u00edctimas\u201d.<\/p>\n<p><strong>Las afirmaciones<\/strong>: Despu\u00e9s de que la estudiante de doctorado de la Universidad de Tufts fuera detenida por agentes federales enmascarados la primavera pasada, McLaughlin dijo a CNN que los investigadores hab\u00edan determinado que R\u00fcmeysa \u00d6zt\u00fcrk estaba \u201cinvolucrada en actividades en apoyo a Hamas, una organizaci\u00f3n terrorista extranjera\u201d.<\/p>\n<p><strong>La evidencia<\/strong>: El mes pasado, <a href=\"https:\/\/www.cnn.com\/2026\/01\/23\/politics\/court-documents-student-israel-op-ed\">un memorando reci\u00e9n publicado del Departamento de Estado<\/a> dijo que los investigadores no encontraron que \u00d6zt\u00fcrk hubiera \u201checho declaraciones p\u00fablicas indicando apoyo a una organizaci\u00f3n terrorista\u201d. Se\u00f1al\u00f3 que el DHS no encontr\u00f3 motivos para expulsarla por \u201capoyo material a una organizaci\u00f3n terrorista extranjera o actividad terrorista\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La inminente salida de la portavoz del Departamento de Seguridad Nacional, Tricia McLaughlin, de la agencia es la \u00faltima se\u00f1al de un reinicio en la agresiva estrategia de deportaci\u00f3n del Gobierno de Trump, que ha perdido un fuerte respaldo entre los estadounidenses. Y es dif\u00edcil exagerar el gran papel que jug\u00f3 en eso la comunicaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1471366","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Todas las afirmaciones del DHS de Trump que se han desmoronado - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/17\/afirmaciones-dhs-trump-desmoronado-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Todas las afirmaciones del DHS de Trump que se han desmoronado - Noticias\" \/>\n<meta property=\"og:description\" content=\"La inminente salida de la portavoz del Departamento de Seguridad Nacional, Tricia McLaughlin, de la agencia es la \u00faltima se\u00f1al de un reinicio en la agresiva estrategia de deportaci\u00f3n del Gobierno de Trump, que ha perdido un fuerte respaldo entre los estadounidenses. Y es dif\u00edcil exagerar el gran papel que jug\u00f3 en eso la comunicaci\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/17\/afirmaciones-dhs-trump-desmoronado-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-18T03:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/17\/afirmaciones-dhs-trump-desmoronado-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/17\/afirmaciones-dhs-trump-desmoronado-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Todas las afirmaciones del DHS de Trump que se han desmoronado\",\"datePublished\":\"2026-02-18T03:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/17\/afirmaciones-dhs-trump-desmoronado-trax\/\"},\"wordCount\":1573,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/17\/afirmaciones-dhs-trump-desmoronado-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/17\/afirmaciones-dhs-trump-desmoronado-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/17\/afirmaciones-dhs-trump-desmoronado-trax\/\",\"name\":\"Todas las afirmaciones del DHS de Trump que se han desmoronado - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-18T03:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/17\/afirmaciones-dhs-trump-desmoronado-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/17\/afirmaciones-dhs-trump-desmoronado-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/17\/afirmaciones-dhs-trump-desmoronado-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Todas las afirmaciones del DHS de Trump que se han desmoronado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Todas las afirmaciones del DHS de Trump que se han desmoronado - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/17\/afirmaciones-dhs-trump-desmoronado-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Todas las afirmaciones del DHS de Trump que se han desmoronado - Noticias","og_description":"La inminente salida de la portavoz del Departamento de Seguridad Nacional, Tricia McLaughlin, de la agencia es la \u00faltima se\u00f1al de un reinicio en la agresiva estrategia de deportaci\u00f3n del Gobierno de Trump, que ha perdido un fuerte respaldo entre los estadounidenses. Y es dif\u00edcil exagerar el gran papel que jug\u00f3 en eso la comunicaci\u00f3n [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/17\/afirmaciones-dhs-trump-desmoronado-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-18T03:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/17\/afirmaciones-dhs-trump-desmoronado-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/17\/afirmaciones-dhs-trump-desmoronado-trax\/"},"author":{"name":"","@id":""},"headline":"Todas las afirmaciones del DHS de Trump que se han desmoronado","datePublished":"2026-02-18T03:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/17\/afirmaciones-dhs-trump-desmoronado-trax\/"},"wordCount":1573,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/17\/afirmaciones-dhs-trump-desmoronado-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/17\/afirmaciones-dhs-trump-desmoronado-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/17\/afirmaciones-dhs-trump-desmoronado-trax\/","name":"Todas las afirmaciones del DHS de Trump que se han desmoronado - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-18T03:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/17\/afirmaciones-dhs-trump-desmoronado-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/17\/afirmaciones-dhs-trump-desmoronado-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/17\/afirmaciones-dhs-trump-desmoronado-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Todas las afirmaciones del DHS de Trump que se han desmoronado"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/17\/afirmaciones-dhs-trump-desmoronado-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Todas las afirmaciones del DHS de Trump que se han desmoronado","url":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/17\/afirmaciones-dhs-trump-desmoronado-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/17\/afirmaciones-dhs-trump-desmoronado-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-18T03:03:46Z","datePublished":"2026-02-18T03:03:46Z","dateModified":"2026-02-18T03:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Todas las afirmaciones del DHS de Trump que se han desmoronado\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/17\\\/afirmaciones-dhs-trump-desmoronado-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/02\\\/17\\\/afirmaciones-dhs-trump-desmoronado-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-18T03:03:46Z\",\"datePublished\":\"2026-02-18T03:03:46Z\",\"dateModified\":\"2026-02-18T03:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1469015,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/12\/05\/congresista-adelita-grijalva-gas-pimienta-redada-ice-trax\/","url_meta":{"origin":1471366,"position":0},"title":"La congresista Adelita Grijalva dice que fue rociada con gas pimienta durante una redada de ICE en Arizona","author":"","date":"diciembre 5, 2025","format":false,"excerpt":"La representante Adelita Grijalva dijo el viernes que fue rociada con gas pimienta y empujada durante una redada del Servicio Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en Tucson, Arizona, una afirmaci\u00f3n que el Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) refut\u00f3 r\u00e1pidamente.La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471350,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/17\/renuncia-tricia-mclaughlin-portavoz-departamento-seguridad-nacional-trax\/","url_meta":{"origin":1471366,"position":1},"title":"Renuncia la portavoz del Departamento de Seguridad Nacional Tricia McLaughlin","author":"","date":"febrero 17, 2026","format":false,"excerpt":"La principal portavoz del Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s), Tricia McLaughlin, renunciar\u00e1, dijo a CNN un funcionario del Gobieno de Trump.Se espera que McLaughlin deje su puesto de secretaria adjunta la pr\u00f3xima semana.Su salida se produce tras los tiroteos en Minnesota, donde relatos contradictorios pusieron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459634,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/03\/07\/gobierno-trump-detiene-familias-migrantes-ninos-inmigracion-ilegal-trax\/","url_meta":{"origin":1471366,"position":2},"title":"El Gobierno de Trump detiene a familias migrantes con ni\u00f1os como parte de su campa\u00f1a contra la inmigraci\u00f3n ilegal","author":"","date":"marzo 7, 2025","format":false,"excerpt":"El Gobierno de Donald Trump reconoce que est\u00e1 deteniendo a familias migrantes con ni\u00f1os como parte de una campa\u00f1a m\u00e1s amplia contra la inmigraci\u00f3n ilegal, dijo una portavoz del Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) a CNN.\u201cLa conclusi\u00f3n es que estas personas tienen \u00f3rdenes finales de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464557,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/07\/15\/gobierno-trump-deporta-inmigrantes-pais-distinto-de-origen-trax\/","url_meta":{"origin":1471366,"position":3},"title":"El Gobierno de Trump deporta a otro grupo de inmigrantes a un pa\u00eds distinto a su pa\u00eds de origen","author":"","date":"julio 15, 2025","format":false,"excerpt":"El Gobierno de Trump anunci\u00f3 el martes un nuevo vuelo de deportaci\u00f3n hacia un pa\u00eds lejano para inmigrantes indocumentados sin v\u00ednculos conocidos con ese destino.En esta ocasi\u00f3n, la portavoz del Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s), Tricia McLaughlin, inform\u00f3 en X que la agencia traslad\u00f3 a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464170,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/07\/03\/abogados-kilmar-abrego-el-salvador-trax\/","url_meta":{"origin":1471366,"position":4},"title":"Abogados de Kilmar \u00c1brego Garc\u00eda detallan torturas y malos tratos en la megac\u00e1rcel de El Salvador","author":"","date":"julio 3, 2025","format":false,"excerpt":"Los abogados de Kilmar \u00c1brego Garc\u00eda continuaron el mi\u00e9rcoles su esfuerzo para mantener vivo su caso civil contra la administraci\u00f3n Trump, solicitando enmendar la demanda para incluir lo que describen como la \u201ctortura y maltrato\u201d que experiment\u00f3 en la notoria megaprisi\u00f3n de El Salvador, adonde fue deportado injustamente y retenido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467153,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/10\/06\/miedo-corte-migratoria-cierre-gobierno-orix\/","url_meta":{"origin":1471366,"position":5},"title":"As\u00ed se vive el pasillo del terror, donde el cierre del Gobierno no detiene las deportaciones","author":"","date":"octubre 6, 2025","format":false,"excerpt":"En medio del cierre del Gobierno, un pasillo en una corte migratoria no ha cesado de funcionar como escenario del miedo y la presi\u00f3n en el marco de la ofensiva de la administraci\u00f3n de Trump, que busca acelerar cada vez m\u00e1s las deportaciones.Se trata del 26 Federal Plaza, en el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1471366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1471366"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1471366\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1471366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1471366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1471366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}