{"id":1472955,"date":"2026-04-08T03:03:48","date_gmt":"2026-04-08T10:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/08\/sospechosos-ataque-alcalde-mamdani-nueva-york-planes-trax\/"},"modified":"2026-04-08T03:03:48","modified_gmt":"2026-04-08T10:03:48","slug":"sospechosos-ataque-alcalde-mamdani-nueva-york-planes-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/08\/sospechosos-ataque-alcalde-mamdani-nueva-york-planes-trax\/","title":{"rendered":"Sospechosos del ataque frente a residencia del alcalde de Nueva York detallaron sus planes en cuadernos y grabaciones"},"content":{"rendered":"<p>Dos hombres acusados \u200b\u200bde <a href=\"https:\/\/www.cnn.com\/2026\/03\/10\/us\/mamdani-gracie-mansion-protest-what-we-know\">intentar detonar bombas caseras<\/a> durante las protestas cerca de la residencia del alcalde de la ciudad de Nueva York, Zohran Mamdani, el mes pasado, detallaron en un cuaderno y a trav\u00e9s de grabaciones de audio c\u00f3mo esperaban que su ataque matara a decenas de personas, seg\u00fan una acusaci\u00f3n formal publicada el martes.<\/p>\n<p>Emir Balat, de 18 a\u00f1os, e Ibrahim Kayumi, de 19, quienes fueron arrestados el 7 de marzo frente a Gracie Mansion, fueron acusados \u200b\u200bde ocho delitos, entre ellos proporcionar apoyo material a una organizaci\u00f3n terrorista extranjera y conspirar para usar un arma de destrucci\u00f3n masiva en el ataque inspirado por ISIS, seg\u00fan informaron los fiscales federales.<\/p>\n<p>\u201cLo \u00fanico que s\u00e9 es que quiero sembrar el terror, hermano\u201d y \u201cQuiero aterrorizar a esta gente\u201d, le dijo Kayumi a Balat la ma\u00f1ana del ataque, seg\u00fan un video grabado por la c\u00e1mara del tablero del auto mientras los dos viajaban de Pensilvania a Manhattan, seg\u00fan la acusaci\u00f3n.<\/p>\n<p><a href=\"https:\/\/www.cnn.com\/2026\/03\/10\/politics\/mamdani-gracie-mansion-response-balancing-act\">Seg\u00fan explic\u00f3, Mamdani<\/a>, el primer alcalde musulm\u00e1n de la ciudad, y su esposa, Rama Duwaji, no se encontraban en casa en ese momento.<\/p>\n<p>La acusaci\u00f3n detalla las pruebas obtenidas del veh\u00edculo presuntamente utilizado por Balat y Kayumi, ciudadanos estadounidenses de Pensilvania, incluyendo una libreta manuscrita y aproximadamente tres d\u00edas de grabaciones de video y audio de la c\u00e1mara del salpicadero.<\/p>\n<p>El cuaderno inclu\u00eda los pasos de su plan, entre ellos una lista de ingredientes y equipos necesarios para mezclar explosivos y los pasos para construir una bomba.<\/p>\n<p>En otra parte del cuaderno, figuraban detalles de un aparente plan alternativo para un ataque utilizando un veh\u00edculo y una lista de posibles objetivos, \u201cque inclu\u00edan \u2018festivales\u2019, \u2018desfiles\u2019, \u2018protestas\u2019 y \u2018celebraciones\u2019\u201d, seg\u00fan indica el documento.<\/p>\n<p>Seg\u00fan el documento, las grabaciones de la c\u00e1mara del salpicadero, captadas durante su trayecto desde Pensilvania hasta Manhattan, detallaban las conversaciones sobre c\u00f3mo llevar\u00edan a cabo el ataque, el probable resultado del mismo y c\u00f3mo ten\u00edan como objetivo a \u201cel gobierno\u201d y a \u201clos civiles\u201d.<\/p>\n<p>Tras el ataque, agentes del FBI recuperaron \u201crestos de explosivos y materiales para fabricar bombas\u201d del interior de un almac\u00e9n en Pensilvania que Balat hab\u00eda alquilado pocos d\u00edas antes, seg\u00fan el documento. Entre las pruebas se encontraban dos recipientes con residuos del potente explosivo TATP.<\/p>\n<p>CNN se ha puesto en contacto con los abogados de Balat y Kayumi para obtener comentarios.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dos hombres acusados \u200b\u200bde intentar detonar bombas caseras durante las protestas cerca de la residencia del alcalde de la ciudad de Nueva York, Zohran Mamdani, el mes pasado, detallaron en un cuaderno y a trav\u00e9s de grabaciones de audio c\u00f3mo esperaban que su ataque matara a decenas de personas, seg\u00fan una acusaci\u00f3n formal publicada el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1472955","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sospechosos del ataque frente a residencia del alcalde de Nueva York detallaron sus planes en cuadernos y grabaciones - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/08\/sospechosos-ataque-alcalde-mamdani-nueva-york-planes-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sospechosos del ataque frente a residencia del alcalde de Nueva York detallaron sus planes en cuadernos y grabaciones - Noticias\" \/>\n<meta property=\"og:description\" content=\"Dos hombres acusados \u200b\u200bde intentar detonar bombas caseras durante las protestas cerca de la residencia del alcalde de la ciudad de Nueva York, Zohran Mamdani, el mes pasado, detallaron en un cuaderno y a trav\u00e9s de grabaciones de audio c\u00f3mo esperaban que su ataque matara a decenas de personas, seg\u00fan una acusaci\u00f3n formal publicada el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/08\/sospechosos-ataque-alcalde-mamdani-nueva-york-planes-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-08T10:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/08\/sospechosos-ataque-alcalde-mamdani-nueva-york-planes-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/08\/sospechosos-ataque-alcalde-mamdani-nueva-york-planes-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Sospechosos del ataque frente a residencia del alcalde de Nueva York detallaron sus planes en cuadernos y grabaciones\",\"datePublished\":\"2026-04-08T10:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/08\/sospechosos-ataque-alcalde-mamdani-nueva-york-planes-trax\/\"},\"wordCount\":452,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/08\/sospechosos-ataque-alcalde-mamdani-nueva-york-planes-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/08\/sospechosos-ataque-alcalde-mamdani-nueva-york-planes-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/08\/sospechosos-ataque-alcalde-mamdani-nueva-york-planes-trax\/\",\"name\":\"Sospechosos del ataque frente a residencia del alcalde de Nueva York detallaron sus planes en cuadernos y grabaciones - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-08T10:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/08\/sospechosos-ataque-alcalde-mamdani-nueva-york-planes-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/08\/sospechosos-ataque-alcalde-mamdani-nueva-york-planes-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/08\/sospechosos-ataque-alcalde-mamdani-nueva-york-planes-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sospechosos del ataque frente a residencia del alcalde de Nueva York detallaron sus planes en cuadernos y grabaciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sospechosos del ataque frente a residencia del alcalde de Nueva York detallaron sus planes en cuadernos y grabaciones - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/08\/sospechosos-ataque-alcalde-mamdani-nueva-york-planes-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Sospechosos del ataque frente a residencia del alcalde de Nueva York detallaron sus planes en cuadernos y grabaciones - Noticias","og_description":"Dos hombres acusados \u200b\u200bde intentar detonar bombas caseras durante las protestas cerca de la residencia del alcalde de la ciudad de Nueva York, Zohran Mamdani, el mes pasado, detallaron en un cuaderno y a trav\u00e9s de grabaciones de audio c\u00f3mo esperaban que su ataque matara a decenas de personas, seg\u00fan una acusaci\u00f3n formal publicada el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/08\/sospechosos-ataque-alcalde-mamdani-nueva-york-planes-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-08T10:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/08\/sospechosos-ataque-alcalde-mamdani-nueva-york-planes-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/08\/sospechosos-ataque-alcalde-mamdani-nueva-york-planes-trax\/"},"author":{"name":"","@id":""},"headline":"Sospechosos del ataque frente a residencia del alcalde de Nueva York detallaron sus planes en cuadernos y grabaciones","datePublished":"2026-04-08T10:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/08\/sospechosos-ataque-alcalde-mamdani-nueva-york-planes-trax\/"},"wordCount":452,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/08\/sospechosos-ataque-alcalde-mamdani-nueva-york-planes-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/08\/sospechosos-ataque-alcalde-mamdani-nueva-york-planes-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/08\/sospechosos-ataque-alcalde-mamdani-nueva-york-planes-trax\/","name":"Sospechosos del ataque frente a residencia del alcalde de Nueva York detallaron sus planes en cuadernos y grabaciones - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-08T10:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/08\/sospechosos-ataque-alcalde-mamdani-nueva-york-planes-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/08\/sospechosos-ataque-alcalde-mamdani-nueva-york-planes-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/08\/sospechosos-ataque-alcalde-mamdani-nueva-york-planes-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Sospechosos del ataque frente a residencia del alcalde de Nueva York detallaron sus planes en cuadernos y grabaciones"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/08\/sospechosos-ataque-alcalde-mamdani-nueva-york-planes-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Sospechosos del ataque frente a residencia del alcalde de Nueva York detallaron sus planes en cuadernos y grabaciones","url":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/08\/sospechosos-ataque-alcalde-mamdani-nueva-york-planes-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/08\/sospechosos-ataque-alcalde-mamdani-nueva-york-planes-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-08T10:03:48Z","datePublished":"2026-04-08T10:03:48Z","dateModified":"2026-04-08T10:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Sospechosos del ataque frente a residencia del alcalde de Nueva York detallaron sus planes en cuadernos y grabaciones\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/04\\\/08\\\/sospechosos-ataque-alcalde-mamdani-nueva-york-planes-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/04\\\/08\\\/sospechosos-ataque-alcalde-mamdani-nueva-york-planes-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-08T10:03:48Z\",\"datePublished\":\"2026-04-08T10:03:48Z\",\"dateModified\":\"2026-04-08T10:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1472046,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/03\/10\/mamdani-gracie-mansion-protesta-detenidos-trax\/","url_meta":{"origin":1472955,"position":0},"title":"Qui\u00e9nes son los dos acusados \u200b\u200bde lanzar bombas improvisadas cerca de la casa de Mamdani en Nueva York","author":"","date":"marzo 10, 2026","format":false,"excerpt":"Este s\u00e1bado, dos hombres de Pensilvania siguieron la ruta de miles de personas al cruzar el puente George Washington hacia la ciudad de Nueva York. Pero menos de una hora despu\u00e9s, su trayectoria dio un giro sombr\u00edo al ser arrestados por lanzar bombas caseras durante una protesta antimusulmana frente a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448229,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/04\/17\/matan-a-jose-sanchez-alcalde-del-canton-ponce-enriquez-en-ecuador-orix\/","url_meta":{"origin":1472955,"position":1},"title":"Matan a Jos\u00e9 S\u00e1nchez, alcalde del cant\u00f3n Ponce Enr\u00edquez en Ecuador","author":"","date":"abril 17, 2024","format":false,"excerpt":"(CNN En Espa\u00f1ol) -- El prefecto de la provincia de Azuay, Juan Crist\u00f3bal Lloret, confirm\u00f3 este mi\u00e9rcoles por la noche la muerte, tras un ataque armado, de Jos\u00e9 S\u00e1nchez, alcalde del cant\u00f3n Camilo Ponce Enr\u00edquez, ubicado en la provincia de Azuay al sur de Ecuador.\u201cEntre sollozos e impotencia funcionarios municipales\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469426,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/12\/19\/ataque-eln-ejercito-muertos-colombia-orix\/","url_meta":{"origin":1472955,"position":2},"title":"Sube a 7 el n\u00famero de muertos tras ataque contra una base del Ej\u00e9rcito de Colombia en el norte del pa\u00eds","author":"","date":"diciembre 19, 2025","format":false,"excerpt":"Siete soldados murieron y otros resultaron heridos este jueves tras un ataque con explosivos contra una base del Ej\u00e9rcito de Colombia en el norte del pa\u00eds, seg\u00fan anunci\u00f3 la Segunda Divisi\u00f3n del Ej\u00e9rcito.El presunto atentado tuvo lugar contra la Base Militar del 27, adscrita al Batall\u00f3n de Infanter\u00eda N\u00famero 14,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472000,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/03\/08\/explosivo-casa-mamdani-alcalde-nueva-york-trax\/","url_meta":{"origin":1472955,"position":3},"title":"Lanzan explosivo casero cerca de la casa del alcalde de Nueva York","author":"","date":"marzo 8, 2026","format":false,"excerpt":"Una jornada de intensas protestas frente a la residencia del alcalde de Nueva York deriv\u00f3 en caos el s\u00e1bado, luego de que un manifestante arrojara un explosivo improvisado en pleno paso peatonal.El dispositivo era capaz de causar \u201clesiones graves o la muerte\u201d, dijo la Polic\u00eda de Nueva York (NYPD) el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1453080,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/09\/25\/acusan-al-alcalde-de-nueva-york-eric-adams-trax\/","url_meta":{"origin":1472955,"position":4},"title":"Imputan al alcalde de Nueva York, Eric Adams, seg\u00fan fuentes","author":"","date":"septiembre 25, 2024","format":false,"excerpt":"(CNN) -- El alcalde de Nueva York, Eric Adams, fue acusado de al menos un delito federal, seg\u00fan informan a CNN varias fuentes familiarizadas con el asunto.El New York Times fue el primero en informar de la acusaci\u00f3n.La acusaci\u00f3n es consecuencia de una investigaci\u00f3n federal de un mes de duraci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455159,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/10\/16\/capturan-bogota-integrantes-tren-aragua-ataque-orix\/","url_meta":{"origin":1472955,"position":5},"title":"Capturan en Bogot\u00e1 a presuntos integrantes del Tren de Aragua por ataque con granada que dej\u00f3 dos muertos","author":"","date":"octubre 16, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Cinco personas presuntamente vinculadas a la organizaci\u00f3n criminal transnacional Tren de Aragua, que supuestamente participaron en un ataque con granada en septiembre, fueron capturadas en Bogot\u00e1, anunci\u00f3 el alcalde de la capital colombiana, Carlos Gal\u00e1n, este mi\u00e9rcoles.\"Hoy queremos reportar un resultado muy importante en la lucha contra la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1472955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1472955"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1472955\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1472955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1472955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1472955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}