{"id":1472959,"date":"2026-04-08T05:03:48","date_gmt":"2026-04-08T12:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/08\/agentes-tsa-salarios-atrasados-facturas-acumuladas-trax\/"},"modified":"2026-04-08T05:03:48","modified_gmt":"2026-04-08T12:03:48","slug":"agentes-tsa-salarios-atrasados-facturas-acumuladas-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/08\/agentes-tsa-salarios-atrasados-facturas-acumuladas-trax\/","title":{"rendered":"Agentes de la TSA recibieron parte de sus salarios atrasados. Afirman que no es suficiente para cubrir facturas acumuladas"},"content":{"rendered":"<p>Una supervisora \u200b\u200bde la Administraci\u00f3n de Seguridad del Transporte, que sufre de insomnio y estr\u00e9s desde que comenz\u00f3 el cierre parcial del Gobierno a mediados de febrero, estaba despierta a las 3:00 de la madrugada del 30 de marzo cuando recibi\u00f3 en su tel\u00e9fono la alerta que llevaba semanas esperando con impaciencia.<\/p>\n<p>Le hab\u00edan ingresado su sueldo en su cuenta bancaria, el primero en semanas.<\/p>\n<p>Pero en cuanto vio la cantidad, pens\u00f3: \u201c\u00bfD\u00f3nde est\u00e1 el resto?\u201d. Le faltaban al menos US$ 1.000 d\u00f3lares de atrasos, lo que empa\u00f1\u00f3 su alivio. Calcul\u00f3 que los pocos miles de d\u00f3lares que s\u00ed recibi\u00f3 apenas cubr\u00edan la mitad de sus gastos pendientes.<\/p>\n<p>\u201cEl dinero se esfum\u00f3 en cuesti\u00f3n de d\u00edas, apenas alcanzaba para pagar las facturas que pod\u00eda cubrir\u201d, declar\u00f3 la supervisora del Aeropuerto Internacional de Tampa, quien lleva una d\u00e9cada trabajando en la agencia. \u201cTodav\u00eda tengo que llamar a todos mis acreedores y hablar con diferentes personas para decirles: \u2018Oigan, denme un poco de tiempo\u2019. Es rid\u00edculo\u201d.<\/p>\n<p>La supervisora, que solicit\u00f3 el anonimato al hablar de su trabajo, es una de las decenas de miles de empleados de la TSA que recibieron al menos parte del pago retroactivo que se les adeudaba despu\u00e9s de que el presidente Donald Trump <a href=\"https:\/\/www.cnn.com\/2026\/03\/26\/politics\/dhs-shutdown-funding-talks-congress\">ordenara<\/a> al Departamento de Seguridad Nacional <a href=\"https:\/\/www.cnn.com\/2026\/03\/27\/politics\/when-tsa-paid-trump-shutdown\">pagar a los trabajadores de la TSA<\/a>.<\/p>\n<p>Esta medida se produjo despu\u00e9s de que el Congreso no lograra llegar a un acuerdo para financiar la agencia, dejando a los empleados de la TSA trabajando sin retribuci\u00f3n.<\/p>\n<p>Como consecuencia, miles de empleados dejaron de ir a trabajar, lo que provoc\u00f3 <a href=\"https:\/\/www.cnn.com\/2026\/03\/10\/us\/tsa-shutdown-lines\" rel=\"noopener noreferrer\" target=\"_blank\">largas filas<\/a> en muchos aeropuertos estadounidenses. Trump pag\u00f3 a los trabajadores con fondos provenientes de su <a href=\"https:\/\/www.cnn.com\/2025\/07\/01\/politics\/congress-senate-bill-tax-spending-trump-gop-explainer\" rel=\"noopener noreferrer\" target=\"_blank\">amplio paquete de medidas de pol\u00edtica interna,<\/a> que firm\u00f3 el verano pasado.<\/p>\n<p>No est\u00e1 claro cu\u00e1ndo terminar\u00e1 el <a href=\"https:\/\/www.cnn.com\/2026\/02\/12\/politics\/department-homeland-security-government-shutdown\">cierre parcial del Gobierno, que seg\u00fan la administraci\u00f3n es el m\u00e1s largo de la historia, ya que el Congreso se fue de receso de dos semanas en Washington sin aprobar nuevos fondos para el departamento. <\/a><\/p>\n<p><a href=\"https:\/\/www.cnn.com\/2026\/02\/12\/politics\/department-homeland-security-government-shutdown\">Trump orden\u00f3 que <\/a><a href=\"https:\/\/www.cnn.com\/2026\/04\/02\/politics\/dhs-senate-house-bill\">se les pagara a todos los empleados del DHS<\/a>, ampliando una directiva anterior.<\/p>\n<p>Cuando el Congreso regrese a Washington la pr\u00f3xima semana, se espera que la C\u00e1mara de Representantes considere una medida de financiamiento parcial que originalmente fue rechazada antes del receso.<\/p>\n<p>El presidente de la C\u00e1mara, Mike Johnson, anunci\u00f3 <a href=\"https:\/\/www.cnn.com\/2026\/04\/01\/politics\/dhs-shutdown-republican-leaders-plan\" rel=\"noopener noreferrer\" target=\"_blank\">un plan de dos v\u00edas<\/a> junto con el l\u00edder de la mayor\u00eda del Senado, John Thune, la semana pasada.<\/p>\n<p>Sin embargo, no est\u00e1 claro cu\u00e1ndo, o si, la C\u00e1mara de Representantes aprobar\u00e1 el proyecto de ley que <a href=\"https:\/\/www.cnn.com\/2026\/03\/27\/politics\/dhs-shutdown-funding-bill-senate-house-vote\">inicialmente hab\u00edan rechazado<\/a>, y la adopci\u00f3n de cualquier proyecto de ley con una agenda m\u00e1s amplia ser\u00e1 una prueba importante para los l\u00edderes republicanos que se enfrentan a m\u00e1rgenes ajustados en el Congreso a solo unos meses de las elecciones de mitad de mandato.<\/p>\n<p>Por ahora, los trabajadores se encuentran en una situaci\u00f3n de incertidumbre, sin ninguna garant\u00eda de que el cierre vaya a terminar pronto.<\/p>\n<p>Se espera que el pr\u00f3ximo d\u00eda de pago sea alrededor de este viernes e incluir\u00e1 la compensaci\u00f3n actual junto con las horas extras no retribuidas y el saldo de un cheque parcial de finales de febrero, seg\u00fan Johnny Jones, secretario-tesorero nacional del sindicato que representa a los agentes de la TSA, la Federaci\u00f3n Estadounidense de Empleados Gubernamentales, Consejo 100 de la TSA.<\/p>\n<p>\u201cEl sexto pago ya est\u00e1 listo, y todo indica que (los trabajadores) recibir\u00e1n el pago retroactivo y los ajustes en el pr\u00f3ximo mes de abril\u201d, afirm\u00f3.<\/p>\n<p>Sin embargo, el sindicato afirm\u00f3 que existe una creciente preocupaci\u00f3n e incertidumbre sobre la compensanci\u00f3n de los sueldos a fin de mes.<\/p>\n<p>En un memorando dirigido a \u201ctodos los empleados del DHS\u201d, enviado el lunes y al que tuvo acceso CNN, se inform\u00f3 a los trabajadores que recibir\u00e1n su salario a finales de esta semana, seg\u00fan lo previsto, as\u00ed como el resto del pago correspondiente a finales de febrero y cualquier per\u00edodo adicional por el que no hayan recibido remuneraci\u00f3n desde que comenz\u00f3 el cierre del Gobierno.<\/p>\n<p>Para colmo de la confusi\u00f3n y la inquietud de los trabajadores, el memorando sugiere que este podr\u00eda ser el \u00faltimo cheque en un tiempo.<\/p>\n<p>Sin embargo, el martes por la noche, un funcionario de la administraci\u00f3n declar\u00f3 a CNN que el memorando en realidad no se aplicaba a los trabajadores de la TSA.<\/p>\n<p>En un comunicado enviado a CNN a \u00faltima hora del martes, el Departamento de Seguridad Nacional (DHS) inform\u00f3 que los empleados de la TSA recibir\u00e1n su salario, previsto para finales de abril.<\/p>\n<p>Por el momento, los trabajadores de la TSA se encuentran en una situaci\u00f3n de incertidumbre, ya que las facturas y el estr\u00e9s siguen acumul\u00e1ndose y se est\u00e1n tomando decisiones dif\u00edciles, dijo Antoinette Wade, funcionaria de la TSA y presidenta de AFGE 1047, el sindicato que representa a los trabajadores de la TSA en Louisiana y Misisipi.<\/p>\n<p>\u201cLa gente tiene que priorizar qu\u00e9 medicamentos recetados compra y a qu\u00e9 miembros de la familia les da prioridad antes de comprar los suyos\u201d, indic\u00f3. \u201cEso los pone en riesgo para su salud. He escuchado muchas historias de padres que tienen que tomar decisiones muy dif\u00edciles por sus hijos en estos momentos. Es desalentador, y nadie deber\u00eda verse en esta situaci\u00f3n\u201d.<\/p>\n<p>El sindicato ha comenzado a abogar por bonos de US$ 10.000 para todos los trabajadores de la TSA, porque \u201cnecesitan ser compensados\u201d, declar\u00f3 Jones. El DHS otorg\u00f3 US$ 10.000 a los trabajadores despu\u00e9s del \u00faltimo cierre, pero solo a aquellos que se presentaron a todos sus turnos programados y no faltaron.<\/p>\n<p>Los trabajadores siguen esperando ser indemnizados.<\/p>\n<p>\u201cPor suerte, ya podemos empezar a pagar algunas de esas facturas\u201d, manifest\u00f3 Wade. \u201cLlevamos meses debi\u00e9ndolas, y eso nos ha ayudado, pero no es suficiente. Seguimos pasando apuros econ\u00f3micos\u201d.<\/p>\n<p>Sin embargo, seg\u00fan Jones, muchos empleados de la TSA afirman no haber recibido la totalidad de los pagos que les correspond\u00edan en marzo.<\/p>\n<p>\u201cAlgunas personas recibieron su sueldo completo, pero parece que la gran mayor\u00eda de los que faltaron al trabajo fueron dados de baja sin permiso o no recibieron el pago correcto\u201d, declar\u00f3 a CNN.<\/p>\n<p>Seg\u00fan las nuevas normas de este a\u00f1o, la TSA exige documentaci\u00f3n detallada si alguien est\u00e1 enfermo o tiene otro motivo justificado por el que no pudo entrar. Si no presentan la documentaci\u00f3n o esta no es aceptada, se les registra como ausentes sin permiso.<\/p>\n<p>Los trabajadores que se ausenten sin permiso no recibir\u00e1n remuneraci\u00f3n por el tiempo que no se presenten a trabajar, y no podr\u00e1n utilizar sus vacaciones ni sus d\u00edas de baja por enfermedad para cubrir dicha ausencia.<\/p>\n<p>Un agente de la TSA en Nashville tuvo que usar su reembolso de impuestos para pagar el alquiler del mes pasado y parte de la guarder\u00eda de sus hijos, seg\u00fan cont\u00f3 su esposa a CNN. Los cheques que recibi\u00f3 la semana pasada tambi\u00e9n fueron directamente a parar a la guarder\u00eda.<\/p>\n<p>Esto ha dejado a la familia sin recursos para reparar uno de sus veh\u00edculos ni para celebrar la fiesta de cumplea\u00f1os de uno de sus hijos como hab\u00edan planeado. En su lugar, servir\u00e1n menos comida y prescindir\u00e1n de un arco de globos para ahorrar dinero.<\/p>\n<p>Adem\u00e1s, aunque le pagaron por el tiempo que se tom\u00f3 libre para cuidar a su familia cuando enfermaron durante el cierre, la agencia cuestion\u00f3 posteriormente la validez de su justificante m\u00e9dico y solicit\u00f3 la aprobaci\u00f3n de su supervisor.<\/p>\n<p>El asunto se resolvi\u00f3 a su favor. Pero ahora, \u00e9l y su esposa est\u00e1n preocupados por lo que suceder\u00eda si tiene que tomarse otro d\u00eda libre antes de que termine el impasse, a pesar de que a\u00fan tiene d\u00edas por enfermedad y vacaciones pagadas.<\/p>\n<p>\u201cEs casi como si intentaran castigar a los agentes. \u00bfSe tratar\u00e1 de una reprimenda o una medida disciplinaria que podr\u00eda costarle el puesto?\u201d, cuestion\u00f3. \u201cEs como sentir que nuestra cabeza est\u00e1 en la guillotina, esperando a que caiga\u201d.<\/p>\n<p>Si bien los fondos recientes est\u00e1n ayudando a la gente a ponerse al d\u00eda con el alquiler, algunos empleados todav\u00eda est\u00e1n luchando por salir del apuro, lidiando con recargos por mora de US$ 75 diarios porque no pudieron realizar el pago a tiempo, seg\u00fan Jones.<\/p>\n<p>\u201cComo este cierre no afect\u00f3 a todas las agencias y nadie estaba siendo compensado, los cobradores de deudas y las empresas de alquiler dec\u00edan: \u2018Esta vez no nos importa mucho, no vamos a poder hacer nada por ustedes\u2019\u201d, afirm\u00f3 Jones.<\/p>\n<p>La administraci\u00f3n Trump afirma ahora que este es el cierre del Gobierno m\u00e1s largo de la historia estadounidense; sin embargo, solo afecta al Departamento de Seguridad Nacional (DHS), mientras que muchas crisis anteriores, incluida la del oto\u00f1o pasado, afectaron a todo el aparato gubernamental.<\/p>\n<p>En esta ocasi\u00f3n, muchos viajeros ni siquiera se percataron del cierre hasta que las colas daban la vuelta a los aeropuertos.<\/p>\n<p>\u201cA la gente le han dicho literalmente: \u2018Miren, no hay nada que podamos hacer\u2019\u201d, explic\u00f3 Wade.<\/p>\n<p>El \u00faltimo cierre, que se produce apenas unos meses despu\u00e9s del estancamiento de seis semanas del oto\u00f1o pasado, ha llevado a algunos trabajadores a preguntarse si deber\u00edan seguir trabajando para la TSA, seg\u00fan Cameron Cochems, vicepresidente regional de Idaho del sindicato AFGE Local 1127.<\/p>\n<p>Cientos de personas han renunciado desde mediados de febrero.<\/p>\n<p>\u201cEst\u00e1 trastocando nuestras vidas, no solo en el aspecto financiero, sino que tambi\u00e9n es emocionalmente agotador\u201d, declar\u00f3. \u201cLa gente no puede planificar su vida. No pueden decidir qu\u00e9 quieren hacer en una o dos semanas porque no saben si habr\u00e1 otro cierre o si este va a continuar\u201d.<\/p>\n<p>El Congreso regresa de su receso la pr\u00f3xima semana, y solo entonces podr\u00e1 alcanzar una soluci\u00f3n a largo plazo para los trabajadores del DHS.<\/p>\n<p>\u201cYa hemos tenido que cancelar nuestras vacaciones mientras (el Congreso) se va de vacaciones\u201d, expuso Jones.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una supervisora \u200b\u200bde la Administraci\u00f3n de Seguridad del Transporte, que sufre de insomnio y estr\u00e9s desde que comenz\u00f3 el cierre parcial del Gobierno a mediados de febrero, estaba despierta a las 3:00 de la madrugada del 30 de marzo cuando recibi\u00f3 en su tel\u00e9fono la alerta que llevaba semanas esperando con impaciencia. Le hab\u00edan ingresado [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1472959","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Agentes de la TSA recibieron parte de sus salarios atrasados. Afirman que no es suficiente para cubrir facturas acumuladas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/08\/agentes-tsa-salarios-atrasados-facturas-acumuladas-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agentes de la TSA recibieron parte de sus salarios atrasados. Afirman que no es suficiente para cubrir facturas acumuladas - Noticias\" \/>\n<meta property=\"og:description\" content=\"Una supervisora \u200b\u200bde la Administraci\u00f3n de Seguridad del Transporte, que sufre de insomnio y estr\u00e9s desde que comenz\u00f3 el cierre parcial del Gobierno a mediados de febrero, estaba despierta a las 3:00 de la madrugada del 30 de marzo cuando recibi\u00f3 en su tel\u00e9fono la alerta que llevaba semanas esperando con impaciencia. Le hab\u00edan ingresado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/08\/agentes-tsa-salarios-atrasados-facturas-acumuladas-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-08T12:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/08\/agentes-tsa-salarios-atrasados-facturas-acumuladas-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/08\/agentes-tsa-salarios-atrasados-facturas-acumuladas-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Agentes de la TSA recibieron parte de sus salarios atrasados. Afirman que no es suficiente para cubrir facturas acumuladas\",\"datePublished\":\"2026-04-08T12:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/08\/agentes-tsa-salarios-atrasados-facturas-acumuladas-trax\/\"},\"wordCount\":1744,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/08\/agentes-tsa-salarios-atrasados-facturas-acumuladas-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/08\/agentes-tsa-salarios-atrasados-facturas-acumuladas-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/08\/agentes-tsa-salarios-atrasados-facturas-acumuladas-trax\/\",\"name\":\"Agentes de la TSA recibieron parte de sus salarios atrasados. Afirman que no es suficiente para cubrir facturas acumuladas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-08T12:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/08\/agentes-tsa-salarios-atrasados-facturas-acumuladas-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/08\/agentes-tsa-salarios-atrasados-facturas-acumuladas-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/08\/agentes-tsa-salarios-atrasados-facturas-acumuladas-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agentes de la TSA recibieron parte de sus salarios atrasados. Afirman que no es suficiente para cubrir facturas acumuladas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Agentes de la TSA recibieron parte de sus salarios atrasados. Afirman que no es suficiente para cubrir facturas acumuladas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/08\/agentes-tsa-salarios-atrasados-facturas-acumuladas-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Agentes de la TSA recibieron parte de sus salarios atrasados. Afirman que no es suficiente para cubrir facturas acumuladas - Noticias","og_description":"Una supervisora \u200b\u200bde la Administraci\u00f3n de Seguridad del Transporte, que sufre de insomnio y estr\u00e9s desde que comenz\u00f3 el cierre parcial del Gobierno a mediados de febrero, estaba despierta a las 3:00 de la madrugada del 30 de marzo cuando recibi\u00f3 en su tel\u00e9fono la alerta que llevaba semanas esperando con impaciencia. Le hab\u00edan ingresado [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/08\/agentes-tsa-salarios-atrasados-facturas-acumuladas-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-08T12:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/08\/agentes-tsa-salarios-atrasados-facturas-acumuladas-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/08\/agentes-tsa-salarios-atrasados-facturas-acumuladas-trax\/"},"author":{"name":"","@id":""},"headline":"Agentes de la TSA recibieron parte de sus salarios atrasados. Afirman que no es suficiente para cubrir facturas acumuladas","datePublished":"2026-04-08T12:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/08\/agentes-tsa-salarios-atrasados-facturas-acumuladas-trax\/"},"wordCount":1744,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/08\/agentes-tsa-salarios-atrasados-facturas-acumuladas-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/08\/agentes-tsa-salarios-atrasados-facturas-acumuladas-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/08\/agentes-tsa-salarios-atrasados-facturas-acumuladas-trax\/","name":"Agentes de la TSA recibieron parte de sus salarios atrasados. Afirman que no es suficiente para cubrir facturas acumuladas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-08T12:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/08\/agentes-tsa-salarios-atrasados-facturas-acumuladas-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/08\/agentes-tsa-salarios-atrasados-facturas-acumuladas-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/08\/agentes-tsa-salarios-atrasados-facturas-acumuladas-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Agentes de la TSA recibieron parte de sus salarios atrasados. Afirman que no es suficiente para cubrir facturas acumuladas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/08\/agentes-tsa-salarios-atrasados-facturas-acumuladas-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Agentes de la TSA recibieron parte de sus salarios atrasados. Afirman que no es suficiente para cubrir facturas acumuladas","url":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/08\/agentes-tsa-salarios-atrasados-facturas-acumuladas-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/08\/agentes-tsa-salarios-atrasados-facturas-acumuladas-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-08T12:03:48Z","datePublished":"2026-04-08T12:03:48Z","dateModified":"2026-04-08T12:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Agentes de la TSA recibieron parte de sus salarios atrasados. Afirman que no es suficiente para cubrir facturas acumuladas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/04\\\/08\\\/agentes-tsa-salarios-atrasados-facturas-acumuladas-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/04\\\/08\\\/agentes-tsa-salarios-atrasados-facturas-acumuladas-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-08T12:03:48Z\",\"datePublished\":\"2026-04-08T12:03:48Z\",\"dateModified\":\"2026-04-08T12:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1472478,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/03\/23\/fondos-contribuyentes-caballo-peluqueria-anuncio-noem-trax\/","url_meta":{"origin":1472959,"position":0},"title":"Miles de d\u00f3lares de los contribuyentes se gastaron en un caballo, peluquer\u00eda y m\u00e1s para el anuncio de Noem en Monte Rushmore","author":"","date":"marzo 23, 2026","format":false,"excerpt":"Decenas de miles de d\u00f3lares de los contribuyentes se gastaron en peluquer\u00eda y maquillaje y en un caballo para el anuncio que mostraba a la secretaria saliente del Departamento de Seguridad Nacional, Kristi Noem, frente al Monte Rushmore, seg\u00fan facturas vistas por CNN.Las facturas al Strategy Group, un subcontratista del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447169,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/03\/21\/gastos-campana-presidencial-2024-biden-trump-informes-financieros-trax\/","url_meta":{"origin":1472959,"position":1},"title":"El dinero de campa\u00f1a Biden aumenta, los honorarios de abogados de Trump se acumulan y m\u00e1s conclusiones de los \u00faltimos informes financieros","author":"","date":"marzo 21, 2024","format":false,"excerpt":"(CNN) -- La campa\u00f1a de Donald Trump experiment\u00f3 un aumento en las donaciones en febrero, pero no logr\u00f3 igualar el ritmo acelerado de recaudaci\u00f3n de fondos establecido por Joe Biden, cuya operaci\u00f3n pol\u00edtica ampli\u00f3 su ya sustancial ventaja financiera sobre su rival republicano al empezar marzo y enfrentarse a la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466617,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/09\/19\/precio-calefaccion-subir-estadounidenses-trax\/","url_meta":{"origin":1472959,"position":2},"title":"M\u00e1s malas noticias para los estadounidenses que luchan contra la inflaci\u00f3n: el precio de la calefacci\u00f3n est\u00e1 a punto de subir","author":"","date":"septiembre 19, 2025","format":false,"excerpt":"Las facturas de calefacci\u00f3n de este invierno le pondr\u00e1n la piel de gallina a muchos estadounidenses.Se espera que el costo de mantenerse caliente en casa aumente un promedio de 7,6 %, hasta US$ 976 esta temporada, seg\u00fan una nueva estimaci\u00f3n de la Asociaci\u00f3n Nacional de Directores de Asistencia Energ\u00e9tica. El\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1410775,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2022\/07\/05\/quien-era-el-mexicano-que-murio-en-el-tiroteo-del-4-de-julio\/","url_meta":{"origin":1472959,"position":3},"title":"\u00bfQui\u00e9n era el mexicano que muri\u00f3 en el tiroteo del 4 de julio?","author":"agomez","date":"julio 5, 2022","format":false,"excerpt":"Nicol\u00e1s Toledo era padre de 8 hijos y abuelo de muchos nietos, escribi\u00f3 su nieta Xochil Toledo.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471153,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/12\/facturas-calefaccion-suben-frio-extremo-trax\/","url_meta":{"origin":1472959,"position":4},"title":"El fr\u00edo extremo dispara las facturas de calefacci\u00f3n en Estados Unidos","author":"agomez","date":"febrero 12, 2026","format":false,"excerpt":"Laura Kotting calcul\u00f3 que su factura de calefacci\u00f3n ser\u00eda m\u00e1s alta de lo habitual debido a las recientes temperaturas polares. Pero no estaba preparada para que el cobro mensual m\u00e1s reciente aumentara casi 30 % hasta los US$ 200 en comparaci\u00f3n con el a\u00f1o pasado.\u201cLo primero que pens\u00e9 fue: \u2018No\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457301,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/01\/07\/deudas-medicas-eliminaran-informes-crediticios-trax\/","url_meta":{"origin":1472959,"position":5},"title":"Las deudas m\u00e9dicas dejar\u00e1n de aparecer en los historiales crediticios","author":"","date":"enero 7, 2025","format":false,"excerpt":"Los estadounidenses ya no tendr\u00e1n que preocuparse por facturas m\u00e9dicas impagas que da\u00f1en sus informes y puntuaciones crediticias.El Gobierno de Biden est\u00e1 ultimando una medida que pondr\u00e1 fin a la inclusi\u00f3n de la deuda m\u00e9dica en los informes crediticios y prohibir\u00e1 a los prestamistas utilizar cierta informaci\u00f3n m\u00e9dica en las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1472959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1472959"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1472959\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1472959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1472959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1472959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}