{"id":1472962,"date":"2026-04-08T06:03:45","date_gmt":"2026-04-08T13:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/08\/tension-arbitraje-puertos-canal-panama-orix\/"},"modified":"2026-04-08T06:03:45","modified_gmt":"2026-04-08T13:03:45","slug":"tension-arbitraje-puertos-canal-panama-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/08\/tension-arbitraje-puertos-canal-panama-orix\/","title":{"rendered":"Crece la tensi\u00f3n por los puertos de Panam\u00e1: ahora se enfrentan dos empresas"},"content":{"rendered":"<p>La empresa Panama Ports Company (PPC), filial del grupo hongkon\u00e9s CK Hutchison y que tuvo por m\u00e1s de 25 a\u00f1os la concesi\u00f3n de los puertos de Balboa y Crist\u00f3bal en el canal de Panam\u00e1, anunci\u00f3 este martes el inicio de un arbitraje internacional contra la compa\u00f1\u00eda danesa Maersk, a la que la Autoridad Mar\u00edtima de Panam\u00e1 le entreg\u00f3 la operaci\u00f3n transitoria de las terminales.<\/p>\n<p>La firma dijo en un <a href=\"https:\/\/x.com\/i\/status\/2041653953201340879\">comunicado<\/a> que el arbitraje se basa \u201cen un contrato de largo plazo para facilitar un enfoque colaborativo de negocio mediante el uso exclusivo de las operaciones de las terminales portuarias de PPC en Panam\u00e1 y el acceso a un rango de instalaciones operativas e informaci\u00f3n de PPC\u201d, y acus\u00f3 a Maersk de \u201csocavar\u201d el acuerdo.<\/p>\n<p>\u201c(Maersk) se aline\u00f3 con la Rep\u00fablica de Panam\u00e1 en conexi\u00f3n con su campa\u00f1a estatal contra PPC y un esquema para sustituirla mediante una toma que instal\u00f3 nuevos operadores portuarios\u201d, se\u00f1al\u00f3 la multinacional.<\/p>\n<p>Maersk confirm\u00f3 el inicio del procedimiento y dijo a CNN que \u201cno considera que sea responsable de las reclamaciones y las abordar\u00e1 en el foro correspondiente\u201d.<\/p>\n<p>PPC dijo tambi\u00e9n que el arbitraje tendr\u00e1 lugar en Londres y que el reclamo es \u201cdistinto y sin perjuicio de los pasos en curso de PPC para hacer responsable a Panam\u00e1 por su conducta anticontrato y antiinversionista\u201d. CNN contact\u00f3 al Gobierno de Panam\u00e1 para solicitar comentarios y espera respuesta.<\/p>\n<p>A fines de enero, la Corte Suprema de Panam\u00e1 <a href=\"https:\/\/www.cnn.com\/2026\/01\/30\/world\/hong-kong-panama-canal-ports-intl-hnk\">dej\u00f3 firme un fallo<\/a> inapelable que anul\u00f3 el contrato con PPC para la operaci\u00f3n en ambos extremos del Canal con gran parte de capital chino, lo que la compa\u00f1\u00eda denunci\u00f3 como una \u201c<a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/25\/latinoamerica\/panama-salida-panama-ports-china-preocupacion-orix\">toma ilegal<\/a>\u201d y afirm\u00f3 que los da\u00f1os escalaron a \u201cm\u00e1s de US$ 2.000 millones\u201d.<\/p>\n<p>El presidente de Panam\u00e1, Jos\u00e9 Ra\u00fal Mulino, ha rechazado las acusaciones de ilegalidad y asegur\u00f3 que su pa\u00eds es \u201cun Estado de Derecho\u201d y que el fallo debe ser respetado.<\/p>\n<p>Maersk, a trav\u00e9s de APM Terminals, dijo tras el fallo que estaba dispuesta a asumir la operaci\u00f3n temporalmente con el objetivo de \u201cmitigar los riesgos que pueda afectar los servicios esenciales para el comercio regional y global\u201d y subray\u00f3 que \u201cno es parte de los procesos legales en curso ni participa en decisiones sobre la estructura y administraci\u00f3n futura\u201d.<\/p>\n<p>La v\u00eda fluvial estrat\u00e9gica, por donde transita anualmente alrededor del 40 por ciento de todo el tr\u00e1fico de contenedores de Estados Unidos, es uno de los <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/05\/latinoamerica\/analisis-eeuu-china-canal-panama-internacional-trax\">puntos clave de las tensiones entre Washington y Beijing<\/a>.<\/p>\n<p>La semana pasada, EE.UU. volvi\u00f3 a criticar las acciones de China, a quien acusa de <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/27\/latinoamerica\/puertos-canal-panama-eeuu-china-represalias-orix\">detener buques<\/a> con bandera paname\u00f1a como parte de una serie de represalias tras la suspensi\u00f3n de contratos. Por su parte, el Gobierno chino <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/03\/mundo\/china-responde-eeuu-canal-panama-intento-tomar-control-orix\">respondi\u00f3<\/a> que los se\u00f1alamientos \u201ccarecen de fundamento\u201d y que \u201crevelan su intento\u201d de controlar el canal.<\/p>\n<p>El presidente Donald Trump, desde antes de asumir su segundo mandato, ha estado criticando la supuesta influencia de China en el canal. A su vez, Beijing impidi\u00f3 que el conglomerado hongkon\u00e9s vendiera a un consorcio liderado por el gestor estadounidense de activos BlackRock unas 40 terminales alrededor del mundo, incluidas las paname\u00f1as.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La empresa Panama Ports Company (PPC), filial del grupo hongkon\u00e9s CK Hutchison y que tuvo por m\u00e1s de 25 a\u00f1os la concesi\u00f3n de los puertos de Balboa y Crist\u00f3bal en el canal de Panam\u00e1, anunci\u00f3 este martes el inicio de un arbitraje internacional contra la compa\u00f1\u00eda danesa Maersk, a la que la Autoridad Mar\u00edtima de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1472962","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Crece la tensi\u00f3n por los puertos de Panam\u00e1: ahora se enfrentan dos empresas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/08\/tension-arbitraje-puertos-canal-panama-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crece la tensi\u00f3n por los puertos de Panam\u00e1: ahora se enfrentan dos empresas - Noticias\" \/>\n<meta property=\"og:description\" content=\"La empresa Panama Ports Company (PPC), filial del grupo hongkon\u00e9s CK Hutchison y que tuvo por m\u00e1s de 25 a\u00f1os la concesi\u00f3n de los puertos de Balboa y Crist\u00f3bal en el canal de Panam\u00e1, anunci\u00f3 este martes el inicio de un arbitraje internacional contra la compa\u00f1\u00eda danesa Maersk, a la que la Autoridad Mar\u00edtima de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/08\/tension-arbitraje-puertos-canal-panama-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-08T13:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/08\/tension-arbitraje-puertos-canal-panama-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/08\/tension-arbitraje-puertos-canal-panama-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Crece la tensi\u00f3n por los puertos de Panam\u00e1: ahora se enfrentan dos empresas\",\"datePublished\":\"2026-04-08T13:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/08\/tension-arbitraje-puertos-canal-panama-orix\/\"},\"wordCount\":574,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/08\/tension-arbitraje-puertos-canal-panama-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/08\/tension-arbitraje-puertos-canal-panama-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/08\/tension-arbitraje-puertos-canal-panama-orix\/\",\"name\":\"Crece la tensi\u00f3n por los puertos de Panam\u00e1: ahora se enfrentan dos empresas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-08T13:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/08\/tension-arbitraje-puertos-canal-panama-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/08\/tension-arbitraje-puertos-canal-panama-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/08\/tension-arbitraje-puertos-canal-panama-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Crece la tensi\u00f3n por los puertos de Panam\u00e1: ahora se enfrentan dos empresas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Crece la tensi\u00f3n por los puertos de Panam\u00e1: ahora se enfrentan dos empresas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/08\/tension-arbitraje-puertos-canal-panama-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Crece la tensi\u00f3n por los puertos de Panam\u00e1: ahora se enfrentan dos empresas - Noticias","og_description":"La empresa Panama Ports Company (PPC), filial del grupo hongkon\u00e9s CK Hutchison y que tuvo por m\u00e1s de 25 a\u00f1os la concesi\u00f3n de los puertos de Balboa y Crist\u00f3bal en el canal de Panam\u00e1, anunci\u00f3 este martes el inicio de un arbitraje internacional contra la compa\u00f1\u00eda danesa Maersk, a la que la Autoridad Mar\u00edtima de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/08\/tension-arbitraje-puertos-canal-panama-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-08T13:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/08\/tension-arbitraje-puertos-canal-panama-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/08\/tension-arbitraje-puertos-canal-panama-orix\/"},"author":{"name":"","@id":""},"headline":"Crece la tensi\u00f3n por los puertos de Panam\u00e1: ahora se enfrentan dos empresas","datePublished":"2026-04-08T13:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/08\/tension-arbitraje-puertos-canal-panama-orix\/"},"wordCount":574,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/08\/tension-arbitraje-puertos-canal-panama-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/08\/tension-arbitraje-puertos-canal-panama-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/08\/tension-arbitraje-puertos-canal-panama-orix\/","name":"Crece la tensi\u00f3n por los puertos de Panam\u00e1: ahora se enfrentan dos empresas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-08T13:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/08\/tension-arbitraje-puertos-canal-panama-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/08\/tension-arbitraje-puertos-canal-panama-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/08\/tension-arbitraje-puertos-canal-panama-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Crece la tensi\u00f3n por los puertos de Panam\u00e1: ahora se enfrentan dos empresas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/08\/tension-arbitraje-puertos-canal-panama-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Crece la tensi\u00f3n por los puertos de Panam\u00e1: ahora se enfrentan dos empresas","url":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/08\/tension-arbitraje-puertos-canal-panama-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/08\/tension-arbitraje-puertos-canal-panama-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-08T13:03:45Z","datePublished":"2026-04-08T13:03:45Z","dateModified":"2026-04-08T13:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Crece la tensi\\u00f3n por los puertos de Panam\\u00e1: ahora se enfrentan dos empresas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/04\\\/08\\\/tension-arbitraje-puertos-canal-panama-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/04\\\/08\\\/tension-arbitraje-puertos-canal-panama-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-08T13:03:45Z\",\"datePublished\":\"2026-04-08T13:03:45Z\",\"dateModified\":\"2026-04-08T13:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1473032,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/10\/panama-expresa-preocupacion-china-puertos-baja-tension-orix\/","url_meta":{"origin":1472962,"position":0},"title":"Panam\u00e1 eleva su inquietud a China por los barcos detenidos, pero advierte que no quiere escalar la tensi\u00f3n","author":"","date":"abril 10, 2026","format":false,"excerpt":"El presidente de Panam\u00e1, Jos\u00e9 Ra\u00fal Mulino, dijo que desde su Gobierno han transmitido sus preocupaciones a las autoridades diplom\u00e1ticas de China por las tensiones sobre los puertos en ambos extremos de la v\u00eda interoce\u00e1nica del pa\u00eds. Al mismo tiempo, el mandatario advirti\u00f3 que no quiere que el conflicto escale.Mulino\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470945,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/02\/06\/panama-advertencias-eeuu-china-canal-orix\/","url_meta":{"origin":1472962,"position":1},"title":"&#171;No se va a dejar amenazar por ning\u00fan pa\u00eds&#187;: Panam\u00e1 busca hacer un dif\u00edcil equilibrio entre advertencias de EE.UU. y China","author":"","date":"febrero 6, 2026","format":false,"excerpt":"Panam\u00e1 est\u00e1 tironeado por amenazas. Esta semana, el fallo de la Corte Suprema de Justicia de Panam\u00e1 que anul\u00f3 el contrato de una empresa de Hong Kong para gestionar dos puertos en puntos estrat\u00e9gicos del Canal de Panam\u00e1 ha puesto al pa\u00eds centroamericano como blanco de las presiones de China.No\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472624,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/03\/27\/puertos-canal-panama-eeuu-china-represalias-orix\/","url_meta":{"origin":1472962,"position":2},"title":"EE.UU. dice que China est\u00e1 deteniendo buques de Panam\u00e1 en &#171;represalia&#187; por p\u00e9rdida de puertos en el Canal","author":"","date":"marzo 27, 2026","format":false,"excerpt":"Estados Unidos denunci\u00f3 el jueves que China est\u00e1 ejerciendo \u201crepresalias\u201d contra Panam\u00e1 que afectan al transporte mar\u00edtimo mundial, mientras crecen las tensiones en torno a dos puertos sobre el Canal de Panam\u00e1 que eran operados por una empresa de capitales chinos cuyo contrato fue anulado recientemente.La Comisi\u00f3n Mar\u00edtima Federal de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472810,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/02\/eeuu-china-canal-panama-respaldo-orix\/","url_meta":{"origin":1472962,"position":3},"title":"EE.UU. respalda &#171;firmemente&#187; la soberan\u00eda de Panam\u00e1 mientras critica a China por &#171;socavar&#187; el comercio global","author":"","date":"abril 2, 2026","format":false,"excerpt":"El Gobierno de Estados Unidos insisti\u00f3 este jueves en criticar las acciones de China, a quien acusa de detener buques con bandera paname\u00f1a en el canal de Panam\u00e1 como parte de una serie de \u201crepresalias\u201d tras la suspensi\u00f3n de contratos en dos puertos del Canal que hasta enero operaban con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472837,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/03\/china-responde-eeuu-canal-panama-intento-tomar-control-orix\/","url_meta":{"origin":1472962,"position":4},"title":"Fuerte respuesta de China a Rubio por Panam\u00e1: &#171;Las alegaciones revelan el intento de EE.UU. de tomar el control del canal&#187;","author":"","date":"abril 3, 2026","format":false,"excerpt":"Luego de que el Gobierno de Estados Unidos acusara a China de detener buques con bandera paname\u00f1a en sus puertos, el Gobierno chino respondi\u00f3 este viernes que los se\u00f1alamientos \u201ccarecen de fundamento\u201d y que \u201crevelan su intento\u201d de controlar el canal de Panam\u00e1, una v\u00eda mar\u00edtima clave para el comercio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470661,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/01\/30\/corte-suprema-panama-empresa-china-fallo-canal-orix\/","url_meta":{"origin":1472962,"position":5},"title":"La Corte Suprema de Panam\u00e1 declara inconstitucional la concesi\u00f3n de puertos a una compa\u00f1\u00eda de Hong Kong","author":"","date":"enero 30, 2026","format":false,"excerpt":"El presidente de Panam\u00e1, Jos\u00e9 Ra\u00fal Mulino, anunci\u00f3 este viernes que una subsidiaria del grupo AP Moller - Maersk asumir\u00e1 transitoriamente la operaci\u00f3n de los puertos de Balboa y Crist\u00f3bal, en ambos extremos del Canal de Panam\u00e1, luego de que la Corte Suprema del pa\u00eds declarara inconstitucional el contrato de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1472962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1472962"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1472962\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1472962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1472962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1472962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}