{"id":1472997,"date":"2026-04-09T08:03:45","date_gmt":"2026-04-09T15:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/09\/inflacion-indice-pce-guerra-iran-trax\/"},"modified":"2026-04-09T08:03:45","modified_gmt":"2026-04-09T15:03:45","slug":"inflacion-indice-pce-guerra-iran-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/09\/inflacion-indice-pce-guerra-iran-trax\/","title":{"rendered":"La inflaci\u00f3n se mantuvo alta en el periodo previo a la guerra de Ir\u00e1n, seg\u00fan la Reserva Federal"},"content":{"rendered":"<p>Los estadounidenses siguieron gastando en febrero incluso cuando los precios aumentaban, y se espera que la guerra con Ir\u00e1n impulse a\u00fan m\u00e1s los costos, seg\u00fan datos publicados este jueves.<\/p>\n<p>El gasto del consumidor aument\u00f3 un 0,5 % en febrero, frente a un incremento del 0,3 % en enero, seg\u00fan un informe retrasado por el cierre del Gobierno publicado este jueves por el Departamento de Comercio.<\/p>\n<p>Sin embargo, al tener en cuenta la inflaci\u00f3n elevada, el gasto aument\u00f3 apenas un 0,1% respecto a enero.<\/p>\n<p>El informe tambi\u00e9n mostr\u00f3 que la inflaci\u00f3n se mantuvo persistentemente por encima de lo habitual: el \u00edndice de precios del gasto en consumo personal (PCE, por sus siglas en ingl\u00e9s), el indicador que la Reserva Federal utiliza para su objetivo del 2 %, subi\u00f3 un 0,4 % respecto a enero, lo que mantuvo la tasa anual en 2,8 %.<\/p>\n<p>Excluyendo los precios de alimentos y energ\u00eda, que suelen ser bastante vol\u00e1tiles, el \u00edndice subyacente del PCE tambi\u00e9n aument\u00f3 un 0,4 %, lo que situ\u00f3 la tasa anual en 3 %.<\/p>\n<p>Los economistas esperaban que los precios en general aumentaran un 0,3 % respecto a enero, lo que dejar\u00eda la tasa anual de inflaci\u00f3n en 2,8 %, seg\u00fan FactSet.<\/p>\n<p>Al excluir energ\u00eda y alimentos, estimaban que el \u00edndice subyacente del PCE aumentara un 0,4 % en el mes, pero que la tasa anual bajara ligeramente a 3 % desde el 3,1 % reportado inicialmente, en parte debido a comparaciones con un per\u00edodo del a\u00f1o pasado en el que la inflaci\u00f3n fue alta.<\/p>\n<p>Un informe separado del Departamento de Comercio publicado este jueves mostr\u00f3 que el crecimiento econ\u00f3mico de Estados Unidos fue m\u00e1s d\u00e9bil de lo reportado previamente, apenas unos meses antes de que Estados Unidos e Israel iniciaran una guerra desestabilizadora con Ir\u00e1n.<\/p>\n<p>El producto interno bruto (PIB), la medida m\u00e1s amplia de la producci\u00f3n econ\u00f3mica, creci\u00f3 a una tasa anualizada de 0,5 % en el per\u00edodo de octubre a diciembre, por debajo del 0,7 % de la segunda estimaci\u00f3n y muy por debajo del 1,4 % reportado inicialmente. La estimaci\u00f3n m\u00e1s reciente incorpor\u00f3 nuevos datos que muestran una inversi\u00f3n empresarial m\u00e1s d\u00e9bil en el cuarto trimestre, un per\u00edodo en el que el Gobierno de Estados Unidos estuvo cerrado durante un r\u00e9cord de 43 d\u00edas.<\/p>\n<p>El conjunto de nuevos datos econ\u00f3micos publicados este jueves, junto con las expectativas de que la inflaci\u00f3n aumente tras los impactos en la energ\u00eda y las cadenas de suministro derivados de la guerra, sugieren que los responsables de pol\u00edtica monetaria de la Reserva Federal podr\u00edan estar a\u00fan menos dispuestos a reducir las tasas de inter\u00e9s, escribi\u00f3 Guatieri, de BMO.<\/p>\n<p>\u201cCon la inflaci\u00f3n general probablemente acerc\u00e1ndose al 4 % pronto, hay pocas probabilidades de que la Reserva Federal flexibilice su pol\u00edtica en el corto plazo\u201d, escribi\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los estadounidenses siguieron gastando en febrero incluso cuando los precios aumentaban, y se espera que la guerra con Ir\u00e1n impulse a\u00fan m\u00e1s los costos, seg\u00fan datos publicados este jueves. El gasto del consumidor aument\u00f3 un 0,5 % en febrero, frente a un incremento del 0,3 % en enero, seg\u00fan un informe retrasado por el cierre [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1472997","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La inflaci\u00f3n se mantuvo alta en el periodo previo a la guerra de Ir\u00e1n, seg\u00fan la Reserva Federal - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/09\/inflacion-indice-pce-guerra-iran-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La inflaci\u00f3n se mantuvo alta en el periodo previo a la guerra de Ir\u00e1n, seg\u00fan la Reserva Federal - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los estadounidenses siguieron gastando en febrero incluso cuando los precios aumentaban, y se espera que la guerra con Ir\u00e1n impulse a\u00fan m\u00e1s los costos, seg\u00fan datos publicados este jueves. El gasto del consumidor aument\u00f3 un 0,5 % en febrero, frente a un incremento del 0,3 % en enero, seg\u00fan un informe retrasado por el cierre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/09\/inflacion-indice-pce-guerra-iran-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-09T15:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/09\/inflacion-indice-pce-guerra-iran-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/09\/inflacion-indice-pce-guerra-iran-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La inflaci\u00f3n se mantuvo alta en el periodo previo a la guerra de Ir\u00e1n, seg\u00fan la Reserva Federal\",\"datePublished\":\"2026-04-09T15:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/09\/inflacion-indice-pce-guerra-iran-trax\/\"},\"wordCount\":511,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/09\/inflacion-indice-pce-guerra-iran-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/09\/inflacion-indice-pce-guerra-iran-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/09\/inflacion-indice-pce-guerra-iran-trax\/\",\"name\":\"La inflaci\u00f3n se mantuvo alta en el periodo previo a la guerra de Ir\u00e1n, seg\u00fan la Reserva Federal - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-09T15:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/09\/inflacion-indice-pce-guerra-iran-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/09\/inflacion-indice-pce-guerra-iran-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/09\/inflacion-indice-pce-guerra-iran-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La inflaci\u00f3n se mantuvo alta en el periodo previo a la guerra de Ir\u00e1n, seg\u00fan la Reserva Federal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La inflaci\u00f3n se mantuvo alta en el periodo previo a la guerra de Ir\u00e1n, seg\u00fan la Reserva Federal - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/09\/inflacion-indice-pce-guerra-iran-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La inflaci\u00f3n se mantuvo alta en el periodo previo a la guerra de Ir\u00e1n, seg\u00fan la Reserva Federal - Noticias","og_description":"Los estadounidenses siguieron gastando en febrero incluso cuando los precios aumentaban, y se espera que la guerra con Ir\u00e1n impulse a\u00fan m\u00e1s los costos, seg\u00fan datos publicados este jueves. El gasto del consumidor aument\u00f3 un 0,5 % en febrero, frente a un incremento del 0,3 % en enero, seg\u00fan un informe retrasado por el cierre [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/09\/inflacion-indice-pce-guerra-iran-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-09T15:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/09\/inflacion-indice-pce-guerra-iran-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/09\/inflacion-indice-pce-guerra-iran-trax\/"},"author":{"name":"","@id":""},"headline":"La inflaci\u00f3n se mantuvo alta en el periodo previo a la guerra de Ir\u00e1n, seg\u00fan la Reserva Federal","datePublished":"2026-04-09T15:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/09\/inflacion-indice-pce-guerra-iran-trax\/"},"wordCount":511,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/09\/inflacion-indice-pce-guerra-iran-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/09\/inflacion-indice-pce-guerra-iran-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/09\/inflacion-indice-pce-guerra-iran-trax\/","name":"La inflaci\u00f3n se mantuvo alta en el periodo previo a la guerra de Ir\u00e1n, seg\u00fan la Reserva Federal - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-09T15:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/09\/inflacion-indice-pce-guerra-iran-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/09\/inflacion-indice-pce-guerra-iran-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/09\/inflacion-indice-pce-guerra-iran-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La inflaci\u00f3n se mantuvo alta en el periodo previo a la guerra de Ir\u00e1n, seg\u00fan la Reserva Federal"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/09\/inflacion-indice-pce-guerra-iran-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La inflaci\u00f3n se mantuvo alta en el periodo previo a la guerra de Ir\u00e1n, seg\u00fan la Reserva Federal","url":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/09\/inflacion-indice-pce-guerra-iran-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/09\/inflacion-indice-pce-guerra-iran-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-09T15:03:45Z","datePublished":"2026-04-09T15:03:45Z","dateModified":"2026-04-09T15:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La inflaci\\u00f3n se mantuvo alta en el periodo previo a la guerra de Ir\\u00e1n, seg\\u00fan la Reserva Federal\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/04\\\/09\\\/inflacion-indice-pce-guerra-iran-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/04\\\/09\\\/inflacion-indice-pce-guerra-iran-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-09T15:03:45Z\",\"datePublished\":\"2026-04-09T15:03:45Z\",\"dateModified\":\"2026-04-09T15:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1459033,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/02\/21\/confianza-consumidores-estadounidenses-desploma-aranceles-inflacion-trax\/","url_meta":{"origin":1472997,"position":0},"title":"La confianza de los consumidores estadounidenses se desploma por los temores a los aranceles y la inflaci\u00f3n","author":"","date":"febrero 21, 2025","format":false,"excerpt":"La inflaci\u00f3n est\u00e1 repuntando de nuevo y el presidente Donald Trump dijo esta semana que todo es culpa de su predecesor. Pero no importa a qui\u00e9n culpe Trump, el estado de \u00e1nimo econ\u00f3mico de Estados Unidos se est\u00e1 agriando, y \u00e9l es quien recibe las cr\u00edticas por ello.La encuesta m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472103,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/03\/11\/inflacion-eeuu-guerra-iran-cambio-trax\/","url_meta":{"origin":1472997,"position":1},"title":"La inflaci\u00f3n se mantuvo estable en febrero, pero la guerra con Ir\u00e1n podr\u00eda cambiar eso","author":"","date":"marzo 11, 2026","format":false,"excerpt":"La inflaci\u00f3n anual se mantuvo sin cambios el mes pasado en 2,4 %, seg\u00fan el \u00edndice de precios al consumidor m\u00e1s reciente, publicado este mi\u00e9rcoles.En t\u00e9rminos mensuales, los precios aumentaron 0,3 % en febrero, un ritmo m\u00e1s r\u00e1pido que el 0,2 % registrado en enero, de acuerdo con la Oficina\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460573,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/03\/28\/estadounidenses-preocupados-aumento-desempleo-encuesta-trax\/","url_meta":{"origin":1472997,"position":2},"title":"Los estadounidenses no hab\u00edan estado tan preocupados por el aumento del desempleo desde 2009, seg\u00fan una encuesta","author":"","date":"marzo 28, 2025","format":false,"excerpt":"Los estadounidenses no solo temen cada vez m\u00e1s una mayor inflaci\u00f3n, con el presidente Donald Trump a punto de anunciar una serie de aranceles en pocos d\u00edas, sino que muchos m\u00e1s ahora temen un aumento del desempleo.La confianza del consumidor se desplom\u00f3 un 12% este mes, seg\u00fan inform\u00f3 la Universidad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459819,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/03\/12\/inflacion-ee-uu-febrero-aranceles-trax\/","url_meta":{"origin":1472997,"position":3},"title":"La inflaci\u00f3n en EE.UU. se desaceler\u00f3 en febrero, pero los aranceles y la guerra comercial de Trump acechan","author":"","date":"marzo 12, 2025","format":false,"excerpt":"La inflaci\u00f3n en EE.UU. se desaceler\u00f3 m\u00e1s de lo previsto en febrero y se enfri\u00f3 por primera vez en cuatro meses. Sin embargo, este avance podr\u00eda ser ef\u00edmero, ya que el presidente Donald Trump intensifica su guerra comercial, que amenaza con aumentar los precios para los estadounidenses.El \u00cdndice de Precios\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472618,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/03\/27\/confianza-consumidor-economia-eeuu-guerra-iran-trax\/","url_meta":{"origin":1472997,"position":4},"title":"Incluso los ricos est\u00e1n perdiendo la confianza en el rumbo econ\u00f3mico de EE.UU.","author":"","date":"marzo 27, 2026","format":false,"excerpt":"Los estadounidenses se est\u00e1n volviendo m\u00e1s pesimistas sobre la econom\u00eda de Estados Unidos a medida que la guerra con Ir\u00e1n sigue sacudiendo los mercados, con el \u00e1nimo deterior\u00e1ndose en todos los grupos de ingresos \u2014incluidos los m\u00e1s ricos.La confianza del consumidor cay\u00f3 un 6 % este mes hasta una lectura\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458707,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/02\/13\/precios-mayoristas-altos-senal-inflacion-estancado-trax\/","url_meta":{"origin":1472997,"position":5},"title":"Los precios mayoristas en EE.UU. se mantuvieron altos el mes pasado, se\u00f1al de que la inflaci\u00f3n puede haberse estancado","author":"","date":"febrero 13, 2025","format":false,"excerpt":"La inflaci\u00f3n mayorista en Estados Unidos se mantuvo persistentemente elevada el mes pasado, otra se\u00f1al de que podr\u00edan avecinarse precios a\u00fan m\u00e1s altos para los compradores estadounidenses.El \u00cdndice de Precios a la Producci\u00f3n (IPP), que mide las variaciones promedio de los precios observadas por los productores y fabricantes, subi\u00f3 un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1472997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1472997"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1472997\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1472997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1472997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1472997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}