{"id":1473024,"date":"2026-04-10T01:03:51","date_gmt":"2026-04-10T08:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/10\/regreso-parte-arriesgada-mision-lunar-artemis-trax\/"},"modified":"2026-04-10T01:03:51","modified_gmt":"2026-04-10T08:03:51","slug":"regreso-parte-arriesgada-mision-lunar-artemis-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/10\/regreso-parte-arriesgada-mision-lunar-artemis-trax\/","title":{"rendered":"De regreso a casa: la parte m\u00e1s arriesgada de la misi\u00f3n lunar Artemis II a\u00fan est\u00e1 por llegar"},"content":{"rendered":"<p>Los astronautas de Artemis II se han enfrentado a numerosos peligros en su hist\u00f3rica misi\u00f3n lunar, incluyendo la tensi\u00f3n extrema durante el despegue el 1 de abril, cuando su cohete consumi\u00f3 millones de galones de combustible, y el desaf\u00edo de sortear peligrosos campos de radiaci\u00f3n en ruta hacia la Luna.<\/p>\n<p>Pero quiz\u00e1s el hito m\u00e1s desalentador est\u00e9 por venir: el reingreso.<\/p>\n<p>Durante esta fase del vuelo, la nave espacial de los astronautas se acerca a la Tierra a gran velocidad y se adentra en la densa capa interna de la atm\u00f3sfera terrestre, mientras se desplaza a m\u00e1s de 30 veces la velocidad del sonido.<\/p>\n<p>Este proceso provoca una violenta compresi\u00f3n de las mol\u00e9culas de aire que puede calentar el exterior de la c\u00e1psula a m\u00e1s de 2.760 grados Celsius.<\/p>\n<p>\u201cPara ser sincero, he estado pensando en la reentrada desde el 3 de abril de 2023, cuando nos asignaron a esta misi\u00f3n\u201d, declar\u00f3 el astronauta de Artemis II, Victor Glover, refiri\u00e9ndose a esta fase durante un evento con los medios el mi\u00e9rcoles.<\/p>\n<p>\u201cEn una de las primeras ruedas de prensa, nos preguntaron qu\u00e9 es lo que m\u00e1s esperamos, y yo respond\u00ed: el amerizaje. Es un poco gracioso, pero tambi\u00e9n es literal: tenemos que regresar. Ya han visto much\u00edsimos datos, pero lo mejor viene con nosotros. Hay muchas m\u00e1s fotos, muchas m\u00e1s historias\u201d, coment\u00f3.<\/p>\n<p>La reentrada se considera una de las etapas m\u00e1s precarias, si no la m\u00e1s precaria, de cualquier vuelo espacial. Y la misi\u00f3n Artemis II la atravesar\u00e1 con un problema conocido que los controladores de la misi\u00f3n est\u00e1n monitoreando.<\/p>\n<p>El problema sali\u00f3 a la luz tras el vuelo de prueba no tripulado Artemis I alrededor de la Luna en 2022, despu\u00e9s del cual los equipos de la misi\u00f3n descubrieron que el escudo t\u00e9rmico de la c\u00e1psula hab\u00eda regresado con preocupantes marcas y grietas.<\/p>\n<p>Un escudo t\u00e9rmico es un componente crucial dise\u00f1ado para proteger a la nave espacial y a sus astronautas de las temperaturas extremas durante el descenso a la Tierra.<\/p>\n<p>La nave espacial Artemis I Orion regres\u00f3 a casa sana y salva, pero los da\u00f1os plantearon interrogantes sobre hasta qu\u00e9 punto los ingenieros comprend\u00edan el material utilizado para crear este hardware, llamado Avcoat, y c\u00f3mo se comporta durante la peligrosa y din\u00e1mica fase final del vuelo.<\/p>\n<p>Si el escudo t\u00e9rmico se da\u00f1a o se agrieta de una manera espec\u00edfica, podr\u00eda provocar una falla catastr\u00f3fica. Y no existe ning\u00fan mecanismo de escape que pueda salvar a los astronautas en ese punto del viaje. Si el escudo t\u00e9rmico falla, la misi\u00f3n y la tripulaci\u00f3n se perder\u00edan.<\/p>\n<p>La nave espacial Orion de la misi\u00f3n Artemis II cuenta con un escudo t\u00e9rmico casi id\u00e9ntico al de la misi\u00f3n Artemis I.<\/p>\n<p>Si bien los funcionarios de la NASA han reconocido que <a href=\"https:\/\/www.cnn.com\/2026\/01\/23\/science\/artemis-2-orion-capsule-heat-shield\" rel=\"noopener noreferrer\" target=\"_blank\">no es el ideal<\/a>, la agencia sostiene que puede traer de regreso a los astronautas \u2014Reid Wiseman, Victor Glover y Christina Koch de la NASA, y Jeremy Hansen de la Agencia Espacial Canadiense\u2014 sanos y salvos, gracias a algunos cambios realizados en la estrategia de reentrada de la misi\u00f3n.<\/p>\n<p>Los responsables de la misi\u00f3n afirman estar seguros de haber hecho bien su trabajo y de comprender las limitaciones del escudo t\u00e9rmico, as\u00ed como la forma de proteger a la tripulaci\u00f3n, declar\u00f3 Amit Kshatriya, administrador adjunto de la NASA, durante una rueda de prensa el jueves. Y a\u00f1adi\u00f3: \u201cLa tripulaci\u00f3n pondr\u00e1 su vida en juego\u201d.<\/p>\n<p>Pero reconoci\u00f3 que hay mucho en juego.<\/p>\n<p>\u201cLa nave espacial Orion entrar\u00e1 en la atm\u00f3sfera terrestre a aproximadamente 25.000 millas por hora (40.000 km\/h). Ese escudo t\u00e9rmico\u2026 soportar\u00e1 toda la fuerza de la reentrada\u201d, explic\u00f3. \u201cCada sistema que hemos demostrado durante los \u00faltimos nueve d\u00edas \u2014soporte vital, navegaci\u00f3n, propulsi\u00f3n, comunicaciones\u2014 depende de los \u00faltimos minutos del vuelo\u201d.<\/p>\n<p>Los problemas detectados en la misi\u00f3n Artemis I dieron lugar a m\u00e1s de un a\u00f1o de investigaciones, an\u00e1lisis y pruebas en tierra, mientras la NASA intentaba comprender el comportamiento inesperado del escudo t\u00e9rmico.<\/p>\n<p>Sin embargo, y esto es crucial, cuando la Artemis I regres\u00f3, el escudo t\u00e9rmico ya estaba instalado en la c\u00e1psula Artemis II. Esto significaba que era demasiado tarde para modificar la estructura o el dise\u00f1o del escudo t\u00e9rmico para este vuelo tripulado.<\/p>\n<p>Para solucionar el problema, la NASA ha optado por colocar la c\u00e1psula Artemis II y a los astronautas en una trayectoria diferente a la que sigui\u00f3 la Artemis I para su regreso a casa.<\/p>\n<p>Mientras que el vuelo de prueba de 2022 utiliz\u00f3 una reentrada con \u201csalto\u201d, en la que la c\u00e1psula se hundi\u00f3 brevemente en la atm\u00f3sfera antes de volver a elevar su altitud y realizar una segunda ca\u00edda, este viaje intentar\u00e1 una reentrada m\u00e1s elevada, seg\u00fan el director de vuelo de la NASA, <strong><\/strong>Rick Henfling.<\/p>\n<p>El dise\u00f1o modificado tiene como objetivo crear condiciones de calentamiento m\u00e1s favorables, con la esperanza de limitar, aunque no eliminar, la aparici\u00f3n de grietas en el escudo t\u00e9rmico.<\/p>\n<p>El proceso de investigaci\u00f3n ha dado a los expertos de la NASA la confianza de que, incluso si el escudo t\u00e9rmico no funciona de manera \u00f3ptima, los astronautas regresar\u00e1n a casa sanos y salvos.<\/p>\n<p>Howard Hu, director del programa Ori\u00f3n de la NASA, reiter\u00f3 esta opini\u00f3n en una entrevista previa al lanzamiento a finales de marzo. Tambi\u00e9n confirm\u00f3 que la agencia espacial comenzar\u00e1 a evaluar el rendimiento del escudo t\u00e9rmico de Artemis II inmediatamente despu\u00e9s de su regreso.<\/p>\n<p>Tras el previsto amerizaje de la c\u00e1psula Orion frente a la costa de San Diego, mientras los astronautas son trasladados en helic\u00f3ptero a un buque de recuperaci\u00f3n, un buzo se sumergir\u00e1 en el oc\u00e9ano para fotografiar el escudo t\u00e9rmico desde abajo, proporcionando a los responsables de la misi\u00f3n algunas de las primeras pruebas de su funcionamiento.<\/p>\n<p>\u201cEste es un escudo t\u00e9rmico defectuoso\u201d, declar\u00f3 en enero a CNN el Dr. Danny Olivas, exastronauta de la NASA que form\u00f3 parte del equipo de revisi\u00f3n independiente designado por la agencia espacial para <a href=\"https:\/\/www.calameo.com\/read\/00270123481c7e3a8c300\">investigar<\/a> el incidente. \u201cNo cabe duda: este no es el escudo t\u00e9rmico que la NASA querr\u00eda proporcionar a sus astronautas\u201d.<\/p>\n<p>Aun as\u00ed, Olivas afirm\u00f3 creer que la NASA \u201ctiene el problema bajo control\u201d tras llevar a cabo una investigaci\u00f3n exhaustiva.<\/p>\n<p>La toma de decisiones de la NASA ha suscitado cr\u00edticas.<\/p>\n<p>El Dr. Charlie Camarda, experto en escudos t\u00e9rmicos, cient\u00edfico investigador y exastronauta de la NASA que tambi\u00e9n form\u00f3 parte de la primera tripulaci\u00f3n del transbordador espacial que despeg\u00f3 tras el desastre del Columbia en 2003, se encuentra entre un <a href=\"https:\/\/www.cnn.com\/2026\/01\/23\/science\/artemis-2-orion-capsule-heat-shield\">grupo de antiguos empleados de la NASA<\/a> que no creen que la agencia espacial debiera haber enviado seres humanos a bordo de la misi\u00f3n lunar Artemis II.<\/p>\n<p>Fue invitado a una reuni\u00f3n en la sede de la NASA en enero para discutir el tema y revisar los datos de las investigaciones de la agencia. Camarda declar\u00f3 que se march\u00f3 sin estar convencido de que la agencia comprendiera c\u00f3mo las grietas en el escudo t\u00e9rmico pod\u00edan crecer o provocar una falla en vuelo.<\/p>\n<p>\u201cEl hecho de que decidi\u00e9ramos enviar tripulaci\u00f3n en un veh\u00edculo con un escudo t\u00e9rmico defectuoso es irresponsable, y estoy seguro de que ning\u00fan investigador del programa Apolo habr\u00eda permitido tal decisi\u00f3n\u201d, declar\u00f3 Camarda a CNN. \u201cLa NASA se ha negado a intentar desarrollar una soluci\u00f3n anal\u00edtica que pudiera ayudar a validar todos los mecanismos de fallo del escudo t\u00e9rmico ablativo\u201d.<\/p>\n<p>Durante una conversaci\u00f3n a finales de marzo, Camarda coment\u00f3 que \u00e9l y otros exempleados de la NASA con ideas afines enviaron cartas a los responsables de seguridad expresando sus inquietudes.<\/p>\n<p>Entre los firmantes figuraban Dan Rasky, experto en sistemas avanzados de entrada y materiales de protecci\u00f3n t\u00e9rmica que trabaj\u00f3 en la NASA durante m\u00e1s de 30 a\u00f1os, y Edgar Zapata, ingeniero jubilado del Centro Espacial Kennedy que a\u00fan forma parte del Consejo Externo de Conceptos Avanzados Innovadores de la NASA (NIAC).<\/p>\n<p>Un responsable de seguridad respondi\u00f3 diciendo que el comit\u00e9, denominado Panel Asesor de Seguridad Aeroespacial o ASAP, \u201ctendr\u00eda en cuenta sus preocupaciones\u201d.<\/p>\n<p>Camarda recalc\u00f3 que su oposici\u00f3n a Artemis II no se basa en la creencia de que terminar\u00e1 en un fracaso catastr\u00f3fico. Cree que es probable que la misi\u00f3n regrese a salvo.<\/p>\n<p>Seg\u00fan declar\u00f3 Camarda a CNN, lo que m\u00e1s teme es que un vuelo seguro de Artemis II sirva para que la direcci\u00f3n de la NASA confirme la solidez de sus procesos de toma de decisiones. Y eso, advirti\u00f3 Camarda, sin duda generar\u00e1 en la agencia una falsa sensaci\u00f3n de seguridad.<\/p>\n<p>La NASA ha recalcado repetidamente que la seguridad es su m\u00e1xima prioridad.<\/p>\n<p>En un <a href=\"https:\/\/www.cnn.com\/2026\/01\/23\/science\/artemis-2-orion-capsule-heat-shield\">comunicado<\/a> a CNN en enero, la NASA manifest\u00f3 que la agencia \u201cconsider\u00f3 todos los aspectos\u201d al tomar sus decisiones con respecto al escudo t\u00e9rmico de Artemis II, y se\u00f1al\u00f3 que tambi\u00e9n existe \u201cincertidumbre que viene con el desarrollo y la calificaci\u00f3n de los procesos de cambio del proceso de fabricaci\u00f3n\u201d.<\/p>\n<p>Tanto los altos cargos del programa Artemis II como los astronautas han manifestado su confianza en que la NASA comprende el problema y que la c\u00e1psula regresar\u00e1 a casa sana y salva.<\/p>\n<p>\u201cLos investigadores descubrieron la causa principal, que fue clave\u201d para comprender y resolver el problema del escudo t\u00e9rmico, <a href=\"https:\/\/aerospaceamerica.aiaa.org\/artemis-ii-crew-expresses-confidence-in-orion-capsule-heat-shield\/\">declar\u00f3 Wiseman a los periodistas en julio pasado<\/a>. \u201cSi seguimos la nueva trayectoria de reentrada que la NASA ha planeado, este escudo t\u00e9rmico ser\u00e1 seguro para volar\u201d.<\/p>\n<p>Olivas, el exastronauta que particip\u00f3 en la investigaci\u00f3n, tambi\u00e9n se\u00f1al\u00f3 que \u201cno hay vuelo que despegue sin que quede alguna duda persistente\u201d.<\/p>\n<p>\u201cPero la NASA realmente entiende lo que tiene\u201d, indic\u00f3 Olivas. \u201cSaben la importancia del escudo t\u00e9rmico para la seguridad de la tripulaci\u00f3n, y creo que han hecho bien su trabajo\u201d.<\/p>\n<p>Debbie Korth, subdirectora del programa Orion de la NASA, reiter\u00f3 durante una conferencia de prensa el mi\u00e9rcoles que las pruebas que la agencia realiz\u00f3 despu\u00e9s de Artemis I le dieron confianza en el plan para traer de vuelta a casa a los astronautas de Artemis II.<\/p>\n<p>\u201cComprendemos c\u00f3mo se comporta el resto del veh\u00edculo y hemos llevado a cabo un extenso programa de pruebas en tierra para entender c\u00f3mo se comporta este escudo t\u00e9rmico\u201d, asegur\u00f3 Korth.<\/p>\n<p>Seg\u00fan indic\u00f3, la NASA planea utilizar la trayectoria de reentrada modificada \u00fanicamente para esta misi\u00f3n.<\/p>\n<p>En futuros vuelos, incluido Artemis III, la c\u00e1psula Orion incorporar\u00e1 materiales de escudo t\u00e9rmico actualizados, dise\u00f1ados para ser m\u00e1s permeables, lo que, con suerte, evitar\u00e1 el problema de las grietas.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los astronautas de Artemis II se han enfrentado a numerosos peligros en su hist\u00f3rica misi\u00f3n lunar, incluyendo la tensi\u00f3n extrema durante el despegue el 1 de abril, cuando su cohete consumi\u00f3 millones de galones de combustible, y el desaf\u00edo de sortear peligrosos campos de radiaci\u00f3n en ruta hacia la Luna. Pero quiz\u00e1s el hito m\u00e1s [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1473024","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>De regreso a casa: la parte m\u00e1s arriesgada de la misi\u00f3n lunar Artemis II a\u00fan est\u00e1 por llegar - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/10\/regreso-parte-arriesgada-mision-lunar-artemis-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"De regreso a casa: la parte m\u00e1s arriesgada de la misi\u00f3n lunar Artemis II a\u00fan est\u00e1 por llegar - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los astronautas de Artemis II se han enfrentado a numerosos peligros en su hist\u00f3rica misi\u00f3n lunar, incluyendo la tensi\u00f3n extrema durante el despegue el 1 de abril, cuando su cohete consumi\u00f3 millones de galones de combustible, y el desaf\u00edo de sortear peligrosos campos de radiaci\u00f3n en ruta hacia la Luna. Pero quiz\u00e1s el hito m\u00e1s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/10\/regreso-parte-arriesgada-mision-lunar-artemis-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-10T08:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/regreso-parte-arriesgada-mision-lunar-artemis-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/regreso-parte-arriesgada-mision-lunar-artemis-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"De regreso a casa: la parte m\u00e1s arriesgada de la misi\u00f3n lunar Artemis II a\u00fan est\u00e1 por llegar\",\"datePublished\":\"2026-04-10T08:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/regreso-parte-arriesgada-mision-lunar-artemis-trax\/\"},\"wordCount\":1892,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/10\/regreso-parte-arriesgada-mision-lunar-artemis-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/regreso-parte-arriesgada-mision-lunar-artemis-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/10\/regreso-parte-arriesgada-mision-lunar-artemis-trax\/\",\"name\":\"De regreso a casa: la parte m\u00e1s arriesgada de la misi\u00f3n lunar Artemis II a\u00fan est\u00e1 por llegar - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-10T08:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/regreso-parte-arriesgada-mision-lunar-artemis-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/10\/regreso-parte-arriesgada-mision-lunar-artemis-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/regreso-parte-arriesgada-mision-lunar-artemis-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"De regreso a casa: la parte m\u00e1s arriesgada de la misi\u00f3n lunar Artemis II a\u00fan est\u00e1 por llegar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"De regreso a casa: la parte m\u00e1s arriesgada de la misi\u00f3n lunar Artemis II a\u00fan est\u00e1 por llegar - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/10\/regreso-parte-arriesgada-mision-lunar-artemis-trax\/","og_locale":"es_ES","og_type":"article","og_title":"De regreso a casa: la parte m\u00e1s arriesgada de la misi\u00f3n lunar Artemis II a\u00fan est\u00e1 por llegar - Noticias","og_description":"Los astronautas de Artemis II se han enfrentado a numerosos peligros en su hist\u00f3rica misi\u00f3n lunar, incluyendo la tensi\u00f3n extrema durante el despegue el 1 de abril, cuando su cohete consumi\u00f3 millones de galones de combustible, y el desaf\u00edo de sortear peligrosos campos de radiaci\u00f3n en ruta hacia la Luna. Pero quiz\u00e1s el hito m\u00e1s [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/10\/regreso-parte-arriesgada-mision-lunar-artemis-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-10T08:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/10\/regreso-parte-arriesgada-mision-lunar-artemis-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/10\/regreso-parte-arriesgada-mision-lunar-artemis-trax\/"},"author":{"name":"","@id":""},"headline":"De regreso a casa: la parte m\u00e1s arriesgada de la misi\u00f3n lunar Artemis II a\u00fan est\u00e1 por llegar","datePublished":"2026-04-10T08:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/10\/regreso-parte-arriesgada-mision-lunar-artemis-trax\/"},"wordCount":1892,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/10\/regreso-parte-arriesgada-mision-lunar-artemis-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/10\/regreso-parte-arriesgada-mision-lunar-artemis-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/10\/regreso-parte-arriesgada-mision-lunar-artemis-trax\/","name":"De regreso a casa: la parte m\u00e1s arriesgada de la misi\u00f3n lunar Artemis II a\u00fan est\u00e1 por llegar - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-10T08:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/10\/regreso-parte-arriesgada-mision-lunar-artemis-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/10\/regreso-parte-arriesgada-mision-lunar-artemis-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/10\/regreso-parte-arriesgada-mision-lunar-artemis-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"De regreso a casa: la parte m\u00e1s arriesgada de la misi\u00f3n lunar Artemis II a\u00fan est\u00e1 por llegar"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/10\/regreso-parte-arriesgada-mision-lunar-artemis-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"De regreso a casa: la parte m\u00e1s arriesgada de la misi\u00f3n lunar Artemis II a\u00fan est\u00e1 por llegar","url":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/10\/regreso-parte-arriesgada-mision-lunar-artemis-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/10\/regreso-parte-arriesgada-mision-lunar-artemis-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-10T08:03:51Z","datePublished":"2026-04-10T08:03:51Z","dateModified":"2026-04-10T08:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"De regreso a casa: la parte m\\u00e1s arriesgada de la misi\\u00f3n lunar Artemis II a\\u00fan est\\u00e1 por llegar\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/04\\\/10\\\/regreso-parte-arriesgada-mision-lunar-artemis-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/04\\\/10\\\/regreso-parte-arriesgada-mision-lunar-artemis-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-10T08:03:51Z\",\"datePublished\":\"2026-04-10T08:03:51Z\",\"dateModified\":\"2026-04-10T08:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1470186,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/01\/17\/artemis-ii-luna-aterrizaje-trax\/","url_meta":{"origin":1473024,"position":0},"title":"Cuatro astronautas est\u00e1n a punto de emprender un viaje sin precedentes hacia la Luna. \u00bfPero por qu\u00e9 no aterrizar\u00e1n?","author":"","date":"enero 17, 2026","format":false,"excerpt":"La nave espacial que pronto podr\u00eda transportar a cuatro personas en una hist\u00f3rica misi\u00f3n lunar, el cohete del Sistema de Lanzamiento Espacial (SLS) de la NASA y la c\u00e1psula Ori\u00f3n, ser\u00e1 el centro de atenci\u00f3n este s\u00e1bado, cuando realice un viaje de una hora desde el Edificio de Ensamblaje de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443404,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/01\/09\/primero-en-cnn-se-espera-que-la-nasa-anuncie-un-retraso-de-meses-para-la-mision-lunar-tripulada-artemis\/","url_meta":{"origin":1473024,"position":1},"title":"Primero en CNN: se espera que la NASA anuncie un &#171;retraso de meses&#187; para la misi\u00f3n lunar tripulada Artemis","author":"","date":"enero 9, 2024","format":false,"excerpt":"(CNN) -- Se espera que la direcci\u00f3n de la NASA anuncie este martes un \"retraso de meses\" en la primera misi\u00f3n tripulada del emblem\u00e1tico programa Artemis de la agencia, seg\u00fan un empleado y un exempleado de la NASA.El retraso afecta a la misi\u00f3n Artemis II de la NASA, que pretende\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443406,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/01\/09\/primero-en-cnn-se-espera-que-la-nasa-anuncie-un-retraso-de-meses-para-la-mision-lunar-tripulada-artemis-2\/","url_meta":{"origin":1473024,"position":2},"title":"Primero en CNN: se espera que la NASA anuncie un &#171;retraso de meses&#187; para la misi\u00f3n lunar tripulada Artemis","author":"","date":"enero 9, 2024","format":false,"excerpt":"(CNN) -- Se espera que la direcci\u00f3n de la NASA anuncie este martes un \"retraso de meses\" en la primera misi\u00f3n tripulada del emblem\u00e1tico programa Artemis de la agencia, seg\u00fan un empleado y un exempleado de la NASA.El retraso afecta a la misi\u00f3n Artemis II de la NASA, que pretende\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472845,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/03\/donde-esta-orion-que-sigue-artemis-ii-luna-trax\/","url_meta":{"origin":1473024,"position":3},"title":"D\u00f3nde est\u00e1 la nave Orion y qu\u00e9 sigue para la misi\u00f3n Artemis II en su camino a la Luna","author":"","date":"abril 3, 2026","format":false,"excerpt":"La misi\u00f3n Artemis II cruz\u00f3 un umbral crucial e hist\u00f3rico el jueves, cuando la nave espacial Orion encendi\u00f3 su motor e impuls\u00f3 a cuatro astronautas hacia la Luna, en un viaje de varios d\u00edas que los llevar\u00e1 m\u00e1s lejos en el espacio de lo que cualquier ser humano ha viajado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472895,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/06\/donde-esta-artemis-orion-que-sigue-luna-trax\/","url_meta":{"origin":1473024,"position":4},"title":"D\u00f3nde est\u00e1 la nave Orion y qu\u00e9 sigue para la misi\u00f3n Artemis II en su camino a la Luna","author":"","date":"abril 6, 2026","format":false,"excerpt":"La misi\u00f3n Artemis II est\u00e1 ahora m\u00e1s cerca de la Luna que de la Tierra, con cuatro astronautas avanzando hacia su objetivo en una trayectoria de asistencia gravitatoria que los llevar\u00e1 m\u00e1s lejos en el espacio de lo que ning\u00fan ser humano ha llegado antes.El viaje \u2014tripulado por Reid Wiseman,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469701,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/12\/31\/nasa-luna-mision-artemis-2-trax\/","url_meta":{"origin":1473024,"position":5},"title":"La NASA estar\u00eda a semanas de su mayor desaf\u00edo en d\u00e9cadas: un viaje tripulado a la Luna","author":"","date":"diciembre 31, 2025","format":false,"excerpt":"La aspiraci\u00f3n de devolver astronautas estadounidenses a la Luna ha estado en limbo durante d\u00e9cadas, debido a que los planes han sido adoptados y rechazados de una administraci\u00f3n presidencial a otra. Sin embargo, en 2026, ese objetivo cobrar\u00e1 un enfoque m\u00e1s claro.El programa Artemis de la NASA \u2014una iniciativa anunciada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1473024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1473024"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1473024\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1473024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1473024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1473024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}