{"id":1473026,"date":"2026-04-10T04:03:53","date_gmt":"2026-04-10T11:03:53","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/10\/mensaje-religioso-pascua-secretaria-agricultura-desencadena-criticas-trax\/"},"modified":"2026-04-10T04:03:53","modified_gmt":"2026-04-10T11:03:53","slug":"mensaje-religioso-pascua-secretaria-agricultura-desencadena-criticas-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/10\/mensaje-religioso-pascua-secretaria-agricultura-desencadena-criticas-trax\/","title":{"rendered":"Un mensaje religioso de Pascua de la secretaria de Agricultura a los funcionarios desencadena fuertes cr\u00edticas"},"content":{"rendered":"<p>Un mensaje de Pascua con la frase \u201cCristo ha resucitado\u201d enviado por la secretaria de Agricultura ha desatado una ola de rechazo dentro del departamento, provocando la indignaci\u00f3n de algunos de sus casi 100.000 empleados y motivando la presentaci\u00f3n de una queja formal contra la secretaria.<\/p>\n<p>Los empleados de las 4.500 oficinas del departamento en todo el pa\u00eds recibieron el domingo un correo electr\u00f3nico de la secretaria Brooke Rollins con el siguiente mensaje: \u201c\u00a1Feliz Pascua. \u00c9l ha resucitado verdaderamente!\u201d.<\/p>\n<p>Rollins comunic\u00f3 a todo el personal del departamento que se trataba de un d\u00eda para celebrar \u201cel fundamento de nuestra fe\u201d.<\/p>\n<p>\u201cDesde el pie de la Cruz el Viernes Santo hasta la piedra apartada de la tumba, ahora vac\u00eda, el pecado ha sido destruido. Jes\u00fas ha resucitado de entre los muertos. Y Dios nos ha concedido a cada uno de nosotros la victoria y una vida nueva\u201d, rezaba el correo electr\u00f3nico.<\/p>\n<p>La queja, obtenida por CNN, fue presentada ante la Oficina del Asesor Especial (OSC, por sus siglas en ingl\u00e9s) por Ethan Roberts, presidente de un sindicato local de empleados federales que, a su vez, es empleado del USDA. La OSC es una agencia federal de investigaci\u00f3n independiente que examina las denuncias de los empleados federales que alegan violaciones de leyes, normas o reglamentos.<\/p>\n<p>En su queja, Roberts afirm\u00f3 que el correo electr\u00f3nico constitu\u00eda un \u201cserm\u00f3n a favor del cristianismo\u201d enviado a todos los empleados del USDA el d\u00eda de Pascua, alegando que violaba la cl\u00e1usula de establecimiento de la Primera Enmienda. Roberts a\u00f1adi\u00f3 que el correo electr\u00f3nico \u201csocavaba la separaci\u00f3n entre la Iglesia y el Estado\u201d.<\/p>\n<p>Roberts declar\u00f3 a CNN que el correo electr\u00f3nico de la secretaria, al hacer referencia al \u201cpecado\u201d y al \u201cInfierno\u201d, le hizo \u201csentir como si ese fuera mi destino si no consideraba la Pascua tan sagrada como lo hace la secretaria Rollins\u201d.<\/p>\n<p>La queja exige la retractaci\u00f3n del correo electr\u00f3nico de Pascua y que se ponga fin al env\u00edo de cualquier otro correo electr\u00f3nico del departamento que celebre o respalde festividades religiosas.<\/p>\n<p>Un portavoz del USDA declar\u00f3 a CNN en un comunicado: \u201cLa secretaria est\u00e1 en su derecho de enviar un mensaje a los empleados y al p\u00fablico con motivo de la festividad de Pascua, tal como lo han hecho en el pasado otros secretarios de Agricultura y presidentes\u201d.<\/p>\n<p>Otro empleado del USDA, que solicit\u00f3 el anonimato para poder hablar con libertad, coment\u00f3 a CNN que se sinti\u00f3 molesto al recibir el correo electr\u00f3nico.<\/p>\n<p>\u201cUtilizar recursos gubernamentales para promover una religi\u00f3n contradice lo que aprend\u00ed sobre los fundamentos de Estados Unidos, basados \u200b\u200ben la separaci\u00f3n entre la Iglesia y el Estado\u201d, afirm\u00f3 el empleado. \u201cAunque muchos de mis compa\u00f1eros de trabajo tambi\u00e9n estaban celebrando la Pascua jud\u00eda, el correo electr\u00f3nico no hac\u00eda referencia a ninguna otra tradici\u00f3n religiosa\u201d. La Freedom from Religion Foundation, una organizaci\u00f3n sin fines de lucro que aboga por la separaci\u00f3n entre la Iglesia y el Estado, comunic\u00f3 a CNN que recibi\u00f3 quejas sobre el mensaje de Pascua de Rollins por parte de casi 30 empleados del USDA, quienes expresaron su indignaci\u00f3n y calificaron el mensaje de \u201cinapropiado e insultante\u201d. La organizaci\u00f3n declar\u00f3 haber enviado una carta formal a la secretaria exigi\u00e9ndole que deje de \u201cpromover sus creencias religiosas personales a trav\u00e9s de comunicaciones oficiales\u201d.<\/p>\n<p>Bajo la presidencia de Donald Trump, momentos como este \u2014poco frecuentes en administraciones recientes\u2014 se est\u00e1n volviendo habituales. Se ha alentado a los ciudadanos estadounidenses a dedicar una hora a la oraci\u00f3n cada semana. Algunas agencias gubernamentales han inaugurado sus reuniones con una oraci\u00f3n o han organizado servicios religiosos peri\u00f3dicos. Vers\u00edculos b\u00edblicos e imaginer\u00eda cristiana aparecen ahora en las cuentas oficiales de redes sociales del gobierno.<\/p>\n<p>Una serie de iniciativas de car\u00e1cter religioso, impulsadas por la Casa Blanca, han propiciado un resurgimiento religioso sistem\u00e1tico en las operaciones, la cultura y las pol\u00edticas del gobierno.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un mensaje de Pascua con la frase \u201cCristo ha resucitado\u201d enviado por la secretaria de Agricultura ha desatado una ola de rechazo dentro del departamento, provocando la indignaci\u00f3n de algunos de sus casi 100.000 empleados y motivando la presentaci\u00f3n de una queja formal contra la secretaria. Los empleados de las 4.500 oficinas del departamento en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1473026","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un mensaje religioso de Pascua de la secretaria de Agricultura a los funcionarios desencadena fuertes cr\u00edticas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/10\/mensaje-religioso-pascua-secretaria-agricultura-desencadena-criticas-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un mensaje religioso de Pascua de la secretaria de Agricultura a los funcionarios desencadena fuertes cr\u00edticas - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un mensaje de Pascua con la frase \u201cCristo ha resucitado\u201d enviado por la secretaria de Agricultura ha desatado una ola de rechazo dentro del departamento, provocando la indignaci\u00f3n de algunos de sus casi 100.000 empleados y motivando la presentaci\u00f3n de una queja formal contra la secretaria. Los empleados de las 4.500 oficinas del departamento en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/10\/mensaje-religioso-pascua-secretaria-agricultura-desencadena-criticas-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-10T11:03:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/mensaje-religioso-pascua-secretaria-agricultura-desencadena-criticas-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/mensaje-religioso-pascua-secretaria-agricultura-desencadena-criticas-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un mensaje religioso de Pascua de la secretaria de Agricultura a los funcionarios desencadena fuertes cr\u00edticas\",\"datePublished\":\"2026-04-10T11:03:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/mensaje-religioso-pascua-secretaria-agricultura-desencadena-criticas-trax\/\"},\"wordCount\":716,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/10\/mensaje-religioso-pascua-secretaria-agricultura-desencadena-criticas-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/mensaje-religioso-pascua-secretaria-agricultura-desencadena-criticas-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/10\/mensaje-religioso-pascua-secretaria-agricultura-desencadena-criticas-trax\/\",\"name\":\"Un mensaje religioso de Pascua de la secretaria de Agricultura a los funcionarios desencadena fuertes cr\u00edticas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-10T11:03:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/mensaje-religioso-pascua-secretaria-agricultura-desencadena-criticas-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/10\/mensaje-religioso-pascua-secretaria-agricultura-desencadena-criticas-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/mensaje-religioso-pascua-secretaria-agricultura-desencadena-criticas-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un mensaje religioso de Pascua de la secretaria de Agricultura a los funcionarios desencadena fuertes cr\u00edticas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un mensaje religioso de Pascua de la secretaria de Agricultura a los funcionarios desencadena fuertes cr\u00edticas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/10\/mensaje-religioso-pascua-secretaria-agricultura-desencadena-criticas-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Un mensaje religioso de Pascua de la secretaria de Agricultura a los funcionarios desencadena fuertes cr\u00edticas - Noticias","og_description":"Un mensaje de Pascua con la frase \u201cCristo ha resucitado\u201d enviado por la secretaria de Agricultura ha desatado una ola de rechazo dentro del departamento, provocando la indignaci\u00f3n de algunos de sus casi 100.000 empleados y motivando la presentaci\u00f3n de una queja formal contra la secretaria. Los empleados de las 4.500 oficinas del departamento en [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/10\/mensaje-religioso-pascua-secretaria-agricultura-desencadena-criticas-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-10T11:03:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/10\/mensaje-religioso-pascua-secretaria-agricultura-desencadena-criticas-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/10\/mensaje-religioso-pascua-secretaria-agricultura-desencadena-criticas-trax\/"},"author":{"name":"","@id":""},"headline":"Un mensaje religioso de Pascua de la secretaria de Agricultura a los funcionarios desencadena fuertes cr\u00edticas","datePublished":"2026-04-10T11:03:53+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/10\/mensaje-religioso-pascua-secretaria-agricultura-desencadena-criticas-trax\/"},"wordCount":716,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/10\/mensaje-religioso-pascua-secretaria-agricultura-desencadena-criticas-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/10\/mensaje-religioso-pascua-secretaria-agricultura-desencadena-criticas-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/10\/mensaje-religioso-pascua-secretaria-agricultura-desencadena-criticas-trax\/","name":"Un mensaje religioso de Pascua de la secretaria de Agricultura a los funcionarios desencadena fuertes cr\u00edticas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-10T11:03:53+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/10\/mensaje-religioso-pascua-secretaria-agricultura-desencadena-criticas-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/10\/mensaje-religioso-pascua-secretaria-agricultura-desencadena-criticas-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/10\/mensaje-religioso-pascua-secretaria-agricultura-desencadena-criticas-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un mensaje religioso de Pascua de la secretaria de Agricultura a los funcionarios desencadena fuertes cr\u00edticas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/10\/mensaje-religioso-pascua-secretaria-agricultura-desencadena-criticas-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un mensaje religioso de Pascua de la secretaria de Agricultura a los funcionarios desencadena fuertes cr\u00edticas","url":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/10\/mensaje-religioso-pascua-secretaria-agricultura-desencadena-criticas-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/10\/mensaje-religioso-pascua-secretaria-agricultura-desencadena-criticas-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-10T11:03:53Z","datePublished":"2026-04-10T11:03:53Z","dateModified":"2026-04-10T11:03:53Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un mensaje religioso de Pascua de la secretaria de Agricultura a los funcionarios desencadena fuertes cr\\u00edticas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/04\\\/10\\\/mensaje-religioso-pascua-secretaria-agricultura-desencadena-criticas-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/04\\\/10\\\/mensaje-religioso-pascua-secretaria-agricultura-desencadena-criticas-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-10T11:03:53Z\",\"datePublished\":\"2026-04-10T11:03:53Z\",\"dateModified\":\"2026-04-10T11:03:53Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1472876,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/05\/papa-leon-xiv-misa-pascua-domingo-trax\/","url_meta":{"origin":1473026,"position":0},"title":"El papa Le\u00f3n XIV se centra en mantener la esperanza en medio de la guerra y el sufrimiento en su primera Misa de Pascua","author":"","date":"abril 5, 2026","format":false,"excerpt":"El papa Le\u00f3n XIV se centr\u00f3 en mantener la esperanza en medio de la violencia de la guerra, el cambio clim\u00e1tico y otros sufrimientos, en su primera homil\u00eda de Pascua desde que se convirti\u00f3 el a\u00f1o pasado en el l\u00edder de la Iglesia cat\u00f3lica.El papa Le\u00f3n, al hablar durante la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464330,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/07\/08\/secretaria-agricultura-amnistia-inmigrantes-reemplazados-trax\/","url_meta":{"origin":1473026,"position":1},"title":"No habr\u00e1 &#171;amnist\u00eda&#187; para inmigrantes para buscar una fuerza laboral &#171;100 % estadounidense&#187;, dice secretaria de Agricultura","author":"","date":"julio 8, 2025","format":false,"excerpt":"La secretaria de Agricultura, Brooke Rollins, declar\u00f3 este martes durante una conferencia de prensa que no habr\u00e1 \u201camnist\u00eda\u201d para los inmigrantes y que las deportaciones masivas continuar\u00e1n para lograr una fuerza laboral 100 % estadounidense. Rollins mencion\u00f3 el n\u00famero de adultos en el programa de Medicaid y afirm\u00f3 que hay\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461414,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/04\/20\/papa-bendicion-pascua-reunion-jd-vance-trax\/","url_meta":{"origin":1473026,"position":2},"title":"El papa da la bendici\u00f3n de Pascua en la aparici\u00f3n m\u00e1s destacada hasta el momento tras reunirse brevemente con J.D. Vance","author":"","date":"abril 20, 2025","format":false,"excerpt":"El papa Francisco dio la tradicional bendici\u00f3n de Pascua el domingo, apareciendo desde el balc\u00f3n de la Bas\u00edlica de San Pedro frente a una multitud encantada, en lo que marca su aparici\u00f3n de m\u00e1s alto perfil hasta ahora desde que fue dado de alta del hospital.El pont\u00edfice de 88 a\u00f1os\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461086,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/04\/11\/brooke-rollins-carne-argentina-orix\/","url_meta":{"origin":1473026,"position":3},"title":"Secretaria de Agricultura de Trump apunta contra la carne argentina: &#171;Vamos a poner a Estados Unidos primero&#187;","author":"","date":"abril 11, 2025","format":false,"excerpt":"En medio de la guerra comercial lanzada por Donald Trump con el anuncio de aranceles generalizados, un comentario de la secretaria de Agricultura podr\u00eda hacer encender las alarmas entre los productores de carne argentinos.\u201cVamos a poner a Estados Unidos primero; no a China, no a India, no a la carne\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447570,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/03\/31\/rey-carlos-pascua-servicio-religioso-trax\/","url_meta":{"origin":1473026,"position":4},"title":"El rey Carlos asiste a un servicio religioso de Pascua, su aparici\u00f3n p\u00fablica m\u00e1s significativa desde que le diagnosticaron c\u00e1ncer","author":"","date":"marzo 31, 2024","format":false,"excerpt":"(CNN) -- El rey Carlos III hace su aparici\u00f3n p\u00fablica m\u00e1s importante desde que se le diagnostic\u00f3 c\u00e1ncer el mes pasado, al asistir al tradicional servicio religioso de maitines de Pascua en Windsor el domingo.Carlos, de 75 a\u00f1os, parec\u00eda estar de buen humor cuando lleg\u00f3 en coche a la capilla\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447327,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/03\/25\/papa-francisco-se-salta-homilia-en-la-misa-del-domingo-de-ramos-trax\/","url_meta":{"origin":1473026,"position":5},"title":"El papa Francisco se salta por sorpresa la homil\u00eda en la misa del Domingo de Ramos","author":"","date":"marzo 25, 2024","format":false,"excerpt":"(CNN) --El papa Francisco inesperadamente se salt\u00f3 la homil\u00eda durante la misa de este domingo de ramos en el Vaticano.La homil\u00eda es un serm\u00f3n durante el cual el papa interpreta las escrituras y explica su significado en el mundo actual.El papa presidi\u00f3 el servicio que marca el comienzo de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1473026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1473026"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1473026\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1473026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1473026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1473026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}