{"id":1473043,"date":"2026-04-10T17:03:46","date_gmt":"2026-04-11T00:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/10\/aumentan-casos-sarampion-mexico-orix\/"},"modified":"2026-04-10T17:03:46","modified_gmt":"2026-04-11T00:03:46","slug":"aumentan-casos-sarampion-mexico-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/10\/aumentan-casos-sarampion-mexico-orix\/","title":{"rendered":"Aumentan los casos de sarampi\u00f3n en M\u00e9xico y ya se registraron un 39 % m\u00e1s que en 2025, seg\u00fan la Secretar\u00eda de Salud"},"content":{"rendered":"<p>M\u00e9xico sigue posicionado como uno de los pa\u00edses con mayor cantidad de <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/05\/mexico\/video\/sarampion-brote-alerta-mexico-mundial-conclusiones-tv\">casos de sarampi\u00f3n<\/a> en Am\u00e9rica. En lo que va del 2026, la Secretar\u00eda de Salud del pa\u00eds registr\u00f3 9.015 casos hasta el 9 de abril, un aumento considerable si se tiene en cuenta que durante 2025 se report\u00f3 un total de 6.464.<\/p>\n<p>Esto quiere decir que en los primeros meses de 2026, M\u00e9xico ya registr\u00f3 un 39,4 % m\u00e1s de casos de sarampi\u00f3n que en todo 2025, de acuerdo con los <a href=\"https:\/\/www.gob.mx\/cms\/uploads\/attachment\/file\/1070309\/INFORME_DIARIO_SARAMPION_20260409.pdf\">registros oficiales<\/a>.<\/p>\n<p>El Sistema Especial para la Vigilancia Epidemiol\u00f3gica de las Enfermedades Febriles Exantem\u00e1ticas de M\u00e9xico (EFE), confirm\u00f3 que entre enero de 2025 y el 9 de abril de 2026 se ha confirmado un total acumulado de 15.479 casos de sarampi\u00f3n, con un total de 36 muertes.<\/p>\n<p>Jalisco, con 5.197 casos, es el estado mexicano donde m\u00e1s enfermos se reportaron desde enero y donde los registros muestran la mayor incidencia de la enfermedad. Le siguen Chiapas y Ciudad de M\u00e9xico, cada uno con 735 casos; y luego el estado de M\u00e9xico, con 285.<\/p>\n<p>M\u00e1s de 200 casos se registraron en otros estados como Sinaloa, Sonora, Durango y Puebla; mientras que el resto report\u00f3 un n\u00famero menor a 200. El \u00fanico estado que no ha reportado casos en lo que va del a\u00f1o es Tamaulipas, que en 2025 s\u00ed registr\u00f3 12.<\/p>\n<p>El grupo de edad con el mayor n\u00famero de casos es de 1 a 4 a\u00f1os, seguido del grupo de 25 a 29 a\u00f1os y luego el de 5 a 9 a\u00f1os, se\u00f1al\u00f3 la secretar\u00eda de Salud en su reporte.<\/p>\n<p>En lo que va del a\u00f1o, 9 personas han muerto por sarampi\u00f3n en M\u00e9xico. 3 de ellas en Jalisco,1 en Ciudad de M\u00e9xico, 1 en Michoac\u00e1n, 1 en Guerrero, 1 en Sinaloa, 1 en Durango y 1 en Tlaxcala.<\/p>\n<p>La presidenta de M\u00e9xico, Claudia Sheinbaum, <a href=\"https:\/\/x.com\/Claudiashein\/status\/2023913475286986824\">llam\u00f3 en febrero a la poblaci\u00f3n<\/a> a que se vacune en el marco de la campa\u00f1a gratuita de prevenci\u00f3n contra la enfermedad, que aplica a menores de 6 meses a 12 a\u00f1os y a personas de 13 a 49 a\u00f1os, que deben contar con el esquema completo de dos dosis.<\/p>\n<p>Las autoridades incluso establecieron <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/05\/latinoamerica\/ops-alerta-salud-aumento-casos-sarampion-ap#:~:text=Las%20autoridades%20incluso%20han%20establecido%20cl%C3%ADnicas%20m%C3%B3viles%20de%20vacunaci%C3%B3n%20en%20centros%20de%20alta%20concurrencia%20como%20aeropuertos%20y%20terminales%20de%20autobuses.%20Mientras%20tanto%2C%20en%20la%20capital%2C%20la%20jefa%20de%20Gobierno%2C%20Clara%20Brugada%2C%20lanz%C3%B3%20esta%20semana%202.000%20nuevos%20m%C3%B3dulos%20de%20vacunaci%C3%B3n.\">cl\u00ednicas m\u00f3viles de vacunaci\u00f3n<\/a> en centros de alta circulaci\u00f3n, como terminales o aeropuertos.<\/p>\n<p>El reporte de aumento de casos, a pocas semanas del inicio del Mundial 2026, agrega preocupaci\u00f3n al panorama en M\u00e9xico por el temor a que <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/05\/mexico\/video\/sarampion-brote-alerta-mexico-mundial-conclusiones-tv\">se agrave la crisis<\/a> por esos eventos.<\/p>\n<p>A nivel mundial, el sarampi\u00f3n sigue siendo una de las principales causas de muerte en ni\u00f1os peque\u00f1os, pese a que existe una vacuna segura y eficaz para prevenirlo desde 1980, detalla la Organizaci\u00f3n Panamericana de la Salud (OPS). Entre 2000 y 2023, la tasa de mortalidad de la enfermedad a nivel mundial <a href=\"https:\/\/www.paho.org\/es\/temas\/sarampion\">disminuy\u00f3 en un 83 %<\/a> gracias en parte a la vacunaci\u00f3n.<\/p>\n<p>En 2025 se notificaron 14.975 casos confirmados de sarampi\u00f3n en 13 pa\u00edses, un n\u00famero 32 veces mayor en comparaci\u00f3n con 2024, dijo la OPS. En una alerta emitida en febrero, el organismo de la OMS remarc\u00f3 que el 78 % de los casos recientes involucraron a personas no vacunadas, luego de un a\u00f1o de un <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/05\/latinoamerica\/ops-alerta-salud-aumento-casos-sarampion-ap\">crecimiento sostenido de casos<\/a>.<\/p>\n<p>La enfermedad viral, que se transmite mediante gotas de aire de la nariz, boca o garganta de una persona infectada, puede causar severos problemas de salud y sus complicaciones pueden llevar a la muerte.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9xico sigue posicionado como uno de los pa\u00edses con mayor cantidad de casos de sarampi\u00f3n en Am\u00e9rica. En lo que va del 2026, la Secretar\u00eda de Salud del pa\u00eds registr\u00f3 9.015 casos hasta el 9 de abril, un aumento considerable si se tiene en cuenta que durante 2025 se report\u00f3 un total de 6.464. Esto [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1473043","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aumentan los casos de sarampi\u00f3n en M\u00e9xico y ya se registraron un 39 % m\u00e1s que en 2025, seg\u00fan la Secretar\u00eda de Salud - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/10\/aumentan-casos-sarampion-mexico-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aumentan los casos de sarampi\u00f3n en M\u00e9xico y ya se registraron un 39 % m\u00e1s que en 2025, seg\u00fan la Secretar\u00eda de Salud - Noticias\" \/>\n<meta property=\"og:description\" content=\"M\u00e9xico sigue posicionado como uno de los pa\u00edses con mayor cantidad de casos de sarampi\u00f3n en Am\u00e9rica. En lo que va del 2026, la Secretar\u00eda de Salud del pa\u00eds registr\u00f3 9.015 casos hasta el 9 de abril, un aumento considerable si se tiene en cuenta que durante 2025 se report\u00f3 un total de 6.464. Esto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/10\/aumentan-casos-sarampion-mexico-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-11T00:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/aumentan-casos-sarampion-mexico-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/aumentan-casos-sarampion-mexico-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Aumentan los casos de sarampi\u00f3n en M\u00e9xico y ya se registraron un 39 % m\u00e1s que en 2025, seg\u00fan la Secretar\u00eda de Salud\",\"datePublished\":\"2026-04-11T00:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/aumentan-casos-sarampion-mexico-orix\/\"},\"wordCount\":605,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/10\/aumentan-casos-sarampion-mexico-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/aumentan-casos-sarampion-mexico-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/10\/aumentan-casos-sarampion-mexico-orix\/\",\"name\":\"Aumentan los casos de sarampi\u00f3n en M\u00e9xico y ya se registraron un 39 % m\u00e1s que en 2025, seg\u00fan la Secretar\u00eda de Salud - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-11T00:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/aumentan-casos-sarampion-mexico-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/10\/aumentan-casos-sarampion-mexico-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/aumentan-casos-sarampion-mexico-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aumentan los casos de sarampi\u00f3n en M\u00e9xico y ya se registraron un 39 % m\u00e1s que en 2025, seg\u00fan la Secretar\u00eda de Salud\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aumentan los casos de sarampi\u00f3n en M\u00e9xico y ya se registraron un 39 % m\u00e1s que en 2025, seg\u00fan la Secretar\u00eda de Salud - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/10\/aumentan-casos-sarampion-mexico-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Aumentan los casos de sarampi\u00f3n en M\u00e9xico y ya se registraron un 39 % m\u00e1s que en 2025, seg\u00fan la Secretar\u00eda de Salud - Noticias","og_description":"M\u00e9xico sigue posicionado como uno de los pa\u00edses con mayor cantidad de casos de sarampi\u00f3n en Am\u00e9rica. En lo que va del 2026, la Secretar\u00eda de Salud del pa\u00eds registr\u00f3 9.015 casos hasta el 9 de abril, un aumento considerable si se tiene en cuenta que durante 2025 se report\u00f3 un total de 6.464. Esto [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/10\/aumentan-casos-sarampion-mexico-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-11T00:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/10\/aumentan-casos-sarampion-mexico-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/10\/aumentan-casos-sarampion-mexico-orix\/"},"author":{"name":"","@id":""},"headline":"Aumentan los casos de sarampi\u00f3n en M\u00e9xico y ya se registraron un 39 % m\u00e1s que en 2025, seg\u00fan la Secretar\u00eda de Salud","datePublished":"2026-04-11T00:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/10\/aumentan-casos-sarampion-mexico-orix\/"},"wordCount":605,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/10\/aumentan-casos-sarampion-mexico-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/10\/aumentan-casos-sarampion-mexico-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/10\/aumentan-casos-sarampion-mexico-orix\/","name":"Aumentan los casos de sarampi\u00f3n en M\u00e9xico y ya se registraron un 39 % m\u00e1s que en 2025, seg\u00fan la Secretar\u00eda de Salud - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-11T00:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/10\/aumentan-casos-sarampion-mexico-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/10\/aumentan-casos-sarampion-mexico-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/10\/aumentan-casos-sarampion-mexico-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Aumentan los casos de sarampi\u00f3n en M\u00e9xico y ya se registraron un 39 % m\u00e1s que en 2025, seg\u00fan la Secretar\u00eda de Salud"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/10\/aumentan-casos-sarampion-mexico-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Aumentan los casos de sarampi\u00f3n en M\u00e9xico y ya se registraron un 39 % m\u00e1s que en 2025, seg\u00fan la Secretar\u00eda de Salud","url":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/10\/aumentan-casos-sarampion-mexico-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/monterey-salinas\/2026\/04\/10\/aumentan-casos-sarampion-mexico-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-11T00:03:46Z","datePublished":"2026-04-11T00:03:46Z","dateModified":"2026-04-11T00:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Aumentan los casos de sarampi\\u00f3n en M\\u00e9xico y ya se registraron un 39 % m\\u00e1s que en 2025, seg\\u00fan la Secretar\\u00eda de Salud\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/04\\\/10\\\/aumentan-casos-sarampion-mexico-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/monterey-salinas\\\/2026\\\/04\\\/10\\\/aumentan-casos-sarampion-mexico-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-11T00:03:46Z\",\"datePublished\":\"2026-04-11T00:03:46Z\",\"dateModified\":\"2026-04-11T00:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1464251,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/07\/05\/casos-sarampion-record-estados-unidos-trax\/","url_meta":{"origin":1473043,"position":0},"title":"R\u00e9cord de casos de sarampi\u00f3n desde que la enfermedad fue declarada erradicada en Estados Unidos","author":"","date":"julio 5, 2025","format":false,"excerpt":"La disminuci\u00f3n de la cobertura de vacunaci\u00f3n infantil y un gran brote latente que se desencaden\u00f3 en una zona del oeste de Texas, una zona con baja cobertura de vacunaci\u00f3n, han llevado a Estados Unidos a alcanzar un nuevo y preocupante hito: este a\u00f1o se han registrado m\u00e1s casos de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459940,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/03\/14\/gobierno-confirma-22-casos-sarampion-2025-orix\/","url_meta":{"origin":1473043,"position":1},"title":"Gobierno de M\u00e9xico confirma 22 casos de sarampi\u00f3n en lo que va de 2025","author":"","date":"marzo 14, 2025","format":false,"excerpt":"El Gobierno de M\u00e9xico inform\u00f3 a trav\u00e9s de un comunicado que ya se han registrado en el pa\u00eds 22 casos confirmados de sarampi\u00f3n.Las autoridades reportaron hasta ahora 416 casos probables de sarampi\u00f3n o rub\u00e9ola, incluyendo a los 22 positivos, de los cuales 18 corresponden al estado de Chihuahua y los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461361,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/04\/18\/mitad-estados-casos-sarampion-trax\/","url_meta":{"origin":1473043,"position":2},"title":"La mitad de los estados de EE.UU. ha reportado casos de sarampi\u00f3n este a\u00f1o","author":"","date":"abril 18, 2025","format":false,"excerpt":"La mitad de los estados en EE.UU. est\u00e1n reportando casos de sarampi\u00f3n, con un total nacional que supera los 800 casos hasta ahora este a\u00f1o, seg\u00fan un conteo de CNN.La mayor\u00eda de los casos se concentran en un brote multistatal que involucra a Texas, Nuevo M\u00e9xico, Oklahoma y posiblemente Kansas,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459939,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/03\/14\/casos-sarampion-estados-unidos-superan-total-2024-trax\/","url_meta":{"origin":1473043,"position":3},"title":"Los casos de sarampi\u00f3n en Estados Unidos superan el total de 2024 en tan solo 3 meses de 2025","author":"","date":"marzo 14, 2025","format":false,"excerpt":"Con tan solo tres meses transcurridos de 2025, Estados Unidos ha superado el n\u00famero total de casos de sarampi\u00f3n en el pa\u00eds de todo el a\u00f1o pasado.En lo que va de 2025, se han notificado al menos 308 casos de sarampi\u00f3n en Estados Unidos, seg\u00fan datos de los Centros para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460096,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2025\/03\/18\/brote-sarampion-asciende-321-casos-trax\/","url_meta":{"origin":1473043,"position":4},"title":"El brote de sarampi\u00f3n en varios estados de EE.UU. asciende a 321 casos","author":"","date":"marzo 18, 2025","format":false,"excerpt":"Se han reportado 321 casos en el brote de sarampi\u00f3n en curso en Texas, Nuevo M\u00e9xico y Oklahoma, informaron los estados el martes. Esto representa un aumento de 25 casos desde la actualizaci\u00f3n del viernes.Texas ha reportado 279 casos asociados al brote, Nuevo M\u00e9xico ha informado 38 casos y Oklahoma\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470573,"url":"https:\/\/noticiasya.com\/monterey-salinas\/2026\/01\/28\/caso-sarampion-instalacion-ice-arizona-trax\/","url_meta":{"origin":1473043,"position":5},"title":"Confirman caso de sarampi\u00f3n en una instalaci\u00f3n de ICE en Arizona","author":"","date":"enero 28, 2026","format":false,"excerpt":"El Departamento de Seguridad Nacional de Estados Unidos inform\u00f3 que una persona detenida en una instalaci\u00f3n del Servicio de Control de Inmigraci\u00f3n y Aduanas (ICE, por sus siglas en ingl\u00e9s) en Arizona tiene sarampi\u00f3n, un virus altamente contagioso que puede causar fiebre alta y un sarpullido caracter\u00edstico.A principios de este\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/monterey-salinas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1473043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/comments?post=1473043"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/posts\/1473043\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/media?parent=1473043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/categories?post=1473043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/monterey-salinas\/wp-json\/wp\/v2\/tags?post=1473043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}