{"id":1439051,"date":"2023-05-19T12:09:57","date_gmt":"2023-05-19T19:09:57","guid":{"rendered":"https:\/\/noticiasya.com\/?p=1439051"},"modified":"2023-05-19T12:09:57","modified_gmt":"2023-05-19T19:09:57","slug":"gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/","title":{"rendered":"Gritos, llanto y hasta golpes en las filas para boletos de Luis Miguel"},"content":{"rendered":"<p>La gira de Luis Miguel ha causado una locura en todo el continente y es que era de esperarse que el regreso de &#171;El Sol&#187; se convertir\u00eda en uno de los m\u00e1s esperados en a\u00f1os no solo por el furor tras su serie de Netflix, sino por el acervo musical que guarda en su m\u00e1s de 20 discos de estudio y las compilaciones de \u00e9xitos que todo el mundo conoce.<\/p>\n<p>La venta de boletos tanto en M\u00e9xico como en Estados Unidos ha estado marcada por el llanto y la desesperaci\u00f3n de los fans al no alcanzar boletos y quedarse esperando en filas virtuales que parecen no tener fin.<\/p>\n<p>Tanto ha sido el revuelo por la compra de los tickets que las redes sociales se han llenado de memes para aquellos que no les queda de otra m\u00e1s que re\u00edr y reclamos de los que se quedaron a nada de completar la compra de sus boletos.<\/p>\n<p>En el caso de M\u00e9xico, la fiebre por ver a LuisMi ha llevado a los fans a compartir en redes los tr\u00e1gicos momentos que han atravesado tanto en internet como en las taquillas de los venues y como en todo lugar con caos, la gente se ha vuelto loca hasta el punto de llegar a los golpes.<\/p>\n<p>Esta ma\u00f1ana se report\u00f3 que una de las taquillas para comprar boletos, dos fans terminaron agarr\u00e1ndose a golpes debido a la mala organizaci\u00f3n de las filas y el orden que les correspond\u00eda, aunque muchos se\u00f1alan que se trata de dos revendedores que quer\u00edan quedarse &#171;con todo el pastel&#187;.<\/p>\n<p>En un pa\u00eds como M\u00e9xico en el que reina la desorganizaci\u00f3n, no sorprende que a lo largo de las filas hayan revendedores infiltrados queriendo comprar boletos para despu\u00e9s venderlos a precios altos, pero el verdadero problema, es que hay gente que los paga.<\/p>\n<p>De cualquier forma, la pelea de estos dos sujetos qued\u00f3 en video para los curiosos que quisieran saber c\u00f3mo es que se pone el ambiente en las filas para comprar boletitos en M\u00e9xico&#8230;<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"es\" dir=\"ltr\">T\u00fa pap\u00e1 pele\u00e1ndose por boletos de Luis Miguel  <a href=\"https:\/\/t.co\/p9a3nxNSjz\">pic.twitter.com\/p9a3nxNSjz<\/a><\/p>\n<p>&mdash; el gosco (@ghostcolour) <a href=\"https:\/\/twitter.com\/ghostcolour\/status\/1658971345802199045?ref_src=twsrc%5Etfw\">May 17, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La gira de Luis Miguel ha causado una locura en todo el continente y es que era de esperarse que el regreso de &#171;El Sol&#187; se convertir\u00eda en uno de los m\u00e1s esperados en a\u00f1os no solo por el furor tras su serie de Netflix, sino por el acervo musical que guarda en su m\u00e1s [&hellip;]<\/p>\n","protected":false},"author":195803851,"featured_media":1439053,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[51],"tags":[207,208,209,210,211],"class_list":["post-1439051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento","tag-boletos","tag-concierto","tag-luis-miguel","tag-pelea","tag-taquilla","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gritos, llanto y hasta golpes en las filas para boletos de Luis Miguel - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/las-vegas\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gritos, llanto y hasta golpes en las filas para boletos de Luis Miguel - Noticias\" \/>\n<meta property=\"og:description\" content=\"La gira de Luis Miguel ha causado una locura en todo el continente y es que era de esperarse que el regreso de &#171;El Sol&#187; se convertir\u00eda en uno de los m\u00e1s esperados en a\u00f1os no solo por el furor tras su serie de Netflix, sino por el acervo musical que guarda en su m\u00e1s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/las-vegas\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-19T19:09:57+00:00\" \/>\n<meta name=\"author\" content=\"Eduardo Salinas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Salinas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/las-vegas\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/las-vegas\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/\"},\"author\":{\"name\":\"Eduardo Salinas\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\"},\"headline\":\"Gritos, llanto y hasta golpes en las filas para boletos de Luis Miguel\",\"datePublished\":\"2023-05-19T19:09:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/las-vegas\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/\"},\"wordCount\":375,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/las-vegas\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Boletos\",\"Concierto\",\"Luis Miguel\",\"Pelea\",\"Taquilla\"],\"articleSection\":[\"Entretenimiento\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/las-vegas\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/\",\"url\":\"https:\/\/noticiasya.com\/las-vegas\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/\",\"name\":\"Gritos, llanto y hasta golpes en las filas para boletos de Luis Miguel - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/las-vegas\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/las-vegas\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2023-05-19T19:09:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/las-vegas\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/las-vegas\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/las-vegas\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/las-vegas\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gritos, llanto y hasta golpes en las filas para boletos de Luis Miguel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0\",\"name\":\"Eduardo Salinas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g\",\"caption\":\"Eduardo Salinas\"},\"sameAs\":[\"http:\/\/eduardo.salinas@entravision.com\"],\"url\":\"https:\/\/noticiasya.com\/nacional\/author\/eduardosalinas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gritos, llanto y hasta golpes en las filas para boletos de Luis Miguel - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/las-vegas\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/","og_locale":"es_ES","og_type":"article","og_title":"Gritos, llanto y hasta golpes en las filas para boletos de Luis Miguel - Noticias","og_description":"La gira de Luis Miguel ha causado una locura en todo el continente y es que era de esperarse que el regreso de &#171;El Sol&#187; se convertir\u00eda en uno de los m\u00e1s esperados en a\u00f1os no solo por el furor tras su serie de Netflix, sino por el acervo musical que guarda en su m\u00e1s [&hellip;]","og_url":"https:\/\/noticiasya.com\/las-vegas\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/","og_site_name":"Noticias","article_published_time":"2023-05-19T19:09:57+00:00","author":"Eduardo Salinas","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Eduardo Salinas","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/las-vegas\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/las-vegas\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/"},"author":{"name":"Eduardo Salinas","@id":"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0"},"headline":"Gritos, llanto y hasta golpes en las filas para boletos de Luis Miguel","datePublished":"2023-05-19T19:09:57+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/las-vegas\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/"},"wordCount":375,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"image":{"@id":"https:\/\/noticiasya.com\/las-vegas\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/#primaryimage"},"thumbnailUrl":"","keywords":["Boletos","Concierto","Luis Miguel","Pelea","Taquilla"],"articleSection":["Entretenimiento"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/las-vegas\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/","url":"https:\/\/noticiasya.com\/las-vegas\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/","name":"Gritos, llanto y hasta golpes en las filas para boletos de Luis Miguel - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/noticiasya.com\/las-vegas\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/#primaryimage"},"image":{"@id":"https:\/\/noticiasya.com\/las-vegas\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/#primaryimage"},"thumbnailUrl":"","datePublished":"2023-05-19T19:09:57+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/las-vegas\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/las-vegas\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/las-vegas\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/las-vegas\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Gritos, llanto y hasta golpes en las filas para boletos de Luis Miguel"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/noticiasya.com\/#\/schema\/person\/4465cb4584b40dfc04e6d5f1eb9805c0","name":"Eduardo Salinas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/53ef4c1ba9c4b41bbf590918000506ea3d08c65bc805b1c3651ee175be1cf0b1?s=96&d=mm&r=g","caption":"Eduardo Salinas"},"sameAs":["http:\/\/eduardo.salinas@entravision.com"],"url":"https:\/\/noticiasya.com\/nacional\/author\/eduardosalinas"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Gritos, llanto y hasta golpes en las filas para boletos de Luis Miguel","url":"http:\/\/noticiasya.com\/nacional\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2023\/05\/19\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Entretenimiento","author":[{"@type":"Person","name":"Eduardo Salinas"}],"creator":["Eduardo Salinas"],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":["boletos","concierto","luis miguel","pelea","taquilla"],"dateCreated":"2023-05-19T19:09:57Z","datePublished":"2023-05-19T19:09:57Z","dateModified":"2023-05-19T19:09:57Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Gritos, llanto y hasta golpes en las filas para boletos de Luis Miguel\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2023\\\/05\\\/19\\\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2023\\\/05\\\/19\\\/gritos-llanto-y-hasta-golpes-en-las-filas-para-boletos-de-luis-miguel\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Entretenimiento\",\"author\":[{\"@type\":\"Person\",\"name\":\"Eduardo Salinas\"}],\"creator\":[\"Eduardo Salinas\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[\"boletos\",\"concierto\",\"luis miguel\",\"pelea\",\"taquilla\"],\"dateCreated\":\"2023-05-19T19:09:57Z\",\"datePublished\":\"2023-05-19T19:09:57Z\",\"dateModified\":\"2023-05-19T19:09:57Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1440740,"url":"https:\/\/noticiasya.com\/nacional\/2023\/09\/14\/los-boletos-para-luis-miguel-en-las-vegas-alcanzaron-hasta-150-mil-pesos\/","url_meta":{"origin":1439051,"position":0},"title":"Los boletos para Luis Miguel en Las Vegas alcanzaron hasta 150 mil pesos","author":"Eduardo Salinas","date":"septiembre 14, 2023","format":false,"excerpt":"Una de las visitas obligadas para Luis Miguel en su gira 2023 es sin duda el escenario de Las Vegas, donde no solo ofrecer\u00e1 su espect\u00e1culo sino que tambi\u00e9n dar\u00e1 el grito de Independencia de M\u00e9xico pues llegar\u00e1 este 15 de septiembre al Park MGM. Como sabemos, los boletos para\u2026","rel":"","context":"In &quot;Entretenimiento&quot;","block_context":{"text":"Entretenimiento","link":"https:\/\/noticiasya.com\/nacional\/categoria\/entretenimiento"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/09\/img10.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/09\/img10.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/09\/img10.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/09\/img10.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1456665,"url":"https:\/\/noticiasya.com\/nacional\/2024\/12\/16\/luis-miguel-cierra-gira-mas-taquillera-orix\/","url_meta":{"origin":1439051,"position":1},"title":"Con m\u00e1s de US$ 300 millones recaudados, Luis Miguel cierra en Argentina &#171;la gira latina m\u00e1s taquillera de todos los tiempos&#187;","author":"Eduardo Salinas","date":"diciembre 16, 2024","format":false,"excerpt":"Fiel al dicho popular \u201ctodo termina donde inicia\u201d, el astro mexicano Luis Miguel finalizar\u00e1 este martes y mi\u00e9rcoles en el Campo Argentino de Polo de la ciudad de Buenos Aires, Argentina, su exitosa gira internacional \u201cLuis Miguel 2023-2024\u201d, considerada por Billboard Boxcore como \u201cla gira latina m\u00e1s taquillera de todos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446283,"url":"https:\/\/noticiasya.com\/nacional\/2024\/03\/04\/luis-miguel-suspende-concierto-en-bolivia-orix\/","url_meta":{"origin":1439051,"position":2},"title":"Luis Miguel suspende su concierto en Bolivia por \u201ccircunstancias\u201d que afectan \u201cla viabilidad del espect\u00e1culo\u201d","author":"","date":"marzo 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El cantante mexicano Luis Miguel suspendi\u00f3 este lunes el concierto que ten\u00eda programado en Santa Cruz, Bolivia, el 28 de marzo debido a \u201ccircunstancias de car\u00e1cter log\u00edstico que afectan la viabilidad del espect\u00e1culo\u201d, seg\u00fan se inform\u00f3 en un comunicado difundido por ETime, uno de los organizadores de la\u2026","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446399,"url":"https:\/\/noticiasya.com\/nacional\/2024\/03\/04\/luis-miguel-suspende-concierto-en-bolivia-orix-2\/","url_meta":{"origin":1439051,"position":3},"title":"Luis Miguel suspende su concierto en Bolivia por \u201ccircunstancias\u201d que afectan \u201cla viabilidad del espect\u00e1culo\u201d","author":"agomez","date":"marzo 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El cantante mexicano Luis Miguel suspendi\u00f3 este lunes el concierto que ten\u00eda programado en Santa Cruz, Bolivia, el 28 de marzo debido a \u201ccircunstancias de car\u00e1cter log\u00edstico que afectan la viabilidad del espect\u00e1culo\u201d, seg\u00fan se inform\u00f3 en un comunicado difundido por ETime, uno de los organizadores de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1415596,"url":"https:\/\/noticiasya.com\/nacional\/2022\/07\/26\/los-lugares-que-han-vendido-boletos-ganadores-de-mega-millions-en-colorado\/","url_meta":{"origin":1439051,"position":4},"title":"Los lugares que han vendido boletos ganadores de Mega Millions en Colorado","author":"agomez","date":"julio 26, 2022","format":false,"excerpt":"Nunca alguien en el estado se ha ganado el premio mayor y este martes hay r\u00e9cord en el bote a entregar.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/nacional\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467442,"url":"https:\/\/noticiasya.com\/nacional\/2025\/10\/16\/millon-boletos-vendidos-mundial-2026-orix\/","url_meta":{"origin":1439051,"position":5},"title":"FIFA: m\u00e1s de un mill\u00f3n de boletos vendidos para el Mundial 2026, con M\u00e9xico, Colombia y Argentina entre los m\u00e1s compradores","author":"agomez","date":"octubre 16, 2025","format":false,"excerpt":"Faltan 270 d\u00edas para el comienzo de la Copa del Mundo 2026, pero muchos aficionados ya lo sienten un poco m\u00e1s cerca. La FIFA dio a conocer este jueves que ya se han vendido m\u00e1s de un mill\u00f3n de boletos durante la primera fase de preventa, que comenz\u00f3 en septiembre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1439051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/users\/195803851"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1439051"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1439051\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1439051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1439051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1439051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}