{"id":1443579,"date":"2024-01-12T11:33:37","date_gmt":"2024-01-12T19:33:37","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1443579"},"modified":"2024-01-12T11:33:37","modified_gmt":"2024-01-12T19:33:37","slug":"mapaches-zorros-suricatas-corea-del-sur-toma-medidas-drasticas-contra-los-controvertidos-cafes-de-animales","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2024\/01\/12\/mapaches-zorros-suricatas-corea-del-sur-toma-medidas-drasticas-contra-los-controvertidos-cafes-de-animales\/","title":{"rendered":"Mapaches, zorros, suricatas: Corea del Sur toma medidas dr\u00e1sticas contra los controvertidos caf\u00e9s de animales"},"content":{"rendered":"<p>(CNN) &#8212; Enjaulado detr\u00e1s de un vidrio, un mapache regordete corre durante unos segundos en una rueda de ejercicio antes de volver a caer al suelo. En el siguiente recinto, un par de perros de la pradera, que parecen marmotas, se posan sobre troncos bajo la deslumbrante luz artificial de una l\u00e1mpara de techo.<\/p>\n<p>Al otro lado del vidrio, los clientes encantados beben caf\u00e9 con leche y se toman selfies con los animales en una escena que se desarrolla en toda Corea del Sur.<\/p>\n<p>Los caf\u00e9s de animales han ganado popularidad en el pa\u00eds durante la \u00faltima d\u00e9cada, primero con gatos y perros, luego con especies de vida silvestre cada vez m\u00e1s inusuales en la era de la viralidad en l\u00ednea.<\/p>\n<p>S\u00f3lo en este caf\u00e9, en el moderno distrito universitario Hongdae de Se\u00fal, hay m\u00e1s de 40 especies, incluidos puercoespines, serpientes, zorros y hurones, seg\u00fan un letrero en la puerta que lo anuncia como un lugar \u00fanico para citas.<\/p>\n<p>Corea del Sur aprueba un proyecto de ley para prohibir el consumo de carne de perro<\/p>\n<p>Un miembro del personal alimenta a un mapache albino en un caf\u00e9 de animales en Se\u00fal, Corea del Sur, el 2 de abril de 2020. (Cr\u00e9dito: Ed Jones\/AFP\/Getty Images)<\/p>\n<p>Pero los caf\u00e9s tambi\u00e9n han avivado la controversia, y los defensores del bienestar animal han presionado durante mucho tiempo para imponer restricciones m\u00e1s severas o incluso una prohibici\u00f3n total de este tipo de negocios.<\/p>\n<p>La creciente oposici\u00f3n llev\u00f3 al Gobierno de Corea del Sur a tomar medidas dr\u00e1sticas con un conjunto de nuevas leyes que entraron en vigor en diciembre, prohibiendo efectivamente que los caf\u00e9s exhiban animales salvajes vivos a menos que est\u00e9n registrados como zool\u00f3gicos o acuarios.<\/p>\n<p>Los expertos dicen que si bien es un paso positivo, es necesario hacer m\u00e1s, dado el alcance limitado de la ley y la oposici\u00f3n de los due\u00f1os de negocios que argumentan que sus medios de vida est\u00e1n en riesgo.<\/p>\n<p>&#171;Dado que todo tiene que ver con dinero\u2026 creo que los efectos (de la ley) ser\u00e1n m\u00ednimos&#187;, dijo Jang Ji-deok, director general del Departamento de Gesti\u00f3n Zool\u00f3gica del Instituto Nacional de Ecolog\u00eda, que asesor\u00f3 al Gobierno sobre la legislaci\u00f3n.<\/p>\n<p>&#171;Sin embargo, (la introducci\u00f3n de la ley) todav\u00eda significa que las cosas est\u00e1n mejorando gradualmente&#187;, agreg\u00f3.<\/p>\n<p>El auge de los caf\u00e9s de animales<\/p>\n<p>Desde que se abri\u00f3 el primer caf\u00e9 de gatos del mundo en Taiw\u00e1n en 1998, la moda se ha extendido internacionalmente y, a principios de la d\u00e9cada de 2010, se abrieron muchos caf\u00e9s en toda Corea del Sur. En un t\u00edpico caf\u00e9 de animales, los clientes pueden disfrutar de bebidas o comida mientras acarician o alimentan a los peludos residentes, un concepto especialmente novedoso en los centros urbanos donde las oportunidades de interactuar con animales no domesticados son pocas.<\/p>\n<p>Pero los animales expuestos en Corea r\u00e1pidamente se expandieron m\u00e1s all\u00e1 del t\u00edpico gato dom\u00e9stico: un caf\u00e9 en Hongdae, por ejemplo, atrae a los visitantes con sus ovejas esponjosas y su interior con tem\u00e1tica de ovejas.<\/p>\n<p>Kang Aesol, residente de Se\u00fal, dijo que recientemente visit\u00f3 el caf\u00e9 de las ovejas, habiendo o\u00eddo hablar de \u00e9l durante a\u00f1os. Describi\u00f3 la visita como una manera de \u201cganar tranquilidad\u201d despu\u00e9s de pasar largos y frustrantes d\u00edas detr\u00e1s de una computadora en el trabajo.<\/p>\n<p>&#171;Cuando ves la inocencia de los animales, \u00bfno se desvanece la ira en tu coraz\u00f3n?&#187;, dijo. &#171;Las ovejas parec\u00edan tranquilas y yo tambi\u00e9n&#187;.<\/p>\n<p>Singapur cambiar\u00e1 una ley que proh\u00edbe tener gatos en los apartamentos construidos por el gobierno<\/p>\n<p>Una mujer se toma una selfie con una oveja en un caf\u00e9 de ovejas en Se\u00fal el 17 de febrero de 2015. (Cr\u00e9dito: Ed Jones\/AFP\/Getty Images)<\/p>\n<p>Hasta las leyes recientemente modificadas, exist\u00edan pocas regulaciones. Seg\u00fan la anterior ley de protecci\u00f3n animal, s\u00f3lo era ilegal recolectar o comercializar especies en peligro de extinci\u00f3n. Eso significaba que animales salvajes como mapaches, ganado como ovejas y otros animales vistos como novedades eran presa f\u00e1cil para los caf\u00e9s de mascotas, que estaban adem\u00e1s protegidos por su registro comercial oficial como restaurantes o \u00e1reas de descanso.<\/p>\n<p>Y con la creciente demanda, se avecinaban grandes ganancias.<\/p>\n<p>\u201c\u00a1Propietarios que administran cafeter\u00edas, restaurantes y otras tiendas pero tienen dificultades para operarlas porque no realizan ventas! Intenten cambiarse a una cafeter\u00eda de mascotas, que es popular hoy en d\u00eda. \u00a1Sus ganancias marcar\u00e1n una gran diferencia!&#187;, aconseja Aevan, una empresa de consultor\u00eda de negocios de mascotas con sede en Corea, en su sitio web.<\/p>\n<p>Seg\u00fan su modelo de negocio, Aevan estima que el lanzamiento de un caf\u00e9 para perros costar\u00eda un m\u00ednimo de US$ 40.000 y podr\u00eda generar m\u00e1s de US$ 15.000 al mes en ganancias netas.<\/p>\n<p>Las redes sociales tambi\u00e9n han influido. Una b\u00fasqueda r\u00e1pida en Google muestra innumerables blogs de viajes, videos de YouTube y publicaciones de Instagram sobre caf\u00e9s para mascotas coreanos. Un caf\u00e9 para perros Samoyedo en Se\u00fal tiene m\u00e1s de 81.000 seguidores en Instagram y la fila para obtener mesa a menudo llega hasta m\u00e1s all\u00e1 de la puerta.<\/p>\n<p>Lo que dicen los cr\u00edticos<\/p>\n<p>A medida que proliferaron los caf\u00e9s de animales, siguieron las cr\u00edticas.<\/p>\n<p>Informes de los medios locales han se\u00f1alado los peque\u00f1os y estrechos espacios en los que viven los animales; el estr\u00e9s causado por el contacto y manipulaci\u00f3n constante por parte de los visitantes; problemas de salud por mala alimentaci\u00f3n, y los visitantes a menudo reciben golosinas para alimentar a los animales; y otras lagunas en la atenci\u00f3n, como enriquecimiento o preparaci\u00f3n insuficientes.<\/p>\n<p>Muchas empresas tienen reglas como prohibir a los clientes recoger ciertos animales o no permitir la entrada a ni\u00f1os menores de cierta edad.<\/p>\n<p>Kang dijo que el caf\u00e9 de ovejas que visit\u00f3 ten\u00eda reglas para evitar que los clientes asustaran a las ovejas. Tambi\u00e9n hab\u00eda un lavabo para que los clientes se lavaran las manos antes y despu\u00e9s de acariciar a los animales.<\/p>\n<p>Dijo que s\u00f3lo acarici\u00f3 a las ovejas \u201ccon mucho cuidado\u201d unas cuantas veces, temiendo que un mayor manejo las hiciera sentir inc\u00f3modas, y pas\u00f3 el resto de la visita observ\u00e1ndolas desde la distancia \u201cmientras com\u00edan, rumian y descansaban entre ellas&#187;.<\/p>\n<p>&#171;Cuando escuchas el t\u00e9rmino &#8216;caf\u00e9 de animales&#8217;, es posible que tengas ideas preconcebidas sobre el abuso animal, pero despu\u00e9s de enterarme de este (caf\u00e9), pens\u00e9 que era un sistema realmente bueno\u201d, dijo. &#171;Las ovejas parec\u00edan muy sanas y no parec\u00edan ansiosas&#187;.<\/p>\n<p>Los gatos entienden sus nombres y tal vez eligen ignorarlo, sugiere un estudio<\/p>\n<p>En esta foto tomada el 31 de marzo de 2020 un grupo de canguros comen mientras un miembro del personal observa, en el caf\u00e9 de animales Eden Meerkat Friends en Se\u00fal. (Cr\u00e9dito: Ed Jones\/AFP\/Getty Images)<\/p>\n<p>Pero no todos los caf\u00e9s cuentan con estos sistemas y los riesgos pueden ser mayores dependiendo de la especie animal, dicen los expertos.<\/p>\n<p>&#171;A trav\u00e9s del contacto f\u00edsico no s\u00f3lo se afectan los animales, sino que tambi\u00e9n puede afectar a quienes los tocan, como la posibilidad de que se propaguen enfermedades zoon\u00f3ticas. A pesar de esto, los visitantes y aprendices contin\u00faan toc\u00e1ndolos para tener la experiencia completa\u201d, dijo Jang, del Instituto Nacional de Ecolog\u00eda.<\/p>\n<p>&#171;Lo mismo ocurre con la alimentaci\u00f3n de los animales&#187;, dijo, a\u00f1adiendo que muchos zool\u00f3gicos y caf\u00e9s cerrados cierran los lunes &#171;porque es cuando todos los animales se enferman por comer la comida que les dan los visitantes&#187;.<\/p>\n<p>Cambio de leyes<\/p>\n<p>A pesar de a\u00f1os de cabildeo, los intentos anteriores de introducir regulaciones se han estancado, incluida una propuesta de enmienda a la Ley de Protecci\u00f3n Animal que finalmente fracas\u00f3.<\/p>\n<p>Pero, dijo Jang, la nueva legislaci\u00f3n promulgada el mes pasado refleja la creciente preocupaci\u00f3n del Gobierno por &#171;casos de animales venenosos y peligrosos que se exhiben y venden indiscriminadamente en el pa\u00eds&#187;, as\u00ed como la creciente presi\u00f3n del p\u00fablico.<\/p>\n<p>Seg\u00fan las nuevas enmiendas a la Ley de Protecci\u00f3n de la Vida Silvestre, s\u00f3lo las instalaciones oficialmente registradas como zool\u00f3gicos o acuarios pueden exhibir \u201canimales salvajes vivos\u201d. Los caf\u00e9s de animales existentes ahora tienen cuatro a\u00f1os para obtener el registro como zool\u00f3gico o acuario, o cerrar, seg\u00fan la ley, con el per\u00edodo de gracia destinado a minimizar cualquier abandono de animales por parte de los caf\u00e9s que cierran.<\/p>\n<p>&#171;Muchos caf\u00e9s sobre mapaches y otros animales cerraron debido al covid-19\u201d, dijo Jang. &#171;La realidad es que, con el cierre de estos caf\u00e9s, muchos de estos animales est\u00e1n siendo abandonados y los lugares que se supone que deben acogerlos tambi\u00e9n est\u00e1n cerrando&#187;.<\/p>\n<p>En una foto tomada el 2 de abril de 2020, un gato sentado en una mesa en el Table A Raccoon Cafe en Se\u00fal. (Cr\u00e9dito: Ed Jones\/AFP\/Getty Images)<\/p>\n<p>Un refugio administrado por el Gobierno para animales abandonados en peligro de extinci\u00f3n corre el riesgo de desbordarse, por lo que el Ministerio de Medio Ambiente est\u00e1 construyendo m\u00e1s instalaciones de este tipo, incluida una para \u201cfauna ex\u00f3tica\u201d no amenazada, dijo.<\/p>\n<p>Jang a\u00f1adi\u00f3 que la concesi\u00f3n de licencias para zool\u00f3gicos y acuarios establece ciertos est\u00e1ndares para los recintos de animales, la dotaci\u00f3n de personal, la gesti\u00f3n de enfermedades y seguridad, y exige inspecciones peri\u00f3dicas.<\/p>\n<p>&#171;Con esto, creo que se proporcionar\u00e1n mejores ambientes para los animales a medida que se aplique m\u00e1s la educaci\u00f3n sobre el bienestar de los animales&#187;, dijo Jang.<\/p>\n<p>Pero la ley ha preocupado a algunos due\u00f1os de negocios, quienes dicen que las medidas del Gobierno no hacen lo suficiente para amortiguar el golpe a los caf\u00e9s, o a sus animales residentes.<\/p>\n<p>Koo Jung-hwan, propietario de un caf\u00e9 de suricatas en Se\u00fal, dice que se encuentra en una encrucijada sobre si entablar una disputa legal, cerrar su negocio o solicitar una licencia como zool\u00f3gico cubierto. Dado el per\u00edodo de gracia, planea mantener su negocio abierto por ahora, pero expres\u00f3 su preocupaci\u00f3n por la posibilidad de que otros caf\u00e9s abandonen a sus animales.<\/p>\n<p>&#171;La ley proh\u00edbe los caf\u00e9s de animales, pero no ofrece alternativas ni soluciones como qu\u00e9 hacer con los animales. El Gobierno deber\u00eda haber pensado en eso&#187;, dijo, y agreg\u00f3 que se quedar\u00eda con sus suricatas incluso si su caf\u00e9 eventualmente cerrara.<\/p>\n<p>&#171;Tengo que conservarlos por el resto de sus vidas porque son mi familia\u201d, dijo. &#171;Tengo el deber de cuidarlos&#187;.<\/p>\n<p>Pr\u00f3ximos pasos<\/p>\n<p>En el otro lado del debate, algunos activistas y defensores dicen que la ley no va lo suficientemente lejos porque solo se centra en caf\u00e9s que exhiben vida silvestre, lo que significa que los caf\u00e9s con animales clasificados como \u201cmascotas\u201d o \u201cganado\u201d est\u00e1n exentos de la normativa, ya se trate de perros y gatos o de hurones y ovejas.<\/p>\n<p>Estas excepciones \u201cpodr\u00edan aprovecharse\u201d, dijo Jang, y agreg\u00f3 que las leyes de bienestar animal \u201cno se implementan con tanta fuerza\u201d en Corea del Sur en comparaci\u00f3n con algunos pa\u00edses europeos con reglas m\u00e1s estrictas. Sin embargo, dijo, es poco probable que las autoridades ampl\u00eden la ley para incluir a las mascotas y al ganado, lo que podr\u00eda diezmar la industria de los caf\u00e9s de animales y los peque\u00f1os ranchos en todo el pa\u00eds.<\/p>\n<p>Un miembro del personal sostiene un ualab\u00ed en un caf\u00e9 de animales en Se\u00fal, Corea del Sur, el 31 de marzo de 2020. (Cr\u00e9dito: Ed Jones\/AFP\/Getty Images)<\/p>\n<p>&#171;Porque los due\u00f1os de estas empresas tienen derecho a sobrevivir, no creo que el Estado pueda imponerlo\u201d, afirm\u00f3. \u201cEs como un arma de doble filo. Algunas personas&#8230; nos dicen que no podemos quitarle el sustento a la gente, mientras que los activistas por los derechos de los animales quieren que todos estos establecimientos cierren sus puertas\u201d.<\/p>\n<p>Se est\u00e1n preparando m\u00e1s propuestas. El Instituto Nacional de Ecolog\u00eda, a cargo del Gobierno, ha sugerido pautas como introducir programas educativos en caf\u00e9s de animales, exigir a los visitantes que se pongan guantes antes de manipular animales y limitarlos a s\u00f3lo uno o dos minutos con cada animal, dijo Jang. Y aunque el progreso es gradual, las nuevas leyes lo alientan.<\/p>\n<p>&#171;Es agradable ver c\u00f3mo las cosas que alguna vez esper\u00e9 se est\u00e1n convirtiendo poco a poco en realidad\u201d, dijo, y agreg\u00f3 que el siguiente paso es asegurar m\u00e1s fondos para que los zool\u00f3gicos y acuarios mejoren sus instalaciones. &#171;Estoy seguro de que nuestro pa\u00eds puede hacerlo&#187;.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Enjaulado detr\u00e1s de un vidrio, un mapache regordete corre durante unos segundos en una rueda de ejercicio antes de volver a caer al suelo. En el siguiente recinto, un par de perros de la pradera, que parecen marmotas, se posan sobre troncos bajo la deslumbrante luz artificial de una l\u00e1mpara de techo. Al [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1443579","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mapaches, zorros, suricatas: Corea del Sur toma medidas dr\u00e1sticas contra los controvertidos caf\u00e9s de animales - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/01\/12\/mapaches-zorros-suricatas-corea-del-sur-toma-medidas-drasticas-contra-los-controvertidos-cafes-de-animales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mapaches, zorros, suricatas: Corea del Sur toma medidas dr\u00e1sticas contra los controvertidos caf\u00e9s de animales - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Enjaulado detr\u00e1s de un vidrio, un mapache regordete corre durante unos segundos en una rueda de ejercicio antes de volver a caer al suelo. En el siguiente recinto, un par de perros de la pradera, que parecen marmotas, se posan sobre troncos bajo la deslumbrante luz artificial de una l\u00e1mpara de techo. Al [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/01\/12\/mapaches-zorros-suricatas-corea-del-sur-toma-medidas-drasticas-contra-los-controvertidos-cafes-de-animales\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-12T19:33:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/12\/mapaches-zorros-suricatas-corea-del-sur-toma-medidas-drasticas-contra-los-controvertidos-cafes-de-animales\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/12\/mapaches-zorros-suricatas-corea-del-sur-toma-medidas-drasticas-contra-los-controvertidos-cafes-de-animales\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Mapaches, zorros, suricatas: Corea del Sur toma medidas dr\u00e1sticas contra los controvertidos caf\u00e9s de animales\",\"datePublished\":\"2024-01-12T19:33:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/12\/mapaches-zorros-suricatas-corea-del-sur-toma-medidas-drasticas-contra-los-controvertidos-cafes-de-animales\/\"},\"wordCount\":2210,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/12\/mapaches-zorros-suricatas-corea-del-sur-toma-medidas-drasticas-contra-los-controvertidos-cafes-de-animales\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/12\/mapaches-zorros-suricatas-corea-del-sur-toma-medidas-drasticas-contra-los-controvertidos-cafes-de-animales\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/01\/12\/mapaches-zorros-suricatas-corea-del-sur-toma-medidas-drasticas-contra-los-controvertidos-cafes-de-animales\/\",\"name\":\"Mapaches, zorros, suricatas: Corea del Sur toma medidas dr\u00e1sticas contra los controvertidos caf\u00e9s de animales - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-12T19:33:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/12\/mapaches-zorros-suricatas-corea-del-sur-toma-medidas-drasticas-contra-los-controvertidos-cafes-de-animales\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/12\/mapaches-zorros-suricatas-corea-del-sur-toma-medidas-drasticas-contra-los-controvertidos-cafes-de-animales\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/12\/mapaches-zorros-suricatas-corea-del-sur-toma-medidas-drasticas-contra-los-controvertidos-cafes-de-animales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mapaches, zorros, suricatas: Corea del Sur toma medidas dr\u00e1sticas contra los controvertidos caf\u00e9s de animales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mapaches, zorros, suricatas: Corea del Sur toma medidas dr\u00e1sticas contra los controvertidos caf\u00e9s de animales - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/01\/12\/mapaches-zorros-suricatas-corea-del-sur-toma-medidas-drasticas-contra-los-controvertidos-cafes-de-animales\/","og_locale":"es_ES","og_type":"article","og_title":"Mapaches, zorros, suricatas: Corea del Sur toma medidas dr\u00e1sticas contra los controvertidos caf\u00e9s de animales - Noticias","og_description":"(CNN) &#8212; Enjaulado detr\u00e1s de un vidrio, un mapache regordete corre durante unos segundos en una rueda de ejercicio antes de volver a caer al suelo. En el siguiente recinto, un par de perros de la pradera, que parecen marmotas, se posan sobre troncos bajo la deslumbrante luz artificial de una l\u00e1mpara de techo. Al [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/01\/12\/mapaches-zorros-suricatas-corea-del-sur-toma-medidas-drasticas-contra-los-controvertidos-cafes-de-animales\/","og_site_name":"Noticias","article_published_time":"2024-01-12T19:33:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/01\/12\/mapaches-zorros-suricatas-corea-del-sur-toma-medidas-drasticas-contra-los-controvertidos-cafes-de-animales\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/01\/12\/mapaches-zorros-suricatas-corea-del-sur-toma-medidas-drasticas-contra-los-controvertidos-cafes-de-animales\/"},"author":{"name":"","@id":""},"headline":"Mapaches, zorros, suricatas: Corea del Sur toma medidas dr\u00e1sticas contra los controvertidos caf\u00e9s de animales","datePublished":"2024-01-12T19:33:37+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/01\/12\/mapaches-zorros-suricatas-corea-del-sur-toma-medidas-drasticas-contra-los-controvertidos-cafes-de-animales\/"},"wordCount":2210,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/01\/12\/mapaches-zorros-suricatas-corea-del-sur-toma-medidas-drasticas-contra-los-controvertidos-cafes-de-animales\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/01\/12\/mapaches-zorros-suricatas-corea-del-sur-toma-medidas-drasticas-contra-los-controvertidos-cafes-de-animales\/","url":"https:\/\/noticiasya.com\/2024\/01\/12\/mapaches-zorros-suricatas-corea-del-sur-toma-medidas-drasticas-contra-los-controvertidos-cafes-de-animales\/","name":"Mapaches, zorros, suricatas: Corea del Sur toma medidas dr\u00e1sticas contra los controvertidos caf\u00e9s de animales - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-12T19:33:37+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/01\/12\/mapaches-zorros-suricatas-corea-del-sur-toma-medidas-drasticas-contra-los-controvertidos-cafes-de-animales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/01\/12\/mapaches-zorros-suricatas-corea-del-sur-toma-medidas-drasticas-contra-los-controvertidos-cafes-de-animales\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/01\/12\/mapaches-zorros-suricatas-corea-del-sur-toma-medidas-drasticas-contra-los-controvertidos-cafes-de-animales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Mapaches, zorros, suricatas: Corea del Sur toma medidas dr\u00e1sticas contra los controvertidos caf\u00e9s de animales"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2024\/01\/12\/mapaches-zorros-suricatas-corea-del-sur-toma-medidas-drasticas-contra-los-controvertidos-cafes-de-animales\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Mapaches, zorros, suricatas: Corea del Sur toma medidas dr\u00e1sticas contra los controvertidos caf\u00e9s de animales","url":"http:\/\/noticiasya.com\/nacional\/2024\/01\/12\/mapaches-zorros-suricatas-corea-del-sur-toma-medidas-drasticas-contra-los-controvertidos-cafes-de-animales\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2024\/01\/12\/mapaches-zorros-suricatas-corea-del-sur-toma-medidas-drasticas-contra-los-controvertidos-cafes-de-animales\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-12T19:33:37Z","datePublished":"2024-01-12T19:33:37Z","dateModified":"2024-01-12T19:33:37Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Mapaches, zorros, suricatas: Corea del Sur toma medidas dr\\u00e1sticas contra los controvertidos caf\\u00e9s de animales\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2024\\\/01\\\/12\\\/mapaches-zorros-suricatas-corea-del-sur-toma-medidas-drasticas-contra-los-controvertidos-cafes-de-animales\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2024\\\/01\\\/12\\\/mapaches-zorros-suricatas-corea-del-sur-toma-medidas-drasticas-contra-los-controvertidos-cafes-de-animales\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-12T19:33:37Z\",\"datePublished\":\"2024-01-12T19:33:37Z\",\"dateModified\":\"2024-01-12T19:33:37Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1443411,"url":"https:\/\/noticiasya.com\/nacional\/2024\/01\/09\/corea-del-sur-aprueba-un-proyecto-de-ley-para-prohibir-el-consumo-de-carne-de-perro-poniendo-fin-a-una-practica-controvertida-a-medida-que-cambian-los-habitos-de-consumo\/","url_meta":{"origin":1443579,"position":0},"title":"Corea del Sur aprueba un proyecto de ley para prohibir el consumo de carne de perro, poniendo fin a una pr\u00e1ctica controvertida a medida que cambian los h\u00e1bitos de consumo","author":"","date":"enero 9, 2024","format":false,"excerpt":"(CNN) --\u00a0 El parlamento de Corea del Sur aprob\u00f3 este martes un proyecto de ley que proh\u00edbe la cr\u00eda y el sacrificio de perros para consumo, poniendo fin a la pr\u00e1ctica tradicional pero controvertida de comer carne de perro despu\u00e9s de a\u00f1os de debate a nivel nacional.El proyecto de ley\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451612,"url":"https:\/\/noticiasya.com\/nacional\/2024\/08\/05\/dolce-gabbana-perfume-perros-trax\/","url_meta":{"origin":1443579,"position":1},"title":"Dolce &#038; Gabbana lanz\u00f3 un nuevo perfume, pero no es para humanos","author":"","date":"agosto 5, 2024","format":false,"excerpt":"(CNN) -- No contento con vestir a las estrellas m\u00e1s destacadas de la escena musical, desde Beyonc\u00e9 y Usher hasta Christina Aguilera, Dolce & Gabbana ahora tiene la mira puesta en hacer que los perros sean un poco m\u00e1s elegantes.La \u00faltima propuesta de la marca de moda italiana es para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455096,"url":"https:\/\/noticiasya.com\/nacional\/2024\/10\/14\/tendencia-cafeterias-mascotas-dinero-merienda-china-trax\/","url_meta":{"origin":1443579,"position":2},"title":"En China, las mascotas ganan dinero en las cafeter\u00edas mientras sus due\u00f1os las env\u00edan a trabajar","author":"","date":"octubre 14, 2024","format":false,"excerpt":"(CNN) -- Jane Xue envi\u00f3 a su perro, un samoyedo de 2 a\u00f1os llamado OK, a su primer d\u00eda de trabajo a mediados de septiembre. \u00bfSu empleador? Una cafeter\u00eda canina de Fuzhou, en el sureste de China.\"Siento que es como cuando los padres mandan a sus hijos al colegio\", dijo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456181,"url":"https:\/\/noticiasya.com\/nacional\/2024\/11\/30\/repatrian-animales-madagascar-peligro-de-extincion-trax\/","url_meta":{"origin":1443579,"position":3},"title":"Repatrian a Madagascar a casi 1.000 animales en peligro de extinci\u00f3n en un hito contra el tr\u00e1fico de especies","author":"","date":"noviembre 30, 2024","format":false,"excerpt":"Bangkok, Tailandia (CNN) -- Tailandia enviar\u00e1 a Madagascar casi 1.000 tortugas y l\u00e9mures en peligro de extinci\u00f3n, en una victoria hist\u00f3rica contra el tr\u00e1fico de animales. El primer lote llegar\u00e1 el s\u00e1bado.Seg\u00fan las autoridades tailandesas, se trata de la mayor repatriaci\u00f3n jam\u00e1s realizada entre ambos pa\u00edses.La polic\u00eda tailandesa recuper\u00f3 1.117\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442569,"url":"https:\/\/noticiasya.com\/nacional\/2023\/12\/24\/liberen-a-bella-la-lucha-por-liberar-a-una-beluga-del-acuario-de-un-mega-centro-comercial-de-corea-del-sur\/","url_meta":{"origin":1443579,"position":4},"title":"Liberen a Bella: la lucha por liberar a una beluga del acuario de un mega centro comercial de Corea del Sur","author":"","date":"diciembre 24, 2023","format":false,"excerpt":"Se\u00fal, Corea del Sur (CNN) -- Un tanque est\u00e9ril con paredes de concreto y rocas artificiales, ubicado en los pisos inferiores de un mega centro comercial de Corea del Sur, ha sido el hogar de una ballena beluga hembra durante casi una d\u00e9cada.Se cree que la ballena ten\u00eda alrededor de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442572,"url":"https:\/\/noticiasya.com\/nacional\/2023\/12\/24\/liberen-a-bella-la-lucha-por-liberar-a-una-beluga-del-acuario-de-un-mega-centro-comercial-de-corea-del-sur-2\/","url_meta":{"origin":1443579,"position":5},"title":"Liberen a Bella: la lucha por liberar a una beluga del acuario de un mega centro comercial de Corea del Sur","author":"","date":"diciembre 24, 2023","format":false,"excerpt":"Se\u00fal, Corea del Sur (CNN) -- Un tanque est\u00e9ril con paredes de concreto y rocas artificiales, ubicado en los pisos inferiores de un mega centro comercial de Corea del Sur, ha sido el hogar de una ballena beluga hembra durante casi una d\u00e9cada.Se cree que la ballena ten\u00eda alrededor de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1443579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1443579"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1443579\/revisions"}],"predecessor-version":[{"id":1443600,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1443579\/revisions\/1443600"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1443579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1443579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1443579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}