{"id":1443608,"date":"2024-01-12T22:33:28","date_gmt":"2024-01-13T06:33:28","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1443608"},"modified":"2024-01-12T22:33:28","modified_gmt":"2024-01-13T06:33:28","slug":"citigroup-despedira-a-20-000-empleados","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2024\/01\/12\/citigroup-despedira-a-20-000-empleados\/","title":{"rendered":"Citigroup despedir\u00e1 a 20.000 empleados"},"content":{"rendered":"<p>(CNN) &#8212; Citigroup despedir\u00e1 a 20.000 empleados durante los pr\u00f3ximos dos a\u00f1os, inform\u00f3 este viernes el director financiero Mark Mason. Los recortes ocurren despu\u00e9s de que la compa\u00f1\u00eda reportara una p\u00e9rdida neta de US$ 1.800 millones en el cuarto trimestre de 2023, su peor trimestre en 15 a\u00f1os.<\/p>\n<p>El banco espera que la reducci\u00f3n de personal le ahorre US$ 2.500 millones a largo plazo.<\/p>\n<p>El banco inform\u00f3 una enorme p\u00e9rdida de ganancias de US$ 1,16 por acci\u00f3n durante el cuarto trimestre, muy por debajo de las estimaciones de una p\u00e9rdida de 11 centavos por acci\u00f3n, seg\u00fan FactSet.<\/p>\n<p>Citi dijo que tuvo varios costos \u00fanicos que afectaron sus resultados. Entre ellos, un cargo de US$ 1.700 millones relacionado con la crisis bancaria regional de la primavera pasada, una p\u00e9rdida de US$ 880 millones en Argentina y unos US$ 800 millones en costos de reestructuraci\u00f3n asociados con alrededor de 7.000 despidos en 2023.<\/p>\n<p>La inteligencia artificial ya est\u00e1 vinculada a despidos en la industria que la cre\u00f3<\/p>\n<p>Estos despidos forman parte de los esfuerzos de larga data de la CEO de Citi, Jane Fraser, por reducir la burocracia de la empresa e impulsar las rezagadas ganancias. Fraser calific\u00f3 los resultados de &#171;muy decepcionantes&#187; en una llamada telef\u00f3nica en la ma\u00f1ana de este viernes, pero dijo que 2024 ser\u00eda un &#171;a\u00f1o decisivo&#187; para el tercer prestamista m\u00e1s grande de Estados Unidos.<\/p>\n<p>&#171;Cada vez que una industria o empresa pasa por este tipo de reducciones es dif\u00edcil para la moral&#187;, dijo Manson en una llamada con periodistas el viernes. &#171;Dicho esto, quisiera se\u00f1alar el hecho de que hemos sido muy claros acerca de la estrategia de la empresa y muy claros acerca del impulso que esperamos&#187;.<\/p>\n<p>Adem\u00e1s de los 20.000 empleos que se eliminar\u00e1n en las operaciones de la compa\u00f1\u00eda, el banco dijo que despedir\u00e1 a 40.000 empleados de su unidad minorista mexicana a trav\u00e9s de una oferta p\u00fablica inicial (IPO), reduciendo la plantilla total de la compa\u00f1\u00eda de 240.000 trabajadores a alrededor de 180.000.<\/p>\n<p>En los pr\u00f3ximos a\u00f1os, el banco se\u00f1al\u00f3 que espera pagar hasta US$ 1.000 millones en indemnizaciones por despidos y costos de reorganizaci\u00f3n relacionados con la reestructuraci\u00f3n que tiene planificada.<\/p>\n<p>Un portavoz de Citi dijo que los despidos tendr\u00edan un alcance global pero se neg\u00f3 a desglosar las cifras por regi\u00f3n.<\/p>\n<p>La CEO Jane Fraser anunci\u00f3 por primera vez sus amplios esfuerzos de reestructuraci\u00f3n en septiembre pasado. Sus planes para reorganizar el liderazgo del banco, aumentar la rendici\u00f3n de cuentas e incrementar el precio de las acciones, dijo, requerir\u00edan una reducci\u00f3n de personal.<\/p>\n<p>&#171;Nos despediremos de algunos colegas muy talentosos y trabajadores&#187;, escribi\u00f3 Fraser en ese momento.<\/p>\n<p>Las acciones de Citi cayeron un 1,2% en las operaciones de la tarde.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Citigroup despedir\u00e1 a 20.000 empleados durante los pr\u00f3ximos dos a\u00f1os, inform\u00f3 este viernes el director financiero Mark Mason. Los recortes ocurren despu\u00e9s de que la compa\u00f1\u00eda reportara una p\u00e9rdida neta de US$ 1.800 millones en el cuarto trimestre de 2023, su peor trimestre en 15 a\u00f1os. El banco espera que la reducci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1443608","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Citigroup despedir\u00e1 a 20.000 empleados - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/01\/12\/citigroup-despedira-a-20-000-empleados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Citigroup despedir\u00e1 a 20.000 empleados - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Citigroup despedir\u00e1 a 20.000 empleados durante los pr\u00f3ximos dos a\u00f1os, inform\u00f3 este viernes el director financiero Mark Mason. Los recortes ocurren despu\u00e9s de que la compa\u00f1\u00eda reportara una p\u00e9rdida neta de US$ 1.800 millones en el cuarto trimestre de 2023, su peor trimestre en 15 a\u00f1os. El banco espera que la reducci\u00f3n de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/01\/12\/citigroup-despedira-a-20-000-empleados\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-13T06:33:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/12\/citigroup-despedira-a-20-000-empleados\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/12\/citigroup-despedira-a-20-000-empleados\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Citigroup despedir\u00e1 a 20.000 empleados\",\"datePublished\":\"2024-01-13T06:33:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/12\/citigroup-despedira-a-20-000-empleados\/\"},\"wordCount\":487,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/12\/citigroup-despedira-a-20-000-empleados\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/12\/citigroup-despedira-a-20-000-empleados\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/01\/12\/citigroup-despedira-a-20-000-empleados\/\",\"name\":\"Citigroup despedir\u00e1 a 20.000 empleados - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-13T06:33:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/12\/citigroup-despedira-a-20-000-empleados\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/01\/12\/citigroup-despedira-a-20-000-empleados\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/01\/12\/citigroup-despedira-a-20-000-empleados\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Citigroup despedir\u00e1 a 20.000 empleados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Citigroup despedir\u00e1 a 20.000 empleados - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/01\/12\/citigroup-despedira-a-20-000-empleados\/","og_locale":"es_ES","og_type":"article","og_title":"Citigroup despedir\u00e1 a 20.000 empleados - Noticias","og_description":"(CNN) &#8212; Citigroup despedir\u00e1 a 20.000 empleados durante los pr\u00f3ximos dos a\u00f1os, inform\u00f3 este viernes el director financiero Mark Mason. Los recortes ocurren despu\u00e9s de que la compa\u00f1\u00eda reportara una p\u00e9rdida neta de US$ 1.800 millones en el cuarto trimestre de 2023, su peor trimestre en 15 a\u00f1os. El banco espera que la reducci\u00f3n de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/01\/12\/citigroup-despedira-a-20-000-empleados\/","og_site_name":"Noticias","article_published_time":"2024-01-13T06:33:28+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/01\/12\/citigroup-despedira-a-20-000-empleados\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/01\/12\/citigroup-despedira-a-20-000-empleados\/"},"author":{"name":"","@id":""},"headline":"Citigroup despedir\u00e1 a 20.000 empleados","datePublished":"2024-01-13T06:33:28+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/01\/12\/citigroup-despedira-a-20-000-empleados\/"},"wordCount":487,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/01\/12\/citigroup-despedira-a-20-000-empleados\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/01\/12\/citigroup-despedira-a-20-000-empleados\/","url":"https:\/\/noticiasya.com\/2024\/01\/12\/citigroup-despedira-a-20-000-empleados\/","name":"Citigroup despedir\u00e1 a 20.000 empleados - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-13T06:33:28+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/01\/12\/citigroup-despedira-a-20-000-empleados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/01\/12\/citigroup-despedira-a-20-000-empleados\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/01\/12\/citigroup-despedira-a-20-000-empleados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Citigroup despedir\u00e1 a 20.000 empleados"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2024\/01\/12\/citigroup-despedira-a-20-000-empleados\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Citigroup despedir\u00e1 a 20.000 empleados","url":"http:\/\/noticiasya.com\/nacional\/2024\/01\/12\/citigroup-despedira-a-20-000-empleados\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2024\/01\/12\/citigroup-despedira-a-20-000-empleados\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-13T06:33:28Z","datePublished":"2024-01-13T06:33:28Z","dateModified":"2024-01-13T06:33:28Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Citigroup despedir\\u00e1 a 20.000 empleados\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2024\\\/01\\\/12\\\/citigroup-despedira-a-20-000-empleados\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2024\\\/01\\\/12\\\/citigroup-despedira-a-20-000-empleados\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-13T06:33:28Z\",\"datePublished\":\"2024-01-13T06:33:28Z\",\"dateModified\":\"2024-01-13T06:33:28Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1464161,"url":"https:\/\/noticiasya.com\/nacional\/2025\/07\/02\/microsoft-despedira-9000-empleados-recorte-trax\/","url_meta":{"origin":1443608,"position":0},"title":"Microsoft despedir\u00e1 a unos 9.000 empleados en su mayor recorte desde 2023","author":"","date":"julio 2, 2025","format":false,"excerpt":"Microsoft est\u00e1 despidiendo a miles de empleados, en su tercera ronda de recortes en los \u00faltimos meses, confirm\u00f3 la empresa este mi\u00e9rcoles.La reducci\u00f3n de personal afectar\u00e1 a menos del 4 % de la fuerza laboral total de la compa\u00f1\u00eda, es decir, a unos 9.000 trabajadores, seg\u00fan un portavoz de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448499,"url":"https:\/\/noticiasya.com\/nacional\/2024\/04\/25\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\/","url_meta":{"origin":1443608,"position":1},"title":"Ford informa de una p\u00e9rdida masiva por cada veh\u00edculo el\u00e9ctrico que vendi\u00f3","author":"","date":"abril 25, 2024","format":false,"excerpt":"(CNN) -- La unidad de veh\u00edculos el\u00e9ctricos de Ford inform\u00f3 que las p\u00e9rdidas se dispararon en el primer trimestre a US$ 1.300 millones, o us$ 132.000 por cada uno de los 10.000 veh\u00edculos que vendi\u00f3 en los primeros tres meses del a\u00f1o, lo que contribuy\u00f3 a reducir las ganancias de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458004,"url":"https:\/\/noticiasya.com\/nacional\/2025\/01\/29\/elon-musk-boeing-air-force-one-trax\/","url_meta":{"origin":1443608,"position":2},"title":"Elon Musk visita Boeing por el retraso de los nuevos aviones Air Force One","author":"","date":"enero 29, 2025","format":false,"excerpt":"Elon Musk aprovech\u00f3 su nuevo rol dedicado a la eficiencia gubernamental para visitar las operaciones de su competidor Boeing y analizar la demora en la renovaci\u00f3n de dos aviones 747 para convertirlos en la pr\u00f3xima generaci\u00f3n de aviones Air Force One, dijo el martes el CEO de Boeing, Kelly Ortberg.En\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473785,"url":"https:\/\/noticiasya.com\/nacional\/2026\/05\/04\/gamestop-oferta-compra-ebay-trax\/","url_meta":{"origin":1443608,"position":3},"title":"GameStop hace una audaz oferta de US$ 56.000 millones por eBay, con la esperanza de rivalizar con Amazon","author":"","date":"mayo 4, 2026","format":false,"excerpt":"GameStop ha ofrecido comprar al gigante del comercio electr\u00f3nico eBay por US$ 55.500 millones, una uni\u00f3n que el jefe del minorista de videojuegos cree que podr\u00eda producir un \u201ccompetidor leg\u00edtimo\u201d de Amazon.La oferta llega en medio de una especie de resurgimiento de eBay, que ha impulsado su reinvenci\u00f3n frente al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448488,"url":"https:\/\/noticiasya.com\/nacional\/2024\/04\/24\/boeing-pagara-443-millones-aerolineas-inmovilizacion-max-9-trax\/","url_meta":{"origin":1443608,"position":4},"title":"Boeing pagar\u00e1 US$ 443 millones a las aerol\u00edneas por la inmovilizaci\u00f3n del Max 9","author":"","date":"abril 24, 2024","format":false,"excerpt":"(CNN) --\u00a0Boeing registr\u00f3 unas p\u00e9rdidas ligeramente inferiores en el primer trimestre en comparaci\u00f3n con el mismo periodo del a\u00f1o anterior, pero se\u00f1al\u00f3 que la correcci\u00f3n de los problemas que acapararon la atenci\u00f3n tras el incidente de Alaska Air retrasar\u00e1 su recuperaci\u00f3n financiera y le costar\u00e1 US$ 443 millones en compensaciones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449608,"url":"https:\/\/noticiasya.com\/nacional\/2024\/05\/20\/trump-media-perdida-300-millones-trimestre-trax\/","url_meta":{"origin":1443608,"position":5},"title":"Trump Media perdi\u00f3 m\u00e1s de US$ 300 millones el \u00faltimo trimestre con ingresos muy escasos","author":"","date":"mayo 20, 2024","format":false,"excerpt":"(CNN) -- Trump Media & Technology Group perdi\u00f3 m\u00e1s de US$ 300 millones durante el primer trimestre y gener\u00f3 muy pocos ingresos, anunci\u00f3 este lunes el propietario de Truth Social en un comunicado de prensa.Los resultados plantear\u00e1n preguntas adicionales sobre la valoraci\u00f3n multimillonaria de la nueva empresa p\u00fablica, que es\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1443608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1443608"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1443608\/revisions"}],"predecessor-version":[{"id":1443624,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1443608\/revisions\/1443624"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1443608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1443608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1443608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}