{"id":1443635,"date":"2024-01-13T11:33:31","date_gmt":"2024-01-13T19:33:31","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1443635"},"modified":"2024-01-13T11:33:31","modified_gmt":"2024-01-13T19:33:31","slug":"por-que-para-las-personas-con-depresion-cosas-cotidianas-como-levantarse-de-la-cama-banarse-y-comer-pueden-ser-una-lucha","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2024\/01\/13\/por-que-para-las-personas-con-depresion-cosas-cotidianas-como-levantarse-de-la-cama-banarse-y-comer-pueden-ser-una-lucha\/","title":{"rendered":"Por qu\u00e9 para las personas con depresi\u00f3n cosas cotidianas como levantarse de la cama, ba\u00f1arse y comer pueden ser una lucha"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; La depresi\u00f3n puede dejarte por fuera del normal transcurrir de tu vida cotidiana en cualquier momento. Y si piensas que solo se trata de tristeza profunda que se mejora teniendo &#171;actitud positiva&#187;, debes saber que muchas personas pueden verse afectadas en su d\u00eda a d\u00eda por cuenta de esta enfermedad.<\/p>\n<p>Seg\u00fan la Organizaci\u00f3n Mundial de la Salud (OMS), una persona que est\u00e1 deprimida experimenta un estado de \u00e1nimo lleno de &#171;tristeza, irritabilidad, sensaci\u00f3n de vac\u00edo&#187;, una p\u00e9rdida del disfrute de la vida o el desinter\u00e9s en las actividades, &#171;la mayor parte del d\u00eda, casi todos los d\u00edas, durante al menos dos semanas&#187;.<\/p>\n<p>Se estima que aproximadamente 280 millones de personas padecen depresi\u00f3n en todo el mundo, lo que representa un 3,8% del estimado de la poblaci\u00f3n, seg\u00fan la OMS.<\/p>\n<p>Para la mitad de los afectados, un episodio es todo lo que experimentar\u00e1n. Pero despu\u00e9s de tres o m\u00e1s, estos episodios tienen un 90% m\u00e1s de probabilidades de volverse recurrentes.<\/p>\n<p>&#171;Cuando estamos hablando de la depresi\u00f3n, estamos hablando de una tristeza persistente que no te deja funcionar en tu d\u00eda a d\u00eda&#187;, le dijo a CNN la Dra Karen Mart\u00ednez, miembro del Comit\u00e9 de Salud P\u00fablica Asociaci\u00f3n de Ansiedad y Depresi\u00f3n de Estados Unidos (ADAA por sus siglas en ingl\u00e9s), una organizaci\u00f3n dedicada a la prevenci\u00f3n, el tratamiento y la cura de varios trastornos como la ansiedad y la depresi\u00f3n.<\/p>\n<p>La depresi\u00f3n, dice Mart\u00ednez, es una respuesta a un evento de p\u00e9rdida que experimenta una persona: puede la p\u00e9rdida de una persona, una decepci\u00f3n, o algo que pueda hacerla &#171;cuestionar sobre el sentido de la vida, de si hay esperanza, de si uno debe seguir&#187;.<\/p>\n<p>Dentro de una mente deprimida: as\u00ed se siente vivir con depresi\u00f3n (interactivo)<\/p>\n<p>M\u00e1s que &#171;falta de voluntad&#187;: as\u00ed afecta tu d\u00eda a d\u00eda la depresi\u00f3n<\/p>\n<p>Hay personas en cuyos momentos m\u00e1s duros de depresi\u00f3n no pueden levantarse de la cama; para ellos ba\u00f1arse es todo un reto. Comer se vuelve un desaf\u00edo porque el apetito se va y la esperanza de un futuro no existe.<\/p>\n<p>Entonces, \u00bfpara qu\u00e9 luchar?, se preguntan.<\/p>\n<p>&#171;Cuando uno no se quiere levantar de la cama, cuando uno est\u00e1 &#8216;cosido a la cama&#8217;, uno quisiera (levantarse) y el cuerpo no le da, ni los brazos, ni las piernas. Y uno por dentro sabe que debe de levantarse, pero no puede. Yo creo que en esos instantes es cuando la enfermedad empezaba a tomar el poder sobre uno como persona&#187;, le dijo a CNN Jonny Castro, un economista de 28 a\u00f1os que vive en Bogot\u00e1, y a quien le diagnosticaron depresi\u00f3n hace unos cuatro a\u00f1os.<\/p>\n<p>&#171;Yo pensaba y en mi interior sent\u00eda que esa era mi forma de ser: introvertida, de pronto un poco emocionalmente inestable. Pero yo nunca me imagin\u00e9 que tuviera algo que se llamaba depresi\u00f3n y nunca alcanc\u00e9 a dimensionar que era una enfermedad realmente seria&#187;, le dijo Castro a CNN.<\/p>\n<p>Hace unos cuatro a\u00f1os, Castro tuvo una crisis muy fuerte que lo oblig\u00f3 a encerrarse durante una semana. Durante ese tiempo, no dorm\u00eda, no com\u00eda y viv\u00eda &#171;muy angustiado todo el tiempo&#187;. Entonces decidi\u00f3 ir a una cl\u00ednica de salud mental donde estuvo interno por alg\u00fan tiempo. All\u00ed empez\u00f3 a recibir orientaci\u00f3n sobre su condici\u00f3n, lo medicaron, y luego entr\u00f3 a terapias para estabilizar su estado de \u00e1nimo.<\/p>\n<p>Una situaci\u00f3n parecida le ocurre a Mar\u00eda Alejandra, una bogotana de 32 a\u00f1os que nos pide no divulgar su nombre completo. Cuenta que ha lidiado con una depresi\u00f3n que le fue diagnosticada a los 15 a\u00f1os, junto con un trastorno alimenticio de bulimia y anorexia.<\/p>\n<p>Dice que cuando tiene episodios de depresi\u00f3n \u2014que vuelven de vez en cuando\u2014 siente que su entorno empieza a no gustarle y pierde las ganas de seguir luchando contra la corriente.<\/p>\n<p>&#171;En el momento que yo estoy en depresi\u00f3n siento que la vida no era lo que yo quer\u00eda. Empiezo a sentir una tristeza profunda que no logro describir; un vac\u00edo en el coraz\u00f3n, en el cuerpo en el que yo digo ya no m\u00e1s&#8230; no vale la pena, me canse de ir contra la corriente&#187;.<\/p>\n<p>\u00bfC\u00f3mo combatir la depresi\u00f3n? Expertas explican los tratamientos y opciones<\/p>\n<p>Y levantarse a hacer cosas diarias no es una cuesti\u00f3n de simple &#171;voluntad&#187;, dice ella.<\/p>\n<p>&#171;Es dif\u00edcil porque no existe (la voluntad). No le ves sentido a la vida. En realidad t\u00fa quisieras no estar ah\u00ed. Yo he tenido pensamientos suicidas en los que le digo a Dios &#8216;ll\u00e9vame&#8217;, no le veo sentido a la vida. Es una situaci\u00f3n de cansancio, de desgaste emocional, que lo lleva a uno a estar tirado en cama, y as\u00ed te muestren videos y fotos de tus seres queridos, simplemente no quiero porque mi alma est\u00e1 congelada&#187;, dice Mar\u00eda Alejandra.<\/p>\n<p>Y Castro, quien dice que si bien s\u00ed es cuesti\u00f3n de voluntad levantarse de la cama en esos momentos dif\u00edciles, reconoce que hay momentos en los que es imposible hacerlo.<\/p>\n<p>Estudio revela que la pandemia afect\u00f3 la salud mental de los ni\u00f1os 1:54<\/p>\n<p>\u00bfPor qu\u00e9 ocurre esto?<\/p>\n<p>Seg\u00fan la Dra. Mart\u00ednez, de la ADAA, cuando una persona est\u00e1 en una depresi\u00f3n cl\u00ednica no puede encontrar una motivaci\u00f3n para salir del estado de tristeza profunda porque su cerebro &#171;b\u00e1sicamente est\u00e1 apagado&#187;.<\/p>\n<p>&#171;En la depresi\u00f3n lo que se ve afectado son estos circuitos del cerebro que tienen que ver con la motivaci\u00f3n&#187;, explica Mart\u00ednez. &#171;As\u00ed que ocurre este evento donde todo lo que normalmente nos ayuda a levantarse de la cama, salir de la casa, enfocarse en el trabajo, esos circuitos, como quien dice, se apagan y entonces uno no encuentra la manera de volver a prenderlos&#187;.<\/p>\n<p>Por otra parte, el pensamiento de una persona con depresi\u00f3n est\u00e1 tan fusionado con el contenido de su mente, que esa persona termina por creer &#171;firmemente que sus creencias son un hecho en realidad y termina cuestion\u00e1ndose el para qu\u00e9&#187; seguir adelante, seg\u00fan el psicoterapeuta Jose Verdejo del equipo de Desansiedad, un grupo especializado en el tratamiento de la ansiedad.<\/p>\n<p>&#171;Alguien que tiene una percepci\u00f3n negativa de s\u00ed mismo y con carencia de valor, asume que el resto lo ve de la misma forma y se a\u00edsla socialmente, lo que crea una vida carente de oportunidades de reconocimiento y val\u00eda, que finalmente el afectado termina acomodando como una prueba en la realidad de que carece de valor y de que est\u00e1 condenado a sufrir, desmotiv\u00e1ndolo a\u00fan m\u00e1s&#187;, le dijo Verdejo a CNN.<\/p>\n<p>Mostrar compasi\u00f3n, aceptar otras culturas: c\u00f3mo prevenir el suicidio en la comunidad latina<\/p>\n<p>M\u00e1s all\u00e1 de &#171;actitud positiva&#187;<\/p>\n<p>Un error frecuente en el que caen muchos es decirle a una persona que sufre depresi\u00f3n que le ponga &#171;actitud positiva a la vida&#187;, que se d\u00e9 cuenta que lo tiene todo y &#171;no hay raz\u00f3n para estar tristes&#187; o muchas palabras que m\u00e1s que apoyar a una persona en esta situaci\u00f3n, pueden darle m\u00e1s cargas y no ser \u00fatiles en absoluto.<\/p>\n<p>&#171;Es un des\u00e1nimo que no se alivia diciendo &#8216;ponle actitud positiva'&#187;, dice Mar\u00eda Alejandra.<\/p>\n<p>Y como los pensamientos son algo en lo que las personas tienen un &#171;escaso control&#187;, seg\u00fan Verdejo, &#171;este tipo de consejos no son \u00fatiles&#187;.<\/p>\n<p>&#171;La persona con depresi\u00f3n probablemente ya intent\u00f3 hacerlo y se frustr\u00f3 al no conseguirlo, por lo que vuelve a frustrarse cuando su entorno le insiste en aquello. El apoyo que necesita una persona con depresi\u00f3n es desde un v\u00ednculo seguro, desde un intento de comprensi\u00f3n en vez de la cr\u00edtica&#187;, dice el experto.<\/p>\n<p>Mart\u00ednez, por su parte, dice que como psiquiatra ve muy a menudo casos de depresi\u00f3n y ansiedad, por lo que es importante hablar sobre salud mental para quitar los estigmas sobre estos temas.<\/p>\n<p>&#171;Yo lo m\u00e1s que veo es personas que est\u00e1n teniendo dificultades adapt\u00e1ndose a lo que est\u00e1 ocurriendo, a las situaciones del d\u00eda a d\u00eda&#187;, dijo Mart\u00ednez quien recomienda buscar ayuda en caso que identifiques algunos de los s\u00edntomas de los que aqu\u00ed hablamos.<\/p>\n<p>Los detonantes<\/p>\n<p>Si bien hay personas que pueden recuperarse durante largos periodos de la enfermedad, muchos deben lidiar con las consecuencias de esta enfermedad durante mucho tiempo, y hay detonantes que pueden conllevar a un episodio depresivo severo.<\/p>\n<p>En el caso de Castro, dice que llevar un estilo de vida desordenado, trasnochar, hace que empiece el malestar, la incomodidad, y esos son los primeros signos de una crisis por venir.<\/p>\n<p>&#171;El a\u00f1o pasado, como en marzo, me intent\u00f3 dar un episodio muy fuerte porque estaba muy cargado con trabajo, con estudio, con muchas cosas y me empec\u00e9 a descontrolar un poco. Sin embargo, yo me doy cuenta y pues tomo la ayuda, retomo lo que ya sab\u00eda que ten\u00eda que hacer y empiezo otra vez, digamos a estabilizarme an\u00edmicamente y qu\u00edmicamente y todo&#187;, dice Castro.<\/p>\n<p>A Mar\u00eda Alejandra las situaciones en las que siente rechazo y siente inseguridad de s\u00ed misma le disparan la ansiedad y los episodios depresivos.<\/p>\n<p>&#171;Cuando yo siento el rechazo de alguien, eso a m\u00ed me vuelve nada. Yo odio el rechazo. Cuando a m\u00ed alguien me rechaza, siento que se me para la vida&#187;, dice ella.<\/p>\n<p>\u00bfC\u00f3mo acercarse a una persona con depresi\u00f3n?<\/p>\n<p>La Dra. Mart\u00ednez dice que la mejor manera para acercarse a una persona con depresi\u00f3n es &#171;enfocarse en las conductas&#187; de esa persona y no en la persona misma, para evitar un tono cr\u00edtico o de juzgamiento.<\/p>\n<p>&#171;Es mejor decir: &#8216;Yo noto que \u00faltimamente t\u00fa, que te encantaba la m\u00fasica, no est\u00e1s escuchando m\u00fasica&#8230; o &#8216;noto que te llamo y no me contestas la llamada&#8217;. As\u00ed que enfocarnos en la conducta para los seres humanos es un poco m\u00e1s f\u00e1cil que aceptar que hay un cambio en la conducta, que hay un cambio en nuestras emociones&#187;.<\/p>\n<p>Por su parte, Verdejo dice que para ayudar a una persona con depresi\u00f3n es necesario mostrarle apoyo incondicional.<\/p>\n<p>&#171;Para ayudar a una persona con depresi\u00f3n es necesario dar muestras de afecto y preocupaci\u00f3n que le hagan cuestionarse la veracidad y utilidad de sus normas mentales&#187;, dice. &#171;Pero por sobre todo, sugerirle adherir a un proceso psicol\u00f3gico que le permita generar la flexibilidad psicol\u00f3gica necesaria para superar su depresi\u00f3n y construir una vida con prop\u00f3sito, y sentido en vez de seguir atrapado en aquel pasado que lo da\u00f1\u00f3&#187;.<\/p>\n<p>Actualmente tanto Castro como Mar\u00eda Alejandra est\u00e1n en tratamientos psiqui\u00e1tricos y toman medicamentos para controlar la depresi\u00f3n. En el momento de esta entrevista ambos dijeron sentirse bien y afirmaron que no han tenido un episodio depresivo desde hace un rato.<\/p>\n<p>Ambos coinciden en que lo mejor que pueden hacer las personas con depresi\u00f3n es buscar ayuda profesional y tambi\u00e9n una red de apoyo que pueda soportarlos en los momentos m\u00e1s dif\u00edciles por los que pasen.<\/p>\n<p>Y adem\u00e1s, hablar sobre salud mental es importante para quitar el tab\u00fa a esta situaci\u00f3n que es muy com\u00fan, aunque silenciosa, en todo el mundo.<\/p>\n<p>\u00bfD\u00f3nde buscar ayuda si sufres depresi\u00f3n?<\/p>\n<p>Si tienes s\u00edntomas de depresi\u00f3n, la Asociaci\u00f3n Estadounidense de Ansiedad y Depresi\u00f3n es una organizaci\u00f3n internacional sin fines de lucro que brinda tratamiento, apoyo e informaci\u00f3n sobre recursos.<\/p>\n<p>ARGENTINA<\/p>\n<p>L\u00ednea de prevenci\u00f3n del suicidio \u2013 ayuda al suicida en l\u00ednea<br \/>\nTEL\u00c9FONO: (54-11) 5275-1135 o 135 desde Buenos Aires y GBA<\/p>\n<p>Hablemos de Todo<br \/>\nCorreo electr\u00f3nico:\u00a0contacto@hablemosdetodo.gob.ar<br \/>\nDirectorio telef\u00f3nico<\/p>\n<p>BOLIVIA<\/p>\n<p>Tel\u00e9fono de la esperanza<br \/>\nLa Paz: 2248486<\/p>\n<p>BRASIL<\/p>\n<p>Centro de Valoriza\u00e7\u00e3o da Vida, CVV<br \/>\nTel\u00e9fono: 188<br \/>\nChat: (ayuda por chat)<br \/>\nCorreo electr\u00f3nico: atendimento@cvv.org.br<\/p>\n<p>CHILE<\/p>\n<p>Tel\u00e9fono de la esperanza<br \/>\nTel\u00e9fono: 005642221200<\/p>\n<p>Todo mfejora, ayuda por correo electr\u00f3nico o chat<\/p>\n<p>COLOMBIA<\/p>\n<p>Tel\u00e9fono de la esperanza<\/p>\n<p>Barranquilla:(605) 372 27 27<\/p>\n<p>Bogot\u00e1: (601) 323 24 25<\/p>\n<p>Medell\u00edn: (604) 284 66 00<\/p>\n<p>Pasto: +573016326701<\/p>\n<p>Asociaci\u00f3n Colombiana contra la Depresi\u00f3n y el P\u00e1nico\u00a0(Asodep):\u00a0+57 310 5655415<\/p>\n<p>COSTA RICA<\/p>\n<p>Tel\u00e9fono de la esperanza<br \/>\nCorreo electr\u00f3nico: telefonodelaesperanzacr@gmail.com<\/p>\n<p>ECUADOR<\/p>\n<p>Tel\u00e9fono de la esperanza<br \/>\nQuito: (593) 2 6000477 &#8211; 2923327<\/p>\n<p>ESPA\u00d1A<\/p>\n<p>Tel\u00e9fono de la esperanza:\u00a0717 003 717<\/p>\n<p>HONDURAS<\/p>\n<p>Tel\u00e9fono de la esperanza<br \/>\nSan Pedro Sula:\u00a0(00 504) 2558 08 08<\/p>\n<p>M\u00c9XICO<\/p>\n<p>Instituto Hispanoamericano de Suicidologia, A.C<br \/>\nTel\u00e9fono: +5255 46313300<br \/>\nCorreo electr\u00f3nico: info@suicidiologia.com.mx<\/p>\n<p>Decide Vivir M\u00e9xico, A.C.<\/p>\n<p>PER\u00da<\/p>\n<p>Sentido (Centro Peruano de Suicidolog\u00eda y Prevenci\u00f3n del Suicidio)<br \/>\nTel\u00e9fono: 01 498 2711<\/p>\n<p>Tel\u00e9fono de la esperanza<br \/>\nLima: (00 51 1) 273 8026<\/p>\n<p>PUERTO RICO<\/p>\n<p>L\u00ednea PAS (Primera Ayuda Psicosocial)<br \/>\nTel\u00e9fono: 1-800-981-0023<\/p>\n<p>URUGUAY<\/p>\n<p>\u00daltimo recurso<br \/>\nTel\u00e9fono: 0800-Vive (8483)<\/p>\n<p>VENEZUELA<\/p>\n<p>Tel\u00e9fono de la esperanza<\/p>\n<p>Valencia: 0241-8433308<\/p>\n<p>Nacional: 0-800-PSIQUE<\/p>\n<p>&#8212; Nota del editor: esta historia fue publicada originalmente en 2022.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; La depresi\u00f3n puede dejarte por fuera del normal transcurrir de tu vida cotidiana en cualquier momento. Y si piensas que solo se trata de tristeza profunda que se mejora teniendo &#171;actitud positiva&#187;, debes saber que muchas personas pueden verse afectadas en su d\u00eda a d\u00eda por cuenta de esta enfermedad. Seg\u00fan la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1443635","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Por qu\u00e9 para las personas con depresi\u00f3n cosas cotidianas como levantarse de la cama, ba\u00f1arse y comer pueden ser una lucha - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/13\/por-que-para-las-personas-con-depresion-cosas-cotidianas-como-levantarse-de-la-cama-banarse-y-comer-pueden-ser-una-lucha\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Por qu\u00e9 para las personas con depresi\u00f3n cosas cotidianas como levantarse de la cama, ba\u00f1arse y comer pueden ser una lucha - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; La depresi\u00f3n puede dejarte por fuera del normal transcurrir de tu vida cotidiana en cualquier momento. Y si piensas que solo se trata de tristeza profunda que se mejora teniendo &#171;actitud positiva&#187;, debes saber que muchas personas pueden verse afectadas en su d\u00eda a d\u00eda por cuenta de esta enfermedad. Seg\u00fan la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/13\/por-que-para-las-personas-con-depresion-cosas-cotidianas-como-levantarse-de-la-cama-banarse-y-comer-pueden-ser-una-lucha\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-13T19:33:31+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/13\/por-que-para-las-personas-con-depresion-cosas-cotidianas-como-levantarse-de-la-cama-banarse-y-comer-pueden-ser-una-lucha\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/13\/por-que-para-las-personas-con-depresion-cosas-cotidianas-como-levantarse-de-la-cama-banarse-y-comer-pueden-ser-una-lucha\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Por qu\u00e9 para las personas con depresi\u00f3n cosas cotidianas como levantarse de la cama, ba\u00f1arse y comer pueden ser una lucha\",\"datePublished\":\"2024-01-13T19:33:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/13\/por-que-para-las-personas-con-depresion-cosas-cotidianas-como-levantarse-de-la-cama-banarse-y-comer-pueden-ser-una-lucha\/\"},\"wordCount\":2247,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/13\/por-que-para-las-personas-con-depresion-cosas-cotidianas-como-levantarse-de-la-cama-banarse-y-comer-pueden-ser-una-lucha\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/13\/por-que-para-las-personas-con-depresion-cosas-cotidianas-como-levantarse-de-la-cama-banarse-y-comer-pueden-ser-una-lucha\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/13\/por-que-para-las-personas-con-depresion-cosas-cotidianas-como-levantarse-de-la-cama-banarse-y-comer-pueden-ser-una-lucha\/\",\"name\":\"Por qu\u00e9 para las personas con depresi\u00f3n cosas cotidianas como levantarse de la cama, ba\u00f1arse y comer pueden ser una lucha - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-13T19:33:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/13\/por-que-para-las-personas-con-depresion-cosas-cotidianas-como-levantarse-de-la-cama-banarse-y-comer-pueden-ser-una-lucha\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/13\/por-que-para-las-personas-con-depresion-cosas-cotidianas-como-levantarse-de-la-cama-banarse-y-comer-pueden-ser-una-lucha\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/13\/por-que-para-las-personas-con-depresion-cosas-cotidianas-como-levantarse-de-la-cama-banarse-y-comer-pueden-ser-una-lucha\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Por qu\u00e9 para las personas con depresi\u00f3n cosas cotidianas como levantarse de la cama, ba\u00f1arse y comer pueden ser una lucha\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Por qu\u00e9 para las personas con depresi\u00f3n cosas cotidianas como levantarse de la cama, ba\u00f1arse y comer pueden ser una lucha - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/01\/13\/por-que-para-las-personas-con-depresion-cosas-cotidianas-como-levantarse-de-la-cama-banarse-y-comer-pueden-ser-una-lucha\/","og_locale":"es_ES","og_type":"article","og_title":"Por qu\u00e9 para las personas con depresi\u00f3n cosas cotidianas como levantarse de la cama, ba\u00f1arse y comer pueden ser una lucha - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; La depresi\u00f3n puede dejarte por fuera del normal transcurrir de tu vida cotidiana en cualquier momento. Y si piensas que solo se trata de tristeza profunda que se mejora teniendo &#171;actitud positiva&#187;, debes saber que muchas personas pueden verse afectadas en su d\u00eda a d\u00eda por cuenta de esta enfermedad. Seg\u00fan la [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/13\/por-que-para-las-personas-con-depresion-cosas-cotidianas-como-levantarse-de-la-cama-banarse-y-comer-pueden-ser-una-lucha\/","og_site_name":"Noticias","article_published_time":"2024-01-13T19:33:31+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/13\/por-que-para-las-personas-con-depresion-cosas-cotidianas-como-levantarse-de-la-cama-banarse-y-comer-pueden-ser-una-lucha\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/13\/por-que-para-las-personas-con-depresion-cosas-cotidianas-como-levantarse-de-la-cama-banarse-y-comer-pueden-ser-una-lucha\/"},"author":{"name":"","@id":""},"headline":"Por qu\u00e9 para las personas con depresi\u00f3n cosas cotidianas como levantarse de la cama, ba\u00f1arse y comer pueden ser una lucha","datePublished":"2024-01-13T19:33:31+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/13\/por-que-para-las-personas-con-depresion-cosas-cotidianas-como-levantarse-de-la-cama-banarse-y-comer-pueden-ser-una-lucha\/"},"wordCount":2247,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/13\/por-que-para-las-personas-con-depresion-cosas-cotidianas-como-levantarse-de-la-cama-banarse-y-comer-pueden-ser-una-lucha\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/13\/por-que-para-las-personas-con-depresion-cosas-cotidianas-como-levantarse-de-la-cama-banarse-y-comer-pueden-ser-una-lucha\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/13\/por-que-para-las-personas-con-depresion-cosas-cotidianas-como-levantarse-de-la-cama-banarse-y-comer-pueden-ser-una-lucha\/","name":"Por qu\u00e9 para las personas con depresi\u00f3n cosas cotidianas como levantarse de la cama, ba\u00f1arse y comer pueden ser una lucha - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-13T19:33:31+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/13\/por-que-para-las-personas-con-depresion-cosas-cotidianas-como-levantarse-de-la-cama-banarse-y-comer-pueden-ser-una-lucha\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/13\/por-que-para-las-personas-con-depresion-cosas-cotidianas-como-levantarse-de-la-cama-banarse-y-comer-pueden-ser-una-lucha\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/13\/por-que-para-las-personas-con-depresion-cosas-cotidianas-como-levantarse-de-la-cama-banarse-y-comer-pueden-ser-una-lucha\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Por qu\u00e9 para las personas con depresi\u00f3n cosas cotidianas como levantarse de la cama, ba\u00f1arse y comer pueden ser una lucha"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2024\/01\/13\/por-que-para-las-personas-con-depresion-cosas-cotidianas-como-levantarse-de-la-cama-banarse-y-comer-pueden-ser-una-lucha\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Por qu\u00e9 para las personas con depresi\u00f3n cosas cotidianas como levantarse de la cama, ba\u00f1arse y comer pueden ser una lucha","url":"http:\/\/noticiasya.com\/nacional\/2024\/01\/13\/por-que-para-las-personas-con-depresion-cosas-cotidianas-como-levantarse-de-la-cama-banarse-y-comer-pueden-ser-una-lucha\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2024\/01\/13\/por-que-para-las-personas-con-depresion-cosas-cotidianas-como-levantarse-de-la-cama-banarse-y-comer-pueden-ser-una-lucha\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-13T19:33:31Z","datePublished":"2024-01-13T19:33:31Z","dateModified":"2024-01-13T19:33:31Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Por qu\\u00e9 para las personas con depresi\\u00f3n cosas cotidianas como levantarse de la cama, ba\\u00f1arse y comer pueden ser una lucha\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2024\\\/01\\\/13\\\/por-que-para-las-personas-con-depresion-cosas-cotidianas-como-levantarse-de-la-cama-banarse-y-comer-pueden-ser-una-lucha\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2024\\\/01\\\/13\\\/por-que-para-las-personas-con-depresion-cosas-cotidianas-como-levantarse-de-la-cama-banarse-y-comer-pueden-ser-una-lucha\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-13T19:33:31Z\",\"datePublished\":\"2024-01-13T19:33:31Z\",\"dateModified\":\"2024-01-13T19:33:31Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1456680,"url":"https:\/\/noticiasya.com\/nacional\/2024\/12\/17\/caminar-1000-pasos-depresion-estudio-trax\/","url_meta":{"origin":1443635,"position":0},"title":"Caminar tan solo 1.000 pasos m\u00e1s al d\u00eda podr\u00eda reducir el riesgo de depresi\u00f3n, seg\u00fan un estudio","author":"","date":"diciembre 17, 2024","format":false,"excerpt":"Los pasos que des cada d\u00eda podr\u00edan contribuir a reducir los s\u00edntomas de la depresi\u00f3n, seg\u00fan un nuevo estudio.Un estudio publicado el lunes en la revista acad\u00e9mica JAMA Network Open encontr\u00f3 que un mayor n\u00famero de pasos diarios se asocia con menos s\u00edntomas depresivos.\u201cNuestro estudio aporta m\u00e1s pruebas de que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451364,"url":"https:\/\/noticiasya.com\/nacional\/2024\/07\/23\/brain-care-score-herramienta-predecir-riesgo-demencia-depresion-trax\/","url_meta":{"origin":1443635,"position":1},"title":"Una sencilla herramienta puede predecir el riesgo de demencia y depresi\u00f3n, seg\u00fan un estudio","author":"","date":"julio 23, 2024","format":false,"excerpt":"(CNN) -- Cient\u00edficos anunciaron en diciembre la creaci\u00f3n con \u00e9xito del Brain Care Score, una herramienta para evaluar el riesgo de demencia o ictus sin necesidad de procedimientos m\u00e9dicos.Seg\u00fan un nuevo estudio, esta puntuaci\u00f3n, que tambi\u00e9n ayuda a pacientes y m\u00e9dicos a identificar cambios beneficiosos en el estilo de vida,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442719,"url":"https:\/\/noticiasya.com\/nacional\/2023\/12\/27\/enfrenta-estos-problemas-de-salud-para-reducir-el-riesgo-de-demencia-temprana-segun-un-estudio\/","url_meta":{"origin":1443635,"position":2},"title":"Enfrenta estos problemas de salud para reducir el riesgo de demencia temprana, seg\u00fan un estudio","author":"","date":"diciembre 27, 2023","format":false,"excerpt":"(CNN) \u2014 El deterioro cognitivo puede comenzar a\u00f1os antes de que aparezcan los primeros signos de demencia, que para algunos puede ocurrir tan r\u00e1pido como a los 30 a\u00f1os, una condici\u00f3n conocida como demencia de inicio temprano o de aparici\u00f3n precoz. Se estima que casi 4 millones de personas de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470134,"url":"https:\/\/noticiasya.com\/nacional\/2026\/01\/15\/terapia-cerebral-experimental-depresion-resultados-utiles-trax\/","url_meta":{"origin":1443635,"position":3},"title":"Primero en CNN: una nueva terapia experimental ofrece esperanza para pacientes con depresi\u00f3n","author":"","date":"enero 15, 2026","format":false,"excerpt":"A sus 27 a\u00f1os, Valerie Zeko vio c\u00f3mo el verano se desvanec\u00eda desde la soledad de su sof\u00e1. Mientras otros disfrutaban de la playa, ella permanec\u00eda cautiva frente al televisor, incapaz de conectar con amigos o su entorno. Lo que en aquel momento parec\u00eda apat\u00eda, result\u00f3 ser algo mucho m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456624,"url":"https:\/\/noticiasya.com\/nacional\/2024\/12\/15\/huir-vida-fenomeno-comun-trax\/","url_meta":{"origin":1443635,"position":4},"title":"\u00bfAlguna vez has querido huir de tu vida? Por qu\u00e9 este fen\u00f3meno es m\u00e1s com\u00fan de lo que crees","author":"","date":"diciembre 15, 2024","format":false,"excerpt":"Un hombre de familia de Wisconsin. Un artista entusiasta de Hawai. Un graduado de la Ivy League de Maryland. A primera vista, Ryan Borgwardt, Hannah Kobayashi y Luigi Mangione llevan vidas distintas y provienen de or\u00edgenes dispares. Sin embargo, todos tomaron caminos inesperados, desapareciendo de sus trabajos, rutinas, amigos y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447674,"url":"https:\/\/noticiasya.com\/nacional\/2024\/04\/03\/fda-autoriza-primer-tratamiento-digital-depresion-criticas-expertos-trax\/","url_meta":{"origin":1443635,"position":5},"title":"La FDA autoriza el primer tratamiento digital para la depresi\u00f3n, pero expertos advierten que la investigaci\u00f3n a\u00fan es incipiente","author":"","date":"abril 3, 2024","format":false,"excerpt":"(CNN) -- La Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. (FDA, por sus siglas en ingl\u00e9s) autoriz\u00f3 el uso de Rejoyn, el primer tratamiento digital con receta para el trastorno depresivo mayor.Rejoyn, fabricado por Otsuka Pharmaceutical y Click Therapeutics, es una aplicaci\u00f3n para tel\u00e9fonos inteligentes que se utiliza junto con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1443635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1443635"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1443635\/revisions"}],"predecessor-version":[{"id":1443652,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1443635\/revisions\/1443652"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1443635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1443635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1443635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}