{"id":1449422,"date":"2024-05-12T19:03:41","date_gmt":"2024-05-13T02:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/12\/chris-pine-habla-sobre-acne-trax\/"},"modified":"2024-05-12T19:03:41","modified_gmt":"2024-05-13T02:03:41","slug":"chris-pine-habla-sobre-acne-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nacional\/2024\/05\/12\/chris-pine-habla-sobre-acne-trax\/","title":{"rendered":"Chris Pine se sincera sobre su lucha contra el acn\u00e9: &#171;S\u00e9 lo deprimente que puede ser&#187;"},"content":{"rendered":"<p>(CNN) &#8212; Chris Pine tuvo que ser fuerte en Hollywood en medio de una lucha contra el acn\u00e9 al principio de su carrera.<\/p>\n<p>En un episodio reciente del podcast &#171;Happy Sad Confused&#187;, Pine dijo que ten\u00eda una &#171;piel horrible&#187; tanto cuando era adolescente como despu\u00e9s de la universidad, y discrep\u00f3 con el hecho de que el acn\u00e9 a veces puede considerarse como algo que solo sufren los adolescentes. En su caso, dijo, fue \u201ctremendamente debilitante y realmente incapacitante emocionalmente\u201d.<\/p>\n<p>\u201cFue uno de los puntos m\u00e1s traum\u00e1ticos de mi vida pero es mi historia\u201d, afirm\u00f3.<\/p>\n<p>La discusi\u00f3n fue provocada por el presentador del podcast, Josh Horowitz, que le pregunt\u00f3 a Pine c\u00f3mo se sent\u00eda acerca de los comentarios que el director de casting de \u201cThe OC\u201d, Patrick Rush, hizo el a\u00f1o pasado en el libro de 2023 de Alan Sepinwall, \u201cWelcome to The OC: The Oral History\u201d.<\/p>\n<p>All\u00ed, Rush revel\u00f3 que Pine ley\u00f3 el papel de Ryan Atwood para la serie, pero que su &#171;piel realmente mala&#187; en ese momento era &#171;insuperable&#187; para Rush. El papel de Atwood finalmente fue para el actor Ben McKenzie, quien protagoniz\u00f3 la serie durante su ejecuci\u00f3n de 2003 a 2007.<\/p>\n<p>Chris Pine agradece al &#171;dios del cine&#187; por el \u00e9xito de &#171;Dungeons &#038; Dragons: Honor Among Thieves&#187;<\/p>\n<p>Pine dijo con franqueza que sent\u00eda que Rush &#171;no ten\u00eda que hablar de eso&#187; en el libro.<\/p>\n<p>&#171;Puedo entender que quer\u00edan tener gente bonita haciendo cosas bonitas y el acn\u00e9 grave no es lo ideal&#187;, dijo. &#171;No quiero decir que estoy agradecido por no haberlo conseguido (&#8230;) pero estoy bien con eso&#187;.<\/p>\n<p>Pine, por supuesto, est\u00e1 m\u00e1s que bien. Luego tuvo una exitosa carrera en Hollywood en la que interpret\u00f3 al Capit\u00e1n Kirk en la franquicia reiniciada de &#171;Star Trek&#187; y apareci\u00f3 en pel\u00edculas aclamadas por la cr\u00edtica como &#171;Don&#8217;t Worry Darling&#187; y &#171;Hell or High Water&#187;.<\/p>\n<p>Dijo que nunca olvidar\u00e1 la lucha que atraves\u00f3 para llegar a este punto.<\/p>\n<p>\u201cS\u00e9 lo deprimente que puede ser y el tipo de tristeza a la que te puede arrastrar\u201d, coment\u00f3. &#171;Pero un d\u00eda se pone mejor&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Chris Pine tuvo que ser fuerte en Hollywood en medio de una lucha contra el acn\u00e9 al principio de su carrera. En un episodio reciente del podcast &#171;Happy Sad Confused&#187;, Pine dijo que ten\u00eda una &#171;piel horrible&#187; tanto cuando era adolescente como despu\u00e9s de la universidad, y discrep\u00f3 con el hecho de que [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449422","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Chris Pine se sincera sobre su lucha contra el acn\u00e9: &quot;S\u00e9 lo deprimente que puede ser&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/12\/chris-pine-habla-sobre-acne-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chris Pine se sincera sobre su lucha contra el acn\u00e9: &quot;S\u00e9 lo deprimente que puede ser&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Chris Pine tuvo que ser fuerte en Hollywood en medio de una lucha contra el acn\u00e9 al principio de su carrera. En un episodio reciente del podcast &#171;Happy Sad Confused&#187;, Pine dijo que ten\u00eda una &#171;piel horrible&#187; tanto cuando era adolescente como despu\u00e9s de la universidad, y discrep\u00f3 con el hecho de que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/12\/chris-pine-habla-sobre-acne-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-13T02:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/12\/chris-pine-habla-sobre-acne-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/12\/chris-pine-habla-sobre-acne-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Chris Pine se sincera sobre su lucha contra el acn\u00e9: &#171;S\u00e9 lo deprimente que puede ser&#187;\",\"datePublished\":\"2024-05-13T02:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/12\/chris-pine-habla-sobre-acne-trax\/\"},\"wordCount\":391,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/12\/chris-pine-habla-sobre-acne-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/12\/chris-pine-habla-sobre-acne-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/12\/chris-pine-habla-sobre-acne-trax\/\",\"name\":\"Chris Pine se sincera sobre su lucha contra el acn\u00e9: \\\"S\u00e9 lo deprimente que puede ser\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-13T02:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/12\/chris-pine-habla-sobre-acne-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/12\/chris-pine-habla-sobre-acne-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/12\/chris-pine-habla-sobre-acne-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chris Pine se sincera sobre su lucha contra el acn\u00e9: &#171;S\u00e9 lo deprimente que puede ser&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chris Pine se sincera sobre su lucha contra el acn\u00e9: \"S\u00e9 lo deprimente que puede ser\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/12\/chris-pine-habla-sobre-acne-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Chris Pine se sincera sobre su lucha contra el acn\u00e9: \"S\u00e9 lo deprimente que puede ser\" - Noticias","og_description":"(CNN) &#8212; Chris Pine tuvo que ser fuerte en Hollywood en medio de una lucha contra el acn\u00e9 al principio de su carrera. En un episodio reciente del podcast &#171;Happy Sad Confused&#187;, Pine dijo que ten\u00eda una &#171;piel horrible&#187; tanto cuando era adolescente como despu\u00e9s de la universidad, y discrep\u00f3 con el hecho de que [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/12\/chris-pine-habla-sobre-acne-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-13T02:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/12\/chris-pine-habla-sobre-acne-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/12\/chris-pine-habla-sobre-acne-trax\/"},"author":{"name":"","@id":""},"headline":"Chris Pine se sincera sobre su lucha contra el acn\u00e9: &#171;S\u00e9 lo deprimente que puede ser&#187;","datePublished":"2024-05-13T02:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/12\/chris-pine-habla-sobre-acne-trax\/"},"wordCount":391,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/12\/chris-pine-habla-sobre-acne-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/12\/chris-pine-habla-sobre-acne-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/12\/chris-pine-habla-sobre-acne-trax\/","name":"Chris Pine se sincera sobre su lucha contra el acn\u00e9: \"S\u00e9 lo deprimente que puede ser\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-13T02:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/12\/chris-pine-habla-sobre-acne-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/12\/chris-pine-habla-sobre-acne-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/12\/chris-pine-habla-sobre-acne-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Chris Pine se sincera sobre su lucha contra el acn\u00e9: &#171;S\u00e9 lo deprimente que puede ser&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nacional\/2024\/05\/12\/chris-pine-habla-sobre-acne-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Chris Pine se sincera sobre su lucha contra el acn\u00e9: &#171;S\u00e9 lo deprimente que puede ser&#187;","url":"http:\/\/noticiasya.com\/nacional\/2024\/05\/12\/chris-pine-habla-sobre-acne-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nacional\/2024\/05\/12\/chris-pine-habla-sobre-acne-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-13T02:03:41Z","datePublished":"2024-05-13T02:03:41Z","dateModified":"2024-05-13T02:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Chris Pine se sincera sobre su lucha contra el acn\\u00e9: &#171;S\\u00e9 lo deprimente que puede ser&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2024\\\/05\\\/12\\\/chris-pine-habla-sobre-acne-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nacional\\\/2024\\\/05\\\/12\\\/chris-pine-habla-sobre-acne-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-13T02:03:41Z\",\"datePublished\":\"2024-05-13T02:03:41Z\",\"dateModified\":\"2024-05-13T02:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1457580,"url":"https:\/\/noticiasya.com\/nacional\/2025\/01\/16\/margaret-qualley-prosteticos-the-substance-trax\/","url_meta":{"origin":1449422,"position":0},"title":"Margaret Qualley dice que su piel tard\u00f3 un a\u00f1o en recuperarse de los prost\u00e9ticos que us\u00f3 en &#171;The Substance&#187;","author":"","date":"enero 16, 2025","format":false,"excerpt":"La estrella de Hollywood Margaret Qualley revel\u00f3 que los prost\u00e9ticos que us\u00f3 en la aclamada pel\u00edcula de terror \u201cThe Substance\u201d causaron tanto da\u00f1o en su piel que le tom\u00f3 alrededor de un a\u00f1o recuperarse.\u201cAl final, cuando est\u00e1n grabando por debajo de mi falda en los cr\u00e9ditos iniciales, cuando est\u00e1n como\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460009,"url":"https:\/\/noticiasya.com\/nacional\/2025\/03\/17\/videos-fuerzas-afines-gobierno-sirio-masacre-trax\/","url_meta":{"origin":1449422,"position":1},"title":"\u00a1Limpieza \u00e9tnica! Videos muestran a fuerzas afines al gobierno sirio disfrutando con masacre de minor\u00edas en ciudad costera","author":"","date":"marzo 17, 2025","format":false,"excerpt":"Una madre y su hija se agachan junto a las ventanas de su \u00e1tico mientras hombres armados se re\u00fanen frente a la puerta. Intentan no hacer ruido. Pero en el video que grabaron furtivamente de este tenso momento, se ve claramente que apenas pueden controlar su respiraci\u00f3n agitada.Ese mismo d\u00eda,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445090,"url":"https:\/\/noticiasya.com\/nacional\/2024\/02\/08\/continua-la-busqueda-de-5-marines-despues-de-que-su-helicoptero-fuera-encontrado-en-el-sur-de-california\/","url_meta":{"origin":1449422,"position":2},"title":"Contin\u00faa la b\u00fasqueda de 5 marines despu\u00e9s de que su helic\u00f3ptero fuera encontrado en el sur de California","author":"","date":"febrero 8, 2024","format":false,"excerpt":"(CNN) --\u00a0 Contin\u00faa la b\u00fasqueda de cinco marines estadounidenses cuyo helic\u00f3ptero militar fue encontrado en Pine Valley, en el sur de California, esta semana despu\u00e9s de que no lleg\u00f3 a una base de San Diego como estaba previsto.Los marines estaban en un vuelo de entrenamiento a bordo de un CH-53E\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455426,"url":"https:\/\/noticiasya.com\/nacional\/2024\/10\/29\/glaciar-antartida-largar-humo-espacio-trax\/","url_meta":{"origin":1449422,"position":3},"title":"Un glaciar clave de la Ant\u00e1rtida parece &#171;desprender humo&#187; desde una vista satelital","author":"","date":"octubre 29, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Un glaciar vital en la Ant\u00e1rtida occidental parece estar humeando en una rara imagen capturada por un sat\u00e9lite de la NASA a principios de este mes.El llamado \u201chumo marino\u201d en realidad no es humo sino niebla, y aparece en forma de volutas blancas algodonosas sobre la superficie oscura\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456276,"url":"https:\/\/noticiasya.com\/nacional\/2024\/12\/05\/hegseth-candidatura-pentagono-trump-trax\/","url_meta":{"origin":1449422,"position":4},"title":"AN\u00c1LISIS | Hegseth sigue en pie, pero a\u00fan no ha salvado su candidatura al Pent\u00e1gono","author":"","date":"diciembre 5, 2024","format":false,"excerpt":"La selecci\u00f3n de Pete Hegseth para dirigir el Pent\u00e1gono est\u00e1 estancada en el limbo, mientras lucha ferozmente contra las acusaciones de consumo de alcohol y conducta sexual inapropiada y no puede estar seguro de si el presidente electo Donald Trump realmente le cubre las espaldas.Una alta fuente de la transici\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468117,"url":"https:\/\/noticiasya.com\/nacional\/2025\/11\/07\/comunidad-dakota-escasez-snap-trax\/","url_meta":{"origin":1449422,"position":5},"title":"Una comunidad al borde del abismo teme lo peor ante la escasez de fondos y alimentos del programa SNAP","author":"","date":"noviembre 7, 2025","format":false,"excerpt":"Cuatro perros corren hacia la \u00fanica tienda de comestibles, saludando y siguiendo a los acompa\u00f1antes humanos con la esperanza de conseguir alguna migaja.Pero para muchos residentes de aqu\u00ed, conseguir comida no es tarea f\u00e1cil.Esta comunidad, ubicada en el extremo sur de Dakota del Sur, es la m\u00e1s poblada de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nacional\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1449422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/comments?post=1449422"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/posts\/1449422\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/media?parent=1449422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/categories?post=1449422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nacional\/wp-json\/wp\/v2\/tags?post=1449422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}